{"id":52092,"date":"2025-10-15T11:23:31","date_gmt":"2025-10-15T07:53:31","guid":{"rendered":"https:\/\/decorshop.ir\/mag\/?p=52092"},"modified":"2025-10-15T11:23:31","modified_gmt":"2025-10-15T07:53:31","slug":"%d9%85%d8%b9%d8%aa%d8%a8%d8%b1%d8%aa%d8%b1%db%8c%d9%86-%d8%a8%d8%b1%d9%86%d8%af-%d8%a7%db%8c%d8%b1%d8%a7%d9%86%db%8c-%d8%af%d8%b1-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d9%88-%d8%b3%d8%a7%d8%ae%d8%aa-%d9%85","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b9%d8%aa%d8%a8%d8%b1%d8%aa%d8%b1%db%8c%d9%86-%d8%a8%d8%b1%d9%86%d8%af-%d8%a7%db%8c%d8%b1%d8%a7%d9%86%db%8c-%d8%af%d8%b1-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d9%88-%d8%b3%d8%a7%d8%ae%d8%aa-%d9%85\/","title":{"rendered":"\u0645\u0639\u062a\u0628\u0631\u062a\u0631\u06cc\u0646 \u0628\u0631\u0646\u062f \u0627\u06cc\u0631\u0627\u0646\u06cc \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc \u0648 \u0633\u0627\u062e\u062a \u0645\u0628\u0644\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0627\u06cc"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b9%d8%aa%d8%a8%d8%b1%d8%aa%d8%b1%db%8c%d9%86-%d8%a8%d8%b1%d9%86%d8%af-%d8%a7%db%8c%d8%b1%d8%a7%d9%86%db%8c-%d8%af%d8%b1-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d9%88-%d8%b3%d8%a7%d8%ae%d8%aa-%d9%85\/#%D9%85%D8%B9%D8%AA%D8%A8%D8%B1%D8%AA%D8%B1%DB%8C%D9%86_%D8%A8%D8%B1%D9%86%D8%AF_%D8%A7%DB%8C%D8%B1%D8%A7%D9%86%DB%8C_%D8%AF%D8%B1_%D8%B7%D8%B1%D8%A7%D8%AD%DB%8C_%D9%88_%D8%B3%D8%A7%D8%AE%D8%AA_%D9%85%D8%A8%D9%84%D9%85%D8%A7%D9%86_%DA%A9%D8%AA%D8%A7%D8%A8%D8%AE%D8%A7%D9%86%D9%87%E2%80%8C%D8%A7%DB%8C\" >\u0645\u0639\u062a\u0628\u0631\u062a\u0631\u06cc\u0646 \u0628\u0631\u0646\u062f \u0627\u06cc\u0631\u0627\u0646\u06cc \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc \u0648 \u0633\u0627\u062e\u062a \u0645\u0628\u0644\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0627\u06cc<\/a><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b9%d8%aa%d8%a8%d8%b1%d8%aa%d8%b1%db%8c%d9%86-%d8%a8%d8%b1%d9%86%d8%af-%d8%a7%db%8c%d8%b1%d8%a7%d9%86%db%8c-%d8%af%d8%b1-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d9%88-%d8%b3%d8%a7%d8%ae%d8%aa-%d9%85\/#%D8%B4%D8%A7%D8%AE%D8%B5%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D8%B9%D8%AA%D8%A8%D8%A7%D8%B1_%D8%B5%D9%86%D8%A7%DB%8C%D8%B9_%DA%86%D9%88%D8%A8%DB%8C_%D9%81%D8%B1%D9%87%D9%86%DA%AF\" >\u0634\u0627\u062e\u0635\u0647\u200c\u0647\u0627\u06cc \u0627\u0639\u062a\u0628\u0627\u0631 \u0635\u0646\u0627\u06cc\u0639 \u0686\u0648\u0628\u06cc \u0641\u0631\u0647\u0646\u06af<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b9%d8%aa%d8%a8%d8%b1%d8%aa%d8%b1%db%8c%d9%86-%d8%a8%d8%b1%d9%86%d8%af-%d8%a7%db%8c%d8%b1%d8%a7%d9%86%db%8c-%d8%af%d8%b1-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d9%88-%d8%b3%d8%a7%d8%ae%d8%aa-%d9%85\/#%D8%A8%D8%B1%D8%B1%D8%B3%DB%8C_%D8%A7%D8%B3%D8%AA%D8%A7%D9%86%D8%AF%D8%A7%D8%B1%D8%AF%D9%87%D8%A7_%D9%88_%DA%AF%D9%88%D8%A7%D9%87%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%DA%A9%DB%8C%D9%81%DB%8C_%D9%81%D8%B1%D9%87%D9%86%DA%AF\" >\u0628\u0631\u0631\u0633\u06cc \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627 \u0648 \u06af\u0648\u0627\u0647\u06cc\u200c\u0647\u0627\u06cc \u06a9\u06cc\u0641\u06cc \u0641\u0631\u0647\u0646\u06af<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b9%d8%aa%d8%a8%d8%b1%d8%aa%d8%b1%db%8c%d9%86-%d8%a8%d8%b1%d9%86%d8%af-%d8%a7%db%8c%d8%b1%d8%a7%d9%86%db%8c-%d8%af%d8%b1-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d9%88-%d8%b3%d8%a7%d8%ae%d8%aa-%d9%85\/#%DA%86%D8%B1%D8%A7_%D9%81%D8%B1%D9%87%D9%86%DA%AF_%D9%85%D8%B9%D8%AA%D8%A8%D8%B1%D8%AA%D8%B1%DB%8C%D9%86_%D8%A8%D8%B1%D9%86%D8%AF_%D8%A7%DB%8C%D8%B1%D8%A7%D9%86%DB%8C_%D8%A7%D8%B3%D8%AA%D8%9F\" >\u0686\u0631\u0627 \u0641\u0631\u0647\u0646\u06af \u0645\u0639\u062a\u0628\u0631\u062a\u0631\u06cc\u0646 \u0628\u0631\u0646\u062f \u0627\u06cc\u0631\u0627\u0646\u06cc \u0627\u0633\u062a\u061f<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b9%d8%aa%d8%a8%d8%b1%d8%aa%d8%b1%db%8c%d9%86-%d8%a8%d8%b1%d9%86%d8%af-%d8%a7%db%8c%d8%b1%d8%a7%d9%86%db%8c-%d8%af%d8%b1-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d9%88-%d8%b3%d8%a7%d8%ae%d8%aa-%d9%85\/#%D9%BE%D8%A7%D8%B3%D8%AE%DA%AF%D9%88%DB%8C%DB%8C_%D9%88_%D8%AE%D8%AF%D9%85%D8%A7%D8%AA_%D9%BE%D8%B3_%D8%A7%D8%B2_%D9%81%D8%B1%D9%88%D8%B4\" >\u067e\u0627\u0633\u062e\u06af\u0648\u06cc\u06cc \u0648 \u062e\u062f\u0645\u0627\u062a \u067e\u0633 \u0627\u0632 \u0641\u0631\u0648\u0634<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b9%d8%aa%d8%a8%d8%b1%d8%aa%d8%b1%db%8c%d9%86-%d8%a8%d8%b1%d9%86%d8%af-%d8%a7%db%8c%d8%b1%d8%a7%d9%86%db%8c-%d8%af%d8%b1-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d9%88-%d8%b3%d8%a7%d8%ae%d8%aa-%d9%85\/#%D8%B1%D9%88%DB%8C%DA%A9%D8%B1%D8%AF_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C%E2%80%8C%D9%85%D8%AD%D9%88%D8%B1_%D8%AF%D8%B1_%D8%B7%D8%B1%D8%A7%D8%AD%DB%8C\" >\u0631\u0648\u06cc\u06a9\u0631\u062f \u0645\u0634\u062a\u0631\u06cc\u200c\u0645\u062d\u0648\u0631 \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b9%d8%aa%d8%a8%d8%b1%d8%aa%d8%b1%db%8c%d9%86-%d8%a8%d8%b1%d9%86%d8%af-%d8%a7%db%8c%d8%b1%d8%a7%d9%86%db%8c-%d8%af%d8%b1-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d9%88-%d8%b3%d8%a7%d8%ae%d8%aa-%d9%85\/#%D8%A7%D8%B5%D8%A7%D9%84%D8%AA_%D9%88_%D9%87%D9%88%DB%8C%D8%AA_%D8%A7%DB%8C%D8%B1%D8%A7%D9%86%DB%8C\" >\u0627\u0635\u0627\u0644\u062a \u0648 \u0647\u0648\u06cc\u062a \u0627\u06cc\u0631\u0627\u0646\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b9%d8%aa%d8%a8%d8%b1%d8%aa%d8%b1%db%8c%d9%86-%d8%a8%d8%b1%d9%86%d8%af-%d8%a7%db%8c%d8%b1%d8%a7%d9%86%db%8c-%d8%af%d8%b1-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d9%88-%d8%b3%d8%a7%d8%ae%d8%aa-%d9%85\/#%D8%AA%D9%88%D9%84%DB%8C%D8%AF_%D8%B3%D9%81%D8%A7%D8%B1%D8%B4%DB%8C\" >\u062a\u0648\u0644\u06cc\u062f \u0633\u0641\u0627\u0631\u0634\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b9%d8%aa%d8%a8%d8%b1%d8%aa%d8%b1%db%8c%d9%86-%d8%a8%d8%b1%d9%86%d8%af-%d8%a7%db%8c%d8%b1%d8%a7%d9%86%db%8c-%d8%af%d8%b1-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d9%88-%d8%b3%d8%a7%d8%ae%d8%aa-%d9%85\/#%D9%82%DB%8C%D9%85%D8%AA_%D9%88_%DA%A9%DB%8C%D9%81%DB%8C%D8%AA\" >\u0642\u06cc\u0645\u062a \u0648 \u06a9\u06cc\u0641\u06cc\u062a<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b9%d8%aa%d8%a8%d8%b1%d8%aa%d8%b1%db%8c%d9%86-%d8%a8%d8%b1%d9%86%d8%af-%d8%a7%db%8c%d8%b1%d8%a7%d9%86%db%8c-%d8%af%d8%b1-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d9%88-%d8%b3%d8%a7%d8%ae%d8%aa-%d9%85\/#%D9%81%D8%B1%D9%87%D9%86%DA%AF%D8%9B_%D8%A7%D8%B2_%DA%AF%D8%B0%D8%B4%D8%AA%D9%87_%D8%AA%D8%A7_%D8%A2%DB%8C%D9%86%D8%AF%D9%87\" >\u0641\u0631\u0647\u0646\u06af\u061b \u0627\u0632 \u06af\u0630\u0634\u062a\u0647 \u062a\u0627 \u0622\u06cc\u0646\u062f\u0647<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h1><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%D8%AA%D8%A8%D8%B1%D8%AA%D8%B1%DB%8C%D9%86_%D8%A8%D8%B1%D9%86%D8%AF_%D8%A7%DB%8C%D8%B1%D8%A7%D9%86%DB%8C_%D8%AF%D8%B1_%D8%B7%D8%B1%D8%A7%D8%AD%DB%8C_%D9%88_%D8%B3%D8%A7%D8%AE%D8%AA_%D9%85%D8%A8%D9%84%D9%85%D8%A7%D9%86_%DA%A9%D8%AA%D8%A7%D8%A8%D8%AE%D8%A7%D9%86%D9%87%E2%80%8C%D8%A7%DB%8C\"><\/span>\u0645\u0639\u062a\u0628\u0631\u062a\u0631\u06cc\u0646 \u0628\u0631\u0646\u062f \u0627\u06cc\u0631\u0627\u0646\u06cc \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc \u0648 \u0633\u0627\u062e\u062a \u0645\u0628\u0644\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0627\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h1>\n<p>\u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0627\u0645\u0631\u0648\u0632 \u06a9\u0647 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0628\u0647 \u0641\u0636\u0627\u06cc\u06cc \u067e\u0648\u06cc\u0627 \u0628\u0631\u0627\u06cc \u0645\u0637\u0627\u0644\u0639\u0647\u060c \u06a9\u0627\u0631 \u0648 \u062a\u0639\u0627\u0645\u0644 \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647\u200c\u0627\u0646\u062f\u060c \u0627\u0647\u0645\u06cc\u062a \u0645\u0628\u0644\u0645\u0627\u0646 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0628\u06cc\u0634 \u0627\u0632 \u067e\u06cc\u0634 \u0646\u0645\u0627\u06cc\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0647\u0631 \u0641\u0636\u0627\u060c \u0627\u0632 \u06cc\u06a9 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647 \u0639\u0645\u0648\u0645\u06cc \u0628\u0632\u0631\u06af \u062a\u0627 \u06af\u0648\u0634\u0647 \u062f\u0646\u062c \u0645\u0637\u0627\u0644\u0639\u0647 \u062f\u0631 \u06cc\u06a9 \u0622\u067e\u0627\u0631\u062a\u0645\u0627\u0646 \u06a9\u0648\u0686\u06a9\u060c \u0646\u06cc\u0627\u0632\u0645\u0646\u062f \u0645\u0628\u0644\u0645\u0627\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0646\u0647\u200c\u062a\u0646\u0647\u0627 \u0632\u06cc\u0628\u0627 \u0628\u0627\u0634\u062f\u060c \u0628\u0644\u06a9\u0647 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0648 \u062f\u0648\u0627\u0645 \u0628\u0627\u0644\u0627\u06cc\u06cc \u0646\u06cc\u0632 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u06cc\u0627\u0646\u060c \u0646\u0627\u0645\u200c\u0647\u0627\u06cc\u06cc \u0628\u0647 \u0686\u0634\u0645 \u0645\u06cc\u200c\u062e\u0648\u0631\u0646\u062f \u06a9\u0647 \u0628\u0627 \u0646\u06af\u0627\u0647\u06cc \u0639\u0645\u06cc\u0642 \u0628\u0647 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0648 \u0628\u0627 \u062a\u0645\u0631\u06a9\u0632 \u0628\u0631 \u06a9\u06cc\u0641\u06cc\u062a\u060c \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u0633\u0627\u06cc\u0631 \u0631\u0642\u0628\u0627 \u0645\u062a\u0645\u0627\u06cc\u0632 \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f. \u0628\u0631\u0646\u062f \u0645\u0639\u062a\u0628\u0631 \u0645\u0628\u0644\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647 \u0627\u06cc\u060c \u062d\u0627\u0635\u0644 \u0633\u0627\u0644\u200c\u0647\u0627 \u062a\u062c\u0631\u0628\u0647 \u0648 \u062a\u0639\u0647\u062f \u0628\u0647 \u0627\u0635\u0648\u0644 \u06a9\u06cc\u0641\u06cc\u062a\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u062a\u0648\u0644\u06cc\u062f \u0647\u0631 \u0642\u0637\u0639\u0647 \u0627\u0632 \u0645\u0628\u0644\u0645\u0627\u0646\u060c \u0627\u0632 \u0637\u0631\u0627\u062d\u06cc \u062a\u0627 \u0627\u062c\u0631\u0627\u060c \u0646\u0645\u0648\u062f \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0635\u0646\u0627\u06cc\u0639 \u0686\u0648\u0628\u06cc \u0641\u0631\u0647\u0646\u06af \u0628\u0627 \u0631\u0648\u06cc\u06a9\u0631\u062f\u06cc \u0645\u062a\u0641\u0627\u0648\u062a\u060c \u062a\u0648\u0627\u0646\u0633\u062a\u0647 \u0627\u0633\u062a \u062c\u0627\u06cc\u06af\u0627\u0647 \u0648\u06cc\u0698\u0647\u200c\u0627\u06cc \u062f\u0631 \u0627\u06cc\u0646 \u0635\u0646\u0639\u062a \u0628\u0647 \u062f\u0633\u062a \u0622\u0648\u0631\u062f \u0648 \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u067e\u06cc\u0634\u06af\u0627\u0645\u0627\u0646 \u0634\u0646\u0627\u062e\u062a\u0647 \u0634\u0648\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/cdn.triboon.net\/media\/reportage_images\/debe4937-126d-4297-8920-a2273f899742.jpg\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B4%D8%A7%D8%AE%D8%B5%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D8%B9%D8%AA%D8%A8%D8%A7%D8%B1_%D8%B5%D9%86%D8%A7%DB%8C%D8%B9_%DA%86%D9%88%D8%A8%DB%8C_%D9%81%D8%B1%D9%87%D9%86%DA%AF\"><\/span>\u0634\u0627\u062e\u0635\u0647\u200c\u0647\u0627\u06cc \u0627\u0639\u062a\u0628\u0627\u0631 \u0635\u0646\u0627\u06cc\u0639 \u0686\u0648\u0628\u06cc \u0641\u0631\u0647\u0646\u06af<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u0639\u062a\u0628\u0627\u0631 \u06cc\u06a9 \u0628\u0631\u0646\u062f \u062a\u0646\u0647\u0627 \u0628\u0647 \u0642\u062f\u0645\u062a \u0622\u0646 \u0646\u06cc\u0633\u062a\u060c \u0628\u0644\u06a9\u0647 \u0628\u0647 \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u0627\u06cc \u0627\u0632 \u0639\u0648\u0627\u0645\u0644 \u0628\u0633\u062a\u06af\u06cc \u062f\u0627\u0631\u062f \u06a9\u0647 \u06a9\u06cc\u0641\u06cc\u062a\u060c \u062a\u0639\u0647\u062f \u0648 \u0646\u0648\u0622\u0648\u0631\u06cc \u0631\u0627 \u062f\u0631 \u0628\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f. \u0635\u0646\u0627\u06cc\u0639 \u0686\u0648\u0628\u06cc \u0641\u0631\u0647\u0646\u06af \u0628\u0627 \u062a\u06a9\u06cc\u0647 \u0628\u0631 \u0627\u06cc\u0646 \u0627\u0635\u0648\u0644\u060c \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u0627\u06cc \u0627\u0632 \u0634\u0627\u062e\u0635\u0647\u200c\u0647\u0627 \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u06a9\u0631\u062f\u0647 \u06a9\u0647 \u0622\u0646 \u0631\u0627 \u0627\u0632 \u0633\u0627\u06cc\u0631 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0645\u062a\u0645\u0627\u06cc\u0632 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<ul>\n<li><strong>\u0646\u0648\u0622\u0648\u0631\u06cc \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc:<\/strong> \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u062f\u0644\u0627\u06cc\u0644 \u0645\u0648\u0641\u0642\u06cc\u062a \u0641\u0631\u0647\u0646\u06af\u060c \u0631\u0648\u06cc\u06a9\u0631\u062f \u0646\u0648\u0622\u0648\u0631\u0627\u0646\u0647 \u0622\u0646 \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc \u0627\u0633\u062a. \u062a\u06cc\u0645 \u0637\u0631\u0627\u062d\u06cc \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0628\u0627 \u062f\u0631\u06a9 \u06a9\u0627\u0645\u0644 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0645\u062f\u0631\u0646\u060c \u0645\u0628\u0644\u0645\u0627\u0646\u06cc \u0631\u0627 \u062e\u0644\u0642 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0647\u0645 \u0627\u0632 \u0646\u0638\u0631 \u0632\u06cc\u0628\u0627\u06cc\u06cc\u200c\u0634\u0646\u0627\u062e\u062a\u06cc \u062c\u0630\u0627\u0628 \u0627\u0633\u062a \u0648 \u0647\u0645 \u0627\u0632 \u0646\u0638\u0631 \u0639\u0645\u0644\u06a9\u0631\u062f\u060c \u0627\u0646\u062a\u0638\u0627\u0631\u0627\u062a \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0631\u0627 \u0628\u0631\u0622\u0648\u0631\u062f\u0647 \u0645\u06cc\u200c\u0633\u0627\u0632\u062f. \u0627\u06cc\u0646 \u0631\u0648\u06cc\u06a9\u0631\u062f \u0628\u0647 \u0648\u06cc\u0698\u0647 \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc \u0645\u0628\u0644\u0645\u0627\u0646 \u0645\u0646\u0639\u0637\u0641 \u0628\u0631\u0627\u06cc \u0641\u0636\u0627\u0647\u0627\u06cc \u0686\u0646\u062f\u0645\u0646\u0638\u0648\u0631\u0647 \u0648 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc \u06a9\u0627\u0645\u0644\u0627\u064b \u0645\u0634\u0647\u0648\u062f \u0627\u0633\u062a.<\/li>\n<li><strong>\u06a9\u06cc\u0641\u06cc\u062a \u0645\u0648\u0627\u062f \u0627\u0648\u0644\u06cc\u0647:<\/strong> \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0686\u0648\u0628\u200c\u0647\u0627\u06cc \u0645\u0631\u063a\u0648\u0628 \u0648 \u0645\u062a\u0631\u06cc\u0627\u0644\u200c\u0647\u0627\u06cc \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a\u060c \u067e\u0627\u06cc\u0647 \u0648 \u0627\u0633\u0627\u0633 \u062f\u0648\u0627\u0645 \u0648 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0645\u0628\u0644\u0645\u0627\u0646 \u0627\u0633\u062a. \u0641\u0631\u0647\u0646\u06af \u0628\u0627 \u062f\u0642\u062a \u0628\u0627\u0644\u0627\u060c \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u0648\u0627\u062f \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062e\u0648\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u062a\u0636\u0645\u06cc\u0646 \u06a9\u0646\u062f \u06a9\u0647 \u0647\u0631 \u0645\u062d\u0635\u0648\u0644\u060c \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647\u200c\u06cc \u0645\u062f\u0627\u0648\u0645 \u0648 \u06af\u0630\u0631 \u0632\u0645\u0627\u0646 \u0645\u0642\u0627\u0648\u0645 \u0627\u0633\u062a.<\/li>\n<li><strong>\u062a\u0648\u062c\u0647 \u0628\u0647 \u062c\u0632\u0626\u06cc\u0627\u062a:<\/strong> \u0647\u0631 \u0642\u0637\u0639\u0647 \u0627\u0632 \u0645\u0628\u0644\u0645\u0627\u0646 \u0641\u0631\u0647\u0646\u06af\u060c \u0627\u0632 \u06a9\u0648\u0686\u06a9\u200c\u062a\u0631\u06cc\u0646 \u0627\u062a\u0635\u0627\u0644\u0627\u062a \u062a\u0627 \u067e\u0631\u062f\u0627\u062e\u062a \u0646\u0647\u0627\u06cc\u06cc\u060c \u0628\u0627 \u062f\u0642\u062a \u0628\u06cc\u200c\u0646\u0638\u06cc\u0631\u06cc \u0633\u0627\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u06cc\u0646 \u0648\u0633\u0648\u0627\u0633 \u062f\u0631 \u062c\u0632\u0626\u06cc\u0627\u062a\u060c \u0646\u0647\u200c\u062a\u0646\u0647\u0627 \u0628\u0647 \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0645\u062d\u0635\u0648\u0644 \u0645\u06cc\u200c\u0627\u0641\u0632\u0627\u06cc\u062f\u060c \u0628\u0644\u06a9\u0647 \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u0633\u062a\u062d\u06a9\u0627\u0645 \u0648 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0622\u0646 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/li>\n<li><strong>\u06af\u0627\u0631\u0627\u0646\u062a\u06cc \u0648 \u062e\u062f\u0645\u0627\u062a \u067e\u0633 \u0627\u0632 \u0641\u0631\u0648\u0634<\/strong>: \u062a\u0639\u0647\u062f \u06cc\u06a9 \u0628\u0631\u0646\u062f \u0628\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u0634 \u0628\u0627 \u0627\u0631\u0627\u0626\u0647 \u06af\u0627\u0631\u0627\u0646\u062a\u06cc \u0648 \u062e\u062f\u0645\u0627\u062a \u067e\u0633 \u0627\u0632 \u0641\u0631\u0648\u0634 \u06a9\u0627\u0645\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0635\u0646\u0627\u06cc\u0639 \u0686\u0648\u0628\u06cc \u0641\u0631\u0647\u0646\u06af \u0628\u0627 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062e\u0648\u062f\u060c \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u062f\u0631 \u0635\u0648\u0631\u062a \u0628\u0631\u0648\u0632 \u0647\u0631\u06af\u0648\u0646\u0647 \u0645\u0634\u06a9\u0644\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0631\u0648\u06cc \u06a9\u0645\u06a9 \u062a\u06cc\u0645 \u0645\u062a\u062e\u0635\u0635 \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u062d\u0633\u0627\u0628 \u06a9\u0646\u0646\u062f.<\/li>\n<li><strong>\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9<\/strong>: \u0645\u0628\u0644\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0627\u06cc \u0628\u0627\u06cc\u062f \u0628\u0647\u200c\u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u0648\u062f \u06a9\u0647 \u0627\u0632 \u0633\u0644\u0627\u0645\u062a \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u062f\u0631 \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a \u0645\u062d\u0627\u0641\u0638\u062a \u06a9\u0646\u062f. \u0641\u0631\u0647\u0646\u06af \u0628\u0627 \u0631\u0639\u0627\u06cc\u062a \u0627\u0635\u0648\u0644 \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u060c \u0645\u0628\u0644\u0645\u0627\u0646\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0628\u0647 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0637\u0648\u0644\u0627\u0646\u06cc \u0631\u0627 \u0628\u062f\u0648\u0646 \u0627\u062d\u0633\u0627\u0633 \u062e\u0633\u062a\u06af\u06cc \u06cc\u0627 \u0622\u0633\u06cc\u0628 \u0628\u0647 \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a\u060c \u0628\u0647 \u0645\u0637\u0627\u0644\u0639\u0647 \u06cc\u0627 \u06a9\u0627\u0631 \u0628\u067e\u0631\u062f\u0627\u0632\u0646\u062f.<\/li>\n<\/ul>\n<p>\u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0647\u0645\u060c \u0628\u0627\u0639\u062b \u0634\u062f\u0647\u200c\u0627\u0646\u062f \u06a9\u0647 <a href=\"https:\/\/farhangwood.com\/\" target=\"_blank\" rel=\"follow noopener\">\u0635\u0646\u0627\u06cc\u0639 \u0686\u0648\u0628 \u0641\u0631\u0647\u0646\u06af<\/a> \u0628\u0647 \u06cc\u06a9 \u0646\u0627\u0645 \u0642\u0627\u0628\u0644 \u0627\u0639\u062a\u0645\u0627\u062f \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0645\u0628\u0644\u0645\u0627\u0646 \u0627\u06cc\u0631\u0627\u0646 \u062a\u0628\u062f\u06cc\u0644 \u0634\u0648\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/cdn.triboon.net\/media\/reportage_images\/26787770-49fd-4e47-97d7-455eb7b05587.jpg\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A8%D8%B1%D8%B1%D8%B3%DB%8C_%D8%A7%D8%B3%D8%AA%D8%A7%D9%86%D8%AF%D8%A7%D8%B1%D8%AF%D9%87%D8%A7_%D9%88_%DA%AF%D9%88%D8%A7%D9%87%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%DA%A9%DB%8C%D9%81%DB%8C_%D9%81%D8%B1%D9%87%D9%86%DA%AF\"><\/span>\u0628\u0631\u0631\u0633\u06cc \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627 \u0648 \u06af\u0648\u0627\u0647\u06cc\u200c\u0647\u0627\u06cc \u06a9\u06cc\u0641\u06cc \u0641\u0631\u0647\u0646\u06af<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u06a9\u06cc\u0641\u06cc\u062a \u062f\u0631 \u0635\u0646\u0639\u062a \u0645\u0628\u0644\u0645\u0627\u0646 \u06cc\u06a9 \u0627\u062f\u0639\u0627 \u0646\u06cc\u0633\u062a\u060c \u0628\u0644\u06a9\u0647 \u0628\u0627\u06cc\u062f \u0628\u0627 \u0645\u062f\u0627\u0631\u06a9 \u0648 \u06af\u0648\u0627\u0647\u06cc\u200c\u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631 \u0627\u062b\u0628\u0627\u062a \u0634\u0648\u062f. \u0641\u0631\u0647\u0646\u06af \u062f\u0631 \u062a\u0648\u0644\u06cc\u062f\u0627\u062a \u062e\u0648\u062f\u060c \u0641\u0631\u0627\u062a\u0631 \u0627\u0632 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0645\u0644\u06cc \u0639\u0645\u0644 \u06a9\u0631\u062f\u0647 \u0648 \u0628\u0627 \u062f\u0631\u06cc\u0627\u0641\u062a \u06af\u0648\u0627\u0647\u06cc\u200c\u0647\u0627\u06cc \u06a9\u06cc\u0641\u06cc \u0645\u062e\u062a\u0644\u0641\u060c \u062a\u0639\u0647\u062f \u062e\u0648\u062f \u0628\u0647 \u0628\u0631\u062a\u0631\u06cc \u0631\u0627 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u06af\u0648\u0627\u0647\u06cc\u200c\u0647\u0627 \u0634\u0627\u0645\u0644 \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0647\u0633\u062a\u0646\u062f:<\/p>\n<ul>\n<li><strong>\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f ISO:<\/strong> \u0627\u06cc\u0646 \u06af\u0648\u0627\u0647\u06cc \u0646\u0634\u0627\u0646\u200c\u062f\u0647\u0646\u062f\u0647 \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u06cc\u0641\u06cc\u062a \u062c\u0627\u0645\u0639 \u062f\u0631 \u0641\u0631\u0627\u06cc\u0646\u062f\u0647\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u0627\u0633\u062a. \u062f\u0631\u06cc\u0627\u0641\u062a \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0639\u0646\u0627\u0633\u062a \u06a9\u0647 \u0641\u0631\u0647\u0646\u06af \u062f\u0631 \u062a\u0645\u0627\u0645 \u0645\u0631\u0627\u062d\u0644\u060c \u0627\u0632 \u0637\u0631\u0627\u062d\u06cc \u062a\u0627 \u062a\u062d\u0648\u06cc\u0644 \u0645\u062d\u0635\u0648\u0644\u060c \u0627\u0632 \u06cc\u06a9 \u0633\u06cc\u0633\u062a\u0645 \u0645\u062f\u06cc\u0631\u06cc\u062a\u06cc \u0645\u0646\u0633\u062c\u0645 \u0648 \u06a9\u0627\u0631\u0622\u0645\u062f \u067e\u06cc\u0631\u0648\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/li>\n<li><strong>\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0627\u06cc\u200c\u0646\u0645\u0627\u062f<\/strong>: \u0648\u062c\u0648\u062f \u0627\u06cc\u200c\u0646\u0645\u0627\u062f \u062f\u0631 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u06cc\u06a9 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u060c \u0646\u0634\u0627\u0646\u200c\u062f\u0647\u0646\u062f\u0647 \u0642\u0627\u0646\u0648\u0646\u06cc \u0628\u0648\u062f\u0646 \u0641\u0639\u0627\u0644\u06cc\u062a \u0648 \u0631\u0639\u0627\u06cc\u062a \u062d\u0642\u0648\u0642 \u0645\u0635\u0631\u0641\u200c\u06a9\u0646\u0646\u062f\u0647 \u0627\u0633\u062a. \u0635\u0646\u0627\u06cc\u0639 \u0686\u0648\u0628\u06cc \u0641\u0631\u0647\u0646\u06af \u0628\u0627 \u06a9\u0633\u0628 \u0627\u06cc\u0646 \u0646\u0645\u0627\u062f\u060c \u062a\u0639\u0647\u062f \u062e\u0648\u062f \u0628\u0647 \u0634\u0641\u0627\u0641\u06cc\u062a \u0648 \u0627\u06cc\u062c\u0627\u062f \u0627\u0639\u062a\u0645\u0627\u062f \u062f\u0631 \u062e\u0631\u06cc\u062f \u0622\u0646\u0644\u0627\u06cc\u0646 \u0631\u0627 \u0627\u062b\u0628\u0627\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/li>\n<li><strong>\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9:<\/strong> \u0645\u0628\u0644\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0627\u06cc \u0628\u0627\u06cc\u062f \u0628\u0647\u200c\u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u0648\u062f \u06a9\u0647 \u0633\u0644\u0627\u0645\u062a \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0631\u0627 \u062f\u0631 \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a \u062a\u0636\u0645\u06cc\u0646 \u06a9\u0646\u062f. \u0641\u0631\u0647\u0646\u06af \u0628\u0627 \u0631\u0639\u0627\u06cc\u062a \u0627\u0635\u0648\u0644 \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u060c \u0645\u0628\u0644\u0645\u0627\u0646\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0627\u0632 \u0622\u0633\u06cc\u0628\u200c\u0647\u0627\u06cc \u062c\u0633\u0645\u06cc \u0646\u0627\u0634\u06cc \u0627\u0632 \u0646\u0634\u0633\u062a\u0646 \u0637\u0648\u0644\u0627\u0646\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u0645\u062b\u0627\u0644\u060c \u0637\u0631\u0627\u062d\u06cc \u0645\u0646\u0627\u0633\u0628 \u067e\u0634\u062a\u06cc \u0635\u0646\u062f\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0647 \u0648 \u0627\u0631\u062a\u0641\u0627\u0639 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0645\u06cc\u0632\u0647\u0627\u060c \u0627\u0632 \u0645\u0648\u0627\u0631\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0627\u06cc\u0646 \u0628\u0631\u0646\u062f \u0628\u0647 \u062f\u0642\u062a \u0631\u0639\u0627\u06cc\u062a \u0645\u06cc\u200c\u0634\u0648\u062f.<\/li>\n<\/ul>\n<p>\u0647\u0645\u0686\u0646\u06cc\u0646 \u0644\u0627\u0632\u0645 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u0641\u0631\u0647\u0646\u06af \u0628\u0627 \u067e\u0627\u06cc\u0628\u0646\u062f\u06cc \u0628\u0647 \u0645\u0633\u0626\u0648\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u062e\u0648\u062f\u060c \u0627\u0632 \u0645\u0648\u0627\u062f \u0627\u0648\u0644\u06cc\u0647 \u067e\u0627\u06cc\u062f\u0627\u0631 \u0648 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u0633\u0627\u0632\u06af\u0627\u0631 \u0628\u0627 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0631\u0648\u06cc\u06a9\u0631\u062f \u0628\u0647 \u062d\u0641\u0638 \u0645\u0646\u0627\u0628\u0639 \u0637\u0628\u06cc\u0639\u06cc \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0646\u0634\u0627\u0646\u200c\u062f\u0647\u0646\u062f\u0647 \u0622\u06cc\u0646\u062f\u0647\u200c\u0646\u06af\u0631 \u0628\u0648\u062f\u0646 \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627 \u0648 \u06af\u0648\u0627\u0647\u06cc\u200c\u0647\u0627\u060c \u0645\u0647\u0631 \u062a\u0623\u06cc\u06cc\u062f\u06cc \u0628\u0631 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0627\u0639\u062a\u0628\u0627\u0631 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0641\u0631\u0647\u0646\u06af \u0647\u0633\u062a\u0646\u062f \u0648 \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062e\u0627\u0637\u0631 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u06a9\u0647 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0622\u0646\u200c\u0647\u0627 \u0631\u0648\u06cc \u06cc\u06a9 \u0645\u062d\u0635\u0648\u0644 \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0628\u0627\u062f\u0648\u0627\u0645 \u0627\u0633\u062a.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/cdn.triboon.net\/media\/reportage_images\/67aafc41-9407-47c3-b415-c92ef83bb6e8.jpg\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%DA%86%D8%B1%D8%A7_%D9%81%D8%B1%D9%87%D9%86%DA%AF_%D9%85%D8%B9%D8%AA%D8%A8%D8%B1%D8%AA%D8%B1%DB%8C%D9%86_%D8%A8%D8%B1%D9%86%D8%AF_%D8%A7%DB%8C%D8%B1%D8%A7%D9%86%DB%8C_%D8%A7%D8%B3%D8%AA%D8%9F\"><\/span>\u0686\u0631\u0627 \u0641\u0631\u0647\u0646\u06af \u0645\u0639\u062a\u0628\u0631\u062a\u0631\u06cc\u0646 \u0628\u0631\u0646\u062f \u0627\u06cc\u0631\u0627\u0646\u06cc \u0627\u0633\u062a\u061f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u06cc\u0646 \u0633\u0648\u0627\u0644 \u06a9\u0647 \u0686\u0631\u0627 \u0641\u0631\u0647\u0646\u06af \u0645\u0639\u062a\u0628\u0631\u062a\u0631\u06cc\u0646 \u0628\u0631\u0646\u062f \u0627\u06cc\u0631\u0627\u0646\u06cc \u0627\u0633\u062a\u061f \u0628\u0627\u06cc\u062f \u06af\u0641\u062a \u06a9\u0647 \u0627\u0639\u062a\u0628\u0627\u0631 \u06cc\u06a9 \u0628\u0631\u0646\u062f\u060c \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0627\u0632 \u0639\u0648\u0627\u0645\u0644 \u0645\u062e\u062a\u0644\u0641 \u0627\u0633\u062a \u06a9\u0647 \u062a\u062c\u0631\u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u060c \u062e\u062f\u0645\u0627\u062a \u067e\u0633 \u0627\u0632 \u0641\u0631\u0648\u0634 \u0648 \u0646\u06af\u0631\u0634 \u06a9\u0644\u06cc \u0628\u0647 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631 \u0631\u0627 \u062f\u0631 \u0628\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%BE%D8%A7%D8%B3%D8%AE%DA%AF%D9%88%DB%8C%DB%8C_%D9%88_%D8%AE%D8%AF%D9%85%D8%A7%D8%AA_%D9%BE%D8%B3_%D8%A7%D8%B2_%D9%81%D8%B1%D9%88%D8%B4\"><\/span>\u067e\u0627\u0633\u062e\u06af\u0648\u06cc\u06cc \u0648 \u062e\u062f\u0645\u0627\u062a \u067e\u0633 \u0627\u0632 \u0641\u0631\u0648\u0634<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><strong>\u062a\u0639\u0647\u062f \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc:<\/strong> \u0641\u0631\u0647\u0646\u06af \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062e\u0648\u062f \u0628\u0647 \u0686\u0634\u0645 \u0634\u0631\u06a9\u0627\u06cc \u0628\u0644\u0646\u062f\u0645\u062f\u062a \u0646\u06af\u0627\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0628\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u0634\u0627\u0648\u0631\u0647\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc \u0642\u0628\u0644 \u0627\u0632 <a href=\"https:\/\/farhangwood.com\/product-category\/office-furniture\/\" target=\"_blank\" rel=\"follow noopener\">\u062e\u0631\u06cc\u062f \u0645\u0628\u0644\u0645\u0627\u0646 \u0622\u0645\u0648\u0632\u0634\u06cc \u0648 \u0627\u062f\u0627\u0631\u06cc<\/a> \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u06a9\u0627\u0645\u0644 \u067e\u0633 \u0627\u0632 \u0641\u0631\u0648\u0634\u060c \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0628\u06cc\u200c\u0646\u0638\u06cc\u0631 \u0628\u0631\u0627\u06cc \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062e\u0648\u062f \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/li>\n<li><strong>\u06af\u0627\u0631\u0627\u0646\u062a\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a:<\/strong> \u062a\u0645\u0627\u0645\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0641\u0631\u0647\u0646\u06af \u062f\u0627\u0631\u0627\u06cc \u06af\u0627\u0631\u0627\u0646\u062a\u06cc \u0645\u0639\u062a\u0628\u0631 \u0647\u0633\u062a\u0646\u062f. \u0627\u06cc\u0646 \u06af\u0627\u0631\u0627\u0646\u062a\u06cc\u060c \u0646\u0647\u200c\u062a\u0646\u0647\u0627 \u0646\u0634\u0627\u0646\u200c\u062f\u0647\u0646\u062f\u0647 \u0627\u0639\u062a\u0645\u0627\u062f \u0628\u0631\u0646\u062f \u0628\u0647 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062e\u0648\u062f \u0627\u0633\u062a\u060c \u0628\u0644\u06a9\u0647 \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u062f\u0631 \u0635\u0648\u0631\u062a \u0628\u0631\u0648\u0632 \u0647\u0631\u06af\u0648\u0646\u0647 \u0645\u0634\u06a9\u0644\u060c \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0644\u0627\u0632\u0645 \u0631\u0627 \u062f\u0631\u06cc\u0627\u0641\u062a \u062e\u0648\u0627\u0647\u0646\u062f \u06a9\u0631\u062f.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B1%D9%88%DB%8C%DA%A9%D8%B1%D8%AF_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C%E2%80%8C%D9%85%D8%AD%D9%88%D8%B1_%D8%AF%D8%B1_%D8%B7%D8%B1%D8%A7%D8%AD%DB%8C\"><\/span>\u0631\u0648\u06cc\u06a9\u0631\u062f \u0645\u0634\u062a\u0631\u06cc\u200c\u0645\u062d\u0648\u0631 \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0646\u0642\u0627\u0637 \u0642\u0648\u062a \u0627\u0635\u0644\u06cc \u0641\u0631\u0647\u0646\u06af\u060c \u062a\u0648\u062c\u0647 \u0628\u0647 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0648\u0627\u0642\u0639\u06cc \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0628\u0631\u0646\u062f \u0628\u0627 \u0634\u0646\u06cc\u062f\u0646 \u0646\u0638\u0631\u0627\u062a \u0648 \u0628\u0627\u0632\u062e\u0648\u0631\u062f\u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646\u060c \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0647\u200c\u0637\u0648\u0631 \u0645\u062f\u0627\u0648\u0645 \u0628\u0647\u0628\u0648\u062f \u0645\u06cc\u200c\u0628\u062e\u0634\u062f. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644\u060c \u0637\u0631\u0627\u062d\u06cc\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f \u0645\u06cc\u0632 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647 \u062f\u0631 \u067e\u0627\u0633\u062e \u0628\u0647 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0641\u0636\u0627\u0647\u0627\u06cc \u06a9\u0648\u0686\u06a9 \u0648 \u0686\u0646\u062f\u0645\u0646\u0638\u0648\u0631\u0647 \u0627\u0646\u062c\u0627\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0631\u0648\u06cc\u06a9\u0631\u062f \u062a\u0639\u0627\u0645\u0644\u06cc\u060c \u0641\u0631\u0647\u0646\u06af \u0631\u0627 \u0628\u0647 \u06cc\u06a9 \u0634\u0631\u06cc\u06a9 \u0642\u0627\u0628\u0644 \u0627\u0639\u062a\u0645\u0627\u062f \u062f\u0631 \u062e\u0644\u0642 \u0641\u0636\u0627\u0647\u0627\u06cc \u0622\u0645\u0648\u0632\u0634\u06cc \u0648 \u0641\u0631\u0647\u0646\u06af\u06cc \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B5%D8%A7%D9%84%D8%AA_%D9%88_%D9%87%D9%88%DB%8C%D8%AA_%D8%A7%DB%8C%D8%B1%D8%A7%D9%86%DB%8C\"><\/span>\u0627\u0635\u0627\u0644\u062a \u0648 \u0647\u0648\u06cc\u062a \u0627\u06cc\u0631\u0627\u0646\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0641\u0631\u0647\u0646\u06af \u0628\u0627 \u0627\u0644\u0647\u0627\u0645 \u0627\u0632 \u0647\u0646\u0631 \u0648 \u0645\u0639\u0645\u0627\u0631\u06cc \u0627\u06cc\u0631\u0627\u0646\u06cc\u060c \u0645\u0628\u0644\u0645\u0627\u0646\u06cc \u0631\u0627 \u0637\u0631\u0627\u062d\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0639\u06cc\u0646 \u062d\u0627\u0644 \u06a9\u0647 \u0645\u062f\u0631\u0646 \u0627\u0633\u062a\u060c \u062d\u0633 \u0648 \u062d\u0627\u0644 \u0627\u0635\u0627\u0644\u062a \u0631\u0627 \u062f\u0631 \u062e\u0648\u062f \u062f\u0627\u0631\u062f. \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0637\u0631\u062d\u200c\u0647\u0627\u06cc \u0628\u0648\u0645\u06cc \u0648 \u062a\u0631\u06a9\u06cc\u0628 \u0622\u0646\u200c\u0647\u0627 \u0628\u0627 \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc\u200c\u0647\u0627\u06cc \u0631\u0648\u0632\u060c \u0628\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0627\u06cc\u0646 \u0628\u0631\u0646\u062f \u0647\u0648\u06cc\u062a\u06cc \u062e\u0627\u0635 \u0645\u06cc\u200c\u0628\u062e\u0634\u062f \u06a9\u0647 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0645\u0634\u0627\u0628\u0647\u06cc \u0646\u062f\u0627\u0631\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%D9%88%D9%84%DB%8C%D8%AF_%D8%B3%D9%81%D8%A7%D8%B1%D8%B4%DB%8C\"><\/span>\u062a\u0648\u0644\u06cc\u062f \u0633\u0641\u0627\u0631\u0634\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0648 \u0641\u0636\u0627\u0647\u0627\u06cc \u0641\u0631\u0647\u0646\u06af\u06cc \u062f\u0627\u0631\u0627\u06cc \u0627\u0628\u0639\u0627\u062f \u0648 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0645\u0646\u062d\u0635\u0631\u0628\u0647\u200c\u0641\u0631\u062f\u06cc \u0647\u0633\u062a\u0646\u062f. \u0641\u0631\u0647\u0646\u06af \u0628\u0627 \u0627\u0631\u0627\u0626\u0647 \u062e\u062f\u0645\u0627\u062a \u062a\u0648\u0644\u06cc\u062f \u0633\u0641\u0627\u0631\u0634\u06cc\u060c \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062f\u0642\u06cc\u0642\u0627\u064b \u0647\u0645\u0627\u0646 \u0645\u0628\u0644\u0645\u0627\u0646\u06cc \u0631\u0627 \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u0646\u062f \u06a9\u0647 \u0628\u0647 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0646\u062d\u0648 \u0628\u0627 \u0641\u0636\u0627\u06cc \u0622\u0646\u200c\u0647\u0627 \u0647\u0645\u0627\u0647\u0646\u06af \u0627\u0633\u062a.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%82%DB%8C%D9%85%D8%AA_%D9%88_%DA%A9%DB%8C%D9%81%DB%8C%D8%AA\"><\/span>\u0642\u06cc\u0645\u062a \u0648 \u06a9\u06cc\u0641\u06cc\u062a<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0647\u0646\u06af\u0627\u0645 \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0628\u0644\u0645\u0627\u0646\u060c \u0642\u06cc\u0645\u062a <a href=\"https:\/\/farhangwood.com\/product-category\/office-furniture\/\" target=\"_blank\" rel=\"follow noopener\">\u0645\u0628\u0644\u0645\u0627\u0646 \u0627\u062f\u0627\u0631\u06cc \u0648 \u0622\u0645\u0648\u0632\u0634\u06cc<\/a>\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06cc\u06a9 \u0639\u0627\u0645\u0644 \u062a\u0639\u06cc\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0628\u0627\u0634\u062f\u060c \u0627\u0645\u0627 \u0646\u0628\u0627\u06cc\u062f \u062a\u0646\u0647\u0627 \u0645\u0639\u06cc\u0627\u0631 \u0628\u0627\u0634\u062f. \u0645\u0628\u0644\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0627\u06cc \u06cc\u06a9 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0628\u0644\u0646\u062f\u0645\u062f\u062a \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0635\u0648\u0631\u062a \u0627\u0646\u062a\u062e\u0627\u0628 \u0635\u062d\u06cc\u062d\u060c \u0633\u0627\u0644\u200c\u0647\u0627 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a. \u0628\u0627 \u0627\u06cc\u0646\u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0628\u0627 \u0642\u06cc\u0645\u062a \u067e\u0627\u06cc\u06cc\u0646\u200c\u062a\u0631 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0645\u0648\u062c\u0648\u062f \u0628\u0627\u0634\u0646\u062f\u060c \u0627\u0645\u0627 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0627\u063a\u0644\u0628 \u0627\u0632 \u06a9\u06cc\u0641\u06cc\u062a \u067e\u0627\u06cc\u06cc\u0646\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631\u0646\u062f \u0648 \u062f\u0631 \u062f\u0631\u0627\u0632\u0645\u062f\u062a \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u0639\u0645\u06cc\u0631 \u06cc\u0627 \u062a\u0639\u0648\u06cc\u0636 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062e\u0648\u0627\u0647\u0646\u062f \u062f\u0627\u0634\u062a.<\/p>\n<p>\u0641\u0631\u0647\u0646\u06af \u0628\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc \u06a9\u0647 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0627\u0632 \u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628 \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0647\u0633\u062a\u0646\u062f\u060c \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u0647\u0648\u0634\u0645\u0646\u062f\u0627\u0646\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u062a\u0639\u0627\u062f\u0644 \u0628\u06cc\u0646 \u0627\u06cc\u0646 \u062f\u0648 \u0639\u0627\u0645\u0644\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u062f\u0644\u0627\u06cc\u0644\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0641\u0631\u0647\u0646\u06af \u0631\u0627 \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0628\u0631\u0646\u062f \u0645\u0639\u062a\u0628\u0631 \u0645\u0628\u0644\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647 \u0627\u06cc \u0645\u0639\u0631\u0641\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0647\u0631 \u0642\u0637\u0639\u0647 \u0645\u06cc\u0632 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647 \u06a9\u0647 \u062a\u0648\u0633\u0637 \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0646\u062a\u06cc\u062c\u0647\u200c\u06cc \u06cc\u06a9 \u0641\u0631\u0627\u06cc\u0646\u062f \u062f\u0642\u06cc\u0642 \u0648 \u06a9\u0646\u062a\u0631\u0644\u200c\u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u062a\u0636\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u06a9\u06cc\u0641\u06cc\u062a \u0646\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%81%D8%B1%D9%87%D9%86%DA%AF%D8%9B_%D8%A7%D8%B2_%DA%AF%D8%B0%D8%B4%D8%AA%D9%87_%D8%AA%D8%A7_%D8%A2%DB%8C%D9%86%D8%AF%D9%87\"><\/span>\u0641\u0631\u0647\u0646\u06af\u061b \u0627\u0632 \u06af\u0630\u0634\u062a\u0647 \u062a\u0627 \u0622\u06cc\u0646\u062f\u0647<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0635\u0646\u0627\u06cc\u0639 \u0686\u0648\u0628 \u0641\u0631\u0647\u0646\u06af \u0628\u0627 \u0633\u0627\u0628\u0642\u0647\u200c\u0627\u06cc \u062f\u0631\u062e\u0634\u0627\u0646 \u062f\u0631 \u0635\u0646\u0639\u062a \u0645\u0628\u0644\u0645\u0627\u0646\u060c \u0627\u0632 \u0647\u0645\u0627\u0646 \u0627\u0628\u062a\u062f\u0627 \u0628\u0627 \u0647\u062f\u0641 \u0627\u06cc\u062c\u0627\u062f \u062a\u062d\u0648\u0644 \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc \u0648 \u062a\u0648\u0644\u06cc\u062f \u0645\u0628\u0644\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0627\u06cc \u062a\u0623\u0633\u06cc\u0633 \u0634\u062f. \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0628\u0627 \u067e\u0634\u062a\u06a9\u0627\u0631 \u0648 \u0646\u0648\u0622\u0648\u0631\u06cc\u060c \u062a\u0648\u0627\u0646\u0633\u062a \u062c\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0628\u0631\u062c\u0633\u062a\u0647 \u0628\u0627\u0632 \u06a9\u0646\u062f \u0648 \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0627\u0644\u06af\u0648 \u0628\u0631\u0627\u06cc \u0633\u0627\u06cc\u0631 \u0628\u0631\u0646\u062f\u0647\u0627 \u0645\u0637\u0631\u062d \u0634\u0648\u062f. \u0628\u0627 \u0646\u06af\u0627\u0647\u06cc \u0628\u0647 \u0622\u06cc\u0646\u062f\u0647\u060c \u0641\u0631\u0647\u0646\u06af \u062f\u0631 \u0646\u0638\u0631 \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0627 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0628\u0631 \u0631\u0648\u06cc \u0641\u0646\u0627\u0648\u0631\u06cc\u200c\u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u0648 \u062a\u062d\u0642\u06cc\u0642 \u0648 \u062a\u0648\u0633\u0639\u0647\u060c \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u06cc\u0634 \u0627\u0632 \u067e\u06cc\u0634 \u0628\u0647\u0628\u0648\u062f \u0628\u062e\u0634\u062f \u0648 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u062f\u0631 \u062d\u0627\u0644 \u062a\u063a\u06cc\u06cc\u0631 \u0628\u0627\u0632\u0627\u0631 \u0631\u0627 \u0628\u0631\u0622\u0648\u0631\u062f\u0647 \u0633\u0627\u0632\u062f.<\/p>\n<p><strong>\u0633\u062e\u0646 \u067e\u0627\u06cc\u0627\u0646\u06cc<\/strong><\/p>\n<p>\u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u067e\u0631\u0631\u0642\u0627\u0628\u062a \u0627\u0645\u0631\u0648\u0632\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u06cc\u06a9 \u0628\u0631\u0646\u062f \u0645\u0639\u062a\u0628\u0631 \u0645\u0628\u0644\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647 \u0627\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0686\u0627\u0644\u0634\u200c\u0628\u0631\u0627\u0646\u06af\u06cc\u0632 \u0628\u0627\u0634\u062f. \u0627\u0645\u0627 \u0628\u0627 \u0628\u0631\u0631\u0633\u06cc \u062f\u0642\u06cc\u0642 \u0634\u0627\u062e\u0635\u0647\u200c\u0647\u0627\u06cc \u0627\u0639\u062a\u0628\u0627\u0631\u060c \u0645\u0627\u0646\u0646\u062f \u06a9\u06cc\u0641\u06cc\u062a \u0645\u0648\u0627\u062f \u0627\u0648\u0644\u06cc\u0647\u060c \u0637\u0631\u0627\u062d\u06cc \u0646\u0648\u0622\u0648\u0631\u0627\u0646\u0647 \u0648 \u062a\u0639\u0647\u062f \u0628\u0647 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u06cc\u06a9 \u0646\u062a\u06cc\u062c\u0647\u200c\u06af\u06cc\u0631\u06cc \u0642\u0637\u0639\u06cc \u0631\u0633\u06cc\u062f. \u0635\u0646\u0627\u06cc\u0639 \u0686\u0648\u0628\u06cc \u0641\u0631\u0647\u0646\u06af \u0628\u0627 \u0631\u0648\u06cc\u06a9\u0631\u062f\u06cc \u062c\u0627\u0645\u0639 \u0648 \u0645\u0634\u062a\u0631\u06cc\u200c\u0645\u062d\u0648\u0631\u060c \u0646\u0647\u200c\u062a\u0646\u0647\u0627 \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0628\u0627\u062f\u0648\u0627\u0645 \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0628\u0644\u06a9\u0647 \u0628\u0627 \u0627\u0631\u0627\u0626\u0647 \u062e\u062f\u0645\u0627\u062a \u067e\u0633 \u0627\u0632 \u0641\u0631\u0648\u0634 \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u06a9\u0627\u0645\u0644\u060c \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0628\u06cc\u200c\u0646\u0638\u06cc\u0631 \u0628\u0631\u0627\u06cc \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062e\u0648\u062f \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u0622\u0648\u0631\u062f.<\/p>\n<p>\u0627\u06cc\u0646 \u0639\u0648\u0627\u0645\u0644\u060c \u062f\u0631 \u06a9\u0646\u0627\u0631 \u062a\u0648\u062c\u0647 \u0628\u0647 \u062c\u0632\u0626\u06cc\u0627\u062a \u0648 \u0627\u0635\u0627\u0644\u062a \u0637\u0631\u062d\u200c\u0647\u0627\u060c \u0641\u0631\u0647\u0646\u06af \u0631\u0627 \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u0645\u0639\u062a\u0628\u0631\u062a\u0631\u06cc\u0646 \u0628\u0631\u0646\u062f \u0627\u06cc\u0631\u0627\u0646\u06cc \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0637\u0631\u0627\u062d\u06cc \u0648 \u0633\u0627\u062e\u062a \u0645\u0628\u0644\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0627\u06cc \u0645\u0639\u0631\u0641\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u0646\u062a\u062e\u0627\u0628 \u0641\u0631\u0647\u0646\u06af\u060c \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0631\u0648\u06cc \u06a9\u06cc\u0641\u06cc\u062a\u060c \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0648 \u0622\u0631\u0627\u0645\u0634 \u062f\u0631 \u0641\u0636\u0627\u06cc \u0645\u0637\u0627\u0644\u0639\u0647 \u0648 \u06a9\u0627\u0631 \u0627\u0633\u062a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0627\u0645\u0631\u0648\u0632 \u06a9\u0647 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0628\u0647 \u0641\u0636\u0627\u06cc\u06cc \u067e\u0648\u06cc\u0627 \u0628\u0631\u0627\u06cc \u0645\u0637\u0627\u0644\u0639\u0647\u060c \u06a9\u0627\u0631 \u0648 \u062a\u0639\u0627\u0645\u0644 \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647\u200c\u0627\u0646\u062f\u060c \u0627\u0647\u0645\u06cc\u062a \u0645\u0628\u0644\u0645\u0627\u0646 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0628\u06cc\u0634 \u0627\u0632 \u067e\u06cc\u0634 \u0646\u0645\u0627\u06cc\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0647\u0631 \u0641\u0636\u0627\u060c \u0627\u0632 \u06cc\u06a9 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647 \u0639\u0645\u0648\u0645\u06cc \u0628\u0632\u0631\u06af \u062a\u0627 \u06af\u0648\u0634\u0647 \u062f\u0646\u062c \u0645\u0637\u0627\u0644\u0639\u0647 \u062f\u0631 \u06cc\u06a9 \u0622\u067e\u0627\u0631\u062a\u0645\u0627\u0646 \u06a9\u0648\u0686\u06a9\u060c \u0646\u06cc\u0627\u0632\u0645\u0646\u062f \u0645\u0628\u0644\u0645\u0627\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0646\u0647\u200c\u062a\u0646\u0647\u0627 \u0632\u06cc\u0628\u0627 \u0628\u0627\u0634\u062f\u060c \u0628\u0644\u06a9\u0647 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0648 \u062f\u0648\u0627\u0645 \u0628\u0627\u0644\u0627\u06cc\u06cc \u0646\u06cc\u0632 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u06cc\u0627\u0646\u060c \u0646\u0627\u0645\u200c\u0647\u0627\u06cc\u06cc \u0628\u0647 \u0686\u0634\u0645 \u0645\u06cc\u200c\u062e\u0648\u0631\u0646\u062f \u06a9\u0647 \u0628\u0627 \u0646\u06af\u0627\u0647\u06cc \u0639\u0645\u06cc\u0642 \u0628\u0647 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0648 \u0628\u0627 \u062a\u0645\u0631\u06a9\u0632 \u0628\u0631 \u06a9\u06cc\u0641\u06cc\u062a\u060c \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u0633\u0627\u06cc\u0631 \u0631\u0642\u0628\u0627 \u0645\u062a\u0645\u0627\u06cc\u0632 \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f. \u0628\u0631\u0646\u062f \u0645\u0639\u062a\u0628\u0631 \u0645\u0628\u0644\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647 \u0627\u06cc\u060c \u062d\u0627\u0635\u0644 \u0633\u0627\u0644\u200c\u0647\u0627 \u062a\u062c\u0631\u0628\u0647 \u0648 \u062a\u0639\u0647\u062f \u0628\u0647 \u0627\u0635\u0648\u0644 \u06a9\u06cc\u0641\u06cc\u062a\u06cc \u0627\u0633\u062a&#8230;<\/p>\n","protected":false},"author":3,"featured_media":52093,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[678],"tags":[],"class_list":["post-52092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-678"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/52092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=52092"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/52092\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/52093"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=52092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=52092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=52092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}