{"id":49454,"date":"2025-01-04T11:27:26","date_gmt":"2025-01-04T07:57:26","guid":{"rendered":"https:\/\/decorshop.ir\/mag\/?p=49454"},"modified":"2025-01-04T11:29:24","modified_gmt":"2025-01-04T07:59:24","slug":"%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/","title":{"rendered":"\u0622\u0634\u0646\u0627\u06cc\u06cc \u06a9\u0627\u0645\u0644 \u0628\u0627 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc (Gravity) | \u0622\u0631\u0627\u0645\u0634 \u062f\u0631 \u0644\u062d\u0638\u0647 | \u062a\u0631\u0646\u062f 2025"},"content":{"rendered":"<p><strong>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc (Gravity)<\/strong> \u06cc\u06a9\u06cc \u0627\u0632 \u0646\u0648\u0622\u0648\u0631\u0627\u0646\u0647\u200c\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc <strong><a href=\"https:\/\/decorshop.ir\/product-category\/%d8%b5%d9%86%d8%af%d9%84%db%8c-%d8%a7%d8%af%d8%a7%d8%b1%db%8c\/\">\u0635\u0646\u062f\u0644\u06cc \u0627\u062f\u0627\u0631\u06cc<\/a><\/strong> \u0648 \u062e\u0627\u0646\u06af\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u0647\u062f\u0641 \u0627\u06cc\u062c\u0627\u062f \u0631\u0627\u062d\u062a\u06cc \u0648 \u0622\u0631\u0627\u0645\u0634 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u06a9\u0627\u0631 \u06cc\u0627 \u062f\u0641\u062a\u0631 \u06a9\u0627\u0631 \u062e\u0627\u0646\u06af\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 <a href=\"https:\/\/decorshop.ir\/product-category\/%d8%b5%d9%86%d8%af%d9%84%db%8c-%d8%a7%d8%af%d8%a7%d8%b1%db%8c\/\"><strong>\u062e\u0631\u06cc\u062f \u0635\u0646\u062f\u0644\u06cc \u0627\u062f\u0627\u0631\u06cc<\/strong><\/a> \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0632 \u0646\u0634\u0633\u062a\u0646 \u0628\u0647 \u0634\u0645\u0627 \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u062f\u060c \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0627\u0634\u062f.<\/p>\n<p>\u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0627 \u0637\u0631\u0627\u062d\u06cc \u0645\u0646\u062d\u0635\u0631 \u0628\u0647 \u0641\u0631\u062f \u062e\u0648\u062f\u060c \u0627\u0645\u06a9\u0627\u0646 \u062a\u0648\u0632\u06cc\u0639 \u0645\u062a\u0639\u0627\u062f\u0644 \u0648\u0632\u0646 \u0628\u062f\u0646 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u06a9\u0631\u062f\u0647 \u0648 \u0641\u0634\u0627\u0631 \u0628\u0631 \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 <strong>\u062f\u06a9\u0648\u0631\u0645\u06af<\/strong> \u0642\u0635\u062f \u062f\u0627\u0631\u06cc\u0645 \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u060c \u0645\u0632\u0627\u06cc\u0627 \u0648 \u06a9\u0627\u0631\u0628\u0631\u062f\u0647\u0627\u06cc \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u067e\u0631\u062f\u0627\u0632\u06cc\u0645 \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0627 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/p>\n<hr \/>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" >\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0686\u06cc\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D8%B7%D8%B1%D8%A7%D8%AD_%D9%88_%D8%B3%D8%A7%D8%B2%D9%86%D8%AF%D9%87_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C_%DA%A9%DB%8C%D8%B3%D8%AA%D8%9F\" >\u0637\u0631\u0627\u062d \u0648 \u0633\u0627\u0632\u0646\u062f\u0647 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u06a9\u06cc\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D9%88%DB%8C%DA%98%DA%AF%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D8%B5%D9%84%DB%8C_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C\" >\u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0627\u0635\u0644\u06cc \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D8%B7%D8%B1%D8%A7%D8%AD%DB%8C_%D8%A7%D8%B1%DA%AF%D9%88%D9%86%D9%88%D9%85%DB%8C%DA%A9\" >\u0637\u0631\u0627\u062d\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D9%82%D8%A7%D8%A8%D9%84%DB%8C%D8%AA_%D8%AA%D9%86%D8%B8%DB%8C%D9%85_%D8%B2%D8%A7%D9%88%DB%8C%D9%87\" >\u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u0646\u0638\u06cc\u0645 \u0632\u0627\u0648\u06cc\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D8%AC%D9%86%D8%B3_%D9%85%D8%B1%D8%BA%D9%88%D8%A8_%D9%85%D9%88%D8%A7%D8%AF\" >\u062c\u0646\u0633 \u0645\u0631\u063a\u0648\u0628 \u0645\u0648\u0627\u062f<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C\" >\u06a9\u0627\u0631\u0628\u0631\u062f \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%DA%86%D8%B1%D8%A7_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C_%D9%85%D8%AD%D8%A8%D9%88%D8%A8_%D8%A7%D8%B3%D8%AA%D8%9F\" >\u0686\u0631\u0627 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0645\u062d\u0628\u0648\u0628 \u0627\u0633\u062a\u061f<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D8%A2%D8%B1%D8%A7%D9%85%D8%B4_%D8%AF%D8%B1_%D9%84%D8%AD%D8%B8%D9%87_%D8%A8%D8%A7_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C\" >\u0622\u0631\u0627\u0645\u0634 \u062f\u0631 \u0644\u062d\u0638\u0647 \u0628\u0627 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%AA%D9%85%D8%B1%DA%A9%D8%B2\" >\u0627\u0641\u0632\u0627\u06cc\u0634 \u062a\u0645\u0631\u06a9\u0632<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D8%B7%D8%B1%D8%A7%D8%AD%DB%8C_%D8%B4%DB%8C%DA%A9_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C\" >\u0637\u0631\u0627\u062d\u06cc \u0634\u06cc\u06a9 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D9%85%D8%B2%D8%A7%DB%8C%D8%A7%DB%8C_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C\" >\u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%DA%A9%D8%A7%D9%87%D8%B4_%D9%81%D8%B4%D8%A7%D8%B1_%D8%A8%D8%B1_%D8%B3%D8%AA%D9%88%D9%86_%D9%81%D9%82%D8%B1%D8%A7%D8%AA\" >\u06a9\u0627\u0647\u0634 \u0641\u0634\u0627\u0631 \u0628\u0631 \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D8%AF%D8%B1%D8%AF%D9%87%D8%A7%DB%8C_%D8%B9%D8%B6%D9%84%D8%A7%D9%86%DB%8C\" >\u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062f\u0631\u062f\u0647\u0627\u06cc \u0639\u0636\u0644\u0627\u0646\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D8%A8%D9%87%D8%A8%D9%88%D8%AF_%D8%AC%D8%B1%DB%8C%D8%A7%D9%86_%D8%AE%D9%88%D9%86\" >\u0628\u0647\u0628\u0648\u062f \u062c\u0631\u06cc\u0627\u0646 \u062e\u0648\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%D8%AD%D8%B3_%D8%B1%D8%A7%D8%AD%D8%AA%DB%8C_%D9%88_%D8%A2%D8%B1%D8%A7%D9%85%D8%B4_%D8%AF%D8%B1_%D9%85%D8%AD%DB%8C%D8%B7_%DA%A9%D8%A7%D8%B1\" >\u0627\u06cc\u062c\u0627\u062f \u062d\u0633 \u0631\u0627\u062d\u062a\u06cc \u0648 \u0622\u0631\u0627\u0645\u0634 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u06a9\u0627\u0631<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D9%86%D8%AD%D9%88%D9%87_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D9%88_%D8%AE%D8%B1%DB%8C%D8%AF_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C\" >\u0646\u062d\u0648\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0648 \u062e\u0631\u06cc\u062f \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D8%AA%D9%81%D8%A7%D9%88%D8%AA_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C_%D8%A8%D8%A7_%D8%B3%D8%A7%DB%8C%D8%B1_%D8%B5%D9%86%D8%AF%D9%84%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D8%AF%D8%A7%D8%B1%DB%8C\" >\u062a\u0641\u0627\u0648\u062a \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u0633\u0627\u06cc\u0631 \u0635\u0646\u062f\u0644\u06cc\u200c\u0647\u0627\u06cc \u0627\u062f\u0627\u0631\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D8%B9%D9%85%D9%84%DA%A9%D8%B1%D8%AF_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C_%DA%86%DA%AF%D9%88%D9%86%D9%87_%D8%A7%D8%B3%D8%AA%D8%9F\" >\u0639\u0645\u0644\u06a9\u0631\u062f \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0686\u06af\u0648\u0646\u0647 \u0627\u0633\u062a\u061f<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%DA%86%DA%AF%D9%88%D9%86%D9%87_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C_%D8%B1%D8%A7_%D8%A8%D8%A7_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D8%AA%D8%B1%DA%A9%DB%8C%D8%A8_%DA%A9%D9%86%DB%8C%D9%85%D8%9F\" >\u0686\u06af\u0648\u0646\u0647 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0631\u0627 \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062a\u0631\u06a9\u06cc\u0628 \u06a9\u0646\u06cc\u0645\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b4%d9%86%d8%a7%db%8c%db%8c-%da%a9%d8%a7%d9%85%d9%84-%d8%a8%d8%a7-%d8%b5%d9%86%d8%af%d9%84%db%8c-%da%af%d8%b1%d8%a7%d9%88%db%8c%d8%aa%db%8c-gravity\/#%D8%AC%D9%85%D8%B9_%D8%A8%D9%86%D8%AF%DB%8C\" >\u062c\u0645\u0639 \u0628\u0646\u062f\u06cc<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0686\u06cc\u0633\u062a\u061f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0646\u0648\u0639\u06cc \u0635\u0646\u062f\u0644\u06cc \u0645\u062f\u0631\u0646 \u0648 \u067e\u06cc\u0634\u0631\u0641\u062a\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u0647\u062f\u0641 \u06a9\u0627\u0647\u0634 \u0627\u0633\u062a\u0631\u0633\u200c\u0647\u0627\u06cc \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u0628\u062f\u0646 \u0648 \u0627\u06cc\u062c\u0627\u062f \u0622\u0631\u0627\u0645\u0634 \u062f\u0631 \u0637\u0648\u0644 \u0631\u0648\u0632 \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0627 \u0627\u0644\u0647\u0627\u0645 \u0627\u0632 \u062d\u0627\u0644\u062a \u0628\u06cc\u200c\u0648\u0632\u0646\u06cc \u062f\u0631 \u0641\u0636\u0627\u060c \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0632 \u0646\u0634\u0633\u062a\u0646 \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0637\u0631\u0627\u062d\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u0622\u0646 \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u062f\u0646 \u0631\u0627 \u062f\u0631 \u062d\u0627\u0644\u062a \u0637\u0628\u06cc\u0639\u06cc \u0646\u06af\u0647 \u0645\u06cc\u200c\u062f\u0627\u0631\u062f \u0648 \u0641\u0634\u0627\u0631 \u0631\u0648\u06cc \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a \u0648 \u0639\u0636\u0644\u0627\u062a \u0631\u0627 \u0628\u0647 \u062d\u062f\u0627\u0642\u0644 \u0645\u06cc\u200c\u0631\u0633\u0627\u0646\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49457\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity.jpg\" alt=\"\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc (Gravity)\" width=\"1280\" height=\"1280\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity.jpg 1280w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity-300x300.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity-1024x1024.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity-150x150.jpg 150w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity-768x768.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0628\u0631\u062c\u0633\u062a\u0647 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc\u060c \u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u0648\u0632\u06cc\u0639 \u06cc\u06a9\u0646\u0648\u0627\u062e\u062a \u0648\u0632\u0646 \u0628\u062f\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0627\u0632 \u062e\u0633\u062a\u06af\u06cc \u0646\u0627\u0634\u06cc \u0627\u0632 \u0646\u0634\u0633\u062a\u0646 \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0627 \u062a\u0646\u0638\u06cc\u0645 \u0632\u0627\u0648\u06cc\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u060c \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u06cc \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f \u0648 \u0628\u0631\u0627\u06cc \u0627\u0646\u0648\u0627\u0639 \u06a9\u0627\u0631\u0628\u0631\u062f\u0647\u0627\u060c \u0627\u0632 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u0627\u062f\u0627\u0631\u06cc \u062a\u0627 \u0641\u0636\u0627\u0647\u0627\u06cc \u062e\u0627\u0646\u06af\u06cc\u060c \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a. \u0637\u0631\u0627\u062d\u06cc \u0634\u06cc\u06a9 \u0648 \u0645\u0648\u0627\u062f \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647\u200c\u0634\u062f\u0647 \u062f\u0631 \u0633\u0627\u062e\u062a \u0622\u0646\u060c \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0631\u0627 \u0628\u0647 \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0648 \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0627\u0647\u0645\u06cc\u062a \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<blockquote><p><em><strong>\u00a0\u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0627 \u0627\u0644\u06af\u0648\u0628\u0631\u062f\u0627\u0631\u06cc \u0627\u0632 \u062d\u0627\u0644\u062a \u0628\u06cc\u200c\u0648\u0632\u0646\u06cc\u060c \u0646\u0634\u0633\u062a\u0646 \u0631\u0627 \u0628\u0647 \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0644\u0630\u062a\u200c\u0628\u062e\u0634 \u062a\u0628\u062f\u06cc\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0637\u0631\u0627\u062d\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u0622\u0646 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0628\u062f\u0646 \u062f\u0631 \u0648\u0636\u0639\u06cc\u062a \u0637\u0628\u06cc\u0639\u06cc \u0642\u0631\u0627\u0631 \u0628\u06af\u06cc\u0631\u062f \u0648 \u0627\u0632 \u0641\u0634\u0627\u0631 \u0631\u0648\u06cc \u0639\u0636\u0644\u0627\u062a \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0634\u0648\u062f.<\/strong><\/em><\/p><\/blockquote>\n<h2 class=\"whitespace-pre-wrap\"><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%A7%D8%AD_%D9%88_%D8%B3%D8%A7%D8%B2%D9%86%D8%AF%D9%87_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C_%DA%A9%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span>\u0637\u0631\u0627\u062d \u0648 \u0633\u0627\u0632\u0646\u062f\u0647 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u06a9\u06cc\u0633\u062a\u061f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0637\u0631\u0627\u062d \u0648 \u0633\u0627\u0632\u0646\u062f\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc (Gravity) \u0641\u0631\u062f\u06cc \u0628\u0647 \u0646\u0627\u0645 <strong>\u067e\u06cc\u062a\u0631 \u0627\u0648\u067e\u0633\u0648\u06cc\u06a9 (<a href=\"https:\/\/de.wikipedia.org\/wiki\/Peter_Opsvik\" rel=\"nofollow noopener\" target=\"_blank\">Peter Opsvik<\/a>)<\/strong>\u060c \u0637\u0631\u0627\u062d \u0635\u0646\u0639\u062a\u06cc \u0628\u0631\u062c\u0633\u062a\u0647 \u0646\u0631\u0648\u0698\u06cc\u060c \u0627\u0633\u062a. \u0627\u0648 \u062f\u0631 \u062f\u0647\u0647 1980 \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0631\u0646\u062f \u0646\u0631\u0648\u0698\u06cc <strong>Varier<\/strong> \u0637\u0631\u0627\u062d\u06cc \u06a9\u0631\u062f. \u067e\u06cc\u062a\u0631 \u0627\u0648\u067e\u0633\u0648\u06cc\u06a9 \u0628\u0627 \u062a\u0645\u0631\u06a9\u0632 \u0628\u0631 \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc \u0648 \u0631\u0627\u062d\u062a\u06cc\u060c \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0631\u0627 \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0637\u0631\u0627\u062d\u06cc \u06a9\u0631\u062f \u06a9\u0647 \u0628\u062a\u0648\u0627\u0646\u062f \u0628\u062f\u0646 \u0631\u0627 \u062f\u0631 \u062d\u0627\u0644\u062a \u0637\u0628\u06cc\u0639\u06cc \u0648 \u0645\u062a\u0639\u0627\u062f\u0644 \u0642\u0631\u0627\u0631 \u062f\u0647\u062f. \u0627\u06cc\u0646 \u0637\u0631\u0627\u062d\u06cc \u0627\u0644\u0647\u0627\u0645\u200c\u06af\u0631\u0641\u062a\u0647 \u0627\u0632 \u0627\u0635\u0648\u0644 \u0628\u06cc\u200c\u0648\u0632\u0646\u06cc \u0648 \u0648\u0636\u0639\u06cc\u062a \u0628\u062f\u0646 \u062f\u0631 \u062d\u0627\u0644\u062a \u0634\u0646\u0627\u0648\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0641\u0634\u0627\u0631\u0647\u0627\u06cc \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49458\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/5xime6b4nii71.webp\" alt=\"\u067e\u06cc\u062a\u0631 \u0627\u0648\u067e\u0633\u0648\u06cc\u06a9 \u062e\u0627\u0644\u0642 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc\" width=\"640\" height=\"480\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/5xime6b4nii71.webp 640w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/5xime6b4nii71-300x225.webp 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/5xime6b4nii71-86x64.webp 86w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0645\u062f\u0631\u0646\u060c \u0628\u0627 \u062d\u0641\u0638 \u0627\u0635\u0648\u0644 \u0637\u0631\u0627\u062d\u06cc \u0627\u0648\u067e\u0633\u0648\u06cc\u06a9\u060c \u0628\u0647 \u06a9\u0645\u06a9 \u0641\u0646\u0627\u0648\u0631\u06cc\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u0631\u0641\u062a\u0647\u200c\u062a\u0631 \u0648 \u0645\u0648\u0627\u062f \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a \u0628\u0647\u0628\u0648\u062f \u06cc\u0627\u0641\u062a\u0647 \u0627\u0633\u062a. \u0627\u0645\u0631\u0648\u0632\u0647 \u0628\u0631\u0646\u062f Varier \u0647\u0645\u0686\u0646\u0627\u0646 \u0628\u0647 \u062a\u0648\u0644\u06cc\u062f \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0645\u0634\u063a\u0648\u0644 \u0627\u0633\u062a \u0648 \u0628\u0627 \u0627\u0641\u0632\u0648\u062f\u0646 \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u062c\u062f\u06cc\u062f\u060c \u0645\u0627\u0646\u0646\u062f \u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u0646\u0638\u06cc\u0645 \u062f\u0642\u06cc\u0642\u200c\u062a\u0631 \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u062a\u0631\u06cc\u0627\u0644 \u0645\u062f\u0631\u0646\u060c \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0628\u06cc\u200c\u0646\u0638\u06cc\u0631 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<hr \/>\n<h2><span class=\"ez-toc-section\" id=\"%D9%88%DB%8C%DA%98%DA%AF%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D8%B5%D9%84%DB%8C_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C\"><\/span>\u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0627\u0635\u0644\u06cc \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u0637\u0631\u0627\u062d\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u062e\u0648\u062f\u060c \u0628\u0647 \u0637\u0648\u0631 \u0648\u06cc\u0698\u0647 \u0628\u0631\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u0648 \u06a9\u0627\u0647\u0634 \u0641\u0634\u0627\u0631 \u0631\u0648\u06cc \u0628\u062f\u0646 \u0633\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a. \u06cc\u06a9\u06cc \u0627\u0632 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0627\u0635\u0644\u06cc \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc\u060c \u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u0646\u0638\u06cc\u0645 \u062f\u0631 \u0686\u0646\u062f\u06cc\u0646 \u062d\u0627\u0644\u062a \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u06a9\u0627\u0631\u0628\u0631 \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0645\u06cc\u200c\u062f\u0647\u062f \u062a\u0627 \u062f\u0631 \u0648\u0636\u0639\u06cc\u062a\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u0632 \u0622\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u062f. \u0627\u0632 \u062c\u0645\u0644\u0647 \u0627\u06cc\u0646 \u062d\u0627\u0644\u062a\u200c\u0647\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u062d\u0627\u0644\u062a \u0628\u06cc\u200c\u0648\u0632\u0646\u06cc \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f \u06a9\u0647 \u0628\u0627\u0639\u062b \u062a\u0648\u0632\u06cc\u0639 \u06cc\u06a9\u0646\u0648\u0627\u062e\u062a \u0648\u0632\u0646 \u0628\u062f\u0646 \u0648 \u06a9\u0627\u0647\u0634 \u0641\u0634\u0627\u0631 \u0628\u0631 \u0631\u0648\u06cc \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a \u0648 \u0645\u0641\u0627\u0635\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49459\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity-1.jpg\" alt=\"\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc (Gravity)\" width=\"705\" height=\"718\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity-1.jpg 705w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity-1-295x300.jpg 295w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/p>\n<p>\u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0631\u0627\u062d\u062a\u06cc\u060c \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0648\u0627\u062f \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a \u062f\u0631 \u0633\u0627\u062e\u062a\u0627\u0631 \u062e\u0648\u062f\u060c \u062f\u0648\u0627\u0645 \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f. \u0637\u0631\u0627\u062d\u06cc \u0632\u06cc\u0628\u0627\u06cc \u0622\u0646 \u0646\u06cc\u0632 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0647\u0645\u0627\u0647\u0646\u06af \u0634\u0648\u062f. \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u0641\u0631\u0627\u0647\u0645 \u0622\u0648\u0631\u062f\u0646 \u0622\u0631\u0627\u0645\u0634 \u062f\u0631 \u0644\u062d\u0638\u0627\u062a \u0637\u0648\u0644\u0627\u0646\u06cc \u0646\u0634\u0633\u062a\u0646\u060c \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0639\u0627\u0644\u06cc \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a \u0627\u0633\u062a.<\/p>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%A7%D8%AD%DB%8C_%D8%A7%D8%B1%DA%AF%D9%88%D9%86%D9%88%D9%85%DB%8C%DA%A9\"><\/span>\u0637\u0631\u0627\u062d\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0637\u0631\u0627\u062d\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0627\u0632 \u062a\u0645\u0627\u0645\u06cc \u0646\u0642\u0627\u0637 \u0628\u062f\u0646\u060c \u0628\u0647 \u0648\u06cc\u0698\u0647 \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a\u060c \u0628\u0647\u200c\u062e\u0648\u0628\u06cc \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0637\u0631\u0627\u062d\u06cc \u0628\u0631 \u0627\u0633\u0627\u0633 \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u062f\u0642\u06cc\u0642 \u0622\u0646\u0627\u062a\u0648\u0645\u06cc \u0628\u062f\u0646 \u0627\u0646\u0633\u0627\u0646 \u0634\u06a9\u0644 \u06af\u0631\u0641\u062a\u0647 \u0648 \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0633\u0627\u0639\u0627\u062a \u0637\u0648\u0644\u0627\u0646\u06cc \u0631\u0648\u06cc \u0635\u0646\u062f\u0644\u06cc \u0645\u06cc\u200c\u0646\u0634\u06cc\u0646\u0646\u062f\u060c \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49461\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity.jpg\" alt=\"\u0637\u0631\u0627\u062d\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u0635\u0646\u062f\u0644\u06cc (Gravity)\" width=\"1280\" height=\"960\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity.jpg 1280w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-300x225.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-1024x768.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-768x576.jpg 768w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-86x64.jpg 86w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>\u0628\u0627 \u062a\u06a9\u06cc\u0647 \u0628\u0631 \u0627\u0635\u0648\u0644 \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u060c \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0641\u0634\u0627\u0631 \u0648\u0627\u0631\u062f \u0628\u0631 \u0639\u0636\u0644\u0627\u062a \u0648 \u0645\u0641\u0627\u0635\u0644 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f \u0648 \u062e\u0633\u062a\u06af\u06cc \u0631\u0627 \u0628\u0647 \u062d\u062f\u0627\u0642\u0644 \u0645\u06cc\u200c\u0631\u0633\u0627\u0646\u062f. \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644\u060c \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0645\u062d\u0628\u0648\u0628 \u062f\u0631 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u06cc \u0648 \u062e\u0627\u0646\u06af\u06cc \u0627\u0633\u062a\u060c \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u0633\u0644\u0627\u0645\u062a\u06cc \u0648 \u0631\u0627\u062d\u062a\u06cc \u0627\u0641\u0631\u0627\u062f \u062f\u0631 \u0627\u0648\u0644\u0648\u06cc\u062a \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u062f.<\/p>\n<blockquote><p><em><strong>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0627\u0632 \u062a\u0645\u0627\u0645\u06cc \u0646\u0642\u0627\u0637 \u0628\u062f\u0646 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0628\u0647 \u06a9\u0627\u0647\u0634 \u062e\u0633\u062a\u06af\u06cc \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/strong><\/em><\/p><\/blockquote>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D9%82%D8%A7%D8%A8%D9%84%DB%8C%D8%AA_%D8%AA%D9%86%D8%B8%DB%8C%D9%85_%D8%B2%D8%A7%D9%88%DB%8C%D9%87\"><\/span>\u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u0646\u0638\u06cc\u0645 \u0632\u0627\u0648\u06cc\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0645\u0646\u062d\u0635\u0631\u0628\u0647\u200c\u0641\u0631\u062f \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc\u060c \u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u0646\u0638\u06cc\u0645 \u0632\u0627\u0648\u06cc\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u0633\u062a \u06a9\u0647 \u0627\u0645\u06a9\u0627\u0646 \u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0628\u062f\u0646 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0642\u0627\u0628\u0644\u06cc\u062a \u0628\u0647 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0627\u062c\u0627\u0632\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f \u062a\u0627 \u062f\u0631 \u062d\u0627\u0644\u062a\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u060c \u0627\u0632 \u0646\u0634\u0633\u062a\u0646 \u0641\u0639\u0627\u0644 \u062a\u0627 \u0627\u0633\u062a\u0631\u0627\u062d\u062a \u06a9\u0627\u0645\u0644\u060c \u0635\u0646\u062f\u0644\u06cc \u0631\u0627 \u062a\u0646\u0638\u06cc\u0645 \u06a9\u0646\u0646\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49460\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/varier-gravity-balans-chair.jpg\" alt=\"\u0635\u0646\u062f\u0644\u06cc (Gravity)\" width=\"970\" height=\"660\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/varier-gravity-balans-chair.jpg 970w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/varier-gravity-balans-chair-300x204.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/varier-gravity-balans-chair-768x523.jpg 768w\" sizes=\"auto, (max-width: 970px) 100vw, 970px\" \/><\/p>\n<p>\u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u06cc \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc\u060c \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u067e\u0648\u06cc\u0627 \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u0632\u0627\u0648\u06cc\u0647 \u0646\u0634\u06cc\u0645\u0646\u060c \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0634\u062e\u0635\u06cc\u200c\u0633\u0627\u0632\u06cc\u200c\u0634\u062f\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u06a9\u0647 \u0628\u0627\u0639\u062b \u06a9\u0627\u0647\u0634 \u0641\u0634\u0627\u0631 \u0648 \u0628\u0647\u0628\u0648\u062f \u06af\u0631\u062f\u0634 \u062e\u0648\u0646 \u062f\u0631 \u0628\u062f\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<blockquote><p><em><strong>\u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0631\u062c\u0633\u062a\u0647\u200c\u062a\u0631\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc\u060c \u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u0646\u0638\u06cc\u0645 \u0632\u0627\u0648\u06cc\u0647 \u0646\u0634\u06cc\u0645\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u06a9\u0627\u0631\u0628\u0631 \u0627\u0645\u06a9\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u062d\u0627\u0644\u062a \u062f\u0644\u062e\u0648\u0627\u0647 \u062e\u0648\u062f \u0631\u0627 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u062f.<\/strong><\/em><\/p><\/blockquote>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AC%D9%86%D8%B3_%D9%85%D8%B1%D8%BA%D9%88%D8%A8_%D9%85%D9%88%D8%A7%D8%AF\"><\/span>\u062c\u0646\u0633 \u0645\u0631\u063a\u0648\u0628 \u0645\u0648\u0627\u062f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0648\u0627\u062f \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a \u0633\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a \u062a\u0627 \u062f\u0648\u0627\u0645 \u0648 \u0631\u0627\u062d\u062a\u06cc \u0622\u0646 \u062f\u0631 \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a \u062a\u0636\u0645\u06cc\u0646 \u0634\u0648\u062f. \u0641\u0648\u0645\u200c\u0647\u0627\u06cc \u062d\u0627\u0641\u0638\u0647\u200c\u062f\u0627\u0631 (Memory Foam) \u0628\u0647\u200c\u06a9\u0627\u0631\u0631\u0641\u062a\u0647 \u062f\u0631 \u0622\u0646 \u0628\u0627 \u0641\u0631\u0645 \u0628\u062f\u0646 \u062a\u0637\u0628\u06cc\u0642 \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0647 \u0648 \u062d\u0633 \u0631\u0627\u062d\u062a\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n<p>\u0647\u0645\u0686\u0646\u06cc\u0646 \u067e\u0627\u0631\u0686\u0647\u200c\u0647\u0627\u06cc \u062a\u0646\u0641\u0633\u200c\u067e\u0630\u06cc\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647\u200c\u0634\u062f\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc\u060c \u0645\u0627\u0646\u0639 \u062a\u0639\u0631\u06cc\u0642 \u062f\u0631 \u0637\u0648\u0644 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0627\u06cc\u0646 \u062a\u0631\u06a9\u06cc\u0628 \u0627\u0632 \u0645\u062a\u0631\u06cc\u0627\u0644 \u0645\u0631\u063a\u0648\u0628\u060c \u0647\u0645\u0631\u0627\u0647 \u0628\u0627 \u0637\u0631\u0627\u062d\u06cc \u0645\u062f\u0631\u0646\u060c \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0644\u0630\u062a\u200c\u0628\u062e\u0634 \u0627\u0632 \u0646\u0634\u0633\u062a\u0646 \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0628\u0647 \u0627\u0631\u0645\u063a\u0627\u0646 \u0645\u06cc\u200c\u0622\u0648\u0631\u062f.<\/p>\n<blockquote><p><em><strong>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0641\u0648\u0645\u200c\u0647\u0627\u06cc \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a \u0648 \u067e\u0627\u0631\u0686\u0647\u200c\u0647\u0627\u06cc \u062a\u0646\u0641\u0633\u200c\u067e\u0630\u06cc\u0631 \u062f\u0631 \u0633\u0627\u062e\u062a \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc\u060c \u0631\u0627\u062d\u062a\u06cc \u0648 \u062f\u0648\u0627\u0645 \u0631\u0627 \u062a\u0636\u0645\u06cc\u0646 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/strong><\/em><\/p><\/blockquote>\n<h2><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C\"><\/span>\u06a9\u0627\u0631\u0628\u0631\u062f \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49462\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u0637\u0631\u0627\u062d\u06cc-\u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity.jpg\" alt=\"\u06a9\u0627\u0631\u0628\u0631\u062f \u0637\u0631\u0627\u062d\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u0635\u0646\u062f\u0644\u06cc (Gravity)\" width=\"1280\" height=\"960\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u0637\u0631\u0627\u062d\u06cc-\u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity.jpg 1280w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u0637\u0631\u0627\u062d\u06cc-\u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-300x225.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u0637\u0631\u0627\u062d\u06cc-\u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-1024x768.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u0637\u0631\u0627\u062d\u06cc-\u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-768x576.jpg 768w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u0637\u0631\u0627\u062d\u06cc-\u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-86x64.jpg 86w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0634\u0631\u0627\u06cc\u0637 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0627\u0628\u0632\u0627\u0631 \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u0648 \u0633\u0644\u0627\u0645\u062a \u0628\u062f\u0646 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u06af\u06cc\u0631\u062f. \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0637\u0631\u0627\u062d\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u062e\u0648\u062f\u060c \u0641\u0634\u0627\u0631 \u0631\u0627 \u0627\u0632 \u0631\u0648\u06cc \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a\u060c \u06af\u0631\u062f\u0646 \u0648 \u0634\u0627\u0646\u0647\u200c\u0647\u0627 \u0628\u0631 \u0645\u06cc\u200c\u062f\u0627\u0631\u062f\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0637\u0648\u0644\u0627\u0646\u06cc \u0631\u0627 \u067e\u0634\u062a \u0645\u06cc\u0632 \u0645\u06cc\u200c\u0646\u0634\u06cc\u0646\u0646\u062f \u06cc\u0627 \u062f\u0631 \u0645\u0639\u0631\u0636 \u0627\u0633\u062a\u0631\u0633\u200c\u0647\u0627\u06cc \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u0647\u0633\u062a\u0646\u062f\u060c \u0628\u0633\u06cc\u0627\u0631 \u0645\u0641\u06cc\u062f \u0627\u0633\u062a.<\/p>\n<p>\u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u06a9\u0627\u0631\u0628\u0631\u062f\u0647\u0627\u06cc \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062f\u0631 \u0632\u0645\u0627\u0646 \u0627\u0633\u062a\u0631\u0627\u062d\u062a \u0648 \u062e\u0648\u0627\u0628 \u0627\u0633\u062a. \u0628\u0627 \u062a\u0646\u0638\u06cc\u0645 \u0632\u0627\u0648\u06cc\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u060c \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0647 \u06a9\u0627\u0631\u0628\u0631 \u0627\u062c\u0627\u0632\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f \u062a\u0627 \u062f\u0631 \u0648\u0636\u0639\u06cc\u062a \u0628\u06cc\u200c\u0648\u0632\u0646\u06cc \u0642\u0631\u0627\u0631 \u06af\u06cc\u0631\u062f \u0648 \u0627\u062d\u0633\u0627\u0633 \u0631\u0627\u062d\u062a\u06cc \u0639\u0645\u06cc\u0642 \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u062a\u0646\u0634\u200c\u0647\u0627\u06cc \u062c\u0633\u0645\u06cc \u0648 \u0630\u0647\u0646\u06cc \u0648 \u0628\u0647\u0628\u0648\u062f \u062c\u0631\u06cc\u0627\u0646 \u062e\u0648\u0646 \u0645\u0641\u06cc\u062f \u0627\u0633\u062a.<\/p>\n<ul>\n<li>\u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc <strong>\u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u06cc<\/strong> \u06a9\u0647 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0646\u0634\u0633\u062a\u0646 \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a \u062f\u0627\u0631\u0646\u062f.<\/li>\n<li>\u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0639\u0627\u0644\u06cc \u0628\u0631\u0627\u06cc <strong>\u0631\u06cc\u0644\u06a9\u0633\u06cc\u0634\u0646 \u0648 \u0645\u062f\u06cc\u062a\u06cc\u0634\u0646<\/strong>.<\/li>\n<li>\u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u0645\u0634\u06a9\u0644\u0627\u062a <strong>\u06a9\u0645\u0631\u062f\u0631\u062f<\/strong> \u06cc\u0627 <strong>\u0641\u0634\u0627\u0631 \u0639\u0636\u0644\u0627\u0646\u06cc<\/strong>.<\/li>\n<\/ul>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0637\u0631\u0627\u062d\u06cc \u0645\u0646\u062d\u0635\u0631\u0628\u0647\u200c\u0641\u0631\u062f \u0648 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0628\u0627\u0644\u0627\u06cc\u0634\u060c \u0637\u0631\u0641\u062f\u0627\u0631\u0627\u0646 \u0632\u06cc\u0627\u062f\u06cc \u062f\u0631 \u062d\u0648\u0632\u0647 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0627\u062f\u0627\u0631\u06cc \u0648 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<hr \/>\n<h2><span class=\"ez-toc-section\" id=\"%DA%86%D8%B1%D8%A7_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C_%D9%85%D8%AD%D8%A8%D9%88%D8%A8_%D8%A7%D8%B3%D8%AA%D8%9F\"><\/span>\u0686\u0631\u0627 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0645\u062d\u0628\u0648\u0628 \u0627\u0633\u062a\u061f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49463\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity-2.jpg\" alt=\"\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc (Gravity)\" width=\"1341\" height=\"1006\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity-2.jpg 1341w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity-2-300x225.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity-2-1024x768.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity-2-768x576.jpg 768w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-Gravity-2-86x64.jpg 86w\" sizes=\"auto, (max-width: 1341px) 100vw, 1341px\" \/><\/p>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0637\u0631\u0627\u062d\u06cc \u062e\u0644\u0627\u0642\u0627\u0646\u0647 \u0648 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u062d\u0628\u0648\u0628\u200c\u062a\u0631\u06cc\u0646 \u0627\u0646\u062a\u062e\u0627\u0628\u200c\u0647\u0627 \u062f\u0631 \u0628\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc\u200c\u0647\u0627\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0627 \u062a\u0631\u06a9\u06cc\u0628 \u0631\u0627\u062d\u062a\u06cc\u060c \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0648 \u0641\u0646\u0627\u0648\u0631\u06cc \u0645\u062f\u0631\u0646\u060c \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0628\u06cc\u200c\u0646\u0638\u06cc\u0631 \u0627\u0632 \u0646\u0634\u0633\u062a\u0646 \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0627\u0632 \u062d\u0627\u0644\u062a \u0628\u06cc\u200c\u0648\u0632\u0646\u06cc \u06a9\u0647 \u0622\u0631\u0627\u0645\u0634 \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f \u062a\u0627 \u0637\u0631\u0627\u062d\u06cc \u0634\u06cc\u06a9 \u0648 \u0645\u06cc\u0646\u06cc\u0645\u0627\u0644 \u06a9\u0647 \u0628\u0627 \u0641\u0636\u0627\u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0647\u0645\u062e\u0648\u0627\u0646\u06cc \u062f\u0627\u0631\u062f\u060c \u062f\u0644\u0627\u06cc\u0644 \u0645\u062a\u0639\u062f\u062f\u06cc \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0622\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f.<\/p>\n<p>\u0628\u0627 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u0647\u0645\u0686\u0648\u0646 \u06a9\u0627\u0647\u0634 \u0627\u0633\u062a\u0631\u0633 \u0628\u062f\u0646\u060c \u0628\u0647\u0628\u0648\u062f \u062a\u0645\u0631\u06a9\u0632 \u0648 \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u06cc \u0628\u0627\u0644\u0627\u060c \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u067e\u0631\u0637\u0631\u0641\u062f\u0627\u0631\u062a\u0631\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062f\u0631 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u06cc \u0648 \u062e\u0627\u0646\u06af\u06cc \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647 \u0633\u0647 \u062f\u0644\u06cc\u0644 \u0627\u0635\u0644\u06cc \u0645\u062d\u0628\u0648\u0628\u06cc\u062a \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645.<\/p>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A2%D8%B1%D8%A7%D9%85%D8%B4_%D8%AF%D8%B1_%D9%84%D8%AD%D8%B8%D9%87_%D8%A8%D8%A7_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C\"><\/span>\u0622\u0631\u0627\u0645\u0634 \u062f\u0631 \u0644\u062d\u0638\u0647 \u0628\u0627 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0628\u0631\u062c\u0633\u062a\u0647 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc\u060c \u0627\u06cc\u062c\u0627\u062f \u062d\u0633 \u0622\u0631\u0627\u0645\u0634 \u0641\u0648\u0631\u06cc \u0627\u0633\u062a. \u0637\u0631\u0627\u062d\u06cc \u062e\u0627\u0635 \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u0635\u0644 \u0628\u06cc\u200c\u0648\u0632\u0646\u06cc\u060c \u0641\u0634\u0627\u0631 \u0648\u0627\u0631\u062f \u0628\u0631 \u0646\u0642\u0627\u0637 \u062d\u0633\u0627\u0633 \u0628\u062f\u0646\u060c \u0645\u0627\u0646\u0646\u062f \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a \u0648 \u06af\u0631\u062f\u0646 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0628\u0647 \u06a9\u0627\u0631\u0628\u0631 \u0627\u0645\u06a9\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u0628\u062f\u0648\u0646 \u0627\u062d\u0633\u0627\u0633 \u062e\u0633\u062a\u06af\u06cc\u060c \u0633\u0627\u0639\u062a\u200c\u0647\u0627 \u0631\u0648\u06cc \u0635\u0646\u062f\u0644\u06cc \u0628\u0646\u0634\u06cc\u0646\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49464\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/httpsd1e00ek4ebabms.cloudfront.n.jpg\" alt=\"\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc (Gravity)\" width=\"700\" height=\"394\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/httpsd1e00ek4ebabms.cloudfront.n.jpg 700w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/httpsd1e00ek4ebabms.cloudfront.n-300x169.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>\u0627\u06cc\u0646 \u062d\u0627\u0644\u062a \u0622\u0631\u0627\u0645\u0634\u200c\u0628\u062e\u0634\u060c \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0645\u0634\u0627\u0628\u0647 \u0634\u0646\u0627\u0648\u0631\u06cc \u062f\u0631 \u0641\u0636\u0627 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u067e\u0631\u062a\u0646\u0634 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0627\u0633\u062a. \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u0627\u06cc\u0646 \u0642\u0627\u0628\u0644\u06cc\u062a\u060c \u0646\u0647\u200c\u062a\u0646\u0647\u0627 \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0631\u0648\u0632\u0645\u0631\u0647 \u0628\u0644\u06a9\u0647 \u0628\u0631\u0627\u06cc \u0644\u062d\u0638\u0627\u062a \u0627\u0633\u062a\u0631\u0627\u062d\u062a \u0646\u06cc\u0632 \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u0628\u06cc\u200c\u0646\u0638\u06cc\u0631 \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<blockquote><p><em><strong>\u062d\u0627\u0644\u062a \u0628\u06cc\u200c\u0648\u0632\u0646\u06cc \u06a9\u0647 \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u06a9\u0645\u200c\u0646\u0638\u06cc\u0631 \u0627\u0632 \u0622\u0631\u0627\u0645\u0634 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u0622\u0648\u0631\u062f.<\/strong><\/em><\/p><\/blockquote>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%AA%D9%85%D8%B1%DA%A9%D8%B2\"><\/span>\u0627\u0641\u0632\u0627\u06cc\u0634 \u062a\u0645\u0631\u06a9\u0632<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u06a9\u0627\u0647\u0634 \u0641\u0634\u0627\u0631 \u0648 \u062e\u0633\u062a\u06af\u06cc \u0639\u0636\u0644\u0627\u062a\u060c \u0628\u0647 \u0628\u0647\u0628\u0648\u062f \u062a\u0645\u0631\u06a9\u0632 \u062f\u0631 \u0637\u0648\u0644 \u06a9\u0627\u0631 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062d\u0627\u0644\u062a \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u0622\u0646 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u0628\u062f\u0646 \u062f\u0631 \u0648\u0636\u0639\u06cc\u062a \u0637\u0628\u06cc\u0639\u06cc \u0642\u0631\u0627\u0631 \u06af\u06cc\u0631\u062f \u0648 \u0627\u0632 \u0627\u062d\u0633\u0627\u0633 \u062f\u0631\u062f \u0648 \u0646\u0627\u0631\u0627\u062d\u062a\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0634\u0648\u062f. \u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0637\u0648\u0644\u0627\u0646\u06cc \u067e\u0634\u062a \u0645\u06cc\u0632 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u0646\u0634\u06cc\u0646\u0646\u062f\u060c \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0627\u0633\u062a.<\/p>\n<p>\u062a\u0645\u0631\u06a9\u0632 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0647 \u0645\u0639\u0646\u0627\u06cc \u0628\u0647\u0631\u0647\u200c\u0648\u0631\u06cc \u0628\u0627\u0644\u0627\u062a\u0631 \u0648 \u0627\u062d\u0633\u0627\u0633 \u0631\u0636\u0627\u06cc\u062a \u062f\u0631 \u062d\u06cc\u0646 \u0627\u0646\u062c\u0627\u0645 \u0648\u0638\u0627\u06cc\u0641 \u0631\u0648\u0632\u0627\u0646\u0647 \u0627\u0633\u062a. \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u0641\u0631\u0627\u0647\u0645 \u06a9\u0631\u062f\u0646 \u0627\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637 \u0627\u06cc\u062f\u0647\u200c\u0622\u0644\u060c \u0628\u0647 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0648\u0638\u0627\u06cc\u0641 \u062e\u0648\u062f \u0631\u0627 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0647\u062a\u0631\u06cc \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0646\u062f \u0648 \u0627\u0646\u0631\u0698\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u0627\u062f\u0627\u0645\u0647 \u0631\u0648\u0632 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f.<\/p>\n<blockquote><p><em><strong>\u0628\u0627 \u06a9\u0627\u0647\u0634 \u0641\u0634\u0627\u0631 \u0628\u062f\u0646\u060c \u062a\u0645\u0631\u06a9\u0632 \u0641\u0631\u062f \u062f\u0631 \u0627\u0646\u062c\u0627\u0645 \u06a9\u0627\u0631\u0647\u0627\u06cc \u0627\u062f\u0627\u0631\u06cc \u0628\u0647\u0628\u0648\u062f \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f.<\/strong><\/em><\/p><\/blockquote>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%A7%D8%AD%DB%8C_%D8%B4%DB%8C%DA%A9_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C\"><\/span>\u0637\u0631\u0627\u062d\u06cc \u0634\u06cc\u06a9 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49465\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0634\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity.jpg\" alt=\"\u0637\u0631\u0627\u062d\u06cc \u0634\u06cc\u06a9 \u0635\u0646\u062f\u0644\u06cc (Gravity)\" width=\"768\" height=\"576\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0634\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity.jpg 768w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0634\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-300x225.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0634\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-86x64.jpg 86w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>\u0637\u0631\u0627\u062d\u06cc \u0645\u062f\u0631\u0646 \u0648 \u0634\u06cc\u06a9 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc\u060c \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u062c\u0630\u0627\u0628 \u0628\u0631\u0627\u06cc \u0641\u0636\u0627\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062e\u0637\u0648\u0637 \u0645\u06cc\u0646\u06cc\u0645\u0627\u0644 \u0648 \u0645\u0648\u0627\u062f \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a\u060c \u062c\u0644\u0648\u0647\u200c\u0627\u06cc \u0632\u06cc\u0628\u0627 \u0648 \u0647\u0645\u0627\u0647\u0646\u06af \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646\u200c\u0647\u0627\u06cc \u0627\u0645\u0631\u0648\u0632\u06cc \u0628\u0647 \u0622\u0646 \u0628\u062e\u0634\u06cc\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0637\u0631\u0627\u062d\u06cc \u0628\u0631\u0627\u06cc \u062f\u0641\u0627\u062a\u0631 \u06a9\u0627\u0631\u06cc\u060c \u0641\u0636\u0627\u0647\u0627\u06cc \u062e\u0627\u0646\u06af\u06cc \u0648 \u062d\u062a\u06cc \u0627\u062a\u0627\u0642\u200c\u0647\u0627\u06cc \u0627\u0633\u062a\u0631\u0627\u062d\u062a \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a.<\/p>\n<p>\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0638\u0627\u0647\u0631 \u0632\u06cc\u0628\u0627\u060c \u062a\u0631\u06a9\u06cc\u0628 \u0645\u062a\u0631\u06cc\u0627\u0644 \u0645\u0631\u063a\u0648\u0628 \u0648 \u0637\u0631\u0627\u062d\u06cc \u0647\u0648\u0634\u0645\u0646\u062f\u0627\u0646\u0647\u060c \u062f\u0648\u0627\u0645 \u0648 \u0639\u0645\u0644\u06a9\u0631\u062f \u0628\u0627\u0644\u0627\u06cc \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0631\u0627 \u062a\u0636\u0645\u06cc\u0646 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc\u060c \u0646\u0647\u200c\u062a\u0646\u0647\u0627 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0631\u0627\u062d\u062a\u06cc\u060c \u0628\u0644\u06a9\u0647 \u0628\u0647 \u062e\u0627\u0637\u0631 \u062c\u0630\u0627\u0628\u06cc\u062a \u0628\u0635\u0631\u06cc\u200c\u0627\u0634\u060c \u0628\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u062d\u0628\u0648\u0628\u200c\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647\u200c\u0647\u0627 \u062f\u0631 \u0628\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc\u200c\u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<blockquote><p><em><strong>\u0638\u0627\u0647\u0631 \u0645\u062f\u0631\u0646 \u0648 \u0645\u06cc\u0646\u06cc\u0645\u0627\u0644 \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc\u060c \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u062c\u0630\u0627\u0628 \u0628\u0631\u0627\u06cc \u062f\u0641\u0627\u062a\u0631 \u06a9\u0627\u0631\u06cc \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/strong><\/em><\/p><\/blockquote>\n<hr \/>\n<h2><span class=\"ez-toc-section\" id=\"%D9%85%D8%B2%D8%A7%DB%8C%D8%A7%DB%8C_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C\"><\/span>\u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0637\u0631\u0627\u062d\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u0648 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u0648\u06cc\u0698\u0647\u200c\u0627\u0634\u060c \u0645\u0632\u0627\u06cc\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0631\u062f \u06a9\u0647 \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u06cc \u0648 \u062e\u0627\u0646\u06af\u06cc \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0627 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u06a9\u0627\u0647\u0634 \u0641\u0634\u0627\u0631 \u0628\u0631 \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a \u0648 \u0627\u06cc\u062c\u0627\u062f \u0631\u0627\u062d\u062a\u06cc \u062f\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a\u060c \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0633\u0627\u0639\u0627\u062a \u0632\u06cc\u0627\u062f\u06cc \u0631\u0648\u06cc \u0635\u0646\u062f\u0644\u06cc \u0645\u06cc\u200c\u0646\u0634\u06cc\u0646\u0646\u062f\u060c \u0628\u0633\u06cc\u0627\u0631 \u0645\u0641\u06cc\u062f \u0627\u0633\u062a. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647 \u0686\u0647\u0627\u0631 \u0645\u0632\u06cc\u062a \u0627\u0635\u0644\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645.<\/p>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D9%87%D8%B4_%D9%81%D8%B4%D8%A7%D8%B1_%D8%A8%D8%B1_%D8%B3%D8%AA%D9%88%D9%86_%D9%81%D9%82%D8%B1%D8%A7%D8%AA\"><\/span>\u06a9\u0627\u0647\u0634 \u0641\u0634\u0627\u0631 \u0628\u0631 \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0635\u0644\u06cc\u200c\u062a\u0631\u06cc\u0646 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc\u060c \u06a9\u0627\u0647\u0634 \u0641\u0634\u0627\u0631 \u0648\u0627\u0631\u062f \u0628\u0631 \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a \u0627\u0633\u062a. \u0637\u0631\u0627\u062d\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0628\u062f\u0646 \u062f\u0631 \u062d\u0627\u0644\u062a \u0637\u0628\u06cc\u0639\u06cc \u0648 \u0645\u062a\u0648\u0627\u0632\u0646 \u0642\u0631\u0627\u0631 \u06af\u06cc\u0631\u062f \u0648 \u0647\u06cc\u0686 \u0641\u0634\u0627\u0631\u06cc \u0628\u0647 \u06a9\u0645\u0631 \u0648\u0627\u0631\u062f \u0646\u0634\u0648\u062f. \u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0628\u0627\u0639\u062b \u06a9\u0627\u0647\u0634 \u0627\u062d\u062a\u0645\u0627\u0644 \u0628\u0631\u0648\u0632 \u0645\u0634\u06a9\u0644\u0627\u062a \u062c\u062f\u06cc \u0647\u0645\u0686\u0648\u0646 \u062f\u06cc\u0633\u06a9 \u06a9\u0645\u0631 \u0648 \u06af\u0631\u062f\u0646 \u062f\u0631\u062f \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u062f\u0631\u0633\u062a \u0627\u0632 \u0642\u0633\u0645\u062a\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0628\u062f\u0646\u060c \u0628\u0647 \u0648\u06cc\u0698\u0647 \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a\u060c \u0627\u062d\u0633\u0627\u0633 \u0631\u0627\u062d\u062a\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0631\u0627 \u062f\u0631 \u0637\u0648\u0644 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0631\u062f. \u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc\u060c \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0631\u0627 \u0628\u0647 \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0632\u0645\u0627\u0646 \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u067e\u0634\u062a \u0645\u06cc\u0632 \u0645\u06cc\u200c\u06af\u0630\u0631\u0627\u0646\u0646\u062f\u060c \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49466\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0645\u0632\u0627\u06cc\u0627\u06cc-\u0627\u0633\u062a\u0641\u0627\u062f\u0647-\u0627\u0632-\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc.jpg\" alt=\"\u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc\" width=\"575\" height=\"390\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0645\u0632\u0627\u06cc\u0627\u06cc-\u0627\u0633\u062a\u0641\u0627\u062f\u0647-\u0627\u0632-\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc.jpg 575w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0645\u0632\u0627\u06cc\u0627\u06cc-\u0627\u0633\u062a\u0641\u0627\u062f\u0647-\u0627\u0632-\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-300x203.jpg 300w\" sizes=\"auto, (max-width: 575px) 100vw, 575px\" \/><\/p>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D8%AF%D8%B1%D8%AF%D9%87%D8%A7%DB%8C_%D8%B9%D8%B6%D9%84%D8%A7%D9%86%DB%8C\"><\/span>\u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062f\u0631\u062f\u0647\u0627\u06cc \u0639\u0636\u0644\u0627\u0646\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u0631\u062f\u0647\u0627\u06cc \u0639\u0636\u0644\u0627\u0646\u06cc \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0646\u0634\u0633\u062a\u0646 \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a \u062f\u0631 \u0648\u0636\u0639\u06cc\u062a \u0646\u0627\u062f\u0631\u0633\u062a \u06cc\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0635\u0646\u062f\u0644\u06cc\u200c\u0647\u0627\u06cc \u0646\u0627\u0645\u0646\u0627\u0633\u0628 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u0634\u0648\u062f. \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u0637\u0631\u0627\u062d\u06cc \u0645\u0646\u062d\u0635\u0631 \u0628\u0647 \u0641\u0631\u062f \u062e\u0648\u062f\u060c \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0639\u0636\u0644\u0627\u062a \u0628\u062f\u0646 \u062f\u0631 \u062d\u0627\u0644\u062a \u0631\u0627\u062d\u062a\u06cc \u0642\u0631\u0627\u0631 \u06af\u06cc\u0631\u0646\u062f \u0648 \u0641\u0634\u0627\u0631 \u06a9\u0645\u062a\u0631\u06cc \u0628\u0647 \u0622\u0646\u0647\u0627 \u0648\u0627\u0631\u062f \u0634\u0648\u062f. \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0628\u0627\u0639\u062b \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f\u0647\u0627\u06cc \u0639\u0636\u0644\u0627\u0646\u06cc \u0646\u0627\u0634\u06cc \u0627\u0632 \u0646\u0634\u0633\u062a\u0646 \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p>\u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc\u060c \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0627\u0632 \u062f\u0631\u062f\u0647\u0627\u06cc \u06af\u0631\u062f\u0646\u060c \u0634\u0627\u0646\u0647\u200c\u0647\u0627 \u0648 \u06a9\u0645\u0631 \u06a9\u0647 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0646\u0627\u0634\u06cc \u0627\u0632 \u0646\u0634\u0633\u062a\u0646 \u0646\u0627\u062f\u0631\u0633\u062a \u0647\u0633\u062a\u0646\u062f\u060c \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0647 \u0645\u0634\u06a9\u0644\u0627\u062a \u0639\u0636\u0644\u0627\u0646\u06cc \u062f\u0686\u0627\u0631 \u0647\u0633\u062a\u0646\u062f\u060c \u06cc\u06a9 \u0631\u0627\u0647\u200c\u062d\u0644 \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0631\u0641\u0639 \u0645\u0634\u06a9\u0644\u0627\u062a \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u0627\u0633\u062a.<\/p>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A8%D9%87%D8%A8%D9%88%D8%AF_%D8%AC%D8%B1%DB%8C%D8%A7%D9%86_%D8%AE%D9%88%D9%86\"><\/span>\u0628\u0647\u0628\u0648\u062f \u062c\u0631\u06cc\u0627\u0646 \u062e\u0648\u0646<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0647\u0628\u0648\u062f \u062c\u0631\u06cc\u0627\u0646 \u062e\u0648\u0646 \u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0628\u0631\u062c\u0633\u062a\u0647 \u062e\u0648\u062f \u0645\u06cc\u200c\u0628\u0627\u0634\u062f. \u0628\u0627 \u062a\u0646\u0638\u06cc\u0645 \u0632\u0627\u0648\u06cc\u0647 \u0635\u0646\u062f\u0644\u06cc \u0648 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0646 \u0628\u062f\u0646 \u062f\u0631 \u0648\u0636\u0639\u06cc\u062a \u0645\u0646\u0627\u0633\u0628\u060c \u062e\u0648\u0646\u200c\u0631\u0633\u0627\u0646\u06cc \u0628\u0647 \u0627\u0646\u062f\u0627\u0645\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0628\u062f\u0646 \u0628\u0647\u062a\u0631 \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0628\u0647 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062a\u0648\u0631\u0645\u060c \u0627\u062d\u0633\u0627\u0633 \u0633\u0646\u06af\u06cc\u0646\u06cc \u0648 \u062e\u0633\u062a\u06af\u06cc \u062f\u0631 \u0628\u062f\u0646 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<p>\u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0628\u0647\u200c\u0648\u06cc\u0698\u0647 \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0645\u062f\u062a\u200c\u0632\u0645\u0627\u0646 \u0637\u0648\u0644\u0627\u0646\u06cc \u0631\u0648\u06cc \u0635\u0646\u062f\u0644\u06cc \u0645\u06cc\u200c\u0646\u0634\u06cc\u0646\u0646\u062f \u0648 \u062f\u0686\u0627\u0631 \u0645\u0634\u06a9\u0644\u0627\u062a \u06af\u0631\u062f\u0634 \u062e\u0648\u0646 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f\u060c \u0645\u0641\u06cc\u062f \u0627\u0633\u062a. \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc\u060c \u062c\u0631\u06cc\u0627\u0646 \u062e\u0648\u0646 \u0628\u0647\u0628\u0648\u062f \u06cc\u0627\u0641\u062a\u0647 \u0648 \u0627\u0632 \u0628\u0631\u0648\u0632 \u0645\u0634\u06a9\u0644\u0627\u062a\u06cc \u0645\u0627\u0646\u0646\u062f \u0648\u0627\u0631\u06cc\u0633 \u0648 \u0633\u0627\u06cc\u0631 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u06af\u0631\u062f\u0634 \u062e\u0648\u0646 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49467\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0634\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-2.jpg\" alt=\"\u0637\u0631\u0627\u062d\u06cc \u0634\u06cc\u06a9 \u0635\u0646\u062f\u0644\u06cc (Gravity) 2\" width=\"720\" height=\"720\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0634\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-2.jpg 720w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0634\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-2-300x300.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0637\u0631\u0627\u062d\u06cc-\u0634\u06cc\u06a9-\u0635\u0646\u062f\u0644\u06cc-Gravity-2-150x150.jpg 150w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%D8%AD%D8%B3_%D8%B1%D8%A7%D8%AD%D8%AA%DB%8C_%D9%88_%D8%A2%D8%B1%D8%A7%D9%85%D8%B4_%D8%AF%D8%B1_%D9%85%D8%AD%DB%8C%D8%B7_%DA%A9%D8%A7%D8%B1\"><\/span>\u0627\u06cc\u062c\u0627\u062f \u062d\u0633 \u0631\u0627\u062d\u062a\u06cc \u0648 \u0622\u0631\u0627\u0645\u0634 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u06a9\u0627\u0631<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc \u0648 \u0631\u0627\u062d\u062a\u06cc\u060c \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0622\u0631\u0627\u0645\u0634\u200c\u0628\u062e\u0634 \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0637\u0631\u0627\u062d\u06cc \u0622\u0646 \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0627\u062d\u0633\u0627\u0633 \u0631\u0627\u062d\u062a\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0647 \u0627\u0641\u0631\u0627\u062f \u0645\u06cc\u200c\u062f\u0647\u062f \u0648 \u0627\u0632 \u0627\u0633\u062a\u0631\u0633\u200c\u0647\u0627\u06cc \u0631\u0648\u0632\u0645\u0631\u0647 \u06a9\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u062d\u0633 \u0631\u0627\u062d\u062a\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0628\u0647\u0628\u0648\u062f \u0631\u0648\u062d\u06cc\u0647 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u0647\u0631\u0647\u200c\u0648\u0631\u06cc \u062f\u0631 \u0645\u062d\u06cc\u0637 \u06a9\u0627\u0631 \u0645\u0646\u062c\u0631 \u0634\u0648\u062f.<\/p>\n<p>\u062d\u0633 \u0622\u0631\u0627\u0645\u0634 \u0627\u06cc\u062c\u0627\u062f\u0634\u062f\u0647 \u062a\u0648\u0633\u0637 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0647\u200c\u0648\u06cc\u0698\u0647 \u062f\u0631 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u06cc \u067e\u0631\u062a\u0646\u0634 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u06a9\u0627\u0647\u0634 \u0627\u0633\u062a\u0631\u0633 \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u0647 \u0648 \u062a\u0645\u0631\u06a9\u0632 \u0631\u0627 \u0628\u0627\u0644\u0627 \u0628\u0628\u0631\u062f. \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0631\u0627\u062d\u062a\u06cc \u0641\u06cc\u0632\u06cc\u06a9\u06cc\u060c \u0627\u062d\u0633\u0627\u0633 \u0622\u0631\u0627\u0645\u0634 \u0630\u0647\u0646\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0631\u0646\u062f \u0648 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0622\u0646\u0647\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f.<\/p>\n<hr \/>\n<h2><span class=\"ez-toc-section\" id=\"%D9%86%D8%AD%D9%88%D9%87_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D9%88_%D8%AE%D8%B1%DB%8C%D8%AF_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C\"><\/span>\u0646\u062d\u0648\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0648 \u062e\u0631\u06cc\u062f \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062f\u0631 \u0647\u0646\u06af\u0627\u0645 \u062e\u0631\u06cc\u062f \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc\u060c \u0628\u0627\u06cc\u062f \u0628\u0647 \u0686\u0646\u062f \u0646\u06a9\u062a\u0647 \u0627\u0633\u0627\u0633\u06cc \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u0648\u0644\u06cc\u0646 \u0645\u0648\u0631\u062f \u06a9\u06cc\u0641\u06cc\u062a \u0645\u0648\u0627\u062f \u0633\u0627\u062e\u062a \u0627\u0633\u062a. \u0635\u0646\u062f\u0644\u06cc\u200c\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0641\u0631\u06cc\u0645 \u0645\u0642\u0627\u0648\u0645 \u0648 \u067e\u0648\u0634\u0634\u200c\u0647\u0627\u06cc \u0631\u0627\u062d\u062a \u0628\u0627\u0639\u062b \u062f\u0648\u0627\u0645 \u0648 \u0631\u0627\u062d\u062a\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0645\u062e\u062a\u0644\u0641 \u0627\u0632 \u062c\u0645\u0644\u0647 \u0627\u0631\u062a\u0641\u0627\u0639 \u0648 \u0632\u0627\u0648\u06cc\u0647 \u067e\u0634\u062a\u06cc\u060c \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0631\u0627\u062d\u062a\u200c\u062a\u0631 \u0627\u0632 \u0635\u0646\u062f\u0644\u06cc \u0627\u0647\u0645\u06cc\u062a \u0648\u06cc\u0698\u0647\u200c\u0627\u06cc \u062f\u0627\u0631\u062f.<\/p>\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0632\u0645\u06cc\u0646\u0647\u060c \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0644\u0648\u0633\u062a\u0631 \u062f\u06a9\u0648\u0631\u0634\u0627\u067e \u0628\u0627 \u0627\u0631\u0627\u0626\u0647 \u0627\u0646\u0648\u0627\u0639 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0639\u0627\u0644\u06cc \u0648 \u062a\u0636\u0645\u06cc\u0646 \u0634\u062f\u0647\u060c \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0627\u0633\u062a. \u062a\u0646\u0648\u0639 \u0645\u062f\u0644\u200c\u0647\u0627 \u0648 \u0628\u0631\u0646\u062f\u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631 \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0627\u06cc\u0646 \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u0634\u0645\u0627 \u0631\u0627 \u0631\u0627\u062d\u062a\u200c\u062a\u0631 \u062e\u0648\u0627\u0647\u062f \u06a9\u0631\u062f \u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0631 \u0627\u0633\u0627\u0633 \u0646\u06cc\u0627\u0632 \u062e\u0648\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0631\u0627 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u06cc\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49468\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/gravity-balans-lounge-chair-by-peter-opsvik-for-stokke-1980s.jpg\" alt=\"gravity chair\" width=\"1650\" height=\"1651\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/gravity-balans-lounge-chair-by-peter-opsvik-for-stokke-1980s.jpg 1650w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/gravity-balans-lounge-chair-by-peter-opsvik-for-stokke-1980s-300x300.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/gravity-balans-lounge-chair-by-peter-opsvik-for-stokke-1980s-1024x1024.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/gravity-balans-lounge-chair-by-peter-opsvik-for-stokke-1980s-150x150.jpg 150w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/gravity-balans-lounge-chair-by-peter-opsvik-for-stokke-1980s-768x768.jpg 768w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/gravity-balans-lounge-chair-by-peter-opsvik-for-stokke-1980s-1536x1536.jpg 1536w\" sizes=\"auto, (max-width: 1650px) 100vw, 1650px\" \/><\/p>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%D9%81%D8%A7%D9%88%D8%AA_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C_%D8%A8%D8%A7_%D8%B3%D8%A7%DB%8C%D8%B1_%D8%B5%D9%86%D8%AF%D9%84%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D8%AF%D8%A7%D8%B1%DB%8C\"><\/span>\u062a\u0641\u0627\u0648\u062a \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u0633\u0627\u06cc\u0631 \u0635\u0646\u062f\u0644\u06cc\u200c\u0647\u0627\u06cc \u0627\u062f\u0627\u0631\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0627\u0632 \u062f\u06cc\u06af\u0631 \u0635\u0646\u062f\u0644\u06cc\u200c\u0647\u0627\u06cc \u0627\u062f\u0627\u0631\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0637\u0631\u0627\u062d\u06cc \u062e\u0627\u0635 \u0648 \u0641\u0646\u0627\u0648\u0631\u06cc\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u0631\u0641\u062a\u0647 \u0645\u062a\u0645\u0627\u06cc\u0632 \u0627\u0633\u062a. \u0628\u0631\u062e\u0644\u0627\u0641 \u0635\u0646\u062f\u0644\u06cc\u200c\u0647\u0627\u06cc \u0645\u0639\u0645\u0648\u0644\u06cc \u06a9\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u06a9\u0648\u062a\u0627\u0647\u200c\u0645\u062f\u062a \u0645\u0646\u0627\u0633\u0628 \u0647\u0633\u062a\u0646\u062f\u060c \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u062e\u0648\u062f \u0628\u0627\u0639\u062b \u06a9\u0627\u0647\u0634 \u0641\u0634\u0627\u0631 \u0628\u0631 \u0628\u062f\u0646 \u062f\u0631 \u0647\u0646\u06af\u0627\u0645 \u0646\u0634\u0633\u062a\u0646 \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0647\u200c\u0648\u06cc\u0698\u0647 \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0633\u0627\u0639\u0627\u062a \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u067e\u0634\u062a \u0645\u06cc\u0632 \u0645\u06cc\u200c\u06af\u0630\u0631\u0627\u0646\u0646\u062f\u060c \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0627\u0633\u062a.<\/p>\n<p>\u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc\u200c\u0647\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0631\u0646\u062f \u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0634\u06a9\u0644 \u0628\u062f\u0646 \u062a\u0637\u0627\u0628\u0642 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f. \u0637\u0631\u0627\u062d\u06cc \u0634\u06cc\u06a9 \u0648 \u0645\u062f\u0631\u0646 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0646\u06cc\u0632 \u0622\u0646 \u0631\u0627 \u0627\u0632 \u0633\u0627\u06cc\u0631 \u0635\u0646\u062f\u0644\u06cc\u200c\u0647\u0627\u06cc \u0627\u062f\u0627\u0631\u06cc \u0645\u062a\u0645\u0627\u06cc\u0632 \u06a9\u0631\u062f\u0647 \u0648 \u0628\u0647 \u0622\u0646 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc\u06cc \u0645\u06cc\u200c\u0628\u062e\u0634\u062f \u06a9\u0647 \u062f\u0631 \u0627\u06a9\u062b\u0631 \u0635\u0646\u062f\u0644\u06cc\u200c\u0647\u0627\u06cc \u0645\u0639\u0645\u0648\u0644\u06cc \u06cc\u0627\u0641\u062a \u0646\u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B9%D9%85%D9%84%DA%A9%D8%B1%D8%AF_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C_%DA%86%DA%AF%D9%88%D9%86%D9%87_%D8%A7%D8%B3%D8%AA%D8%9F\"><\/span>\u0639\u0645\u0644\u06a9\u0631\u062f \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0686\u06af\u0648\u0646\u0647 \u0627\u0633\u062a\u061f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u06a9\u0627\u0631\u0628\u0631 \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0645\u0634\u0627\u0628\u0647 \u0628\u0627 \u062d\u0627\u0644\u062a \u0628\u06cc\u200c\u0648\u0632\u0646\u06cc \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u062f. \u0639\u0645\u0644\u06a9\u0631\u062f \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u06a9\u0627\u0646\u06cc\u0632\u0645 \u062e\u0627\u0635\u06cc \u0628\u0647 \u062f\u0633\u062a \u0645\u06cc\u200c\u0622\u06cc\u062f \u06a9\u0647 \u0632\u0627\u0648\u06cc\u0647 \u0646\u0634\u0633\u062a\u0646 \u0631\u0627 \u0628\u0647 \u0637\u0648\u0631 \u062e\u0648\u062f\u06a9\u0627\u0631 \u062a\u0646\u0638\u06cc\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u06a9\u0627\u0631\u0628\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u062f\u0631 \u0648\u0636\u0639\u06cc\u062a\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u0632 \u062c\u0645\u0644\u0647 \u0648\u0636\u0639\u06cc\u062a \u062e\u0648\u0627\u0628\u06cc\u062f\u0647 \u06cc\u0627 \u0646\u06cc\u0645\u0647 \u062e\u0648\u0627\u0628\u06cc\u062f\u0647 \u0642\u0631\u0627\u0631 \u06af\u06cc\u0631\u062f. \u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0628\u0647 \u06a9\u0627\u0647\u0634 \u0641\u0634\u0627\u0631 \u0631\u0648\u06cc \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a \u0648 \u0639\u0636\u0644\u0627\u062a \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0627\u062d\u0633\u0627\u0633 \u0631\u0627\u062d\u062a\u06cc \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0645\u06cc\u200c\u0628\u062e\u0634\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49470\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0639\u0645\u0644\u06a9\u0631\u062f-\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-scaled.jpg\" alt=\"\u0639\u0645\u0644\u06a9\u0631\u062f \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0639\u0645\u0644\u06a9\u0631\u062f-\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-scaled.jpg 2560w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0639\u0645\u0644\u06a9\u0631\u062f-\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-300x225.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0639\u0645\u0644\u06a9\u0631\u062f-\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-1024x768.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0639\u0645\u0644\u06a9\u0631\u062f-\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-768x576.jpg 768w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0639\u0645\u0644\u06a9\u0631\u062f-\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-1536x1152.jpg 1536w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0639\u0645\u0644\u06a9\u0631\u062f-\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-2048x1536.jpg 2048w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2025\/01\/\u0639\u0645\u0644\u06a9\u0631\u062f-\u0635\u0646\u062f\u0644\u06cc-\u06af\u0631\u0627\u0648\u06cc\u062a\u06cc-86x64.jpg 86w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u0633\u06cc\u0633\u062a\u0645 \u062a\u0646\u0638\u06cc\u0645 \u0632\u0627\u0648\u06cc\u0647\u060c \u0642\u0627\u062f\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0648\u0632\u0646 \u0628\u062f\u0646 \u0631\u0627 \u0628\u0647 \u0637\u0648\u0631 \u06cc\u06a9\u0646\u0648\u0627\u062e\u062a \u062a\u0648\u0632\u06cc\u0639 \u06a9\u0646\u062f \u0648 \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0628\u0627\u0639\u062b \u06a9\u0627\u0647\u0634 \u0641\u0634\u0627\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0645\u0641\u0627\u0635\u0644 \u0648 \u0639\u0636\u0644\u0627\u062a \u0648\u0627\u0631\u062f \u0645\u06cc\u200c\u0634\u0648\u062f. \u0628\u0647 \u0627\u06cc\u0646 \u062a\u0631\u062a\u06cc\u0628\u060c \u06a9\u0627\u0631\u0628\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0633\u0627\u0639\u062a\u200c\u0647\u0627 \u0628\u062f\u0648\u0646 \u0627\u062d\u0633\u0627\u0633 \u062e\u0633\u062a\u06af\u06cc \u06cc\u0627 \u062f\u0631\u062f\u060c \u0627\u0632 \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0639\u0645\u0644\u06a9\u0631\u062f\u060c \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0633\u0627\u0639\u0627\u062a \u0637\u0648\u0644\u0627\u0646\u06cc \u0631\u0627 \u067e\u0634\u062a \u0645\u06cc\u0632 \u0645\u06cc\u200c\u0646\u0634\u06cc\u0646\u0646\u062f \u06cc\u0627 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0627\u0633\u062a\u0631\u0627\u062d\u062a \u062f\u0631 \u062d\u06cc\u0646 \u06a9\u0627\u0631 \u062f\u0627\u0631\u0646\u062f\u060c \u0628\u0633\u06cc\u0627\u0631 \u0645\u0641\u06cc\u062f \u0627\u0633\u062a.<\/p>\n<ul>\n<li><strong>\u0637\u0631\u0627\u062d\u06cc \u0686\u0646\u062f\u0645\u0646\u0638\u0648\u0631\u0647:<\/strong><br \/>\n\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u0646\u0638\u06cc\u0645 \u0628\u0647 \u0686\u0647\u0627\u0631 \u062d\u0627\u0644\u062a \u0645\u062e\u062a\u0644\u0641\u060c \u0627\u0645\u06a9\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062f\u0631 \u0645\u0648\u0642\u0639\u06cc\u062a\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0645\u0627\u0646\u0646\u062f \u06a9\u0627\u0631\u060c \u0627\u0633\u062a\u0631\u0627\u062d\u062a \u0648 \u062d\u062a\u06cc \u062e\u0648\u0627\u0628\u06cc\u062f\u0646 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/li>\n<li><strong>\u062a\u06a9\u06cc\u0647 \u0628\u0631 \u062a\u0639\u0627\u062f\u0644 \u0628\u062f\u0646:<\/strong><br \/>\n\u0637\u0631\u0627\u062d\u06cc \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0631 \u0627\u0633\u0627\u0633 \u062a\u0639\u0627\u062f\u0644 \u0628\u062f\u0646 \u0627\u0633\u062a \u0648 \u0628\u0627 \u062a\u06a9\u06cc\u0647 \u0628\u0631 \u0645\u06a9\u0627\u0646\u06cc\u0632\u0645 \u06af\u0631\u0627\u0646\u0634 \u0632\u0645\u06cc\u0646\u060c \u0648\u0632\u0646 \u0628\u062f\u0646 \u0631\u0627 \u0628\u0647 \u0637\u0648\u0631 \u0645\u062a\u0639\u0627\u062f\u0644 \u062a\u0648\u0632\u06cc\u0639 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0628\u0627\u0639\u062b \u06a9\u0627\u0647\u0634 \u0641\u0634\u0627\u0631 \u0631\u0648\u06cc \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a\u060c \u06af\u0631\u062f\u0646 \u0648 \u0634\u0627\u0646\u0647\u200c\u0647\u0627 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/li>\n<li><strong>\u062d\u0627\u0644\u062a \u0628\u06cc\u200c\u0648\u0632\u0646\u06cc (Zero Gravity):<\/strong><br \/>\n\u062f\u0631 \u06cc\u06a9\u06cc \u0627\u0632 \u062d\u0627\u0644\u062a\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc\u060c \u0628\u062f\u0646 \u062f\u0631 \u0645\u0648\u0642\u0639\u06cc\u062a \u0628\u06cc\u200c\u0648\u0632\u0646\u06cc \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f. \u0627\u06cc\u0646 \u0648\u0636\u0639\u06cc\u062a \u0641\u0634\u0627\u0631 \u0627\u0632 \u0631\u0648\u06cc \u0628\u062f\u0646 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0627\u062f\u0647 \u0648 \u0627\u062d\u0633\u0627\u0633 \u0622\u0631\u0627\u0645\u0634 \u0639\u0645\u06cc\u0642\u06cc \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/li>\n<li><strong>\u0645\u0648\u0627\u062f \u0633\u0627\u0632\u0646\u062f\u0647 \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a:<\/strong><br \/>\n\u0627\u0632 \u0686\u0648\u0628 \u0648 \u067e\u0627\u0631\u0686\u0647\u200c\u0647\u0627\u06cc \u0645\u0642\u0627\u0648\u0645 \u0633\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0648 \u0637\u0631\u0627\u062d\u06cc \u0622\u0646 \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0628\u0627\u0644\u0627 \u0648 \u0638\u0627\u0647\u0631\u06cc \u0632\u06cc\u0628\u0627 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<\/li>\n<\/ul>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%DA%86%DA%AF%D9%88%D9%86%D9%87_%D8%B5%D9%86%D8%AF%D9%84%DB%8C_%DA%AF%D8%B1%D8%A7%D9%88%DB%8C%D8%AA%DB%8C_%D8%B1%D8%A7_%D8%A8%D8%A7_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D8%AA%D8%B1%DA%A9%DB%8C%D8%A8_%DA%A9%D9%86%DB%8C%D9%85%D8%9F\"><\/span>\u0686\u06af\u0648\u0646\u0647 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0631\u0627 \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062a\u0631\u06a9\u06cc\u0628 \u06a9\u0646\u06cc\u0645\u061f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0637\u0631\u0627\u062d\u06cc \u0645\u062f\u0631\u0646 \u0648 \u0645\u06cc\u0646\u06cc\u0645\u0627\u0644\u06cc\u0633\u062a\u06cc\u060c \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u062a\u0631\u06a9\u06cc\u0628 \u0634\u0648\u062f. \u0631\u0646\u06af\u200c\u0647\u0627 \u0648 \u062e\u0637\u0648\u0637 \u0633\u0627\u062f\u0647 \u0622\u0646 \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647\u200c\u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0636\u0627\u06cc \u0627\u062f\u0627\u0631\u06cc \u06cc\u0627 \u062e\u0627\u0646\u06af\u06cc \u0634\u0645\u0627 \u0647\u0645\u062e\u0648\u0627\u0646\u06cc \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0628\u0631\u0627\u06cc \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u06cc \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0645\u062f\u0631\u0646\u060c \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0639\u0646\u0635\u0631 \u0628\u0631\u062c\u0633\u062a\u0647 \u0648 \u06a9\u0627\u0631\u0622\u0645\u062f \u062f\u0631 \u0641\u0636\u0627 \u0628\u0627\u0634\u062f.<\/p>\n<p>\u0628\u0631\u0627\u06cc \u062a\u0631\u06a9\u06cc\u0628 \u0622\u0646 \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0645\u0628\u0644\u0645\u0627\u0646 \u0627\u062f\u0627\u0631\u06cc \u0645\u06cc\u0646\u06cc\u0645\u0627\u0644 \u0648 \u0645\u062f\u0631\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0631\u0646\u06af\u200c\u0647\u0627\u06cc \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0645\u062d\u06cc\u0637\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0647\u0645\u0627\u0647\u0646\u06af\u06cc \u0645\u0637\u0644\u0648\u0628\u06cc \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f\u0647 \u0648 \u0627\u0632 \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0648 \u0639\u0645\u0644\u06a9\u0631\u062f \u0628\u0627\u0644\u0627\u06cc \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0647\u0631\u0647\u200c\u0645\u0646\u062f \u0634\u0648\u06cc\u062f.<\/p>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AC%D9%85%D8%B9_%D8%A8%D9%86%D8%AF%DB%8C\"><\/span>\u062c\u0645\u0639 \u0628\u0646\u062f\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0645\u0646\u062d\u0635\u0631 \u0628\u0647 \u0641\u0631\u062f\u06cc \u06a9\u0647 \u062f\u0627\u0631\u062f\u060c \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u0639\u0627\u0644\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0631\u0627\u062d\u062a\u06cc \u0648 \u0632\u06cc\u0628\u0627\u06cc\u06cc \u062f\u0631 \u0645\u062d\u06cc\u0637 \u06a9\u0627\u0631\u06cc \u062e\u0648\u062f \u0647\u0633\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0627 \u0637\u0631\u0627\u062d\u06cc \u0627\u0631\u06af\u0648\u0646\u0648\u0645\u06cc\u06a9 \u0648 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u0648\u06cc\u0698\u0647\u060c \u0627\u0632 \u0641\u0634\u0627\u0631 \u0628\u0647 \u0628\u062f\u0646 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0631\u062f\u0647 \u0648 \u0622\u0631\u0627\u0645\u0634 \u0631\u0627 \u062f\u0631 \u0644\u062d\u0638\u0627\u062a \u0637\u0648\u0644\u0627\u0646\u06cc \u0646\u0634\u0633\u062a\u0646 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u0622\u0648\u0631\u062f.<\/p>\n<p>\u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0645\u062a\u0641\u0627\u0648\u062a \u0648 \u0627\u0631\u062a\u0642\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u062f\u0631 \u0645\u062d\u0644 \u06a9\u0627\u0631 \u062e\u0648\u062f \u0647\u0633\u062a\u06cc\u062f\u060c \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0627\u0633\u062a. \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u062f\u06a9\u0648\u0631\u0634\u0627\u067e \u0628\u0627 \u0627\u0631\u0627\u0626\u0647 \u0627\u0646\u0648\u0627\u0639 <strong><a href=\"https:\/\/decorshop.ir\/product-category\/office-furniture\/\">\u0645\u0628\u0644\u0645\u0627\u0646 \u0627\u062f\u0627\u0631\u06cc<\/a><\/strong> \u0648 \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u062c\u0631\u0628\u0647 \u062e\u0631\u06cc\u062f\u06cc \u0631\u0627\u062d\u062a \u0648 \u0645\u0637\u0645\u0626\u0646 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0641\u0631\u0627\u0647\u0645 \u06a9\u0646\u062f.<\/p>\n<blockquote><p><em><strong>\u0622\u06cc\u0627 \u0628\u0647 \u0622\u0631\u0627\u0645\u0634 \u062f\u0631 \u0644\u062d\u0638\u0647 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u06cc\u062f\u061f \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u062a\u062c\u0631\u0628\u0647 \u0646\u0632\u062f\u06cc\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f!<\/strong><\/em><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>\u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc (Gravity) \u06cc\u06a9\u06cc \u0627\u0632 \u0646\u0648\u0622\u0648\u0631\u0627\u0646\u0647\u200c\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0635\u0646\u062f\u0644\u06cc \u0627\u062f\u0627\u0631\u06cc \u0648 \u062e\u0627\u0646\u06af\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u0647\u062f\u0641 \u0627\u06cc\u062c\u0627\u062f \u0631\u0627\u062d\u062a\u06cc \u0648 \u0622\u0631\u0627\u0645\u0634 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u06a9\u0627\u0631 \u06cc\u0627 \u062f\u0641\u062a\u0631 \u06a9\u0627\u0631 \u062e\u0627\u0646\u06af\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u062e\u0631\u06cc\u062f \u0635\u0646\u062f\u0644\u06cc \u0627\u062f\u0627\u0631\u06cc \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0632 \u0646\u0634\u0633\u062a\u0646 \u0628\u0647 \u0634\u0645\u0627 \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u062f\u060c \u0635\u0646\u062f\u0644\u06cc \u06af\u0631\u0627\u0648\u06cc\u062a\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0627\u0634\u062f. \u0627\u06cc\u0646 \u0635\u0646\u062f\u0644\u06cc \u0628\u0627 \u0637\u0631\u0627\u062d\u06cc [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":49455,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[706,41,53],"tags":[],"class_list":["post-49454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-706","category-41","category-53"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/49454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=49454"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/49454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/49455"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=49454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=49454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=49454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}