{"id":48997,"date":"2024-12-16T17:45:10","date_gmt":"2024-12-16T14:15:10","guid":{"rendered":"https:\/\/decorshop.ir\/mag\/?p=48997"},"modified":"2024-12-16T17:45:10","modified_gmt":"2024-12-16T14:15:10","slug":"%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/","title":{"rendered":"\u0631\u0627\u0632\u0647\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0645\u0646\u0627\u0633\u0628: \u0645\u0642\u0627\u06cc\u0633\u0647 \u0627\u0646\u0648\u0627\u0639 \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u062f\u0644"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D8%B1%D8%A7%D8%B2%D9%87%D8%A7%DB%8C_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D9%85%D8%AF%D9%84\" >\u0631\u0627\u0632\u0647\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0645\u0646\u0627\u0633\u0628: \u0645\u0642\u0627\u06cc\u0633\u0647 \u0627\u0646\u0648\u0627\u0639 \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u062f\u0644<\/a><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D9%85%D8%B9%D8%B1%D9%81%DB%8C_%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C\" >\u0645\u0639\u0631\u0641\u06cc \u0627\u0646\u0648\u0627\u0639 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_LED\" >\u0686\u0631\u0627\u063a \u062e\u0637\u06cc LED<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D9%81%D9%84%D9%88%D8%B1%D8%B3%D9%86%D8%AA\" >\u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0641\u0644\u0648\u0631\u0633\u0646\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D9%87%D8%A7%D9%84%D9%88%DA%98%D9%86\" >\u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0647\u0627\u0644\u0648\u0698\u0646<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D9%81%D8%A7%DA%A9%D8%AA%D9%88%D8%B1%D9%87%D8%A7%DB%8C_%D9%85%D9%87%D9%85_%D8%AF%D8%B1_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C\" >\u0641\u0627\u06a9\u062a\u0648\u0631\u0647\u0627\u06cc \u0645\u0647\u0645 \u062f\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D8%B1%D9%88%DA%A9%D8%A7%D8%B1%D8%8C_%D8%AA%D9%88%DA%A9%D8%A7%D8%B1_%D9%88_%D8%A2%D9%88%DB%8C%D8%B2\" >\u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0631\u0648\u06a9\u0627\u0631\u060c \u062a\u0648\u06a9\u0627\u0631 \u0648 \u0622\u0648\u06cc\u0632<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D8%B4%D8%AF%D8%AA_%D9%86%D9%88%D8%B1_%D9%88_%D9%84%D9%88%D9%85%D9%86\" >\u0634\u062f\u062a \u0646\u0648\u0631 \u0648 \u0644\u0648\u0645\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D8%AF%D9%85%D8%A7%DB%8C_%D8%B1%D9%86%DA%AF_%D9%86%D9%88%D8%B1_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C\" >\u062f\u0645\u0627\u06cc \u0631\u0646\u06af \u0646\u0648\u0631 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D8%B7%D9%88%D9%84_%D8%B9%D9%85%D8%B1_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D9%88_%D9%85%D8%B5%D8%B1%D9%81_%D8%A7%D9%86%D8%B1%DA%98%DB%8C_%D8%A2%D9%86\" >\u0637\u0648\u0644 \u0639\u0645\u0631 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0648 \u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc \u0622\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D9%82%D8%A7%D8%A8%D9%84%DB%8C%D8%AA_%D8%AA%D9%86%D8%B8%DB%8C%D9%85_%D9%86%D9%88%D8%B1_%D8%AF%DB%8C%D9%85%D8%B1\" >\u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u0646\u0638\u06cc\u0645 \u0646\u0648\u0631 (\u062f\u06cc\u0645\u0631)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D9%85%D9%82%D8%A7%D9%88%D9%85%D8%AA_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D8%AF%D8%B1_%D8%A8%D8%B1%D8%A7%D8%A8%D8%B1_%D8%A2%D8%A8_%D9%88_%DA%AF%D8%B1%D8%AF%D9%88%D8%BA%D8%A8%D8%A7%D8%B1\" >\u0645\u0642\u0627\u0648\u0645\u062a \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0622\u0628 \u0648 \u06af\u0631\u062f\u0648\u063a\u0628\u0627\u0631<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D8%B1%D8%A7%D9%87%D9%86%D9%85%D8%A7%DB%8C_%D8%AE%D8%B1%DB%8C%D8%AF_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C%D8%9B_%D9%86%DA%A9%D8%A7%D8%AA_%D9%85%D9%87%D9%85\" >\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0686\u0631\u0627\u063a \u062e\u0637\u06cc\u061b \u0646\u06a9\u0627\u062a \u0645\u0647\u0645<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D9%86%DA%A9%D8%A7%D8%AA_%D9%85%D9%87%D9%85_%D9%82%D8%A8%D9%84_%D8%A7%D8%B2_%D8%AE%D8%B1%DB%8C%D8%AF_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C\" >\u0646\u06a9\u0627\u062a \u0645\u0647\u0645 \u0642\u0628\u0644 \u0627\u0632 \u062e\u0631\u06cc\u062f \u0686\u0631\u0627\u063a \u062e\u0637\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D8%A8%D8%B1%D8%B1%D8%B3%DB%8C_%DA%AF%D8%A7%D8%B1%D8%A7%D9%86%D8%AA%DB%8C_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D9%88_%D8%AE%D8%AF%D9%85%D8%A7%D8%AA_%D9%BE%D8%B3_%D8%A7%D8%B2_%D9%81%D8%B1%D9%88%D8%B4\" >\u0628\u0631\u0631\u0633\u06cc \u06af\u0627\u0631\u0627\u0646\u062a\u06cc \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0648 \u062e\u062f\u0645\u0627\u062a \u067e\u0633 \u0627\u0632 \u0641\u0631\u0648\u0634<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D9%82%DB%8C%D9%85%D8%AA_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D8%AF%D8%B1_%D9%81%D8%B1%D9%88%D8%B4%DA%AF%D8%A7%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%85%D8%AE%D8%AA%D9%84%D9%81\" >\u0645\u0642\u0627\u06cc\u0633\u0647 \u0642\u06cc\u0645\u062a \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u062f\u0631 \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D9%86%D8%B5%D8%A8_%D9%88_%D9%86%DA%AF%D9%87%D8%AF%D8%A7%D8%B1%DB%8C_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C\" >\u0646\u0635\u0628 \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0686\u0631\u0627\u063a \u062e\u0637\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d8%b2%d9%87%d8%a7%db%8c-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%da%86%d8%b1%d8%a7%d8%ba-%d8%ae%d8%b7%db%8c-%d9%85%d9%86%d8%a7%d8%b3%d8%a8\/#%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C_%D8%B1%D8%A7%D9%87%D9%86%D9%85%D8%A7%DB%8C_%D8%AE%D8%B1%DB%8C%D8%AF_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C\" >\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc \u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0686\u0631\u0627\u063a \u062e\u0637\u06cc<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h1 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D8%B1%D8%A7%D8%B2%D9%87%D8%A7%DB%8C_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D9%85%D8%AF%D9%84\"><\/span><strong>\u0631\u0627\u0632\u0647\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0645\u0646\u0627\u0633\u0628: \u0645\u0642\u0627\u06cc\u0633\u0647 \u0627\u0646\u0648\u0627\u0639 \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u062f\u0644<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h1>\n<p><strong><img decoding=\"async\" src=\"https:\/\/cdn.triboon.net\/media\/reportage_images\/bc53bf76-f4d0-47bf-970d-f568d24f930a.jpg\" alt=\"\u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u062f\u0631 \u0633\u0642\u0641 \u0648 \u062f\u06cc\u0648\u0627\u0631\" \/><\/strong><\/p>\n<p dir=\"rtl\">\u0627\u0632 \u0632\u0645\u0627\u0646 \u0627\u062e\u062a\u0631\u0627\u0639 \u0644\u0627\u0645\u067e \u062a\u0648\u0633\u0637 \u062a\u0648\u0645\u0627\u0633 \u0627\u062f\u06cc\u0633\u0648\u0646\u060c \u0644\u0627\u0645\u067e\u200c\u0647\u0627 \u0628\u0647 \u0627\u0628\u0632\u0627\u0631 \u0636\u0631\u0648\u0631\u06cc \u0628\u0631\u0627\u06cc \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647\u200c\u0627\u0646\u062f. \u0627\u0645\u0631\u0648\u0632\u0647\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u0644\u0627\u0645\u067e\u200c\u0647\u0627 \u0646\u06cc\u0627\u0632\u0645\u0646\u062f \u062f\u0642\u062a \u0648 \u0633\u0644\u06cc\u0642\u0647 \u0627\u0633\u062a\u060c \u0632\u06cc\u0631\u0627 \u0622\u0646\u200c\u0647\u0627 \u0646\u0642\u0634 \u0645\u0647\u0645\u06cc \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0627\u06cc\u0641\u0627 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0631\u0648\u0646\u062f \u0637\u0631\u0627\u062d\u06cc \u0645\u06cc\u0646\u06cc\u0645\u0627\u0644\u06cc\u0633\u062a\u06cc\u060c \u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc \u062e\u0637\u06cc \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0641\u0636\u0627\u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0634\u0646\u0627\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0646\u062d\u0648\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0627\u0632 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0647\u0633\u062a\u06cc\u062f\u060c \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u0646\u062f\u0647\u06cc\u062f.<\/p>\n<h2 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%D8%B1%D9%81%DB%8C_%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C\"><\/span><strong>\u0645\u0639\u0631\u0641\u06cc \u0627\u0646\u0648\u0627\u0639 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p dir=\"rtl\">\u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc \u062e\u0637\u06cc \u0627\u0632 \u0645\u062d\u0628\u0648\u0628\u200c\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0645\u062f\u0631\u0646 \u0647\u0633\u062a\u0646\u062f\u061b \u0627\u0645\u0627 \u0622\u06cc\u0627 \u062a\u0627\u0628\u0647\u200c\u062d\u0627\u0644 \u0628\u0647 \u0627\u06cc\u0646 \u0641\u06a9\u0631 \u06a9\u0631\u062f\u0647\u200c\u0627\u06cc\u062f \u06a9\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0648\u0639 \u0645\u0646\u0627\u0633\u0628 \u0686\u0631\u0627\u063a \u0628\u0631\u0627\u06cc \u062e\u0627\u0646\u0647\u060c \u0645\u062d\u0644 \u06a9\u0627\u0631 \u06cc\u0627 \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0686\u0642\u062f\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0648 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0641\u0636\u0627 \u062a\u0623\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u0628\u0627\u0634\u062f\u061f \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0627\u0646\u0648\u0627\u0639 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc\u060c \u0645\u0632\u0627\u06cc\u0627 \u0648 \u0645\u0639\u0627\u06cc\u0628 \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645 \u062a\u0627 \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u06cc\u0645 \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0646\u0627\u0633\u0628\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f.<\/p>\n<table>\n<thead>\n<tr>\n<th style=\"text-align: center;\">\u0648\u06cc\u0698\u06af\u06cc<\/th>\n<th style=\"text-align: center;\">\u0686\u0631\u0627\u063a \u062e\u0637\u06cc LED<\/th>\n<th style=\"text-align: center;\">\u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0641\u0644\u0648\u0631\u0633\u0646\u062a<\/th>\n<th style=\"text-align: center;\">\u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0647\u0627\u0644\u0648\u0698\u0646<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td><strong>\u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc<\/strong><\/td>\n<td style=\"text-align: right;\">\u06a9\u0645<\/td>\n<td style=\"text-align: right;\">\u0645\u062a\u0648\u0633\u0637<\/td>\n<td style=\"text-align: right;\">\u0628\u0627\u0644\u0627<\/td>\n<\/tr>\n<tr>\n<td><strong>\u0637\u0648\u0644 \u0639\u0645\u0631<\/strong><\/td>\n<td>\u0628\u0627\u0644\u0627<\/td>\n<td>\u0645\u062a\u0648\u0633\u0637<\/td>\n<td>\u067e\u0627\u06cc\u06cc\u0646<\/td>\n<\/tr>\n<tr>\n<td><strong>\u06a9\u06cc\u0641\u06cc\u062a \u0646\u0648\u0631<\/strong><\/td>\n<td>\u06cc\u06a9\u0646\u0648\u0627\u062e\u062a \u0648 \u062c\u0630\u0627\u0628<\/td>\n<td>\u0646\u0627\u067e\u0627\u06cc\u062f\u0627\u0631 \u0648 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062e\u0633\u062a\u0647\u200c\u06a9\u0646\u0646\u062f\u0647 \u0628\u0627\u0634\u062f<\/td>\n<td>\u0642\u0648\u06cc \u0648 \u0628\u0627 \u062f\u0645\u0627\u06cc \u0631\u0646\u06af \u06af\u0631\u0645<\/td>\n<\/tr>\n<tr>\n<td><strong>\u0642\u06cc\u0645\u062a \u0627\u0648\u0644\u06cc\u0647<\/strong><\/td>\n<td>\u0628\u0627\u0644\u0627\u062a\u0631<\/td>\n<td>\u067e\u0627\u06cc\u06cc\u0646\u200c\u062a\u0631<\/td>\n<td>\u0645\u062a\u0648\u0633\u0637<\/td>\n<\/tr>\n<tr>\n<td><strong>\u06a9\u0627\u0631\u0628\u0631\u062f<\/strong><\/td>\n<td>\u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u062e\u0627\u0646\u0647\u060c \u0627\u062f\u0627\u0631\u0647 \u0648 \u06af\u0627\u0644\u0631\u06cc\u200c\u0647\u0627<\/td>\n<td>\u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0641\u0636\u0627\u0647\u0627\u06cc \u0628\u0632\u0631\u06af<\/td>\n<td>\u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0633\u0627\u0644\u0646\u200c\u0647\u0627\u06cc \u0646\u0645\u0627\u06cc\u0634 \u0648 \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627<\/td>\n<\/tr>\n<tr>\n<td><strong>\u0645\u0632\u0627\u06cc\u0627<\/strong><\/td>\n<td>\u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0647\u0632\u06cc\u0646\u0647 \u0628\u0631\u0642\u060c \u0637\u0648\u0644 \u0639\u0645\u0631 \u0628\u0627\u0644\u0627<\/td>\n<td>\u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628\u060c \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0646\u0648\u0631 \u0632\u06cc\u0627\u062f<\/td>\n<td>\u0646\u0648\u0631 \u0642\u0648\u06cc \u0648 \u062f\u0645\u0627\u06cc \u0631\u0646\u06af \u06af\u0631\u0645<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\"><strong>\u0645\u0639\u0627\u06cc\u0628<\/strong><\/td>\n<td style=\"text-align: right;\">\u0642\u06cc\u0645\u062a \u0627\u0648\u0644\u06cc\u0647 \u0628\u0627\u0644\u0627<\/td>\n<td style=\"text-align: right;\">\u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc \u0628\u06cc\u0634\u062a\u0631\u060c \u0639\u0645\u0631 \u06a9\u0648\u062a\u0627\u0647\u200c\u062a\u0631<\/td>\n<td style=\"text-align: right;\">\u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc \u0628\u0627\u0644\u0627\u060c \u0639\u0645\u0631 \u06a9\u0648\u062a\u0627\u0647\u200c\u062a\u0631<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_LED\"><\/span><strong>\u0686\u0631\u0627\u063a \u062e\u0637\u06cc LED<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p dir=\"rtl\">\u0627\u06cc\u0646 \u0686\u0631\u0627\u063a\u200c\u0647\u0627 \u0646\u0647 \u062a\u0646\u0647\u0627 \u0627\u0646\u0631\u0698\u06cc \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0645\u06cc \u0645\u0635\u0631\u0641 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0637\u0648\u0644 \u0639\u0645\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0644\u0627\u06cc\u06cc \u0647\u0645 \u062f\u0627\u0631\u0646\u062f. \u0627\u0632 \u0646\u0638\u0631 \u0638\u0627\u0647\u0631\u06cc \u0646\u06cc\u0632 \u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc LED \u0646\u0648\u0631 \u0628\u0633\u06cc\u0627\u0631 \u06cc\u06a9\u0646\u0648\u0627\u062e\u062a \u0648 \u062c\u0630\u0627\u0628\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u06a9\u0647 \u0628\u0631\u0627\u06cc \u062e\u0627\u0646\u0647\u060c \u0627\u062f\u0627\u0631\u0647\u060c \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627 \u0648 \u062d\u062a\u06cc \u06af\u0627\u0644\u0631\u06cc\u200c\u0647\u0627\u06cc \u0647\u0646\u0631\u06cc \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a. \u0634\u0627\u06cc\u062f \u0642\u06cc\u0645\u062a \u0686\u0631\u0627\u063a \u062e\u0637\u06cc LED \u06a9\u0645\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0628\u0627\u0634\u062f\u061b \u0627\u0645\u0627 \u0628\u0627 \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0647\u0632\u06cc\u0646\u0647 \u0628\u0631\u0642 \u0648 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0628\u0627\u0644\u0627 \u0627\u06cc\u0646 \u0647\u0632\u06cc\u0646\u0647 \u06a9\u0627\u0645\u0644\u0627\u064b \u062c\u0628\u0631\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<h3 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D9%81%D9%84%D9%88%D8%B1%D8%B3%D9%86%D8%AA\"><\/span><strong>\u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0641\u0644\u0648\u0631\u0633\u0646\u062a<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p dir=\"rtl\">\u0627\u06cc\u0646 \u0686\u0631\u0627\u063a\u200c\u0647\u0627 \u0642\u06cc\u0645\u062a \u0627\u0648\u0644\u06cc\u0647 \u06a9\u0645\u062a\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 LED \u062f\u0627\u0631\u0646\u062f \u0648 \u0628\u0631\u0627\u06cc \u0641\u0636\u0627\u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u06a9\u0647 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0646\u0648\u0631 \u0632\u06cc\u0627\u062f \u062f\u0627\u0631\u0646\u062f \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0647\u0633\u062a\u0646\u062f.<br \/>\n\u0627\u0645\u0627 \u0647\u0645\u0627\u0646\u200c\u0637\u0648\u0631 \u06a9\u0647 \u0645\u06cc\u200c\u062f\u0627\u0646\u06cc\u062f \u0647\u0631 \u0627\u0631\u0632\u0627\u0646\u06cc \u0628\u06cc\u200c\u062f\u0644\u06cc\u0644 \u0646\u06cc\u0633\u062a. \u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc \u062e\u0637\u06cc \u0641\u0644\u0648\u0631\u0633\u0646\u062a \u0627\u0646\u0631\u0698\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0645\u0635\u0631\u0641 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0639\u0645\u0631 \u06a9\u0648\u062a\u0627\u0647\u200c\u062a\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 LED \u062f\u0627\u0631\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u062f\u0631 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0627\u00a0 LED\u060c \u0646\u0648\u0631 \u0622\u0646\u200c\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u06a9\u0645\u06cc \u0646\u0627\u067e\u0627\u06cc\u062f\u0627\u0631 \u0628\u0627\u0634\u062f \u0648 \u0628\u0631\u0627\u06cc \u0686\u0634\u0645 \u062e\u0633\u062a\u0647\u200c\u06a9\u0646\u0646\u062f\u0647\u200c\u062a\u0631 \u0628\u0647 \u0646\u0638\u0631 \u0628\u0631\u0633\u062f.<\/p>\n<h3 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D9%87%D8%A7%D9%84%D9%88%DA%98%D9%86\"><\/span><strong>\u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0647\u0627\u0644\u0648\u0698\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p dir=\"rtl\">\u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0686\u0631\u0627\u063a\u06cc \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u0646\u0648\u0631\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0642\u0648\u06cc \u0648 \u062f\u0645\u0627\u06cc \u0631\u0646\u06af \u06af\u0631\u0645 \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u062f \u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc \u062e\u0637\u06cc \u0647\u0627\u0644\u0648\u0698\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u06af\u0632\u06cc\u0646\u0647 \u062e\u0648\u0628\u06cc \u0628\u0627\u0634\u0646\u062f. \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0686\u0631\u0627\u063a\u200c\u0647\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u062f\u0631 \u0641\u0636\u0627\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0647 \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0634\u062f\u06cc\u062f \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u0646\u062f \u0645\u062b\u0644 \u0633\u0627\u0644\u0646\u200c\u0647\u0627\u06cc \u0646\u0645\u0627\u06cc\u0634 \u06cc\u0627 \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u062e\u0627\u0635 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<br \/>\n\u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644 \u0627\u06af\u0631 \u0628\u0647 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0647\u0627\u0644\u0648\u0698\u0646 \u0648 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc LED \u0628\u067e\u0631\u062f\u0627\u0632\u06cc\u0645\u060c \u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc \u0628\u0627\u0644\u0627 \u0648 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0646\u0633\u0628\u062a\u0627\u064b \u06a9\u0645 \u0627\u0632 \u0646\u0642\u0627\u0637 \u0636\u0639\u0641 \u0627\u0635\u0644\u06cc \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0647\u0627\u0644\u0648\u0698\u0646 \u0647\u0633\u062a\u0646\u062f.<\/p>\n<h2 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D9%81%D8%A7%DA%A9%D8%AA%D9%88%D8%B1%D9%87%D8%A7%DB%8C_%D9%85%D9%87%D9%85_%D8%AF%D8%B1_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C\"><\/span><strong>\u0641\u0627\u06a9\u062a\u0648\u0631\u0647\u0627\u06cc \u0645\u0647\u0645 \u062f\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p dir=\"rtl\">\u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u0628\u0627 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u062f\u0631 \u06cc\u06a9 \u0645\u062d\u06cc\u0637 \u0646\u06cc\u0627\u0632\u0645\u0646\u062f \u062f\u0642\u062a \u0648 \u062a\u0648\u062c\u0647 \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0627\u0633\u062a\u061b \u0686\u0631\u0627\u06a9\u0647 \u0647\u0631 \u0641\u0636\u0627\u06cc\u06cc \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u062e\u0627\u0635\u06cc \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0628\u0627 \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u062f\u0631\u0633\u062a \u0628\u0631\u0637\u0631\u0641 \u0634\u0648\u0646\u062f. \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u062f\u0631\u0633\u062a \u0686\u0631\u0627\u063a\u200e\u0647\u0627\u06cc \u062e\u0637\u06cc \u062d\u062a\u0645\u0627 \u0628\u0627\u06cc\u062f \u062f\u0631\u0645\u0648\u0631\u062f \u0641\u0627\u06a9\u062a\u0648\u0631\u0647\u0627\u06cc \u0645\u0647\u0645 \u0622\u0646 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u06a9\u0627\u0641\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647 \u062a\u0648\u0636\u06cc\u062d \u0633\u0627\u062f\u0647\u200c\u06cc \u0647\u0631 \u06cc\u06a9 \u0627\u0632 \u0641\u0627\u06a9\u062a\u0648\u0631\u0647\u0627\u06cc \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u062e\u0648\u0627\u0647\u06cc\u0645 \u067e\u0631\u062f\u0627\u062e\u062a:<\/p>\n<h3 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D8%B1%D9%88%DA%A9%D8%A7%D8%B1%D8%8C_%D8%AA%D9%88%DA%A9%D8%A7%D8%B1_%D9%88_%D8%A2%D9%88%DB%8C%D8%B2\"><\/span><strong>\u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0631\u0648\u06a9\u0627\u0631\u060c \u062a\u0648\u06a9\u0627\u0631 \u0648 \u0622\u0648\u06cc\u0632<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p dir=\"rtl\">\u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc \u062e\u0637\u06cc \u0628\u0647 \u0633\u0647 \u062f\u0633\u062a\u0647 \u0631\u0648\u06a9\u0627\u0631\u060c \u062a\u0648\u06a9\u0627\u0631 \u0648 \u0622\u0648\u06cc\u0632 \u062a\u0642\u0633\u06cc\u0645 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc \u062e\u0637\u06cc \u0631\u0648\u06a9\u0627\u0631 \u0628\u0631 \u0631\u0648\u06cc \u0633\u0637\u0648\u062d\u06cc \u0645\u0627\u0646\u0646\u062f \u0633\u0642\u0641 \u06cc\u0627 \u062f\u06cc\u0648\u0627\u0631 \u0646\u0635\u0628 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0648 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0642\u0627\u0628\u0644\u06cc\u062a \u062f\u0633\u062a\u0631\u0633\u06cc \u0648 \u062a\u0639\u0648\u06cc\u0636 \u062f\u0627\u0631\u0646\u062f \u06a9\u0647 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0641\u0636\u0627\u0647\u0627\u06cc \u0639\u0645\u0648\u0645\u06cc \u0648 \u062a\u062c\u0627\u0631\u06cc \u0645\u0646\u0627\u0633\u0628 \u0645\u06cc\u200c\u0633\u0627\u0632\u062f. \u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc \u062e\u0637\u06cc \u062a\u0648\u06a9\u0627\u0631 \u062f\u0631 \u062f\u0627\u062e\u0644 \u0633\u0642\u0641 \u06cc\u0627 \u062f\u06cc\u0648\u0627\u0631 \u062c\u0627\u0633\u0627\u0632\u06cc \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0648 \u0638\u0627\u0647\u0631\u06cc \u0632\u06cc\u0628\u0627 \u0648 \u0645\u06cc\u0646\u06cc\u0645\u0627\u0644\u06cc\u0633\u062a\u06cc \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0637\u0631\u0627\u062d\u06cc\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0645\u062f\u0631\u0646 \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0647\u0633\u062a\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc \u0622\u0648\u06cc\u0632 \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u0639\u0644\u0642 \u0627\u0632 \u0633\u0642\u0641 \u0622\u0648\u06cc\u0632\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0648 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0628\u0631\u0627\u06cc \u062a\u0623\u06a9\u06cc\u062f \u0628\u0631 \u0646\u0642\u0627\u0637 \u062e\u0627\u0635\u06cc \u0627\u0632 \u0641\u0636\u0627 \u0645\u0627\u0646\u0646\u062f \u0645\u06cc\u0632\u0647\u0627\u06cc \u0646\u0627\u0647\u0627\u0631\u062e\u0648\u0631\u06cc \u06cc\u0627 \u062c\u0627\u06cc\u06af\u0627\u0647 \u0646\u0634\u06cc\u0645\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u06cc\u0646 \u0627\u06cc\u0646 \u0627\u0646\u0648\u0627\u0639 \u0686\u0631\u0627\u063a\u200c\u0647\u0627 \u0628\u0633\u062a\u06af\u06cc \u0628\u0647 \u0646\u06cc\u0627\u0632 \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u0648 \u0637\u0631\u0627\u062d\u06cc \u0641\u0636\u0627 \u062f\u0627\u0631\u062f.<\/p>\n<p dir=\"rtl\"><img decoding=\"async\" src=\"https:\/\/cdn.triboon.net\/media\/reportage_images\/c4056aae-cbc2-4d74-8ddc-2bdf1eed74d0.jpg\" alt=\"\u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0622\u0648\u06cc\u0632 \u062f\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\" \/><\/p>\n<h3 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D8%B4%D8%AF%D8%AA_%D9%86%D9%88%D8%B1_%D9%88_%D9%84%D9%88%D9%85%D9%86\"><\/span><strong>\u0634\u062f\u062a \u0646\u0648\u0631 \u0648 \u0644\u0648\u0645\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u06cc\u0646 \u0633\u0648\u0627\u0644 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u067e\u06cc\u0634 \u0628\u06cc\u0627\u06cc\u062f \u06a9\u0647 <strong><a href=\"https:\/\/partonoortoos.com\/blog\/what-is-lumen\/\" target=\"_blank\" rel=\"follow noopener\">\u0644\u0648\u0645\u0646 \u0686\u06cc\u0633\u062a\u061f<\/a><\/strong>\u060c \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u062a\u0639\u0627\u0631\u06cc\u0641 \u06a9\u0627\u0645\u0644 \u0622\u0646 \u0622\u0648\u0631\u062f\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a:<\/p>\n<blockquote>\n<p dir=\"rtl\"><strong>\u0644\u0648\u0645\u0646 \u0648\u0627\u062d\u062f \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u06af\u06cc\u0631\u06cc \u0634\u062f\u062a \u0646\u0648\u0631 \u0627\u0633\u062a\u061b \u0628\u0647 \u0632\u0628\u0627\u0646 \u0633\u0627\u062f\u0647 \u06cc\u0639\u0646\u06cc \u0645\u0642\u062f\u0627\u0631 \u0646\u0648\u0631\u06cc \u06a9\u0647 \u06cc\u06a9 \u0645\u0646\u0628\u0639 \u0646\u0648\u0631 \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0647\u0631 \u0686\u0642\u062f\u0631 \u0644\u0648\u0645\u0646 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0627\u0634\u062f\u060c \u0646\u0648\u0631 \u0622\u0646 \u0644\u0627\u0645\u067e \u06cc\u0627 \u0645\u0646\u0628\u0639 \u0646\u0648\u0631\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0648 \u0631\u0648\u0634\u0646\u200c\u062a\u0631 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/strong><\/p>\n<\/blockquote>\n<p dir=\"rtl\">\u0647\u0631 \u0641\u0636\u0627\u06cc\u06cc \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0645\u0642\u062f\u0627\u0631 \u0645\u0634\u062e\u0635\u06cc \u0627\u0632 \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f \u0648 \u0627\u06cc\u0646\u062c\u0627\u0633\u062a \u06a9\u0647 \u0645\u0641\u0647\u0648\u0645 \u0644\u0648\u0645\u0646 \u0648\u0627\u0631\u062f \u0645\u06cc\u062f\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0644\u0648\u0645\u0646 \u0645\u06cc\u0632\u0627\u0646 \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u062a\u0648\u0644\u06cc\u062f \u0634\u062f\u0647 \u062a\u0648\u0633\u0637 \u0686\u0631\u0627\u063a \u0631\u0627 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0627\u06af\u0631 \u0642\u0635\u062f \u062f\u0627\u0631\u06cc\u062f \u0686\u0631\u0627\u063a\u06cc \u0628\u0631\u0627\u06cc \u0627\u062a\u0627\u0642 \u0646\u0634\u06cc\u0645\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f \u0644\u0648\u0645\u0646 \u0645\u062a\u0648\u0633\u0637 \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a \u062a\u0627 \u0641\u0636\u0627\u06cc\u06cc \u062f\u0644\u067e\u0630\u06cc\u0631 \u0648 \u0622\u0631\u0627\u0645 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u062f. \u0627\u0645\u0627 \u0628\u0631\u0627\u06cc \u0641\u0636\u0627\u0647\u0627\u06cc \u06a9\u0627\u0631\u06cc \u06cc\u0627 \u0645\u0637\u0627\u0644\u0639\u0647 \u0628\u0627\u06cc\u062f \u0686\u0631\u0627\u063a\u06cc \u0628\u0627 \u0644\u0648\u0645\u0646 \u0628\u0627\u0644\u0627\u062a\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0646\u0648\u0631 \u06a9\u0627\u0641\u06cc \u0628\u0631\u0627\u06cc \u062a\u0645\u0631\u06a9\u0632 \u0641\u0631\u0627\u0647\u0645 \u0634\u0648\u062f. \u0646\u06a9\u062a\u0647 \u0645\u0647\u0645 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0647\u0645\u06cc\u0634\u0647 \u0628\u0647 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0641\u0636\u0627\u06cc\u06cc \u062e\u0648\u062f \u0641\u06a9\u0631 \u06a9\u0646\u06cc\u062f. \u0627\u0646\u062a\u062e\u0627\u0628 \u06cc\u06a9 \u0686\u0631\u0627\u063a \u0628\u0627 \u0634\u062f\u062a \u0646\u0648\u0631 \u06a9\u0645 \u0628\u0631\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u06cc\u0627 \u0628\u0627 \u0634\u062f\u062a \u0646\u0648\u0631 \u0632\u06cc\u0627\u062f \u0628\u0631\u0627\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0646\u062a\u06cc\u062c\u0647 \u0645\u0637\u0644\u0648\u0628\u06cc \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<\/p>\n<h3 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D8%AF%D9%85%D8%A7%DB%8C_%D8%B1%D9%86%DA%AF_%D9%86%D9%88%D8%B1_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C\"><\/span><strong>\u062f\u0645\u0627\u06cc \u0631\u0646\u06af \u0646\u0648\u0631 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p dir=\"rtl\">\u062f\u0645\u0627\u06cc \u0631\u0646\u06af \u0646\u0648\u0631 \u06a9\u0647 \u0628\u0627 \u0648\u0627\u062d\u062f \u06a9\u0644\u0648\u06cc\u0646 (K) \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u06af\u06cc\u0631\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0647\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f. \u0628\u0647 \u0646\u0648\u0631\u06cc \u06a9\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0647 \u0631\u0646\u06af \u0622\u0628\u06cc \u0645\u062a\u0645\u0627\u06cc\u0644 \u0628\u0627\u0634\u062f \u0646\u0648\u0631 \u0633\u0631\u062f \u0648 \u0628\u0647 \u0646\u0648\u0631\u06cc \u06a9\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0645\u062a\u0645\u0627\u06cc\u0644 \u0628\u0647 \u0632\u0631\u062f \u0628\u0627\u0634\u062f \u0646\u0648\u0631 \u06af\u0631\u0645 \u06af\u0641\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u06af\u0631 \u062f\u0645\u0627\u06cc \u0646\u0648\u0631 \u0628\u06cc\u0646 2700 \u062a\u0627 3000 \u06a9\u0644\u0648\u06cc\u0646 \u0628\u0627\u0634\u062f \u0646\u0648\u0631 \u06af\u0631\u0645\u06cc \u062f\u0627\u0631\u062f \u0648 \u0627\u06af\u0631 \u0628\u06cc\u0646 5000 \u062a\u0627 6500 \u06a9\u0644\u0648\u06cc\u0646 \u0628\u0627\u0634\u062f \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0639\u0646\u0627\u0633\u062a \u06a9\u0647 \u0686\u0631\u0627\u063a \u0646\u0648\u0631 \u0633\u0631\u062f\u06cc \u062f\u0627\u0631\u062f. \u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc \u062e\u0637\u06cc \u06a9\u0647 \u062f\u0627\u0631\u0627\u06cc \u062f\u0645\u0627\u06cc \u0631\u0646\u06af 3500 \u062a\u0627 4500 \u06a9\u0644\u0648\u06cc\u0646 \u0647\u0633\u062a\u0646\u062f \u0646\u06cc\u0632 \u062f\u0627\u0631\u0627\u06cc \u0646\u0648\u0631 \u062e\u0646\u062b\u06cc \u0647\u0633\u062a\u0646\u062f. \u0627\u0645\u0627 \u0645\u0647\u0645 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0628\u062f\u0627\u0646\u06cc\u062f \u0647\u0631 \u0631\u0646\u06af \u0646\u0648\u0631 \u0628\u0627\u06cc\u062f \u0628\u0631\u0627\u06cc \u0686\u0647 \u0641\u0636\u0627\u06cc\u06cc \u0628\u0647 \u06a9\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0634\u0648\u062f\u061f<\/p>\n<ul>\n<li><strong>\u0646\u0648\u0631 \u06af\u0631\u0645 (\u062f\u0645\u0627\u06cc \u067e\u0627\u06cc\u06cc\u0646)<\/strong><br \/>\n\u0646\u0648\u0631 \u06af\u0631\u0645 \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0641\u0636\u0627\u0647\u0627\u06cc \u0622\u0631\u0627\u0645\u0634\u200c\u0628\u062e\u0634 \u0645\u062b\u0644 \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u06cc\u0627 \u0646\u0634\u06cc\u0645\u0646 \u0627\u0633\u062a \u0648 \u062d\u0633 \u0635\u0645\u06cc\u0645\u06cc\u062a \u0648 \u0631\u0627\u062d\u062a\u06cc \u0631\u0627 \u0628\u0647 \u0641\u0636\u0627 \u0645\u06cc\u200c\u0628\u062e\u0634\u062f.<\/li>\n<li><strong>\u0646\u0648\u0631 \u0633\u0631\u062f (\u062f\u0645\u0627\u06cc \u0628\u0627\u0644\u0627)<\/strong><br \/>\n\u0627\u06cc\u0646 \u0646\u0648\u0631 \u0628\u0631\u0627\u06cc \u0641\u0636\u0627\u0647\u0627\u06cc \u06a9\u0627\u0631\u06cc \u06cc\u0627 \u062c\u0627\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0647 \u062a\u0645\u0631\u06a9\u0632 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u06cc\u062f \u0645\u062b\u0644 \u0627\u062a\u0627\u0642 \u0645\u0637\u0627\u0644\u0639\u0647 \u06cc\u0627 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a\u061b \u0686\u0631\u0627\u06a9\u0647 \u0633\u0631\u062f\u06cc \u062f\u0645\u0627 \u062d\u0633 \u062a\u0645\u06cc\u0632\u06cc \u0648 \u0627\u0646\u0631\u0698\u06cc \u0631\u0627 \u0627\u0644\u0642\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/li>\n<\/ul>\n<h3 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D8%B7%D9%88%D9%84_%D8%B9%D9%85%D8%B1_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D9%88_%D9%85%D8%B5%D8%B1%D9%81_%D8%A7%D9%86%D8%B1%DA%98%DB%8C_%D8%A2%D9%86\"><\/span><strong>\u0637\u0648\u0644 \u0639\u0645\u0631 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0648 \u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc \u0622\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p dir=\"rtl\">\u0686\u0631\u0627\u063a\u200c\u0647\u0627 \u0641\u0642\u0637 \u0647\u0632\u06cc\u0646\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0646\u062f\u0627\u0631\u0646\u062f\u061b \u0645\u0635\u0631\u0641 \u0628\u0631\u0642 \u0648 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0622\u0646\u200c\u0647\u0627 \u0646\u06cc\u0632 \u062f\u0631 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u06a9\u0644\u06cc \u062a\u0623\u062b\u06cc\u0631 \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0631\u0646\u062f. \u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc LED \u0627\u0632 \u0627\u06cc\u0646 \u0646\u0638\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0647\u0648\u0634\u0645\u0646\u062f\u0627\u0646\u0647 \u0647\u0633\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0686\u0631\u0627\u063a\u200c\u0647\u0627 \u0627\u0646\u0631\u0698\u06cc \u06a9\u0645\u06cc \u0645\u0635\u0631\u0641 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0633\u0627\u0644\u200c\u0647\u0627 \u0628\u062f\u0648\u0646 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u062a\u0639\u0648\u06cc\u0636 \u06a9\u0627\u0631 \u06a9\u0646\u0646\u062f.<br \/>\n\u0627\u06af\u0631 \u0646\u06af\u0631\u0627\u0646 \u0642\u0628\u0636 \u0628\u0631\u0642 \u0647\u0633\u062a\u06cc\u062f \u06cc\u0627 \u0628\u0647 \u0645\u062d\u06cc\u0637\u200c\u0632\u06cc\u0633\u062a \u0627\u0647\u0645\u06cc\u062a \u0645\u06cc\u200c\u062f\u0647\u06cc\u062f \u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc LED \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0647\u0633\u062a\u0646\u062f. \u0634\u0627\u06cc\u062f \u0642\u06cc\u0645\u062a \u0686\u0631\u0627\u063a \u062e\u0637\u06cc LED \u06a9\u0645\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0628\u0627\u0634\u062f\u061b \u0627\u0645\u0627 \u062f\u0631 \u0628\u0644\u0646\u062f \u0645\u062f\u062a \u0627\u06cc\u0646 \u0647\u0632\u06cc\u0646\u0647 \u06a9\u0627\u0645\u0644\u0627\u064b \u062c\u0628\u0631\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<h3 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D9%82%D8%A7%D8%A8%D9%84%DB%8C%D8%AA_%D8%AA%D9%86%D8%B8%DB%8C%D9%85_%D9%86%D9%88%D8%B1_%D8%AF%DB%8C%D9%85%D8%B1\"><\/span><strong>\u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u0646\u0638\u06cc\u0645 \u0646\u0648\u0631 (\u062f\u06cc\u0645\u0631)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p dir=\"rtl\">\u062a\u0635\u0648\u0631 \u06a9\u0646\u06cc\u062f \u062f\u0631 \u062d\u0627\u0644 \u0645\u0637\u0627\u0644\u0639\u0647 \u0647\u0633\u062a\u06cc\u062f \u0648 \u0628\u0647 \u0646\u0648\u0631 \u0642\u0648\u06cc \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u06cc\u062f\u061b \u0627\u0645\u0627 \u0647\u0646\u06af\u0627\u0645 \u062a\u0645\u0627\u0634\u0627\u06cc \u0641\u06cc\u0644\u0645 \u0646\u0648\u0631 \u0645\u0644\u0627\u06cc\u0645\u200c\u062a\u0631\u06cc \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f. \u0627\u06cc\u0646\u062c\u0627\u0633\u062a \u06a9\u0647 \u062f\u06cc\u0645\u0631\u0647\u0627 \u0648\u0627\u0631\u062f \u0639\u0645\u0644 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc \u062e\u0637\u06cc \u0645\u062f\u0631\u0646\u06cc \u06a9\u0647 \u0627\u06cc\u0646 \u0642\u0627\u0628\u0644\u06cc\u062a \u0631\u0627 \u062f\u0627\u0631\u0646\u062f \u0628\u0647 \u0634\u0645\u0627 \u0627\u062c\u0627\u0632\u0647 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u0634\u062f\u062a \u0646\u0648\u0631 \u0631\u0627 \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0634\u0631\u0627\u06cc\u0637 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0647\u06cc\u062f.<br \/>\n\u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0646\u0647 \u062a\u0646\u0647\u0627 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0627\u0633\u062a\u061b \u0628\u0644\u06a9\u0647 \u0628\u0647 \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0628\u0631\u0642 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0639\u0645\u0631 \u0686\u0631\u0627\u063a \u0646\u06cc\u0632 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0646\u06a9\u062a\u0647 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647 \u0647\u0646\u06af\u0627\u0645 \u062e\u0631\u06cc\u062f \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0633\u0627\u0632\u06af\u0627\u0631\u06cc \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0628\u0627 \u062f\u06cc\u0645\u0631 \u062f\u0642\u062a \u06a9\u0646\u06cc\u062f.<\/p>\n<p dir=\"rtl\"><img decoding=\"async\" src=\"https:\/\/cdn.triboon.net\/media\/reportage_images\/4bc207f5-ebf5-4129-a17f-3ca316aa354a.jpg\" alt=\"\u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u062a\u0648\u06a9\u0627\u0631 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u06a9\u0627\u0631\" \/><\/p>\n<h3 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%82%D8%A7%D9%88%D9%85%D8%AA_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D8%AF%D8%B1_%D8%A8%D8%B1%D8%A7%D8%A8%D8%B1_%D8%A2%D8%A8_%D9%88_%DA%AF%D8%B1%D8%AF%D9%88%D8%BA%D8%A8%D8%A7%D8%B1\"><\/span><strong>\u0645\u0642\u0627\u0648\u0645\u062a \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0622\u0628 \u0648 \u06af\u0631\u062f\u0648\u063a\u0628\u0627\u0631<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p dir=\"rtl\">\u0627\u06af\u0631 \u0642\u0635\u062f \u062f\u0627\u0631\u06cc\u062f \u0627\u0632 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u062f\u0631 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u062e\u0627\u0631\u062c\u06cc \u0645\u062b\u0644 \u062d\u06cc\u0627\u0637 \u06cc\u0627 \u0645\u06a9\u0627\u0646\u200c\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0634\u0631\u0627\u06cc\u0637 \u0633\u062e\u062a \u0645\u0627\u0646\u0646\u062f \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0635\u0646\u0639\u062a\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u062d\u062a\u0645\u0627\u064b \u0628\u0647 \u0645\u0642\u0627\u0648\u0645\u062a \u0622\u0646 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0622\u0628 \u0648 \u06af\u0631\u062f\u0648\u063a\u0628\u0627\u0631 \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u06a9\u0647 \u0628\u0627 \u062f\u0631\u062c\u0647 \u062d\u0641\u0627\u0638\u062a \u06cc\u0627 IP \u0645\u0634\u062e\u0635 \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0636\u0645\u06cc\u0646 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0686\u0631\u0627\u063a \u0634\u0645\u0627 \u062f\u0648\u0627\u0645 \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u0648 \u062f\u0631 \u0647\u0631 \u0634\u0631\u0627\u06cc\u0637\u06cc \u0628\u0647\u200c\u062e\u0648\u0628\u06cc \u0639\u0645\u0644 \u06a9\u0646\u062f. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644 \u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc\u06cc \u0628\u0627 IP65 \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u0628\u0627\u0632 \u0647\u0633\u062a\u0646\u062f\u061b \u0632\u06cc\u0631\u0627 \u06a9\u0627\u0645\u0644\u0627\u064b \u0636\u062f\u0622\u0628\u200c\u0627\u0646\u062f \u0648 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u06af\u0631\u062f\u0648\u063a\u0628\u0627\u0631 \u0646\u06cc\u0632 \u0622\u0633\u06cc\u0628 \u0646\u0645\u06cc\u200c\u0628\u06cc\u0646\u0646\u062f.<\/p>\n<h2 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D8%B1%D8%A7%D9%87%D9%86%D9%85%D8%A7%DB%8C_%D8%AE%D8%B1%DB%8C%D8%AF_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C%D8%9B_%D9%86%DA%A9%D8%A7%D8%AA_%D9%85%D9%87%D9%85\"><\/span><strong>\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0686\u0631\u0627\u063a \u062e\u0637\u06cc\u061b \u0646\u06a9\u0627\u062a \u0645\u0647\u0645<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p dir=\"rtl\">\u0648\u0642\u062a\u06cc \u062a\u0635\u0645\u06cc\u0645 \u0628\u0647 \u0646\u0635\u0628 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u062f\u0631 \u06cc\u06a9 \u0645\u062d\u06cc\u0637 \u0645\u06cc\u200c\u06af\u06cc\u0631\u06cc\u062f \u062d\u062a\u0645\u0627\u064b \u0628\u0627\u06cc\u062f \u0628\u0647 \u0627\u06cc\u0646 \u0686\u0646\u062f \u0645\u0648\u0631\u062f \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f\u060c \u0686\u0631\u0627\u06a9\u0647 \u062e\u0631\u06cc\u062f \u0686\u0631\u0627\u063a \u062e\u0637\u06cc\u0650 \u0627\u0634\u062a\u0628\u0627\u0647\u060c \u0646\u062a\u06cc\u062c\u0647 \u0646\u0627\u0645\u0637\u0644\u0648\u0628\u06cc \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a:<\/p>\n<h3 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D9%86%DA%A9%D8%A7%D8%AA_%D9%85%D9%87%D9%85_%D9%82%D8%A8%D9%84_%D8%A7%D8%B2_%D8%AE%D8%B1%DB%8C%D8%AF_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C\"><\/span><strong>\u0646\u06a9\u0627\u062a \u0645\u0647\u0645 \u0642\u0628\u0644 \u0627\u0632 \u062e\u0631\u06cc\u062f \u0686\u0631\u0627\u063a \u062e\u0637\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p dir=\"rtl\">\u062d\u062a\u0645\u0627\u064b \u067e\u06cc\u0634 \u0627\u0632 \u062e\u0631\u06cc\u062f \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0641\u0636\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u0645\u0634\u062e\u0635 \u06a9\u0646\u06cc\u062f. \u0647\u0645\u0627\u0646\u200c\u0637\u0648\u0631 \u06a9\u0647 \u06af\u0641\u062a\u06cc\u0645 \u0628\u0631\u0631\u0633\u06cc \u0634\u062f\u062a \u0646\u0648\u0631\u060c \u062f\u0645\u0627\u06cc \u0631\u0646\u06af \u0648 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0641\u0646\u06cc \u0645\u0627\u0646\u0646\u062f \u062f\u06cc\u0645\u0631 \u0648 \u0645\u0642\u0627\u0648\u0645\u062a \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0639\u0648\u0627\u0645\u0644 \u0645\u062d\u06cc\u0637\u06cc \u0627\u0632 \u0627\u0648\u0644\u0648\u06cc\u062a\u200c\u0647\u0627 \u0647\u0633\u062a\u0646\u062f.<\/p>\n<h3 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D8%A8%D8%B1%D8%B1%D8%B3%DB%8C_%DA%AF%D8%A7%D8%B1%D8%A7%D9%86%D8%AA%DB%8C_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D9%88_%D8%AE%D8%AF%D9%85%D8%A7%D8%AA_%D9%BE%D8%B3_%D8%A7%D8%B2_%D9%81%D8%B1%D9%88%D8%B4\"><\/span><strong>\u0628\u0631\u0631\u0633\u06cc \u06af\u0627\u0631\u0627\u0646\u062a\u06cc \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0648 \u062e\u062f\u0645\u0627\u062a \u067e\u0633 \u0627\u0632 \u0641\u0631\u0648\u0634<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p dir=\"rtl\">\u0628\u0647\u062a\u0631\u06cc\u0646 \u0628\u0631\u0646\u062f \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0628\u0631\u0646\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 \u06af\u0627\u0631\u0627\u0646\u062a\u06cc \u0645\u0639\u062a\u0628\u0631 \u0648 \u062e\u062f\u0645\u0627\u062a \u067e\u0633 \u0627\u0632 \u0641\u0631\u0648\u0634 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f\u061b \u0686\u0631\u0627\u06a9\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u062e\u06cc\u0627\u0644 \u0634\u0645\u0627 \u0631\u0627 \u0627\u0632 \u0628\u0627\u0628\u062a \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0631\u0627\u062d\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h3 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87_%D9%82%DB%8C%D9%85%D8%AA_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C_%D8%AF%D8%B1_%D9%81%D8%B1%D9%88%D8%B4%DA%AF%D8%A7%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%85%D8%AE%D8%AA%D9%84%D9%81\"><\/span><strong>\u0645\u0642\u0627\u06cc\u0633\u0647 \u0642\u06cc\u0645\u062a \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u062f\u0631 \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p dir=\"rtl\">\u0628\u0631\u0627\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0646 \u0628\u0647\u062a\u0631\u06cc\u0646 <a href=\"https:\/\/partonoortoos.com\/product-category\/linear-light\/\" target=\"_blank\" rel=\"follow noopener\"><strong>\u0642\u06cc\u0645\u062a \u0686\u0631\u0627\u063a \u062e\u0637\u06cc<\/strong><\/a> \u062a\u0648\u0635\u06cc\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u0627\u0632 \u0686\u0646\u062f\u06cc\u0646 \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0645\u062e\u062a\u0644\u0641 \u0628\u0627\u0632\u062f\u06cc\u062f \u06a9\u0646\u06cc\u062f \u0648 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0631\u0627 \u0628\u0627 \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0645\u0642\u0627\u06cc\u0633\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<p dir=\"rtl\"><img decoding=\"async\" src=\"https:\/\/cdn.triboon.net\/media\/reportage_images\/5cc09529-66c8-4b57-98c4-d88ff03480b6.jpg\" alt=\"\u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u062a\u0648\u06a9\u0627\u0631 \u062f\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\" \/><\/p>\n<h2 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D9%86%D8%B5%D8%A8_%D9%88_%D9%86%DA%AF%D9%87%D8%AF%D8%A7%D8%B1%DB%8C_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C\"><\/span><strong>\u0646\u0635\u0628 \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0686\u0631\u0627\u063a \u062e\u0637\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p dir=\"rtl\">\u0628\u0631\u0627\u06cc \u0646\u0635\u0628 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc\u060c \u0627\u0628\u062a\u062f\u0627 \u0645\u06a9\u0627\u0646 \u0645\u0646\u0627\u0633\u0628\u06cc \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0646\u0648\u0631 \u0628\u0647 \u0637\u0648\u0631 \u06cc\u06a9\u0646\u0648\u0627\u062e\u062a \u067e\u062e\u0634 \u0634\u0648\u062f. \u0642\u0628\u0644 \u0627\u0632 \u0634\u0631\u0648\u0639\u060c \u062f\u0633\u062a\u0648\u0631\u0627\u0644\u0639\u0645\u0644\u200c\u0647\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u0647 \u0631\u0627 \u0628\u0627 \u062f\u0642\u062a \u0645\u0637\u0627\u0644\u0639\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0627\u0632 \u0627\u0628\u0632\u0627\u0631 \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u06cc\u0645\u0646\u06cc \u0631\u0627 \u0628\u0627 \u0628\u0631\u0631\u0633\u06cc \u0627\u062a\u0635\u0627\u0644\u0627\u062a \u0628\u0631\u0642\u06cc \u0628\u0631\u0631\u0633\u06cc \u06a9\u0646\u06cc\u062f. \u067e\u0633 \u0627\u0632 \u0646\u0635\u0628\u060c \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0639\u0645\u0631 \u0686\u0631\u0627\u063a\u060c \u0628\u0647 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0622\u0646 \u062a\u0648\u062c\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u061b \u0628\u0647 \u0637\u0648\u0631 \u062f\u0648\u0631\u0647\u200c\u0627\u06cc \u0633\u0637\u062d \u0686\u0631\u0627\u063a\u200c\u0647\u0627 \u0631\u0627 \u062a\u0645\u06cc\u0632 \u06a9\u0646\u06cc\u062f \u0648 \u0633\u0644\u0627\u0645\u062a \u0633\u06cc\u0645\u200c\u06a9\u0634\u06cc \u0648 \u0642\u0637\u0639\u0627\u062a \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0627\u0632 \u0628\u0631\u0648\u0632 \u0645\u0634\u06a9\u0644\u0627\u062a \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0634\u0648\u062f.<\/p>\n<h2 dir=\"rtl\"><span class=\"ez-toc-section\" id=\"%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C_%D8%B1%D8%A7%D9%87%D9%86%D9%85%D8%A7%DB%8C_%D8%AE%D8%B1%DB%8C%D8%AF_%DA%86%D8%B1%D8%A7%D8%BA_%D8%AE%D8%B7%DB%8C\"><\/span><strong>\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc \u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0686\u0631\u0627\u063a \u062e\u0637\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p dir=\"rtl\">\u0627\u0646\u062a\u062e\u0627\u0628 \u0648 \u062e\u0631\u06cc\u062f \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u0645\u0646\u0627\u0633\u0628 \u0646\u06cc\u0627\u0632\u0645\u0646\u062f \u062a\u0648\u062c\u0647 \u0628\u0647 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0641\u0636\u0627\u060c \u0628\u0648\u062f\u062c\u0647 \u0648 \u0633\u0644\u06cc\u0642\u0647 \u0634\u062e\u0635\u06cc \u0627\u0633\u062a. \u0628\u0627 \u0645\u0642\u0627\u06cc\u0633\u0647 \u06a9\u06cc\u0641\u06cc\u062a\u060c \u0642\u06cc\u0645\u062a \u0648 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0641\u0646\u06cc\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0631\u0646\u062f \u0645\u0639\u062a\u0628\u0631 \u0648 \u0631\u0639\u0627\u06cc\u062a \u0646\u06a9\u0627\u062a \u0646\u0635\u0628 \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0628\u0647 \u0634\u0645\u0627 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0627\u0632 \u062e\u0631\u06cc\u062f \u062e\u0648\u062f \u0631\u0627\u0636\u06cc \u062e\u0648\u0627\u0647\u06cc\u062f \u0628\u0648\u062f. \u0628\u0627 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0631\u062f\u0646 \u0646\u06a9\u0627\u062a \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u062e\u0631\u06cc\u062f\u06cc \u0647\u0648\u0634\u0645\u0646\u062f\u0627\u0646\u0647 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u06cc\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0632 \u0632\u0645\u0627\u0646 \u0627\u062e\u062a\u0631\u0627\u0639 \u0644\u0627\u0645\u067e \u062a\u0648\u0633\u0637 \u062a\u0648\u0645\u0627\u0633 \u0627\u062f\u06cc\u0633\u0648\u0646\u060c \u0644\u0627\u0645\u067e\u200c\u0647\u0627 \u0628\u0647 \u0627\u0628\u0632\u0627\u0631 \u0636\u0631\u0648\u0631\u06cc \u0628\u0631\u0627\u06cc \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647\u200c\u0627\u0646\u062f. \u0627\u0645\u0631\u0648\u0632\u0647\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u0644\u0627\u0645\u067e\u200c\u0647\u0627 \u0646\u06cc\u0627\u0632\u0645\u0646\u062f \u062f\u0642\u062a \u0648 \u0633\u0644\u06cc\u0642\u0647 \u0627\u0633\u062a\u060c \u0632\u06cc\u0631\u0627 \u0622\u0646\u200c\u0647\u0627 \u0646\u0642\u0634 \u0645\u0647\u0645\u06cc \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0627\u06cc\u0641\u0627 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0631\u0648\u0646\u062f \u0637\u0631\u0627\u062d\u06cc \u0645\u06cc\u0646\u06cc\u0645\u0627\u0644\u06cc\u0633\u062a\u06cc\u060c \u0686\u0631\u0627\u063a\u200c\u0647\u0627\u06cc \u062e\u0637\u06cc \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0641\u0636\u0627\u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0634\u0646\u0627\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0646\u062d\u0648\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0627\u0632 \u0686\u0631\u0627\u063a \u062e\u0637\u06cc \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0647\u0633\u062a\u06cc\u062f\u060c \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u0646\u062f\u0647\u06cc\u062f.<\/p>\n","protected":false},"author":3,"featured_media":48998,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[678],"tags":[702,704,703,49],"class_list":["post-48997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-678","tag-702","tag-704","tag-703","tag-49"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/48997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=48997"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/48997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/48998"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=48997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=48997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=48997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}