{"id":46095,"date":"2024-09-11T13:28:11","date_gmt":"2024-09-11T09:58:11","guid":{"rendered":"https:\/\/decorshop.ir\/mag\/?p=46095"},"modified":"2024-09-11T13:28:11","modified_gmt":"2024-09-11T09:58:11","slug":"%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/","title":{"rendered":"\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647 \u0648 \u062e\u0648\u0634\u0645\u0632\u0647 | 5 \u0631\u0633\u067e\u06cc \u062c\u0630\u0627\u0628 | \u0641\u0642\u0637 150 \u06a9\u0627\u0644\u0631\u06cc"},"content":{"rendered":"<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0645\u062d\u0628\u0648\u0628 \u062a\u0631\u06cc\u0646 \u0648 \u062e\u0648\u0634\u0645\u0632\u0647 \u062a\u0631\u06cc\u0646 \u063a\u0630\u0627\u0647\u0627\u06cc \u0641\u0633\u062a \u0641\u0648\u062f \u06a9\u0647 \u0622\u0645\u0627\u062f\u0647 \u06a9\u0631\u062f\u0646 \u0622\u0646 \u0632\u0645\u0627\u0646 \u0632\u06cc\u0627\u062f\u06cc \u0646\u0645\u06cc \u0628\u0631\u062f\u060c <a href=\"\/mag\/\u0637\u0631\u0632-\u062a\u0647\u06cc\u0647-\u0627\u0633\u0646\u06a9-\u0633\u0627\u062f\u0647-\u0648-\u062e\u0648\u0634\u0645\u0632\u0647\"><strong>\u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647<\/strong><\/a> \u0627\u0633\u062a. \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0644\u06cc \u0627\u0633\u0646\u06a9 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u06cc\u0627\u0646 \u0648\u0639\u062f\u0647 \u0647\u0627\u06cc \u067e\u0631\u0637\u0631\u0641\u062f\u0627\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646 \u062f\u0631 \u06a9\u0645\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0645\u0645\u06a9\u0646 \u0628\u0627 \u062a\u0631\u06a9\u06cc\u0628 \u0645\u0648\u0627\u062f \u0645\u062e\u062a\u0644\u0641 \u0622\u0646 \u0631\u0627 \u062a\u0647\u06cc\u0647 \u06a9\u0631\u062f. \u0627\u06cc\u0646 \u0641\u0633\u062a \u0641\u0648\u062f \u062e\u0648\u0634\u0645\u0632\u0647 \u0631\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0637\u0628\u0642 \u0633\u0644\u06cc\u0642\u0647 \u0648 \u0630\u0627\u0626\u0642\u0647 \u062e\u0648\u062f \u0628\u0627 \u0645\u0648\u0627\u062f \u0645\u062e\u0644\u0641\u06cc \u0645\u0627\u0646\u0646\u062f \u0645\u0631\u063a\u060c \u06a9\u0627\u0644\u0628\u0627\u0633\u060c \u06af\u0648\u0634\u062a \u0648 &#8230; \u062e\u06cc\u0644\u06cc \u0633\u0631\u06cc\u0639 \u062f\u0631\u0633\u062a \u06a9\u0646\u06cc\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u06cc\u0646 \u0645\u06cc\u0627\u0646 \u0648\u0639\u062f\u0647 \u0633\u0627\u062f\u0647\u00a0 \u0648 \u0645\u0631\u0627\u062d\u0644 \u062a\u0647\u06cc\u0647 \u0622\u0646 \u0631\u0627 \u062a\u0648\u0636\u06cc\u062d \u0645\u06cc \u062f\u0647\u06cc\u0645.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D9%85%D9%88%D8%A7%D8%AF_%D9%84%D8%A7%D8%B2%D9%85_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%D8%B3%D8%A7%D8%AF%D9%87_%D8%A8%D8%A7_%DA%98%D8%A7%D9%85%D8%A8%D9%88%D9%86\" >\u0645\u0648\u0627\u062f \u0644\u0627\u0632\u0645 \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647 \u0628\u0627 \u0698\u0627\u0645\u0628\u0648\u0646<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D9%85%D8%B1%D8%A7%D8%AD%D9%84_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%DA%98%D8%A7%D9%85%D8%A8%D9%88%D9%86\" >\u0645\u0631\u0627\u062d\u0644 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0698\u0627\u0645\u0628\u0648\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%A7%D8%B3%D9%86%DA%A9_%DB%8C%DA%A9_%D9%85%DB%8C%D8%A7%D9%86_%D9%88%D8%B9%D8%AF%D9%87_%D8%AE%D9%88%D8%B4%D9%85%D8%B2%D9%87_%D9%88_%D8%B9%D8%A7%D9%84%DB%8C\" >\u0627\u0633\u0646\u06a9 \u06cc\u06a9 \u0645\u06cc\u0627\u0646 \u0648\u0639\u062f\u0647 \u062e\u0648\u0634\u0645\u0632\u0647 \u0648 \u0639\u0627\u0644\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%A7%D8%B3%D9%86%DA%A9_%D8%B3%D8%A7%D8%AF%D9%87_%D9%88_%D9%BE%D9%86%DB%8C%D8%B1%DB%8C\" >\u0627\u0646\u0648\u0627\u0639 \u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647 \u0648 \u067e\u0646\u06cc\u0631\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%D9%85%D8%B1%D8%BA_%D9%88_%D9%82%D8%A7%D8%B1%DA%86_%D8%B1%DA%98%DB%8C%D9%85%DB%8C_%D9%81%D9%82%D8%B7_150_%DA%A9%D8%A7%D9%84%D8%B1%DB%8C\" >\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686 \u0631\u0698\u06cc\u0645\u06cc | \u0641\u0642\u0637 150 \u06a9\u0627\u0644\u0631\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%A7%D8%B3%D9%86%DA%A9_%D9%85%D8%B1%D8%BA_%D9%88_%D9%82%D8%A7%D8%B1%DA%86%D8%8C_%DB%8C%DA%A9_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D9%81%D9%88%D9%82%E2%80%8C%D8%A7%D9%84%D8%B9%D8%A7%D8%AF%D9%87\" >\u0627\u0633\u0646\u06a9 \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686\u060c \u06cc\u06a9 \u0627\u0646\u062a\u062e\u0627\u0628 \u0641\u0648\u0642\u200c\u0627\u0644\u0639\u0627\u062f\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D9%85%D9%88%D8%A7%D8%AF_%D9%84%D8%A7%D8%B2%D9%85_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%D9%85%D8%B1%D8%BA_%D9%88_%D9%82%D8%A7%D8%B1%DA%86\" >\u0645\u0648\u0627\u062f \u0644\u0627\u0632\u0645 \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%D9%85%D8%B1%D8%BA_%D9%88_%D9%82%D8%A7%D8%B1%DA%86\" >\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%D8%AA%D8%BA%D8%B0%DB%8C%D9%87%E2%80%8C%D8%A7%DB%8C_%D8%A7%D8%B3%D9%86%DA%A9_%D9%82%D8%A7%D8%B1%DA%86_%D9%88_%D9%85%D8%B1%D8%BA\" >\u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062a\u063a\u0630\u06cc\u0647\u200c\u0627\u06cc \u0627\u0633\u0646\u06a9 \u0642\u0627\u0631\u0686 \u0648 \u0645\u0631\u063a<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%DB%8C_%D8%A7%D8%B3%D9%86%DA%A9_%D8%B1%DA%98%DB%8C%D9%85%DB%8C_%D9%81%D9%88%D9%82_%D8%A7%D9%84%D8%B9%D8%A7%D8%AF%D9%87_%D8%AE%D9%88%D8%B4%D9%85%D8%B2%D9%87\" >\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u06cc \u0627\u0633\u0646\u06a9 \u0631\u0698\u06cc\u0645\u06cc \u0641\u0648\u0642 \u0627\u0644\u0639\u0627\u062f\u0647 \u062e\u0648\u0634\u0645\u0632\u0647<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D9%85%D9%88%D8%A7%D8%AF_%D9%84%D8%A7%D8%B2%D9%85_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%D8%B1%DA%98%DB%8C%D9%85%DB%8C\" >\u0645\u0648\u0627\u062f \u0644\u0627\u0632\u0645 \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0631\u0698\u06cc\u0645\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%D8%B1%DA%98%DB%8C%D9%85%DB%8C\" >\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0631\u0698\u06cc\u0645\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%D8%AA%D8%BA%D8%B0%DB%8C%D9%87%E2%80%8C%D8%A7%DB%8C_%D8%A7%D8%B3%D9%86%DA%A9_%D8%B1%DA%98%DB%8C%D9%85%DB%8C\" >\u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062a\u063a\u0630\u06cc\u0647\u200c\u0627\u06cc \u0627\u0633\u0646\u06a9 \u0631\u0698\u06cc\u0645\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%A7%D8%B3%D9%86%DA%A9_%D8%B3%D8%A7%D8%AF%D9%87_%D8%A8%D8%A7_%DA%AF%D9%88%D8%B4%D8%AA_%DA%86%D8%B1%D8%AE_%DA%A9%D8%B1%D8%AF%D9%87_%D8%AE%D9%88%D8%B4%D9%85%D8%B2%D9%87_%D8%AF%D8%B1_5_%D9%85%D8%B1%D8%AD%D9%84%D9%87\" >\u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647 \u0628\u0627 \u06af\u0648\u0634\u062a \u0686\u0631\u062e \u06a9\u0631\u062f\u0647 \u062e\u0648\u0634\u0645\u0632\u0647 \u062f\u0631 5 \u0645\u0631\u062d\u0644\u0647<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%DA%AF%D9%88%D8%B4%D8%AA_%DA%86%D8%B1%D8%AE%E2%80%8C%DA%A9%D8%B1%D8%AF%D9%87_%D8%A8%D9%87_%DB%B2_%D8%B1%D9%88%D8%B4\" >\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647 \u0628\u0647 \u06f2 \u0631\u0648\u0634<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D9%85%D9%88%D8%A7%D8%AF_%D9%84%D8%A7%D8%B2%D9%85_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%DA%AF%D9%88%D8%B4%D8%AA_%DA%86%D8%B1%D8%AE%E2%80%8C%DA%A9%D8%B1%D8%AF%D9%87\" >\u0645\u0648\u0627\u062f \u0644\u0627\u0632\u0645 \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%DA%AF%D9%88%D8%B4%D8%AA_%DA%86%D8%B1%D8%AE%E2%80%8C%DA%A9%D8%B1%D8%AF%D9%87_%D8%B1%D9%88%D8%B4_%D8%A7%D9%88%D9%84\" >\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647 (\u0631\u0648\u0634 \u0627\u0648\u0644)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%DA%AF%D9%88%D8%B4%D8%AA_%DA%86%D8%B1%D8%AE%E2%80%8C%DA%A9%D8%B1%D8%AF%D9%87_%D8%B1%D9%88%D8%B4_%D8%AF%D9%88%D9%85\" >\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647 (\u0631\u0648\u0634 \u062f\u0648\u0645)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D9%86%DA%A9%D8%A7%D8%AA_%D9%85%D9%87%D9%85_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%DA%AF%D9%88%D8%B4%D8%AA_%DA%86%D8%B1%D8%AE%E2%80%8C%DA%A9%D8%B1%D8%AF%D9%87\" >\u0646\u06a9\u0627\u062a \u0645\u0647\u0645 \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%b2-%d8%aa%d9%87%db%8c%d9%87-%d8%a7%d8%b3%d9%86%da%a9-%d8%b3%d8%a7%d8%af%d9%87-%d9%88-%d8%ae%d9%88%d8%b4%d9%85%d8%b2%d9%87-5-%d8%b1%d8%b3%d9%be%db%8c-%d8%ac%d8%b0%d8%a7%d8%a8-%d9%81\/#%D8%AC%D9%85%D8%B9_%D8%A8%D9%86%D8%AF%DB%8C\" >\u062c\u0645\u0639 \u0628\u0646\u062f\u06cc<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D9%85%D9%88%D8%A7%D8%AF_%D9%84%D8%A7%D8%B2%D9%85_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%D8%B3%D8%A7%D8%AF%D9%87_%D8%A8%D8%A7_%DA%98%D8%A7%D9%85%D8%A8%D9%88%D9%86\"><\/span>\u0645\u0648\u0627\u062f \u0644\u0627\u0632\u0645 \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647 \u0628\u0627 \u0698\u0627\u0645\u0628\u0648\u0646<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0647\u0645\u0627\u0646 \u0637\u0648\u0631 \u06a9\u0647 \u0627\u0634\u0627\u0631\u0647 \u0634\u062f\u060c \u0628\u0631\u0627\u06cc \u062f\u0631\u0633\u062a \u06a9\u0631\u062f\u0646 \u06cc\u06a9 <strong>\u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647<\/strong> \u0648 \u062e\u0648\u0634\u0645\u0632\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647 \u0628\u0627 \u0698\u0627\u0645\u0628\u0648\u0646\u060c \u063a\u0630\u0627\u06cc\u06cc \u0633\u0627\u062f\u0647 \u0648 \u062e\u0648\u0634 \u0637\u0639\u0645 \u0627\u0633\u062a \u0648 \u0628\u0631\u0627\u06cc \u067e\u0630\u06cc\u0631\u0627\u06cc\u06cc \u0627\u0632 \u0645\u0647\u0645\u0627\u0646\u0627\u0646 \u062f\u0631 \u062c\u0634\u0646 \u0647\u0627\u06cc \u06a9\u0648\u0686\u06a9 \u06af\u0632\u06cc\u0646\u0647 \u0627\u06cc \u0639\u0627\u0644\u06cc \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc \u0634\u0648\u062f. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0645\u0648\u0627\u062f \u0644\u0627\u0632\u0645 \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u06cc\u06a9 \u0627\u0633\u0646\u06a9 \u062e\u0648\u0634 \u0637\u0639\u0645 \u0631\u0627 \u0645\u0639\u0631\u0641\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u0645.<\/p>\n<ul>\n<li>\u0698\u0627\u0645\u0628\u0648\u0646 \u06af\u0648\u0634\u062a \u06cc\u0627 \u0645\u0631\u063a<\/li>\n<li>\u0646\u0627\u0646 \u062a\u0633\u062a<\/li>\n<li>\u0642\u0627\u0631\u0686<\/li>\n<li>\u067e\u0646\u06cc\u0631 \u067e\u06cc\u062a\u0632\u0627<\/li>\n<li>\u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647 \u0627\u06cc<\/li>\n<li>\u0646\u0645\u06a9<\/li>\n<li>\u0641\u0644\u0641\u0644<\/li>\n<li>\u0622\u0648\u06cc\u0634\u0646<\/li>\n<li>\u0630\u0631\u062a \u067e\u062e\u062a\u0647 \u06cc\u0627 \u06a9\u0646\u0633\u0631\u0648\u06cc<\/li>\n<li>\u06af\u06cc\u0634\u0646\u06cc\u0632\u060c \u062c\u0639\u0641\u0631\u06cc \u0648 \u067e\u06cc\u0627\u0632\u0686\u0647 ( \u062f\u0644\u062e\u0648\u0627\u0647)<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-46096\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0637\u0631\u0632-\u062a\u0647\u06cc\u0647-\u0627\u0633\u0646\u06a9-\u0633\u0627\u062f\u0647-\u0648-\u062e\u0648\u0634\u0645\u0632\u0647-\u0628\u0627-\u0698\u0627\u0645\u0628\u0648\u0646.webp\" alt=\"\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647 \u0648 \u062e\u0648\u0634\u0645\u0632\u0647 \u0628\u0627 \u0698\u0627\u0645\u0628\u0648\u0646\" width=\"459\" height=\"459\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0637\u0631\u0632-\u062a\u0647\u06cc\u0647-\u0627\u0633\u0646\u06a9-\u0633\u0627\u062f\u0647-\u0648-\u062e\u0648\u0634\u0645\u0632\u0647-\u0628\u0627-\u0698\u0627\u0645\u0628\u0648\u0646.webp 459w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0637\u0631\u0632-\u062a\u0647\u06cc\u0647-\u0627\u0633\u0646\u06a9-\u0633\u0627\u062f\u0647-\u0648-\u062e\u0648\u0634\u0645\u0632\u0647-\u0628\u0627-\u0698\u0627\u0645\u0628\u0648\u0646-300x300.webp 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0637\u0631\u0632-\u062a\u0647\u06cc\u0647-\u0627\u0633\u0646\u06a9-\u0633\u0627\u062f\u0647-\u0648-\u062e\u0648\u0634\u0645\u0632\u0647-\u0628\u0627-\u0698\u0627\u0645\u0628\u0648\u0646-150x150.webp 150w\" sizes=\"auto, (max-width: 459px) 100vw, 459px\" \/><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"390\"><strong>\u0645\u0648\u0627\u062f \u0644\u0627\u0632\u0645<\/strong><\/td>\n<td width=\"390\"><strong>\u0645\u0642\u062f\u0627\u0631 \u0645\u0648\u0627\u062f \u0627\u0648\u0644\u06cc\u0647<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"390\">\u0698\u0627\u0645\u0628\u0648\u0646<\/td>\n<td width=\"390\">250 \u06af\u0631\u0645<\/td>\n<\/tr>\n<tr>\n<td width=\"390\">\u0642\u0627\u0631\u0686<\/td>\n<td width=\"390\">250 \u06af\u0631\u0645<\/td>\n<\/tr>\n<tr>\n<td width=\"390\">\u067e\u0646\u06cc\u0631 \u067e\u06cc\u062a\u0632\u0627<\/td>\n<td width=\"390\">150 \u06af\u0631\u0645<\/td>\n<\/tr>\n<tr>\n<td width=\"390\">\u0630\u0631\u062a \u067e\u062e\u062a\u0647 \u0634\u062f\u0647 \u06cc\u0627 \u06a9\u0646\u0633\u0631\u0648\u06cc<\/td>\n<td width=\"390\">\u0628\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0644\u0627\u0632\u0645<\/td>\n<\/tr>\n<tr>\n<td width=\"390\">\u0646\u0627\u0646 \u062a\u0633\u062a<\/td>\n<td width=\"390\">\u06cc\u06a9 \u0628\u0633\u062a\u0647<\/td>\n<\/tr>\n<tr>\n<td width=\"390\">\u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647\u200c\u0627\u06cc<\/td>\n<td width=\"390\">150 \u06af\u0631\u0645<\/td>\n<\/tr>\n<tr>\n<td width=\"390\">\u0646\u0645\u06a9<\/td>\n<td width=\"390\">\u0628\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0644\u0627\u0632\u0645<\/td>\n<\/tr>\n<tr>\n<td width=\"390\">\u0622\u0648\u06cc\u0634\u0646<\/td>\n<td width=\"390\">\u0628\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0644\u0627\u0632\u0645<\/td>\n<\/tr>\n<tr>\n<td width=\"390\">\u0641\u0644\u0641\u0644 \u0633\u06cc\u0627\u0647<\/td>\n<td width=\"390\">\u0628\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0644\u0627\u0632\u0645<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D8%B1%D8%A7%D8%AD%D9%84_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%DA%98%D8%A7%D9%85%D8%A8%D9%88%D9%86\"><\/span>\u0645\u0631\u0627\u062d\u0644 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0698\u0627\u0645\u0628\u0648\u0646<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 <strong>\u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647<\/strong> \u0628\u0627 \u0698\u0627\u0645\u0628\u0648\u0646 \u0628\u0647 \u062f\u0633\u062a\u06af\u0627\u0647 \u0633\u0627\u0646\u062f\u0648\u06cc\u0686 \u0633\u0627\u0632 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u06cc\u062f. \u0642\u0628\u0644 \u0627\u0632 \u06af\u0630\u0627\u0634\u062a\u0646 \u0627\u0633\u0646\u06a9 \u0647\u0627 \u062f\u0631 \u062f\u0633\u062a\u06af\u0627\u0647 \u0628\u0627\u06cc\u062f \u062f\u0633\u062a\u06af\u0627\u0647 \u0631\u0627 \u0631\u0648\u0634\u0646 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u06af\u0631\u0645 \u0634\u0648\u062f. \u0627\u0628\u062a\u062f\u0627 \u0628\u0627\u06cc\u062f \u0698\u0627\u0645\u0628\u0648\u0646 \u0647\u0627\u060c \u0642\u0627\u0631\u0686 \u0647\u0627 \u0648 \u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647 \u0627\u06cc \u0631\u0627 \u0628\u0647 \u0642\u0637\u0639\u0627\u062a \u0631\u06cc\u0632 \u062e\u0631\u062f \u06a9\u0646\u06cc\u062f. \u0633\u067e\u0633 \u062f\u0631 \u06cc\u06a9 \u0645\u0627\u0647\u06cc \u062a\u0627\u0628\u0647 \u06a9\u0645\u06cc \u0631\u0648\u063a\u06cc \u0628\u0631\u06cc\u0632\u06cc\u062f \u0648 \u0642\u0627\u0631\u0686 \u0647\u0627 \u0631\u0627 \u0628\u0627 \u062d\u0631\u0627\u0631\u062a \u0632\u06cc\u0627\u062f \u062a\u0641\u062a \u062f\u0647\u06cc\u062f \u062a\u0627 \u0622\u0628 \u0622\u0646 \u06af\u0631\u0641\u062a\u0647 \u0634\u0648\u062f. \u062f\u0631 \u0645\u0631\u062d\u0644\u0647 \u0628\u0639\u062f\u06cc\u060c \u0698\u0627\u0645\u0628\u0648\u0646 \u0647\u0627\u06cc \u062e\u0631\u062f \u0634\u062f\u0647\u060c \u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647 \u0627\u06cc \u0648 \u0630\u0631\u062a \u0631\u0627 \u0628\u0647 \u0642\u0627\u0631\u0686 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0628\u0639\u062f \u06a9\u0645\u06cc \u0646\u0645\u06a9 \u0648 \u0641\u0644\u0641\u0644 \u0628\u0647 \u0645\u0648\u0627\u062f \u0628\u0632\u0646\u06cc\u062f. \u0628\u0639\u062f \u0627\u0632 \u062e\u0646\u06a9 \u0634\u062f\u0646 \u0645\u0648\u0627\u062f \u0628\u0647 \u06a9\u0641 \u0633\u0627\u0646\u062f\u0648\u06cc\u0686 \u0633\u0627\u0632 \u06a9\u0647 \u0627\u0632 \u0642\u0628\u0644 \u0631\u0648\u0634\u0646 \u06a9\u0631\u062f\u06cc\u0645 \u06a9\u0645\u06cc \u0631\u0648\u063a\u0646 \u0645\u06cc \u0632\u0646\u06cc\u0645 .<\/p>\n<p>\u062f\u0631 \u0645\u0631\u062d\u0644\u0647 \u0628\u0639\u062f\u06cc \u0646\u0627\u0646 \u062a\u0633\u062a \u0631\u0627 \u0631\u0648\u06cc \u0635\u0641\u062d\u0647 \u0633\u0627\u0646\u062f\u0648\u06cc\u0686 \u0633\u0627\u0632 \u0645\u06cc \u06af\u0630\u0627\u0631\u06cc\u0645 \u0648 \u0628\u0639\u062f \u0627\u0632 \u0631\u06cc\u062e\u062a\u0646 \u0645\u0648\u0627\u062f \u0622\u0645\u0627\u062f\u0647 \u0634\u062f\u0647 \u0628\u0647 \u0622\u0646 \u067e\u0646\u06cc\u0631 \u067e\u06cc\u062a\u0632\u0627 \u0627\u0636\u0627\u0641\u0647 \u0645\u06cc \u06a9\u0646\u06cc\u0645. \u0633\u067e\u0633 \u0646\u0627\u0646 \u062a\u0633\u062a \u062f\u06cc\u06af\u0631\u06cc \u0631\u0648\u06cc \u0645\u0648\u0627\u062f \u0645\u06cc \u06af\u0630\u0627\u0631\u06cc\u0645 \u0648 \u0628\u0627 \u0627\u062d\u062a\u06cc\u0627\u0637 \u062f\u0631 \u0633\u0627\u0646\u062f\u0648\u06cc\u0686 \u0633\u0627\u0632 \u0631\u0627 \u0645\u06cc \u0628\u0646\u062f\u06cc\u0645. \u0628\u0639\u062f \u0627\u0632 \u062d\u062f\u0648\u062f 5 \u0627\u0644\u06cc 10 \u062f\u0642\u06cc\u0642\u0647 \u0627\u0633\u0646\u06a9 \u0647\u0627 \u0622\u0645\u0627\u062f\u0647 \u0647\u0633\u062a\u0646\u062f \u0648 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0646\u0648\u0634 \u062c\u0627\u0646 \u06a9\u0646\u06cc\u062f.<\/p>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B3%D9%86%DA%A9_%DB%8C%DA%A9_%D9%85%DB%8C%D8%A7%D9%86_%D9%88%D8%B9%D8%AF%D9%87_%D8%AE%D9%88%D8%B4%D9%85%D8%B2%D9%87_%D9%88_%D8%B9%D8%A7%D9%84%DB%8C\"><\/span>\u0627\u0633\u0646\u06a9 \u06cc\u06a9 \u0645\u06cc\u0627\u0646 \u0648\u0639\u062f\u0647 \u062e\u0648\u0634\u0645\u0632\u0647 \u0648 \u0639\u0627\u0644\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u0633\u0646\u06a9 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u062e\u0648\u0634\u0645\u0632\u0647 \u062a\u0631\u06cc\u0646 \u0645\u06cc\u0627\u0646 \u0648\u0639\u062f\u0647 \u0647\u0627 \u0648 \u067e\u06cc\u0634 \u063a\u0630\u0627\u0647\u0627\u060c \u0628\u0647 \u0631\u0648\u0634 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u062f\u0631 \u0633\u0627\u0646\u062f\u0648\u06cc\u0686 \u0633\u0627\u0632 \u0622\u0645\u0627\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a \u0646\u062f\u0627\u0634\u062a\u0646 \u0633\u0627\u0646\u062f\u0648\u06cc\u0686 \u0633\u0627\u0632 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u062a\u0627\u0628\u0647 \u0628\u0631\u0627\u06cc \u062f\u0631\u0633\u062a \u06a9\u0631\u062f\u0646 \u06cc\u06a9 <strong>\u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647<\/strong> \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u06cc\u06a9 \u0627\u0633\u0646\u06a9 \u062e\u0627\u0646\u06af\u06cc \u0633\u0627\u062f\u0647\u060c \u06af\u0632\u06cc\u0646\u0647 \u0647\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0628\u0647 \u062c\u0632\u0621 \u0698\u0627\u0645\u0628\u0648\u0646 \u062f\u0627\u0631\u06cc\u062f. \u0634\u0645\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u06cc\u0646 \u0645\u06cc\u0627\u0646 \u0648\u0639\u062f\u0647 \u0631\u0627 \u0628\u0627 \u0628\u0647 \u062c\u0632\u0621 \u0698\u0627\u0645\u0628\u0648\u0646 \u0628\u0627 \u06af\u0648\u0634\u062a \u0686\u0631\u062e \u06a9\u0631\u062f\u0647 \u06cc\u0627 \u0645\u0631\u063a \u062f\u0631\u0633\u062a \u06a9\u0646\u06cc\u062f.<\/p>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%A7%D8%B3%D9%86%DA%A9_%D8%B3%D8%A7%D8%AF%D9%87_%D9%88_%D9%BE%D9%86%DB%8C%D8%B1%DB%8C\"><\/span>\u0627\u0646\u0648\u0627\u0639 \u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647 \u0648 \u067e\u0646\u06cc\u0631\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>\u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647<\/strong> \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0641\u0633\u062a \u0641\u0648\u062f \u062e\u0648\u0634\u0645\u0632\u0647\u060c \u0628\u0627 \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u0645\u062a\u0646\u0648\u0639 \u0648 \u0631\u0648\u0634 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0622\u0645\u0627\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f. \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u062f\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0645\u0648\u0627\u0642\u0639 \u0627\u0632 \u0646\u0627\u0646 \u062a\u0633\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f \u0648\u0644\u06cc \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0646\u0627\u0646 \u06cc\u0648\u0641\u06a9\u0627 \u0648 \u0628\u0642\u06cc\u0647 \u0646\u0627\u0646 \u0647\u0627 \u0647\u0645 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u062a\u0646\u0648\u0639\u06cc \u06a9\u0647 \u062f\u0631 \u0645\u0648\u0627\u062f \u062a\u0634\u06a9\u06cc\u0644 \u062f\u0647\u0646\u062f\u0647 \u0627\u0633\u0646\u06a9 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f\u060c \u0645\u0648\u062c\u0628 \u0634\u062f\u0647 \u062a\u0627 \u0627\u06cc\u0646 \u0645\u06cc\u0627\u0646 \u0648\u0639\u062f\u0647 \u0637\u0631\u0641\u062f\u0627\u0631\u0627\u0646 \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647 \u0645\u0639\u0631\u0641\u06cc \u0686\u0646\u062f \u0645\u062f\u0644 \u0627\u0633\u0646\u06a9 \u062e\u0648\u0634 \u0637\u0639\u0645 \u067e\u0646\u06cc\u0631\u06cc \u0627\u0634\u0627\u0631\u0647 \u0645\u06cc \u06a9\u0646\u06cc\u0645.<\/p>\n<ul>\n<li>\u0627\u0633\u0646\u06a9 \u0645\u0631\u063a<\/li>\n<li>\u0627\u0633\u0646\u06a9 \u06af\u0648\u0634\u062a \u0686\u0631\u062e \u06a9\u0631\u062f\u0647<\/li>\n<li>\u0627\u0633\u0646\u06a9 \u067e\u06cc\u062a\u0632\u0627\u06cc\u06cc<\/li>\n<li>\u0627\u0633\u0646\u06a9 \u0633\u0628\u0632\u06cc\u062c\u0627\u062a<\/li>\n<\/ul>\n<hr \/>\n<h2 title=\"\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686 \u0631\u0698\u06cc\u0645\u06cc\"><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%D9%85%D8%B1%D8%BA_%D9%88_%D9%82%D8%A7%D8%B1%DA%86_%D8%B1%DA%98%DB%8C%D9%85%DB%8C_%D9%81%D9%82%D8%B7_150_%DA%A9%D8%A7%D9%84%D8%B1%DB%8C\"><\/span>\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686 \u0631\u0698\u06cc\u0645\u06cc | \u0641\u0642\u0637 150 \u06a9\u0627\u0644\u0631\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0644\u0630\u062a \u062e\u0648\u0631\u062f\u0646 \u0646\u0627\u0646 \u062a\u0631\u062f \u0648 \u0628\u0631\u0634\u062a\u0647 \u06a9\u0647 \u0632\u06cc\u0631 \u062f\u0646\u062f\u0627\u0646 \u062e\u064f\u0631\u062f \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u062a\u0631\u06a9\u06cc\u0628 \u0641\u0648\u0642\u200c\u0627\u0644\u0639\u0627\u062f\u0647 \u067e\u0646\u06cc\u0631 \u067e\u06cc\u062a\u0632\u0627\u06cc \u06a9\u0634\u200c\u062f\u0627\u0631\u060c \u0686\u06cc\u0632\u06cc \u0627\u0633\u062a \u06a9\u0647 \u06a9\u0645\u062a\u0631 \u06a9\u0633\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0622\u0646 \u0646\u0647 \u0628\u06af\u0648\u06cc\u062f. \u0627\u0633\u0646\u06a9 \u0627\u0632 \u0622\u0646 \u062f\u0633\u062a\u0647 \u062e\u0648\u0631\u0627\u06a9\u06cc\u200c\u0647\u0627\u06cc \u062f\u0644\u200c\u0646\u0634\u06cc\u0646 \u0648 \u062e\u0648\u0634\u0645\u0632\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0647\u0645\u06cc\u0634\u0647 \u062c\u0627\u06cc\u06cc \u062f\u0631 \u0642\u0644\u0628 \u0648 \u062e\u0627\u0637\u0631\u0627\u062a \u0645\u0627 \u062f\u0627\u0631\u062f. \u062d\u0627\u0644\u0627 \u062a\u0635\u0648\u0631 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0627\u0633\u0646\u06a9\u060c \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0627\u0632 \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686 \u0628\u0627\u0634\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u062a\u0631\u06a9\u06cc\u0628 \u0647\u06cc\u062c\u0627\u0646\u200c\u0627\u0646\u06af\u06cc\u0632\u060c \u0637\u0639\u0645\u06cc \u0634\u06af\u0641\u062a\u200c\u0627\u0646\u06af\u06cc\u0632 \u0648 \u0639\u0637\u0631 \u062f\u0644\u067e\u0630\u06cc\u0631\u06cc \u0646\u0635\u06cc\u0628\u062a\u0627\u0646 \u062e\u0648\u0627\u0647\u062f \u0634\u062f \u06a9\u0647 \u0628\u062f\u0648\u0646 \u0634\u06a9 \u0634\u0645\u0627 \u0631\u0627 \u0648\u0633\u0648\u0633\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0647\u0631 \u0686\u0647 \u0632\u0648\u062f\u062a\u0631 \u0622\u0646 \u0631\u0627 \u0627\u0645\u062a\u062d\u0627\u0646 \u06a9\u0646\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B3%D9%86%DA%A9_%D9%85%D8%B1%D8%BA_%D9%88_%D9%82%D8%A7%D8%B1%DA%86%D8%8C_%DB%8C%DA%A9_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D9%81%D9%88%D9%82%E2%80%8C%D8%A7%D9%84%D8%B9%D8%A7%D8%AF%D9%87\"><\/span>\u0627\u0633\u0646\u06a9 \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686\u060c \u06cc\u06a9 \u0627\u0646\u062a\u062e\u0627\u0628 \u0641\u0648\u0642\u200c\u0627\u0644\u0639\u0627\u062f\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u06af\u0631 \u06a9\u0645\u06cc \u062f\u0631 \u062f\u0633\u062a\u0648\u0631 \u067e\u062e\u062a\u200c\u0647\u0627\u06cc \u0627\u0633\u0646\u06a9 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a\u06cc \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u06cc\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647 \u06cc\u06a9 \u0645\u06cc\u0627\u0646\u200c\u0648\u0639\u062f\u0647 \u0633\u0627\u0644\u0645 \u0648 \u062d\u062a\u06cc \u06a9\u0645\u200c\u06a9\u0627\u0644\u0631\u06cc \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0646\u06cc\u062f. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0627 \u0647\u0645 \u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u06cc\u06a9 \u0627\u0633\u0646\u06a9 \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686 \u0644\u0630\u06cc\u0630 \u0648 \u0633\u0627\u062f\u0647 \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0642\u0637\u0639\u0627\u064b \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0646\u062a\u062e\u0627\u0628\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0647\u0631 \u0645\u0648\u0642\u0639\u06cc\u062a\u06cc \u0627\u0633\u062a. \u0622\u0645\u0627\u062f\u0647\u200c\u0627\u06cc\u062f\u061f \u0628\u0632\u0646 \u0628\u0631\u06cc\u0645!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-46097\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0627\u0633\u0646\u06a9-\u0645\u0631\u063a-\u0648-\u0642\u0627\u0631\u0686-\u0631\u0698\u06cc\u0645\u06cc.jpg\" alt=\"\u0627\u0633\u0646\u06a9 \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686 \u0631\u0698\u06cc\u0645\u06cc\" width=\"800\" height=\"533\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0627\u0633\u0646\u06a9-\u0645\u0631\u063a-\u0648-\u0642\u0627\u0631\u0686-\u0631\u0698\u06cc\u0645\u06cc.jpg 800w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0627\u0633\u0646\u06a9-\u0645\u0631\u063a-\u0648-\u0642\u0627\u0631\u0686-\u0631\u0698\u06cc\u0645\u06cc-300x200.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0627\u0633\u0646\u06a9-\u0645\u0631\u063a-\u0648-\u0642\u0627\u0631\u0686-\u0631\u0698\u06cc\u0645\u06cc-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D9%88%D8%A7%D8%AF_%D9%84%D8%A7%D8%B2%D9%85_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%D9%85%D8%B1%D8%BA_%D9%88_%D9%82%D8%A7%D8%B1%DA%86\"><\/span>\u0645\u0648\u0627\u062f \u0644\u0627\u0632\u0645 \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>\u067e\u06cc\u0627\u0632 \u062e\u0644\u0627\u0644\u06cc: \u06f1 \u0639\u062f\u062f \u0645\u062a\u0648\u0633\u0637<\/li>\n<li>\u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647\u200c\u0627\u06cc: \u06f1 \u0639\u062f\u062f<\/li>\n<li>\u0642\u0627\u0631\u0686: \u06f5 \u0639\u062f\u062f \u0645\u062a\u0648\u0633\u0637<\/li>\n<li>\u067e\u0646\u06cc\u0631 \u067e\u06cc\u062a\u0632\u0627: \u0628\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0644\u0627\u0632\u0645<\/li>\n<li>\u0633\u06cc\u0646\u0647 \u0645\u0631\u063a: \u06f2 \u0639\u062f\u062f \u067e\u062e\u062a\u0647 \u0648 \u0631\u06cc\u0634\u200c\u0631\u06cc\u0634 \u0634\u062f\u0647<\/li>\n<li>\u0646\u0627\u0646 \u062a\u0633\u062a: \u0628\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0644\u0627\u0632\u0645<\/li>\n<li>\u0646\u0645\u06a9\u060c \u0641\u0644\u0641\u0644 \u0648 \u0622\u0648\u06cc\u0634\u0646: \u0628\u0647 \u0645\u0642\u062f\u0627\u0631 \u062f\u0644\u062e\u0648\u0627\u0647<\/li>\n<li>\u0633\u0633 \u06a9\u0686\u0627\u067e \u06cc\u0627 \u0645\u0627\u06cc\u0648\u0646\u0632: \u0628\u0631\u0627\u06cc \u0637\u0639\u0645\u200c\u062f\u0647\u06cc<\/li>\n<\/ul>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%D9%85%D8%B1%D8%BA_%D9%88_%D9%82%D8%A7%D8%B1%DA%86\"><\/span>\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ol>\n<li><strong>\u062a\u0641\u062a \u062f\u0627\u062f\u0646 \u067e\u06cc\u0627\u0632<\/strong>: \u0627\u0628\u062a\u062f\u0627 \u067e\u06cc\u0627\u0632 \u062e\u0644\u0627\u0644\u06cc \u0631\u0627 \u0628\u0627 \u06a9\u0645\u06cc \u0631\u0648\u063a\u0646 \u062f\u0631 \u062a\u0627\u0628\u0647 \u062a\u0641\u062a \u062f\u0647\u06cc\u062f \u062a\u0627 \u0646\u0631\u0645 \u0648 \u0637\u0644\u0627\u06cc\u06cc \u0634\u0648\u062f.<\/li>\n<li><strong>\u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f\u0646 \u0642\u0627\u0631\u0686<\/strong>: \u0642\u0627\u0631\u0686\u200c\u0647\u0627\u06cc \u062e\u0631\u062f \u0634\u062f\u0647 \u0631\u0627 \u0628\u0647 \u067e\u06cc\u0627\u0632 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u062a\u0641\u062a \u062f\u0647\u06cc\u062f \u062a\u0627 \u0622\u0628 \u0642\u0627\u0631\u0686\u200c\u0647\u0627 \u06a9\u0634\u06cc\u062f\u0647 \u0648 \u06a9\u0645\u06cc \u0637\u0644\u0627\u06cc\u06cc \u0634\u0648\u0646\u062f.<\/li>\n<li><strong>\u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647\u200c\u0627\u06cc<\/strong>: \u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647\u200c\u0627\u06cc \u062e\u0631\u062f \u0634\u062f\u0647 \u0631\u0627 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0686\u0646\u062f \u062f\u0642\u06cc\u0642\u0647 \u062f\u06cc\u06af\u0631 \u062a\u0641\u062a \u062f\u0647\u06cc\u062f \u062a\u0627 \u0639\u0637\u0631 \u0622\u0646 \u0622\u0632\u0627\u062f \u0634\u0648\u062f.<\/li>\n<li><strong>\u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f\u0646 \u0645\u0631\u063a<\/strong>: \u0645\u0631\u063a\u200c\u0647\u0627\u06cc \u0631\u06cc\u0634 \u0634\u062f\u0647 \u0631\u0627 \u0628\u0647 \u062a\u0631\u06a9\u06cc\u0628 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0647\u0645\u0647 \u0645\u0648\u0627\u062f \u0631\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0628\u0627 \u0647\u0645 \u0645\u062e\u0644\u0648\u0637 \u06a9\u0646\u06cc\u062f.<\/li>\n<li><strong>\u0627\u062f\u0648\u06cc\u0647\u200c\u062c\u0627\u062a<\/strong>: \u0646\u0645\u06a9\u060c \u0641\u0644\u0641\u0644 \u0648 \u0622\u0648\u06cc\u0634\u0646 \u0631\u0627 \u0628\u0647 \u0645\u06cc\u0632\u0627\u0646 \u062f\u0644\u062e\u0648\u0627\u0647 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f\u0647 \u0648 \u0686\u0646\u062f \u062f\u0642\u06cc\u0642\u0647 \u062f\u06cc\u06af\u0631 \u0647\u0645\u0647 \u0645\u0648\u0627\u062f \u0631\u0627 \u0628\u0627 \u0647\u0645 \u062a\u0641\u062a \u062f\u0647\u06cc\u062f.<\/li>\n<li><strong>\u0622\u0645\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc \u0646\u0627\u0646 \u062a\u0633\u062a<\/strong>: \u0631\u0648\u06cc \u0646\u0627\u0646\u200c\u0647\u0627\u06cc \u062a\u0633\u062a \u06a9\u0645\u06cc \u0633\u0633 \u06a9\u0686\u0627\u067e \u06cc\u0627 \u0645\u0627\u06cc\u0648\u0646\u0632 \u0628\u0645\u0627\u0644\u06cc\u062f \u062a\u0627 \u0637\u0639\u0645 \u0628\u0647\u062a\u0631\u06cc \u0628\u06af\u06cc\u0631\u062f.<\/li>\n<li><strong>\u0686\u06cc\u062f\u0646 \u0645\u0648\u0627\u062f<\/strong>: \u0627\u0632 \u0645\u062e\u0644\u0648\u0637 \u0645\u0648\u0627\u062f \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686 \u0631\u0648\u06cc \u0646\u0627\u0646 \u062a\u0633\u062a\u200c\u0647\u0627 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f \u0648 \u0633\u067e\u0633 \u0645\u0642\u062f\u0627\u0631\u06cc \u067e\u0646\u06cc\u0631 \u067e\u06cc\u062a\u0632\u0627 \u0631\u0648\u06cc \u0622\u0646\u200c\u0647\u0627 \u0628\u0631\u06cc\u0632\u06cc\u062f.<\/li>\n<li><strong>\u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0646 \u0646\u0627\u0646 \u062f\u0648\u0645<\/strong>: \u06cc\u06a9 \u062a\u06a9\u0647 \u0646\u0627\u0646 \u062f\u06cc\u06af\u0631 \u0631\u0648\u06cc \u0645\u0648\u0627\u062f \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f \u0648 \u06a9\u0645\u06cc \u0641\u0634\u0627\u0631 \u062f\u0647\u06cc\u062f \u062a\u0627 \u0645\u0648\u0627\u062f \u0628\u06cc\u0646 \u0646\u0627\u0646\u200c\u0647\u0627 \u0642\u0631\u0627\u0631 \u0628\u06af\u06cc\u0631\u062f.<\/li>\n<li><strong>\u067e\u062e\u062a \u062f\u0631 \u0633\u0627\u0646\u062f\u0648\u06cc\u0686\u200c\u0633\u0627\u0632<\/strong>: \u0627\u0633\u0646\u06a9\u200c\u0647\u0627 \u0631\u0627 \u062f\u0631 \u0633\u0627\u0646\u062f\u0648\u06cc\u0686\u200c\u0633\u0627\u0632 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f \u0648 \u0645\u0646\u062a\u0638\u0631 \u0628\u0645\u0627\u0646\u06cc\u062f \u062a\u0627 \u0646\u0627\u0646\u200c\u0647\u0627 \u0637\u0644\u0627\u06cc\u06cc \u0648 \u067e\u0646\u06cc\u0631 \u0622\u0628 \u0634\u0648\u062f.<\/li>\n<\/ol>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%D8%AA%D8%BA%D8%B0%DB%8C%D9%87%E2%80%8C%D8%A7%DB%8C_%D8%A7%D8%B3%D9%86%DA%A9_%D9%82%D8%A7%D8%B1%DA%86_%D9%88_%D9%85%D8%B1%D8%BA\"><\/span>\u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062a\u063a\u0630\u06cc\u0647\u200c\u0627\u06cc \u0627\u0633\u0646\u06a9 \u0642\u0627\u0631\u0686 \u0648 \u0645\u0631\u063a<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u06a9\u0644 \u0627\u06cc\u0646 \u0645\u0642\u062f\u0627\u0631 \u0627\u0633\u0646\u06a9 \u06a9\u0647 \u0628\u0627 \u0645\u0648\u0627\u062f \u0630\u06a9\u0631 \u0634\u062f\u0647 \u062a\u0647\u06cc\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u062d\u062f\u0648\u062f \u06f1\u06f8\u06f0\u06f0 \u06a9\u0627\u0644\u0631\u06cc \u062f\u0627\u0631\u062f \u0648 \u0628\u0631\u0627\u06cc \u06f1\u06f2 \u0646\u0641\u0631 \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a. \u0627\u06af\u0631 \u0647\u0631 \u0646\u0641\u0631 \u06cc\u06a9 \u0627\u0633\u0646\u06a9 \u0645\u06cc\u0644 \u06a9\u0646\u062f\u060c \u0645\u0642\u0627\u062f\u06cc\u0631 \u062a\u063a\u0630\u06cc\u0647\u200c\u0627\u06cc \u0632\u06cc\u0631 \u0628\u0647 \u0627\u0648 \u062e\u0648\u0627\u0647\u062f \u0631\u0633\u06cc\u062f:<\/p>\n<ul>\n<li><strong>\u06a9\u0627\u0644\u0631\u06cc<\/strong>: \u06f1\u06f5\u06f0<\/li>\n<li><strong>\u06a9\u0631\u0628\u0648\u0647\u06cc\u062f\u0631\u0627\u062a<\/strong>: \u06f1\u06f9.\u06f3\u06f3 \u06af\u0631\u0645<\/li>\n<li><strong>\u0686\u0631\u0628\u06cc<\/strong>: \u06f3.\u06f8\u06f8 \u06af\u0631\u0645<\/li>\n<li><strong>\u067e\u0631\u0648\u062a\u0626\u06cc\u0646<\/strong>: \u06f1\u06f1.\u06f8\u06f3 \u06af\u0631\u0645<\/li>\n<\/ul>\n<p>\u0627\u06cc\u0646 \u0627\u0633\u0646\u06a9\u060c \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u062e\u0648\u0634\u0645\u0632\u06af\u06cc\u060c \u06cc\u06a9 \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0646\u0627\u0633\u0628 \u0648 \u0646\u0633\u0628\u062a\u0627\u064b \u0633\u0627\u0644\u0645 \u0628\u0631\u0627\u06cc \u0645\u06cc\u0627\u0646\u200c\u0648\u0639\u062f\u0647 \u06cc\u0627 \u0634\u0627\u0645 \u0633\u0628\u06a9 \u0627\u0633\u062a. \u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06af\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u063a\u0630\u0627\u06cc\u06cc \u0645\u062a\u0646\u0648\u0639 \u0647\u0633\u062a\u06cc\u062f\u060c \u0627\u0633\u0646\u06a9 \u0645\u0631\u063a \u0648 \u0642\u0627\u0631\u0686 \u0631\u0627 \u062d\u062a\u0645\u0627\u064b \u0627\u0645\u062a\u062d\u0627\u0646 \u06a9\u0646\u06cc\u062f!<\/p>\n<div class=\"article-desc\">\n<h2 title=\"\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u06cc \u0627\u0633\u0646\u06a9 \u0631\u0698\u06cc\u0645\u06cc \u0641\u0648\u0642 \u0627\u0644\u0639\u0627\u062f\u0647 \u062e\u0648\u0634\u0645\u0632\u0647\"><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%DB%8C_%D8%A7%D8%B3%D9%86%DA%A9_%D8%B1%DA%98%DB%8C%D9%85%DB%8C_%D9%81%D9%88%D9%82_%D8%A7%D9%84%D8%B9%D8%A7%D8%AF%D9%87_%D8%AE%D9%88%D8%B4%D9%85%D8%B2%D9%87\"><\/span>\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u06cc \u0627\u0633\u0646\u06a9 \u0631\u0698\u06cc\u0645\u06cc \u0641\u0648\u0642 \u0627\u0644\u0639\u0627\u062f\u0647 \u062e\u0648\u0634\u0645\u0632\u0647<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"article-desc\">\n<p>\u0627\u0633\u0646\u06a9\u200c\u0647\u0627 \u0647\u0645\u06cc\u0634\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u062e\u0648\u0631\u0627\u06a9\u06cc\u200c\u0647\u0627\u06cc \u0645\u062d\u0628\u0648\u0628 \u0648 \u0645\u0648\u0631\u062f \u0639\u0644\u0627\u0642\u0647 \u0647\u0645\u0647\u060c \u0628\u0647\u200c\u062e\u0635\u0648\u0635 \u0628\u0686\u0647\u200c\u0647\u0627 \u0647\u0633\u062a\u0646\u062f. \u0628\u0627 \u0648\u062c\u0648\u062f \u0627\u06cc\u0646\u060c \u0627\u0633\u0646\u06a9\u200c\u0647\u0627\u06cc \u0622\u0645\u0627\u062f\u0647\u200c\u0627\u06cc \u06a9\u0647 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0645\u0648\u062c\u0648\u062f\u0646\u062f\u060c \u0645\u0645\u0644\u0648 \u0627\u0632 \u0633\u0648\u0633\u06cc\u0633\u060c \u06a9\u0627\u0644\u0628\u0627\u0633\u060c \u067e\u0646\u06cc\u0631\u0647\u0627\u06cc \u067e\u0631\u0686\u0631\u0628 \u0648 \u0633\u0633\u200c\u0647\u0627\u06cc \u0633\u0646\u06af\u06cc\u0646 \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0647\u0645 \u06a9\u0627\u0644\u0631\u06cc \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u0646\u062f \u0648 \u0647\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627\u0639\u062b \u0627\u0641\u0632\u0627\u06cc\u0634 \u0648\u0632\u0646 \u0634\u0648\u0646\u062f. \u0628\u0631\u0627\u06cc \u0647\u0645\u06cc\u0646\u060c \u0645\u0627 \u0627\u06cc\u0646\u200c\u062c\u0627 \u0647\u0633\u062a\u06cc\u0645 \u062a\u0627 \u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u06cc\u06a9 \u0627\u0633\u0646\u06a9 \u0631\u0698\u06cc\u0645\u06cc \u0648 \u062e\u0648\u0634\u0645\u0632\u0647 \u0631\u0627 \u0628\u0627 \u0634\u0645\u0627 \u0628\u0647 \u0627\u0634\u062a\u0631\u0627\u06a9 \u0628\u06af\u0630\u0627\u0631\u06cc\u0645. \u0627\u06cc\u0646 \u0627\u0633\u0646\u06a9 \u0631\u0698\u06cc\u0645\u06cc \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0633\u0628\u0632\u06cc\u062c\u0627\u062a \u062a\u0627\u0632\u0647 \u0648 \u0633\u0627\u0644\u0645 \u062f\u0631\u0633\u062a \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0628\u0647 \u0634\u0645\u0627 \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0645\u06cc\u200c\u062f\u0647\u062f \u062a\u0627 \u0627\u0632 \u06cc\u06a9 \u063a\u0630\u0627\u06cc \u0644\u0630\u06cc\u0630 \u0644\u0630\u062a \u0628\u0628\u0631\u06cc\u062f\u060c \u0628\u062f\u0648\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u0646\u06af\u0631\u0627\u0646 \u06a9\u0627\u0644\u0631\u06cc \u0628\u0627\u0644\u0627 \u06cc\u0627 \u062e\u0631\u0627\u0628 \u0634\u062f\u0646 \u0631\u0698\u06cc\u0645 \u062e\u0648\u062f \u0628\u0627\u0634\u06cc\u062f.<\/p>\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u062f\u0633\u062a\u0648\u0631\u060c \u062a\u0644\u0627\u0634 \u06a9\u0631\u062f\u06cc\u0645 \u062a\u0627 \u0628\u0627 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0627\u0632 \u0633\u0628\u0632\u06cc\u062c\u0627\u062a \u06a9\u0645\u200c\u06a9\u0627\u0644\u0631\u06cc \u0648 \u0645\u0648\u0627\u062f \u0633\u0627\u0644\u0645\u060c \u0637\u0639\u0645\u06cc \u0628\u06cc\u200c\u0646\u0638\u06cc\u0631 \u062e\u0644\u0642 \u06a9\u0646\u06cc\u0645. \u0627\u06af\u0631\u0686\u0647 \u067e\u0646\u06cc\u0631 \u0648 \u0633\u0633 \u0641\u0631\u0627\u0646\u0633\u0648\u06cc \u0647\u0645\u0686\u0646\u0627\u0646 \u062f\u0631 \u0627\u06cc\u0646 \u062f\u0633\u062a\u0648\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u062f\u0647\u200c\u0627\u0646\u062f \u062a\u0627 \u0645\u0632\u0647 \u062f\u0644\u067e\u0630\u06cc\u0631 \u0627\u06cc\u0646 \u0627\u0633\u0646\u06a9 \u062d\u0641\u0638 \u0634\u0648\u062f\u060c \u0628\u0647 \u0634\u0645\u0627 \u062a\u0648\u0635\u06cc\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u062f\u0631 \u0645\u0635\u0631\u0641 \u0622\u0646\u200c\u0647\u0627 \u0627\u0639\u062a\u062f\u0627\u0644 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0647\u0645\u0686\u0646\u0627\u0646 \u0631\u0698\u06cc\u0645 \u062e\u0648\u062f \u0631\u0627 \u0631\u0639\u0627\u06cc\u062a \u06a9\u0646\u06cc\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-46098\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0637\u0631\u0632-\u062a\u0647\u06cc\u0647-\u06cc-\u0627\u0633\u0646\u06a9-\u0631\u0698\u06cc\u0645\u06cc-\u0641\u0648\u0642-\u0627\u0644\u0639\u0627\u062f\u0647-\u062e\u0648\u0634\u0645\u0632\u0647.jpg\" alt=\"\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u06cc \u0627\u0633\u0646\u06a9 \u0631\u0698\u06cc\u0645\u06cc \u0641\u0648\u0642 \u0627\u0644\u0639\u0627\u062f\u0647 \u062e\u0648\u0634\u0645\u0632\u0647\" width=\"600\" height=\"399\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0637\u0631\u0632-\u062a\u0647\u06cc\u0647-\u06cc-\u0627\u0633\u0646\u06a9-\u0631\u0698\u06cc\u0645\u06cc-\u0641\u0648\u0642-\u0627\u0644\u0639\u0627\u062f\u0647-\u062e\u0648\u0634\u0645\u0632\u0647.jpg 600w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0637\u0631\u0632-\u062a\u0647\u06cc\u0647-\u06cc-\u0627\u0633\u0646\u06a9-\u0631\u0698\u06cc\u0645\u06cc-\u0641\u0648\u0642-\u0627\u0644\u0639\u0627\u062f\u0647-\u062e\u0648\u0634\u0645\u0632\u0647-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D9%88%D8%A7%D8%AF_%D9%84%D8%A7%D8%B2%D9%85_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%D8%B1%DA%98%DB%8C%D9%85%DB%8C\"><\/span>\u0645\u0648\u0627\u062f \u0644\u0627\u0632\u0645 \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0631\u0698\u06cc\u0645\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>\u067e\u0646\u06cc\u0631 \u0648\u0631\u0642\u0647\u200c\u0627\u06cc \u06a9\u0645\u200c\u0686\u0631\u0628: \u06f5\u06f0 \u06af\u0631\u0645<\/li>\n<li>\u067e\u06cc\u0627\u0632 \u0633\u0631\u062e \u0634\u062f\u0647 (\u0628\u0627 \u062d\u062f\u0627\u0642\u0644 \u0631\u0648\u063a\u0646): \u0646\u0635\u0641 \u0642\u0627\u0634\u0642 \u063a\u0630\u0627\u062e\u0648\u0631\u06cc<\/li>\n<li>\u0646\u0627\u0646 \u062a\u0633\u062a \u0633\u0628\u0648\u0633\u200c\u062f\u0627\u0631: \u06f1 \u0639\u062f\u062f<\/li>\n<li>\u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647\u200c\u0627\u06cc \u062e\u0631\u062f \u0634\u062f\u0647: \u06f1 \u067e\u06cc\u0645\u0627\u0646\u0647<\/li>\n<li>\u06af\u0644 \u06a9\u0644\u0645 \u0628\u062e\u0627\u0631\u067e\u0632: \u0646\u0635\u0641 \u0644\u06cc\u0648\u0627\u0646<\/li>\n<li>\u06af\u0648\u062c\u0647 \u0641\u0631\u0646\u06af\u06cc \u062e\u0631\u062f \u0634\u062f\u0647: \u06f1 \u0639\u062f\u062f<\/li>\n<li>\u0642\u0627\u0631\u0686 \u062e\u0631\u062f \u0634\u062f\u0647: \u0646\u0635\u0641 \u0644\u06cc\u0648\u0627\u0646<\/li>\n<li>\u0633\u0633 \u0641\u0631\u0627\u0646\u0633\u0648\u06cc \u06a9\u0645\u200c\u0686\u0631\u0628: \u06f1 \u0642\u0627\u0634\u0642 \u0686\u0627\u06cc\u062e\u0648\u0631\u06cc<\/li>\n<li>\u0622\u0628 \u0644\u06cc\u0645\u0648 \u062a\u0631\u0634 \u062a\u0627\u0632\u0647: \u06cc\u06a9 \u0647\u0634\u062a\u0645 \u067e\u06cc\u0645\u0627\u0646\u0647<\/li>\n<li>\u0646\u0645\u06a9\u060c \u0641\u0644\u0641\u0644\u060c \u067e\u0648\u062f\u0631 \u06a9\u0627\u0631\u06cc: \u0628\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0644\u0627\u0632\u0645<\/li>\n<\/ul>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%D8%B1%DA%98%DB%8C%D9%85%DB%8C\"><\/span>\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u0631\u0698\u06cc\u0645\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ol>\n<li><strong>\u0628\u062e\u0627\u0631\u067e\u0632 \u06a9\u0631\u062f\u0646 \u06af\u0644 \u06a9\u0644\u0645<\/strong>: \u0627\u0628\u062a\u062f\u0627 \u06af\u0644 \u06a9\u0644\u0645\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0628\u062e\u0627\u0631\u067e\u0632 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0646\u0631\u0645 \u0648 \u0622\u0645\u0627\u062f\u0647 \u0645\u0635\u0631\u0641 \u0634\u0648\u0646\u062f.<\/li>\n<li><strong>\u062a\u0641\u062a \u062f\u0627\u062f\u0646 \u0633\u0628\u0632\u06cc\u062c\u0627\u062a<\/strong>: \u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647\u200c\u0627\u06cc \u0648 \u067e\u06cc\u0627\u0632 \u0631\u0627 \u0628\u0627 \u0645\u0642\u062f\u0627\u0631 \u06a9\u0645\u06cc \u0631\u0648\u063a\u0646 \u062f\u0631 \u062a\u0627\u0628\u0647 \u062a\u0641\u062a \u062f\u0647\u06cc\u062f \u062a\u0627 \u0646\u0631\u0645 \u0634\u0648\u0646\u062f. \u0633\u067e\u0633 \u0646\u0645\u06a9\u060c \u0641\u0644\u0641\u0644\u060c \u067e\u0648\u062f\u0631 \u06a9\u0627\u0631\u06cc \u0648 \u0622\u0628\u0644\u06cc\u0645\u0648 \u0631\u0627 \u0628\u0647 \u0622\u0646\u200c\u0647\u0627 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0645\u0648\u0627\u062f \u0631\u0627 \u0628\u0627 \u0647\u0645 \u0645\u062e\u0644\u0648\u0637 \u06a9\u0646\u06cc\u062f.<\/li>\n<li><strong>\u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f\u0646 \u06af\u0648\u062c\u0647 \u0648 \u0642\u0627\u0631\u0686<\/strong>: \u06af\u0648\u062c\u0647 \u0641\u0631\u0646\u06af\u06cc \u062e\u0631\u062f \u0634\u062f\u0647 \u0648 \u0642\u0627\u0631\u0686 \u0631\u0627 \u0646\u06cc\u0632 \u0628\u0647 \u0645\u0648\u0627\u062f \u062a\u0627\u0628\u0647 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u06a9\u0645\u06cc \u062a\u0641\u062a \u062f\u0647\u06cc\u062f \u062a\u0627 \u0639\u0637\u0631 \u0648 \u0637\u0639\u0645 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u06af\u06cc\u0631\u0646\u062f.<\/li>\n<li><strong>\u0622\u0645\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc \u0646\u0627\u0646 \u062a\u0633\u062a<\/strong>: \u0633\u0627\u0646\u062f\u0648\u06cc\u0686\u200c\u0633\u0627\u0632 \u0631\u0627 \u0631\u0648\u0634\u0646 \u06a9\u0631\u062f\u0647 \u0648 \u0628\u0627 \u0645\u0642\u062f\u0627\u0631 \u06a9\u0645\u06cc \u0631\u0648\u063a\u0646 \u0686\u0631\u0628 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0646\u0627\u0646 \u0628\u0647 \u0622\u0646 \u0646\u0686\u0633\u0628\u062f.<\/li>\n<li><strong>\u0686\u06cc\u062f\u0646 \u0645\u0648\u0627\u062f \u0631\u0648\u06cc \u0646\u0627\u0646<\/strong>: \u06cc\u06a9 \u062a\u06a9\u0647 \u0646\u0627\u0646 \u062a\u0633\u062a \u0633\u0628\u0648\u0633\u200c\u062f\u0627\u0631 \u0628\u0631\u062f\u0627\u0631\u06cc\u062f \u0648 \u06cc\u06a9 \u0648\u0631\u0642\u0647 \u067e\u0646\u06cc\u0631 \u0631\u0648\u06cc \u0622\u0646 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f. \u0633\u067e\u0633 \u0645\u062e\u0644\u0648\u0637 \u0633\u0628\u0632\u06cc\u062c\u0627\u062a \u0631\u0627 \u0631\u0648\u06cc \u067e\u0646\u06cc\u0631 \u0631\u06cc\u062e\u062a\u0647 \u0648 \u06cc\u06a9 \u0648\u0631\u0642\u0647 \u062f\u06cc\u06af\u0631 \u067e\u0646\u06cc\u0631 \u0631\u0648\u06cc \u0645\u0648\u0627\u062f \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f.<\/li>\n<li><strong>\u0628\u0633\u062a\u0646 \u0627\u0633\u0646\u06a9<\/strong>: \u06cc\u06a9 \u062a\u06a9\u0647 \u0646\u0627\u0646 \u062f\u06cc\u06af\u0631 \u0631\u0648\u06cc \u067e\u0646\u06cc\u0631 \u0648 \u0645\u0648\u0627\u062f \u0628\u06af\u0630\u0627\u0631\u06cc\u062f \u0648 \u06a9\u0645\u06cc \u0641\u0634\u0627\u0631 \u062f\u0647\u06cc\u062f \u062a\u0627 \u0645\u0648\u0627\u062f \u0628\u0647 \u0647\u0645 \u0686\u0633\u0628\u0646\u062f.<\/li>\n<li><strong>\u067e\u062e\u062a \u062f\u0631 \u0633\u0627\u0646\u062f\u0648\u06cc\u0686\u200c\u0633\u0627\u0632<\/strong>: \u0627\u0633\u0646\u06a9 \u0631\u0627 \u062f\u0631\u0648\u0646 \u0633\u0627\u0646\u062f\u0648\u06cc\u0686\u200c\u0633\u0627\u0632 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f \u0648 \u062a\u0627 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0646\u0627\u0646\u200c\u0647\u0627 \u0637\u0644\u0627\u06cc\u06cc \u0648 \u067e\u0646\u06cc\u0631 \u0622\u0628 \u0634\u0648\u062f\u060c \u0635\u0628\u0631 \u06a9\u0646\u06cc\u062f.<\/li>\n<li><strong>\u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f\u0646 \u0633\u0633 \u0641\u0631\u0627\u0646\u0633\u0648\u06cc<\/strong>: \u0628\u0639\u062f \u0627\u0632 \u0622\u0645\u0627\u062f\u0647 \u0634\u062f\u0646 \u0627\u0633\u0646\u06a9\u060c \u0631\u0648\u06cc \u0622\u0646 \u06a9\u0645\u06cc \u0633\u0633 \u0641\u0631\u0627\u0646\u0633\u0648\u06cc \u0628\u0631\u06cc\u0632\u06cc\u062f \u0648 \u0627\u0632 \u0637\u0639\u0645 \u0644\u0630\u06cc\u0630 \u0648 \u0633\u0627\u0644\u0645 \u0622\u0646 \u0644\u0630\u062a \u0628\u0628\u0631\u06cc\u062f.<\/li>\n<\/ol>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%D8%AA%D8%BA%D8%B0%DB%8C%D9%87%E2%80%8C%D8%A7%DB%8C_%D8%A7%D8%B3%D9%86%DA%A9_%D8%B1%DA%98%DB%8C%D9%85%DB%8C\"><\/span>\u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062a\u063a\u0630\u06cc\u0647\u200c\u0627\u06cc \u0627\u0633\u0646\u06a9 \u0631\u0698\u06cc\u0645\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u06cc\u0646 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u06cc\u06a9 \u0639\u062f\u062f \u0627\u0633\u0646\u06a9 \u0627\u0633\u062a. \u062f\u0631 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0627 \u0627\u0633\u0646\u06a9\u200c\u0647\u0627\u06cc \u0686\u0631\u0628 \u0648 \u0633\u0646\u06af\u06cc\u0646\u060c \u0627\u06cc\u0646 \u0627\u0633\u0646\u06a9 \u0631\u0698\u06cc\u0645\u06cc \u0628\u0647 \u0634\u0645\u0627 \u0646\u06cc\u0645\u06cc \u0627\u0632 \u06a9\u0627\u0644\u0631\u06cc \u0645\u0639\u0645\u0648\u0644 \u0631\u0627 \u0645\u06cc\u200c\u062f\u0647\u062f\u060c \u0628\u062f\u0648\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u0632 \u0637\u0639\u0645 \u062e\u0648\u0634\u0645\u0632\u0647 \u0622\u0646 \u06a9\u0645 \u06a9\u0646\u062f.<\/p>\n<ul>\n<li><strong>\u06a9\u0627\u0644\u0631\u06cc \u062f\u0631 \u06cc\u06a9 \u0648\u0639\u062f\u0647<\/strong>: \u06f2\u06f5\u06f0<\/li>\n<li><strong>\u06a9\u0631\u0628\u0648\u0647\u06cc\u062f\u0631\u0627\u062a<\/strong>: \u06f3\u06f8 \u06af\u0631\u0645<\/li>\n<li><strong>\u067e\u0631\u0648\u062a\u0626\u06cc\u0646<\/strong>: \u06f5 \u06af\u0631\u0645<\/li>\n<li><strong>\u0686\u0631\u0628\u06cc<\/strong>: \u06f1\u06f9 \u06af\u0631\u0645<\/li>\n<\/ul>\n<p>\u0627\u06cc\u0646 \u0627\u0633\u0646\u06a9 \u0633\u0628\u06a9\u060c \u0633\u0627\u0644\u0645 \u0648 \u062e\u0648\u0634\u0645\u0632\u0647\u060c \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0647\u0645 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0644\u0630\u062a \u0628\u0631\u062f\u0646 \u0627\u0632 \u063a\u0630\u0627 \u0647\u0633\u062a\u0646\u062f \u0648 \u0647\u0645 \u0646\u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u0646\u062f \u06a9\u0627\u0644\u0631\u06cc \u0627\u0636\u0627\u0641\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u0646\u062f.<\/p>\n<h2 class=\"ptitle\"><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B3%D9%86%DA%A9_%D8%B3%D8%A7%D8%AF%D9%87_%D8%A8%D8%A7_%DA%AF%D9%88%D8%B4%D8%AA_%DA%86%D8%B1%D8%AE_%DA%A9%D8%B1%D8%AF%D9%87_%D8%AE%D9%88%D8%B4%D9%85%D8%B2%D9%87_%D8%AF%D8%B1_5_%D9%85%D8%B1%D8%AD%D9%84%D9%87\"><\/span>\u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647 \u0628\u0627 \u06af\u0648\u0634\u062a \u0686\u0631\u062e \u06a9\u0631\u062f\u0647 \u062e\u0648\u0634\u0645\u0632\u0647 \u062f\u0631 5 \u0645\u0631\u062d\u0644\u0647<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"row post-det\">\n<div class=\"dina-post-details post-aut\">\n<p>\u0627\u0633\u0646\u06a9 \u0628\u0627 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u062e\u0648\u0631\u0627\u06a9\u06cc\u200c\u0647\u0627\u06cc \u0645\u062d\u0628\u0648\u0628 \u0648 \u0631\u0627\u062d\u062a\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0645\u06cc\u0627\u0646\u200c\u0648\u0639\u062f\u0647 \u06cc\u0627 \u062d\u062a\u06cc \u063a\u0630\u0627\u06cc \u0627\u0635\u0644\u06cc \u062f\u0631 \u0646\u0638\u0631 \u06af\u0631\u0641\u062a. \u062a\u0647\u06cc\u0647 \u0627\u06cc\u0646 \u0627\u0633\u0646\u06a9 \u0628\u0633\u06cc\u0627\u0631 \u0633\u0627\u062f\u0647 \u0627\u0633\u062a \u0648 \u062f\u0631 \u06a9\u0645\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0622\u0645\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u06af\u0631 \u0648\u0642\u062a \u06a9\u0645\u06cc \u062f\u0627\u0631\u06cc\u062f \u0648 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u063a\u0630\u0627\u06cc\u06cc \u0633\u0631\u06cc\u0639 \u0648 \u062e\u0648\u0634\u0645\u0632\u0647 \u0647\u0633\u062a\u06cc\u062f\u060c \u0627\u0633\u0646\u06a9 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647 \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0639\u0627\u0644\u06cc \u0627\u0633\u062a. \u062a\u0646\u0647\u0627 \u0628\u0627 \u06a9\u0645\u06cc \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647 \u0648 \u0686\u0646\u062f \u0645\u0627\u062f\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0633\u0627\u062f\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u06cc\u0646 \u0627\u0633\u0646\u06a9 \u0644\u0630\u06cc\u0630 \u0631\u0627 \u062a\u0647\u06cc\u0647 \u06a9\u0646\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0627\u06cc\u0646 \u062e\u0648\u0631\u0627\u06a9\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0641\u06cc\u0646\u06af\u0631\u0641\u0648\u062f \u062f\u0631 \u0645\u06cc\u0647\u0645\u0627\u0646\u06cc\u200c\u0647\u0627 \u06cc\u0627 \u062f\u0648\u0631\u0647\u0645\u06cc\u200c\u0647\u0627 \u0633\u0631\u0648 \u0634\u0648\u062f. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647\u060c \u062f\u0648 \u0631\u0648\u0634 \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u06cc\u0646 \u0627\u0633\u0646\u06a9 \u062e\u0648\u0634\u0645\u0632\u0647 \u0628\u0647 \u0634\u0645\u0627 \u0622\u0645\u0648\u0632\u0634 \u062e\u0648\u0627\u0647\u06cc\u0645 \u062f\u0627\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-46099\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0627\u0633\u0646\u06a9-\u0633\u0627\u062f\u0647-\u0628\u0627-\u06af\u0648\u0634\u062a-\u0686\u0631\u062e-\u06a9\u0631\u062f\u0647-\u062e\u0648\u0634\u0645\u0632\u0647-\u062f\u0631-5-\u0645\u0631\u062d\u0644\u0647.jpg\" alt=\"\u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647 \u0628\u0627 \u06af\u0648\u0634\u062a \u0686\u0631\u062e \u06a9\u0631\u062f\u0647 \u062e\u0648\u0634\u0645\u0632\u0647 \u062f\u0631 5 \u0645\u0631\u062d\u0644\u0647\" width=\"640\" height=\"598\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0627\u0633\u0646\u06a9-\u0633\u0627\u062f\u0647-\u0628\u0627-\u06af\u0648\u0634\u062a-\u0686\u0631\u062e-\u06a9\u0631\u062f\u0647-\u062e\u0648\u0634\u0645\u0632\u0647-\u062f\u0631-5-\u0645\u0631\u062d\u0644\u0647.jpg 640w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/09\/\u0627\u0633\u0646\u06a9-\u0633\u0627\u062f\u0647-\u0628\u0627-\u06af\u0648\u0634\u062a-\u0686\u0631\u062e-\u06a9\u0631\u062f\u0647-\u062e\u0648\u0634\u0645\u0632\u0647-\u062f\u0631-5-\u0645\u0631\u062d\u0644\u0647-300x280.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%DA%AF%D9%88%D8%B4%D8%AA_%DA%86%D8%B1%D8%AE%E2%80%8C%DA%A9%D8%B1%D8%AF%D9%87_%D8%A8%D9%87_%DB%B2_%D8%B1%D9%88%D8%B4\"><\/span>\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647 \u0628\u0647 \u06f2 \u0631\u0648\u0634<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u0633\u0646\u06a9 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647 \u06cc\u06a9 \u062e\u0648\u0631\u0627\u06a9\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0633\u0631\u0627\u0633\u0631 \u062c\u0647\u0627\u0646 \u0637\u0631\u0641\u062f\u0627\u0631\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631\u06cc \u062f\u0627\u0631\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628\u060c \u062f\u0648 \u0631\u0648\u0634 \u0645\u062e\u062a\u0644\u0641 \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u06cc\u0646 \u0627\u0633\u0646\u06a9 \u0631\u0627 \u0628\u0647 \u0634\u0645\u0627 \u0622\u0645\u0648\u0632\u0634 \u062e\u0648\u0627\u0647\u06cc\u0645 \u062f\u0627\u062f. \u0627\u06af\u0631 \u062f\u0633\u062a\u06af\u0627\u0647 \u0633\u0627\u0646\u062f\u0648\u06cc\u0686\u200c\u0633\u0627\u0632 \u06cc\u0627 \u062a\u0648\u0633\u062a\u0631 \u0646\u062f\u0627\u0631\u06cc\u062f\u060c \u0646\u06af\u0631\u0627\u0646 \u0646\u0628\u0627\u0634\u06cc\u062f\u061b \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u062a\u0627\u0628\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f\u0647 \u0648 \u0627\u06cc\u0646 \u0627\u0633\u0646\u06a9 \u0644\u0630\u06cc\u0630 \u0631\u0627 \u062f\u0631 \u062e\u0627\u0646\u0647 \u0622\u0645\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D9%88%D8%A7%D8%AF_%D9%84%D8%A7%D8%B2%D9%85_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%DA%AF%D9%88%D8%B4%D8%AA_%DA%86%D8%B1%D8%AE%E2%80%8C%DA%A9%D8%B1%D8%AF%D9%87\"><\/span>\u0645\u0648\u0627\u062f \u0644\u0627\u0632\u0645 \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>\u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647: \u06f4\u06f0\u06f0 \u06af\u0631\u0645<\/li>\n<li>\u0633\u06cc\u0628\u200c\u0632\u0645\u06cc\u0646\u06cc: \u06f4 \u0639\u062f\u062f<\/li>\n<li>\u0642\u0627\u0631\u0686: \u06f2\u06f0\u06f0 \u06af\u0631\u0645<\/li>\n<li>\u067e\u06cc\u0627\u0632: \u06f1 \u0639\u062f\u062f<\/li>\n<li>\u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647\u200c\u0627\u06cc: \u06f1 \u0639\u062f\u062f<\/li>\n<li>\u0646\u0627\u0646 \u062a\u0633\u062a: \u06f1\u06f2 \u0639\u062f\u062f<\/li>\n<li>\u0631\u0628 \u06af\u0648\u062c\u0647\u200c\u0641\u0631\u0646\u06af\u06cc: \u06f1 \u0642\u0627\u0634\u0642 \u063a\u0630\u0627\u062e\u0648\u0631\u06cc<\/li>\n<li>\u0633\u0633 \u06a9\u0686\u0627\u067e: \u0628\u0647 \u0645\u0642\u062f\u0627\u0631 \u062f\u0644\u062e\u0648\u0627\u0647<\/li>\n<li>\u067e\u0646\u06cc\u0631 \u067e\u06cc\u062a\u0632\u0627 \u06cc\u0627 \u067e\u0646\u06cc\u0631 \u06af\u0648\u062f\u0627: \u0628\u0647 \u0645\u0642\u062f\u0627\u0631 \u0644\u0627\u0632\u0645<\/li>\n<li>\u0646\u0645\u06a9 \u0648 \u0641\u0644\u0641\u0644 \u0633\u06cc\u0627\u0647: \u0628\u0647 \u0645\u0642\u062f\u0627\u0631 \u0644\u0627\u0632\u0645<\/li>\n<li>\u0632\u0631\u062f\u0686\u0648\u0628\u0647\u060c \u067e\u0648\u062f\u0631 \u0633\u06cc\u0631 \u0648 \u0622\u0648\u06cc\u0634\u0646: \u0647\u0631 \u06a9\u062f\u0627\u0645 \u00bc \u0642\u0627\u0634\u0642 \u0686\u0627\u06cc\u200c\u062e\u0648\u0631\u06cc<\/li>\n<li>\u0631\u0648\u063a\u0646 \u06cc\u0627 \u06a9\u0631\u0647: \u0628\u0647 \u0645\u0642\u062f\u0627\u0631 \u0644\u0627\u0632\u0645<\/li>\n<\/ul>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%DA%AF%D9%88%D8%B4%D8%AA_%DA%86%D8%B1%D8%AE%E2%80%8C%DA%A9%D8%B1%D8%AF%D9%87_%D8%B1%D9%88%D8%B4_%D8%A7%D9%88%D9%84\"><\/span>\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647 (\u0631\u0648\u0634 \u0627\u0648\u0644)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ol>\n<li><strong>\u0622\u0645\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc \u0633\u06cc\u0628\u200c\u0632\u0645\u06cc\u0646\u06cc<\/strong>: \u0627\u0628\u062a\u062f\u0627 \u0633\u06cc\u0628\u200c\u0632\u0645\u06cc\u0646\u06cc\u200c\u0647\u0627 \u0631\u0627 \u0622\u0628\u200c\u067e\u0632 \u06a9\u0631\u062f\u0647 \u0648 \u0633\u067e\u0633 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u067e\u0648\u0631\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u06af\u0631 \u0633\u06cc\u0628\u200c\u0632\u0645\u06cc\u0646\u06cc \u0633\u0631\u062e\u200c\u0634\u062f\u0647 \u0631\u0627 \u062a\u0631\u062c\u06cc\u062d \u0645\u06cc\u200c\u062f\u0647\u06cc\u062f\u060c \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647\u200c\u0635\u0648\u0631\u062a \u0646\u06af\u06cc\u0646\u06cc \u062e\u0631\u062f \u06a9\u0631\u062f\u0647 \u0648 \u062f\u0631 \u0631\u0648\u063a\u0646 \u0633\u0631\u062e \u06a9\u0646\u06cc\u062f.<\/li>\n<li><strong>\u062a\u0641\u062a \u062f\u0627\u062f\u0646 \u0642\u0627\u0631\u0686<\/strong>: \u0642\u0627\u0631\u0686\u200c\u0647\u0627 \u0631\u0627 \u0634\u0633\u062a\u0647 \u0648 \u062e\u0634\u06a9 \u06a9\u0646\u06cc\u062f\u060c \u0633\u067e\u0633 \u0628\u0647 \u0635\u0648\u0631\u062a \u062e\u0644\u0627\u0644\u06cc \u0628\u0631\u0634 \u062f\u0647\u06cc\u062f. \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0627 \u06a9\u0645\u06cc \u06a9\u0631\u0647 \u06cc\u0627 \u0631\u0648\u063a\u0646 \u062f\u0631 \u062a\u0627\u0628\u0647 \u062a\u0641\u062a \u062f\u0647\u06cc\u062f. \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062a\u06cc\u0631\u0647 \u0634\u062f\u0646 \u0642\u0627\u0631\u0686\u200c\u0647\u0627\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0686\u0646\u062f \u0642\u0637\u0631\u0647 \u0622\u0628\u200c\u0644\u06cc\u0645\u0648 \u0628\u0647 \u0622\u0646\u200c\u0647\u0627 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f.<\/li>\n<li><strong>\u062a\u0641\u062a \u062f\u0627\u062f\u0646 \u06af\u0648\u0634\u062a<\/strong>: \u067e\u06cc\u0627\u0632 \u0631\u0627 \u062e\u0631\u062f \u06cc\u0627 \u0631\u0646\u062f\u0647 \u06a9\u0631\u062f\u0647 \u0648 \u062f\u0631 \u06a9\u0645\u06cc \u0631\u0648\u063a\u0646 \u062a\u0641\u062a \u062f\u0647\u06cc\u062f \u062a\u0627 \u0637\u0644\u0627\u06cc\u06cc \u0634\u0648\u062f. \u0633\u067e\u0633 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647 \u0631\u0627 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0622\u0646 \u0631\u0627 \u062a\u0627 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0631\u0646\u06af\u0634 \u062a\u063a\u06cc\u06cc\u0631 \u06a9\u0646\u062f\u060c \u062a\u0641\u062a \u062f\u0647\u06cc\u062f.<\/li>\n<li><strong>\u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f\u0646 \u0627\u062f\u0648\u06cc\u0647 \u0648 \u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647\u200c\u0627\u06cc<\/strong>: \u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647\u200c\u0627\u06cc \u062e\u0631\u062f\u0634\u062f\u0647 \u0631\u0627 \u0628\u0647 \u06af\u0648\u0634\u062a \u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f\u0647 \u0648 \u0646\u0645\u06a9\u060c \u0641\u0644\u0641\u0644 \u0633\u06cc\u0627\u0647\u060c \u0632\u0631\u062f\u0686\u0648\u0628\u0647\u060c \u067e\u0648\u062f\u0631 \u0622\u0648\u06cc\u0634\u0646 \u0648 \u0633\u06cc\u0631 \u0631\u0627 \u0647\u0645 \u0628\u0647 \u0622\u0646 \u0628\u06cc\u0641\u0632\u0627\u06cc\u06cc\u062f. \u0633\u067e\u0633 \u0631\u0628 \u06af\u0648\u062c\u0647\u200c\u0641\u0631\u0646\u06af\u06cc \u0631\u0627 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0645\u0648\u0627\u062f \u0631\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0647\u0645 \u0628\u0632\u0646\u06cc\u062f.<\/li>\n<li><strong>\u0645\u062e\u0644\u0648\u0637 \u06a9\u0631\u062f\u0646 \u0645\u0648\u0627\u062f<\/strong>: \u067e\u0633 \u0627\u0632 \u062a\u0641\u062a \u062f\u0627\u062f\u0646 \u0645\u0648\u0627\u062f\u060c \u0633\u06cc\u0628\u200c\u0632\u0645\u06cc\u0646\u06cc \u067e\u0648\u0631\u0647\u200c\u0634\u062f\u0647 \u0648 \u0642\u0627\u0631\u0686 \u0633\u0631\u062e\u200c\u0634\u062f\u0647 \u0631\u0627 \u0628\u0647 \u0645\u062e\u0644\u0648\u0637 \u06af\u0648\u0634\u062a \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f. \u0647\u0645\u0647 \u0645\u0648\u0627\u062f \u0631\u0627 \u0628\u0647\u200c\u062e\u0648\u0628\u06cc \u062a\u0631\u06a9\u06cc\u0628 \u06a9\u0631\u062f\u0647 \u0648 \u0627\u062c\u0627\u0632\u0647 \u062f\u0647\u06cc\u062f \u0628\u0647 \u0645\u062f\u062a \u0686\u0646\u062f \u062f\u0642\u06cc\u0642\u0647 \u0631\u0648\u06cc \u062d\u0631\u0627\u0631\u062a \u0645\u0644\u0627\u06cc\u0645 \u0628\u067e\u0632\u0646\u062f \u062a\u0627 \u0637\u0639\u0645\u200c\u0647\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0628\u0627 \u0647\u0645 \u062a\u0631\u06a9\u06cc\u0628 \u0634\u0648\u0646\u062f.<\/li>\n<li><strong>\u0686\u06cc\u062f\u0646 \u0627\u0633\u0646\u06a9<\/strong>: \u0646\u0627\u0646 \u062a\u0633\u062a \u0631\u0627 \u0622\u0645\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0628\u0631 \u0631\u0648\u06cc \u0622\u0646 \u0645\u0642\u062f\u0627\u0631\u06cc \u0633\u0633 \u06a9\u0686\u0627\u067e \u0628\u0631\u06cc\u0632\u06cc\u062f. \u0633\u067e\u0633 \u067e\u0646\u06cc\u0631 \u067e\u06cc\u062a\u0632\u0627 \u0631\u0627 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f\u0647 \u0648 \u0627\u0632 \u0645\u062e\u0644\u0648\u0637 \u06af\u0648\u0634\u062a \u0648 \u0633\u0628\u0632\u06cc\u062c\u0627\u062a \u0631\u0648\u06cc \u0646\u0627\u0646 \u0628\u0631\u06cc\u0632\u06cc\u062f. \u06cc\u06a9 \u0644\u0627\u06cc\u0647 \u062f\u06cc\u06af\u0631 \u067e\u0646\u06cc\u0631 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f\u0647 \u0648 \u06cc\u06a9 \u0646\u0627\u0646 \u062a\u0633\u062a \u062f\u06cc\u06af\u0631 \u0631\u0648\u06cc \u0622\u0646 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f.<\/li>\n<li><strong>\u06af\u0631\u06cc\u0644 \u06a9\u0631\u062f\u0646 \u0627\u0633\u0646\u06a9<\/strong>: \u0627\u0633\u0646\u06a9\u200c\u0647\u0627 \u0631\u0627 \u062f\u0631\u0648\u0646 \u0633\u0627\u0646\u062f\u0648\u06cc\u0686\u200c\u0633\u0627\u0632 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f \u0648 \u062f\u0633\u062a\u06af\u0627\u0647 \u0631\u0627 \u0631\u0648\u0634\u0646 \u06a9\u0646\u06cc\u062f. \u0635\u0628\u0631 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0646\u0627\u0646 \u062a\u0633\u062a\u200c\u0647\u0627 \u0637\u0644\u0627\u06cc\u06cc \u0648 \u067e\u0646\u06cc\u0631 \u0622\u0628 \u0634\u0648\u062f. \u0627\u06af\u0631 \u062f\u0633\u062a\u06af\u0627\u0647 \u0646\u062f\u0627\u0631\u06cc\u062f\u060c \u0627\u0632 \u062a\u0627\u0628\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0627\u0633\u0646\u06a9\u200c\u0647\u0627 \u0631\u0627 \u0628\u0627 \u06cc\u06a9 \u062c\u0633\u0645 \u0633\u0646\u06af\u06cc\u0646 \u0631\u0648\u06cc \u062d\u0631\u0627\u0631\u062a \u0645\u0644\u0627\u06cc\u0645 \u0628\u067e\u0632\u06cc\u062f \u062a\u0627 \u062a\u0631\u062f \u0634\u0648\u0646\u062f.<\/li>\n<\/ol>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%B2_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%DA%AF%D9%88%D8%B4%D8%AA_%DA%86%D8%B1%D8%AE%E2%80%8C%DA%A9%D8%B1%D8%AF%D9%87_%D8%B1%D9%88%D8%B4_%D8%AF%D9%88%D9%85\"><\/span>\u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647 (\u0631\u0648\u0634 \u062f\u0648\u0645)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0631\u0648\u0634\u060c \u0627\u0633\u0646\u06a9\u200c\u0647\u0627 \u0631\u0627 \u0628\u062f\u0648\u0646 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u062f\u0633\u062a\u06af\u0627\u0647 \u0633\u0627\u0646\u062f\u0648\u06cc\u0686\u200c\u0633\u0627\u0632 \u0648 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062a\u0627\u0628\u0647 \u062a\u0647\u06cc\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645:<\/p>\n<ol>\n<li><strong>\u067e\u062e\u062a \u0645\u0648\u0627\u062f<\/strong>: \u062a\u0645\u0627\u0645\u06cc \u0645\u0631\u0627\u062d\u0644 \u0622\u0645\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc \u0645\u0648\u0627\u062f \u0645\u0627\u0646\u0646\u062f \u0631\u0648\u0634 \u0627\u0648\u0644 \u0627\u0633\u062a\u061b \u0628\u0627 \u0627\u06cc\u0646 \u062a\u0641\u0627\u0648\u062a \u06a9\u0647 \u067e\u0633 \u0627\u0632 \u0622\u0645\u0627\u062f\u0647\u200c\u0633\u0627\u0632\u06cc \u0627\u0633\u0646\u06a9\u200c\u0647\u0627\u060c \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647 \u062c\u0627\u06cc \u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0646 \u062f\u0631 \u062f\u0633\u062a\u06af\u0627\u0647\u060c \u062f\u0631 \u06cc\u06a9 \u062a\u0627\u0628\u0647 \u06af\u0631\u0645 \u0628\u0627 \u0645\u0642\u062f\u0627\u0631 \u06a9\u0645\u06cc \u0631\u0648\u063a\u0646 \u0628\u067e\u0632\u06cc\u062f.<\/li>\n<li><strong>\u067e\u062e\u062a \u062f\u0631 \u062a\u0627\u0628\u0647<\/strong>: \u0627\u0633\u0646\u06a9\u200c\u0647\u0627 \u0631\u0627 \u062f\u0631 \u062a\u0627\u0628\u0647 \u0628\u0686\u06cc\u0646\u06cc\u062f \u0648 \u0628\u0627 \u06cc\u06a9 \u062c\u0633\u0645 \u0633\u0646\u06af\u06cc\u0646 (\u0645\u0627\u0646\u0646\u062f \u0628\u0634\u0642\u0627\u0628) \u06a9\u0647 \u062f\u0627\u062e\u0644 \u0641\u0648\u06cc\u0644 \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0634\u062f\u0647\u060c \u0631\u0648\u06cc \u0622\u0646\u200c\u0647\u0627 \u0641\u0634\u0627\u0631 \u062f\u0647\u06cc\u062f. \u0627\u0633\u0646\u06a9\u200c\u0647\u0627 \u0631\u0627 \u0628\u0631\u0627\u06cc \u06f5 \u062a\u0627 \u06f7 \u062f\u0642\u06cc\u0642\u0647 \u0633\u0631\u062e \u06a9\u0646\u06cc\u062f \u062a\u0627 \u06cc\u06a9 \u0637\u0631\u0641 \u0622\u0646\u200c\u0647\u0627 \u0637\u0644\u0627\u06cc\u06cc \u0634\u0648\u062f. \u0633\u067e\u0633 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0631\u06af\u0631\u062f\u0627\u0646\u06cc\u062f \u062a\u0627 \u0637\u0631\u0641 \u062f\u06cc\u06af\u0631 \u0646\u06cc\u0632 \u0633\u0631\u062e \u0634\u0648\u062f.<\/li>\n<li><strong>\u0633\u0631\u0648 \u0646\u0647\u0627\u06cc\u06cc<\/strong>: \u067e\u0633 \u0627\u0632 \u0637\u0644\u0627\u06cc\u06cc \u0634\u062f\u0646 \u0647\u0631 \u062f\u0648 \u0637\u0631\u0641 \u0627\u0633\u0646\u06a9\u200c\u0647\u0627\u060c \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0627\u0632 \u062a\u0627\u0628\u0647 \u062e\u0627\u0631\u062c \u06a9\u0631\u062f\u0647 \u0648 \u0628\u0627 \u0633\u0633 \u062e\u0631\u062f\u0644 \u06cc\u0627 \u0633\u0633 \u0641\u0631\u0627\u0646\u0633\u0648\u06cc \u0633\u0631\u0648 \u06a9\u0646\u06cc\u062f.<\/li>\n<\/ol>\n<hr \/>\n<h3><span class=\"ez-toc-section\" id=\"%D9%86%DA%A9%D8%A7%D8%AA_%D9%85%D9%87%D9%85_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D9%87%DB%8C%D9%87_%D8%A7%D8%B3%D9%86%DA%A9_%DA%AF%D9%88%D8%B4%D8%AA_%DA%86%D8%B1%D8%AE%E2%80%8C%DA%A9%D8%B1%D8%AF%D9%87\"><\/span>\u0646\u06a9\u0627\u062a \u0645\u0647\u0645 \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u0633\u0646\u06a9 \u06af\u0648\u0634\u062a \u0686\u0631\u062e\u200c\u06a9\u0631\u062f\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0633\u06cc\u0628\u200c\u0632\u0645\u06cc\u0646\u06cc \u0648 \u0642\u0627\u0631\u0686 \u06a9\u0627\u0645\u0644\u0627\u064b \u0627\u062e\u062a\u06cc\u0627\u0631\u06cc \u0627\u0633\u062a\u060c \u0627\u0645\u0627 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f\u0646 \u0622\u0646\u200c\u0647\u0627 \u0627\u0631\u0632\u0634 \u063a\u0630\u0627\u06cc\u06cc \u0627\u0633\u0646\u06a9 \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f.<\/li>\n<li>\u0628\u0631\u0627\u06cc \u0637\u0639\u0645 \u0628\u0647\u062a\u0631\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u062f\u0648\u0631 \u0646\u0627\u0646 \u062a\u0633\u062a \u0631\u0627 \u0628\u0631\u0634 \u062f\u0647\u06cc\u062f \u0648 \u0627\u0632 \u067e\u0646\u06cc\u0631\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0645\u0627\u0646\u0646\u062f \u067e\u0646\u06cc\u0631 \u06af\u0648\u062f\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0686\u0633\u0628\u06cc\u062f\u0646 \u0627\u0633\u0646\u06a9 \u0628\u0647 \u062f\u0633\u062a\u06af\u0627\u0647 \u06cc\u0627 \u062a\u0627\u0628\u0647\u060c \u06a9\u0641 \u0622\u0646 \u0631\u0627 \u06a9\u0645\u06cc \u0686\u0631\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<\/ul>\n<p>\u0628\u0627 \u0627\u06cc\u0646 \u0631\u0648\u0634\u200c\u0647\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0633\u0646\u06a9\u06cc \u062e\u0648\u0634\u0645\u0632\u0647 \u0648 \u0645\u0642\u0648\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u062f \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647\u200c\u062a\u0627\u0646 \u062a\u0647\u06cc\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0627\u0632 \u0637\u0639\u0645 \u0644\u0630\u06cc\u0630 \u0622\u0646 \u0644\u0630\u062a \u0628\u0628\u0631\u06cc\u062f!<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AC%D9%85%D8%B9_%D8%A8%D9%86%D8%AF%DB%8C\"><\/span>\u062c\u0645\u0639 \u0628\u0646\u062f\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 <a href=\"\/mag\/\u0637\u0631\u0632-\u062a\u0647\u06cc\u0647-\u0627\u0633\u0646\u06a9-\u0633\u0627\u062f\u0647-\u0648-\u062e\u0648\u0634\u0645\u0632\u0647\"><strong>\u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647<\/strong><\/a>\u00a0\u067e\u0646\u06cc\u0631\u06cc \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0627\u0632 \u0646\u0627\u0646 \u062a\u0633\u062a \u06cc\u0627 \u0646\u0627\u0646 \u0628\u0627\u06af\u062a \u067e\u0647\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u06a9\u0647 \u0622\u0645\u0627\u062f\u0647 \u06a9\u0631\u062f\u0646 \u0627\u06cc\u0646 \u0645\u06cc\u0627\u0646 \u0648\u0639\u062f\u0647 \u0632\u0645\u0627\u0646 \u0632\u06cc\u0627\u062f\u06cc \u0627\u0632 \u0634\u0645\u0627 \u0646\u0645\u06cc \u06af\u06cc\u0631\u062f\u060c \u06af\u0632\u06cc\u0646\u0647 \u062e\u0648\u0628\u06cc \u0628\u0631\u0627\u06cc \u062f\u0648\u0631\u0647\u0645\u06cc \u0647\u0627\u06cc \u062f\u0648\u0633\u062a\u0627\u0646\u0647 \u0648 \u0645\u0647\u0645\u0627\u0646\u06cc \u0647\u0627\u06cc \u06a9\u0648\u0686\u06a9 \u0627\u0633\u062a. \u062f\u0631 \u0635\u0648\u0631\u062a \u062f\u0644\u062e\u0648\u0627\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0633\u0646\u06a9 \u0631\u0627 \u0641\u0642\u0637 \u0628\u0627 \u0645\u0648\u0627\u062f \u06af\u06cc\u0627\u0647\u06cc \u0645\u0627\u0646\u0646\u062f \u0642\u0627\u0631\u0686\u060c \u0630\u0631\u062a\u060c \u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647 \u0627\u06cc \u0648 \u067e\u0646\u06cc\u0631 \u067e\u06cc\u062a\u0632\u0627 \u062f\u0631\u0633\u062a \u06a9\u0646\u06cc\u062f. \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0644\u06cc \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u0646\u0648\u0627\u0639 \u0627\u0633\u0646\u06a9\u060c \u0647\u06cc\u0686 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a\u06cc \u062f\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u0646\u062f\u0627\u0631\u06cc\u062f.<\/p>\n<p>\u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646 \u0645\u0642\u0627\u0644\u0627\u062a \u0628\u06cc\u0634\u062a\u0631 \u062f\u0631 \u0645\u0648\u0631\u062f \u0637\u0631\u0632 \u062a\u0647\u06cc\u0647 \u0627\u0646\u0648\u0627\u0639 \u0627\u0633\u0646\u06a9\u060c \u0645\u0642\u0627\u0644\u0627\u062a \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u062f\u0631 \u062f\u06a9\u0648\u0631\u0634\u0627\u067e \u0631\u0627 \u0645\u0637\u0627\u0644\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0645\u062d\u0628\u0648\u0628 \u062a\u0631\u06cc\u0646 \u0648 \u062e\u0648\u0634\u0645\u0632\u0647 \u062a\u0631\u06cc\u0646 \u063a\u0630\u0627\u0647\u0627\u06cc \u0641\u0633\u062a \u0641\u0648\u062f \u06a9\u0647 \u0622\u0645\u0627\u062f\u0647 \u06a9\u0631\u062f\u0646 \u0622\u0646 \u0632\u0645\u0627\u0646 \u0632\u06cc\u0627\u062f\u06cc \u0646\u0645\u06cc \u0628\u0631\u062f\u060c \u0627\u0633\u0646\u06a9 \u0633\u0627\u062f\u0647 \u0627\u0633\u062a. \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0644\u06cc \u0627\u0633\u0646\u06a9 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u06cc\u0627\u0646 \u0648\u0639\u062f\u0647 \u0647\u0627\u06cc \u067e\u0631\u0637\u0631\u0641\u062f\u0627\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646 \u062f\u0631 \u06a9\u0645\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0645\u0645\u06a9\u0646 \u0628\u0627 \u062a\u0631\u06a9\u06cc\u0628 \u0645\u0648\u0627\u062f \u0645\u062e\u062a\u0644\u0641 \u0622\u0646 \u0631\u0627 \u062a\u0647\u06cc\u0647 \u06a9\u0631\u062f. \u0627\u06cc\u0646 \u0641\u0633\u062a \u0641\u0648\u062f \u062e\u0648\u0634\u0645\u0632\u0647 \u0631\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0637\u0628\u0642 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":46100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[690,688],"tags":[],"class_list":["post-46095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-690","category-688"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/46095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=46095"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/46095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/46100"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=46095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=46095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=46095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}