{"id":44336,"date":"2024-04-20T12:45:54","date_gmt":"2024-04-20T09:15:54","guid":{"rendered":"https:\/\/decorshop.ir\/mag\/?p=44336"},"modified":"2024-04-20T12:45:54","modified_gmt":"2024-04-20T09:15:54","slug":"%d8%ac%d8%af%db%8c%d8%af%d8%aa%d8%b1%db%8c%d9%86-%d8%b1%d8%a7%d9%87%da%a9%d8%a7%d8%b1%d9%87%d8%a7%db%8c-%d8%ac%d8%b0%d8%a8-%d9%85%d8%b4%d8%aa%d8%b1%db%8c-%da%a9%d8%a7%d8%a8%db%8c%d9%86%d8%aa%d8%9b","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d8%ac%d8%af%db%8c%d8%af%d8%aa%d8%b1%db%8c%d9%86-%d8%b1%d8%a7%d9%87%da%a9%d8%a7%d8%b1%d9%87%d8%a7%db%8c-%d8%ac%d8%b0%d8%a8-%d9%85%d8%b4%d8%aa%d8%b1%db%8c-%da%a9%d8%a7%d8%a8%db%8c%d9%86%d8%aa%d8%9b\/","title":{"rendered":"\u062c\u062f\u06cc\u062f\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc \u06a9\u0627\u0628\u06cc\u0646\u062a\u061b \u06f7 \u062a\u06a9\u0646\u06cc\u06a9 \u0645\u0648\u062b\u0631"},"content":{"rendered":"<p>\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u0648 \u062f\u0627\u0634\u062a\u0646 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0648 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u067e\u06cc\u0627\u0645\u06a9\u06cc \u0627\u0632 \u062c\u0645\u0644\u0647 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u0648\u062b\u0631 \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0641\u0631\u0648\u0634 \u0647\u0633\u062a\u0646\u062f. \u0627\u0644\u0628\u062a\u0647 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631\u06cc \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0641\u0631\u0648\u0634 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f\u061b \u0627\u0645\u0627 \u062a\u0639\u062f\u0627\u062f\u06cc \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0647\u200c\u0627\u0646\u062f. \u0628\u0647\u200c\u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628\u060c \u062c\u062f\u06cc\u062f\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627 \u0648 \u06f7 \u062a\u06a9\u0646\u06cc\u06a9 \u0645\u0648\u062b\u0631 \u0628\u0631\u0627\u06cc \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc \u06a9\u0627\u0628\u06cc\u0646\u062a \u0631\u0627 \u0645\u0639\u0631\u0641\u06cc \u062e\u0648\u0627\u0647\u06cc\u0645 \u06a9\u0631\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u062a\u0648\u0636\u06cc\u062d\u0627\u062a\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u0647\u0645\u06cc\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627 \u062f\u0631 \u0628\u0631\u0642\u0631\u0627\u0631\u06cc \u0627\u0631\u062a\u0628\u0627\u0637 \u0648 \u062a\u0639\u0627\u0645\u0644 \u0645\u0648\u062b\u0631 \u0628\u0627 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631 \u0627\u0631\u0627\u0626\u0647 \u062e\u0648\u0627\u0647\u06cc\u0645 \u062f\u0627\u062f \u062a\u0627 \u0645\u0627\u0644\u06a9\u0627\u0646 \u0627\u06cc\u0646 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u062c\u0627\u0645\u0639\u0647 \u0628\u0632\u0631\u06af\u06cc \u0627\u0632 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0648\u0641\u0627\u062f\u0627\u0631 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d8%ac%d8%af%db%8c%d8%af%d8%aa%d8%b1%db%8c%d9%86-%d8%b1%d8%a7%d9%87%da%a9%d8%a7%d8%b1%d9%87%d8%a7%db%8c-%d8%ac%d8%b0%d8%a8-%d9%85%d8%b4%d8%aa%d8%b1%db%8c-%da%a9%d8%a7%d8%a8%db%8c%d9%86%d8%aa%d8%9b\/#%DB%B1-_%D8%B1%D8%A7%D9%87%E2%80%8C%D8%A7%D9%86%D8%AF%D8%A7%D8%B2%DB%8C_%D9%88_%D8%AF%D8%A7%D8%B4%D8%AA%D9%86_%D9%88%D8%A8%D8%B3%D8%A7%DB%8C%D8%AA_%D8%AD%D8%B1%D9%81%D9%87%E2%80%8C%D8%A7%DB%8C%D8%9B_%D8%B1%D8%A7%D9%87%DA%A9%D8%A7%D8%B1_%D9%85%D9%88%D8%AB%D8%B1_%D8%AC%D8%B0%D8%A8_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C\" >\u06f1- \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u0648 \u062f\u0627\u0634\u062a\u0646 \u0648\u0628\u0633\u0627\u06cc\u062a \u062d\u0631\u0641\u0647\u200c\u0627\u06cc\u061b \u0631\u0627\u0647\u06a9\u0627\u0631 \u0645\u0648\u062b\u0631 \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d8%ac%d8%af%db%8c%d8%af%d8%aa%d8%b1%db%8c%d9%86-%d8%b1%d8%a7%d9%87%da%a9%d8%a7%d8%b1%d9%87%d8%a7%db%8c-%d8%ac%d8%b0%d8%a8-%d9%85%d8%b4%d8%aa%d8%b1%db%8c-%da%a9%d8%a7%d8%a8%db%8c%d9%86%d8%aa%d8%9b\/#%DB%B2-_%D8%B3%D8%A6%D9%88_%D9%88_%D8%A8%D9%87%DB%8C%D9%86%D9%87%E2%80%8C%D8%B3%D8%A7%D8%B2%DB%8C_%D9%85%D9%88%D8%AA%D9%88%D8%B1%D9%87%D8%A7%DB%8C_%D8%AC%D8%B3%D8%AA%D8%AC%D9%88_%D8%A8%D9%87%E2%80%8C%D9%85%D9%86%D8%B8%D9%88%D8%B1_%D8%AF%D8%B3%D8%AA%D8%B1%D8%B3%DB%8C_%D8%A8%D9%87_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C%D8%A7%D9%86_%D9%87%D8%AF%D9%81\" >\u06f2- \u0633\u0626\u0648 \u0648 \u0628\u0647\u06cc\u0646\u0647\u200c\u0633\u0627\u0632\u06cc \u0645\u0648\u062a\u0648\u0631\u0647\u0627\u06cc \u062c\u0633\u062a\u062c\u0648 \u0628\u0647\u200c\u0645\u0646\u0638\u0648\u0631 \u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0647\u062f\u0641<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/%d8%ac%d8%af%db%8c%d8%af%d8%aa%d8%b1%db%8c%d9%86-%d8%b1%d8%a7%d9%87%da%a9%d8%a7%d8%b1%d9%87%d8%a7%db%8c-%d8%ac%d8%b0%d8%a8-%d9%85%d8%b4%d8%aa%d8%b1%db%8c-%da%a9%d8%a7%d8%a8%db%8c%d9%86%d8%aa%d8%9b\/#%DB%B3-_%D8%A7%D8%B2_%D8%AC%D9%85%D9%84%D9%87_%D8%B1%D8%A7%D9%87%DA%A9%D8%A7%D8%B1%D9%87%D8%A7%DB%8C_%D9%85%D9%88%D8%AB%D8%B1_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D8%B1%D8%BA%DB%8C%D8%A8_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C%D8%A7%D9%86_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1%DB%8C%D8%A7%D8%A8%DB%8C_%D9%BE%DB%8C%D8%A7%D9%85%DA%A9%DB%8C_%D8%A7%D8%B3%D8%AA\" >\u06f3- \u0627\u0632 \u062c\u0645\u0644\u0647 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u0648\u062b\u0631 \u0628\u0631\u0627\u06cc \u062a\u0631\u063a\u06cc\u0628 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u067e\u06cc\u0627\u0645\u06a9\u06cc \u0627\u0633\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/%d8%ac%d8%af%db%8c%d8%af%d8%aa%d8%b1%db%8c%d9%86-%d8%b1%d8%a7%d9%87%da%a9%d8%a7%d8%b1%d9%87%d8%a7%db%8c-%d8%ac%d8%b0%d8%a8-%d9%85%d8%b4%d8%aa%d8%b1%db%8c-%da%a9%d8%a7%d8%a8%db%8c%d9%86%d8%aa%d8%9b\/#%DB%B4-_%D8%A7%D9%87%D9%85%DB%8C%D8%AA_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1%DB%8C%D8%A7%D8%A8%DB%8C_%D9%85%D8%AD%D8%AA%D9%88%D8%A7_%D8%AF%D8%B1_%D8%AA%D8%B1%D8%BA%DB%8C%D8%A8_%D9%88_%D8%AC%D8%B0%D8%A8_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C%D8%A7%D9%86_%D8%AC%D8%AF%DB%8C%D8%AF\" >\u06f4- \u0627\u0647\u0645\u06cc\u062a \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u0645\u062d\u062a\u0648\u0627 \u062f\u0631 \u062a\u0631\u063a\u06cc\u0628 \u0648 \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062c\u062f\u06cc\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/decorshop.ir\/mag\/%d8%ac%d8%af%db%8c%d8%af%d8%aa%d8%b1%db%8c%d9%86-%d8%b1%d8%a7%d9%87%da%a9%d8%a7%d8%b1%d9%87%d8%a7%db%8c-%d8%ac%d8%b0%d8%a8-%d9%85%d8%b4%d8%aa%d8%b1%db%8c-%da%a9%d8%a7%d8%a8%db%8c%d9%86%d8%aa%d8%9b\/#%DB%B5-_%D8%A7%D8%B1%D8%B3%D8%A7%D9%84_%D9%BE%DB%8C%D8%A7%D9%85_%D8%AA%D8%A8%D9%84%DB%8C%D8%BA%D8%A7%D8%AA%DB%8C_%D8%A8%D9%87_%D9%85%D8%AE%D8%A7%D8%B7%D8%A8%D8%A7%D9%86_%D9%87%D8%AF%D9%81_%D8%A8%D8%A7_%DA%A9%D9%85%DA%A9_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1%DB%8C%D8%A7%D8%A8%DB%8C_%D8%A7%DB%8C%D9%85%DB%8C%D9%84%DB%8C\" >\u06f5- \u0627\u0631\u0633\u0627\u0644 \u067e\u06cc\u0627\u0645 \u062a\u0628\u0644\u06cc\u063a\u0627\u062a\u06cc \u0628\u0647 \u0645\u062e\u0627\u0637\u0628\u0627\u0646 \u0647\u062f\u0641 \u0628\u0627 \u06a9\u0645\u06a9 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u0627\u06cc\u0645\u06cc\u0644\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/decorshop.ir\/mag\/%d8%ac%d8%af%db%8c%d8%af%d8%aa%d8%b1%db%8c%d9%86-%d8%b1%d8%a7%d9%87%da%a9%d8%a7%d8%b1%d9%87%d8%a7%db%8c-%d8%ac%d8%b0%d8%a8-%d9%85%d8%b4%d8%aa%d8%b1%db%8c-%da%a9%d8%a7%d8%a8%db%8c%d9%86%d8%aa%d8%9b\/#%DB%B6-_%D9%81%D8%B9%D8%A7%D9%84%DB%8C%D8%AA_%D8%AF%D8%B1_%D8%B4%D8%A8%DA%A9%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D8%AC%D8%AA%D9%85%D8%A7%D8%B9%DB%8C%D8%9B_%D8%B1%D8%A7%D9%87%DA%A9%D8%A7%D8%B1%DB%8C_%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AC%D8%B0%D8%A8_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C_%DA%A9%D8%A7%D8%A8%DB%8C%D9%86%D8%AA\" >\u06f6- \u0641\u0639\u0627\u0644\u06cc\u062a \u062f\u0631 \u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc\u061b \u0631\u0627\u0647\u06a9\u0627\u0631\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0628\u0631\u0627\u06cc \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc \u06a9\u0627\u0628\u06cc\u0646\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/decorshop.ir\/mag\/%d8%ac%d8%af%db%8c%d8%af%d8%aa%d8%b1%db%8c%d9%86-%d8%b1%d8%a7%d9%87%da%a9%d8%a7%d8%b1%d9%87%d8%a7%db%8c-%d8%ac%d8%b0%d8%a8-%d9%85%d8%b4%d8%aa%d8%b1%db%8c-%da%a9%d8%a7%d8%a8%db%8c%d9%86%d8%aa%d8%9b\/#%DB%B7-_%D8%AB%D8%A8%D8%AA_%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%DA%A9%D8%B3%D8%A8%E2%80%8C%D9%88%DA%A9%D8%A7%D8%B1_%D8%AF%D8%B1_%DA%AF%D9%88%DA%AF%D9%84_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B3%D8%AA%D8%B1%D8%B3%DB%8C_%D8%A2%D8%B3%D8%A7%D9%86_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C%D8%A7%D9%86_%D8%A8%D9%87_%D8%A2%D9%86\" >\u06f7- \u062b\u0628\u062a \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631 \u062f\u0631 \u06af\u0648\u06af\u0644 \u0628\u0631\u0627\u06cc \u062f\u0633\u062a\u0631\u0633\u06cc \u0622\u0633\u0627\u0646 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0628\u0647 \u0622\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/decorshop.ir\/mag\/%d8%ac%d8%af%db%8c%d8%af%d8%aa%d8%b1%db%8c%d9%86-%d8%b1%d8%a7%d9%87%da%a9%d8%a7%d8%b1%d9%87%d8%a7%db%8c-%d8%ac%d8%b0%d8%a8-%d9%85%d8%b4%d8%aa%d8%b1%db%8c-%da%a9%d8%a7%d8%a8%db%8c%d9%86%d8%aa%d8%9b\/#%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D8%A7%D8%A8%D8%B2%D8%A7%D8%B1%D9%87%D8%A7%DB%8C_%D8%AA%D8%B9%D8%A7%D9%85%D9%84%DB%8C%D8%9B_%D8%AA%DA%A9%D9%86%DB%8C%DA%A9%DB%8C_%D9%85%D9%88%D8%AB%D8%B1_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AC%D8%B0%D8%A8_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C_%DA%A9%D8%A7%D8%A8%DB%8C%D9%86%D8%AA\" >\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u062a\u0639\u0627\u0645\u0644\u06cc\u061b \u062a\u06a9\u0646\u06cc\u06a9\u06cc \u0645\u0648\u062b\u0631 \u0628\u0631\u0627\u06cc \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc \u06a9\u0627\u0628\u06cc\u0646\u062a<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%DB%B1-_%D8%B1%D8%A7%D9%87%E2%80%8C%D8%A7%D9%86%D8%AF%D8%A7%D8%B2%DB%8C_%D9%88_%D8%AF%D8%A7%D8%B4%D8%AA%D9%86_%D9%88%D8%A8%D8%B3%D8%A7%DB%8C%D8%AA_%D8%AD%D8%B1%D9%81%D9%87%E2%80%8C%D8%A7%DB%8C%D8%9B_%D8%B1%D8%A7%D9%87%DA%A9%D8%A7%D8%B1_%D9%85%D9%88%D8%AB%D8%B1_%D8%AC%D8%B0%D8%A8_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C\"><\/span>\u06f1- \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u0648 \u062f\u0627\u0634\u062a\u0646 \u0648\u0628\u0633\u0627\u06cc\u062a \u062d\u0631\u0641\u0647\u200c\u0627\u06cc\u061b \u0631\u0627\u0647\u06a9\u0627\u0631 \u0645\u0648\u062b\u0631 \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u0627\u0648\u0644\u06cc\u0646 \u0648 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u06a9\u0627\u0646\u0627\u0644 \u0627\u0631\u062a\u0628\u0627\u0637\u06cc \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0628\u0627 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0627\u0633\u062a. \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u060c \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0628\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0641\u06cc\u062f \u0648 \u0627\u0631\u0632\u0634\u0645\u0646\u062f\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631 \u062f\u0633\u062a\u0631\u0633\u06cc \u062e\u0648\u0627\u0647\u0646\u062f \u062f\u0627\u0634\u062a \u06a9\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639\u060c \u0628\u0633\u06cc\u0627\u0631 \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0622\u06af\u0627\u0647\u06cc \u0627\u0632 \u0628\u0631\u0646\u062f \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0628\u0627 \u0645\u0627\u0647\u06cc\u062a \u0627\u0635\u0644\u06cc \u0641\u0639\u0627\u0644\u06cc\u062a \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u060c \u0628\u06cc\u0634\u062a\u0631 \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u060c \u0648\u06cc\u062a\u0631\u06cc\u0646 \u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0631\u0627\u06cc \u0646\u0645\u0627\u06cc\u0634 \u0646\u0645\u0648\u0646\u0647\u200c\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u0648\u0641\u0642 \u0646\u06cc\u0632 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f\u061b \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u062a\u0627\u062b\u06cc\u0631\u06cc \u0645\u062b\u0628\u062a\u06cc \u062f\u0631 \u062c\u0644\u0628 \u0627\u0639\u062a\u0645\u0627\u062f \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a.<\/p>\n<p>\u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u0627\u0632 \u062c\u0646\u0628\u0647 \u062f\u06cc\u06af\u0631\u06cc \u062d\u06a9\u0645 \u06cc\u06a9 \u0645\u0647\u0631\u0647 \u0645\u0647\u0645 \u062f\u0631 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc \u06a9\u0627\u0628\u06cc\u0646\u062a \u0631\u0627 \u062f\u0627\u0631\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u0645\u0627\u0644\u06a9 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u06cc \u06a9\u0647 \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0641\u0631\u0648\u0634 \u06a9\u0627\u0628\u06cc\u0646\u062a \u0641\u0639\u0627\u0644\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0627\u06af\u0631 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u0645\u0634\u062a\u0631\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u062c\u0630\u0628 \u06a9\u0646\u06cc\u062f \u06cc\u0627 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0648\u0641\u0627\u062f\u0627\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u060c \u0637\u0631\u0627\u062d\u06cc \u06a9\u0627\u0631\u0628\u0631\u067e\u0633\u0646\u062f \u0633\u0627\u06cc\u062a\u060c \u0627\u0645\u0631\u06cc \u062d\u06cc\u0627\u062a\u06cc \u0627\u0633\u062a. \u0632\u06cc\u0631\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0622\u0646 \u0628\u0631\u0627\u06cc \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0622\u0633\u0627\u0646 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f \u0648 \u062f\u0639\u0648\u062a \u0628\u0647 \u0627\u0642\u062f\u0627\u0645\u200c\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628\u06cc \u062f\u0631 \u0635\u0641\u062d\u0627\u062a \u0645\u062e\u062a\u0644\u0641 \u0633\u0627\u06cc\u062a \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0645\u0632\u06cc\u062a \u062f\u06cc\u06af\u0631 \u062f\u0627\u0634\u062a\u0646 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u060c \u0645\u0634\u0627\u0647\u062f\u0647 \u062f\u0642\u06cc\u0642 \u062a\u0639\u062f\u0627\u062f \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0648 \u062f\u0631\u06cc\u0627\u0641\u062a \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062f\u0642\u06cc\u0642 \u0622\u0646\u200c\u0647\u0627 \u0627\u0633\u062a \u0628\u0647\u200c\u0639\u0644\u0627\u0648\u0647\u060c \u0628\u0627 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062f\u0627\u0634\u062a\u0646 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0628\u0627\u0644\u0642\u0648\u0647\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0637\u0631\u06cc\u0642 <a href=\"https:\/\/farazsms.com\/\" target=\"_blank\" rel=\"noopener\">\u067e\u0646\u0644 \u0627\u0631\u0633\u0627\u0644 \u067e\u06cc\u0627\u0645\u06a9<\/a> \u0628\u0631\u0627\u0633\u0627\u0633 \u0633\u0646 \u0648 \u0645\u062d\u062f\u0648\u062f\u0647 \u062c\u063a\u0631\u0627\u0641\u06cc\u0627\u06cc\u06cc\u060c \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u067e\u06cc\u0627\u0645\u06a9 \u062a\u0628\u0644\u06cc\u063a\u0627\u062a\u06cc \u0627\u0631\u0633\u0627\u0644 \u0648 \u0628\u0627 \u0627\u06cc\u0646 \u06a9\u0627\u0631\u060c \u0633\u0627\u06cc\u062a \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u062a\u0627\u0646 \u0631\u0627 \u0628\u0647 \u0627\u0641\u0631\u0627\u062f \u0628\u06cc\u0634\u062a\u0631\u06cc \u0645\u0639\u0631\u0641\u06cc \u06a9\u0646\u06cc\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%DB%B2-_%D8%B3%D8%A6%D9%88_%D9%88_%D8%A8%D9%87%DB%8C%D9%86%D9%87%E2%80%8C%D8%B3%D8%A7%D8%B2%DB%8C_%D9%85%D9%88%D8%AA%D9%88%D8%B1%D9%87%D8%A7%DB%8C_%D8%AC%D8%B3%D8%AA%D8%AC%D9%88_%D8%A8%D9%87%E2%80%8C%D9%85%D9%86%D8%B8%D9%88%D8%B1_%D8%AF%D8%B3%D8%AA%D8%B1%D8%B3%DB%8C_%D8%A8%D9%87_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C%D8%A7%D9%86_%D9%87%D8%AF%D9%81\"><\/span>\u06f2- \u0633\u0626\u0648 \u0648 \u0628\u0647\u06cc\u0646\u0647\u200c\u0633\u0627\u0632\u06cc \u0645\u0648\u062a\u0648\u0631\u0647\u0627\u06cc \u062c\u0633\u062a\u062c\u0648 \u0628\u0647\u200c\u0645\u0646\u0638\u0648\u0631 \u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0647\u062f\u0641<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0645\u0631\u0648\u0631\u06af\u0631\u0647\u0627 \u0627\u0628\u0632\u0627\u0631 \u0627\u0635\u0644\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0628\u0631\u0627\u06cc \u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a \u0647\u0633\u062a\u0646\u062f \u0648 \u0645\u0648\u062a\u0648\u0631\u0647\u0627\u06cc \u062c\u0633\u062a\u062c\u0648 \u0645\u0627\u0646\u0646\u062f \u06af\u0648\u06af\u0644 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647 \u0633\u0645\u062a \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0647\u062f\u0627\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0627\u0645\u0627 \u0628\u0627\u0648\u062c\u0648\u062f \u0627\u0646\u0628\u0648\u0647\u06cc \u0639\u0646\u0648\u0627\u0646 \u0633\u0627\u06cc\u062a \u062f\u0631 \u0635\u0641\u062d\u0647 \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648\u060c \u0633\u0627\u06cc\u062a\u06cc\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u0627\u0648\u0644 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f \u06a9\u0647 \u0631\u062a\u0628\u0647 \u0648 \u062c\u0627\u06cc\u06af\u0627\u0647 \u0645\u0646\u0627\u0633\u0628\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u0633\u0626\u0648 \u0648 \u0628\u0647\u06cc\u0646\u0647\u200c\u0633\u0627\u0632\u06cc \u0645\u0648\u062a\u0648\u0631\u0647\u0627\u06cc \u062c\u0633\u062a\u062c\u0648 \u0627\u0632 \u062c\u0645\u0644\u0647 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u0648\u062b\u0631 \u0628\u0631\u0627\u06cc \u06a9\u0633\u0628 \u062c\u0627\u06cc\u06af\u0627\u0647 \u0645\u0646\u0627\u0633\u0628 \u062f\u0631 \u0635\u0641\u062d\u0647 \u0646\u062a\u0627\u06cc\u062c \u06af\u0648\u06af\u0644 \u0627\u0633\u062a. \u0628\u0627 \u06a9\u0645\u06a9 \u0633\u0626\u0648\u060c \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u06a9\u0647 \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u06a9\u0631\u062f\u0647\u200c\u0627\u06cc\u062f \u062f\u0631 \u06cc\u06a9 \u06a9\u0644\u0645\u0647 \u06a9\u0644\u06cc\u062f\u06cc \u0645\u0634\u062e\u0635 \u0648 \u0645\u0631\u062a\u0628\u0637 \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u062d\u0648\u0632\u0647 \u0641\u0639\u0627\u0644\u06cc\u062a \u0634\u0645\u0627\u060c \u0631\u062a\u0628\u0647 \u0645\u0646\u0627\u0633\u0628\u06cc \u062f\u0631 \u0635\u0641\u062d\u0647 \u0646\u062a\u0627\u06cc\u062c \u0628\u0647\u200c\u062f\u0633\u062a \u0645\u06cc\u200c\u0622\u0648\u0631\u062f \u0648 \u0628\u0627 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0646 \u062f\u0631 \u0635\u0641\u062d\u0647 \u0627\u0648\u0644 \u0646\u062a\u0627\u06cc\u062c\u060c \u0639\u0646\u0648\u0627\u0646 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0628\u0647 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0646\u0645\u0627\u06cc\u0634 \u062f\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p>\u06a9\u0645\u06a9 \u062f\u06cc\u06af\u0631 \u0633\u0626\u0648 \u0628\u0647 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0628\u0631\u062c\u0633\u062a\u0647\u200c\u062a\u0631 \u06a9\u0631\u062f\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0645\u0646\u062d\u0635\u0631\u0628\u0647\u200c\u0641\u0631\u062f \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06cc\u0627 \u062e\u062f\u0645\u0627\u062a \u0627\u0633\u062a \u06a9\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0631\u0648\u06cc \u0645\u062a\u0645\u0627\u06cc\u0632 \u0634\u062f\u0646 \u0622\u0646\u200c\u0647\u0627 \u0646\u0633\u0628\u062a \u0628\u0647 \u0631\u0642\u0628\u0627 \u062a\u0627\u062b\u06cc\u0631 \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u062f. \u0627\u06af\u0631 \u0645\u062a\u0645\u0627\u06cc\u0632 \u0627\u0632 \u0631\u0642\u0628\u0627 \u062f\u06cc\u062f\u0647 \u0634\u0648\u06cc\u062f\u060c \u0627\u0641\u0632\u0627\u06cc\u0634 \u0686\u0634\u0645\u06af\u06cc\u0631\u06cc \u062f\u0631 \u062a\u0639\u062f\u0627\u062f \u0648\u0631\u0648\u062f\u06cc\u200c\u0647\u0627 \u0648 \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u0647 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u200c \u062e\u0648\u062f \u0645\u0634\u0627\u0647\u062f\u0647 \u062e\u0648\u0627\u0647\u06cc\u062f \u06a9\u0631\u062f. \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u0647 \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u062e\u0634\u06cc \u0628\u0627 \u0639\u0646\u0648\u0627\u0646 \u0648\u0631\u0648\u062f \/ \u062b\u0628\u062a \u0646\u0627\u0645 \u0628\u0647 \u0622\u0646 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0628\u0627 \u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0627\u0631\u062a\u0628\u0627\u0637\u06cc \u0622\u0646\u200c\u0647\u0627 \u0645\u0627\u0646\u0646\u062f \u0634\u0645\u0627\u0631\u0647 \u062a\u0644\u0641\u0646 \u0647\u0645\u0631\u0627\u0647\u060c \u0627\u0632 \u0637\u0631\u06cc\u0642 <a href=\"https:\/\/farazsms.com\/business-sender\/\" target=\"_blank\" rel=\"noopener\">\u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 \u0627\u0631\u0633\u0627\u0644 \u067e\u06cc\u0627\u0645 \u0627\u0646\u0628\u0648\u0647 \u062f\u0631 \u0648\u0627\u062a\u0633 \u0627\u067e<\/a> \u06cc\u0627 \u067e\u0646\u0644 \u0627\u0633 \u0627\u0645 \u0627\u0633 \u067e\u06cc\u0627\u0645 \u0627\u0631\u0633\u0627\u0644 \u06a9\u0646\u06cc\u062f \u0648 \u0634\u0627\u0646\u0633 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u062c\u0630\u0628 \u0648 \u062a\u0628\u062f\u06cc\u0644 \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u062e\u0648\u062f \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc \u0648\u0627\u0642\u0639\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-44338\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/04\/repotage14030201-02.jpg\" alt=\"\" width=\"600\" height=\"400\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/04\/repotage14030201-02.jpg 600w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/04\/repotage14030201-02-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%DB%B3-_%D8%A7%D8%B2_%D8%AC%D9%85%D9%84%D9%87_%D8%B1%D8%A7%D9%87%DA%A9%D8%A7%D8%B1%D9%87%D8%A7%DB%8C_%D9%85%D9%88%D8%AB%D8%B1_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D8%B1%D8%BA%DB%8C%D8%A8_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C%D8%A7%D9%86_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1%DB%8C%D8%A7%D8%A8%DB%8C_%D9%BE%DB%8C%D8%A7%D9%85%DA%A9%DB%8C_%D8%A7%D8%B3%D8%AA\"><\/span>\u06f3- \u0627\u0632 \u062c\u0645\u0644\u0647 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u0648\u062b\u0631 \u0628\u0631\u0627\u06cc \u062a\u0631\u063a\u06cc\u0628 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u067e\u06cc\u0627\u0645\u06a9\u06cc \u0627\u0633\u062a<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u067e\u06cc\u0627\u0645\u06a9\u06cc \u06a9\u0627\u0646\u0627\u0644 \u0627\u0631\u062a\u0628\u0627\u0637\u06cc \u0645\u0646\u0627\u0633\u0628\u06cc \u0627\u0633\u062a \u06a9\u0647 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0628\u0631\u0627\u06cc \u0627\u0637\u0644\u0627\u0639\u200c\u0631\u0633\u0627\u0646\u06cc \u0627\u062e\u0628\u0627\u0631 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631 \u0627\u0632 \u062c\u0645\u0644\u0647 \u062c\u062f\u06cc\u062f\u062a\u0631\u06cc\u0646 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u062f\u0631 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06cc\u0627 \u062e\u062f\u0645\u0627\u062a\u060c \u0627\u0631\u0633\u0627\u0644 \u067e\u06cc\u0627\u0645\u200c\u0647\u0627\u06cc \u062a\u0628\u0644\u06cc\u063a\u0627\u062a\u06cc \u0648 \u062d\u062a\u06cc \u0627\u0646\u062a\u0634\u0627\u0631 \u0645\u0642\u0627\u0644\u0647\u200c\u0627\u06cc \u062a\u0627\u0632\u0647 \u062f\u0631 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u062e\u0648\u062f \u062f\u0631 \u0627\u0632 \u0622\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0627 \u06a9\u0645\u06a9 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u067e\u06cc\u0627\u0645\u06a9\u06cc\u060c \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0645\u0633\u062a\u0642\u06cc\u0645\u0627 \u0628\u0627 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062f\u0631 \u0627\u0631\u062a\u0628\u0627\u0637 \u062e\u0648\u0627\u0647\u0646\u062f \u0628\u0648\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639\u060c \u0628\u0633\u06cc\u0627\u0631 \u062f\u0631 \u0627\u0631\u0633\u0627\u0644 \u067e\u06cc\u0627\u0645\u200c\u0647\u0627\u06cc\u06cc \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0646\u06cc\u0627\u0632 \u0648 \u062e\u0648\u0627\u0633\u062a\u0647 \u0648\u0627\u0642\u0639\u06cc \u0622\u0646\u200c\u0647\u0627 \u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u0627\u0633\u062a.<\/p>\n<p>\u0645\u0632\u06cc\u062a \u062f\u06cc\u06af\u0631 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u067e\u06cc\u0627\u0645\u06a9\u06cc\u060c \u0647\u062f\u0641 \u06af\u0631\u0641\u062a\u0646 \u0637\u06cc\u0641 \u062e\u0627\u0635\u06cc \u0627\u0632 \u0645\u062e\u0627\u0637\u0628\u0627\u0646 \u0628\u0627 \u062e\u0648\u0627\u0633\u062a\u0647 \u0648 \u0646\u06cc\u0627\u0632 \u0645\u0634\u062a\u0631\u06a9 \u0627\u0633\u062a. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0632 \u062c\u0645\u0644\u0647 \u0633\u0627\u06cc\u0631 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u06cc\u0646 \u0631\u0627\u0647\u06a9\u0627\u0631 \u0645\u0648\u062b\u0631 \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f \u06a9\u0647 \u062f\u0631 \u0628\u0631\u0642\u0631\u0627\u0631\u06cc \u0627\u0631\u062a\u0628\u0627\u0637 \u0645\u0648\u062b\u0631 \u0628\u0627 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0628\u0647\u200c\u0645\u0646\u0638\u0648\u0631 \u062c\u0630\u0628 \u0622\u0646\u200c\u0647\u0627 \u0648 \u062f\u0631 \u0631\u0627\u0633\u062a\u0627\u06cc \u0627\u0647\u062f\u0627\u0641 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc\u060c \u0646\u0642\u0634\u06cc \u0645\u0647\u0645\u06cc \u0627\u06cc\u0641\u0627 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n<ul>\n<li>\u0627\u0631\u0633\u0627\u0644 \u067e\u06cc\u0627\u0645 \u062f\u0631 \u06a9\u0648\u062a\u0627\u0647\u200c\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0645\u0645\u06a9\u0646 \u0648 \u0628\u0627 \u0635\u0631\u0641 \u0647\u0632\u06cc\u0646\u0647 \u0627\u0646\u062f\u06a9<\/li>\n<li>\u062f\u0627\u0634\u062a\u0646 \u0646\u0631\u062e \u0628\u0627\u0632\u062f\u06cc\u062f \u0648 \u062a\u0628\u062f\u06cc\u0644 \u0628\u0627\u0644\u0627<\/li>\n<li>\u0627\u0645\u06a9\u0627\u0646 \u0627\u0631\u0633\u0627\u0644 \u067e\u06cc\u0627\u0645 \u06a9\u0627\u0645\u0644\u0627 \u0634\u062e\u0635\u06cc\u200c\u0633\u0627\u0632\u06cc \u0634\u062f\u0647 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646<\/li>\n<\/ul>\n<p>\u067e\u0646\u0644\u200c\u0647\u0627\u06cc \u067e\u06cc\u0627\u0645\u06a9\u06cc \u0628\u0627 \u062f\u0627\u0634\u062a\u0646 \u06a9\u0644\u06cc\u0647 \u0627\u06cc\u0646 \u0645\u0632\u0627\u06cc\u0627\u060c \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0628\u0647\u200c\u0645\u0646\u0638\u0648\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0631\u0648\u0634 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u067e\u06cc\u0627\u0645\u06a9\u06cc \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0628\u0627 \u062e\u0631\u06cc\u062f <a href=\"https:\/\/farazsms.com\/sms-purchase-guide\/\" target=\"_blank\" rel=\"noopener\">\u0628\u0647\u062a\u0631\u06cc\u0646 \u067e\u0646\u0644 \u0647\u0627\u06cc \u067e\u06cc\u0627\u0645\u06a9\u06cc<\/a> \u0627\u0632 \u0645\u0631\u0627\u06a9\u0632 \u0645\u0639\u062a\u0628\u0631\u060c \u062e\u062f\u0645\u0627\u062a \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0648 \u06af\u0632\u0627\u0631\u0634\u200c\u0647\u0627\u06cc \u0634\u0641\u0627\u0641\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0627\u0631\u062f \u0641\u0627\u06a9\u062a\u0648\u0631\u0647\u0627\u06cc \u0645\u0647\u0645\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u06cc\u0646 \u0645\u062f\u0644 \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627 \u0628\u0647 \u0634\u0645\u0627\u0631 \u0645\u06cc\u200c\u0631\u0648\u0646\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%DB%B4-_%D8%A7%D9%87%D9%85%DB%8C%D8%AA_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1%DB%8C%D8%A7%D8%A8%DB%8C_%D9%85%D8%AD%D8%AA%D9%88%D8%A7_%D8%AF%D8%B1_%D8%AA%D8%B1%D8%BA%DB%8C%D8%A8_%D9%88_%D8%AC%D8%B0%D8%A8_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C%D8%A7%D9%86_%D8%AC%D8%AF%DB%8C%D8%AF\"><\/span>\u06f4- \u0627\u0647\u0645\u06cc\u062a \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u0645\u062d\u062a\u0648\u0627 \u062f\u0631 \u062a\u0631\u063a\u06cc\u0628 \u0648 \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062c\u062f\u06cc\u062f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0645\u062d\u062a\u0648\u0627\u0647\u0627 \u0647\u0645\u0627\u0646 \u0627\u0637\u0644\u0627\u0639\u0627\u062a\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0628\u0647\u200c\u0645\u0646\u0638\u0648\u0631 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0622\u06af\u0627\u0647\u06cc \u0627\u0632 \u0628\u0631\u0646\u062f \u06cc\u0627 \u067e\u06cc \u0628\u0631\u062f\u0646 \u0628\u0647 \u0645\u0627\u0647\u06cc\u062a \u0627\u0635\u0644\u06cc \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631 \u062e\u0648\u062f \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u062f\u0647\u06cc\u062f. \u0628\u0647\u200c\u0639\u0644\u0627\u0648\u0647\u060c \u0645\u062d\u062a\u0648\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0645\u0641\u06cc\u062f \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f \u06a9\u0647 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0632\u06cc\u0631 \u0631\u0627 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f:<\/p>\n<ol>\n<li>\u0646\u06a9\u0627\u062a \u0648 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0627\u0631\u0632\u0634\u0645\u0646\u062f\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f<\/li>\n<li>\u062f\u0631\u06a9 \u0645\u0637\u0627\u0644\u0628 \u0622\u0646 \u0628\u0631\u0627\u06cc \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062f\u0634\u0648\u0627\u0631 \u0646\u0628\u0627\u0634\u062f<\/li>\n<li>\u062f\u0631 \u0631\u0627\u0633\u062a\u0627\u06cc \u0627\u0647\u062f\u0627\u0641 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631 \u0646\u0648\u0634\u062a\u0647 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f<\/li>\n<li>\u0646\u06cc\u0627\u0632 \u0648 \u062e\u0648\u0627\u0633\u062a\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0631\u0627 \u0628\u0647\u200c\u062e\u0648\u0628\u06cc \u067e\u0627\u0633\u062e \u062f\u0647\u062f<\/li>\n<li>\u0645\u062a\u0646 \u062f\u0631\u06af\u06cc\u0631\u06a9\u0646\u0646\u062f\u0647 \u0628\u0647\u200c\u0645\u0646\u0638\u0648\u0631 \u062c\u0630\u0628 \u0648 \u062a\u0631\u063a\u06cc\u0628 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f<\/li>\n<\/ol>\n<p>\u062f\u0631 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u0645\u062d\u062a\u0648\u0627\u06cc\u06cc \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u06cc\u0627 \u0633\u0627\u06cc\u0631 \u06a9\u0627\u0646\u0627\u0644\u200c\u0647\u0627\u06cc \u0627\u0631\u062a\u0628\u0627\u0637\u06cc\u060c \u0645\u0637\u0627\u0644\u0628\u06cc \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0622\u0646\u200c\u0647\u0627 \u0627\u0631\u0632\u0634\u0645\u0646\u062f \u0627\u0633\u062a. \u0628\u0627 \u06a9\u0645\u06a9 \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc\u060c \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631 \u0634\u0645\u0627 \u0645\u062d\u062a\u0648\u0627\u06cc\u06cc \u0631\u0627 \u062f\u0631 \u0641\u0636\u0627\u06cc \u0622\u0646\u0644\u0627\u06cc\u0646 \u0645\u0646\u062a\u0634\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u062f\u0642\u06cc\u0642\u0627 \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u067e\u0627\u0633\u062e \u0645\u06cc\u200c\u062f\u0647\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%DB%B5-_%D8%A7%D8%B1%D8%B3%D8%A7%D9%84_%D9%BE%DB%8C%D8%A7%D9%85_%D8%AA%D8%A8%D9%84%DB%8C%D8%BA%D8%A7%D8%AA%DB%8C_%D8%A8%D9%87_%D9%85%D8%AE%D8%A7%D8%B7%D8%A8%D8%A7%D9%86_%D9%87%D8%AF%D9%81_%D8%A8%D8%A7_%DA%A9%D9%85%DA%A9_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1%DB%8C%D8%A7%D8%A8%DB%8C_%D8%A7%DB%8C%D9%85%DB%8C%D9%84%DB%8C\"><\/span>\u06f5- \u0627\u0631\u0633\u0627\u0644 \u067e\u06cc\u0627\u0645 \u062a\u0628\u0644\u06cc\u063a\u0627\u062a\u06cc \u0628\u0647 \u0645\u062e\u0627\u0637\u0628\u0627\u0646 \u0647\u062f\u0641 \u0628\u0627 \u06a9\u0645\u06a9 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u0627\u06cc\u0645\u06cc\u0644\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062f\u0631\u06cc\u0627\u0641\u062a \u0627\u06cc\u0645\u06cc\u0644\u06cc \u0627\u0632 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627\u060c \u0627\u06cc\u0646 \u062d\u0633 \u0631\u0627 \u062f\u0631 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0634\u0645\u0627 \u0628\u0631\u0627\u06cc \u0622\u0646\u200c\u0647\u0627 \u0627\u0631\u0632\u0634 \u0648 \u0627\u0647\u0645\u06cc\u062a \u0641\u0631\u0627\u0648\u0627\u0646\u06cc \u0642\u0627\u0626\u0644 \u0645\u06cc\u200c\u0634\u0648\u06cc\u062f. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644 \u062a\u0635\u0648\u0631 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0627\u06cc\u0645\u06cc\u0644\u06cc \u062d\u0627\u0648\u06cc \u0627\u06cc\u0646 \u067e\u06cc\u0627\u0645 \u0631\u0627 \u0627\u0632 \u0633\u0645\u062a \u0628\u0631\u0646\u062f \u0645\u0648\u0631\u062f\u0639\u0644\u0627\u0642\u0647\u200c\u062a\u0627\u0646 \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0631\u062f\u0647\u200c\u0627\u06cc\u062f \u00ab\u0633\u0644\u0627\u0645 \u0627\u06cc\u0646 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0648\u06cc\u0698\u0647 \u0641\u0642\u0637 \u0645\u062e\u0635\u0648\u0635 \u0634\u0645\u0627 \u0627\u0633\u062a\u060c \u0686\u0648\u0646 \u0634\u0645\u0627 \u062f\u0648\u0633\u062a \u062e\u0648\u0628 \u0645\u0627 \u0647\u0633\u062a\u06cc\u062f\u00bb\u061b \u0622\u06cc\u0627 \u0628\u0627 \u062f\u06cc\u062f\u0646 \u0627\u06cc\u0646 \u0627\u06cc\u0645\u06cc\u0644\u060c \u062d\u0633 \u062e\u0648\u0628\u06cc \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f\u061f \u0645\u0637\u0645\u0626\u0646\u0627 \u067e\u0627\u0633\u062e \u0634\u0645\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u0633\u0648\u0627\u0644 \u0628\u0644\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627\u06cc \u0641\u0631\u0627\u0648\u0627\u0646\u06cc \u0628\u0627 \u067e\u06cc\u0634\u200c\u0641\u0631\u0636 \u0627\u06cc\u0646\u06a9\u0647 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u0627\u06cc\u0645\u06cc\u0644\u06cc \u062f\u06cc\u06af\u0631 \u06a9\u0627\u0631\u06a9\u0631\u062f \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0647 \u0627\u0633\u062a\u061b \u0628\u0647 \u0633\u0631\u0627\u063a \u0622\u0646 \u0646\u0645\u06cc\u200c\u0631\u0648\u0646\u062f. \u0648\u0644\u06cc \u0647\u0645\u0686\u0646\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u0627\u0646 \u062f\u06cc\u062c\u06cc\u062a\u0627\u0644 \u0645\u0627\u0631\u06a9\u062a\u06cc\u0646\u06af\u060c \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u0627\u06cc\u0645\u06cc\u0644\u06cc \u0631\u0627 \u0631\u0648\u0634\u06cc \u0645\u0648\u062b\u0631 \u0645\u06cc\u200c\u062f\u0627\u0646\u0646\u062f \u06a9\u0647 \u0628\u0631\u0627\u06cc \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627\u060c \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0641\u0631\u0648\u0634 \u0686\u0634\u0645\u06af\u06cc\u0631\u06cc \u0628\u0647 \u0627\u0631\u0645\u063a\u0627\u0646 \u0645\u06cc\u200c\u0622\u0648\u0631\u0646\u062f. \u062f\u0644\u06cc\u0644 \u0622\u0646 \u0647\u0645 \u0628\u0647 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0632\u06cc\u0631 \u0645\u0631\u0628\u0648\u0637 \u0645\u06cc\u200c\u0634\u0648\u062f:<\/p>\n<ul>\n<li>\u0627\u0641\u0632\u0627\u06cc\u0634 \u062a\u0631\u0627\u0641\u06cc\u06a9 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0646\u0631\u062e \u0628\u0627\u0632\u062f\u06cc\u062f \u0648 \u0628\u0627\u0632 \u0634\u062f\u0646 \u0628\u0627\u0644\u0627 \u0627\u06cc\u0645\u06cc\u0644\u200c\u0647\u0627<\/li>\n<li>\u062f\u0633\u062a\u0631\u0633\u06cc \u0633\u0631\u06cc\u0639 \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0628\u0647\u200c\u062f\u0644\u06cc\u0644 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06af\u0633\u062a\u0631\u062f\u0647 \u0645\u0631\u062f\u0645 \u0627\u0632 \u06af\u0648\u0634\u06cc\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f<\/li>\n<\/ul>\n<p>\u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u06cc\u0645\u06cc\u0644\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u062a\u0646 \u0622\u0646\u200c\u0647\u0627 \u0628\u0627 \u0631\u0639\u0627\u06cc\u062a \u06a9\u0644\u06cc\u0647 \u0646\u06a9\u0627\u062a \u0648 \u0627\u0635\u0648\u0644 \u0646\u06af\u0627\u0631\u0634\u06cc \u0646\u0648\u0634\u062a\u0647 \u0634\u062f\u0647 \u0648 \u0644\u062d\u0646\u06cc \u062f\u0648\u0633\u062a\u0627\u0646\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u062a\u0648\u0633\u0637 \u0627\u0641\u0631\u0627\u062f \u0628\u0633\u06cc\u0627\u0631\u06cc \u062f\u06cc\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-44339\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/04\/repotage14030201-03.jpg\" alt=\"\" width=\"600\" height=\"400\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/04\/repotage14030201-03.jpg 600w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2024\/04\/repotage14030201-03-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%DB%B6-_%D9%81%D8%B9%D8%A7%D9%84%DB%8C%D8%AA_%D8%AF%D8%B1_%D8%B4%D8%A8%DA%A9%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D8%AC%D8%AA%D9%85%D8%A7%D8%B9%DB%8C%D8%9B_%D8%B1%D8%A7%D9%87%DA%A9%D8%A7%D8%B1%DB%8C_%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AC%D8%B0%D8%A8_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C_%DA%A9%D8%A7%D8%A8%DB%8C%D9%86%D8%AA\"><\/span>\u06f6- \u0641\u0639\u0627\u0644\u06cc\u062a \u062f\u0631 \u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc\u061b \u0631\u0627\u0647\u06a9\u0627\u0631\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0628\u0631\u0627\u06cc \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc \u06a9\u0627\u0628\u06cc\u0646\u062a<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062f\u0631 \u0641\u0636\u0627\u06cc \u062f\u06cc\u062c\u06cc\u062a\u0627\u0644\u060c \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627\u06cc \u0641\u0631\u0627\u0648\u0627\u0646\u06cc \u062f\u0631 \u062d\u0648\u0632\u0647 \u0641\u0639\u0627\u0644\u06cc\u062a\u062a\u0627\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u0646\u062f \u06a9\u0647 \u0628\u0627 \u06a9\u0645\u06a9 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627 \u0648 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u0645\u062e\u062a\u0644\u0641 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062c\u062f\u06cc\u062f \u0647\u0633\u062a\u0646\u062f. \u067e\u0633\u060c \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0628\u0627\u0632\u0627\u0631 \u0631\u0642\u0627\u0628\u062a\u06cc \u0627\u0632 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u0634\u0627\u0628\u0647 \u062e\u0648\u062f \u0633\u0628\u0642\u062a \u0628\u06af\u06cc\u0631\u06cc\u062f \u0648 \u0634\u0627\u0646\u0633 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u060c \u0628\u0627\u06cc\u062f \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f\u062a\u0631\u06cc \u0645\u0627\u0646\u0646\u062f \u0641\u0639\u0627\u0644\u06cc\u062a \u062f\u0631 \u0631\u0633\u0627\u0646\u0647\u200c\u0647\u0627 \u0648 \u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u06a9\u0645\u06a9 \u0628\u06af\u06cc\u0631\u06cc\u062f.<\/p>\n<p>\u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0645\u0627\u0646\u0646\u062f \u0627\u06cc\u0646\u0633\u062a\u0627\u06af\u0631\u0627\u0645\u060c \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u0641\u0631\u0627\u0648\u0627\u0646\u06cc \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u062a\u0627 \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u0628\u0647\u200c\u0645\u0646\u0638\u0648\u0631 \u062f\u0633\u062a\u06cc\u0627\u0628\u06cc \u0628\u0647 \u0627\u0647\u062f\u0627\u0641 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u062e\u0648\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u0646\u062f. \u062f\u0631 \u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc\u060c \u0627\u0645\u06a9\u0627\u0646 \u0627\u0646\u062a\u0634\u0627\u0631 \u0645\u062d\u062a\u0648\u0627 \u062f\u0631 \u0642\u0627\u0644\u0628\u200c\u0647\u0627\u06cc \u0645\u062a\u0646\u0648\u0639\u060c \u0647\u0645\u0631\u0627\u0647 \u0628\u0627 \u0627\u0644\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u06af\u0631\u0627\u0641\u06cc\u06a9\u06cc \u0648 \u0627\u0641\u06a9\u062a\u200c\u0647\u0627\u06cc \u062c\u0630\u0627\u0628 \u0628\u0631\u0627\u06cc \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0641\u0631\u0627\u0647\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a \u062a\u0627 \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0645\u0637\u0644\u0648\u0628 \u067e\u06cc\u0627\u0645 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u062f\u0633\u062a \u0645\u062e\u0627\u0637\u0628\u0627\u0646 \u0628\u0631\u0633\u0627\u0646\u0646\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%DB%B7-_%D8%AB%D8%A8%D8%AA_%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%DA%A9%D8%B3%D8%A8%E2%80%8C%D9%88%DA%A9%D8%A7%D8%B1_%D8%AF%D8%B1_%DA%AF%D9%88%DA%AF%D9%84_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B3%D8%AA%D8%B1%D8%B3%DB%8C_%D8%A2%D8%B3%D8%A7%D9%86_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C%D8%A7%D9%86_%D8%A8%D9%87_%D8%A2%D9%86\"><\/span>\u06f7- \u062b\u0628\u062a \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631 \u062f\u0631 \u06af\u0648\u06af\u0644 \u0628\u0631\u0627\u06cc \u062f\u0633\u062a\u0631\u0633\u06cc \u0622\u0633\u0627\u0646 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0628\u0647 \u0622\u0646<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u0628\u0632\u0627\u0631\u06cc \u06a9\u0647 \u0627\u063a\u0644\u0628 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0628\u0631\u0627\u06cc \u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u0632 \u0622\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0645\u0648\u062a\u0648\u0631 \u062c\u0633\u062a\u200c\u0648\u062c\u0648\u06cc \u06af\u0648\u06af\u0644 \u0627\u0633\u062a. \u0628\u0627 \u062b\u0628\u062a \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631 \u062f\u0631 \u06af\u0648\u06af\u0644 \u0645\u0627\u0646\u0646\u062f \u0634\u0645\u0627\u0631\u0647 \u062a\u0645\u0627\u0633\u060c \u0644\u06cc\u0646\u06a9 \u0633\u0627\u06cc\u062a \u0648 \u0622\u062f\u0631\u0633 \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u062d\u0636\u0648\u0631\u06cc\u060c \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0628\u0647\u200c\u0622\u0633\u0627\u0646\u06cc \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631 \u0634\u0645\u0627 \u0631\u0627 \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u06af\u0648\u06af\u0644\u060c \u0639\u0646\u0648\u0627\u0646 \u0633\u0627\u06cc\u062a\u200c\u0647\u0627 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062b\u0628\u062a \u0634\u062f\u0647 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0646\u0645\u0627\u06cc\u0634 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u062a\u0627 \u0627\u0632 \u0627\u06cc\u0646 \u0637\u0631\u06cc\u0642\u060c \u062a\u062c\u0631\u0628\u0647 \u062e\u0648\u062f \u0627\u0632 \u062f\u0631\u06cc\u0627\u0641\u062a \u062e\u062f\u0645\u0627\u062a \u06cc\u0627 \u062e\u0631\u06cc\u062f \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0631\u0627 \u0622\u0646\u062c\u0627 \u0648\u0627\u0631\u062f \u06a9\u0646\u0646\u062f. \u0628\u0631\u0627\u0633\u0627\u0633 \u0627\u0645\u062a\u06cc\u0627\u0632\u0627\u062a \u0648 \u0646\u0638\u0631\u0627\u062a \u0645\u062b\u0628\u062a \u06a9\u0627\u0631\u0628\u0631\u0627\u0646\u060c \u0633\u0627\u06cc\u062a\u200c\u0647\u0627 \u0631\u062a\u0628\u0647 \u0645\u0646\u0627\u0633\u0628\u06cc \u062f\u0631 \u0635\u0641\u062d\u0647 \u0646\u062a\u0627\u06cc\u062c \u06af\u0648\u06af\u0644 \u0628\u0647 \u062f\u0633\u062a \u0645\u06cc\u200c\u0622\u0648\u0631\u0646\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0631\u0648\u06cc \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0648\u0628\u0633\u0627\u06cc\u062a \u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D8%A7%D8%A8%D8%B2%D8%A7%D8%B1%D9%87%D8%A7%DB%8C_%D8%AA%D8%B9%D8%A7%D9%85%D9%84%DB%8C%D8%9B_%D8%AA%DA%A9%D9%86%DB%8C%DA%A9%DB%8C_%D9%85%D9%88%D8%AB%D8%B1_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AC%D8%B0%D8%A8_%D9%85%D8%B4%D8%AA%D8%B1%DB%8C_%DA%A9%D8%A7%D8%A8%DB%8C%D9%86%D8%AA\"><\/span>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u062a\u0639\u0627\u0645\u0644\u06cc\u061b \u062a\u06a9\u0646\u06cc\u06a9\u06cc \u0645\u0648\u062b\u0631 \u0628\u0631\u0627\u06cc \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc \u06a9\u0627\u0628\u06cc\u0646\u062a<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u0645\u0646\u0627\u0633\u0628 \u0648 \u0645\u0648\u062b\u0631 \u0628\u0631\u0627\u06cc \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646\u060c \u0686\u0627\u0644\u0634 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u062f\u0631 \u0641\u0636\u0627\u06cc \u0622\u0646\u0644\u0627\u06cc\u0646 \u0627\u0645\u0631\u0648\u0632 \u0627\u0633\u062a. \u0628\u0647\u200c\u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644\u060c \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0628\u0647 \u0645\u0639\u0631\u0641\u06cc \u062a\u0639\u062f\u0627\u062f\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627 \u0645\u0627\u0646\u0646\u062f \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u06cc\u06a9 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u062d\u0631\u0641\u0647\u200c\u0627\u06cc\u060c \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u0645\u062d\u062a\u0648\u0627\u06cc\u06cc \u0648 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u067e\u06cc\u0627\u0645\u06a9\u06cc \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f\u06cc\u0645. \u0647\u0645\u0686\u0646\u06cc\u0646 \u062a\u0648\u0636\u06cc\u062d\u0627\u062a\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0647\u0631\u06cc\u06a9 \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0648\u0634\u200c\u0647\u0627 \u0627\u0631\u0627\u0626\u0647 \u06a9\u0631\u062f\u06cc\u0645 \u062a\u0627 \u0628\u0647 \u0635\u0627\u062d\u0628\u0627\u0646 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u06cc\u0645\u060c \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0648 \u062f\u0631 \u0645\u0633\u06cc\u0631\u06cc \u062f\u0631\u0633\u062a \u0628\u0631\u0627\u06cc \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc \u0642\u062f\u0645 \u0628\u0631\u062f\u0627\u0631\u0646\u062f. \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u062a\u0639\u0627\u0645\u0644\u06cc \u0645\u0627\u0646\u0646\u062f \u067e\u0646\u0644 \u067e\u06cc\u0627\u0645\u06a9\u06cc \u0646\u06cc\u0632 \u0627\u0642\u062f\u0627\u0645 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0645\u0631\u0627\u06a9\u0632 \u0645\u0639\u062a\u0628\u0631 \u0631\u0627 \u062a\u0648\u0635\u06cc\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u062a\u0627 \u062e\u06cc\u0627\u0644\u062a\u0627\u0646 \u0627\u0632 \u0628\u0627\u0628\u062a \u062e\u0631\u06cc\u062f \u0645\u062d\u0635\u0648\u0644\u06cc \u062f\u0631 \u0628\u0633\u062a\u0631\u06cc \u0627\u0645\u0646 \u0622\u0633\u0648\u062f\u0647 \u0628\u0627\u0634\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u0648 \u062f\u0627\u0634\u062a\u0646 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0648 \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u067e\u06cc\u0627\u0645\u06a9\u06cc \u0627\u0632 \u062c\u0645\u0644\u0647 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u0648\u062b\u0631 \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0641\u0631\u0648\u0634 \u0647\u0633\u062a\u0646\u062f. \u0627\u0644\u0628\u062a\u0647 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631\u06cc \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0641\u0631\u0648\u0634 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f\u061b \u0627\u0645\u0627 \u062a\u0639\u062f\u0627\u062f\u06cc \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0647\u200c\u0627\u0646\u062f. \u0628\u0647\u200c\u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628\u060c \u062c\u062f\u06cc\u062f\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627 \u0648 \u06f7 \u062a\u06a9\u0646\u06cc\u06a9 \u0645\u0648\u062b\u0631 \u0628\u0631\u0627\u06cc \u062c\u0630\u0628 \u0645\u0634\u062a\u0631\u06cc \u06a9\u0627\u0628\u06cc\u0646\u062a \u0631\u0627 \u0645\u0639\u0631\u0641\u06cc \u062e\u0648\u0627\u0647\u06cc\u0645 \u06a9\u0631\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u062a\u0648\u0636\u06cc\u062d\u0627\u062a\u06cc [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":44337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-44336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/44336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=44336"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/44336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/44337"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=44336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=44336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=44336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}