{"id":43729,"date":"2024-02-01T14:13:27","date_gmt":"2024-02-01T10:43:27","guid":{"rendered":"https:\/\/decorshop.ir\/mag\/?p=43729"},"modified":"2024-02-01T14:13:27","modified_gmt":"2024-02-01T10:43:27","slug":"%d9%85%d8%b2%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d9%81%d8%b1%d8%b4-%d9%81%d8%a7%d9%86%d8%aa%d8%b2%db%8c-%d8%af%d8%b1-%d8%a7%d8%aa%d8%a7%d9%82-%d8%ae%d9%88%d8%a7%d8%a8","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b2%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d9%81%d8%b1%d8%b4-%d9%81%d8%a7%d9%86%d8%aa%d8%b2%db%8c-%d8%af%d8%b1-%d8%a7%d8%aa%d8%a7%d9%82-%d8%ae%d9%88%d8%a7%d8%a8\/","title":{"rendered":"\u0645\u0632\u06cc\u062a \u0647\u0627\u06cc \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u062f\u0631 \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>\u0686\u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647\u200c\u0647\u0627 \u0628\u0647\u200c\u0634\u0645\u0627\u0631 \u0645\u06cc\u200c\u0622\u06cc\u062f\u061f \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0686\u0647 \u0645\u0632\u0627\u06cc\u0627\u06cc\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647\u200c\u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u06a9\u0647 \u062f\u0631 \u0628\u06cc\u0646 \u062e\u0631\u06cc\u062f\u0627\u0631\u0627\u0646 \u0628\u0647 \u0645\u062d\u0628\u0648\u0628\u06cc\u062a \u0631\u0633\u06cc\u062f\u0647 \u0627\u0633\u062a\u061f \u0628\u0627 \u06cc\u0627\u0641\u062a\u0646 \u067e\u0627\u0633\u062e \u0627\u06cc\u0646 \u0633\u0648\u0627\u0644\u0627\u062a \u0627\u062d\u062a\u0645\u0627\u0644\u0627 \u0634\u0645\u0627 \u0646\u06cc\u0632 \u0628\u0631\u0627\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u062f \u0641\u0631\u0634\u200c\u0647\u0627\u06cc \u0641\u0627\u0646\u062a\u0632\u06cc \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0645\u062d\u0635\u0648\u0644\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0628\u0647\u200c\u062e\u0648\u0628\u06cc \u062a\u0646\u0627\u0633\u0628 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0641\u0631\u0634 \u062f\u0631 \u0645\u062f\u0644\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0633\u0644\u06cc\u0642\u0647 \u062e\u0648\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0631\u0627 \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u06a9\u0646\u0646\u062f. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0627 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0648 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0622\u0646 \u0628\u06cc\u0634\u062a\u0631 \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u0634\u0648\u06cc\u0645.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b2%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d9%81%d8%b1%d8%b4-%d9%81%d8%a7%d9%86%d8%aa%d8%b2%db%8c-%d8%af%d8%b1-%d8%a7%d8%aa%d8%a7%d9%82-%d8%ae%d9%88%d8%a7%d8%a8\/#%D9%85%D8%B9%D8%B1%D9%81%DB%8C_%DA%A9%D8%A7%D9%85%D9%84_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C\" >\u0645\u0639\u0631\u0641\u06cc \u06a9\u0627\u0645\u0644 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b2%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d9%81%d8%b1%d8%b4-%d9%81%d8%a7%d9%86%d8%aa%d8%b2%db%8c-%d8%af%d8%b1-%d8%a7%d8%aa%d8%a7%d9%82-%d8%ae%d9%88%d8%a7%d8%a8\/#%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C\" >\u0627\u0646\u0648\u0627\u0639 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b2%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d9%81%d8%b1%d8%b4-%d9%81%d8%a7%d9%86%d8%aa%d8%b2%db%8c-%d8%af%d8%b1-%d8%a7%d8%aa%d8%a7%d9%82-%d8%ae%d9%88%d8%a7%d8%a8\/#%D9%85%D8%B2%D8%A7%DB%8C%D8%A7%DB%8C_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%AE%D9%88%D8%A7%D8%A8\" >\u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0628\u0631\u0627\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b2%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d9%81%d8%b1%d8%b4-%d9%81%d8%a7%d9%86%d8%aa%d8%b2%db%8c-%d8%af%d8%b1-%d8%a7%d8%aa%d8%a7%d9%82-%d8%ae%d9%88%d8%a7%d8%a8\/#%D8%AA%D9%86%D9%88%D8%B9_%D8%AF%D8%B1_%D8%B1%D9%86%DA%AF_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%AE%D9%88%D8%A7%D8%A8\" >\u062a\u0646\u0648\u0639 \u062f\u0631 \u0631\u0646\u06af \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b2%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d9%81%d8%b1%d8%b4-%d9%81%d8%a7%d9%86%d8%aa%d8%b2%db%8c-%d8%af%d8%b1-%d8%a7%d8%aa%d8%a7%d9%82-%d8%ae%d9%88%d8%a7%d8%a8\/#%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%AE%D9%88%D8%A7%D8%A8_%D9%88_%D8%AA%D9%86%D9%88%D8%B9_%D8%AF%D8%B1_%D8%B7%D8%B1%D8%AD\" >\u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0648 \u062a\u0646\u0648\u0639 \u062f\u0631 \u0637\u0631\u062d<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b2%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d9%81%d8%b1%d8%b4-%d9%81%d8%a7%d9%86%d8%aa%d8%b2%db%8c-%d8%af%d8%b1-%d8%a7%d8%aa%d8%a7%d9%82-%d8%ae%d9%88%d8%a7%d8%a8\/#%DA%A9%DB%8C%D9%81%DB%8C%D8%AA_%D8%A8%D8%A7%D9%84%D8%A7%DB%8C_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C\" >\u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627\u06cc \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b2%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d9%81%d8%b1%d8%b4-%d9%81%d8%a7%d9%86%d8%aa%d8%b2%db%8c-%d8%af%d8%b1-%d8%a7%d8%aa%d8%a7%d9%82-%d8%ae%d9%88%d8%a7%d8%a8\/#%D9%81%D8%B1%D8%B4%DB%8C_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%AE%D9%88%D8%A7%D8%A8_%D9%88_%D8%AA%D9%86%D8%A7%D8%B3%D8%A8_%D8%A8%D8%A7_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86\" >\u0641\u0631\u0634\u06cc \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0648 \u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b2%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d9%81%d8%b1%d8%b4-%d9%81%d8%a7%d9%86%d8%aa%d8%b2%db%8c-%d8%af%d8%b1-%d8%a7%d8%aa%d8%a7%d9%82-%d8%ae%d9%88%d8%a7%d8%a8\/#%D9%82%DB%8C%D9%85%D8%AA_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%AE%D9%88%D8%A7%D8%A8\" >\u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b2%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d9%81%d8%b1%d8%b4-%d9%81%d8%a7%d9%86%d8%aa%d8%b2%db%8c-%d8%af%d8%b1-%d8%a7%d8%aa%d8%a7%d9%82-%d8%ae%d9%88%d8%a7%d8%a8\/#%DA%86%D8%B1%D8%A7_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%AE%D9%88%D8%A7%D8%A8_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C_%D8%A8%D8%AE%D8%B1%DB%8C%D9%85%D8%9F\" >\u0686\u0631\u0627 \u0628\u0631\u0627\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0628\u062e\u0631\u06cc\u0645\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/decorshop.ir\/mag\/%d9%85%d8%b2%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d9%81%d8%b1%d8%b4-%d9%81%d8%a7%d9%86%d8%aa%d8%b2%db%8c-%d8%af%d8%b1-%d8%a7%d8%aa%d8%a7%d9%82-%d8%ae%d9%88%d8%a7%d8%a8\/#%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C\" >\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%D8%B1%D9%81%DB%8C_%DA%A9%D8%A7%D9%85%D9%84_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C\"><\/span>\u0645\u0639\u0631\u0641\u06cc \u06a9\u0627\u0645\u0644 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u06af\u0631 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u062a\u0647\u06cc\u0647 \u06a9\u0646\u06cc\u062f \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0627\u0628\u062a\u062f\u0627 \u06a9\u0645\u06cc \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0631\u0627 \u0628\u0634\u0646\u0627\u0633\u06cc\u062f. \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u062f\u0631 \u062f\u0633\u062a\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0645\u062f\u0631\u0646 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f \u0648 \u0628\u0627 \u0637\u0631\u062d \u062e\u0627\u0635 \u062e\u0648\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0645\u062d\u06cc\u0637 \u0631\u0627 \u062a\u0627 \u062d\u062f \u0632\u06cc\u0627\u062f\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u062f.<\/p>\n<p>\u0641\u0631\u0634\u200c\u0647\u0627\u06cc \u0641\u0627\u0646\u062a\u0632\u06cc \u062f\u0631 \u0631\u0646\u06af\u200c\u0647\u0627\u06cc \u0634\u0627\u062f \u0648 \u0633\u0631\u0632\u0646\u062f\u0647 \u06cc\u0627 \u062d\u062a\u06cc \u062e\u0646\u062b\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u062a\u0627 \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0633\u0644\u06cc\u0642\u0647 \u062e\u0648\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0641\u0631\u0634 \u0645\u0639\u0645\u0648\u0644\u0627 \u0628\u0627 \u0637\u0631\u062d \u0648 \u0646\u0642\u0634\u06cc \u06a9\u0627\u0645\u0644\u0627 \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0632 \u0637\u0631\u062d\u200c\u0647\u0627\u06cc \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u0648 \u0628\u062f\u0648\u0646 \u0647\u06cc\u0686 \u0642\u0627\u0646\u0648\u0646 \u062e\u0627\u0635\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0646\u06cc\u0632 \u0628\u0647\u200c\u0631\u0627\u062d\u062a\u06cc \u062f\u0631 \u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0633\u0628\u06a9 \u0645\u062f\u0631\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u0632 \u0622\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C\"><\/span>\u0627\u0646\u0648\u0627\u0639 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u06cc\u0646\u06a9\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0632\u06cc\u062a\u200c\u0647\u0627\u06cc \u0645\u0647\u0645 \u0627\u0646\u062a\u062e\u0627\u0628 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u062a\u0646\u0648\u0639 \u0628\u0627\u0644\u0627\u06cc \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0627\u0633\u062a \u067e\u06cc\u0634 \u0627\u0632 \u0647\u0631 \u0645\u0648\u0631\u062f\u06cc \u0628\u0627\u06cc\u062f \u0627\u0646\u0648\u0627\u0639 \u0622\u0646 \u0631\u0627 \u0628\u0634\u0646\u0627\u0633\u06cc\u0645. \u0628\u0647\u200c\u0637\u0648\u0631 \u06a9\u0644\u06cc \u0645\u062f\u0644\u200c\u0647\u0627\u06cc \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0639\u0628\u0627\u0631\u062a\u200c\u0627\u0646\u062f \u0627\u0632:<\/p>\n<ul>\n<li><strong>\u0641\u0631\u0634 \u0645\u062f\u0631\u0646 \u0641\u0631\u06cc\u0632:<\/strong> \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0628\u0627 \u0646\u062e\u200c\u0647\u0627\u06cc \u0636\u062e\u06cc\u0645 \u0648 \u0628\u062f\u0648\u0646 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a \u062f\u0631 \u0637\u0631\u062d \u0648 \u0646\u0642\u0634 \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u0634\u0648\u062f. \u062f\u0631 \u0646\u06af\u0627\u0647 \u0627\u0648\u0644 \u0627\u062d\u062a\u0645\u0627\u0644\u0627 \u0641\u0631\u0634 \u0641\u0631\u06cc\u0632 \u0631\u0627 \u0628\u0627 \u0642\u0627\u0644\u06cc \u06cc\u0627 \u06af\u0644\u06cc\u0645 \u0627\u0634\u062a\u0628\u0627\u0647 \u0628\u06af\u06cc\u0631\u06cc\u062f. \u062a\u0646\u0648\u0639 \u0628\u0627\u0644\u0627 \u062f\u0631 \u0637\u0631\u062d \u0648 \u0631\u0646\u06af \u0627\u0632 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0645\u062f\u0644 \u0641\u0631\u06cc\u0632 \u0628\u0647\u200c\u0634\u0645\u0627\u0631 \u0645\u06cc\u200c\u0622\u06cc\u0646\u062f.<\/li>\n<li><strong>\u0641\u0631\u0634 \u0634\u0646\u0644:<\/strong> \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0641\u0631\u0634\u200c \u0641\u0627\u0646\u062a\u0632\u06cc \u0636\u062e\u06cc\u0645 \u0646\u06cc\u0633\u062a \u0648 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062e\u06cc\u0644\u06cc \u0634\u0633\u062a\u0647 \u0646\u0634\u0648\u062f. \u0627\u0632\u0627\u06cc\u0646\u200c\u0631\u0648 \u0628\u0631\u0627\u06cc \u0645\u062d\u06cc\u0637\u06cc \u0628\u0627 \u0631\u0641\u062a\u200c\u0648\u0622\u0645\u062f \u0632\u06cc\u0627\u062f \u06af\u0632\u06cc\u0646\u0647 \u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0647\u200c\u0634\u0645\u0627\u0631 \u0646\u0645\u06cc\u200c\u0622\u06cc\u062f. \u0627\u0632 \u0646\u0638\u0631 \u062a\u0646\u0648\u0639 \u062f\u0631 \u0637\u0631\u062d \u0648 \u0631\u0646\u06af \u0646\u06cc\u0632 \u0628\u0627\u06cc\u062f \u06af\u0641\u062a \u062c\u0627\u06cc\u06af\u0627\u0647 \u062e\u0648\u0628\u06cc \u062f\u0627\u0631\u062f.<\/li>\n<li><strong>\u0641\u0631\u0634 \u0634\u06af\u06cc:<\/strong> \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u067e\u0631\u0632\u0647\u0627\u06cc \u0628\u0644\u0646\u062f\u06cc \u062f\u0627\u0631\u062f \u0648 \u0627\u0632 \u06a9\u06cc\u0641\u06cc\u062a \u062e\u06cc\u0644\u06cc \u0628\u0627\u0644\u0627\u06cc\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0646\u06cc\u0633\u062a. \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0628\u0627 \u0641\u0631\u0647\u0646\u06af \u0627\u06cc\u0631\u0627\u0646\u06cc\u200c\u0647\u0627 \u062e\u06cc\u0644\u06cc \u062a\u0646\u0627\u0633\u0628 \u0646\u062f\u0627\u0631\u062f.<\/li>\n<li><strong>\u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0639\u0631\u0648\u0633\u06a9\u06cc:<\/strong> \u0646\u0645\u0648\u0646\u0647 \u062f\u06cc\u06af\u0631\u06cc \u0627\u0632 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0646\u0648\u0639 \u0639\u0631\u0648\u0633\u06a9\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u0637\u0631\u062d\u200c\u0647\u0627\u06cc \u062c\u0630\u0627\u0628 \u06a9\u0648\u062f\u06a9\u0627\u0646\u0647 \u0648 \u0631\u0646\u06af\u200c\u0647\u0627\u06cc \u0634\u0627\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0631\u0627\u06cc \u0627\u062a\u0627\u0642 \u0641\u0631\u0632\u0646\u062f \u0634\u0645\u0627 \u0628\u0647\u200c\u062d\u0633\u0627\u0628 \u0645\u06cc\u200c\u0622\u06cc\u062f.<\/li>\n<\/ul>\n<p><img decoding=\"async\" src=\"https:\/\/cdn.triboon.net\/media\/reportage_images\/d0bae2f4-5887-446e-af6e-b964b10a414c.jpg\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%85%D8%B2%D8%A7%DB%8C%D8%A7%DB%8C_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%AE%D9%88%D8%A7%D8%A8\"><\/span>\u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0628\u0631\u0627\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062d\u0627\u0644 \u06a9\u0647 \u0628\u0627 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627 \u0648 \u062a\u0646\u0648\u0639 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0622\u0634\u0646\u0627 \u0634\u062f\u0647\u200c\u0627\u06cc\u0645 \u0642\u0637\u0639\u0627 \u0645\u06cc\u200c\u062f\u0627\u0646\u06cc\u0645 \u062f\u0644\u06cc\u0644 \u0627\u0646\u062a\u062e\u0627\u0628 \u0622\u0646\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0686\u06cc\u0633\u062a. \u0627\u0645\u0627 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647\u200c\u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u0628\u0627 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0645\u0632\u06cc\u062a\u200c\u0647\u0627 \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u0634\u0648\u06cc\u0645.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cdn.triboon.net\/media\/reportage_images\/6f2ec6e2-6f42-4f6a-adea-914ee35cf3af.jpg\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%D9%86%D9%88%D8%B9_%D8%AF%D8%B1_%D8%B1%D9%86%DA%AF_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%AE%D9%88%D8%A7%D8%A8\"><\/span>\u062a\u0646\u0648\u0639 \u062f\u0631 \u0631\u0646\u06af \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0634\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0641\u0631\u0634 \u0637\u0648\u0633\u06cc \u067e\u0631\u0646\u06af \u06cc\u0627 \u06a9\u0645\u200c\u0631\u0646\u06af\u060c \u0641\u0631\u0634\u200c\u0647\u0627\u06cc \u0644\u0627\u06a9\u06cc\u060c \u0642\u0631\u0645\u0632\u060c \u0637\u06cc\u0641\u200c\u0647\u0627\u06cc \u062a\u06cc\u0631\u0647 \u06cc\u0627 \u0631\u0648\u0634\u0646 \u0631\u0627 \u062f\u0631 \u0628\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0641\u0627\u0646\u062a\u0632\u06cc \u0628\u0647\u200c\u0631\u0627\u062d\u062a\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0646\u06cc\u062f. \u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc \u0628\u0627\u0639\u062b \u0634\u062f\u0647 \u0627\u0641\u0631\u0627\u062f \u0632\u06cc\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0645\u0634\u062a\u0627\u0642 \u0628\u0627\u0634\u0646\u062f.<\/p>\n<p>\u062a\u0646\u0648\u0639 \u0631\u0646\u06af\u06cc \u0632\u06cc\u0627\u062f \u0645\u0627\u0646\u0646\u062f \u062a\u0648\u0644\u06cc\u062f <a href=\"https:\/\/www.bfarsh.com\/product-tag\/%D9%81%D8%B1%D8%B4-%D9%84%D8%A7%DA%A9%DB%8C\/\" target=\"_blank\" rel=\"noopener\">\u0641\u0631\u0634 \u0644\u0627\u06a9\u06cc \u062c\u062f\u06cc\u062f<\/a> \u06cc\u0627 \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc \u0628\u0627 \u0631\u0646\u06af \u062e\u0646\u062b\u06cc \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0628\u0647 \u0634\u0645\u0627 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u062a\u0627 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0633\u0644\u06cc\u0642\u0647 \u06cc\u0627 \u0633\u0628\u06a9 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u062e\u0648\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0648 \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%AE%D9%88%D8%A7%D8%A8_%D9%88_%D8%AA%D9%86%D9%88%D8%B9_%D8%AF%D8%B1_%D8%B7%D8%B1%D8%AD\"><\/span>\u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0648 \u062a\u0646\u0648\u0639 \u062f\u0631 \u0637\u0631\u062d<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062a\u0646\u0648\u0639 \u0628\u0627\u0644\u0627 \u062f\u0631 \u0637\u0631\u062d \u0648 \u0646\u0642\u0634\u0647 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0628\u0627\u0639\u062b \u0634\u062f\u0647 \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u0647\u0631 \u0633\u0644\u06cc\u0642\u0647\u200c\u0627\u06cc \u06a9\u0647 \u062f\u0627\u0631\u0646\u062f \u0641\u0631\u0634 \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0645\u062f\u0644\u200c\u0647\u0627\u06cc \u0641\u0627\u0646\u062a\u0632\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f. \u067e\u0633 \u0628\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0627\u06cc\u0646 \u0645\u062f\u0644 \u062f\u0633\u062a \u0634\u0645\u0627 \u062f\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0637\u0631\u062d \u0628\u0627\u0632\u062a\u0631 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/p>\n<p>\u0627\u0644\u0628\u062a\u0647 \u0627\u06af\u0631 \u0641\u0631\u0634 \u0627\u0641\u0634\u0648\u0646 \u0628\u0627 \u0637\u0631\u0627\u062d\u06cc \u0634\u0644\u0648\u063a \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u0645\u0639\u0645\u0648\u0644\u0627 \u0645\u062f\u0644\u200c\u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0648 \u0646\u0647 \u0641\u0627\u0646\u062a\u0632\u06cc \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631 \u0647\u0633\u062a\u0646\u062f. \u0641\u0631\u0634\u200c\u0647\u0627\u06cc \u0641\u0627\u0646\u062a\u0632\u06cc \u0637\u0631\u062d \u0633\u0627\u062f\u0647\u200c\u062a\u0631\u06cc \u062f\u0627\u0631\u0646\u062f \u0648 \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0646\u06cc\u0632 \u0631\u0627\u062d\u062a\u200c\u062a\u0631 \u0628\u0627 \u0645\u062d\u06cc\u0637 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062a\u0646\u0627\u0633\u0628 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%DA%A9%DB%8C%D9%81%DB%8C%D8%AA_%D8%A8%D8%A7%D9%84%D8%A7%DB%8C_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C\"><\/span>\u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627\u06cc \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0641\u0631\u0634\u200c\u0647\u0627\u06cc \u0641\u0627\u0646\u062a\u0632\u06cc \u0628\u0627 \u0627\u0644\u06cc\u0627\u0641 \u0645\u062e\u062a\u0644\u0641\u06cc \u0645\u0627\u0646\u0646\u062f \u067e\u0634\u0645\u060c \u067e\u0646\u0628\u0647\u060c \u0627\u0628\u0631\u06cc\u0634\u0645 \u0648 \u067e\u0644\u06cc\u200c\u0627\u0633\u062a\u0631 \u0628\u0627\u0641\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0642\u0637\u0639\u0627 \u0647\u0631 \u0686\u0647 \u0645\u062a\u0631\u06cc\u0627\u0644 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062f\u0631 \u062a\u0648\u0644\u06cc\u062f \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0645\u0631\u063a\u0648\u0628\u200c\u062a\u0631 \u0628\u0627\u0634\u062f \u06a9\u06cc\u0641\u06cc\u062a \u0646\u0647\u0627\u06cc\u06cc \u0648 \u0642\u06cc\u0645\u062a \u0622\u0646 \u0646\u06cc\u0632 \u0627\u0641\u0632\u0627\u06cc\u0634 \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<p>\u0627\u0632\u0622\u0646\u062c\u0627\u06cc\u06cc\u200c\u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0641\u0631\u0627\u062f \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0631\u0627 \u0628\u0647\u200c\u062f\u0644\u06cc\u0644 \u0645\u0642\u0631\u0648\u0646\u200c\u0628\u0647\u200c\u0635\u0631\u0641\u0647 \u0628\u0648\u062f\u0646 \u0622\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u0647\u200c\u0647\u0627 \u0627\u0632 \u0627\u0644\u06cc\u0627\u0641 \u067e\u0644\u06cc\u200c\u0627\u0633\u062a\u0631 \u06a9\u0647 \u06a9\u06cc\u0641\u06cc\u062a \u062e\u0648\u0628\u06cc \u0646\u06cc\u0632 \u062f\u0627\u0631\u0646\u062f \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u0627\u06cc\u0646 \u0641\u0631\u0634 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n<p>\u0641\u0631\u0634\u200c\u0647\u0627\u06cc \u067e\u0644\u06cc\u200c\u0627\u0633\u062a\u0631 \u06a9\u06cc\u0641\u06cc\u062a \u062e\u0648\u0628\u06cc \u062f\u0627\u0631\u0646\u062f \u0627\u0645\u0627 \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u0646\u062f \u0641\u0631\u0634\u06cc \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0639\u0627\u0644\u06cc \u0648 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0628\u06cc\u0634\u062a\u0631 \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u06a9\u0646\u0646\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0628\u0627\u0641\u062a\u0647\u200c\u0634\u062f\u0647 \u0627\u0632 \u0627\u0628\u0631\u06cc\u0634\u0645 \u06cc\u0627 \u067e\u0634\u0645 \u06af\u0632\u06cc\u0646\u0647 \u0628\u0647\u062a\u0631\u06cc \u0628\u0647\u200c\u062d\u0633\u0627\u0628 \u0645\u06cc\u200c\u0622\u06cc\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%81%D8%B1%D8%B4%DB%8C_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%AE%D9%88%D8%A7%D8%A8_%D9%88_%D8%AA%D9%86%D8%A7%D8%B3%D8%A8_%D8%A8%D8%A7_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86\"><\/span>\u0641\u0631\u0634\u06cc \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0648 \u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u062f\u0644\u0627\u06cc\u0644 \u06cc\u0627 \u0628\u0647\u200c\u0639\u0628\u0627\u0631\u062a\u06cc \u0645\u0632\u0627\u06cc\u0627\u06cc \u062e\u0631\u06cc\u062f \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u06cc\u062c\u0627\u062f \u062a\u0646\u0627\u0633\u0628 \u0622\u0646 \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0627\u0633\u062a. \u062f\u0631 \u0648\u0627\u0642\u0639 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0628\u0647\u200c\u062f\u0644\u06cc\u0644 \u062a\u0646\u0648\u0639 \u0628\u0627\u0644\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0627\u0631\u062f \u062f\u0631 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u0644\u0628\u062a\u0647 \u0628\u0627 \u0633\u0628\u06a9 \u0645\u062f\u0631\u0646 \u0628\u0647\u200c\u0631\u0627\u062d\u062a\u06cc \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f.<\/p>\n<p>\u0627\u06af\u0631 \u0627\u06cc\u062c\u0627\u062f \u062a\u0646\u0627\u0633\u0628 \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0645\u0634\u06a9\u0644 \u0627\u0633\u062a \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0641\u0631\u0634\u200c\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0637\u0631\u062d\u200c \u0633\u0627\u062f\u0647 \u0648 \u0631\u0646\u06af\u06cc \u062e\u0646\u062b\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u06cc\u0646 \u0645\u062f\u0644 \u0645\u062d\u0635\u0648\u0644 \u062f\u0631 \u0641\u0631\u0634\u200c\u0647\u0627\u06cc \u0641\u0627\u0646\u062a\u0632\u06cc \u0628\u0647\u200c\u0631\u0627\u062d\u062a\u06cc \u0642\u0627\u0628\u0644 \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u0627\u0633\u062a \u0648 \u062f\u06cc\u06af\u0631 \u0644\u0627\u0632\u0645 \u0646\u06cc\u0633\u062a \u0645\u062f\u200c\u062a\u200c\u0632\u0645\u0627\u0646 \u0637\u0648\u0644\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0646 \u0622\u0646 \u0633\u067e\u0631\u06cc \u06a9\u0646\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%82%DB%8C%D9%85%D8%AA_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%AE%D9%88%D8%A7%D8%A8\"><\/span>\u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u06cc\u06af\u0631 \u0645\u0632\u06cc\u062a \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0631\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u062f\u0627\u0646\u0633\u062a. \u0627\u0644\u0628\u062a\u0647 \u0642\u06cc\u0645\u062a \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0628\u0647 \u0639\u0648\u0627\u0645\u0644 \u0632\u06cc\u0627\u062f\u06cc \u0628\u0633\u062a\u06af\u06cc \u062f\u0627\u0631\u062f \u0648 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0628\u0627 \u0627\u06cc\u0646 \u0645\u0648\u0627\u0631\u062f \u0622\u0634\u0646\u0627 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u062f\u0631 \u062d\u06cc\u0646 \u062e\u0631\u06cc\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0631\u0627 \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0627\u06cc\u0646 \u0639\u0648\u0627\u0645\u0644 \u0628\u0627\u06cc\u062f \u0628\u0647 \u062a\u0639\u062f\u0627\u062f \u0634\u0627\u0646\u0647 \u0648 \u062a\u0631\u0627\u06a9\u0645 \u0641\u0631\u0634\u060c \u0627\u0644\u06cc\u0627\u0641 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062f\u0631 \u062a\u0648\u0644\u06cc\u062f \u0645\u062d\u0635\u0648\u0644 \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0628\u0639\u0627\u062f \u0622\u0646 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f. \u062f\u0631\u0635\u0648\u0631\u062a\u06cc\u200c\u06a9\u0647 \u0628\u062e\u0648\u0627\u0647\u06cc\u062f \u0641\u0631\u0634 \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc\u200c\u0634\u062f\u0647 \u062a\u0648\u0633\u0637 \u0634\u0645\u0627 \u0627\u0632 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627\u06cc\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0628\u0627\u0634\u062f \u0628\u0627\u06cc\u062f \u0641\u0627\u0631\u063a \u0627\u0632 \u062a\u0648\u062c\u0647\u200c\u0628\u0647 \u0642\u06cc\u0645\u062a\u060c \u062a\u0646\u0647\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0627\u0644\u06cc\u0627\u0641 \u0648 \u062a\u0639\u062f\u0627\u062f \u0634\u0627\u0646\u0647 \u0645\u062d\u0635\u0648\u0644 \u0631\u0627 \u0645\u062f \u0646\u0638\u0631 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%DA%86%D8%B1%D8%A7_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D8%AA%D8%A7%D9%82_%D8%AE%D9%88%D8%A7%D8%A8_%D9%81%D8%B1%D8%B4_%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C_%D8%A8%D8%AE%D8%B1%DB%8C%D9%85%D8%9F\"><\/span>\u0686\u0631\u0627 \u0628\u0631\u0627\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0628\u062e\u0631\u06cc\u0645\u061f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u0646\u062a\u062e\u0627\u0628 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0628\u0647\u200c\u062f\u0644\u06cc\u0644 \u062a\u0646\u0648\u0639 \u0628\u0627\u0644\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u06cc\u0646 \u0645\u062f\u0644 \u0645\u062d\u0635\u0648\u0644 \u062f\u0627\u0631\u062f \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0627\u0633\u062a \u0648 \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u0633\u0644\u06cc\u0642\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0641\u0631\u0634 \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u062f\u0633\u062a\u0647\u200c\u0628\u0646\u062f\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f. \u0627\u0644\u0628\u062a\u0647 \u062f\u0644\u06cc\u0644 \u0645\u0647\u0645 \u062f\u06cc\u06af\u0631 \u0631\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0628\u0627\u0644\u0627\u06cc \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062f\u0627\u0646\u0633\u062a.<\/p>\n<p>\u0627\u06af\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0634\u0645\u0627 <a href=\"https:\/\/www.bfarsh.com\/product-category\/%D9%81%D8%B1%D8%B4-%D9%81%D8%A7%D9%86%D8%AA%D8%B2%DB%8C\/\" target=\"_blank\" rel=\"noopener\">\u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628<\/a> \u0627\u0633\u062a \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0631\u0627\u06cc \u0633\u0627\u0644\u200c\u0647\u0627\u06cc \u0637\u0648\u0644\u0627\u0646\u06cc \u0628\u062f\u0648\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u0646\u06af\u0631\u0627\u0646 \u062e\u0631\u0627\u0628\u06cc \u0648 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0646 \u06a9\u06cc\u0641\u06cc\u062a \u0622\u0646 \u0628\u0627\u0634\u06cc\u062f \u0627\u0632 \u0645\u062d\u0635\u0648\u0644 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0642\u0627\u0628\u0644\u06cc\u062a \u0627\u06cc\u062c\u0627\u062f \u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646\u200c\u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0648 \u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628 \u0627\u0632 \u062f\u06cc\u06af\u0631 \u062f\u0644\u0627\u06cc\u0644 \u0645\u062d\u0628\u0648\u0628\u06cc\u062a \u0648 \u062e\u0631\u06cc\u062f \u0627\u06cc\u0646 \u0641\u0631\u0634 \u0628\u0647\u200c\u062d\u0633\u0627\u0628 \u0645\u06cc\u200c\u0622\u06cc\u0646\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C\"><\/span>\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0686\u0631\u0627 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0628\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a\u061f \u0627\u0632 \u0645\u0632\u06cc\u062a\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646 \u0641\u0631\u0634 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628 \u0622\u0646 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f. \u0627\u0644\u0628\u062a\u0647 \u0627\u06cc\u0646 \u0642\u06cc\u0645\u062a \u0628\u0647 \u0639\u0648\u0627\u0645\u0644\u06cc \u0645\u0627\u0646\u0646\u062f \u0646\u0648\u0639 \u0627\u0644\u06cc\u0627\u0641 \u0648 \u062a\u0639\u062f\u0627\u062f \u0634\u0627\u0646\u0647 \u0646\u06cc\u0632 \u0628\u0633\u062a\u06af\u06cc \u062f\u0627\u0631\u062f.<\/p>\n<p>\u0627\u0632 \u062f\u06cc\u06af\u0631 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0627\u06cc\u0646 \u0641\u0631\u0634 \u0628\u0627\u06cc\u062f \u0628\u0647 \u062a\u0646\u0648\u0639 \u0628\u0627\u0644\u0627 \u062f\u0631 \u0637\u0631\u062d \u0648 \u0631\u0646\u06af \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0641\u0636\u0627\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0628\u0627\u0644\u0627\u06cc \u0622\u0646 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f. \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0646\u06cc\u0632 <a href=\"https:\/\/www.bfarsh.com\/\" target=\"_blank\" rel=\"noopener\">\u0634\u0631\u06a9\u062a \u0641\u0631\u0634 \u06a9\u0648\u0631\u0648\u0634<\/a> \u0646\u0645\u0648\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u062a\u0646\u0648\u0639\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0641\u0631\u0627\u0647\u0645 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u0686\u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647\u200c\u0647\u0627 \u0628\u0647\u200c\u0634\u0645\u0627\u0631 \u0645\u06cc\u200c\u0622\u06cc\u062f\u061f \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0686\u0647 \u0645\u0632\u0627\u06cc\u0627\u06cc\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647\u200c\u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u06a9\u0647 \u062f\u0631 \u0628\u06cc\u0646 \u062e\u0631\u06cc\u062f\u0627\u0631\u0627\u0646 \u0628\u0647 \u0645\u062d\u0628\u0648\u0628\u06cc\u062a \u0631\u0633\u06cc\u062f\u0647 \u0627\u0633\u062a\u061f \u0628\u0627 \u06cc\u0627\u0641\u062a\u0646 \u067e\u0627\u0633\u062e \u0627\u06cc\u0646 \u0633\u0648\u0627\u0644\u0627\u062a \u0627\u062d\u062a\u0645\u0627\u0644\u0627 \u0634\u0645\u0627 \u0646\u06cc\u0632 \u0628\u0631\u0627\u06cc \u0627\u062a\u0627\u0642 \u062e\u0648\u062f \u0641\u0631\u0634\u200c\u0647\u0627\u06cc \u0641\u0627\u0646\u062a\u0632\u06cc \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f. \u0641\u0631\u0634 \u0641\u0627\u0646\u062a\u0632\u06cc \u0645\u062d\u0635\u0648\u0644\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0628\u0647\u200c\u062e\u0648\u0628\u06cc [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":43730,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[678],"tags":[],"class_list":["post-43729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-678"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/43729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=43729"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/43729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/43730"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=43729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=43729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=43729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}