{"id":36163,"date":"2022-10-27T20:21:23","date_gmt":"2022-10-27T16:51:23","guid":{"rendered":"https:\/\/decorshop.ir\/mag\/?p=36163"},"modified":"2022-10-24T20:47:03","modified_gmt":"2022-10-24T17:17:03","slug":"%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/","title":{"rendered":"\u0627\u0635\u0648\u0644 \u0637\u0631\u0627\u062d\u06cc \u0628\u0631\u0627\u06cc \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644"},"content":{"rendered":"<p><strong>\u0627\u0635\u0648\u0644 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<\/strong>: \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0645\u06cc \u062e\u0648\u0627\u0647\u0646\u062f \u062f\u06a9\u0648\u0631 \u062e\u0627\u0646\u0647 \u0631\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0647\u0646\u062f \u06cc\u0627 \u0628\u0647 \u0637\u0631\u0627\u062d\u06cc \u062f\u0627\u062e\u0644\u06cc \u062c\u0627\u0646 \u0628\u062f\u0647\u0646\u062f\u060c \u0627\u0645\u0627 \u062f\u0631 \u0639\u06cc\u0646 \u062d\u0627\u0644 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u06cc\u062f\u0647 \u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628\u060c \u062e\u0644\u0627\u0642\u0627\u0646\u0647 \u0648 \u067e\u0631 \u062c\u0646\u0628 \u0648 \u062c\u0648\u0634 \u0628\u0627 \u0647\u062f\u0641 \u062f\u0633\u062a\u06cc\u0627\u0628\u06cc \u0628\u0647 \u062e\u0627\u0646\u0647 \u0627\u06cc \u0628\u0627\u0632\u0633\u0627\u0632\u06cc \u0634\u062f\u0647 \u0628\u0627 \u0628\u0648\u062f\u062c\u0647 \u06a9\u0645 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0646\u0628\u0627\u0634\u062f . \u0627\u0632 \u0627\u06cc\u0646 \u0646\u0638\u0631 \u0627\u0635\u0648\u0644 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644 \u0648 \u0645\u0648\u0627\u0631\u062f\u06cc \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0631\u0639\u0627\u06cc\u062a \u0634\u0648\u062f \u0627\u0632 \u0631\u0646\u06af \u0647\u0627 \u062a\u0627 \u062a\u0639\u0627\u062f\u0644 \u0648 \u0646\u06a9\u0627\u062a \u062f\u06cc\u06af\u0631\u06cc \u06a9\u0647 \u0628\u0647 \u062a\u0641\u0635\u06cc\u0644 \u062f\u0631 \u0645\u0648\u0631\u062f \u0622\u0646\u0647\u0627 \u0635\u062d\u0628\u062a \u062e\u0648\u0627\u0647\u06cc\u0645 \u06a9\u0631\u062f \u0631\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 <a href=\"\/mag\/\"><strong>\u062f\u06a9\u0648\u0631\u0645\u06af<\/strong><\/a> \u0628\u0647 \u0634\u0645\u0627 \u0627\u0637\u0644\u0627\u0639 \u062e\u0648\u0627\u0647\u06cc\u0645 \u062f\u0627\u062f.<\/p>\n<table>\n<tbody>\n<tr>\n<td bgcolor=\"#a01818\" width=\"5\"><\/td>\n<td bgcolor=\"#e4e4e4\" width=\"700px\">\u0645\u0634\u0627\u0647\u062f\u0647 \u062c\u062f\u06cc\u062f\u062a\u0631\u06cc\u0646 \u0645\u062f\u0644 \u0647\u0627\u060c \u0642\u06cc\u0645\u062a \u0648 \u062e\u0631\u06cc\u062f <a href=\"\/product-category\/\u0622\u0628\u0627\u0698\u0648\u0631\/\u0622\u0628\u0627\u0698\u0648\u0631-\u0631\u0648\u0645\u06cc\u0632\u06cc\/\"><strong>\u0622\u0628\u0627\u0698\u0648\u0631\u00a0\u0631\u0648\u0645\u06cc\u0632\u06cc<\/strong><\/a><\/td>\n<td bgcolor=\"#a01818\" width=\"5\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/#%D8%A7%D8%B5%D9%88%D9%84_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D8%AF%D8%A7%D8%AE%D9%84%DB%8C_%D9%85%D9%86%D8%B2%D9%84\" >\u0627\u0635\u0648\u0644 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/#%D9%85%D8%A8%D9%84%D9%85%D8%A7%D9%86_%D8%B1%D8%A7_%D8%B4%D8%AE%D8%B5%DB%8C_%DA%A9%D9%86%DB%8C%D8%AF\" >\u0645\u0628\u0644\u0645\u0627\u0646 \u0631\u0627 \u0634\u062e\u0635\u06cc \u06a9\u0646\u06cc\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/#%D8%B1%D9%86%DA%AF_%D9%87%D8%A7_%D8%B1%D8%A7_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%A9%D9%86%DB%8C%D8%AF\" >\u0631\u0646\u06af \u0647\u0627 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/#%D8%B1%D9%86%DA%AF_%D9%87%D8%A7%DB%8C_%D9%85%D8%AA%D8%B6%D8%A7%D8%AF\" >\u0631\u0646\u06af \u0647\u0627\u06cc \u0645\u062a\u0636\u0627\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/#%D8%B1%D9%86%DA%AF_%D9%87%D8%A7%DB%8C_%DA%AF%D8%B1%D8%A7%D8%AF%DB%8C%D8%A7%D9%86_%D8%B3%D9%84%D8%B3%D9%84%D9%87_%D9%85%D8%B1%D8%A7%D8%AA%D8%A8%DB%8C\" >\u0631\u0646\u06af \u0647\u0627\u06cc \u06af\u0631\u0627\u062f\u06cc\u0627\u0646 (\u0633\u0644\u0633\u0644\u0647 \u0645\u0631\u0627\u062a\u0628\u06cc).<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/#%D9%88%D8%AD%D8%AF%D8%AA_%D8%AF%D8%B1_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D8%AF%D8%A7%D8%AE%D9%84%DB%8C_%D9%85%D9%86%D8%B2%D9%84\" >\u0648\u062d\u062f\u062a \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/#%D8%AA%D8%B9%D8%A7%D8%AF%D9%84\" >\u062a\u0639\u0627\u062f\u0644<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/#%D8%AA%D8%B9%D8%A7%D8%AF%D9%84_%D9%85%D8%AA%D9%82%D8%A7%D8%B1%D9%86\" >\u062a\u0639\u0627\u062f\u0644 \u0645\u062a\u0642\u0627\u0631\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/#%D8%AA%D8%B9%D8%A7%D8%AF%D9%84_%D9%86%D8%A7%D9%85%D8%AA%D9%82%D8%A7%D8%B1%D9%86_%D8%AF%D8%B1_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D8%AF%D8%A7%D8%AE%D9%84%DB%8C_%D9%85%D9%86%D8%B2%D9%84\" >\u062a\u0639\u0627\u062f\u0644 \u0646\u0627\u0645\u062a\u0642\u0627\u0631\u0646 \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/#%D8%AA%D8%B9%D8%A7%D8%AF%D9%84_%D8%AA%D8%A7%D8%A8%D8%B4%DB%8C\" >\u062a\u0639\u0627\u062f\u0644 \u062a\u0627\u0628\u0634\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/#%D9%81%D8%B6%D8%A7%D9%87%D8%A7%DB%8C_%D8%B0%D8%AE%DB%8C%D8%B1%D9%87_%D8%B3%D8%A7%D8%B2%DB%8C_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%DA%A9%D9%86%DB%8C%D8%AF\" >\u0641\u0636\u0627\u0647\u0627\u06cc \u0630\u062e\u06cc\u0631\u0647 \u0633\u0627\u0632\u06cc \u0645\u0646\u0627\u0633\u0628 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u06cc\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/#%D8%B1%D9%88%D8%B4%D9%86%D8%A7%DB%8C%DB%8C_%D8%AF%D8%B1_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D8%AF%D8%A7%D8%AE%D9%84%DB%8C_%D9%85%D9%86%D8%B2%D9%84\" >\u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d8%af%d8%a7%d8%ae%d9%84%db%8c-%d9%85%d9%86%d8%b2%d9%84\/#%D9%82%D8%B7%D8%B9%D8%A7%D8%AA_%D8%AA%D8%B2%D8%A6%DB%8C%D9%86%DB%8C_%D9%85%D9%87%D9%85_%D8%AF%D8%B1_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D8%AF%D8%A7%D8%AE%D9%84%DB%8C_%D9%85%D9%86%D8%B2%D9%84\" >\u0642\u0637\u0639\u0627\u062a \u062a\u0632\u0626\u06cc\u0646\u06cc \u0645\u0647\u0645 \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B5%D9%88%D9%84_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D8%AF%D8%A7%D8%AE%D9%84%DB%8C_%D9%85%D9%86%D8%B2%D9%84\"><\/span>\u0627\u0635\u0648\u0644 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0645\u06cc \u062f\u0627\u0646\u06cc\u0645 \u06a9\u0647 \u0637\u0631\u0627\u062d\u06cc \u0648 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0628\u0647 \u062e\u0648\u062f\u06cc \u062e\u0648\u062f \u06cc\u06a9 \u0639\u0644\u0645 \u0648 \u06cc\u06a9 \u0645\u0637\u0627\u0644\u0639\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0634\u0627\u062e\u0647 \u0645\u062c\u0632\u0627 \u062f\u0631 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0647\u0627 \u062a\u062f\u0631\u06cc\u0633 \u0645\u06cc \u0634\u0648\u062f \u0648 \u0647\u0645\u0647 \u0645\u0627 \u0622\u0631\u0632\u0648\u06cc \u062e\u0627\u0646\u0647 \u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0634\u06cc\u06a9 \u0648 \u062e\u06cc\u0631\u0647 \u06a9\u0646\u0646\u062f\u0647 \u0631\u0627 \u062f\u0631 \u0633\u0631 \u0645\u06cc \u067e\u0631\u0648\u0631\u0627\u0646\u06cc\u0645\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0627 \u0645\u0647\u0645 \u062a\u0631\u06cc\u0646 \u0646\u06a9\u0627\u062a \u0648 \u0627\u0635\u0648\u0644 \u0627\u0648\u0644\u06cc\u0647 \u0622\u0634\u0646\u0627 \u0645\u06cc \u0634\u0648\u06cc\u0645. \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D8%A8%D9%84%D9%85%D8%A7%D9%86_%D8%B1%D8%A7_%D8%B4%D8%AE%D8%B5%DB%8C_%DA%A9%D9%86%DB%8C%D8%AF\"><\/span>\u0645\u0628\u0644\u0645\u0627\u0646 \u0631\u0627 \u0634\u062e\u0635\u06cc \u06a9\u0646\u06cc\u062f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<figure id=\"attachment_73806\" class=\"wp-caption aligncenter\" aria-describedby=\"caption-attachment-73806\">\n<figure id=\"attachment_36164\" aria-describedby=\"caption-attachment-36164\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36164 size-full\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646-\u062f\u0627\u062e\u0644\u06cc-\u0645\u0646\u0632\u0644.jpg\" alt=\"\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644\" width=\"700\" height=\"438\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646-\u062f\u0627\u062e\u0644\u06cc-\u0645\u0646\u0632\u0644.jpg 700w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646-\u062f\u0627\u062e\u0644\u06cc-\u0645\u0646\u0632\u0644-300x188.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-36164\" class=\"wp-caption-text\">\u0645\u0628\u0644\u0645\u0627\u0646 \u0648 \u0644\u0648\u0627\u0632\u0645 \u062c\u0627\u0646\u0628\u06cc \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0634\u062e\u0635\u06cc\u062a \u062e\u0648\u062f \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f<\/figcaption><\/figure>\n<table>\n<tbody>\n<tr>\n<td bgcolor=\"#a01818\" width=\"5\"><\/td>\n<td bgcolor=\"#e4e4e4\" width=\"700px\">\u0645\u0634\u0627\u0647\u062f\u0647 \u062c\u062f\u06cc\u062f\u062a\u0631\u06cc\u0646 \u0645\u062f\u0644 \u0647\u0627\u060c \u0642\u06cc\u0645\u062a \u0648 \u062e\u0631\u06cc\u062f <a href=\"\/product-category\/\u0645\u06cc\u0632-\u0648-\u0645\u0628\u0644\/\u0645\u0628\u0644\u0645\u0627\u0646-\u0631\u0627\u062d\u062a\u06cc\/\"><strong>\u0645\u0628\u0644\u0645\u0627\u0646 \u0631\u0627\u062d\u062a\u06cc<\/strong><\/a><\/td>\n<td bgcolor=\"#a01818\" width=\"5\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u062e\u0627\u0646\u0647 \u067e\u0646\u0627\u0647\u06af\u0627\u0647 \u0627\u0645\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u0627 \u067e\u0633 \u0627\u0632 \u06cc\u06a9 \u0631\u0648\u0632 \u0637\u0648\u0644\u0627\u0646\u06cc \u067e\u0631 \u0627\u0632 \u06a9\u0627\u0631 \u0648 \u0633\u062e\u062a\u06cc \u0628\u0647 \u0622\u0646 \u067e\u0646\u0627\u0647 \u0645\u06cc \u0628\u0631\u06cc\u0645 \u0648 \u0645\u06a9\u0627\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0645\u0627 \u0627\u062d\u0633\u0627\u0633 \u0622\u0631\u0627\u0645\u0634 \u0648 \u062a\u0639\u0644\u0642 \u0645\u06cc \u062f\u0647\u062f\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0647\u0646\u06af\u0627\u0645 \u0641\u06a9\u0631 \u06a9\u0631\u062f\u0646 \u0628\u0647 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646\u060c \u0628\u0627\u06cc\u062f \u0628\u0647 \u0641\u06a9\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0642\u0637\u0639\u0627\u062a\u06cc \u0628\u0627\u0634\u06cc\u0645 \u06a9\u0647 \u0645\u0637\u0627\u0628\u0642 \u0628\u0627 \u0634\u062e\u0635\u06cc\u062a \u0633\u0627\u06a9\u0646\u06cc\u0646 \u062e\u0627\u0646\u0647.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B1%D9%86%DA%AF_%D9%87%D8%A7_%D8%B1%D8%A7_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%A9%D9%86%DB%8C%D8%AF\"><\/span>\u0631\u0646\u06af \u0647\u0627 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<figure id=\"attachment_73808\" class=\"wp-caption aligncenter\" aria-describedby=\"caption-attachment-73808\">\n<figure id=\"attachment_36165\" aria-describedby=\"caption-attachment-36165\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36165\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u0631\u0646\u06af-\u062f\u0631-\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646-\u062f\u0627\u062e\u0644\u06cc-\u0645\u0646\u0632\u0644.jpg\" alt=\"\u0631\u0646\u06af \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644\" width=\"700\" height=\"438\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u0631\u0646\u06af-\u062f\u0631-\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646-\u062f\u0627\u062e\u0644\u06cc-\u0645\u0646\u0632\u0644.jpg 700w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u0631\u0646\u06af-\u062f\u0631-\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646-\u062f\u0627\u062e\u0644\u06cc-\u0645\u0646\u0632\u0644-300x188.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-36165\" class=\"wp-caption-text\">\u0647\u0645\u0627\u0647\u0646\u06af\u06cc \u0631\u0646\u06af \u0647\u0627 \u062f\u0631 \u06cc\u06a9 \u0627\u062a\u0627\u0642 \u0628\u0647 \u0631\u0648\u0634\u06cc \u0645\u0634\u0627\u0628\u0647 \u06cc\u0627 \u0645\u062a\u0636\u0627\u062f<\/figcaption><\/figure><\/figure>\n<p>\u0631\u0646\u06af \u0647\u0627 \u0639\u0646\u0635\u0631 \u0645\u0647\u0645\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0628\u0647 \u0645\u06a9\u0627\u0646 \u0646\u0634\u0627\u0637 \u0628\u062e\u0634\u06cc\u062f\u0647 \u0648 \u0622\u0646 \u0631\u0627 \u0627\u062d\u06cc\u0627 \u0645\u06cc \u06a9\u0646\u0646\u062f \u0648 \u0647\u0631 \u0631\u0646\u06af\u06cc \u067e\u06cc\u0627\u0645\u062f\u0647\u0627 \u0648 \u062a\u0627\u062b\u06cc\u0631\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u062e\u0648\u062f \u0631\u0627 \u062f\u0627\u0631\u062f\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0642\u0628\u0644 \u0627\u0632 \u0634\u0631\u0648\u0639 \u0627\u0646\u062a\u062e\u0627\u0628 \u0631\u0646\u06af \u062f\u06cc\u0648\u0627\u0631\u0647\u0627 \u06cc\u0627 \u0645\u0628\u0644\u0645\u0627\u0646\u060c \u0634\u0645\u0627 \u0631\u0627 \u0628\u0627 \u0627\u0644\u06af\u0648\u0647\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0631\u0646\u06af \u0622\u0634\u0646\u0627 \u0645\u06cc \u06a9\u0646\u06cc\u0645.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%B1%D9%86%DA%AF_%D9%87%D8%A7%DB%8C_%D9%85%D8%AA%D8%B6%D8%A7%D8%AF\"><\/span>\u0631\u0646\u06af \u0647\u0627\u06cc \u0645\u062a\u0636\u0627\u062f<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u06a9\u0627\u0631 \u0628\u0631 \u0631\u0648\u06cc \u0627\u06cc\u0646 \u0646\u0642\u0637\u0647 \u0645\u0633\u062a\u0644\u0632\u0645 \u062c\u0633\u0627\u0631\u062a \u0648 \u0634\u062c\u0627\u0639\u062a \u0627\u0633\u062a\u060c \u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u06cc\u062f\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0631\u0646\u06af\u0647\u0627\u06cc \u0645\u062a\u0636\u0627\u062f \u062f\u0631 \u062f\u0627\u06cc\u0631\u0647 \u0631\u0646\u06af \u0645\u0627\u0646\u0646\u062f \u0642\u0631\u0645\u0632 \u0648 \u0633\u0628\u0632\u060c \u0628\u0627 \u0627\u0645\u06a9\u0627\u0646 \u0627\u0641\u0632\u0648\u062f\u0646 \u0631\u0646\u06af\u0647\u0627\u06cc \u0645\u06a9\u0645\u0644 \u0628\u0647 \u0622\u0646\u0647\u0627 \u0628\u0627 \u0645\u062e\u0644\u0648\u0637 \u06a9\u0631\u062f\u0646 \u0622\u0646\u0647\u0627 \u0628\u0627 \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u062f\u0631 \u0646\u0633\u0628\u062a\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u06cc\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0627\u0635\u0644 \u0647\u0627\u0631\u0645\u0648\u0646\u06cc \u0633\u0647 \u06af\u0627\u0646\u0647 \u06a9\u0647 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0645\u0641\u0647\u0648\u0645 \u0627\u0646\u062a\u062e\u0627\u0628 \u0633\u0647 \u0631\u0646\u06af \u0645\u062a\u0636\u0627\u062f \u0645\u0627\u0646\u0646\u062f \u0633\u0628\u0632\u060c \u0646\u0627\u0631\u0646\u062c\u06cc \u0648 \u0628\u0646\u0641\u0634 \u0627\u0633\u062a.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%B1%D9%86%DA%AF_%D9%87%D8%A7%DB%8C_%DA%AF%D8%B1%D8%A7%D8%AF%DB%8C%D8%A7%D9%86_%D8%B3%D9%84%D8%B3%D9%84%D9%87_%D9%85%D8%B1%D8%A7%D8%AA%D8%A8%DB%8C\"><\/span>\u0631\u0646\u06af \u0647\u0627\u06cc \u06af\u0631\u0627\u062f\u06cc\u0627\u0646 (\u0633\u0644\u0633\u0644\u0647 \u0645\u0631\u0627\u062a\u0628\u06cc).<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0627\u06cc\u0646 \u0641\u0631\u0622\u06cc\u0646\u062f \u0645\u0627\u0646\u0646\u062f \u0627\u06cc\u062f\u0647 \u0642\u0628\u0644\u06cc \u0646\u06cc\u0627\u0632 \u0628\u0647 \u062c\u0633\u0627\u0631\u062a \u0648 \u0634\u062c\u0627\u0639\u062a \u0632\u06cc\u0627\u062f\u06cc \u0646\u062f\u0627\u0631\u062f \u0628\u0644\u06a9\u0647 \u0628\u0631 \u062f\u0648 \u0627\u0635\u0644 \u0627\u0633\u062a\u0648\u0627\u0631 \u0627\u0633\u062a:\u00a0\u0631\u0646\u06af \u0647\u0627\u06cc \u0645\u062c\u0627\u0648\u0631 \u0645\u0627\u0646\u0646\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u0622\u0628\u06cc \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0631\u0646\u06af \u0627\u0635\u0644\u06cc \u0648 \u062f\u0648 \u0631\u0646\u06af \u0645\u062c\u0627\u0648\u0631 \u0633\u0628\u0632 \u0645\u0627\u06cc\u0644 \u0628\u0647 \u0622\u0628\u06cc \u0648 \u0628\u0646\u0641\u0634 \u0645\u0627\u06cc\u0644 \u0628\u0647 \u0622\u0628\u06cc.\u00a0\u0627\u0635\u0644 \u062f\u0648\u0645 \u0627\u0646\u062a\u062e\u0627\u0628 \u0631\u0646\u06af \u062e\u0646\u062b\u06cc \u0648 \u0633\u067e\u0633 \u062f\u0648 \u0631\u0646\u06af \u0628\u0631\u06af\u0631\u0641\u062a\u0647 \u0627\u0632 \u0622\u0646 \u0627\u0633\u062a\u060c \u0645\u0627\u0646\u0646\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u0631\u0646\u06af \u0633\u0641\u06cc\u062f \u0648 \u062a\u0631\u06a9\u06cc\u0628 \u0622\u0646 \u0628\u0627 \u0645\u0634\u06a9\u06cc \u0648 \u062e\u0627\u06a9\u0633\u062a\u0631\u06cc.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%88%D8%AD%D8%AF%D8%AA_%D8%AF%D8%B1_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D8%AF%D8%A7%D8%AE%D9%84%DB%8C_%D9%85%D9%86%D8%B2%D9%84\"><\/span>\u0648\u062d\u062f\u062a \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<figure id=\"attachment_73807\" class=\"wp-caption aligncenter\" aria-describedby=\"caption-attachment-73807\">\n<figure id=\"attachment_36166\" aria-describedby=\"caption-attachment-36166\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36166\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u0627\u06cc\u062c\u0627\u062f-\u062a\u0639\u0627\u062f\u0644-\u0648-\u0647\u0645\u0627\u0647\u0646\u06af\u06cc-\u0628\u06cc\u0646-\u0642\u0637\u0639\u0627\u062a-\u0645\u0628\u0644\u0645\u0627\u0646.jpg\" alt=\"\u0627\u06cc\u062c\u0627\u062f \u062a\u0639\u0627\u062f\u0644 \u0648 \u0647\u0645\u0627\u0647\u0646\u06af\u06cc \u0628\u06cc\u0646 \u0642\u0637\u0639\u0627\u062a \u0645\u0628\u0644\u0645\u0627\u0646\" width=\"700\" height=\"438\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u0627\u06cc\u062c\u0627\u062f-\u062a\u0639\u0627\u062f\u0644-\u0648-\u0647\u0645\u0627\u0647\u0646\u06af\u06cc-\u0628\u06cc\u0646-\u0642\u0637\u0639\u0627\u062a-\u0645\u0628\u0644\u0645\u0627\u0646.jpg 700w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u0627\u06cc\u062c\u0627\u062f-\u062a\u0639\u0627\u062f\u0644-\u0648-\u0647\u0645\u0627\u0647\u0646\u06af\u06cc-\u0628\u06cc\u0646-\u0642\u0637\u0639\u0627\u062a-\u0645\u0628\u0644\u0645\u0627\u0646-300x188.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-36166\" class=\"wp-caption-text\">\u0627\u06cc\u062c\u0627\u062f \u062a\u0639\u0627\u062f\u0644 \u0648 \u0647\u0645\u0627\u0647\u0646\u06af\u06cc \u0628\u06cc\u0646 \u0642\u0637\u0639\u0627\u062a \u0645\u0628\u0644\u0645\u0627\u0646 | \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<\/figcaption><\/figure>\n<table>\n<tbody>\n<tr>\n<td bgcolor=\"#a01818\" width=\"5\"><\/td>\n<td bgcolor=\"#e4e4e4\" width=\"700px\">\u0645\u0634\u0627\u0647\u062f\u0647 \u062c\u062f\u06cc\u062f\u062a\u0631\u06cc\u0646 \u0645\u062f\u0644 \u0647\u0627\u060c \u0642\u06cc\u0645\u062a \u0648 \u062e\u0631\u06cc\u062f <a href=\"\/product-category\/\u0645\u0628\u0644\/\u0645\u0628\u0644-\u062a\u062e\u062a\u062e\u0648\u0627\u0628-\u0634\u0648\/\"><strong>\u0645\u0628\u0644 \u062a\u062e\u062a\u062e\u0648\u0627\u0628 \u0634\u0648<\/strong><\/a><\/td>\n<td bgcolor=\"#a01818\" width=\"5\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u0648\u062d\u062f\u062a \u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0646\u06a9\u0627\u062a \u0627\u0633\u0627\u0633\u06cc \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u062e\u0627\u0646\u0647 \u0627\u0633\u062a \u0648 \u0644\u0632\u0648\u0645\u0627\u064b \u0628\u0647 \u0645\u0639\u0646\u0627\u06cc \u062a\u0642\u0627\u0631\u0646 \u06cc\u0627 \u06cc\u06a9\u0646\u0648\u0627\u062e\u062a\u06cc \u062f\u0631 \u0645\u0628\u0644\u0645\u0627\u0646 \u06cc\u0627 \u062d\u06a9\u0627\u06a9\u06cc \u0648 \u0646\u0642\u0627\u0634\u06cc \u062f\u0631 \u06cc\u06a9 \u0645\u06a9\u0627\u0646 \u0646\u06cc\u0633\u062a\u060c \u0628\u0644\u06a9\u0647 \u0646\u06af\u0627\u0647 \u06a9\u0644\u06cc \u0628\u0627\u06cc\u062f \u062d\u0627\u06a9\u06cc \u0627\u0632 \u062a\u062f\u0627\u0648\u0645 \u0648 \u0648\u062c\u0648\u062f \u0646\u0642\u0627\u0637 \u0645\u0634\u062a\u0631\u06a9 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0622\u0646 \u0628\u0627\u0634\u062f. \u06a9\u0647 \u0686\u0634\u0645 \u0627\u0632 \u062c\u0627\u06cc\u06cc \u0628\u0647 \u062c\u0627\u06cc \u062f\u06cc\u06af\u0631 \u062d\u0631\u06a9\u062a \u0645\u06cc \u06a9\u0646\u062f\u060c \u0645\u0627\u0646\u0646\u062f \u0631\u0646\u06af \u0622\u0645\u06cc\u0632\u06cc \u062f\u06cc\u0648\u0627\u0631\u0647\u0627 \u0628\u0647 \u06cc\u06a9 \u0631\u0646\u06af \u06cc\u0627 \u06a9\u0641 \u0647\u0627 \u0627\u0632 \u06cc\u06a9 \u0646\u0648\u0639 \u0645\u062a\u0631\u06cc\u0627\u0644 \u062f\u0631 \u0645\u0628\u0644\u0645\u0627\u0646 \u0647\u0645\u0647 \u0627\u062a\u0627\u0642 \u0647\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f.<\/p>\n<p>\u062f\u0631 \u0627\u06cc\u0646\u062c\u0627 \u0628\u0627\u06cc\u062f \u0628\u0647 \u0646\u06a9\u062a\u0647 \u062f\u06cc\u06af\u0631\u06cc \u0646\u06cc\u0632 \u062a\u0648\u062c\u0647 \u06a9\u0631\u062f \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0645\u0628\u0644\u0645\u0627\u0646 \u0628\u0627 \u0641\u0636\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0634\u063a\u0627\u0644 \u0645\u06cc \u06a9\u0646\u062f \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a \u0645\u0627\u0646\u0646\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u0642\u0637\u0639\u0627\u062a\u06cc \u06a9\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u0622\u0646\u0647\u0627 \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0641\u0636\u0627\u06cc \u0627\u062a\u0627\u0642 \u0628\u0627\u0634\u062f \u062a\u0627 \u0641\u0636\u0627\u06cc\u06cc \u0646\u0627\u0645\u0637\u0644\u0648\u0628 \u0648 \u0634\u0644\u0648\u063a \u0648 \u063a\u06cc\u0631 \u0636\u0631\u0648\u0631\u06cc \u0627\u06cc\u062c\u0627\u062f \u0646\u0634\u0648\u062f. \u0645\u0648\u0627\u0631\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%D8%B9%D8%A7%D8%AF%D9%84\"><\/span>\u062a\u0639\u0627\u062f\u0644<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u06cc\u062f\u0647 \u062a\u0639\u0627\u062f\u0644 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0635\u0648\u0644 \u0627\u0648\u0644\u06cc\u0647 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644 \u0628\u0647 \u0686\u0646\u062f \u0634\u0627\u062e\u0647 \u062a\u0642\u0633\u06cc\u0645 \u0645\u06cc \u0634\u0648\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%AA%D8%B9%D8%A7%D8%AF%D9%84_%D9%85%D8%AA%D9%82%D8%A7%D8%B1%D9%86\"><\/span>\u062a\u0639\u0627\u062f\u0644 \u0645\u062a\u0642\u0627\u0631\u0646<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<figure id=\"attachment_73809\" class=\"wp-caption aligncenter\" aria-describedby=\"caption-attachment-73809\">\n<figure id=\"attachment_36167\" aria-describedby=\"caption-attachment-36167\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36167\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646-\u062f\u0627\u062e\u0644\u06cc-\u0645\u0646\u0632\u0644-1.jpg\" alt=\"\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644\" width=\"700\" height=\"438\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646-\u062f\u0627\u062e\u0644\u06cc-\u0645\u0646\u0632\u0644-1.jpg 700w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646-\u062f\u0627\u062e\u0644\u06cc-\u0645\u0646\u0632\u0644-1-300x188.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-36167\" class=\"wp-caption-text\">\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<\/figcaption><\/figure><\/figure>\n<p>\u0627\u06cc\u0646 \u06cc\u06a9 \u0633\u0628\u06a9 \u0639\u0627\u0631\u06cc \u0627\u0632 \u0646\u0648\u0622\u0648\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u0635\u0644 \u0637\u0631\u0627\u062d\u06cc \u0627\u062a\u0627\u0642 \u0628\u0647 \u06af\u0648\u0646\u0647 \u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u06af\u0648\u06cc\u06cc \u0628\u0647 \u062f\u0648 \u0642\u0633\u0645\u062a \u06a9\u0627\u0645\u0644\u0627\u064b \u06cc\u06a9\u0633\u0627\u0646 \u062a\u0642\u0633\u06cc\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u06af\u0648\u06cc\u06cc \u06cc\u06a9 \u062e\u0637 \u062e\u06cc\u0627\u0644\u06cc \u0628\u06cc\u0646 \u0622\u0646\u0647\u0627 \u0645\u06cc \u06af\u0630\u0631\u062f.\u00a0\u0627\u06cc\u0646 \u0627\u0635\u0644 \u062c\u0630\u0627\u0628 \u0648 \u0631\u0627\u062d\u062a \u0627\u0633\u062a\u060c \u0627\u0645\u0627 \u0628\u0631\u0627\u06cc \u0645\u062f\u062a \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0648\u062a\u0627\u0647\u06cc \u06a9\u0647 \u0641\u0631\u062f \u0632\u0648\u062f \u062e\u0633\u062a\u0647 \u0645\u06cc \u0634\u0648\u062f\u060c \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0648\u062c\u0648\u062f \u0639\u0646\u0635\u0631 \u0631\u0648\u062a\u06cc\u0646 \u0648 \u062a\u06a9\u0631\u0627\u0631 \u062f\u0631 \u0686\u06cc\u062f\u0645\u0627\u0646 \u062a\u0627\u0628\u0644\u0648\u0647\u0627\u060c \u0648\u0633\u0627\u06cc\u0644 \u0648 \u0633\u0627\u06cc\u0631 \u0645\u0648\u0627\u062f \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<blockquote><p><em>\u0628\u06cc\u0634\u062a\u0631 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f:<\/em><\/p><\/blockquote>\n<p><a href=\"\/mag\/\u0645\u0639\u0631\u0641\u06cc-5-\u062a\u0631\u06a9\u06cc\u0628-\u0631\u0646\u06af-\u0627\u062a\u0627\u0642-\u062e\u0648\u0627\u0628-\u0646\u06a9\u0627\u062a-\u0637\u0644\u0627\u06cc\u06cc-\u0639\/\"><strong>\u0645\u0639\u0631\u0641\u06cc \u06f5 \u062a\u0631\u06a9\u06cc\u0628 \u0631\u0646\u06af \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 \u0645\u062f\u0631\u0646 \u0648 \u0634\u06cc\u06a9 + \u0646\u06a9\u0627\u062a \u0637\u0644\u0627\u06cc\u06cc \u0648 \u0639\u06a9\u0633<\/strong><\/a><\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%AA%D8%B9%D8%A7%D8%AF%D9%84_%D9%86%D8%A7%D9%85%D8%AA%D9%82%D8%A7%D8%B1%D9%86_%D8%AF%D8%B1_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D8%AF%D8%A7%D8%AE%D9%84%DB%8C_%D9%85%D9%86%D8%B2%D9%84\"><\/span>\u062a\u0639\u0627\u062f\u0644 \u0646\u0627\u0645\u062a\u0642\u0627\u0631\u0646 \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0628\u0647 \u0622\u0646 \u062a\u0639\u0627\u062f\u0644 \u0641\u0639\u0627\u0644 \u0645\u06cc \u06af\u0648\u06cc\u0646\u062f \u0648 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0632\u06cc\u062a \u0647\u0627\u06cc \u0622\u0646 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0627\u0645\u06a9\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0642\u0637\u0639\u0627\u062a \u0628\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u0647\u0627 \u0648 \u0648\u0632\u0646 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0631\u0627 \u062f\u0631 \u06cc\u06a9 \u0627\u062a\u0627\u0642 \u0645\u06cc \u062f\u0647\u062f \u06a9\u0647 \u0646\u0642\u0634 \u0645\u0647\u0645\u06cc \u062f\u0631 \u0627\u06cc\u0646 \u0627\u0635\u0644 \u062f\u0627\u0631\u062f\u060c \u0645\u0627\u0646\u0646\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u0635\u0646\u062f\u0644\u06cc \u0633\u0627\u062a\u0646 \u06cc\u0627 \u0686\u0648\u0628 \u0628\u0627 \u0645\u06cc\u0632 \u0634\u06cc\u0634\u0647 \u0627\u06cc. \u0648\u0632\u0646 \u0628\u0635\u0631\u06cc \u0634\u06cc\u0634\u0647 \u0633\u0628\u06a9\u062a\u0631 \u0627\u0632 \u0648\u0632\u0646 \u0628\u0635\u0631\u06cc \u0686\u0648\u0628 \u0648 \u0633\u0627\u062a\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627\u0639\u062b \u0645\u06cc \u0634\u0648\u062f \u0627\u062e\u062a\u0644\u0627\u0637 \u0628\u06cc\u0646 \u0622\u0646\u0647\u0627 \u0641\u0636\u0627\u06cc\u06cc \u0646\u0627\u0645\u062a\u0642\u0627\u0631\u0646 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u062f \u0627\u0645\u0627 \u062f\u0631 \u0639\u06cc\u0646 \u062d\u0627\u0644 \u062e\u0633\u062a\u0647 \u06a9\u0646\u0646\u062f\u0647 \u0648 \u062c\u0630\u0627\u0628 \u0646\u06cc\u0633\u062a.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%AA%D8%B9%D8%A7%D8%AF%D9%84_%D8%AA%D8%A7%D8%A8%D8%B4%DB%8C\"><\/span>\u062a\u0639\u0627\u062f\u0644 \u062a\u0627\u0628\u0634\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0627\u06cc\u0646 \u0627\u06cc\u062f\u0647 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u06cc\u062f\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u06cc\u06a9 \u0646\u0642\u0637\u0647 \u062e\u06cc\u0627\u0644\u06cc \u0627\u0633\u062a \u0648 \u0628\u0639\u062f \u0627\u0632 \u0622\u0646 \u0642\u0637\u0639\u0627\u062a \u0645\u0628\u0644\u0645\u0627\u0646 \u062f\u0648\u0631 \u0622\u0646 \u0686\u06cc\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f\u060c \u0686\u06cc\u0632\u06cc \u06a9\u0647 \u0627\u063a\u0644\u0628 \u062f\u0631 \u0648\u0631\u0648\u062f\u06cc \u062e\u0627\u0646\u0647 \u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u067e\u06cc\u062f\u0627 \u0645\u06cc \u06a9\u0646\u06cc\u0645.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%81%D8%B6%D8%A7%D9%87%D8%A7%DB%8C_%D8%B0%D8%AE%DB%8C%D8%B1%D9%87_%D8%B3%D8%A7%D8%B2%DB%8C_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%DA%A9%D9%86%DB%8C%D8%AF\"><\/span>\u0641\u0636\u0627\u0647\u0627\u06cc \u0630\u062e\u06cc\u0631\u0647 \u0633\u0627\u0632\u06cc \u0645\u0646\u0627\u0633\u0628 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u06cc\u062f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u06cc\u062f\u0647\u200c\u0647\u0627\u06cc\u00a0\u0632\u06cc\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0627\u0632 \u0627\u0645\u0644\u0627\u06a9 \u06a9\u0648\u0686\u06a9 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647\u00a0\u0628\u0631\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0645\u0647\u0645 \u0627\u0633\u062a\u060c \u0645\u0627\u0646\u0646\u062f \u0646\u0635\u0628 \u0642\u0641\u0633\u0647\u200c\u0647\u0627\u06cc \u0628\u0644\u0646\u062f \u0631\u0648\u06cc \u062f\u06cc\u0648\u0627\u0631\u0647\u0627\u060c \u062a\u0627 \u0628\u0647 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0627\u06cc\u062d\u062a\u0627\u062c \u0631\u0648\u0632\u0627\u0646\u0647 \u06a9\u0645\u06a9 \u06a9\u0646\u062f \u0648 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u062c\u0644\u0648\u06cc \u0686\u0634\u0645\u0627\u0646\u0645\u0627\u0646 \u0642\u0631\u0627\u0631 \u0646\u062f\u0647\u062f \u0648 \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u0632\u0627\u0646\u0648 \u062f\u0631 \u0627\u062a\u0627\u0642 \u0634\u0648\u062f.<\/p>\n<table>\n<tbody>\n<tr>\n<td bgcolor=\"#a01818\" width=\"5\"><\/td>\n<td bgcolor=\"#e4e4e4\" width=\"700px\">\u0645\u0634\u0627\u0647\u062f\u0647 \u062c\u062f\u06cc\u062f\u062a\u0631\u06cc\u0646 \u0645\u062f\u0644 \u0647\u0627\u060c \u0642\u06cc\u0645\u062a \u0648 \u062e\u0631\u06cc\u062f <a href=\"\/product-category\/\u0622\u0628\u0627\u0698\u0648\u0631\/\u0622\u0628\u0627\u0698\u0648\u0631-\u0627\u06cc\u0633\u062a\u0627\u062f\u0647-\u0648-\u06a9\u0646\u0627\u0631\u0633\u0627\u0644\u0646\u06cc\/\"><strong>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647<\/strong><\/a><\/td>\n<td bgcolor=\"#a01818\" width=\"5\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B1%D9%88%D8%B4%D9%86%D8%A7%DB%8C%DB%8C_%D8%AF%D8%B1_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D8%AF%D8%A7%D8%AE%D9%84%DB%8C_%D9%85%D9%86%D8%B2%D9%84\"><\/span>\u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<figure id=\"attachment_73810\" class=\"wp-caption aligncenter\" aria-describedby=\"caption-attachment-73810\">\n<figure id=\"attachment_36168\" aria-describedby=\"caption-attachment-36168\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36168\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc-\u062f\u0631-\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646-\u0645\u0646\u0632\u0644.jpg\" alt=\"\u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0645\u0646\u0632\u0644\" width=\"700\" height=\"438\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc-\u062f\u0631-\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646-\u0645\u0646\u0632\u0644.jpg 700w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/10\/\u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc-\u062f\u0631-\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646-\u0645\u0646\u0632\u0644-300x188.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-36168\" class=\"wp-caption-text\">\u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<\/figcaption><\/figure><\/figure>\n<p>\u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u062f\u0631 \u062e\u0627\u0646\u0647\u00a0\u06cc\u06a9\u06cc\u00a0\u00a0\u0627\u0632 \u0645\u0647\u0645 \u062a\u0631\u06cc\u0646 \u0639\u0646\u0627\u0635\u0631 \u0648 \u0627\u0635\u0648\u0644 \u0627\u0648\u0644\u06cc\u0647 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u062e\u0627\u0646\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627\u0639\u062b \u0627\u062d\u06cc\u0627 \u0648 \u0627\u062d\u06cc\u0627\u06cc \u0641\u0636\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u062f\u0631 \u0645\u06a9\u0627\u0646 \u0645\u06cc \u0634\u0648\u062f.\u00a0\u0633\u0647 \u0646\u0648\u0639 \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0635\u0646\u0639\u062a\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f.\u00a0\u0646\u0648\u0631 \u062c\u0647\u062a \u062f\u0627\u0631\u060c \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0648\u0638\u06cc\u0641\u0647 \u0648 \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u062d\u0627\u0644\u062a.<\/p>\n<p>\u0627\u0632 \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u06a9\u0627\u0631 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0631\u0627\u06cc \u0645\u06cc\u0632\u0647\u0627\u06cc \u0646\u0627\u0647\u0627\u0631 \u062e\u0648\u0631\u06cc \u0648 \u0686\u0631\u0627\u063a \u0647\u0627\u06cc \u0631\u0648\u0645\u06cc\u0632\u06cc \u06a9\u0646\u0627\u0631 \u062a\u062e\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f \u0648 \u0646\u0648\u0631\u0627\u0641\u06a9\u0646 \u0647\u0627 \u0628\u0631\u0627\u06cc \u0628\u0631\u062c\u0633\u062a\u0647 \u06a9\u0631\u062f\u0646 \u0622\u062b\u0627\u0631 \u0647\u0646\u0631\u06cc\u060c \u0645\u062c\u0633\u0645\u0647 \u0633\u0627\u0632\u06cc \u0648 \u0645\u0648\u0627\u0631\u062f \u062f\u06cc\u06af\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u0634\u0648\u0646\u062f.\u00a0\u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u062d\u0627\u0644\u062a \u062f\u06cc\u062f \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0645\u06cc \u0628\u062e\u0634\u062f \u0648 \u0641\u0636\u0627 \u0631\u0627 \u0632\u0646\u062f\u0647 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<figure id=\"attachment_35791\" aria-describedby=\"caption-attachment-35791\" style=\"width: 700px\" class=\"wp-caption alignnone\"><a href=\"\/product-category\/\u0644\u0648\u0633\u062a\u0631\/\u0644\u0648\u0633\u062a\u0631-\u0622\u0648\u06cc\u0632\/\u0644\u0648\u0633\u062a\u0631-\u0622\u0648\u06cc\u0632-\u0645\u062f\u0631\u0646\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-35791\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/slider-232-scaled.jpg\" alt=\"\u0642\u06cc\u0645\u062a \u0644\u0648\u0633\u062a\u0631 \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628 1401-\u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u062f\u06a9\u0648\u0631\u0634\u0627\u067e\" width=\"700\" height=\"194\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/slider-232-scaled.jpg 2560w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/slider-232-300x83.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/slider-232-1024x284.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/slider-232-768x213.jpg 768w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/slider-232-1536x427.jpg 1536w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/slider-232-2048x569.jpg 2048w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><figcaption id=\"caption-attachment-35791\" class=\"wp-caption-text\"><a href=\"\/product-category\/\u0644\u0648\u0633\u062a\u0631\/\u0644\u0648\u0633\u062a\u0631-\u0622\u0648\u06cc\u0632\/\u0644\u0648\u0633\u062a\u0631-\u0622\u0648\u06cc\u0632-\u0645\u062f\u0631\u0646\/\">\u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0648 \u0622\u0648\u06cc\u0632\u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u062c\u062f\u06cc\u062f<\/a><\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"%D9%82%D8%B7%D8%B9%D8%A7%D8%AA_%D8%AA%D8%B2%D8%A6%DB%8C%D9%86%DB%8C_%D9%85%D9%87%D9%85_%D8%AF%D8%B1_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D8%AF%D8%A7%D8%AE%D9%84%DB%8C_%D9%85%D9%86%D8%B2%D9%84\"><\/span>\u0642\u0637\u0639\u0627\u062a \u062a\u0632\u0626\u06cc\u0646\u06cc \u0645\u0647\u0645 \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0634\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06af\u0644\u200c\u0647\u0627\u060c \u0634\u0645\u0639\u200c\u0647\u0627 \u06cc\u0627 \u0646\u0642\u0627\u0634\u06cc\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u0633\u0637\u062d \u0686\u0634\u0645 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f\u060c \u062d\u0633\u06cc \u0627\u0632 \u062a\u062c\u0645\u0644 \u0648 \u0637\u0631\u0627\u0648\u062a \u0631\u0627 \u0628\u0647 \u0641\u0636\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u062e\u0627\u0646\u0647 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0628\u064f\u0639\u062f \u062f\u06cc\u06af\u0631\u06cc \u062f\u0631 \u0645\u06a9\u0627\u0646 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u0627\u0632 \u0637\u0631\u06cc\u0642 \u0628\u062e\u0634 \u062e\u0627\u0646\u0647\u00a0\u0627\u0648\u0644\u06cc\u0646 \u0648\u0628\u0644\u0627\u06af \u0627\u0645\u0644\u0627\u06a9 \u0628\u0647 \u0632\u0628\u0627\u0646 \u0639\u0631\u0628\u06cc \u062f\u0631 \u0627\u0645\u0627\u0631\u0627\u062a \u0628\u0627 \u0627\u06cc\u062f\u0647 \u0647\u0627\u06cc\u00a0\u062a\u0632\u06cc\u06cc\u0646\u00a0\u062f\u06cc\u0648\u0627\u0631 \u062f\u0631 \u062e\u0627\u0646\u0647\u00a0\u0648 \u0645\u0642\u0627\u0644\u0627\u062a \u062f\u06cc\u06af\u0631 \u0622\u0634\u0646\u0627 \u0634\u0648\u06cc\u062f .<\/p>\n<table>\n<tbody>\n<tr>\n<td bgcolor=\"#a01818\" width=\"5\"><\/td>\n<td bgcolor=\"#e4e4e4\" width=\"700px\">\u0645\u0634\u0627\u0647\u062f\u0647 \u062c\u062f\u06cc\u062f\u062a\u0631\u06cc\u0646 \u0645\u062f\u0644 \u0647\u0627\u060c \u0642\u06cc\u0645\u062a \u0648 \u062e\u0631\u06cc\u062f <a href=\"\/product-category\/\u062a\u0632\u0626\u06cc\u0646\u0627\u062a-\u0648-\u062f\u06a9\u0648\u0631\u06cc\/\u0645\u06cc\u0632-\u0686\u0648\u0628\u06cc\/\"><strong>\u0645\u06cc\u0632 \u062c\u0644\u0648 \u0645\u0628\u0644\u06cc<\/strong><\/a><\/td>\n<td bgcolor=\"#a01818\" width=\"5\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table>\n<thead>\n<tr>\n<th>\u0627\u06af\u0631 \u0642\u0635\u062f \u062e\u0631\u06cc\u062f \u067e\u0627\u0631\u0686\u0647 \u0645\u0628\u0644\u06cc \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644 \u062e\u0648\u062f \u0631\u0627 \u062f\u0627\u0631\u06cc\u062f\u060c \u062e\u0648\u0627\u0646\u062f\u0646 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0631\u0627 \u0628\u0647 \u0634\u0645\u0627 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u06a9\u0646\u06cc\u0645:<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><strong><a href=\"https:\/\/adakpremium.com\/%d9%86%d9%82%d8%b4-%d9%be%d8%a7%d8%b1%da%86%d9%87-%d9%85%d8%a8%d9%84%db%8c-%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c-%d9%85%d8%af%d8%b1%d9%86\/\" rel=\"sponsored noopener\" data-schema-attribute=\"\" target=\"_blank\">\u0646\u0642\u0634 \u067e\u0627\u0631\u0686\u0647 \u0645\u0628\u0644\u06cc \u0645\u062f\u0631\u0646 \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u067e\u0630\u06cc\u0631\u0627\u06cc\u06cc<\/a><\/strong><\/p>\n<p>&nbsp;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0635\u0648\u0644 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u0646\u0632\u0644: \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0645\u06cc \u062e\u0648\u0627\u0647\u0646\u062f \u062f\u06a9\u0648\u0631 \u062e\u0627\u0646\u0647 \u0631\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0647\u0646\u062f \u06cc\u0627 \u0628\u0647 \u0637\u0631\u0627\u062d\u06cc \u062f\u0627\u062e\u0644\u06cc \u062c\u0627\u0646 \u0628\u062f\u0647\u0646\u062f\u060c \u0627\u0645\u0627 \u062f\u0631 \u0639\u06cc\u0646 \u062d\u0627\u0644 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u06cc\u062f\u0647 \u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628\u060c \u062e\u0644\u0627\u0642\u0627\u0646\u0647 \u0648 \u067e\u0631 \u062c\u0646\u0628 \u0648 \u062c\u0648\u0634 \u0628\u0627 \u0647\u062f\u0641 \u062f\u0633\u062a\u06cc\u0627\u0628\u06cc \u0628\u0647 \u062e\u0627\u0646\u0647 \u0627\u06cc \u0628\u0627\u0632\u0633\u0627\u0632\u06cc \u0634\u062f\u0647 \u0628\u0627 \u0628\u0648\u062f\u062c\u0647 \u06a9\u0645 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0646\u0628\u0627\u0634\u062f . \u0627\u0632 \u0627\u06cc\u0646 \u0646\u0638\u0631 \u0627\u0635\u0648\u0644 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":36169,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,50,2,53,34],"tags":[],"class_list":["post-36163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-41","category-50","category-design","category-53","category-34"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/36163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=36163"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/36163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/36169"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=36163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=36163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=36163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}