{"id":35839,"date":"2022-09-12T19:24:51","date_gmt":"2022-09-12T14:54:51","guid":{"rendered":"https:\/\/decorshop.ir\/mag\/?p=35839"},"modified":"2022-09-12T19:25:21","modified_gmt":"2022-09-12T14:55:21","slug":"%d8%b3%d8%aa-%d9%85%d8%a8%d9%84-%d8%b1%d8%a7%d8%ad%d8%aa%db%8c-%d8%a8%d8%a7-%d9%81%d8%b1%d8%b4-%d8%b3%d9%88%d8%b1%d9%85%d9%87-%d8%a7%db%8c","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d8%b3%d8%aa-%d9%85%d8%a8%d9%84-%d8%b1%d8%a7%d8%ad%d8%aa%db%8c-%d8%a8%d8%a7-%d9%81%d8%b1%d8%b4-%d8%b3%d9%88%d8%b1%d9%85%d9%87-%d8%a7%db%8c\/","title":{"rendered":"\u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b3%d8%aa-%d9%85%d8%a8%d9%84-%d8%b1%d8%a7%d8%ad%d8%aa%db%8c-%d8%a8%d8%a7-%d9%81%d8%b1%d8%b4-%d8%b3%d9%88%d8%b1%d9%85%d9%87-%d8%a7%db%8c\/#%D8%B3%D8%AA_%D9%85%D8%A8%D9%84_%D8%B1%D8%A7%D8%AD%D8%AA%DB%8C_%D8%A8%D8%A7_%D9%81%D8%B1%D8%B4\" >\u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b3%d8%aa-%d9%85%d8%a8%d9%84-%d8%b1%d8%a7%d8%ad%d8%aa%db%8c-%d8%a8%d8%a7-%d9%81%d8%b1%d8%b4-%d8%b3%d9%88%d8%b1%d9%85%d9%87-%d8%a7%db%8c\/#1-_%D8%A8%D9%87_%D8%B7%D8%B1%D8%AD_%D9%81%D8%B1%D8%B4_%D8%AA%D9%88%D8%AC%D9%87_%DA%A9%D9%86%DB%8C%D8%AF\" >1- \u0628\u0647 \u0637\u0631\u062d \u0641\u0631\u0634 \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b3%d8%aa-%d9%85%d8%a8%d9%84-%d8%b1%d8%a7%d8%ad%d8%aa%db%8c-%d8%a8%d8%a7-%d9%81%d8%b1%d8%b4-%d8%b3%d9%88%d8%b1%d9%85%d9%87-%d8%a7%db%8c\/#2-_%D8%B1%D9%86%DA%AF_%D9%87%D8%A7%DB%8C_%D9%85%DA%A9%D9%85%D9%84_%D8%B3%D9%88%D8%B1%D9%85%D9%87_%D8%A7%DB%8C_%D8%B1%D8%A7_%D8%A8%D8%B4%D9%86%D8%A7%D8%B3%DB%8C%D8%AF\" >2- \u0631\u0646\u06af \u0647\u0627\u06cc \u0645\u06a9\u0645\u0644 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0631\u0627 \u0628\u0634\u0646\u0627\u0633\u06cc\u062f.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b3%d8%aa-%d9%85%d8%a8%d9%84-%d8%b1%d8%a7%d8%ad%d8%aa%db%8c-%d8%a8%d8%a7-%d9%81%d8%b1%d8%b4-%d8%b3%d9%88%d8%b1%d9%85%d9%87-%d8%a7%db%8c\/#3-_%D8%A8%D9%87_%D8%B3%D8%A7%DB%8C%D8%B1_%D8%B1%D9%86%DA%AF_%D9%87%D8%A7%DB%8C_%D8%A8%D9%87_%DA%A9%D8%A7%D8%B1_%D8%B1%D9%81%D8%AA%D9%87_%D8%AF%D8%B1_%D9%81%D8%B1%D8%B4_%D8%AF%D9%82%D8%AA_%DA%A9%D9%86%DB%8C%D8%AF\" >3- \u0628\u0647 \u0633\u0627\u06cc\u0631 \u0631\u0646\u06af \u0647\u0627\u06cc \u0628\u0647 \u06a9\u0627\u0631 \u0631\u0641\u062a\u0647 \u062f\u0631 \u0641\u0631\u0634 \u062f\u0642\u062a \u06a9\u0646\u06cc\u062f.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b3%d8%aa-%d9%85%d8%a8%d9%84-%d8%b1%d8%a7%d8%ad%d8%aa%db%8c-%d8%a8%d8%a7-%d9%81%d8%b1%d8%b4-%d8%b3%d9%88%d8%b1%d9%85%d9%87-%d8%a7%db%8c\/#4-_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%B3%D8%AA_%D9%85%D8%A8%D9%84_%D8%B1%D8%A7%D8%AD%D8%AA%DB%8C_%D8%A8%D8%A7_%D9%81%D8%B1%D8%B4_%D8%B3%D9%88%D8%B1%D9%85%D9%87_%D8%A7%DB%8C_%D8%A7%D8%B2_%D8%B7%D8%B1%D8%AD_%D9%87%D8%A7%DB%8C_%DA%86%D9%88%D8%A8%DB%8C_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%DA%A9%D9%86%DB%8C%D8%AF\" >4- \u0628\u0631\u0627\u06cc \u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0627\u0632 \u0637\u0631\u062d \u0647\u0627\u06cc \u0686\u0648\u0628\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b3%d8%aa-%d9%85%d8%a8%d9%84-%d8%b1%d8%a7%d8%ad%d8%aa%db%8c-%d8%a8%d8%a7-%d9%81%d8%b1%d8%b4-%d8%b3%d9%88%d8%b1%d9%85%d9%87-%d8%a7%db%8c\/#5-_%D9%86%D9%88%D8%B9_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D9%85%D9%88%D8%B1%D8%AF_%D8%B9%D9%84%D8%A7%D9%82%D9%87_%D8%AE%D9%88%D8%AF_%D8%B1%D8%A7_%D9%85%D8%B4%D8%AE%D8%B5_%DA%A9%D9%86%DB%8C%D8%AF\" >5- \u0646\u0648\u0639 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0645\u0648\u0631\u062f \u0639\u0644\u0627\u0642\u0647 \u062e\u0648\u062f \u0631\u0627 \u0645\u0634\u062e\u0635 \u06a9\u0646\u06cc\u062f!<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B3%D8%AA_%D9%85%D8%A8%D9%84_%D8%B1%D8%A7%D8%AD%D8%AA%DB%8C_%D8%A8%D8%A7_%D9%81%D8%B1%D8%B4\"><\/span><strong>\u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0628\u0631\u0627\u06cc <strong>\u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc<\/strong> \u0628\u0627\u06cc\u062f \u0686\u0647 \u0631\u0646\u06af \u0648 \u0645\u062f\u0644\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0634\u0648\u062f\u061f \u0631\u0646\u06af \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0628\u0647 \u0637\u0648\u0631 \u06af\u0633\u062a\u0631\u062f\u0647 \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0637\u0631\u062d \u0648 \u0646\u0642\u0634 \u0647\u0627\u06cc \u0641\u0631\u0634 \u0647\u0627 \u0628\u0647 \u06a9\u0627\u0631 \u0645\u06cc \u0631\u0648\u062f. \u0639\u062f\u0645 \u0647\u0645\u0627\u0647\u0646\u06af\u06cc \u0631\u0646\u06af <strong><a href=\"https:\/\/adakpremium.com\/product-category\/textile-%D9%BE%D8%A7%D8%B1%DA%86%D9%87-%D9%85%D8%A8%D9%84%DB%8C\/\" rel=\"sponsored noopener\" data-schema-attribute=\"\" target=\"_blank\">\u067e\u0627\u0631\u0686\u0647 \u0645\u0628\u0644\u06cc<\/a><\/strong> \u062f\u0631 <a href=\"\/product-category\/\u0645\u06cc\u0632-\u0648-\u0645\u0628\u0644\/\u0645\u0628\u0644\u0645\u0627\u0646-\u0631\u0627\u062d\u062a\u06cc\/\"><strong>\u0645\u0628\u0644\u0645\u0627\u0646 \u0631\u0627\u062d\u062a\u06cc<\/strong><\/a> \u0648 \u0631\u0646\u06af \u0641\u0631\u0634 \u0647\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0645\u0648\u062c\u0628 \u0628\u0647 \u0647\u0645 \u0631\u06cc\u062e\u062a\u0647 \u0628\u0647 \u0646\u0638\u0631 \u0631\u0633\u06cc\u062f\u0646 \u0645\u062d\u06cc\u0637 \u0634\u0648\u062f. \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0648 \u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0646\u062d\u0648\u0647 <strong>\u0633\u062a \u06a9\u0631\u062f\u0646 \u0645\u0628\u0644 \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc<\/strong> \u0628\u0647 \u0635\u0627\u062d\u0628\u0627\u0646 \u0627\u06cc\u0646 \u0641\u0631\u0634 \u0647\u0627 \u06a9\u0645\u06a9 \u0645\u06cc \u06a9\u0646\u062f \u062a\u0627 \u0641\u0636\u0627\u06cc\u06cc \u0632\u06cc\u0628\u0627\u062a\u0631 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0645\u062d\u06cc\u0637 \u062f\u0627\u062e\u0644\u06cc \u0637\u0631\u0627\u062d\u06cc \u0646\u0645\u0627\u06cc\u0646\u062f.<\/p>\n<p>\u0647\u0645\u0686\u0646\u06cc\u0646 \u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0627\u0644\u0645\u0627\u0646 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0627 \u0641\u0631\u0634 \u0633\u062a \u06a9\u0631\u062f\u060c \u067e\u0631\u062f\u0647 \u0647\u0627 \u0647\u0633\u062a\u0646\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0645\u06a9\u0645\u0644 \u0647\u0627\u06cc \u0631\u0646\u06af \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0631\u0627 \u0634\u0646\u0627\u062e\u062a\u0647 \u0648 \u0627\u06cc\u0646 \u0631\u0646\u06af \u0647\u0627 \u0631\u0627 \u0628\u0627 \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0633\u062a \u06a9\u0646\u06cc\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628<a href=\"\/mag\/\"><strong> \u062f\u06a9\u0648\u0631\u0645\u06af<\/strong><\/a> \u0634\u0645\u0627 \u0631\u0627 \u0628\u0627 \u0645\u0647\u0645\u062a\u0631\u06cc\u0646 \u0646\u06a9\u0627\u062a <strong>\u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc<\/strong> \u0622\u0634\u0646\u0627 \u0645\u06cc \u06a9\u0646\u06cc\u0645.<\/p>\n<figure id=\"attachment_35840\" aria-describedby=\"caption-attachment-35840\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-35840\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/\u0633\u062a-\u0645\u0628\u0644-\u0631\u0627\u062d\u062a\u06cc-\u0628\u0627-\u0641\u0631\u0634-\u0633\u0648\u0631\u0645\u0647-\u0627\u06cc.jpg\" alt=\"\u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc\" width=\"700\" height=\"899\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/\u0633\u062a-\u0645\u0628\u0644-\u0631\u0627\u062d\u062a\u06cc-\u0628\u0627-\u0641\u0631\u0634-\u0633\u0648\u0631\u0645\u0647-\u0627\u06cc.jpg 700w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/\u0633\u062a-\u0645\u0628\u0644-\u0631\u0627\u062d\u062a\u06cc-\u0628\u0627-\u0641\u0631\u0634-\u0633\u0648\u0631\u0645\u0647-\u0627\u06cc-234x300.jpg 234w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-35840\" class=\"wp-caption-text\">\u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc<\/figcaption><\/figure>\n<blockquote><p><em>\u0628\u06cc\u0634\u062a\u0631 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f:<\/em><\/p><\/blockquote>\n<p><a href=\"https:\/\/decorshop.ir\/mag\/%D9%BE%D9%88%D8%B4%D8%A7%D9%86%D8%AF%D9%86-%D8%AF%DB%8C%D9%88%D8%A7%D8%B1-%D8%A8%D8%A7-%DA%A9%D9%85%D8%AA%D8%B1%DB%8C%D9%86-%D9%87%D8%B2%DB%8C%D9%86%D9%87-7-%D9%BE%DB%8C%D8%B4%D9%86%D9%87%D8%A7\/\"><strong>\u067e\u0648\u0634\u0627\u0646\u062f\u0646 \u062f\u06cc\u0648\u0627\u0631 \u0628\u0627 \u06a9\u0645\u062a\u0631\u06cc\u0646 \u0647\u0632\u06cc\u0646\u0647 + \u06f7 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0628\u0647 \u0635\u0631\u0641\u0647<\/strong><\/a><\/p>\n<h3><span class=\"ez-toc-section\" id=\"1-_%D8%A8%D9%87_%D8%B7%D8%B1%D8%AD_%D9%81%D8%B1%D8%B4_%D8%AA%D9%88%D8%AC%D9%87_%DA%A9%D9%86%DB%8C%D8%AF\"><\/span><strong>1- \u0628\u0647 \u0637\u0631\u062d \u0641\u0631\u0634 \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f.<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0647\u0645\u0627\u0646\u0637\u0648\u0631 \u06a9\u0647 \u0645\u06cc \u062f\u0627\u0646\u06cc\u062f\u060c \u0641\u0631\u0634 \u0647\u0627 \u062f\u0627\u0631\u0627\u06cc \u0646\u0642\u0634 \u0648 \u0646\u06af\u0627\u0631\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0647\u0633\u062a\u0646\u062f. \u0627\u06af\u0631 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0634\u0645\u0627 \u062f\u0627\u0631\u0627\u06cc \u0637\u0631\u062d \u0647\u0627\u06cc \u0634\u0644\u0648\u063a \u0627\u0633\u062a\u060c \u0628\u0647 \u0647\u06cc\u0686 \u0639\u0646\u0648\u0627\u0646 \u0627\u0632 \u067e\u0627\u0631\u0686\u0647 \u0647\u0627\u06cc \u0645\u0628\u0644\u06cc \u067e\u0631 \u0637\u0631\u062d \u0648 \u0646\u0642\u0634 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u06a9\u0646\u06cc\u062f. \u0632\u06cc\u0631\u0627 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0633\u0628\u0628 \u0622\u0634\u0641\u062a\u0647 \u0628\u0647 \u0646\u0638\u0631 \u0631\u0633\u06cc\u062f\u0646 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0645\u06cc \u0634\u0648\u062f \u0648 \u0647\u0627\u0631\u0645\u0648\u0646\u06cc \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0627\u06cc\u062c\u0627\u062f \u0646\u0645\u06cc \u06a9\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u0627\u0631 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u067e\u0627\u0631\u0686\u0647 \u0647\u0627\u06cc\u06cc \u0633\u0627\u062f\u0647 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0645\u0628\u0644\u0645\u0627\u0646 \u062e\u0648\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0645\u0627\u06cc\u06cc\u062f. \u062f\u0631 \u0639\u0648\u0636 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u067e\u0627\u0631\u0686\u0647 \u0647\u0627\u06cc \u06a9\u0648\u0633\u0646 \u0647\u0627 \u0631\u0627 \u0628\u0627 \u0637\u0631\u062d \u0647\u0627\u06cc \u06a9\u0645\u06cc \u0634\u0644\u0648\u063a \u062a\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0645\u0627\u06cc\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"2-_%D8%B1%D9%86%DA%AF_%D9%87%D8%A7%DB%8C_%D9%85%DA%A9%D9%85%D9%84_%D8%B3%D9%88%D8%B1%D9%85%D9%87_%D8%A7%DB%8C_%D8%B1%D8%A7_%D8%A8%D8%B4%D9%86%D8%A7%D8%B3%DB%8C%D8%AF\"><\/span><strong>2- \u0631\u0646\u06af \u0647\u0627\u06cc \u0645\u06a9\u0645\u0644 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0631\u0627 \u0628\u0634\u0646\u0627\u0633\u06cc\u062f.<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>\u00a0<\/strong>\u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u062a\u0631\u06cc\u0646 \u0645\u0633\u0627\u0626\u0644\u06cc \u06a9\u0647 \u0628\u0627\u06cc\u062f \u062f\u0631 <strong>\u0633\u062a \u06a9\u0631\u062f\u0646 \u0645\u0628\u0644 \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc<\/strong> \u0628\u0647 \u0622\u0646 \u062a\u0648\u062c\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u060c \u062f\u0627\u0634\u062a\u0646 \u062f\u0627\u0646\u0634 \u0631\u0646\u06af \u0634\u0646\u0627\u0633\u06cc \u0627\u0633\u062a. \u0634\u0645\u0627 \u0628\u0627\u06cc\u062f \u0631\u0646\u06af \u0647\u0627\u06cc \u0645\u06a9\u0645\u0644 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0631\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0628\u0634\u0646\u0627\u0633\u06cc\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0631\u0646\u06af \u0647\u0627\u06cc \u062f\u0631\u0633\u062a\u06cc \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0645\u0648\u062f\u0647 \u0648 \u0647\u0645\u0627\u0646 \u0641\u0636\u0627\u06cc \u0686\u0634\u0645 \u0646\u0648\u0627\u0632\u06cc \u06a9\u0647 \u062f\u0648\u0633\u062a \u062f\u0627\u0631\u06cc\u062f \u0631\u0627 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u06cc\u062f. \u0627\u0632 \u0622\u0646\u062c\u0627 \u06a9\u0647 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u06cc\u06a9 \u0631\u0646\u06af \u062a\u06cc\u0631\u0647 \u0627\u0633\u062a\u060c \u0631\u0646\u06af \u0647\u0627\u06cc \u0631\u0648\u0634\u0646 \u2013 \u062e\u0635\u0648\u0635\u0627 \u0631\u0646\u06af \u0647\u0627\u06cc \u062e\u0646\u062b\u06cc \u0647\u0645\u0686\u0648\u0646 \u06a9\u0631\u0645\u06cc\u060c \u0633\u0641\u06cc\u062f \u0648 \u062e\u0627\u06a9\u0633\u062a\u0631\u06cc \u2013 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0628\u0627 \u0622\u0646 \u0633\u062a \u0645\u06cc \u0634\u0648\u0646\u062f.<\/p>\n<p><a href=\"\/product-category\/\u0645\u06cc\u0632-\u0648-\u0645\u0628\u0644\/\u0645\u0628\u0644-\u0627\u0644\/\"><img decoding=\"async\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/%D8%AE%D8%B1%DB%8C%D8%AF-%D9%85%D8%A8%D9%84-%D8%A7%D9%84.jpg\" alt=\"\u062e\u0631\u06cc\u062f \u0645\u0628\u0644 \u0627\u0644 \u0627\u0632 \u062f\u06a9\u0648\u0631\u0634\u0627\u067e \u0628\u0627 \u0627\u0631\u0633\u0627\u0644 \u0631\u0627\u06cc\u06af\u0627\u0646\" \/><\/a><\/p>\n<p><a href=\"\/product-category\/\u0645\u06cc\u0632-\u0648-\u0645\u0628\u0644\/\u0645\u0628\u0644-\u0627\u0644\/\">\u062e\u0631\u06cc\u062f \u0645\u0628\u0644 \u0627\u0644 \u0627\u0632 \u062f\u06a9\u0648\u0631\u0634\u0627\u067e \u0628\u0627 \u0627\u0631\u0633\u0627\u0644 \u0631\u0627\u06cc\u06af\u0627\u0646<\/a> | \u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc<\/p>\n<h3><span class=\"ez-toc-section\" id=\"3-_%D8%A8%D9%87_%D8%B3%D8%A7%DB%8C%D8%B1_%D8%B1%D9%86%DA%AF_%D9%87%D8%A7%DB%8C_%D8%A8%D9%87_%DA%A9%D8%A7%D8%B1_%D8%B1%D9%81%D8%AA%D9%87_%D8%AF%D8%B1_%D9%81%D8%B1%D8%B4_%D8%AF%D9%82%D8%AA_%DA%A9%D9%86%DB%8C%D8%AF\"><\/span><strong>3- \u0628\u0647 \u0633\u0627\u06cc\u0631 \u0631\u0646\u06af \u0647\u0627\u06cc \u0628\u0647 \u06a9\u0627\u0631 \u0631\u0641\u062a\u0647 \u062f\u0631 \u0641\u0631\u0634 \u062f\u0642\u062a \u06a9\u0646\u06cc\u062f.<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u0631\u0633\u062a \u0627\u0633\u062a \u06a9\u0647 \u0627\u0635\u0644\u06cc \u062a\u0631\u06cc\u0646 \u0631\u0646\u06af \u0628\u0647 \u06a9\u0627\u0631 \u0631\u0641\u062a\u0647 \u062f\u0631 \u0641\u0631\u0634 \u0634\u0645\u0627 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0627\u0633\u062a \u0627\u0645\u0627 \u0627\u062d\u062a\u0645\u0627\u0644\u0627 \u0631\u0646\u06af \u0647\u0627\u06cc \u062f\u06cc\u06af\u0631\u06cc \u0646\u06cc\u0632 \u062f\u0631 \u0628\u0627\u0641\u062a \u0622\u0646 \u0628\u0647 \u06a9\u0627\u0631 \u0631\u0641\u062a\u0647 \u0627\u0646\u062f. \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u0641\u0646\u062f\u0647\u0627\u06cc <strong>\u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc<\/strong>\u060c \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u0631\u0646\u06af \u0647\u0627 \u0627\u0633\u062a. \u0634\u0645\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0631\u0646\u06af \u0645\u0628\u0644\u0645\u0627\u0646 \u0631\u0627\u062d\u062a\u06cc \u062e\u0648\u062f \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0631\u0646\u06af \u06a9\u0648\u0633\u0646 \u0647\u0627 \u0631\u0627 \u0627\u0632 \u0645\u06cc\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0646\u06af \u0647\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0645\u0627\u06cc\u06cc\u062f.<\/p>\n<figure id=\"attachment_35841\" aria-describedby=\"caption-attachment-35841\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-35841\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/\u0645\u0628\u0644-\u0631\u0627\u062d\u062a\u06cc-\u0628\u0627-\u0641\u0631\u0634-\u0633\u0648\u0631\u0645\u0647-\u0627\u06cc.jpg\" alt=\"\u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc\" width=\"700\" height=\"700\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/\u0645\u0628\u0644-\u0631\u0627\u062d\u062a\u06cc-\u0628\u0627-\u0641\u0631\u0634-\u0633\u0648\u0631\u0645\u0647-\u0627\u06cc.jpg 700w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/\u0645\u0628\u0644-\u0631\u0627\u062d\u062a\u06cc-\u0628\u0627-\u0641\u0631\u0634-\u0633\u0648\u0631\u0645\u0647-\u0627\u06cc-300x300.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/09\/\u0645\u0628\u0644-\u0631\u0627\u062d\u062a\u06cc-\u0628\u0627-\u0641\u0631\u0634-\u0633\u0648\u0631\u0645\u0647-\u0627\u06cc-150x150.jpg 150w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-35841\" class=\"wp-caption-text\">\u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"4-_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%B3%D8%AA_%D9%85%D8%A8%D9%84_%D8%B1%D8%A7%D8%AD%D8%AA%DB%8C_%D8%A8%D8%A7_%D9%81%D8%B1%D8%B4_%D8%B3%D9%88%D8%B1%D9%85%D9%87_%D8%A7%DB%8C_%D8%A7%D8%B2_%D8%B7%D8%B1%D8%AD_%D9%87%D8%A7%DB%8C_%DA%86%D9%88%D8%A8%DB%8C_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%DA%A9%D9%86%DB%8C%D8%AF\"><\/span><strong>4- \u0628\u0631\u0627\u06cc \u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0627\u0632 \u0637\u0631\u062d \u0647\u0627\u06cc \u0686\u0648\u0628\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u0646\u062a\u062e\u0627\u0628 \u0637\u0631\u062d \u0647\u0627\u06cc \u0686\u0648\u0628\u06cc \u062f\u0631 \u062a\u0631\u06a9\u06cc\u0628 \u0628\u0627 \u0631\u0646\u06af \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc\u060c \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0647\u0627\u06cc \u067e\u06cc\u0634 \u0631\u0648\u06cc \u0634\u0645\u0627 \u0627\u0633\u062a. \u062f\u0631 \u0648\u0627\u0642\u0639 \u0627\u06af\u0631 \u062f\u0631 \u0628\u062e\u0634 \u0647\u0627\u06cc\u06cc \u0627\u0632 \u0645\u0628\u0644\u0645\u0627\u0646 \u0631\u0627\u062d\u062a\u06cc \u0634\u0645\u0627 \u0637\u0631\u062d \u0647\u0627\u06cc \u0686\u0648\u0628\u06cc \u06a9\u0627\u0631 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f\u060c \u062f\u0631 \u062a\u0631\u06a9\u06cc\u0628 \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0641\u0636\u0627\u06cc\u06cc \u062c\u0630\u0627\u0628 \u0648 \u062f\u06cc\u062f\u0646\u06cc \u0631\u0627 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"5-_%D9%86%D9%88%D8%B9_%D8%AF%DA%A9%D9%88%D8%B1%D8%A7%D8%B3%DB%8C%D9%88%D9%86_%D9%85%D9%88%D8%B1%D8%AF_%D8%B9%D9%84%D8%A7%D9%82%D9%87_%D8%AE%D9%88%D8%AF_%D8%B1%D8%A7_%D9%85%D8%B4%D8%AE%D8%B5_%DA%A9%D9%86%DB%8C%D8%AF\"><\/span><strong>5- \u0646\u0648\u0639 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0645\u0648\u0631\u062f \u0639\u0644\u0627\u0642\u0647 \u062e\u0648\u062f \u0631\u0627 \u0645\u0634\u062e\u0635 \u06a9\u0646\u06cc\u062f!<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0645\u062f\u0631\u0646 \u0645\u0648\u0631\u062f \u0639\u0644\u0627\u0642\u0647 \u0634\u0645\u0627\u0633\u062a \u06cc\u0627 \u062a\u0631\u062c\u06cc\u062d \u0645\u06cc \u062f\u0647\u06cc\u062f \u06cc\u06a9 \u062f\u06a9\u0648\u0631 \u0633\u0646\u062a\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u061f \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0627\u0632 \u0622\u0646 \u0631\u0646\u06af \u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646 \u062f\u0631 \u0647\u0631 \u062f\u0648 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u0648 \u0645\u062f\u0631\u0646 \u0627\u0632 \u0622\u0646 \u0628\u0647\u0631\u0647 \u0645\u0646\u062f \u0634\u062f. \u0627\u0645\u0627 \u062a\u0648\u062c\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u062f\u0631 \u0686\u06cc\u062f\u0646 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0645\u062f\u0631\u0646 \u0645\u0639\u0645\u0648\u0644\u0627 \u0627\u0632 \u0631\u0646\u06af \u0647\u0627\u06cc \u0631\u0648\u0634\u0646 \u062f\u0631 \u062a\u0631\u06a9\u06cc\u0628 \u0628\u0627 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f. \u0627\u0645\u0627 \u0639\u0645\u0648\u0645\u0627 \u062f\u0631 \u062f\u06a9\u0648\u0631 \u06a9\u0644\u0627\u0633\u06cc\u06a9\u060c \u0627\u0632 \u0631\u0646\u06af \u0647\u0627\u06cc \u06af\u0631\u0645 \u062a\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u06cc\u0645 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0645\u0637\u0627\u0644\u0628 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0628\u06cc\u0627\u0646 \u0634\u062f\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0647\u0645\u0627\u0646 \u062f\u06a9\u0648\u0631\u06cc \u06a9\u0647 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644\u0634 \u0647\u0633\u062a\u06cc\u062f \u0631\u0627 \u0637\u0631\u0627\u062d\u06cc \u06a9\u0646\u06cc\u062f.<\/p>\n<blockquote><p><em>\u0628\u06cc\u0634\u062a\u0631 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f:<\/em><\/p><\/blockquote>\n<p><a href=\"\/mag\/\u0631\u0627\u0647\u0646\u0645\u0627\u06cc-\u0633\u062a-\u06a9\u0631\u062f\u0646-\u0631\u0646\u06af-\u0645\u0628\u0644-\u0631\u0627\u062d\u062a\u06cc-\u0628\u0627-\u062f\u06a9\u0648\u0631\u0627\u0633\/\"><strong>\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u0633\u062a \u06a9\u0631\u062f\u0646 \u0631\u0646\u06af \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634 \u0628\u0631\u0627\u06cc \u0633\u062a \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0641\u0631\u0634 \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0628\u0627\u06cc\u062f \u0686\u0647 \u0631\u0646\u06af \u0648 \u0645\u062f\u0644\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0634\u0648\u062f\u061f \u0631\u0646\u06af \u0633\u0648\u0631\u0645\u0647 \u0627\u06cc \u0628\u0647 \u0637\u0648\u0631 \u06af\u0633\u062a\u0631\u062f\u0647 \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0637\u0631\u062d \u0648 \u0646\u0642\u0634 \u0647\u0627\u06cc \u0641\u0631\u0634 \u0647\u0627 \u0628\u0647 \u06a9\u0627\u0631 \u0645\u06cc \u0631\u0648\u062f. \u0639\u062f\u0645 \u0647\u0645\u0627\u0647\u0646\u06af\u06cc \u0631\u0646\u06af \u067e\u0627\u0631\u0686\u0647 \u0645\u0628\u0644\u06cc \u062f\u0631 \u0645\u0628\u0644\u0645\u0627\u0646 \u0631\u0627\u062d\u062a\u06cc \u0648 \u0631\u0646\u06af \u0641\u0631\u0634 \u0647\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0645\u0648\u062c\u0628 \u0628\u0647 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":35842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-35839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/35839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=35839"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/35839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/35842"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=35839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=35839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=35839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}