{"id":35382,"date":"2022-03-03T15:11:42","date_gmt":"2022-03-03T11:41:42","guid":{"rendered":"https:\/\/decorshop.ir\/mag\/?p=35382"},"modified":"2023-04-27T11:50:17","modified_gmt":"2023-04-27T08:20:17","slug":"%d8%a7%d9%86%d8%af%d8%a7%d8%b2%d9%87-%d9%85%d8%a8%d9%84-%d8%b1%d8%a7%d8%ad%d8%aa%db%8c-2","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d8%a7%d9%86%d8%af%d8%a7%d8%b2%d9%87-%d9%85%d8%a8%d9%84-%d8%b1%d8%a7%d8%ad%d8%aa%db%8c-2\/","title":{"rendered":"\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a7%d9%86%d8%af%d8%a7%d8%b2%d9%87-%d9%85%d8%a8%d9%84-%d8%b1%d8%a7%d8%ad%d8%aa%db%8c-2\/#%D8%A7%D9%86%D8%AF%D8%A7%D8%B2%D9%87_%D9%85%D8%A8%D9%84_%D8%B1%D8%A7%D8%AD%D8%AA%DB%8C\" >\u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a7%d9%86%d8%af%d8%a7%d8%b2%d9%87-%d9%85%d8%a8%d9%84-%d8%b1%d8%a7%d8%ad%d8%aa%db%8c-2\/#%D8%AF%D8%B1%D8%A8%D8%A7%D8%B1%D9%87_%DB%8C_%D8%AF%DA%A9%D9%88%D8%B1%D9%85%DA%AF\" >\u062f\u0631\u0628\u0627\u0631\u0647 \u06cc\u00a0\u062f\u06a9\u0648\u0631\u0645\u06af<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D8%AF%D8%A7%D8%B2%D9%87_%D9%85%D8%A8%D9%84_%D8%B1%D8%A7%D8%AD%D8%AA%DB%8C\"><\/span>\u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0645\u0628\u0644 \u0647\u0627 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0633\u0628\u06a9 \u0648 \u0645\u062f\u0644 \u062e\u0648\u062f \u062f\u0631 \u0627\u0646\u062f\u0627\u0632\u0647 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc \u0634\u0648\u0646\u062f \u0648 \u0647\u0645\u0647 \u0645\u0628\u0644 \u0647\u0627 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0633\u0628\u06a9 \u0648 \u0645\u062f\u0644 \u062e\u0648\u062f \u0627\u0632 \u06cc\u06a9 \u0627\u0646\u062f\u0627\u0632\u0647 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u06cc \u067e\u06cc\u0631\u0648\u06cc \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0648 \u0645\u0628\u0644 \u0647\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u0647\u0645 \u0627\u0632 \u0627\u0646\u062f\u0627\u0632\u0647 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0647\u0633\u062a\u0646\u062f \u0627\u0645\u0627 \u06cc\u06a9 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u06cc \u0628\u0631\u0627\u06cc \u0645\u0628\u0644 \u0647\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u062a\u0642\u0631\u06cc\u0628\u0627 \u0647\u0645\u0647 \u062a\u0648\u0644\u06cc\u062f \u06a9\u0646\u0646\u062f\u0647 \u0647\u0627 \u0622\u0646 \u0631\u0627 \u0631\u0639\u0627\u06cc\u062a \u0645\u06cc \u06a9\u0646\u0646\u062f \u0627\u0645\u0627 \u0634\u0645\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0645\u0628\u0644 \u0628\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u062f\u0644\u062e\u0648\u0627\u0647 \u0648 \u0645\u0646\u0627\u0633\u0628 \u0628\u0627 \u0641\u0636\u0627\u06cc \u062e\u0648\u062f \u0633\u0641\u0627\u0631\u0634 \u062f\u0647\u06cc\u062f \u062a\u0627 \u062a\u0648\u0644\u06cc\u062f \u06a9\u0646\u0646\u062f\u0647 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0628\u0633\u0627\u0632\u062f. \u0627\u0645\u0627 \u0627\u06af\u0631 \u0645\u06cc \u062e\u0648\u0627\u0647\u06cc\u062f \u0627\u0646\u062f\u0627\u0632\u0647 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0631\u0627<\/p>\n<p>\u0628\u062f\u0627\u0646\u06cc\u062f \u060c \u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0627 \u062f\u0631 \u062f\u0633\u062a \u062f\u0627\u0634\u062a\u0646 \u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644 \u0647\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc\u060c \u06a9\u0627\u0631 \u0686\u06cc\u062f\u0645\u0627\u0646 \u0631\u0627\u062d\u062a \u062a\u0631 \u067e\u06cc\u0634 \u0645\u06cc \u0631\u0648\u062f \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0645\u0627 \u0631\u0627 \u0647\u0645\u0631\u0627\u0647\u06cc \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0627\u0632 \u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0627\u0637\u0644\u0627\u0639\u0627\u062a\u06cc \u0628\u062f\u0633\u062a \u0622\u0648\u0631\u06cc\u062f.<\/p>\n<p>\u0645\u0628\u0644 \u0647\u0627 \u062f\u0627\u0631\u0627\u06cc \u0637\u0648\u0644 \u060c \u0639\u0645\u0642 \u0648 \u0627\u0631\u062a\u0641\u0627\u0639 \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0644\u06cc \u0637\u0648\u0644 \u0622\u0646\u0647\u0627 \u0628\u06cc\u0646 177 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u062a\u0627 243 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u0645\u062a\u063a\u06cc\u0631 \u0627\u0633\u062a. \u0627\u0632 \u0645\u062a\u062f\u0627\u0648\u0644 \u062a\u0631\u06cc\u0646 \u0645\u0628\u0644\u0645\u0627\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647 \u0645\u0628\u0644 \u0633\u0647 \u0646\u0641\u0631\u0647 \u0628\u0627 \u0637\u0648\u0644 213 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f. \u0639\u0645\u0642 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0645\u0628\u0644 \u0647\u0627 \u0627\u0632 81 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u062a\u0627 101 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u062a\u063a\u06cc\u06cc\u0631 \u0645\u06cc \u06a9\u0646\u062f \u0648 \u0645\u062a\u062f\u0627\u0648\u0644 \u062a\u0631\u06cc\u0646 \u0622\u0646 \u0627\u0632 \u0646\u0638\u0631 \u0639\u0645\u0642\u060c \u00a0\u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0639\u0645\u0642 88 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631\u06cc \u0627\u0633\u062a. \u0648 \u0627\u0631\u062a\u0641\u0627\u0639 \u0645\u0628\u0644 \u0647\u0627 \u0627\u0632 66 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u0634\u0631\u0648\u0639 \u0645\u06cc \u0634\u0648\u062f \u0648 \u062a\u0627 91 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u0627\u062f\u0627\u0645\u0647 \u067e\u06cc\u062f\u0627 \u0645\u06cc \u06a9\u0646\u062f \u0627\u0632 \u0645\u062a\u062f\u0627\u0648\u0644 \u062a\u0631\u06cc\u0646 \u0627\u0631\u062a\u0641\u0627\u0639 \u0647\u0627 \u0628\u0631\u0627\u06cc \u0645\u0628\u0644\u0645\u0627\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647 \u0645\u0628\u0644<\/p>\n<p>\u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0627\u0631\u062a\u0641\u0627\u0639 70 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f.<\/p>\n<figure id=\"attachment_35384\" aria-describedby=\"caption-attachment-35384\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-35384\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/03\/rfgb.jpg\" alt=\"\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \" width=\"800\" height=\"480\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/03\/rfgb.jpg 800w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/03\/rfgb-300x180.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/03\/rfgb-768x461.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-35384\" class=\"wp-caption-text\">\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc<\/figcaption><\/figure>\n<p>\u0627\u0645\u0627 \u0647\u0645\u0627\u0646\u0637\u0648\u0631 \u06a9\u0647 \u06af\u0641\u062a\u06cc\u0645 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0645\u0628\u0644\u0645\u0627\u0646\u06cc \u0628\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u0647\u0627\u06cc \u062f\u0644\u062e\u0648\u0627\u0647 \u0633\u0641\u0627\u0631\u0634 \u062f\u0647\u06cc\u062f \u0627\u0645\u0627 \u0642\u0628\u0644 \u0627\u0632 \u0633\u0641\u0627\u0631\u0634 \u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644\u060c \u0628\u0627\u06cc\u062f \u0645\u062d\u0644\u06cc \u06a9\u0647 \u0642\u0631\u0627\u0631 \u0627\u0633\u062a \u0645\u0628\u0644 \u062f\u0631 \u0622\u0646 \u0642\u0631\u0627\u0631 \u0628\u06af\u06cc\u0631\u062f \u0631\u0627 \u062f\u0631 \u0646\u0638\u0631 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0648 \u0627\u0646\u062f\u0627\u0632\u0647 \u06af\u06cc\u0631\u06cc \u06a9\u0646\u06cc\u062f \u0648 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0622\u0646 \u0645\u0628\u0644 \u0645\u0646\u0627\u0633\u0628 \u0627\u0632 \u0646\u0638\u0631 \u0633\u0627\u06cc\u0632 \u0648 \u0627\u0628\u0639\u0627\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0646\u06a9\u062a\u0647 \u0627\u06cc \u062f\u06cc\u06af\u0631 \u06a9\u0647 \u0628\u0627\u06cc\u062f \u062f\u0631 \u0646\u0638\u0631 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0645\u0628\u0644\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0627\u0632 \u062f\u0631 \u0648\u0631\u0648\u062f\u06cc \u0648 \u0631\u0627\u0647 \u067e\u0644\u0647 \u0647\u0627 \u0648 \u0631\u0627\u0647\u0631\u0648 \u0647\u0627 \u0631\u062f \u0634\u0648\u062f \u0648 \u0627\u0645\u06a9\u0627\u0646 \u062c\u0627\u0628\u062c\u0627\u06cc\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u0648 \u0627\u06af\u0631 \u0646\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u062f\u0631 \u0648\u0631\u0648\u062f\u06cc \u0631\u062f \u06a9\u0646\u06cc\u062f \u0628\u0627\u06cc\u062f \u0628\u0627 \u06a9\u0645\u06a9 \u062c\u0631\u062b\u0642\u06cc\u0644 \u0645\u0628\u0644 \u0647\u0627 \u0631\u0627 \u0627\u0632<\/p>\n<p>\u067e\u0646\u062c\u0631\u0647 \u0648\u0627\u0631\u062f \u062e\u0627\u0646\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a \u0647\u0632\u06cc\u0646\u0647 \u0627\u062c\u0627\u0631\u0647 \u062c\u0631\u062b\u0642\u06cc\u0644 \u0628\u0631 \u062f\u06cc\u06af\u0631 \u0647\u0632\u06cc\u0646\u0647 \u0647\u0627 \u0648\u0627\u0631\u062f \u0645\u06cc \u0634\u0648\u062f \u0648 \u0627\u0632 \u0646\u0638\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0628\u0647 \u0635\u0631\u0641\u0647 \u0646\u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u0641\u0636\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u0628\u06af\u06cc\u0631\u06cc\u062f \u0628\u0627\u06cc\u062f \u0686\u0646\u062f \u06a9\u0627\u0631 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u06cc\u062f \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u062e\u0648\u0627\u0647\u06cc\u0645 \u06af\u0641\u062a.<\/p>\n<p>\u0628\u0631\u0627\u06cc \u0627\u0646\u062f\u0627\u0632\u0647 \u06af\u06cc\u0631\u06cc \u0641\u0636\u0627 \u0628\u0627\u06cc\u062f \u0637\u0648\u0644 \u0648 \u0639\u0631\u0636 \u0627\u062a\u0627\u0642 \u0631\u0627 \u0645\u062a\u0631 \u06a9\u0646\u06cc\u062f \u0648 \u06cc\u0627\u062f\u062f\u0627\u0634\u062a \u06a9\u0646\u06cc\u062f. \u0648 \u0627\u06af\u0631 \u0633\u0642\u0641 \u0645\u0646\u0632\u0644 \u062a\u0627\u0646 \u0628\u0644\u0646\u062f \u0627\u0633\u062a \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0645\u0628\u0644 \u0647\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0627\u0631\u062a\u0641\u0627\u0639 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u0645\u0627 \u0627\u06af\u0631 \u0641\u0636\u0627\u06cc \u0645\u0646\u0632\u0644 \u062a\u0627\u0646 \u06a9\u0645 \u0627\u0633\u062a \u0648 \u062e\u0627\u0646\u0647 \u0627\u06cc \u06a9\u0648\u0686\u06a9 \u062f\u0627\u0631\u06cc\u062f \u0648 \u0627\u0631\u062a\u0641\u0627\u0639 \u0633\u0642\u0641 \u062e\u0627\u0646\u0647 \u062a\u0627\u0646 \u06a9\u0645 \u0627\u0633\u062a \u0627\u0632 \u0645\u0628\u0644 \u0647\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u062d\u062f\u0627\u0642\u0644 \u062a\u0631\u06cc\u0646 \u0627\u0631\u062a\u0641\u0627\u0639 \u0648 \u0637\u0648\u0644 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0627\u062a\u0627\u0642 \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0642\u0631\u0627\u0631 \u0646\u06af\u06cc\u0631\u062f \u0648 \u062c\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0642\u0631\u0627\u0631 \u06af\u06cc\u0631\u06cc \u0645\u06cc\u0632 \u0647\u0627\u06cc \u06a9\u0646\u0627\u0631 \u0645\u0628\u0644\u06cc \u0648 \u062c\u0644\u0648 \u0645\u0628\u0644\u06cc \u0647\u0645 \u0628\u0627\u0642\u06cc \u0628\u0645\u0627\u0646\u062f \u062a\u0627 \u062f\u0631 \u0622\u062e\u0631 \u0641\u0636\u0627\u06cc\u06cc \u0632\u06cc\u0628\u0627 \u0648 \u062f\u0644\u0646\u0634\u06cc\u0646 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f.<\/p>\n<p>\u0628\u0631\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u0645\u0637\u0645\u06cc\u0646 \u0634\u0648\u06cc\u062f \u062c\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0645\u06cc\u0632 \u0647\u0627\u06cc \u06a9\u0646\u0627\u0631 \u0645\u0628\u0644\u06cc \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0631\u0641\u062a \u0648 \u0622\u0645\u062f \u062e\u0648\u062f \u0648 \u0645\u0647\u0645\u0627\u0646\u0627\u0646 \u062f\u0631 \u0646\u0638\u0631 \u06af\u0631\u0641\u062a\u0647 \u0627\u06cc\u062f \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u06cc\u0646 \u0642\u0633\u0645\u062a \u0647\u0627 \u0631\u0627 \u0639\u0644\u0627\u0645\u062a \u06af\u0630\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0627\u0632 \u0627\u0628\u0639\u0627\u062f \u06a9\u0644\u06cc \u0686\u06cc\u062f\u0645\u0627\u0646 \u0645\u0628\u0644 \u0647\u0627 \u0622\u06af\u0627\u0647 \u0628\u0634\u0648\u06cc\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0645\u0648\u0627\u0631\u062f \u06af\u0641\u062a\u0647 \u0634\u062f\u0647 \u0631\u0627 \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f \u062a\u0627 \u0627\u0632 \u062e\u0631\u06cc\u062f\u062a\u0627\u0646 \u067e\u0634\u06cc\u0645\u0627\u0646 \u0646\u0634\u0648\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u062f\u0631 \u0647\u0646\u06af\u0627\u0645 \u062e\u0631\u06cc\u062f \u062d\u062a\u0645\u0627 \u062e\u0648\u062f\u062a\u0627\u0646 \u0627\u0628\u0639\u0627\u062f \u0645\u0628\u0644 \u0631\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u0628\u06af\u06cc\u0631\u06cc\u062f \u0648 \u06cc\u0627 \u0627\u0632 \u0641\u0631\u0648\u0634\u0646\u062f\u0647 \u0628\u067e\u0631\u0633\u06cc\u062f \u062a\u0627 \u0628\u0627 \u0627\u0628\u0639\u0627\u062f\u06cc \u06a9\u0647 \u0645\u062f \u0646\u0638\u0631\u062a\u0627\u0646 \u0627\u0633\u062a \u0647\u0645\u062e\u0648\u0627\u0646\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<\/p>\n<p>\u0647\u0645\u0627\u0646\u0637\u0648\u0631 \u06a9\u0647 \u062f\u0631 \u0645\u0642\u0627\u0644\u0647 \u0647\u0627\u06cc \u0642\u0628\u0644\u06cc \u06af\u0641\u062a\u0647 \u0627\u06cc\u0645 \u0645\u0628\u0644 \u0647\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u062f\u0631 \u0627\u0646\u0648\u0627\u0639 \u0645\u062e\u062a\u0644\u0641\u06cc \u0637\u0631\u0627\u062d\u06cc \u0648 \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc \u0634\u0648\u0646\u062f \u0648 \u0627\u0632 \u0627\u0646\u0648\u0627\u0639 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u0645 \u0628\u0647 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0627\u0644 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0646\u06cc\u0645. \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0627\u0632 \u0645\u0628\u0644 \u0647\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0633\u0628\u06a9 \u0631\u0627\u062d\u062a\u06cc \u06a9\u0647 \u062f\u0627\u0631\u0646\u062f \u0628\u0633\u06cc\u0627\u0631 \u067e\u0631\u0637\u0631\u0641\u062f\u0627\u0631 \u0647\u0633\u062a\u0646\u062f \u0648 \u062a\u0642\u0631\u06cc\u0628\u0627 \u0628\u0627 \u0647\u0631 \u0633\u0644\u06cc\u0642\u0647 \u0627\u06cc \u0645\u0637\u0627\u0628\u0642\u062a \u062f\u0627\u0631\u062f.<\/p>\n<figure id=\"attachment_35383\" aria-describedby=\"caption-attachment-35383\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-35383\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/03\/ewew.jpg\" alt=\"\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \" width=\"800\" height=\"480\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/03\/ewew.jpg 800w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/03\/ewew-300x180.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2022\/03\/ewew-768x461.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-35383\" class=\"wp-caption-text\">\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc<\/figcaption><\/figure>\n<p>\u062f\u0627\u0634\u062a\u0646 \u0645\u0628\u0644 \u0627\u0644 \u0628\u0633\u062a\u06af\u06cc \u0628\u0647 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u06cc\u0648\u0646 \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u062e\u0627\u0646\u0647 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u062a\u0631\u0627\u0698 \u062e\u0627\u0646\u0647 \u0628\u0633\u062a\u06af\u06cc \u062f\u0627\u0631\u062f \u0627\u06af\u0631 \u062e\u0627\u0646\u0647 \u06a9\u0648\u0686\u06a9\u06cc \u062f\u0627\u0631\u06cc\u062f \u0648 \u06cc\u06a9 \u062f\u0633\u062a \u0645\u0628\u0644 \u062f\u0631 \u062e\u0627\u0646\u0647 \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u062f \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0641\u0642\u0637 \u0627\u0632 \u06cc\u06a9 \u0645\u0628\u0644 \u0627\u0644 \u0645\u0627\u0646\u0646\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0633\u062a \u06a9\u0627\u0645\u0644<\/p>\n<p>\u0622\u0646 \u0631\u0627 \u0646\u062e\u0631\u06cc\u062f \u062a\u0627 \u062e\u0627\u0646\u0647 \u0634\u0645\u0627 \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0634\u0644\u0648\u063a \u0646\u0634\u0648\u062f \u0627\u0645\u0627 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0647\u0645 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0646 \u0645\u0628\u0644 \u0647\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u0648 \u0627\u0644 \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0628\u0627 \u062e\u0648\u0627\u0647\u0646\u062f \u0634\u062f \u0648 \u062f\u0631 \u0639\u06cc\u0646 \u062d\u0627\u0644 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0647\u0645 \u0647\u0633\u062a\u0646\u062f. \u062f\u0631 \u062e\u0627\u0646\u0647 \u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0628\u0644 \u0627\u0644 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a\u06cc \u0646\u062f\u0627\u0631\u062f \u0648 \u0634\u0645\u0627 \u0628\u0627 \u0647\u0631 \u0633\u0628\u06a9\u06cc \u0627\u0632 \u0645\u0628\u0644 \u0627\u0644 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062e\u0648\u062f \u0686\u06cc\u062f\u0645\u0627\u0646 \u06a9\u0646\u06cc\u062f \u0627\u0645\u0627 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u0627 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0627\u0644 \u0627\u0633\u062a \u0632\u06cc\u0631\u0627 \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0645\u0628\u0644 \u0647\u0627 \u0647\u0645\u0627\u0646\u0637\u0648\u0631 \u06a9\u0647 \u06af\u0641\u062a\u0647 \u0634\u062f \u062f\u0631 \u0639\u06cc\u0646 \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0631\u0627\u062d\u062a \u0647\u0633\u062a\u0646\u062f. \u0627\u0645\u0627 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631 \u0647\u0627\u06cc \u0645\u0628\u0644 \u0627\u0644 \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632 198 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u0637\u0648\u0644 \u0648 90 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u0639\u0645\u0642 \u0627\u0633\u062a. \u0627\u0644\u0628\u062a\u0647<\/p>\n<p>\u0627\u06cc\u0646 \u0627\u0639\u062f\u0627\u062f \u0645\u062a\u063a\u06cc\u0631 \u0647\u0633\u062a\u0646\u062f \u0648 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u06a9\u0648\u0686\u06a9\u062a\u0631 \u06cc\u0627 \u0628\u0632\u0631\u06af \u062a\u0631 \u0628\u0627\u0634\u062f \u0627\u0645\u0627 \u0628\u0637\u0648\u0631 \u06a9\u0644\u06cc \u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0627\u0644\u060c \u0637\u0648\u0644 \u06a9\u0645\u062a\u0631 2 \u0645\u062a\u0631 \u0648 \u0639\u0645\u0642 \u06a9\u0645\u062a\u0631 \u0627\u0632 1 \u0645\u062a\u0631\u06cc \u062f\u0627\u0631\u062f. \u062f\u0631 \u0631\u0627\u0628\u0637\u0647 \u0628\u0627 \u062e\u0631\u06cc\u062f \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0627\u0644 \u0647\u0645 \u0648\u0631\u0648\u062f\u06cc \u062e\u0627\u0646\u0647 \u060c \u0631\u0627\u0647\u0631\u0648 \u0647\u0627 \u0648 \u0631\u0627\u0647 \u067e\u0644\u0647 \u0647\u0627 \u0631\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u0628\u06af\u06cc\u0631\u06cc\u062f \u0648 \u0645\u0637\u0645\u0626\u0646 \u0634\u0648\u06cc\u062f \u06a9\u0647 \u0645\u0628\u0644 \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u0627\u0632 \u0622\u0646 \u0647\u0627 \u0631\u062f \u0645\u06cc \u0634\u0648\u062f . \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0648\u0631\u062f \u062d\u062a\u0645\u0627 \u0628\u0627 \u0641\u0631\u0648\u0634\u0646\u062f\u0647 \u0645\u0634\u0648\u0631\u062a \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062f\u0642\u06cc\u0642\u06cc \u062f\u0631\u0628\u0627\u0631\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644 \u0628\u0647 \u0634\u0645\u0627 \u0628\u062f\u0647\u062f \u062a\u0627 \u0627\u0632 \u062e\u0631\u06cc\u062f \u062e\u0648\u062f \u067e\u0634\u06cc\u0645\u0627\u0646 \u0646\u0634\u0648\u062f.<\/p>\n<p>\u0645\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0633\u0639\u06cc \u06a9\u0631\u062f\u0647 \u0627\u06cc\u0645 \u062a\u0648\u062c\u0647 \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u062c\u0644\u0628 \u06a9\u0646\u06cc\u0645. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0627 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0647\u0627\u06cc \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0622\u0634\u0646\u0627 \u0634\u062f\u0647 \u0627\u06cc\u062f \u0648 \u0627\u0637\u0644\u0627\u0639 \u06cc\u0627\u0641\u062a\u06cc\u062f \u06a9\u0647 \u0645\u0647\u0645\u062a\u0631\u06cc\u0646 \u0639\u0648\u0627\u0645\u0644 \u0642\u0628\u0644 \u0627\u0632 \u062e\u0631\u06cc\u062f \u0645\u0628\u0644 \u0686\u06a9 \u06a9\u0631\u062f\u0646 \u0639\u0631\u0636 \u0631\u0627\u0647\u0631\u0648 \u0647\u0627 \u060c \u0631\u0627\u0647 \u067e\u0644\u0647 \u0648 \u0648\u0631\u0648\u062f\u06cc \u062e\u0627\u0646\u0647 \u0647\u0627 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u062d\u0644 \u0642\u0631\u0627\u0631 \u06af\u06cc\u0631\u06cc \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc\u060c \u0645\u062a\u0631\u0627\u0698 \u062e\u0627\u0646\u0647 \u0648 \u0627\u0631\u062a\u0641\u0627\u0639 \u0633\u0642\u0641 \u0648 \u062f\u0631 \u0622\u062e\u0631 \u0645\u062d\u0644\u06cc \u0628\u0631\u0627\u06cc \u0631\u0641\u062a \u0622\u0645\u062f \u0648 \u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0646 \u0645\u06cc\u0632 \u0647\u0627\u06cc \u06a9\u0646\u0627\u0631 \u0645\u0628\u0644\u06cc \u0648 \u0645\u06cc\u0632 \u062c\u0644\u0648 \u0645\u0628\u0644\u06cc \u0627\u0633\u062a. \u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u0645 \u0628\u0627 \u0645\u0637\u0627\u0644\u0639\u0647 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u062e\u0631\u06cc\u062f \u062f\u0631\u0633\u062a\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0648 \u0642\u062f\u0645 \u0645\u0648\u062b\u0631\u06cc \u062f\u0631 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062e\u0627\u0646\u0647 \u062e\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f. \u0633\u067e\u0627\u0633 \u0627\u0632 \u0647\u0645\u0631\u0627\u0647\u06cc \u0634\u0645\u0627 \u062e\u0648\u0628\u0627\u0646.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D8%A8%D8%A7%D8%B1%D9%87_%DB%8C_%D8%AF%DA%A9%D9%88%D8%B1%D9%85%DA%AF\"><\/span><strong>\u062f\u0631\u0628\u0627\u0631\u0647 \u06cc\u00a0\u062f\u06a9\u0648\u0631\u0645\u06af<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u0645\u0631\u0648\u0632\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a\u00a0 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0645\u0634\u063a\u0644\u0647 \u06cc \u06a9\u0627\u0631\u06cc \u0627\u0645\u06a9\u0627\u0646 \u062e\u0631\u06cc\u062f \u062d\u0636\u0648\u0631\u06cc \u0648 \u06cc\u0627 \u062d\u062a\u06cc \u0645\u0634\u0627\u0647\u062f\u0647 \u06cc \u0645\u062f\u0644 \u0647\u0627 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0645\u0634\u06a9\u0644 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f \u061b\u00a0 \u06cc\u06a9\u06cc \u0627\u0632 \u0633\u0627\u06cc\u062a \u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631 \u06a9\u0647 \u0627\u0645\u06a9\u0627\u0646 \u062e\u0631\u06cc\u062f \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc\u00a0 \u0631\u0627 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u060c\u00a0<strong><a href=\"https:\/\/decorshop.ir\/\" target=\"_blank\" rel=\"nofollow noopener\">\u062f\u06a9\u0648\u0631\u0634\u0627\u067e<\/a>\u00a0<\/strong>\u0645\u06cc\u0628\u0627\u0634\u062f .<\/p>\n<p>\u0627\u0644\u0628\u062a\u0647 \u0627\u06cc\u0646<a href=\"https:\/\/chenco.ir\/\" target=\"_blank\" rel=\"noopener\">\u00a0<strong>\u0634\u0631\u06a9\u062a<\/strong><\/a><strong>\u00a0<\/strong>\u0628\u0631\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0634\u0645\u0627 \u060c \u0627\u0645\u06a9\u0627\u0646 \u062e\u0631\u06cc\u062f \u0627\u0642\u0633\u0627\u0637\u06cc \u062d\u062a\u06cc \u0628\u062f\u0648\u0646 \u0636\u0627\u0645\u0646 \u0631\u0627 \u062f\u0631 \u0633\u0627\u06cc\u062a \u0641\u0631\u0627\u0647\u0645 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u0648 \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u062d\u0635\u0648\u0644 \u0628\u0647 \u0645\u0634\u06a9\u0644\u06cc \u0628\u0631\u062e\u0648\u0631\u062f \u06a9\u0631\u062f\u06cc\u062f \u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646 \u0647\u0627\u06cc \u062f\u06a9\u0648\u0631\u0634\u0627\u067e \u0628\u0647 \u0635\u0648\u0631\u062a \u0631\u0627\u06cc\u06af\u0627\u0646 \u0645\u0634\u0627\u0648\u0631\u0647 \u0628\u06af\u06cc\u0631\u06cc\u062f .<\/p>\n<p>\u0628\u0631\u0627\u06cc \u0645\u0634\u0627\u0647\u062f\u0647 \u06cc \u0645\u0642\u0627\u0644\u0627\u062a \u0628\u06cc\u0634\u062a\u0631 \u0628\u0647\u00a0<strong><a href=\"https:\/\/decorshop.ir\/mag\/\" target=\"_blank\" rel=\"nofollow noopener\">\u062f\u06a9\u0648\u0631\u0645\u06af<\/a>\u00a0\u0648\u00a0<\/strong><a href=\"https:\/\/chenco.ir\/blog\/\" target=\"_blank\" rel=\"noopener\"><strong>\u0648\u0628\u0644\u0627\u06af \u0686\u0634\u0645\u0647 \u0646\u0648<\/strong>\u0631<\/a>\u00a0\u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u0633\u067e\u0627\u0633 \u0627\u0632 \u0632\u0645\u0627\u0646\u06cc \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u0645\u0627 \u06af\u0630\u0627\u0634\u062a\u06cc\u062f \u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u0645 \u0645\u0637\u0627\u0644\u0628 \u0645\u0642\u0627\u0644\u0647 \u0645\u0641\u06cc\u062f \u0628\u0648\u062f\u0647 \u0628\u0627\u0634\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0646\u062f\u0627\u0632\u0647 \u0645\u0628\u0644 \u0631\u0627\u062d\u062a\u06cc \u0645\u0628\u0644 \u0647\u0627 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0633\u0628\u06a9 \u0648 \u0645\u062f\u0644 \u062e\u0648\u062f \u062f\u0631 \u0627\u0646\u062f\u0627\u0632\u0647 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc \u0634\u0648\u0646\u062f \u0648 \u0647\u0645\u0647 \u0645\u0628\u0644 \u0647\u0627 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0633\u0628\u06a9 \u0648 \u0645\u062f\u0644 \u062e\u0648\u062f \u0627\u0632 \u06cc\u06a9 \u0627\u0646\u062f\u0627\u0632\u0647 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u06cc \u067e\u06cc\u0631\u0648\u06cc \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0648 \u0645\u0628\u0644 \u0647\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u0647\u0645 \u0627\u0632 \u0627\u0646\u062f\u0627\u0632\u0647 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0647\u0633\u062a\u0646\u062f \u0627\u0645\u0627 \u06cc\u06a9 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u06cc \u0628\u0631\u0627\u06cc \u0645\u0628\u0644 \u0647\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":35385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[615,102,63],"class_list":["post-35382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-34","tag-615","tag-102","tag-63"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/35382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=35382"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/35382\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/35385"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=35382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=35382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=35382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}