{"id":34789,"date":"2021-09-19T10:20:45","date_gmt":"2021-09-19T05:50:45","guid":{"rendered":"https:\/\/decorshop.ir\/mag\/?p=34789"},"modified":"2023-04-27T11:52:25","modified_gmt":"2023-04-27T08:22:25","slug":"%d9%86%d8%ad%d9%88%d9%87-%d8%a8%d9%87-%d8%b1%d9%88%d8%b2-%d8%b1%d8%b3%d8%a7%d9%86%db%8c-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%b4%db%8c%d9%84%d8%af-%d8%af%d8%a7%d8%b1","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a8%d9%87-%d8%b1%d9%88%d8%b2-%d8%b1%d8%b3%d8%a7%d9%86%db%8c-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%b4%db%8c%d9%84%d8%af-%d8%af%d8%a7%d8%b1\/","title":{"rendered":"\u0646\u062d\u0648\u0647 \u0628\u0647 \u0631\u0648\u0632 \u0631\u0633\u0627\u0646\u06cc \u0644\u0648\u0633\u062a\u0631 \u0634\u06cc\u0644\u062f \u062f\u0627\u0631"},"content":{"rendered":"<p>\u0646\u062d\u0648\u0647 \u0628\u0647 \u0631\u0648\u0632 \u0631\u0633\u0627\u0646\u06cc \u0644\u0648\u0633\u062a\u0631 \u0634\u06cc\u0644\u062f \u062f\u0627\u0631 \u0634\u0627\u06cc\u062f \u0627\u0632 \u0646\u0638\u0631 \u0634\u0645\u0627 \u06cc\u06a9 \u0645\u0639\u062c\u0632\u0647 \u0627\u0633\u062a. \u062a\u063a\u06cc\u06cc\u0631 \u0644\u0648\u0633\u062a\u0631 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u0634\u0645\u0627 \u0628\u0627 \u0633\u0627\u06cc\u0647 \u0647\u0627 \u0628\u0627 \u0633\u06cc\u0633\u062a\u0645 \u0633\u0627\u06cc\u0647 \u0644\u0648\u0633\u062a\u0631 \u0646\u0648\u0622\u0648\u0631\u0627\u0646\u0647 \u0645\u0627 \u06cc\u06a9 \u0636\u0631\u0628\u0647 \u0645\u062d\u06a9\u0645 \u0648 \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0627\u06cc\u062f\u0647 \u0647\u0627\u06cc \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u0627\u062a\u0627\u0642 \u0646\u0627\u0647\u0627\u0631 \u062e\u0648\u0631\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc \u062f\u0647\u062f. \u0645\u0627 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0631\u0648\u0634 \u0647\u0627\u06cc\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0647 \u0631\u0648\u0632 \u0631\u0633\u0627\u0646\u06cc \u0686\u0631\u0627\u063a \u0633\u0642\u0641\u06cc \u0645\u0648\u062c\u0648\u062f \u0628\u0627 \u0627\u0641\u0632\u0648\u062f\u0646 \u0633\u0627\u06cc\u0647 \u062f\u0631\u0627\u0645 \u0628\u0647 \u0627\u0634\u062a\u0631\u0627\u06a9 \u062e\u0648\u0627\u0647\u06cc\u0645 \u06af\u0630\u0627\u0634\u062a. \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a\u060c \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0637\u0631\u062d \u0631\u0627 \u0628\u0627 \u0627\u0641\u0632\u0648\u062f\u0646 \u0633\u0627\u06cc\u0647 \u0628\u0647 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644 \u0633\u0641\u0627\u0631\u0634\u06cc \u06a9\u0646\u06cc\u062f. \u0686\u0631\u0627\u063a \u067e\u0648\u0633\u062a\u0647 \u06cc\u0627 \u0645\u0647\u0631\u0647 \u0627\u06cc. \u067e\u0633 \u0628\u0627 \u0686\u0634\u0645\u0647 \u0646\u0648\u0631 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627\u0634\u06cc\u062f \u0628\u0627 \u06cc\u06a9 \u0645\u0642\u0627\u0644\u0647 \u062c\u0630\u0627\u0628 \u0648 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u062f\u06cc\u06af\u0631!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34791\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/09\/2050.jpg\" alt=\"\u0644\u0648\u0633\u062a\u0631 \u0634\u06cc\u0644\u062f \u062f\u0627\u0631\" width=\"1400\" height=\"600\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/09\/2050.jpg 1400w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/09\/2050-300x129.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/09\/2050-1024x439.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/09\/2050-768x329.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a8%d9%87-%d8%b1%d9%88%d8%b2-%d8%b1%d8%b3%d8%a7%d9%86%db%8c-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%b4%db%8c%d9%84%d8%af-%d8%af%d8%a7%d8%b1\/#%DA%86%DA%AF%D9%88%D9%86%D9%87_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%B1%D8%A7_%D8%A8%D8%A7_%D8%B4%DB%8C%D9%84%D8%AF_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%B4%DB%8C%D9%84%D8%AF_%D8%AF%D8%A7%D8%B1_%D8%A8%D9%87_%D8%B1%D9%88%D8%B2_%D9%85%DB%8C_%DA%A9%D9%86%DB%8C%D8%AF%D8%9F\" >\u0686\u06af\u0648\u0646\u0647 \u0644\u0648\u0633\u062a\u0631 \u0631\u0627 \u0628\u0627 \u0634\u06cc\u0644\u062f (\u0644\u0648\u0633\u062a\u0631 \u0634\u06cc\u0644\u062f \u062f\u0627\u0631) \u0628\u0647 \u0631\u0648\u0632 \u0645\u06cc \u06a9\u0646\u06cc\u062f\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a8%d9%87-%d8%b1%d9%88%d8%b2-%d8%b1%d8%b3%d8%a7%d9%86%db%8c-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%b4%db%8c%d9%84%d8%af-%d8%af%d8%a7%d8%b1\/#%D8%A2%DB%8C%D8%A7_%D9%86%D8%B5%D8%A8_%D8%B4%DB%8C%D9%84%D8%AF_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%B4%D9%81%D8%A7%D9%81_%D8%A2%D8%B3%D8%A7%D9%86_%D8%A7%D8%B3%D8%AA%D8%9F\" >\u0622\u06cc\u0627 \u0646\u0635\u0628 \u0634\u06cc\u0644\u062f \u0644\u0648\u0633\u062a\u0631 \u0634\u0641\u0627\u0641 \u0622\u0633\u0627\u0646 \u0627\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a8%d9%87-%d8%b1%d9%88%d8%b2-%d8%b1%d8%b3%d8%a7%d9%86%db%8c-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%b4%db%8c%d9%84%d8%af-%d8%af%d8%a7%d8%b1\/#%DA%86%D8%B1%D8%A7%D8%BA_%D9%87%D8%A7%DB%8C_%D8%B3%D9%82%D9%81%DB%8C_%DA%86%D8%B7%D9%88%D8%B1%D8%9F\" >\u0686\u0631\u0627\u063a \u0647\u0627\u06cc \u0633\u0642\u0641\u06cc \u0686\u0637\u0648\u0631\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a8%d9%87-%d8%b1%d9%88%d8%b2-%d8%b1%d8%b3%d8%a7%d9%86%db%8c-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%b4%db%8c%d9%84%d8%af-%d8%af%d8%a7%d8%b1\/#%D8%AF%D8%B1%D8%A8%D8%A7%D8%B1%D9%87_%D8%B4%DB%8C%D9%84%D8%AF_%D9%87%D8%A7_%D9%88_%D9%BE%D8%B1%D8%AF%D9%87_%D9%87%D8%A7%DB%8C_%D9%85%D8%A7_%D8%A8%DB%8C%D8%B4%D8%AA%D8%B1_%D8%A8%D8%AF%D8%A7%D9%86%DB%8C%D8%AF\" >\u062f\u0631\u0628\u0627\u0631\u0647 \u0634\u06cc\u0644\u062f \u0647\u0627 \u0648 \u067e\u0631\u062f\u0647 \u0647\u0627\u06cc \u0645\u0627 \u0628\u06cc\u0634\u062a\u0631 \u0628\u062f\u0627\u0646\u06cc\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a8%d9%87-%d8%b1%d9%88%d8%b2-%d8%b1%d8%b3%d8%a7%d9%86%db%8c-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%b4%db%8c%d9%84%d8%af-%d8%af%d8%a7%d8%b1\/#%D8%B3%D8%AE%D9%86_%D9%BE%D8%A7%DB%8C%D8%A7%D9%86%DB%8C_%DA%86%D8%B4%D9%85%D9%87_%D9%86%D9%88%D8%B1\" >\u0633\u062e\u0646 \u067e\u0627\u06cc\u0627\u0646\u06cc \u0686\u0634\u0645\u0647 \u0646\u0648\u0631<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a8%d9%87-%d8%b1%d9%88%d8%b2-%d8%b1%d8%b3%d8%a7%d9%86%db%8c-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%b4%db%8c%d9%84%d8%af-%d8%af%d8%a7%d8%b1\/#%D8%AF%D8%B1%D8%A8%D8%A7%D8%B1%D9%87_%DB%8C_%DA%86%D8%B4%D9%85%D9%87_%D9%86%D9%88%D8%B1\" >\u062f\u0631\u0628\u0627\u0631\u0647 \u06cc\u00a0\u0686\u0634\u0645\u0647 \u0646\u0648\u0631<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"%DA%86%DA%AF%D9%88%D9%86%D9%87_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%B1%D8%A7_%D8%A8%D8%A7_%D8%B4%DB%8C%D9%84%D8%AF_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%B4%DB%8C%D9%84%D8%AF_%D8%AF%D8%A7%D8%B1_%D8%A8%D9%87_%D8%B1%D9%88%D8%B2_%D9%85%DB%8C_%DA%A9%D9%86%DB%8C%D8%AF%D8%9F\"><\/span><strong>\u0686\u06af\u0648\u0646\u0647 \u0644\u0648\u0633\u062a\u0631 \u0631\u0627 \u0628\u0627 \u0634\u06cc\u0644\u062f (\u0644\u0648\u0633\u062a\u0631 \u0634\u06cc\u0644\u062f \u062f\u0627\u0631) \u0628\u0647 \u0631\u0648\u0632 \u0645\u06cc \u06a9\u0646\u06cc\u062f\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u06a9\u0646\u0648\u0646 \u0646\u062d\u0648\u0647 \u0628\u0647 \u0631\u0648\u0632 \u0631\u0633\u0627\u0646\u06cc \u0644\u0648\u0633\u062a\u0631 \u0628\u0627 \u0633\u0627\u06cc\u0647 \u0647\u0627 \u0631\u0627 \u062a\u0648\u0636\u06cc\u062d \u062e\u0648\u0627\u0647\u0645 \u062f\u0627\u062f. \u0633\u06cc\u0633\u062a\u0645 \u0634\u0641\u0627\u0641 \u0633\u062d\u0631 \u0648 \u062c\u0627\u062f\u0648\u06cc \u0634\u06cc\u0644\u062f \u0644\u0648\u0633\u062a\u0631 \u06cc\u06a9 \u0631\u0648\u0634 \u0627\u0631\u0632\u0627\u0646 \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u0632\u0646\u062f\u06af\u06cc \u062c\u062f\u06cc\u062f \u0628\u0647 \u0644\u0648\u0633\u062a\u0631 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u0634\u0645\u0627 \u0627\u0633\u062a. \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0622\u062f\u0627\u067e\u062a\u0648\u0631 \u0634\u06cc\u0644\u062f \u0628\u0647 \u0634\u0645\u0627 \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0645\u06cc \u062f\u0647\u062f \u06a9\u0647 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0633\u0627\u06cc\u0647 \u062f\u0631\u0627\u0645 \u0628\u0631\u0627\u0642 \u0648 \u0634\u0641\u0627\u0641 \u0631\u0627 \u0628\u0647 \u0627\u06a9\u062b\u0631 \u0686\u0631\u0627\u063a \u0647\u0627\u06cc \u0622\u0648\u06cc\u0632\u0627\u0646 \u0633\u0646\u062a\u06cc \u0648 \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u0633\u0631\u0633\u0631\u0627 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f. \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u0622\u0647\u0646\u06cc \u0628\u0631\u0627\u06cc \u0627\u0645\u0631\u0648\u0632 \u062f\u0631\u0628\u0627\u0631\u0647 \u0633\u0631\u06cc \u0622\u0647\u0646 \u0647\u0627\u06cc \u0641\u0631\u0641\u0648\u0631\u0698\u0647 \u0645\u0627 \u0645\u06cc \u06af\u0648\u06cc\u062f \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0633\u06cc\u0633\u062a\u0645 \u062c\u0627\u062f\u0648\u06cc \u0634\u0641\u0627\u0641 \u0627\u06cc\u062f\u0647 \u0622\u0644 \u0647\u0633\u062a\u0646\u062f.<\/p>\n<p>\u0627\u06cc\u062f\u0647 \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0627\u062a\u0627\u0642 \u063a\u0630\u0627\u062e\u0648\u0631\u06cc \u0634\u06cc\u0644\u062f \u0637\u0628\u0644\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0634\u06cc\u0644\u062f \u0627\u06cc \u0628\u0647 \u0622\u0647\u0646 \u0641\u0631\u0641\u0648\u0631\u0698\u0647 \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u062c\u062f\u06cc\u062f \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u062f. \u0644\u0648\u0633\u062a\u0631 \u0645\u0647\u0631\u0647 \u0627\u06cc \u06cc\u0627 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc. \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0644\u0648\u0627\u0632\u0645 \u062c\u0627\u0646\u0628\u06cc \u0622\u0648\u06cc\u0632\u0627\u0646 \u0628\u0627 \u0632\u0646\u062c\u06cc\u0631 \u0628\u0627 \u0633\u0627\u06cc\u0647\u060c \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0646\u0648\u0631\u06af\u06cc\u0631 \u06a9\u0627\u0645\u0644 \u062e\u0648\u062f \u0631\u0627 \u0633\u0641\u0627\u0631\u0634\u06cc \u06a9\u0646\u06cc\u062f. \u0644\u0637\u0641\u0627\u064b \u067e\u0633\u062a \u0648\u0628\u0644\u0627\u06af \u0645\u0627 \u0631\u0627 \u062f\u0631 \u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u0644\u0648\u0633\u062a\u0631 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f \u062a\u0627 \u0647\u0645\u0647 \u0686\u06cc\u0632 \u0631\u0627 \u062f\u0631 \u0645\u0648\u0631\u062f \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644 \u0645\u0627 \u0628\u06cc\u0627\u0645\u0648\u0632\u06cc\u062f.<\/p>\n<p>\u0633\u06cc\u0633\u062a\u0645 \u0634\u06cc\u0644\u062f \u062f\u0648 \u0642\u0633\u0645\u062a\u06cc \u0634\u0627\u0645\u0644 \u06cc\u06a9 \u0633\u0627\u06cc\u0647 \u062f\u0631\u0627\u0645 \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u06cc\u06a9 \u0622\u0648\u06cc\u0632 \u0622\u0648\u06cc\u0632\u0627\u0646 \u0633\u0627\u06cc\u0647 \u0644\u0648\u0633\u062a\u0631 \u0627\u0633\u062a. \u0644\u0648\u0627\u0632\u0645 \u062c\u0627\u0646\u0628\u06cc \u0634\u06cc\u0644\u062f \u0622\u0648\u06cc\u0632 \u0628\u0647 \u06af\u0648\u0646\u0647 \u0627\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0633\u062a \u0628\u0647 \u062f\u0633\u062a \u0628\u0627 \u0633\u0627\u06cc\u0647 \u0647\u0627\u06cc \u062f\u0631\u0627\u0645 \u06a9\u0627\u0631 \u0645\u06cc \u06a9\u0646\u062f. \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0636\u0645\u06cc\u0645\u0647 \u0634\u06cc\u0644\u062f \u0644\u0648\u0633\u062a\u0631 \u062f\u0631 \u0637\u06cc\u0641 \u06af\u0633\u062a\u0631\u062f\u0647 \u0627\u06cc \u0627\u0632 \u0631\u0648\u06a9\u0634 \u0641\u0644\u0632\u06cc \u0648 \u0647\u0631 \u062c\u0646\u0633 \u062f\u06cc\u06af\u0631\u06cc \u0645\u0648\u062c\u0648\u062f \u0627\u0633\u062a \u062a\u0627 \u0628\u0627 \u0631\u0646\u06af \u0644\u0648\u0633\u062a\u0631 \u0634\u0645\u0627 \u0647\u0645\u0627\u0647\u0646\u06af \u0634\u0648\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A2%DB%8C%D8%A7_%D9%86%D8%B5%D8%A8_%D8%B4%DB%8C%D9%84%D8%AF_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%B4%D9%81%D8%A7%D9%81_%D8%A2%D8%B3%D8%A7%D9%86_%D8%A7%D8%B3%D8%AA%D8%9F\"><\/span><strong>\u0622\u06cc\u0627 \u0646\u0635\u0628 \u0634\u06cc\u0644\u062f \u0644\u0648\u0633\u062a\u0631 \u0634\u0641\u0627\u0641 \u0622\u0633\u0627\u0646 \u0627\u0633\u062a\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0633\u06cc\u0633\u062a\u0645 \u0634\u06cc\u0644\u062f \u0686\u0634\u0645\u0647 \u0646\u0648\u0631 \u0633\u0631\u06cc\u0639 \u0648 \u0622\u0633\u0627\u0646 \u0646\u0635\u0628 \u0645\u06cc \u0634\u0648\u062f. \u0627\u0632 \u0647\u0645\u0647 \u0628\u0647\u062a\u0631 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0644\u0627\u0645\u067e \u0634\u0645\u0627 \u0646\u06cc\u0627\u0632\u06cc \u0628\u0647 \u062d\u0630\u0641 \u0627\u0632 \u0633\u0642\u0641 \u0646\u062f\u0627\u0631\u062f. \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0644\u0648\u0627\u0632\u0645 \u062c\u0627\u0646\u0628\u06cc \u0634\u06cc\u0644\u062f \u062f\u0627\u0631 \u062b\u0628\u062a \u0634\u062f\u0647 \u0633\u0627\u062f\u0647 \u0627\u0633\u062a \u0648 \u062f\u0633\u062a\u0648\u0631\u0627\u0644\u0639\u0645\u0644 \u0647\u0627 \u0631\u0627 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u062f\u0646\u0628\u0627\u0644 \u0645\u06cc \u06a9\u0646\u06cc\u062f. \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062a\u0631\u062a\u06cc\u0628\u060c \u0646\u0635\u0628 \u0631\u0627 \u062d\u062a\u06cc \u0633\u0627\u062f\u0647 \u062a\u0631 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<p>\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0627\u06cc\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u06cc\u06a9 \u067e\u0631\u0648\u0698\u0647 DIY \u0628\u0627\u0634\u062f\u060c \u0632\u06cc\u0631\u0627 \u0646\u06cc\u0627\u0632\u06cc \u0628\u0647 \u0628\u0631\u0642 \u0646\u06cc\u0633\u062a. \u0628\u0631\u0627\u06cc \u0646\u0635\u0628\u060c \u062a\u0646\u0647\u0627 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0646\u0631\u062f\u0628\u0627\u0646 \u0627\u0633\u062a. \u0641\u0642\u0637 \u0634\u06cc\u0644\u062f \u0631\u0627 \u0628\u0647 \u0644\u0648\u0633\u062a\u0631 \u062e\u0648\u062f \u0648\u0635\u0644 \u06a9\u0646\u06cc\u062f \u0648 \u0633\u067e\u0633 \u0631\u0648\u06cc \u0634\u06cc\u0644\u062f \u062f\u0631\u0627\u0645 \u0628\u06a9\u0634\u06cc\u062f. \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u0644\u0648\u0633\u062a\u0631 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u062e\u0648\u062f \u0631\u0627 \u062a\u0645\u06cc\u0632 \u0645\u06cc \u06a9\u0646\u06cc\u062f\u060c \u062d\u0630\u0641 \u0622\u0646 \u0634\u06cc\u0644\u062f \u0633\u0627\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%DA%86%D8%B1%D8%A7%D8%BA_%D9%87%D8%A7%DB%8C_%D8%B3%D9%82%D9%81%DB%8C_%DA%86%D8%B7%D9%88%D8%B1%D8%9F\"><\/span><strong>\u0686\u0631\u0627\u063a \u0647\u0627\u06cc \u0633\u0642\u0641\u06cc \u0686\u0637\u0648\u0631\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u0631 \u062d\u0642\u06cc\u0642\u062a\u060c \u0686\u0631\u0627\u063a \u0647\u0627\u06cc \u0641\u0644\u0627\u0634 \u0633\u0642\u0641\u06cc \u0646\u06cc\u0632 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627 \u0634\u06cc\u0644\u062f \u062c\u062f\u06cc\u062f \u0648 \u0632\u06cc\u0628\u0627\u06cc \u0634\u0645\u0627 \u0638\u0627\u0647\u0631 \u062a\u0627\u0632\u0647 \u0627\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u0628\u0631\u062e\u06cc \u0627\u0632 \u0627\u06cc\u062f\u0647 \u0647\u0627\u06cc \u0633\u0627\u06cc\u0647 \u0631\u0648\u0634\u0646 \u0633\u0642\u0641 \u0634\u0627\u0645\u0644 \u0627\u0641\u0632\u0648\u062f\u0646 \u0633\u0627\u06cc\u0647 \u0647\u0627\u06cc \u0637\u0628\u0644 \u0628\u0647 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644 \u0627\u0633\u062a. \u067e\u0627\u06cc\u0647 \u0647\u0627\u06cc \u0641\u0644\u0627\u0634 \u067e\u0648\u0633\u062a\u0647 \u0648 \u0645\u0647\u0631\u0647 \u062f\u0627\u0631. \u0628\u0627 \u0633\u0627\u06cc\u0647 \u0637\u0628\u0644 \u0648 \u0644\u0648\u0627\u0632\u0645 \u062c\u0627\u0646\u0628\u06cc \u0645\u062a\u0635\u0644\u060c \u0686\u0631\u0627\u063a \u0633\u0642\u0641\u06cc \u0634\u0645\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u062f\u0648 \u0638\u0627\u0647\u0631 \u0645\u062a\u0641\u0627\u0648\u062a \u0646\u0633\u0628\u062a \u0628\u0647 \u06cc\u06a9 \u0642\u06cc\u0645\u062a \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<\/p>\n<p>\u0636\u0645\u06cc\u0645\u0647 \u0633\u0627\u06cc\u0647 \u0631\u0648\u0634\u0646 \u0633\u0642\u0641 \u0634\u06cc\u0644\u062f \u0631\u0627\u0647\u06cc \u0622\u0633\u0627\u0646 \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0648\u062f\u0646 \u0633\u0627\u06cc\u0647 \u0637\u0628\u0644 \u0645\u0627 \u0628\u0647 \u06cc\u06a9 \u0646\u0648\u0631\u06af\u06cc\u0631 \u0646\u0632\u062f\u06cc\u06a9 \u0627\u0633\u062a. \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0622\u062f\u0627\u067e\u062a\u0648\u0631 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0686\u0631\u0627\u063a \u0641\u0644\u0627\u0634 \u0627\u0632 \u0633\u0642\u0641 \u062e\u0627\u0631\u062c \u0646\u0645\u06cc \u0634\u0648\u062f. \u0628\u0647 \u0633\u0627\u062f\u06af\u06cc \u0634\u06cc\u0644\u062f \u0631\u0627 \u0628\u0647 \u0633\u0627\u06cc\u0628\u0627\u0646 \u0648\u0635\u0644 \u06a9\u0646\u06cc\u062f \u0648 \u0633\u067e\u0633 \u0633\u0627\u06cc\u0647 \u062f\u0631\u0627\u0645 \u0631\u0627 \u067e\u06cc\u0686 \u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u062f\u0631 \u06cc\u06a9 \u0644\u062d\u0638\u0647\u060c \u0686\u0631\u0627\u063a \u0647\u0627 \u0648 \u0627\u062a\u0627\u0642 \u0628\u0647 \u0637\u0631\u0632 \u0686\u0634\u0645\u06af\u06cc\u0631\u06cc \u062a\u063a\u06cc\u06cc\u0631 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0641\u0631\u0622\u06cc\u0646\u062f \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0633\u062a\u060c \u0646\u062a\u06cc\u062c\u0647 \u0646\u0647\u0627\u06cc\u06cc \u0628\u0647 \u0631\u0648\u0632 \u0631\u0633\u0627\u0646\u06cc \u067e\u0627\u06cc\u0647 \u0647\u0627\u06cc \u0641\u0644\u0627\u0634 \u0628\u0627 \u0633\u0627\u06cc\u0647 \u0647\u0627 \u0645\u0634\u0627\u0628\u0647 \u0628\u0647 \u0631\u0648\u0632 \u0631\u0633\u0627\u0646\u06cc \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u0627\u0633\u062a.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D8%A8%D8%A7%D8%B1%D9%87_%D8%B4%DB%8C%D9%84%D8%AF_%D9%87%D8%A7_%D9%88_%D9%BE%D8%B1%D8%AF%D9%87_%D9%87%D8%A7%DB%8C_%D9%85%D8%A7_%D8%A8%DB%8C%D8%B4%D8%AA%D8%B1_%D8%A8%D8%AF%D8%A7%D9%86%DB%8C%D8%AF\"><\/span><strong>\u062f\u0631\u0628\u0627\u0631\u0647 \u0634\u06cc\u0644\u062f \u0647\u0627 \u0648 \u067e\u0631\u062f\u0647 \u0647\u0627\u06cc \u0645\u0627 \u0628\u06cc\u0634\u062a\u0631 \u0628\u062f\u0627\u0646\u06cc\u062f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0634\u06cc\u0644\u062f \u0647\u0627\u06cc \u062f\u0631\u0627\u0645 Glow\u00ae Lighting \u0628\u0647 \u0637\u0648\u0631 \u062e\u0627\u0635 \u0628\u0631\u0627\u06cc \u0645\u0637\u0627\u0628\u0642\u062a \u0628\u0627 \u0633\u06cc\u0633\u062a\u0645 \u0634\u06cc\u0644\u062f \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u0633\u0627\u06cc\u0647 \u0647\u0627\u06cc \u0638\u0631\u06cc\u0641 \u0637\u0628\u0644 organza \u062f\u0648 \u062e\u0637 \u0628\u0627 \u0639\u0631\u0636 15 \u0627\u06cc\u0646\u0686 \u0634\u0631\u0648\u0639 \u0645\u06cc \u0634\u0648\u062f. \u0628\u0631\u0627\u06cc \u0628\u06cc\u0627\u0646 \u0686\u0634\u0645\u06af\u06cc\u0631\u060c \u0633\u0627\u06cc\u0647 \u0647\u0627\u06cc \u0637\u0628\u0644 \u0633\u0641\u0627\u0631\u0634\u06cc \u0628\u0647 \u0639\u0631\u0636 45 \u0627\u06cc\u0646\u0686 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0647\u0633\u062a\u0646\u062f. \u0633\u0627\u06cc\u0647 \u0647\u0627\u06cc \u0631\u0648\u0634\u0646 \u0645\u0627 \u0628\u0647 \u0637\u0648\u0631 \u062e\u0627\u0635 \u0637\u0648\u0631\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0646\u062f \u06a9\u0647 \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0644\u0648\u0633\u062a\u0631\u0647\u0627 \u0648 \u0686\u0631\u0627\u063a \u0647\u0627\u06cc \u0633\u0642\u0641\u06cc \u0628\u0627\u0634\u0646\u062f. \u0647\u0645\u0647 \u0686\u06cc\u0632 \u0631\u0627 \u062f\u0631 \u0645\u0648\u0631\u062f \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u0645\u0627 \u0628\u06cc\u0627\u0645\u0648\u0632\u06cc\u062f. \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0628\u0627 \u0628\u0627\u0632\u06cc\u0627\u0641\u062a \u0644\u0648\u0633\u062a\u0631 \u062e\u0633\u062a\u0647 \u062e\u0648\u062f \u0648 \u062f\u0627\u062f\u0646 \u0632\u0646\u062f\u06af\u06cc \u062a\u0627\u0632\u0647 \u0628\u0647 \u0622\u0646 \u062f\u0648\u0633\u062a\u062f\u0627\u0631 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0646\u06cc\u0632 \u0647\u0633\u062a\u06cc\u062f.<\/p>\n<p>\u062f\u0631 \u062d\u0627\u0644\u062a \u06a9\u0644\u06cc \u062e\u0631\u06cc\u062f \u0634\u06cc\u0644\u062f \u0648 \u0627\u0646\u0648\u0627\u0639 \u0642\u0627\u0628 \u0628\u0631\u0627\u06cc \u0644\u0648\u0633\u062a\u0631 \u0641\u06a9\u0631 \u0639\u0627\u0642\u0644\u0627\u0646\u0647 \u0627\u06cc \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc \u0631\u0633\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0627\u0632 \u0647\u0632\u06cc\u0646\u0647 \u0632\u06cc\u0627\u062f\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0645\u06cc \u0634\u0648\u062f. \u0628\u0627 \u0646\u0635\u0628 \u0634\u06cc\u0644\u062f \u0644\u0648\u0633\u062a\u0631 \u0634\u0645\u0627 \u0638\u0627\u0647\u0631\u06cc \u06a9\u0627\u0645\u0644\u0627 \u062c\u062f\u06cc\u062f \u067e\u06cc\u062f\u0627 \u0645\u06cc \u06a9\u0646\u062f \u0648 \u0628\u0639\u06cc\u062f \u0627\u0633\u062a \u062d\u062a\u06cc \u062e\u0648\u062f\u062a\u0627\u0646 \u0622\u0646 \u0631\u0627 \u062f\u0648\u0628\u0627\u0631\u0647 \u0628\u0634\u0646\u0627\u0633\u06cc\u062f! \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646 \u0647\u0627 \u0646\u0635\u0628 \u0644\u0648\u0633\u062a\u0631 \u062c\u062f\u06cc\u062f \u0648 \u067e\u0627\u06cc\u06cc\u0646 \u0622\u0648\u0631\u062f\u0646 \u0644\u0648\u0633\u062a\u0631 \u0642\u062f\u06cc\u0645\u06cc \u0633\u062e\u062a \u0648 \u062e\u0637\u0631\u0646\u0627\u06a9 \u0627\u0633\u062a \u0648 \u0646\u06cc\u0627\u0632 \u0627\u0633\u062a \u0627\u0632 \u06cc\u06a9 \u062d\u0631\u0641\u0647 \u0627\u06cc \u06a9\u0645\u06a9 \u0628\u06af\u06cc\u0631\u06cc\u062f \u06a9\u0647 \u0622\u0646 \u0647\u0645 \u0647\u0632\u06cc\u0646\u0647 \u0647\u0627\u06cc \u062e\u0648\u062f\u0634 \u0631\u0627 \u062f\u0627\u0631\u062f \u0627\u0645\u0627 \u0646\u0635\u0628 \u0634\u06cc\u0644\u062f \u0647\u0627\u06cc \u062c\u062f\u06cc\u062f \u0647\u06cc\u0686 \u0647\u0632\u06cc\u0646\u0647 \u0627\u06cc \u0646\u062f\u0627\u0631\u062f \u0686\u0631\u0627 \u06a9\u0647 \u062e\u0648\u062f\u062a\u0627\u0646 \u0647\u0645 \u0628\u062f\u0648\u0646 \u067e\u0627\u06cc\u06cc\u0646 \u0622\u0648\u0631\u062f\u0646 \u0644\u0648\u0633\u062a\u0631 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0622\u0646 \u0631\u0627 \u062a\u0646\u0647\u0627 \u0628\u0627 \u06cc\u06a9 \u0646\u0631\u062f\u0628\u0627\u0646 \u0646\u0635\u0628 \u06a9\u0646\u06cc\u062f\u060c \u0686\u0647 \u0686\u06cc\u0632\u06cc \u0628\u0647\u062a\u0631 \u0627\u0632 \u0627\u06cc\u0646\u061f!<\/p>\n<p>\u0645\u0633\u0626\u0644\u0647 \u0628\u0639\u062f\u06cc \u062d\u0641\u0638 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u0633\u062a\u060c \u062f\u0648\u0631 \u0631\u06cc\u062e\u062a\u0646 \u0644\u0648\u0633\u062a\u0631 \u0642\u062f\u06cc\u0645\u06cc \u06cc\u0639\u0646\u06cc \u0632\u0628\u0627\u0644\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0648 \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u062c\u062f\u06cc\u062f \u06cc\u0639\u0646\u06cc \u0647\u0632\u06cc\u0646\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0631\u0627\u06cc \u0633\u0627\u062e\u062a \u0648 \u0631\u062f\u067e\u0627\u06cc \u06a9\u0631\u0628\u0646 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0631 \u0631\u0648\u06cc \u06a9\u0631\u0647 \u0632\u0645\u06cc\u0646\u060c \u0686\u06cc\u0632\u06cc \u06a9\u0647 \u0642\u0637\u0639\u0627 \u0647\u06cc\u0686\u06a9\u062f\u0627\u0645 \u0627\u0632 \u0645\u0627 \u062e\u0648\u0627\u0633\u062a\u0627\u0631 \u0622\u0646 \u0646\u06cc\u0633\u062a\u06cc\u0645. \u062f\u0631 \u0627\u0628\u062a\u062f\u0627 \u06af\u0641\u062a\u06cc\u0645 \u06a9\u0647 \u0646\u062d\u0648\u0647 \u0628\u0647 \u0631\u0648\u0632 \u0631\u0633\u0627\u0646\u06cc \u0644\u0648\u0633\u062a\u0631 \u0628\u0627 \u0634\u06cc\u0644\u062f \u0634\u0627\u06cc\u062f \u0627\u0632 \u0646\u0638\u0631 \u0634\u0645\u0627 \u06cc\u06a9 \u0645\u0639\u062c\u0632\u0647 \u0627\u0633\u062a. \u062a\u063a\u06cc\u06cc\u0631 \u0644\u0648\u0633\u062a\u0631 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u0634\u0645\u0627 \u0628\u0627 \u0633\u0627\u06cc\u0647 \u0647\u0627 \u0628\u0627 \u0633\u06cc\u0633\u062a\u0645 \u0633\u0627\u06cc\u0647 \u0644\u0648\u0633\u062a\u0631 \u0646\u0648\u0622\u0648\u0631\u0627\u0646\u0647 \u0645\u0627 \u06cc\u06a9 \u0636\u0631\u0628\u0647 \u0645\u062d\u06a9\u0645 \u0648 \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u0627\u0633\u062a. \u0627\u0645\u0627 \u062f\u06cc\u062f\u06cc\u062f \u06a9\u0647 \u0686\u0642\u062f\u0631 \u0622\u0633\u0627\u0646 \u0628\u0648\u062f!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34792\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/09\/2052.jpg\" alt=\"\u0644\u0648\u0633\u062a\u0631 \u0634\u06cc\u0644\u062f \u062f\u0627\u0631\" width=\"1400\" height=\"600\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/09\/2052.jpg 1400w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/09\/2052-300x129.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/09\/2052-1024x439.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/09\/2052-768x329.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B3%D8%AE%D9%86_%D9%BE%D8%A7%DB%8C%D8%A7%D9%86%DB%8C_%DA%86%D8%B4%D9%85%D9%87_%D9%86%D9%88%D8%B1\"><\/span><strong>\u0633\u062e\u0646 \u067e\u0627\u06cc\u0627\u0646\u06cc \u0686\u0634\u0645\u0647 \u0646\u0648\u0631<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0633\u06cc\u0633\u062a\u0645 \u0634\u06cc\u0644\u062f \u0686\u0634\u0645\u0647 \u0646\u0648\u0631 \u0633\u0631\u06cc\u0639 \u0648 \u0622\u0633\u0627\u0646 \u0646\u0635\u0628 \u0645\u06cc \u0634\u0648\u062f. \u0627\u0632 \u0647\u0645\u0647 \u0628\u0647\u062a\u0631 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0644\u0627\u0645\u067e \u0634\u0645\u0627 \u0646\u06cc\u0627\u0632\u06cc \u0628\u0647 \u062d\u0630\u0641 \u0627\u0632 \u0633\u0642\u0641 \u0646\u062f\u0627\u0631\u062f. \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0644\u0648\u0627\u0632\u0645 \u062c\u0627\u0646\u0628\u06cc \u0634\u06cc\u0644\u062f \u062f\u0627\u0631 \u062b\u0628\u062a \u0634\u062f\u0647 \u0633\u0627\u062f\u0647 \u0627\u0633\u062a \u0648 \u062f\u0633\u062a\u0648\u0631\u0627\u0644\u0639\u0645\u0644 \u0647\u0627 \u0631\u0627 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u062f\u0646\u0628\u0627\u0644 \u0645\u06cc \u06a9\u0646\u06cc\u062f. \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062a\u0631\u062a\u06cc\u0628\u060c \u0646\u0635\u0628 \u0631\u0627 \u062d\u062a\u06cc \u0633\u0627\u062f\u0647 \u062a\u0631 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<p>\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0627\u06cc\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u06cc\u06a9 \u067e\u0631\u0648\u0698\u0647 DIY \u0628\u0627\u0634\u062f\u060c \u0632\u06cc\u0631\u0627 \u0646\u06cc\u0627\u0632\u06cc \u0628\u0647 \u0628\u0631\u0642 \u0646\u06cc\u0633\u062a. \u0628\u0631\u0627\u06cc \u0646\u0635\u0628\u060c \u062a\u0646\u0647\u0627 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0646\u0631\u062f\u0628\u0627\u0646 \u0627\u0633\u062a. \u0641\u0642\u0637 \u0634\u06cc\u0644\u062f \u0631\u0627 \u0628\u0647 \u0644\u0648\u0633\u062a\u0631 \u062e\u0648\u062f \u0648\u0635\u0644 \u06a9\u0646\u06cc\u062f \u0648 \u0633\u067e\u0633 \u0631\u0648\u06cc \u0634\u06cc\u0644\u062f \u062f\u0631\u0627\u0645 \u0628\u06a9\u0634\u06cc\u062f. \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u0644\u0648\u0633\u062a\u0631 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u062e\u0648\u062f \u0631\u0627 \u062a\u0645\u06cc\u0632 \u0645\u06cc \u06a9\u0646\u06cc\u062f\u060c \u062d\u0630\u0641 \u0622\u0646 \u0634\u06cc\u0644\u062f \u0633\u0627\u062f\u0647 \u0627\u0633\u062a. \u0628\u0627 \u0627\u06cc\u0646 \u06a9\u0647 \u0646\u0635\u0628 \u0628\u0633\u06cc\u0627\u0631 \u0622\u0633\u0627\u0646 \u0627\u0633\u062a \u0627\u0645\u0627 \u0647\u0645\u06cc\u0634\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0631\u0627\u06cc \u06a9\u0645\u06a9 \u0628\u0627 \u0645\u0627 \u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D8%A8%D8%A7%D8%B1%D9%87_%DB%8C_%DA%86%D8%B4%D9%85%D9%87_%D9%86%D9%88%D8%B1\"><\/span>\u062f\u0631\u0628\u0627\u0631\u0647 \u06cc<span style=\"color: #ff0000;\">\u00a0\u0686\u0634\u0645\u0647 \u0646\u0648\u0631<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u06a9\u0645\u067e\u0627\u0646\u06cc\u00a0<a href=\"https:\/\/chenco.ir\/\" target=\"_blank\" rel=\"noopener\">\u0686\u0634\u0645\u0647 \u0646\u0648\u0631<\/a>\u00a0\u0627\u0633\u062a \u0628\u0627 \u0642\u062f\u0645\u062a\u06cc \u06f3\u06f0 \u0633\u0627\u0644\u0647 \u0645\u06cc\u0628\u0627\u0634\u062f \u061b \u0647\u0645\u0647 \u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u062f\u0627\u0631\u0627\u06cc \u06af\u0627\u0631\u0627\u0646\u062a\u06cc \u06f1\u06f2 \u0645\u0627\u0647\u0647 \u0645\u06cc\u0628\u0627\u0634\u0646\u062f\u060c\u00a0 \u0628\u0631\u0627\u06cc \u0645\u0634\u0627\u0647\u062f\u0647 \u06cc \u0622\u0646 \u0647\u0627 \u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647 \u0633\u0627\u06cc\u062a\u00a0<a href=\"https:\/\/decorshop.ir\/product-category\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%da%a9%d8%b1%db%8c%d8%b3%d8%aa%d8%a7%d9%84%db%8c\/\" target=\"_blank\" rel=\"nofollow noopener\">\u062f\u06a9\u0648\u0631\u0634\u0627\u067e<\/a>\u00a0\u0645\u0631\u0627\u062c\u0639\u0647 \u0641\u0631\u0645\u0627\u06cc\u06cc\u062f.<\/p>\n<p>\u0627\u0645\u0631\u0648\u0632\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a\u00a0 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0645\u0634\u063a\u0644\u0647 \u06cc \u06a9\u0627\u0631\u06cc \u0627\u0645\u06a9\u0627\u0646 \u062e\u0631\u06cc\u062f \u062d\u0636\u0648\u0631\u06cc \u0648 \u06cc\u0627 \u062d\u062a\u06cc \u0645\u0634\u0627\u0647\u062f\u0647 \u06cc \u0645\u062f\u0644 \u0647\u0627 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0645\u0634\u06a9\u0644 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f \u061b\u00a0 \u06cc\u06a9\u06cc \u0627\u0632 \u0633\u0627\u06cc\u062a \u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631 \u06a9\u0647 \u0627\u0645\u06a9\u0627\u0646 \u062e\u0631\u06cc\u062f \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc\u00a0 \u0631\u0627 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u060c\u00a0<a href=\"https:\/\/decorshop.ir\/\" target=\"_blank\" rel=\"nofollow noopener\">\u062f\u06a9\u0648\u0631\u0634\u0627\u067e<\/a>\u00a0\u0645\u06cc\u0628\u0627\u0634\u062f .<\/p>\n<p>\u0627\u0644\u0628\u062a\u0647 \u0627\u06cc\u0646<a href=\"https:\/\/chenco.ir\/\" target=\"_blank\" rel=\"noopener\">\u00a0\u0634\u0631\u06a9\u062a<\/a>\u00a0\u0628\u0631\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0634\u0645\u0627 \u060c \u0627\u0645\u06a9\u0627\u0646 \u062e\u0631\u06cc\u062f \u0627\u0642\u0633\u0627\u0637\u06cc \u062d\u062a\u06cc \u0628\u062f\u0648\u0646 \u0636\u0627\u0645\u0646 \u0631\u0627 \u062f\u0631 \u0633\u0627\u06cc\u062a \u0641\u0631\u0627\u0647\u0645 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u0648 \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u062d\u0635\u0648\u0644 \u0628\u0647 \u0645\u0634\u06a9\u0644\u06cc \u0628\u0631\u062e\u0648\u0631\u062f \u06a9\u0631\u062f\u06cc\u062f \u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646 \u0647\u0627\u06cc \u062f\u06a9\u0648\u0631\u0634\u0627\u067e \u0628\u0647 \u0635\u0648\u0631\u062a \u0631\u0627\u06cc\u06af\u0627\u0646 \u0645\u0634\u0627\u0648\u0631\u0647 \u0628\u06af\u06cc\u0631\u06cc\u062f .<\/p>\n<p>\u0628\u0631\u0627\u06cc \u0645\u0634\u0627\u0647\u062f\u0647 \u06cc \u0645\u0642\u0627\u0644\u0627\u062a \u0628\u06cc\u0634\u062a\u0631 \u0628\u0647\u00a0<a href=\"https:\/\/decorshop.ir\/mag\/\" target=\"_blank\" rel=\"nofollow noopener\">\u062f\u06a9\u0648\u0631\u0645\u06af<\/a>\u00a0\u0648\u00a0<a href=\"https:\/\/chenco.ir\/blog\/\" target=\"_blank\" rel=\"noopener\">\u0648\u0628\u0644\u0627\u06af \u0686\u0634\u0645\u0647 \u0646\u0648\u0631<\/a>\u00a0\u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0646\u062d\u0648\u0647 \u0628\u0647 \u0631\u0648\u0632 \u0631\u0633\u0627\u0646\u06cc \u0644\u0648\u0633\u062a\u0631 \u0634\u06cc\u0644\u062f \u062f\u0627\u0631 \u0634\u0627\u06cc\u062f \u0627\u0632 \u0646\u0638\u0631 \u0634\u0645\u0627 \u06cc\u06a9 \u0645\u0639\u062c\u0632\u0647 \u0627\u0633\u062a. \u062a\u063a\u06cc\u06cc\u0631 \u0644\u0648\u0633\u062a\u0631 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u0634\u0645\u0627 \u0628\u0627 \u0633\u0627\u06cc\u0647 \u0647\u0627 \u0628\u0627 \u0633\u06cc\u0633\u062a\u0645 \u0633\u0627\u06cc\u0647 \u0644\u0648\u0633\u062a\u0631 \u0646\u0648\u0622\u0648\u0631\u0627\u0646\u0647 \u0645\u0627 \u06cc\u06a9 \u0636\u0631\u0628\u0647 \u0645\u062d\u06a9\u0645 \u0648 \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0627\u06cc\u062f\u0647 \u0647\u0627\u06cc \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u0627\u062a\u0627\u0642 \u0646\u0627\u0647\u0627\u0631 \u062e\u0648\u0631\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc \u062f\u0647\u062f. \u0645\u0627 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0631\u0648\u0634 \u0647\u0627\u06cc\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0647 \u0631\u0648\u0632 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":34790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[202,35,50,34],"tags":[29,483,484,30,211,482,55],"class_list":["post-34789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-202","category-35","category-50","category-34","tag-luster","tag-483","tag-484","tag-30","tag-211","tag-482","tag-55"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/34789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=34789"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/34789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/34790"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=34789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=34789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=34789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}