{"id":34513,"date":"2021-08-31T12:12:21","date_gmt":"2021-08-31T07:42:21","guid":{"rendered":"https:\/\/decorshop.ir\/mag\/?p=34513"},"modified":"2023-04-27T11:53:31","modified_gmt":"2023-04-27T08:23:31","slug":"%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/","title":{"rendered":"\u0646\u062d\u0648\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u067e\u0630\u06cc\u0631\u0627\u06cc\u06cc"},"content":{"rendered":"<p>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u062f\u0627\u0631\u0627\u06cc \u062a\u0646\u0648\u0639 \u0634\u06af\u0641\u062a \u0627\u0646\u06af\u06cc\u0632\u06cc \u0627\u0632 \u0633\u0628\u06a9 \u0647\u0627 \u0647\u0633\u062a\u0646\u062f \u0648 \u0647\u0645\u0647 \u06a9\u0627\u0631\u0647 \u0647\u0633\u062a\u0646\u062f \u060c \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u062a\u0623\u0645\u06cc\u0646 \u0646\u0648\u0631\u060c \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0637\u0631\u0627\u062d\u06cc \u062f\u0627\u062e\u0644\u06cc \u062e\u0627\u0646\u0647 \u0628\u06cc\u0641\u0632\u0627\u06cc\u0646\u062f \u06cc\u0627 \u0628\u0647 \u06af\u0648\u0634\u0647 \u062e\u0627\u0644\u06cc \u0639\u0644\u0627\u0642\u0647 \u0646\u0634\u0627\u0646 \u062f\u0647\u0646\u062f. \u062d\u062a\u06cc \u0628\u0647\u062a\u0631 \u0627\u0632 \u0627\u06cc\u0646\u060c \u0622\u0646 \u0647\u0627 \u0631\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646 \u062f\u0631 \u0647\u0631 \u0632\u0645\u0627\u0646 \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0627\u0632 \u0627\u062a\u0627\u0642\u06cc \u0628\u0647 \u0627\u062a\u0627\u0642 \u062f\u06cc\u06af\u0631 \u0645\u0646\u062a\u0642\u0644 \u06a9\u0631\u062f.<\/p>\n<p>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0633\u0647 \u0644\u0627\u06cc\u0647 \u06a9\u0644\u06cc \u0646\u0648\u0631 \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc \u062f\u0647\u0646\u062f: \u0645\u062d\u06cc\u0637\u060c \u0648\u0638\u06cc\u0641\u0647 \u0648 \u0645\u062a\u0645\u0631\u06a9\u0632 \u06cc\u0627 \u0647\u0645\u0627\u0646 \u0633\u0627\u06cc\u0647 \u0631\u0648\u0634\u0646.<\/p>\n<p>\u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0645\u062d\u06cc\u0637\u060c \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u06a9\u0644\u06cc \u0631\u0627 \u06a9\u0647 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0645\u0646\u0639\u06a9\u0633 \u06cc\u0627 \u0645\u0646\u062a\u0634\u0631 \u0645\u06cc \u0634\u0648\u062f \u060c \u0628\u0647 \u0627\u062a\u0627\u0642 \u0645\u06cc \u062f\u0647\u062f \u060c\u00a0 \u0645\u0634\u062e\u0635\u0647 \u06a9\u0644\u06cc \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062a\u0645\u0627\u06cc\u0644 \u0628\u0647 \u062a\u0627\u0628\u0627\u0646\u062f\u0646 \u0646\u0648\u0631 \u0628\u0647 \u067e\u0647\u0644\u0648 \u0648 \u0628\u0627\u0644\u0627 \u062f\u0627\u0631\u062f. \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0648\u0638\u06cc\u0641\u0647 \u06cc\u06a9 &#8220;\u0646\u0642\u0637\u0647 \u062f\u0627\u063a&#8221; \u0645\u062a\u0645\u0631\u06a9\u0632 \u0627\u0632 \u0646\u0648\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0646\u0648\u0631 \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0645\u06a9 \u0628\u0647 \u06cc\u06a9 \u06a9\u0627\u0631 \u062e\u0627\u0635 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u0634\u0645\u0627 \u0642\u0631\u0627\u0631 \u0645\u06cc \u062f\u0647\u062f. \u0628\u0647 \u0634\u0645\u0627 \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0645\u06cc \u062f\u0647\u062f \u06a9\u0647 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f \u060c \u0635\u0646\u0627\u06cc\u0639 \u062f\u0633\u062a\u06cc \u0648 \u0645\u0648\u0627\u0631\u062f\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u062f\u0633\u062a \u0631\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u06cc\u062f\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0646\u0648\u0631 \u0631\u0627 \u0628\u0647 \u0633\u0645\u062a \u067e\u0627\u06cc\u06cc\u0646 \u0646\u0634\u0627\u0646 \u0645\u06cc \u062f\u0647\u062f. \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u0645\u062a\u0631\u0645\u0631\u06a9\u0632 \u06cc\u0627 \u0633\u0627\u06cc\u0647 \u0631\u0648\u0634\u0646 \u062a\u0648\u062c\u0647 \u0631\u0627 \u0628\u0647 \u0642\u0633\u0645\u062a\u06cc \u0627\u0632 \u0627\u062a\u0627\u0642 \u06cc\u0627 \u06cc\u06a9 \u0634\u06cc\u0621 \u062e\u0627\u0635 \u062c\u0644\u0628 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-34514 size-full\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1599.jpg\" alt=\"\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647\" width=\"1400\" height=\"600\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1599.jpg 1400w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1599-300x129.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1599-1024x439.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1599-768x329.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%D9%82%D8%A8%D9%84_%D8%A7%D8%B2_%D8%AE%D8%B1%DB%8C%D8%AF_%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%DA%86%D9%87_%DA%86%DB%8C%D8%B2%D9%87%D8%A7%DB%8C%DB%8C_%D8%A8%D8%A7%DB%8C%D8%AF_%D8%A8%D8%AF%D8%A7%D9%86%D9%85%D8%9F\" >\u0642\u0628\u0644 \u0627\u0632 \u062e\u0631\u06cc\u062f \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0686\u0647 \u0686\u06cc\u0632\u0647\u0627\u06cc\u06cc \u0628\u0627\u06cc\u062f \u0628\u062f\u0627\u0646\u0645\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%D8%A8%D8%AF%D8%A7%D9%86%DB%8C%D8%AF_%DA%86%D9%82%D8%AF%D8%B1_%D9%81%D8%B6%D8%A7_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%AF%D8%A7%D8%B1%DB%8C%D8%AF\" >\u0628\u062f\u0627\u0646\u06cc\u062f \u0686\u0642\u062f\u0631 \u0641\u0636\u0627 \u0628\u0631\u0627\u06cc \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u062f\u0627\u0631\u06cc\u062f.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%D8%B3%D8%A8%DA%A9_%D9%87%D8%A7%DB%8C_%D9%85%D8%AE%D8%AA%D9%84%D9%81_%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" >\u0633\u0628\u06a9 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0686\u06cc\u0633\u062a\u061f<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%DA%86%D8%B1%D8%A7%D8%BA_%D8%B3%D9%86%D8%AA%DB%8C\" >\u0686\u0631\u0627\u063a \u0633\u0646\u062a\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%DA%86%D8%B1%D8%A7%D8%BA_%D9%82%D9%81%D8%B3%D9%87\" >\u0686\u0631\u0627\u063a \u0642\u0641\u0633\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D9%82%D9%88%D8%B3_%D8%AF%D8%A7%D8%B1\" >\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0642\u0648\u0633 \u062f\u0627\u0631<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%DA%86%D8%B1%D8%A7%D8%BA_%D9%85%D8%B7%D8%A7%D9%84%D8%B9%D9%87\" >\u0686\u0631\u0627\u063a \u0645\u0637\u0627\u0644\u0639\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%D9%84%D8%A7%D9%85%D9%BE_%D9%85%D9%88%D8%B3%D9%88%D9%85_%D8%A8%D9%87_%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%AF%D8%A7%D8%B1%D9%88%D8%AE%D8%A7%D9%86%D9%87\" >\u0644\u0627\u0645\u067e \u0645\u0648\u0633\u0648\u0645 \u0628\u0647 \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u062f\u0627\u0631\u0648\u062e\u0627\u0646\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%D9%84%D8%A7%D9%85%D9%BE_%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%B3%D9%87_%D9%BE%D8%A7%DB%8C%D9%87\" >\u0644\u0627\u0645\u067e \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0633\u0647 \u067e\u0627\u06cc\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%A8%D8%A7_%D8%B7%D8%B1%D8%AD_%DA%86%D8%B1%D8%A7%D8%BA_%D9%85%D8%B4%D8%B9%D9%84\" >\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u00a0\u0628\u0627 \u0637\u0631\u062d \u0686\u0631\u0627\u063a \u0645\u0634\u0639\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%B7%D8%B1%D8%AD_%D9%84%D9%88%D8%B3%D8%AA%D8%B1\" >\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0637\u0631\u062d \u0644\u0648\u0633\u062a\u0631<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%B7%D8%B1%D8%AD_%D8%AF%D8%B1%D8%AE%D8%AA%DB%8C\" >\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0637\u0631\u062d \u062f\u0631\u062e\u062a\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%A8%D9%87_%DA%86%D9%87_%D9%86%D9%88%D8%B9_%D9%84%D8%A7%D9%85%D9%BE_%D8%A7%D8%AD%D8%AA%DB%8C%D8%A7%D8%AC_%D8%AF%D8%A7%D8%B1%D9%85%D8%9F\" >\u0628\u0631\u0627\u06cc \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0628\u0647 \u0686\u0647 \u0646\u0648\u0639 \u0644\u0627\u0645\u067e \u0627\u062d\u062a\u06cc\u0627\u062c \u062f\u0627\u0631\u0645\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%D8%B1%D8%A7%D9%87%D9%86%D9%85%D8%A7%DB%8C%DB%8C_%D8%B3%D8%B1%DB%8C%D8%B9_%D9%88_%D8%AE%D9%84%D8%A7%D8%B5%D9%87_%DA%A9%D8%A7%D9%85%D9%84_%D9%86%D9%88%D8%B4%D8%AA%D9%87\" >\u0631\u0627\u0647\u0646\u0645\u0627\u06cc\u06cc \u0633\u0631\u06cc\u0639 \u0648 \u062e\u0644\u0627\u0635\u0647 \u06a9\u0627\u0645\u0644 \u0646\u0648\u0634\u062a\u0647<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/decorshop.ir\/mag\/%d9%86%d8%ad%d9%88%d9%87-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8-%d8%a2%d8%a8%d8%a7%da%98%d9%88%d8%b1-%d8%a7%db%8c%d8%b3%d8%aa%d8%a7%d8%af%d9%87-%d9%be%d8%b0%db%8c%d8%b1%d8%a7%db%8c%db%8c\/#%D8%AF%D8%B1%D8%A8%D8%A7%D8%B1%D9%87_%DB%8C_%DA%86%D8%B4%D9%85%D9%87_%D9%86%D9%88%D8%B1\" >\u062f\u0631\u0628\u0627\u0631\u0647 \u06cc\u00a0\u0686\u0634\u0645\u0647 \u0646\u0648\u0631<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"%D9%82%D8%A8%D9%84_%D8%A7%D8%B2_%D8%AE%D8%B1%DB%8C%D8%AF_%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%DA%86%D9%87_%DA%86%DB%8C%D8%B2%D9%87%D8%A7%DB%8C%DB%8C_%D8%A8%D8%A7%DB%8C%D8%AF_%D8%A8%D8%AF%D8%A7%D9%86%D9%85%D8%9F\"><\/span>\u0642\u0628\u0644 \u0627\u0632 \u062e\u0631\u06cc\u062f \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0686\u0647 \u0686\u06cc\u0632\u0647\u0627\u06cc\u06cc \u0628\u0627\u06cc\u062f \u0628\u062f\u0627\u0646\u0645\u061f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0628\u062f\u0627\u0646\u06cc\u062f \u0686\u0631\u0627\u063a \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0634\u0645\u0627 \u0628\u0627\u06cc\u062f \u062a\u0627 \u0686\u0647 \u062d\u062f \u0628\u0644\u0646\u062f \u0628\u0627\u0634\u062f \u061b \u0637\u0648\u0644 \u06cc\u06a9 \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0628\u0647 \u0637\u0648\u0631 \u0645\u062a\u0648\u0633\u0637 \u200b\u200b5 \u062a\u0627 6 \u0641\u0648\u062a (1.5 \u062a\u0627 1.8 \u0645\u062a\u0631) \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f. \u0644\u0627\u0645\u067e\u0647\u0627\u06cc\u06cc \u0628\u0647 \u0627\u0631\u062a\u0641\u0627\u0639 7 \u062a\u0627 8 \u0641\u0648\u062a (2 \u062a\u0627 2.4 \u0645\u062a\u0631) \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f\u060c \u0627\u0645\u0627 \u06cc\u0627\u0641\u062a\u0646 \u0622\u0646 \u0647\u0627 \u062f\u0634\u0648\u0627\u0631\u062a\u0631 \u0627\u0633\u062a \u0648 \u0641\u0642\u0637 \u0628\u0627\u06cc\u062f \u062f\u0631 \u0627\u062a\u0627\u0642 \u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u0648 \u0633\u0642\u0641\u0647\u0627\u06cc \u0628\u0644\u0646\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u0648\u062f. \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0631\u0627 \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f:<\/p>\n<ol>\n<li>\u0627\u0632 \u0642\u0627\u0646\u0648\u0646 \u0633\u0637\u062d \u0686\u0634\u0645 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0642\u0633\u0645\u062a \u067e\u0627\u06cc\u06cc\u0646\u06cc \u0644\u0627\u0645\u067e \u06a9\u0641 \u0628\u0627\u06cc\u062f \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u06cc\u0627 \u06a9\u0645\u06cc \u0632\u06cc\u0631 \u0633\u0637\u062d \u0686\u0634\u0645 \u0627\u0641\u0631\u0627\u062f \u0646\u0634\u0633\u062a\u0647 \u0628\u0627\u0634\u062f \u062a\u0627 \u0627\u0632 \u062a\u0627\u0628\u0634 \u062e\u06cc\u0631\u0647 \u06a9\u0646\u0646\u062f\u0647 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0634\u0648\u062f.<\/li>\n<li>\u0627\u06af\u0631 \u0642\u0635\u062f \u062f\u0627\u0631\u06cc\u062f \u0644\u0627\u0645\u067e \u0631\u0627 \u062f\u0648\u0631\u062a\u0631 \u0627\u0632 \u0645\u062d\u0644 \u0646\u0634\u0633\u062a\u0646 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f\u060c \u0627\u0632 \u0644\u0627\u0645\u067e \u0628\u0644\u0646\u062f\u062a\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0647\u0631\u0686\u0647 \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0628\u0644\u0646\u062f\u062a\u0631 \u0628\u0627\u0634\u062f\u060c \u0645\u0633\u0627\u062d\u062a \u0622\u0646 \u0628\u06cc\u0634\u062a\u0631 \u0631\u0648\u0634\u0646 \u0645\u06cc \u0634\u0648\u062f.<\/li>\n<li>\u0627\u06af\u0631 \u0633\u0642\u0641 \u06a9\u0645 \u0627\u0631\u062a\u0641\u0627\u0639 \u0648 \u06a9\u0648\u062a\u0627\u0647\u06cc \u062f\u0627\u0631\u06cc\u062f\u060c \u06cc\u06a9 \u0644\u0627\u0645\u067e \u0628\u0633\u06cc\u0627\u0631 \u0628\u0644\u0646\u062f \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc \u0631\u0633\u062f \u06a9\u0647 \u0646\u0627\u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a. \u0627\u06af\u0631 \u0633\u0642\u0641 \u0628\u0644\u0646\u062f\u06cc \u062f\u0627\u0631\u06cc\u062f\u060c \u06cc\u06a9 \u0644\u0627\u0645\u067e \u06a9\u0648\u062a\u0627\u0647 \u06af\u0645 \u0634\u062f\u0647 \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc \u0631\u0633\u062f.<\/li>\n<li>\u0627\u06af\u0631 \u0645\u0628\u0644\u0645\u0627\u0646 \u06a9\u0645\u06cc \u062f\u0627\u0631\u06cc\u062f\u060c \u06cc\u06a9 \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0628\u0627 \u0644\u0627\u0645\u067e \u0628\u0632\u0631\u06af\u0634 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0644\u0646\u062f \u0628\u0647 \u0637\u0631\u0632 \u0648\u062d\u0634\u062a\u0646\u0627\u06a9\u06cc \u0628\u06cc \u0645\u062d\u0644 \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc \u0631\u0633\u062f. \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062a\u0631\u062a\u06cc\u0628\u060c \u0645\u0628\u0644\u0645\u0627\u0646 \u0628\u0632\u0631\u06af \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0628\u0631 \u06cc\u06a9 \u0686\u0631\u0627\u063a \u0637\u0628\u0642\u0647 \u06a9\u0648\u0686\u06a9 \u06cc\u0627 \u062f\u0648\u06a9 \u0645\u06cc \u0686\u0631\u0628\u062f.<\/li>\n<li>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0647\u0627\u06cc\u06cc \u0628\u0627 \u0627\u0631\u062a\u0641\u0627\u0639 \u0642\u0627\u0628\u0644 \u062a\u0646\u0638\u06cc\u0645 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u0646\u062f \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0645\u0634\u06a9\u0644 \u0627\u0631\u062a\u0641\u0627\u0639 \u0631\u0627 \u062d\u0644 \u06a9\u0631\u062f\u0647 \u0648 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u06a9\u0646\u0646\u062f \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0644\u0627\u0645\u067e \u062f\u0631 \u0645\u06a9\u0627\u0646 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/li>\n<\/ol>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-34515 size-medium alignleft\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/ML7012-1-e1630394729645-300x300.png\" alt=\"\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647\" width=\"300\" height=\"300\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/ML7012-1-e1630394729645-300x300.png 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/ML7012-1-e1630394729645-150x150.png 150w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/ML7012-1-e1630394729645-768x768.png 768w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/ML7012-1-e1630394729645.png 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A8%D8%AF%D8%A7%D9%86%DB%8C%D8%AF_%DA%86%D9%82%D8%AF%D8%B1_%D9%81%D8%B6%D8%A7_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%AF%D8%A7%D8%B1%DB%8C%D8%AF\"><\/span><strong>\u0628\u062f\u0627\u0646\u06cc\u062f \u0686\u0642\u062f\u0631 \u0641\u0636\u0627 \u0628\u0631\u0627\u06cc <\/strong><strong>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647<\/strong><strong> \u062f\u0627\u0631\u06cc\u062f.<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ol>\n<li>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0647\u0627\u06cc \u0633\u0646\u062a\u06cc \u0648 \u0645\u0634\u0639\u0644 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u062f\u0631 \u062d\u062f\u0627\u0642\u0644 \u0645\u0642\u062f\u0627\u0631 \u0641\u0636\u0627 \u062c\u0627 \u0645\u06cc \u0634\u0648\u0646\u062f.<\/li>\n<li>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0647\u0627\u06cc \u0642\u0648\u0633 \u062f\u0627\u0631 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0627\u0645\u062a\u062f\u0627\u062f \u0627\u0641\u0642\u06cc \u0641\u0636\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0631\u0627 \u0627\u0634\u063a\u0627\u0644 \u0645\u06cc \u06a9\u0646\u0646\u062f.<\/li>\n<li>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0633\u0647 \u067e\u0627\u06cc\u0647 \u0641\u0636\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0631\u0627 \u0627\u0634\u063a\u0627\u0644 \u0645\u06cc \u06a9\u0646\u062f. \u0647\u0631\u06af\u0632 \u0646\u0628\u0627\u06cc\u062f \u0628\u0647 \u0646\u0638\u0631 \u0628\u0631\u0633\u062f \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u06af\u06cc\u0631 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u0648 \u0647\u0631\u06af\u0632 \u0646\u0628\u0627\u06cc\u062f \u062f\u0631 \u0631\u0627\u0647 \u0628\u0627\u0634\u062f.<\/li>\n<\/ol>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B3%D8%A8%DA%A9_%D9%87%D8%A7%DB%8C_%D9%85%D8%AE%D8%AA%D9%84%D9%81_%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span><strong>\u0633\u0628\u06a9 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 <\/strong><strong>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647<\/strong> <strong>\u0686\u06cc\u0633\u062a\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<h4><span class=\"ez-toc-section\" id=\"%DA%86%D8%B1%D8%A7%D8%BA_%D8%B3%D9%86%D8%AA%DB%8C\"><\/span>\u0686\u0631\u0627\u063a \u0633\u0646\u062a\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0686\u0631\u0627\u063a \u0633\u0646\u062a\u06cc \u06a9\u0646\u0633\u0648\u0644 \u0646\u06cc\u0632 \u0646\u0627\u0645\u06cc\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f\u060c \u0686\u0631\u0627\u063a \u0633\u0646\u062a\u06cc \u062f\u0627\u0631\u0627\u06cc \u067e\u0627\u06cc\u0647\u060c \u062a\u06cc\u0631 \u0648 \u0633\u0627\u06cc\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0647\u0645\u0627\u0646 \u0627\u0646\u062f\u0627\u0632\u0647 \u0627\u0633\u0627\u0633\u06cc \u0628\u0627\u0634\u062f\u060c \u06cc\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0627 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0632\u06cc\u0627\u062f \u0647\u0631 \u0639\u0646\u0635\u0631 \u0628\u0647 \u0647\u0645\u0627\u0646 \u0627\u0646\u062f\u0627\u0632\u0647 \u06a9\u0647 \u0645\u06cc \u062e\u0648\u0627\u0647\u06cc\u062f \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0628\u0627\u0634\u062f. \u0633\u0627\u06cc\u0647 \u0647\u0627 \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0647\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0645\u062a\u0641\u0627\u0648\u062a \u0647\u0633\u062a\u0646\u062f \u060c \u0627\u0645\u0627 \u0645\u0646\u0627\u0633\u0628 \u062a\u0631\u06cc\u0646 \u0622\u0646 \u0647\u0627 \u0633\u0627\u06cc\u0647 \u0647\u0627\u06cc \u0627\u0645\u067e\u0631\u0627\u062a\u0648\u0631\u06cc \u0645\u062e\u0631\u0648\u0637\u06cc \u0634\u06a9\u0644 \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0627\u0632 \u0628\u0627\u0644\u0627 \u0628\u0647 \u067e\u0627\u06cc\u06cc\u0646 \u0634\u06cc\u0628 \u062f\u0627\u0631\u0646\u062f \u0648 \u0646\u0648\u0631 \u0631\u0627 \u0628\u0647 \u0633\u0645\u062a \u067e\u0627\u06cc\u06cc\u0646 \u0645\u06cc \u0627\u0646\u062f\u0627\u0632\u0646\u062f. \u0644\u0627\u0645\u067e \u0633\u0646\u062a\u06cc \u0628\u0627 \u0627\u06a9\u062b\u0631 \u062f\u06a9\u0648\u0631\u0647\u0627 \u06a9\u0627\u0631 \u0645\u06cc \u06a9\u0646\u062f\u060c \u0628\u0647 \u062c\u0632 \u0633\u0628\u06a9 \u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u06cc\u0627 \u0647\u0631 \u0633\u0628\u06a9 \u0645\u06cc\u0646\u06cc\u0645\u0627\u0644\u06cc\u0633\u062a\u06cc. \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0645\u062d\u06cc\u0637 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%DA%86%D8%B1%D8%A7%D8%BA_%D9%82%D9%81%D8%B3%D9%87\"><\/span>\u0686\u0631\u0627\u063a \u0642\u0641\u0633\u0647<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0686\u0631\u0627\u063a \u0637\u0628\u0642\u0647 \u0642\u0641\u0633\u0647 \u06cc\u06a9 \u0644\u0627\u0645\u067e \u0633\u0646\u062a\u06cc \u0628\u0627 \u0642\u0641\u0633\u0647 \u0627\u06cc \u062f\u0631 \u0642\u0633\u0645\u062a \u0645\u06cc\u0627\u0646\u06cc \u0642\u0637\u0628 \u0627\u0633\u062a. \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u0644\u0627\u0645\u067e \u0642\u0641\u0633\u0647 \u06a9\u0646\u0627\u0631 \u0635\u0646\u062f\u0644\u06cc \u0642\u0631\u0627\u0631 \u0645\u06cc \u06af\u06cc\u0631\u062f\u060c \u06cc\u06a9 \u0645\u06cc\u0632 \u0627\u0646\u062a\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u06a9\u062a\u0627\u0628 \u0647\u0627\u060c \u0645\u062c\u0644\u0627\u062a\u060c \u0639\u06cc\u0646\u06a9 \u06cc\u0627 \u06a9\u0644\u06cc\u062f\u0647\u0627\u06cc \u0634\u0645\u0627 \u0631\u0627 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0646\u06af\u0647 \u0645\u06cc \u062f\u0627\u0631\u062f. \u0628\u0631\u062e\u06cc \u0627\u0632 \u0642\u0641\u0633\u0647 \u0647\u0627 \u0645\u062c\u0647\u0632 \u0628\u0647 \u0627\u062a\u0635\u0627\u0644\u0627\u062a USB \u0647\u0633\u062a\u0646\u062f \u062a\u0627 \u0634\u0645\u0627 \u06cc\u06a9 \u0627\u06cc\u0633\u062a\u06af\u0627\u0647 \u0634\u0627\u0631\u0698 \u0644\u0648\u0627\u0632\u0645 \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u06cc \u062e\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f. \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0645\u062d\u06cc\u0637 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D9%82%D9%88%D8%B3_%D8%AF%D8%A7%D8%B1\"><\/span>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0642\u0648\u0633 \u062f\u0627\u0631<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0686\u0631\u0627\u063a \u06a9\u0641 \u0642\u0648\u0633\u06cc \u0628\u0627 \u0637\u0631\u0627\u062d\u06cc \u0645\u0646\u062d\u0646\u06cc \u0641\u0631\u0627\u06af\u06cc\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0631\u0633\u0648\u0645 \u0627\u0633\u062a. \u0642\u0637\u0628 \u0642\u0648\u0633 \u0628\u0627\u0644\u0627 \u0645\u06cc \u0631\u0648\u062f\u060c \u0642\u0648\u0633 \u0645\u06cc \u06af\u06cc\u0631\u062f \u0648 \u0628\u0647 \u0639\u0642\u0628 \u062e\u0645 \u0645\u06cc \u0634\u0648\u062f. \u062f\u0631 \u0645\u062d\u06cc\u0637 \u0645\u0639\u0627\u0635\u0631 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u0627\u0631 \u0631\u0627 \u0645\u06cc \u06a9\u0646\u062f \u0627\u0645\u0627 \u062c\u0644\u0648\u0647 \u0627\u06cc \u062c\u0630\u0627\u0628 \u0628\u0647 \u0647\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646\u06cc \u0645\u06cc \u0628\u062e\u0634\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a \u0646\u06cc\u0627\u0632 \u0642\u0648\u0633 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u06a9\u0627\u0631 \u062a\u0646\u0638\u06cc\u0645 \u06a9\u0646\u06cc\u062f. \u06cc\u0627 \u0622\u0646 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0645\u062d\u06cc\u0637 \u062f\u0631 \u0641\u0636\u0627\u06cc\u06cc \u0628\u0627 \u0646\u0634\u06cc\u0645\u0646 \u0645\u06a9\u0627\u0644\u0645\u0647 \u06cc\u0627 \u0631\u0648\u06cc \u0645\u06cc\u0632 \u0646\u0627\u0647\u0627\u0631 \u062e\u0648\u0631\u06cc \u067e\u062e\u0634 \u06a9\u0646\u06cc\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-34516 size-full\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1600.jpg\" alt=\"\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u062e\u0645\u06cc\u062f\u0647\" width=\"1400\" height=\"600\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1600.jpg 1400w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1600-300x129.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1600-1024x439.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1600-768x329.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<h4><span class=\"ez-toc-section\" id=\"%DA%86%D8%B1%D8%A7%D8%BA_%D9%85%D8%B7%D8%A7%D9%84%D8%B9%D9%87\"><\/span>\u0686\u0631\u0627\u063a \u0645\u0637\u0627\u0644\u0639\u0647<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0686\u0631\u0627\u063a \u0637\u0628\u0642\u0647 \u0645\u0637\u0627\u0644\u0639\u0647 \u062f\u0627\u0631\u0627\u06cc \u0633\u0627\u06cc\u0647 \u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u06a9\u062c \u0645\u06cc \u0634\u0648\u062f \u0648 \u0628\u0627\u0632\u0648\u06cc \u0627\u0646\u0639\u0637\u0627\u0641 \u067e\u0630\u06cc\u0631 \u062f\u0627\u0631\u062f \u0628\u0647 \u0637\u0648\u0631\u06cc \u06a9\u0647\u060c \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644\u060c \u0646\u0648\u0631 \u0628\u0631 \u0631\u0648\u06cc \u0634\u0627\u0646\u0647 \u0634\u0645\u0627 \u0645\u06cc \u062a\u0627\u0628\u062f. \u0628\u0631\u062e\u06cc \u0627\u0632 \u0644\u0627\u0645\u067e \u0647\u0627 \u0628\u0631\u0627\u06cc \u0627\u0631\u062a\u0641\u0627\u0639 \u062a\u0646\u0638\u06cc\u0645 \u0645\u06cc \u0634\u0648\u0646\u062f. \u0628\u0631\u062e\u06cc \u0628\u0647 \u0634\u0645\u0627 \u0627\u0645\u06a9\u0627\u0646 \u0645\u06cc \u062f\u0647\u0646\u062f \u062a\u0646\u0638\u06cc\u0645 \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0631\u0627 \u062a\u0646\u0638\u06cc\u0645 \u06a9\u0646\u06cc\u062f. \u0686\u0631\u0627\u063a \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\u060c \u0646\u0648\u0634\u062a\u0646\u060c \u06cc\u0627 \u0633\u0648\u0632\u0646 \u062f\u0648\u0632\u06cc \u06cc\u0627 \u0631\u0648\u0634\u0646 \u06a9\u0631\u062f\u0646 \u06cc\u06a9 \u0645\u06cc\u0632 \u0628\u0627\u0632\u06cc \u062f\u0631\u0633\u062a \u062f\u0631 \u062c\u0627\u06cc\u06cc \u0645\u062a\u0645\u0631\u06a9\u0632 \u0645\u06cc \u0634\u0648\u062f. \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0648\u0638\u06cc\u0641\u0647 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D9%84%D8%A7%D9%85%D9%BE_%D9%85%D9%88%D8%B3%D9%88%D9%85_%D8%A8%D9%87_%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%AF%D8%A7%D8%B1%D9%88%D8%AE%D8%A7%D9%86%D9%87\"><\/span>\u0644\u0627\u0645\u067e \u0645\u0648\u0633\u0648\u0645 \u0628\u0647 \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u062f\u0627\u0631\u0648\u062e\u0627\u0646\u0647<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u062f\u0627\u0631\u0648\u062e\u0627\u0646\u0647 \u0646\u0633\u062e\u0647 \u06a9\u0648\u062a\u0627\u0647\u062a\u0631\u06cc \u0627\u0632 \u0686\u0631\u0627\u063a \u0645\u0637\u0627\u0644\u0639\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u062a\u06cc\u0631 \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u0686\u0647\u0627\u0631 \u062a\u0627 \u067e\u0646\u062c \u0641\u0648\u062a \u0627\u0631\u062a\u0641\u0627\u0639 \u062f\u0627\u0631\u062f\u060c \u0633\u067e\u0633 \u0628\u0647 \u06cc\u06a9 \u06cc\u0627 \u062f\u0648 \u0628\u0627\u0632\u0648 \u062a\u0628\u062f\u06cc\u0644 \u0645\u06cc \u0634\u0648\u062f \u06a9\u0647 \u0628\u0633\u062a\u0647 \u0628\u0647 \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u06cc \u062e\u0648\u0627\u0647\u06cc\u062f \u0646\u0648\u0631 \u0647\u062f\u0627\u06cc\u062a \u0634\u0648\u062f\u060c \u0686\u0631\u062e\u0627\u0646\u062f\u0647 \u0648 \u0628\u0647 \u0628\u06cc\u0631\u0648\u0646 \u062d\u0631\u06a9\u062a \u0645\u06cc \u06a9\u0646\u062f \u0648 \u0633\u067e\u0633 \u062f\u0631 \u0635\u0648\u0631\u062a \u0639\u062f\u0645 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0633\u06cc\u0631 \u062e\u0627\u0631\u062c \u0645\u06cc \u0634\u0648\u062f. \u0686\u0631\u0627\u063a \u0647\u0627\u06cc \u062f\u0627\u0631\u0648\u062e\u0627\u0646\u0647 \u0628\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u062f\u0641\u0639\u0627\u062a \u0642\u0628\u0644\u06cc \u062f\u06cc\u062f\u0647 \u0646\u0645\u06cc \u0634\u0648\u0646\u062f \u060c \u0627\u0645\u0627 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0635\u0646\u062f\u0644\u06cc \u06cc\u0627 \u0645\u06cc\u0632 \u06cc\u06a9 \u062a\u0645\u0627\u0633 \u0639\u062c\u06cc\u0628 \u0648 \u06cc\u06a9\u067e\u0627\u0631\u0686\u0647 \u0633\u0627\u0632\u06cc \u0628\u0627 \u0633\u06cc\u0633\u062a\u0645 \u0639\u0627\u0645\u0644 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc \u06a9\u0646\u062f. \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0648\u0638\u06cc\u0641\u0647 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D9%84%D8%A7%D9%85%D9%BE_%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%B3%D9%87_%D9%BE%D8%A7%DB%8C%D9%87\"><\/span>\u0644\u0627\u0645\u067e \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0633\u0647 \u067e\u0627\u06cc\u0647<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0633\u0647 \u067e\u0627\u06cc\u0647 \u0647\u0645 \u0633\u0628\u06a9 \u0648 \u0647\u0645 \u0639\u0645\u0644\u06a9\u0631\u062f \u0631\u0627 \u0628\u0647 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0627\u0648\u0627\u0633\u0637 \u0642\u0631\u0646 \u0645\u06cc \u0627\u0641\u0632\u0627\u06cc\u062f. \u0633\u0647 \u067e\u0627\u06cc\u0647 \u0628\u0647 \u0637\u0648\u0631 \u0645\u0633\u062a\u0642\u0644 \u0628\u0627\u0644\u0627 \u0645\u06cc \u0622\u06cc\u0646\u062f \u0648 \u062f\u0631 \u0633\u0631 \u0644\u0627\u0645\u067e \u06cc\u0627 \u06a9\u0645\u06cc \u0642\u0628\u0644 \u0627\u0632 \u0622\u0646 \u0642\u0637\u0639 \u0645\u06cc \u0634\u0648\u0646\u062f\u060c \u06a9\u0647 \u0628\u0627 \u0622\u0628\u0627\u0698\u0648\u0631 \u0637\u0628\u0644 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0638\u0627\u0647\u0631 \u0631\u0627 \u062f\u0627\u0631\u062f. \u0628\u0631\u062e\u06cc \u0627\u0632 \u0644\u0627\u0645\u067e \u0647\u0627 \u062f\u0627\u0631\u0627\u06cc \u067e\u0627\u0647\u0627\u06cc \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0627\u0631\u062a\u0641\u0627\u0639 \u0647\u0633\u062a\u0646\u062f. \u0628\u0631\u062e\u06cc \u062f\u0627\u0631\u0627\u06cc \u0633\u0631 \u0686\u0631\u0627\u063a \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062f\u0631 \u062c\u0647\u062a \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u0634\u0645\u0627 \u0645\u06cc \u0686\u0631\u062e\u062f. \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0645\u062d\u06cc\u0637 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%A8%D8%A7_%D8%B7%D8%B1%D8%AD_%DA%86%D8%B1%D8%A7%D8%BA_%D9%85%D8%B4%D8%B9%D9%84\"><\/span>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u00a0\u0628\u0627 \u0637\u0631\u062d \u0686\u0631\u0627\u063a \u0645\u0634\u0639\u0644<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0686\u0631\u0627\u063a \u0637\u0628\u0642\u0647 \u0645\u0634\u0639\u0644 \u0634\u0628\u0627\u0647\u062a \u0628\u0647 \u0645\u0634\u0639\u0644 \u062f\u0627\u0631\u062f \u0632\u06cc\u0631\u0627 \u0646\u0648\u0631 \u0628\u0647 \u0633\u0645\u062a \u0628\u0627\u0644\u0627 \u0628\u0647 \u0633\u0645\u062a \u0633\u0642\u0641 \u0647\u062f\u0627\u06cc\u062a \u0645\u06cc \u0634\u0648\u062f. \u0628\u0647 \u0637\u0648\u0631 \u0645\u0639\u0645\u0648\u0644 \u060c \u0633\u0627\u06cc\u0647 \u0627\u06cc \u0628\u0647 \u0634\u06a9\u0644 \u06a9\u0627\u0633\u0647 \u0628\u062e\u0634\u06cc \u0627\u0632 \u0644\u0627\u0645\u067e \u0627\u0633\u062a. \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u0646\u0648\u0631 \u0627\u0632 \u0633\u0642\u0641 \u0645\u0646\u0639\u06a9\u0633 \u0645\u06cc \u0634\u0648\u062f\u060c \u0628\u0647 \u0648\u06cc\u0698\u0647 \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u062f\u0631 \u06af\u0648\u0634\u0647 \u0627\u06cc \u0627\u0632 \u0627\u062a\u0627\u0642 \u0642\u0631\u0627\u0631 \u0645\u06cc \u06af\u06cc\u0631\u062f\u060c \u0646\u0648\u0631 \u0645\u062d\u06cc\u0637 \u0628\u0647 \u0622\u0631\u0627\u0645\u06cc \u06a9\u0644 \u0645\u0646\u0637\u0642\u0647 \u0631\u0627 \u0631\u0648\u0634\u0646 \u0645\u06cc \u06a9\u0646\u062f. \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u0628\u0647 \u06cc\u06a9 \u0639\u0646\u0635\u0631 \u0645\u0627\u0646\u0646\u062f \u0634\u0648\u0645\u06cc\u0646\u0647 \u06cc\u0627 \u06cc\u06a9 \u0634\u06cc\u0621 \u0645\u0648\u0631\u062f \u0639\u0644\u0627\u0642\u0647 \u0645\u0627\u0646\u0646\u062f \u0646\u0642\u0627\u0634\u06cc \u06cc\u0627 \u0645\u062c\u0633\u0645\u0647 \u0647\u062f\u0627\u06cc\u062a \u0645\u06cc \u0634\u0648\u062f\u060c \u0645\u06cc \u062a\u0648\u0627\u0646 \u0627\u0632 \u0686\u0631\u0627\u063a \u0645\u0634\u0639\u0644 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0644\u0647\u062c\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%B7%D8%B1%D8%AD_%D9%84%D9%88%D8%B3%D8%AA%D8%B1\"><\/span>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0637\u0631\u062d \u0644\u0648\u0633\u062a\u0631<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0686\u0631\u0627\u063a \u0637\u0628\u0642\u0647 \u0644\u0648\u0633\u062a\u0631 \u0628\u0633\u06cc\u0627\u0631 \u063a\u06cc\u0631 \u0645\u0639\u0645\u0648\u0644 \u0648 \u0628\u0633\u06cc\u0627\u0631 \u062a\u0632\u0626\u06cc\u0646\u06cc \u0627\u0633\u062a. \u0627\u06cc\u0646 \u067e\u0627\u06cc\u0647 \u0645\u0627\u0646\u0646\u062f \u06cc\u06a9 \u0686\u0631\u0627\u063a \u0633\u0646\u062a\u06cc \u0627\u0633\u062a\u060c \u0627\u0645\u0627 \u062a\u06cc\u0631 \u0628\u0627 \u06cc\u06a9 \u0644\u0648\u0633\u062a\u0631 \u0628\u0647 \u067e\u0627\u06cc\u0627\u0646 \u0645\u06cc \u0631\u0633\u062f: \u0686\u0646\u062f\u06cc\u0646 \u0628\u0627\u0632\u0648 \u062f\u0631\u0627\u0632 \u0645\u06cc \u0634\u0648\u0646\u062f\u060c \u0686\u0631\u0627\u063a \u0647\u0627\u06cc\u06cc \u062f\u0631 \u0627\u0646\u062a\u0647\u0627\u06cc \u0622\u0646\u0647\u0627 \u0648 \u0647\u0631 \u062a\u0639\u062f\u0627\u062f \u062a\u0632\u0626\u06cc\u0646\u0627\u062a\u060c \u0645\u0627\u0646\u0646\u062f \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644 \u06cc\u0627 \u0645\u0631\u0648\u0627\u0631\u06cc\u062f\u060c \u0627\u0632 \u0628\u0627\u0632\u0648\u0647\u0627 \u0622\u0648\u06cc\u0632\u0627\u0646 \u0627\u0633\u062a. \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0645\u062d\u06cc\u0637 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<p>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0637\u0631\u062d \u0686\u0631\u0627\u063a \u0647\u0634\u062a \u067e\u0627<\/p>\n<p>\u0686\u0631\u0627\u063a \u06a9\u0641 \u0647\u0634\u062a \u067e\u0627 (\u0645\u0639\u0631\u0648\u0641 \u0628\u0647 \u0686\u0631\u0627\u063a \u0639\u0646\u06a9\u0628\u0648\u062a\u060c \u0686\u0631\u0627\u063a \u0686\u0646\u062f \u0628\u0627\u0632\u0648\u06cc\u06cc) \u0633\u0631\u06af\u0631\u0645 \u06a9\u0646\u0646\u062f\u0647 \u0648 \u062a\u0632\u0626\u06cc\u0646\u06cc \u0627\u0633\u062a. \u062f\u0627\u0631\u0627\u06cc \u0633\u0647 \u06cc\u0627 \u067e\u0646\u062c \u0628\u0627\u0632\u0648 \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u062f\u0631 \u0647\u0631 \u062c\u0647\u062a \u0628\u0686\u0631\u062e\u0627\u0646\u06cc\u062f \u0648 \u0627\u0632 \u0622\u0646\u0647\u0627 \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u062c\u0644\u0648\u0647 \u0647\u0627\u06cc \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u0646\u06cc \u0628\u0627 \u0646\u0648\u0631 \u0648 \u0633\u0627\u06cc\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0647\u0631 \u0628\u0627\u0632\u0648 \u062f\u0627\u0631\u0627\u06cc \u0633\u0627\u06cc\u0647 \u0627\u06cc \u06a9\u0648\u0686\u06a9 \u0648 \u0631\u0646\u06af\u06cc \u0627\u0633\u062a \u06a9\u0647 \u06cc\u06a9 \u0644\u0627\u0645\u067e \u06a9\u0645 \u062a\u0648\u0627\u0646 \u0631\u0627 \u067e\u0648\u0634\u0634 \u0645\u06cc \u062f\u0647\u062f. \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0645\u062d\u06cc\u0637 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%B7%D8%B1%D8%AD_%D8%AF%D8%B1%D8%AE%D8%AA%DB%8C\"><\/span>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0637\u0631\u062d \u062f\u0631\u062e\u062a\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0686\u0631\u0627\u063a \u06a9\u0641 \u062f\u0631\u062e\u062a \u062f\u0627\u0631\u0627\u06cc \u0633\u0647 \u0628\u0627\u0632\u0648 (\u06cc\u0627 \u0634\u0627\u062e\u0647) \u0648 \u062d\u0641\u0631\u0647 (\u0628\u0631\u06af) \u062f\u0631 \u0627\u0631\u062a\u0641\u0627\u0639\u0627\u062a \u0645\u062e\u062a\u0644\u0641 \u0648 \u062f\u0631 \u062c\u0647\u0627\u062a \u0645\u062e\u062a\u0644\u0641 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a. \u0647\u0631 \u0633\u0648\u06a9\u062a \u0628\u0647 \u0637\u0648\u0631 \u0645\u0633\u062a\u0642\u0644 \u06a9\u0627\u0631 \u0645\u06cc \u06a9\u0646\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u06cc\u06a9\u060c \u062f\u0648 \u06cc\u0627 \u0647\u0645\u0647 \u0644\u0627\u0645\u067e \u0647\u0627 \u0631\u0627 \u0631\u0648\u0634\u0646 \u06a9\u0646\u06cc\u062f. \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0645\u062d\u06cc\u0637 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u06a9\u0646\u062f\u060c \u0627\u0645\u0627 \u0641\u0642\u0637 \u062f\u0631 \u0645\u06a9\u0627\u0646 \u06a9\u0644\u06cc \u0622\u0646.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-34517 size-full\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1601.jpg\" alt=\"\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u062f\u0631\u062e\u062a\u06cc\" width=\"1400\" height=\"600\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1601.jpg 1400w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1601-300x129.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1601-1024x439.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/08\/1601-768x329.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A2%D8%A8%D8%A7%DA%98%D9%88%D8%B1_%D8%A7%DB%8C%D8%B3%D8%AA%D8%A7%D8%AF%D9%87_%D8%A8%D9%87_%DA%86%D9%87_%D9%86%D9%88%D8%B9_%D9%84%D8%A7%D9%85%D9%BE_%D8%A7%D8%AD%D8%AA%DB%8C%D8%A7%D8%AC_%D8%AF%D8%A7%D8%B1%D9%85%D8%9F\"><\/span><strong>\u0628\u0631\u0627\u06cc <\/strong><strong>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647<\/strong> <strong>\u0628\u0647 \u0686\u0647 \u0646\u0648\u0639 \u0644\u0627\u0645\u067e \u0627\u062d\u062a\u06cc\u0627\u062c \u062f\u0627\u0631\u0645\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0631\u0634\u062a\u0647 \u0627\u06cc<\/p>\n<p>\u0627\u06cc\u0646\u0647\u0627 \u0644\u0627\u0645\u067e \u0647\u0627\u06cc\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0645\u0627 \u0628\u0631\u0627\u06cc \u0647\u0645\u06cc\u0634\u0647 \u0627\u0632 \u0622\u0646 \u0647\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f\u0647 \u0627\u06cc\u0645. \u062f\u0627\u062e\u0644 \u0644\u0627\u0645\u067e \u0631\u0634\u062a\u0647 \u0631\u0634\u062a\u0647 \u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0627\u063a \u0645\u06cc \u0634\u0648\u062f \u0648 \u0645\u06cc \u062f\u0631\u062e\u0634\u062f. \u0622\u0646\u0647\u0627 \u062f\u0631 \u0637\u06cc\u0641 \u06af\u0633\u062a\u0631\u062f\u0647 \u0627\u06cc \u0627\u0632 \u0627\u0646\u062f\u0627\u0632\u0647 \u0647\u0627 \u0648 \u062f\u0631\u062c\u0647 \u0648\u0644\u062a\u0627\u0698 \u0647\u0633\u062a\u0646\u062f \u0648 \u0646\u0633\u0628\u062a \u0628\u0647 \u0633\u0627\u06cc\u0631 \u0644\u0627\u0645\u067e \u0647\u0627 \u0627\u0631\u0632\u0627\u0646 \u062a\u0631 \u0647\u0633\u062a\u0646\u062f. \u0627\u0645\u0627 \u0622\u0646 \u0647\u0627 \u0647\u0645\u0686\u0646\u06cc\u0646 \u06a9\u0627\u0631\u0622\u06cc\u06cc \u06a9\u0645\u062a\u0631\u06cc \u062f\u0627\u0631\u0646\u062f \u0648 \u0641\u0642\u0637 \u062d\u062f\u0648\u062f 1000 \u0633\u0627\u0639\u062a \u062f\u0648\u0627\u0645 \u0645\u06cc \u0622\u0648\u0631\u0646\u062f. \u0622\u0646\u0647\u0627 \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u0635\u0631\u0641\u0647 \u062c\u0648\u06cc\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc \u062d\u0630\u0641 \u0645\u06cc \u0634\u0648\u0646\u062f \u0648 \u0646\u0627\u06a9\u0627\u0631\u0622\u0645\u062f \u062e\u0648\u0627\u0647\u0646\u062f \u0628\u0648\u062f.<\/p>\n<p>\u0644\u0627\u0645\u067e \u0647\u0627\u06cc \u0641\u0634\u0631\u062f\u0647 (CFL)<\/p>\n<p>CFL \u0647\u0627 \u0627\u0632 \u06cc\u06a9 \u0686\u0647\u0627\u0631\u0645 \u0627\u0646\u0631\u0698\u06cc \u0644\u0627\u0645\u067e \u0647\u0627\u06cc \u0631\u0634\u062a\u0647 \u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u06a9\u0646\u0646\u062f \u0648 \u0639\u0645\u0631 \u0622\u0646\u0647\u0627 10 \u0628\u0631\u0627\u0628\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0633\u062a. \u0622\u0646\u0647\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u062f\u0631 \u0647\u0631 \u0645\u06a9\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0632 \u0644\u0627\u0645\u067e \u0631\u0634\u062a\u0647 \u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u06a9\u0646\u06cc\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u0648\u0646\u062f. CFL \u0647\u0627 \u062d\u0627\u0648\u06cc \u0645\u0642\u0627\u062f\u06cc\u0631 \u06a9\u0645\u06cc \u062c\u06cc\u0648\u0647 \u0647\u0633\u062a\u0646\u062f \u0648 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0645\u0631\u0627\u0642\u0628\u062a \u062f\u0642\u06cc\u0642 \u062f\u0627\u0631\u0646\u062f. \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u0622\u0646 \u0647\u0627 \u0645\u06cc \u0633\u0648\u0632\u0646\u062f \u0628\u0627\u0632\u06cc\u0627\u0641\u062a \u06a9\u0646\u06cc\u062f.<\/p>\n<p>LED \u0647\u0627 (\u062f\u06cc\u0648\u062f\u0647\u0627\u06cc \u0633\u0627\u0637\u0639 \u06a9\u0646\u0646\u062f\u0647 \u0646\u0648\u0631)<\/p>\n<p>LED \u0647\u0627 \u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631 \u0634\u0628\u06cc\u0647 \u0644\u0627\u0645\u067e \u0647\u0627\u06cc \u0631\u0634\u062a\u0647 \u0627\u06cc \u0647\u0633\u062a\u0646\u062f\u060c \u0627\u0645\u0627 \u0628\u0631\u0627\u06cc \u0644\u0645\u0633 \u0622\u0646\u0647\u0627 \u062e\u06cc\u0644\u06cc \u06af\u0631\u0645 \u0646\u0645\u06cc \u0634\u0648\u062f. \u0622\u0646\u0647\u0627 \u0628\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 CFL \u0647\u0627 \u06a9\u0627\u0631\u0622\u0645\u062f \u0647\u0633\u062a\u0646\u062f \u060c \u0627\u0645\u0627 \u062a\u0627 \u0633\u0647 \u0628\u0631\u0627\u0628\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0639\u0645\u0631 \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0622\u0646\u0647\u0627 \u06af\u0631\u0627\u0646 \u062a\u0631 \u0647\u0633\u062a\u0646\u062f\u060c \u0627\u0645\u0627 \u0628\u0631\u062e\u06cc \u0645\u0646\u0627\u0637\u0642 \u062a\u062e\u0641\u06cc\u0641 \u062e\u062f\u0645\u0627\u062a \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc \u062f\u0647\u0646\u062f. \u062f\u0631 \u06a9\u0644 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0647\u0633\u062a\u0646\u062f\u060c \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0645\u0635\u0631\u0641 \u0628\u0633\u06cc\u0627\u0631 \u067e\u0627\u06cc\u06cc\u0646 \u0627\u0646\u0631\u0698\u06cc \u0648 \u0628\u0627\u0632\u062f\u0647\u06cc \u0628\u0627\u0644\u0627.<\/p>\n<p>\u0647\u0627\u0644\u0648\u0698\u0646<\/p>\n<p>\u0644\u0627\u0645\u067e \u0647\u0627\u06cc \u0647\u0627\u0644\u0648\u0698\u0646 \u0646\u0648\u0631\u06cc \u0631\u0627 \u0628\u06cc\u0634\u062a\u0631 \u0634\u0628\u06cc\u0647 \u0628\u0647 \u0646\u0648\u0631 \u0637\u0628\u06cc\u0639\u06cc \u0631\u0648\u0632 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc \u062f\u0647\u0646\u062f. \u0631\u0646\u06af \u0647\u0627 \u0648\u0627\u0636\u062d \u062a\u0631 \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc \u0631\u0633\u0646\u062f \u0648 \u0622\u0646 \u0647\u0627 \u0631\u0627 \u0628\u0647 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0631\u0627\u06cc \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u06a9\u0627\u0631 \u062a\u0628\u062f\u06cc\u0644 \u0645\u06cc \u06a9\u0646\u062f. \u0622\u0646\u0647\u0627 10 \u062a\u0627 20 \u062f\u0631\u0635\u062f \u0627\u0646\u0631\u0698\u06cc \u06a9\u0645\u062a\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0644\u0627\u0645\u067e \u0631\u0634\u062a\u0647 \u0627\u06cc \u0645\u0635\u0631\u0641 \u0645\u06cc \u06a9\u0646\u0646\u062f \u0648 \u06af\u0631\u0627\u0646 \u062a\u0631 \u0647\u0633\u062a\u0646\u062f. \u0646\u06af\u0631\u0627\u0646\u06cc \u0627\u0635\u0644\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0647\u0631\u06af\u0632 \u0644\u0627\u0645\u067e \u0631\u0627 \u0628\u0627 \u062f\u0633\u062a \u0628\u0631\u0647\u0646\u0647 \u0644\u0645\u0633 \u0646\u06a9\u0646\u06cc\u062f. \u06a9\u0645\u062a\u0631\u06cc\u0646 \u0645\u0642\u062f\u0627\u0631 \u0631\u0648\u063a\u0646 \u0627\u0632 \u062f\u0633\u062a \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0645\u0646\u062c\u0631 \u0628\u0647 \u0627\u0646\u0641\u062c\u0627\u0631 \u0644\u0627\u0645\u067e \u0647\u0646\u06af\u0627\u0645 \u0631\u0648\u0634\u0646 \u0634\u062f\u0646 \u0634\u0648\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B1%D8%A7%D9%87%D9%86%D9%85%D8%A7%DB%8C%DB%8C_%D8%B3%D8%B1%DB%8C%D8%B9_%D9%88_%D8%AE%D9%84%D8%A7%D8%B5%D9%87_%DA%A9%D8%A7%D9%85%D9%84_%D9%86%D9%88%D8%B4%D8%AA%D9%87\"><\/span><strong>\u0631\u0627\u0647\u0646\u0645\u0627\u06cc\u06cc \u0633\u0631\u06cc\u0639 \u0648 \u062e\u0644\u0627\u0635\u0647 \u06a9\u0627\u0645\u0644 \u0646\u0648\u0634\u062a\u0647<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u0646\u062a\u062e\u0627\u0628 \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u06a9\u0627\u0631 \u0633\u062e\u062a\u06cc \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc \u0631\u0633\u062f\u060c \u0627\u06cc\u0646\u0637\u0648\u0631 \u0646\u06cc\u0633\u062a\u061f \u0644\u0627\u0632\u0645 \u0646\u06cc\u0633\u062a \u0628\u0627\u0634\u062f. \u062f\u0631 \u062c\u0627\u06cc\u06cc \u0622\u0646 \u062c\u0627 \u0644\u0627\u0645\u067e \u0631\u0627 \u067e\u06cc\u062f\u0627 \u062e\u0648\u0627\u0647\u06cc\u062f \u06a9\u0631\u062f \u06a9\u0647 \u0645\u0646\u0627\u0633\u0628 \u06a9\u06cc\u0641 \u067e\u0648\u0644 \u0634\u0645\u0627 \u0648 \u062f\u06cc\u062f \u0634\u0645\u0627\u0633\u062a. \u0628\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u062f\u0644\u062e\u0648\u0627\u0647 \u06cc\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u0627\u062a\u0627\u0642 \u062e\u0648\u062f \u0648 \u0647\u062f\u0641 \u0627\u0635\u0644\u06cc \u0644\u0627\u0645\u067e \u0627\u0632 \u0642\u0628\u0644 \u0628\u0631\u0646\u0627\u0645\u0647 \u0631\u06cc\u0632\u06cc \u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u0634\u0645\u0627 \u0628\u0627\u06cc\u062f \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0686\u0646\u062f \u0646\u0648\u0639 \u0644\u0627\u0645\u067e \u0631\u0627 \u062d\u062a\u06cc \u0642\u0628\u0644 \u0627\u0632 \u062e\u0631\u0648\u062c \u0627\u0632 \u062e\u0627\u0646\u0647 \u0628\u0627 \u0622\u0646\u0686\u0647 \u062f\u0631 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a \u0645\u0634\u0627\u0647\u062f\u0647 \u06a9\u0631\u062f\u0647 \u0627\u06cc\u062f \u0627\u0632 \u0628\u06cc\u0646 \u0628\u0628\u0631\u06cc\u062f.<\/p>\n<p>\u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u062e\u0648\u0627\u0647\u06cc\u062f \u0686\u0646\u062f \u0639\u06a9\u0633 \u0641\u0648\u0631\u06cc \u0627\u0632 \u0627\u062a\u0627\u0642 \u0628\u06af\u06cc\u0631\u06cc\u062f. \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0647 \u0634\u0645\u0627 \u062f\u0631 \u062a\u062c\u0633\u0645 \u0686\u06af\u0648\u0646\u06af\u06cc \u0638\u0627\u0647\u0631 \u0644\u0627\u0645\u067e \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/p>\n<p>\u0645\u062d\u062f\u0648\u062f\u0647 \u0642\u06cc\u0645\u062a\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0628\u0647 \u0622\u0646 \u067e\u0627\u06cc\u0628\u0646\u062f \u062e\u0648\u0627\u0647\u06cc\u062f \u0628\u0648\u062f. \u0642\u06cc\u0645\u062a \u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u0627\u0632 \u0686\u0646\u062f \u0635\u062f \u0647\u0632\u0627\u0631 \u062a\u0648\u0645\u0627\u0646 \u062a\u0627 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u0647\u0627 \u062a\u0648\u0645\u0627\u0646 \u06cc\u0627 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u062e\u0648\u062f\u062a\u0627\u0646 \u062d\u062f \u0648 \u0645\u0631\u0632 \u062a\u0639\u06cc\u06cc\u0646 \u06a9\u0646\u06cc\u062f \u0648 \u0641\u0631\u0627\u062a\u0631 \u0627\u0632 \u0622\u0646 \u0646\u0631\u0648\u06cc\u062f\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u0631\u0627 \u0645\u062d\u062f\u0648\u062f \u06a9\u0646\u06cc\u062f \u062a\u0627 \u062e\u0631\u06cc\u062f\u06cc \u0644\u0630\u062a \u0628\u062e\u0634 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f!<\/p>\n<p>\u0628\u0631\u0627\u06cc \u0645\u0634\u0627\u0648\u0631\u0647 \u0648 \u06a9\u0633\u0628 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0628\u06cc\u0634\u062a\u0631 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0627 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u062f\u06a9\u0648\u0631\u0634\u0627\u067e \u062f\u0631 \u062a\u0645\u0627\u0633 \u0628\u0627\u0634\u06cc\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D8%A8%D8%A7%D8%B1%D9%87_%DB%8C_%DA%86%D8%B4%D9%85%D9%87_%D9%86%D9%88%D8%B1\"><\/span>\u062f\u0631\u0628\u0627\u0631\u0647 \u06cc\u00a0<span style=\"color: #ff0000;\">\u0686\u0634\u0645\u0647 \u0646\u0648\u0631<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u06a9\u0645\u067e\u0627\u0646\u06cc\u00a0<a href=\"https:\/\/chenco.ir\/\" target=\"_blank\" rel=\"noopener\">\u0686\u0634\u0645\u0647 \u0646\u0648\u0631<\/a>\u00a0\u0627\u0633\u062a \u0628\u0627 \u0642\u062f\u0645\u062a\u06cc \u06f3\u06f0 \u0633\u0627\u0644\u0647 \u0645\u06cc\u0628\u0627\u0634\u062f \u061b \u0647\u0645\u0647 \u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u062f\u0627\u0631\u0627\u06cc \u06af\u0627\u0631\u0627\u0646\u062a\u06cc \u06f1\u06f2 \u0645\u0627\u0647\u0647 \u0645\u06cc\u0628\u0627\u0634\u0646\u062f\u060c\u00a0 \u0628\u0631\u0627\u06cc \u0645\u0634\u0627\u0647\u062f\u0647 \u06cc \u0622\u0646 \u0647\u0627 \u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647 \u0633\u0627\u06cc\u062a\u00a0<a href=\"https:\/\/decorshop.ir\/product-category\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%da%a9%d8%b1%db%8c%d8%b3%d8%aa%d8%a7%d9%84%db%8c\/\">\u062f\u06a9\u0648\u0631\u0634\u0627\u067e<\/a>\u00a0\u0645\u0631\u0627\u062c\u0639\u0647 \u0641\u0631\u0645\u0627\u06cc\u06cc\u062f.<\/p>\n<p>\u0627\u0645\u0631\u0648\u0632\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a\u00a0 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0645\u0634\u063a\u0644\u0647 \u06cc \u06a9\u0627\u0631\u06cc \u0627\u0645\u06a9\u0627\u0646 \u062e\u0631\u06cc\u062f \u062d\u0636\u0648\u0631\u06cc \u0648 \u06cc\u0627 \u062d\u062a\u06cc \u0645\u0634\u0627\u0647\u062f\u0647 \u06cc \u0645\u062f\u0644 \u0647\u0627 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0645\u0634\u06a9\u0644 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f \u061b\u00a0 \u06cc\u06a9\u06cc \u0627\u0632 \u0633\u0627\u06cc\u062a \u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631 \u06a9\u0647 \u0627\u0645\u06a9\u0627\u0646 \u062e\u0631\u06cc\u062f \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc\u00a0 \u0631\u0627 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u060c\u00a0<a href=\"https:\/\/decorshop.ir\/\">\u062f\u06a9\u0648\u0631\u0634\u0627\u067e<\/a>\u00a0\u0645\u06cc\u0628\u0627\u0634\u062f .<\/p>\n<p>\u0627\u0644\u0628\u062a\u0647 \u0627\u06cc\u0646<a href=\"https:\/\/chenco.ir\/\" target=\"_blank\" rel=\"noopener\">\u00a0\u0634\u0631\u06a9\u062a<\/a>\u00a0\u0628\u0631\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0634\u0645\u0627 \u060c \u0627\u0645\u06a9\u0627\u0646 \u062e\u0631\u06cc\u062f \u0627\u0642\u0633\u0627\u0637\u06cc \u062d\u062a\u06cc \u0628\u062f\u0648\u0646 \u0636\u0627\u0645\u0646 \u0631\u0627 \u062f\u0631 \u0633\u0627\u06cc\u062a \u0641\u0631\u0627\u0647\u0645 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u0648 \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u062d\u0635\u0648\u0644 \u0628\u0647 \u0645\u0634\u06a9\u0644\u06cc \u0628\u0631\u062e\u0648\u0631\u062f \u06a9\u0631\u062f\u06cc\u062f \u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646 \u0647\u0627\u06cc \u062f\u06a9\u0648\u0631\u0634\u0627\u067e \u0628\u0647 \u0635\u0648\u0631\u062a \u0631\u0627\u06cc\u06af\u0627\u0646 \u0645\u0634\u0627\u0648\u0631\u0647 \u0628\u06af\u06cc\u0631\u06cc\u062f .<\/p>\n<p>\u0628\u0631\u0627\u06cc \u0645\u0634\u0627\u0647\u062f\u0647 \u06cc \u0645\u0642\u0627\u0644\u0627\u062a \u0628\u06cc\u0634\u062a\u0631 \u0628\u0647\u00a0<a href=\"https:\/\/decorshop.ir\/mag\/\">\u062f\u06a9\u0648\u0631\u0645\u06af<\/a>\u00a0\u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0622\u0628\u0627\u0698\u0648\u0631 \u0627\u06cc\u0633\u062a\u0627\u062f\u0647 \u062f\u0627\u0631\u0627\u06cc \u062a\u0646\u0648\u0639 \u0634\u06af\u0641\u062a \u0627\u0646\u06af\u06cc\u0632\u06cc \u0627\u0632 \u0633\u0628\u06a9 \u0647\u0627 \u0647\u0633\u062a\u0646\u062f \u0648 \u0647\u0645\u0647 \u06a9\u0627\u0631\u0647 \u0647\u0633\u062a\u0646\u062f \u060c \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u062a\u0623\u0645\u06cc\u0646 \u0646\u0648\u0631\u060c \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0637\u0631\u0627\u062d\u06cc \u062f\u0627\u062e\u0644\u06cc \u062e\u0627\u0646\u0647 \u0628\u06cc\u0641\u0632\u0627\u06cc\u0646\u062f \u06cc\u0627 \u0628\u0647 \u06af\u0648\u0634\u0647 \u062e\u0627\u0644\u06cc \u0639\u0644\u0627\u0642\u0647 \u0646\u0634\u0627\u0646 \u062f\u0647\u0646\u062f. \u062d\u062a\u06cc \u0628\u0647\u062a\u0631 \u0627\u0632 \u0627\u06cc\u0646\u060c \u0622\u0646 \u0647\u0627 \u0631\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646 \u062f\u0631 \u0647\u0631 \u0632\u0645\u0627\u0646 \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0627\u0632 \u0627\u062a\u0627\u0642\u06cc \u0628\u0647 \u0627\u062a\u0627\u0642 \u062f\u06cc\u06af\u0631 \u0645\u0646\u062a\u0642\u0644 \u06a9\u0631\u062f. \u0622\u0628\u0627\u0698\u0648\u0631 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":34519,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[407,35,50,34],"tags":[87,410,409,89,408],"class_list":["post-34513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-407","category-35","category-50","category-34","tag-87","tag-410","tag-409","tag-89","tag-408"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/34513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=34513"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/34513\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/34519"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=34513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=34513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=34513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}