{"id":33823,"date":"2021-07-10T10:35:37","date_gmt":"2021-07-10T06:05:37","guid":{"rendered":"https:\/\/decorshop.ir\/mag\/?p=33823"},"modified":"2023-04-27T11:57:42","modified_gmt":"2023-04-27T08:27:42","slug":"%d8%a8%d8%b1%d8%a7%db%8c-%d8%ac%d9%84%d9%88%da%af%db%8c%d8%b1%db%8c-%d8%a7%d8%b2-%d9%82%d8%b7%d8%b9-%d8%a8%d8%b1%d9%82-%d8%ae%d8%a7%d9%86%da%af%db%8c-%da%86%d9%87-%da%a9%d9%86%db%8c%d9%85","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d8%a8%d8%b1%d8%a7%db%8c-%d8%ac%d9%84%d9%88%da%af%db%8c%d8%b1%db%8c-%d8%a7%d8%b2-%d9%82%d8%b7%d8%b9-%d8%a8%d8%b1%d9%82-%d8%ae%d8%a7%d9%86%da%af%db%8c-%da%86%d9%87-%da%a9%d9%86%db%8c%d9%85\/","title":{"rendered":"\u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0642\u0637\u0639 \u0628\u0631\u0642 \u062e\u0627\u0646\u06af\u06cc \u0686\u0647 \u06a9\u0646\u06cc\u0645 \u061f"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a8%d8%b1%d8%a7%db%8c-%d8%ac%d9%84%d9%88%da%af%db%8c%d8%b1%db%8c-%d8%a7%d8%b2-%d9%82%d8%b7%d8%b9-%d8%a8%d8%b1%d9%82-%d8%ae%d8%a7%d9%86%da%af%db%8c-%da%86%d9%87-%da%a9%d9%86%db%8c%d9%85\/#%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D9%82%D8%B7%D8%B9_%D8%A8%D8%B1%D9%82_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C\" >\u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0642\u0637\u0639 \u0628\u0631\u0642 \u062e\u0627\u0646\u06af\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a8%d8%b1%d8%a7%db%8c-%d8%ac%d9%84%d9%88%da%af%db%8c%d8%b1%db%8c-%d8%a7%d8%b2-%d9%82%d8%b7%d8%b9-%d8%a8%d8%b1%d9%82-%d8%ae%d8%a7%d9%86%da%af%db%8c-%da%86%d9%87-%da%a9%d9%86%db%8c%d9%85\/#%D8%A7%D9%82%D8%AF%D8%A7%D9%85%D8%A7%D8%AA%DB%8C_%DA%A9%D9%87_%D8%AF%D8%B1_%D8%B2%D9%85%D8%A7%D9%86_%D9%82%D8%B7%D8%B9_%D8%A8%D8%B1%D9%82_%D8%A8%D8%A7%DB%8C%D8%AF_%D8%A7%D8%B2_%D8%A2%D9%86_%D8%A7%D8%AC%D8%AA%D9%86%D8%A7%D8%A8_%DA%A9%D8%B1%D8%AF\" >\u0627\u0642\u062f\u0627\u0645\u0627\u062a\u06cc \u06a9\u0647 \u062f\u0631 \u0632\u0645\u0627\u0646 \u0642\u0637\u0639 \u0628\u0631\u0642 \u0628\u0627\u06cc\u062f \u0627\u0632 \u0622\u0646 \u0627\u062c\u062a\u0646\u0627\u0628 \u06a9\u0631\u062f<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a8%d8%b1%d8%a7%db%8c-%d8%ac%d9%84%d9%88%da%af%db%8c%d8%b1%db%8c-%d8%a7%d8%b2-%d9%82%d8%b7%d8%b9-%d8%a8%d8%b1%d9%82-%d8%ae%d8%a7%d9%86%da%af%db%8c-%da%86%d9%87-%da%a9%d9%86%db%8c%d9%85\/#%D8%B4%D9%85%D8%B9\" >\u0634\u0645\u0639 :<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a8%d8%b1%d8%a7%db%8c-%d8%ac%d9%84%d9%88%da%af%db%8c%d8%b1%db%8c-%d8%a7%d8%b2-%d9%82%d8%b7%d8%b9-%d8%a8%d8%b1%d9%82-%d8%ae%d8%a7%d9%86%da%af%db%8c-%da%86%d9%87-%da%a9%d9%86%db%8c%d9%85\/#%D9%87%D8%AF%D8%B1_%D8%AF%D8%A7%D8%AF%D9%86_%D8%A8%D8%A7%D8%AA%D8%B1%DB%8C_%D9%85%D9%88%D8%A8%D8%A7%DB%8C%D9%84\" >\u0647\u062f\u0631 \u062f\u0627\u062f\u0646 \u0628\u0627\u062a\u0631\u06cc \u0645\u0648\u0628\u0627\u06cc\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a8%d8%b1%d8%a7%db%8c-%d8%ac%d9%84%d9%88%da%af%db%8c%d8%b1%db%8c-%d8%a7%d8%b2-%d9%82%d8%b7%d8%b9-%d8%a8%d8%b1%d9%82-%d8%ae%d8%a7%d9%86%da%af%db%8c-%da%86%d9%87-%da%a9%d9%86%db%8c%d9%85\/#%D8%A7%D8%B2_%D8%A8%D8%B1%D9%82_%D9%86%DA%A9%D8%B4%DB%8C%D8%AF%D9%86_%D8%B3%DB%8C%D9%85_%D9%87%D8%A7_%D9%88_%D8%B4%D8%A7%D8%B1%DA%98%D8%B1_%D9%87%D8%A7_%D8%A7%D8%B2_%D8%AF%D8%A7%D8%AE%D9%84_%D9%BE%D8%B1%DB%8C%D8%B2_%D8%A8%D8%B1%D9%82\" >\u0627\u0632 \u0628\u0631\u0642 \u0646\u06a9\u0634\u06cc\u062f\u0646 \u0633\u06cc\u0645 \u0647\u0627 \u0648 \u0634\u0627\u0631\u0698\u0631 \u0647\u0627 \u0627\u0632 \u062f\u0627\u062e\u0644 \u067e\u0631\u06cc\u0632 \u0628\u0631\u0642<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a8%d8%b1%d8%a7%db%8c-%d8%ac%d9%84%d9%88%da%af%db%8c%d8%b1%db%8c-%d8%a7%d8%b2-%d9%82%d8%b7%d8%b9-%d8%a8%d8%b1%d9%82-%d8%ae%d8%a7%d9%86%da%af%db%8c-%da%86%d9%87-%da%a9%d9%86%db%8c%d9%85\/#%D8%AE%D8%A7%D9%85%D9%88%D8%B4_%DA%A9%D8%B1%D8%AF%D9%86_%DA%A9%D9%84_%D9%84%D8%A7%D9%85%D9%BE_%D9%87%D8%A7\" >\u062e\u0627\u0645\u0648\u0634 \u06a9\u0631\u062f\u0646 \u06a9\u0644 \u0644\u0627\u0645\u067e \u0647\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a8%d8%b1%d8%a7%db%8c-%d8%ac%d9%84%d9%88%da%af%db%8c%d8%b1%db%8c-%d8%a7%d8%b2-%d9%82%d8%b7%d8%b9-%d8%a8%d8%b1%d9%82-%d8%ae%d8%a7%d9%86%da%af%db%8c-%da%86%d9%87-%da%a9%d9%86%db%8c%d9%85\/#%D8%A8%D8%A7%D8%B2%D9%88_%D8%A8%D8%B3%D8%AA%D9%87_%DA%A9%D8%B1%D8%AF%D9%86_%D8%A8%DB%8C_%D8%AF%D9%84%DB%8C%D9%84_%D8%AF%D8%B1_%DB%8C%D8%AE%DA%86%D8%A7%D9%84\" >\u0628\u0627\u0632\u0648 \u0628\u0633\u062a\u0647 \u06a9\u0631\u062f\u0646 \u0628\u06cc \u062f\u0644\u06cc\u0644 \u062f\u0631 \u06cc\u062e\u0686\u0627\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a8%d8%b1%d8%a7%db%8c-%d8%ac%d9%84%d9%88%da%af%db%8c%d8%b1%db%8c-%d8%a7%d8%b2-%d9%82%d8%b7%d8%b9-%d8%a8%d8%b1%d9%82-%d8%ae%d8%a7%d9%86%da%af%db%8c-%da%86%d9%87-%da%a9%d9%86%db%8c%d9%85\/#%D9%82%D8%B1%D8%A7%D8%B1_%D8%AF%D8%A7%D8%AF%D9%86_%DA%98%D9%86%D8%B1%D8%A7%D8%AA%D9%88%D8%B1_%D8%AF%D8%B1_%D8%AF%D8%B1_%DA%AF%D8%A7%D8%B1%D8%A7%DA%98_%D9%88_%D9%85%DA%A9%D8%A7%D9%86_%DA%A9%D9%88%DA%86%DA%A9\" >\u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0646 \u0698\u0646\u0631\u0627\u062a\u0648\u0631 \u062f\u0631 \u062f\u0631 \u06af\u0627\u0631\u0627\u0698 \u0648 \u0645\u06a9\u0627\u0646 \u06a9\u0648\u0686\u06a9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a8%d8%b1%d8%a7%db%8c-%d8%ac%d9%84%d9%88%da%af%db%8c%d8%b1%db%8c-%d8%a7%d8%b2-%d9%82%d8%b7%d8%b9-%d8%a8%d8%b1%d9%82-%d8%ae%d8%a7%d9%86%da%af%db%8c-%da%86%d9%87-%da%a9%d9%86%db%8c%d9%85\/#%D8%B0%D8%AE%DB%8C%D8%B1%D9%87_%D9%86%DA%A9%D8%B1%D8%AF%D9%86_%D8%A2%D8%A8\" >\u0630\u062e\u06cc\u0631\u0647 \u0646\u06a9\u0631\u062f\u0646 \u0622\u0628<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D9%82%D8%B7%D8%B9_%D8%A8%D8%B1%D9%82_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C\"><\/span>\u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0642\u0637\u0639 \u0628\u0631\u0642 \u062e\u0627\u0646\u06af\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0642\u0637\u0639 \u0628\u0631\u0642 \u0622\u062b\u0627\u0631 \u0645\u062a\u0639\u062f\u062f \u0627\u062c\u062a\u0645\u0627\u0639\u06cc\u060c \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u0633\u06cc\u0627\u0633\u06cc \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0628\u0631\u0627\u06cc \u0622\u0646 ( \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0642\u0637\u0639 \u0628\u0631\u0642 ) \u0686\u0627\u0631\u0647 \u0627\u0646\u062f\u06cc\u0634\u06cc\u062f \u061b \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u062a\u0631\u06cc\u0646 \u0639\u0648\u0627\u0642\u0628 \u0627\u06cc\u0646 \u0642\u0637\u0639 \u0628\u0631\u0642 \u060c \u0622\u0633\u06cc\u0628 \u062f\u06cc\u062f\u0646 \u0628\u062e\u0634 \u062a\u0648\u0644\u06cc\u062f \u06a9\u0634\u0648\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0645\u062a\u0627\u0633\u0641\u0627\u0646\u0647 \u062f\u0631 \u0633\u0627\u0644\u06cc\u0627\u0646 \u06af\u0630\u0634\u062a\u0647 \u0647\u0645\u0648\u0627\u0631\u0647 \u0628\u062e\u0634 \u062a\u0648\u0644\u06cc\u062f \u0628\u0648\u062f\u0647 \u06a9\u0647 \u0642\u0631\u0628\u0627\u0646\u06cc \u0628\u062e\u0634 \u067e\u0631\u0645\u0635\u0631\u0641 \u0628\u0631\u0642 \u062e\u0627\u0646\u06af\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u06a9\u0631\u0631\u0627\u064b \u062f\u06cc\u062f\u0647 \u0634\u062f\u0647 \u0628\u0647 \u062c\u0627\u06cc \u0686\u0627\u0631\u0647 \u0627\u0646\u062f\u06cc\u0634\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0646\u062a\u0631\u0644 \u0645\u0635\u0631\u0641 \u062f\u0631 \u0628\u062e\u0634 \u0628\u0631\u0642 \u062e\u0627\u0646\u06af\u06cc\u060c \u0628\u0631\u0642 \u0635\u0646\u0627\u06cc\u0639 \u0648 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0645\u0648\u0644\u062f \u0642\u0637\u0639 \u0634\u062f\u0647 \u0648 \u0622\u062b\u0627\u0631 \u062c\u0628\u0631\u0627\u0646 \u0646\u0627\u067e\u0630\u06cc\u0631\u06cc \u0646\u06cc\u0632 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0634\u062a\u0647 \u06a9\u0647 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0646\u0645\u0648\u0646\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u0642\u0637\u0639 \u0628\u0631\u0642 \u0648 \u062a\u0644\u0641 \u0634\u062f\u0646 \u06f2\u06f0\u06f0\u06f0 \u0642\u0637\u0639 \u0645\u0631\u063a \u062f\u0631 \u0634\u0647\u0631 \u0634\u0648\u0637 ( \u0648\u0627\u0642\u0639 \u062f\u0631 \u0622\u0630\u0631\u0628\u0627\u06cc\u062c\u0627\u0646 \u063a\u0631\u0628\u06cc ) \u0627\u0633\u062a \u06a9\u0647 \u0627\u062a\u0641\u0627\u0642 \u0627\u0641\u062a\u0627\u062f\u0647 \u0628\u0648\u062f .<\/p>\n<p>\u0627\u0644\u0628\u062a\u0647 \u0646\u06a9\u062a\u0647 \u0642\u0627\u0628\u0644 \u062a\u0627\u0645\u0644 \u062f\u0631 \u062e\u0635\u0648\u0635 \u0642\u0637\u0639 \u0628\u0631\u0642 \u0628\u062e\u0634 \u0635\u0646\u0639\u062a \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u062d\u0627\u0644\u06cc \u0627\u062a\u0641\u0627\u0642 \u0645\u06cc\u200c\u0627\u0641\u062a\u062f \u06a9\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0628\u062e\u0634 \u067e\u0631\u0645\u0635\u0631\u0641 \u0628\u0631\u0642 \u062e\u0627\u0646\u06af\u06cc \u062d\u062a\u06cc \u0627\u0632 \u0645\u06cc\u0632\u0627\u0646 \u0645\u0635\u0631\u0641 \u062f\u0631 \u0628\u062e\u0634 \u0635\u0646\u0639\u062a \u0647\u0645 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0648\u062f\u0647 \u0648 \u0645\u06cc\u0632\u0627\u0646 \u062a\u0648\u0627\u0646 \u0645\u0635\u0631\u0641\u06cc \u0633\u0647 \u062f\u0647\u06a9 \u0628\u0627\u0644\u0627\u06cc \u0628\u062e\u0634 \u062e\u0627\u0646\u06af\u06cc \u0627\u0632 \u06a9\u0644 \u062a\u0648\u0627\u0646 \u0645\u0635\u0631\u0641\u06cc \u06a9\u0634\u0648\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0645\u06cc\u0628\u0627\u0634\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33824\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/280-min-1.jpg\" alt=\"\u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0642\u0637\u0639 \u0628\u0631\u0642 \u062e\u0627\u0646\u06af\u06cc\" width=\"1400\" height=\"600\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/280-min-1.jpg 1400w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/280-min-1-300x129.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/280-min-1-1024x439.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/280-min-1-768x329.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<p>\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u06a9\u0647 \u062a\u0648\u0627\u0646 \u0645\u0635\u0631\u0641\u06cc \u0628\u062e\u0634 \u062e\u0627\u0646\u06af\u06cc \u0627\u0632 \u0628\u062e\u0634 \u0635\u0646\u0639\u062a \u06a9\u0634\u0648\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0633\u062a\u060c \u0627\u06cc\u0646 \u0648\u062c\u0648\u062f \u0635\u0646\u0627\u06cc\u0639 \u0627\u0633\u062a \u06a9\u0647 \u0642\u06cc\u0645\u062a \u0628\u0631\u0642 \u0631\u0627 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u06a9\u0631\u062f\u0647 \u0648 \u0647\u0632\u06cc\u0646\u0647 \u062a\u0645\u0627\u0645 \u0634\u062f\u0647 \u0622\u0646 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f \u0648 \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0634\u0648\u0631\u200c\u0647\u0627\u06cc \u062f\u0646\u06cc\u0627 \u0642\u06cc\u0645\u062a \u0628\u0631\u0642 \u0635\u0646\u0627\u06cc\u0639 \u0627\u0632 \u0642\u06cc\u0645\u062a \u0628\u062e\u0634 \u062e\u0627\u0646\u06af\u06cc \u0627\u0631\u0632\u0627\u0646 \u062a\u0631 \u0628\u0648\u062f\u0647 \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0631\u0627\u0646 \u0628\u0631\u0639\u06a9\u0633 \u0622\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0627\u0632 \u0633\u0648\u06cc \u062f\u06cc\u06af\u0631\u060c \u0646\u0638\u0627\u0645 \u0641\u0639\u0644\u06cc \u062a\u0639\u0631\u0641\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0628\u0631\u0642 \u062f\u0631 \u06a9\u0634\u0648\u0631 \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u0634\u062a\u0631\u06a9\u0627\u0646 \u067e\u0631\u0645\u0635\u0631\u0641 \u0627\u0632 \u06cc\u0627\u0631\u0627\u0646\u0647 \u0628\u0631\u0642 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0634\u062f\u0647 \u0648 \u0628\u0627 \u0645\u0635\u0627\u0631\u0641 \u0628\u06cc \u0631\u0648\u06cc\u0647 \u0628\u062d\u0631\u0627\u0646 \u0633\u0627\u0632 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u060c \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0648\u0627\u0642\u0639\u06cc\u200c\u0633\u0627\u0632\u06cc \u062a\u0639\u0631\u0641\u0647 \u0628\u0631\u0642 \u0645\u0634\u062a\u0631\u06a9\u06cc\u0646 \u062e\u0627\u0631\u062c \u0627\u0632 \u0627\u0644\u06af\u0648 \u0636\u0631\u0648\u0631\u062a \u062f\u0627\u0631\u062f.<\/p>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u062a\u0631\u06cc\u0646 \u0648 \u0645\u0648\u062b\u0631\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647\u06a9\u0627\u0631\u200c\u0647\u0627\u06cc \u062c\u0647\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646\u060c \u0627\u0641\u0632\u0627\u06cc\u0634 \u0642\u06cc\u0645\u062a \u0628\u0631\u0642 \u0645\u0634\u062a\u0631\u06a9\u06cc\u0646 \u067e\u0631\u0645\u0635\u0631\u0641 \u0627\u0633\u062a.<\/p>\n<p>\u06a9\u0647 \u062f\u0631 \u0647\u0645\u06cc\u0646 \u0631\u0627\u0633\u062a\u0627 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u0627\u0646 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u062f\u0627\u062f\u0647\u200c\u0627\u0646\u062f \u062a\u0627 \u062a\u0639\u0631\u0641\u0647 \u0628\u0631\u0642 \u0645\u0634\u062a\u0631\u06a9\u06cc\u0646 \u062e\u0627\u0631\u062c \u0627\u0632 \u0627\u0644\u06af\u0648 \u0628\u0647 \u0646\u0631\u062e \u062e\u0648\u0631\u0634\u06cc\u062f\u06cc \u062e\u0627\u0646\u06af\u06cc \u062a\u0639\u06cc\u06cc\u0646 \u0634\u062f\u0647 \u0648 \u0628\u0631\u0627\u06cc \u0622\u0646 \u062f\u0644\u0627\u06cc\u0644\u06cc \u0646\u06cc\u0632 \u0622\u0648\u0631\u062f\u0647\u200c\u0627\u0646\u062f \u060c \u0628\u0631\u0631\u0633\u06cc\u200c\u0647\u0627 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u0627\u06af\u0631 \u0645\u0634\u062a\u0631\u06a9\u0627\u0646 \u0628\u0631\u0627\u06cc \u0645\u0635\u0627\u0631\u0641 \u0645\u0627\u0632\u0627\u062f \u0628\u0631 \u0627\u0644\u06af\u0648\u060c \u0628\u0647\u0627\u06cc \u0628\u0631\u0642 \u062e\u0648\u0631\u0634\u06cc\u062f\u06cc \u062a\u0648\u0644\u06cc\u062f \u0628\u0647\u200c\u0648\u0633\u06cc\u0644\u0647 \u0633\u0644\u0648\u0644\u200c\u0647\u0627\u06cc \u062e\u0648\u0631\u0634\u06cc\u062f\u06cc \u0648 \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u0634\u062f\u0647 \u0627\u0632 \u0645\u0631\u062f\u0645 \u0631\u0627 \u067e\u0631\u062f\u0627\u062e\u062a \u06a9\u0646\u0646\u062f\u060c \u0648\u0632\u0627\u0631\u062a \u0646\u06cc\u0631\u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0628\u0631\u0642 \u062a\u0636\u0645\u06cc\u0646\u06cc \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u0634\u062f\u0647 \u0627\u0632 \u0646\u06cc\u0631\u0648\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u062e\u0648\u0631\u0634\u06cc\u062f\u06cc\u060c \u0628\u0631\u0642 \u0645\u0627\u0632\u0627\u062f \u0627\u06cc\u0646 \u0645\u0634\u062a\u0631\u06a9\u0627\u0646 \u0631\u0627 \u062a\u0627\u0645\u06cc\u0646 \u06a9\u0646\u062f.<\/p>\n<p>\u0627\u0644\u0628\u062a\u0647 \u062f\u0631 \u0647\u0631 \u0645\u0646\u0637\u0642\u0647 \u0632\u0645\u0627\u0646 \u0627\u062d\u062a\u0645\u0627\u0644\u06cc \u0642\u0637\u0639 \u0628\u0631\u0642 \u062a\u0627 \u062d\u062f\u0648\u062f\u06cc \u0645\u0634\u062e\u0635 \u0634\u062f\u0647 \u06a9\u0647 \u062f\u0631<strong> <a href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87-%d9%87%d8%a7%db%8c-%d8%ac%d8%a7%db%8c%da%af%d8%b2%db%8c%d9%86-%d8%a8%d8%b1%d8%a7%db%8c-%d9%82%d8%b7%d8%b9%db%8c-%d8%a8%d8%b1%d9%82\/\">\u0645\u0642\u0627\u0644\u0647 \u06cc \u0642\u0628\u0644<\/a><\/strong> \u0645\u06cc\u062a\u0648\u0627\u0646 \u0628\u0647 \u0627\u06cc\u0646 \u0633\u0627\u0639\u0627\u062a \u062f\u0633\u062a\u0631\u0633\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f \u0648 \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0648\u0632 \u0647\u0627 \u0645\u06cc\u062a\u0648\u0627\u0646\u062f \u0628\u0631\u0627\u06cc \u0628\u0631\u0646\u0627\u0645\u0647 \u0631\u06cc\u0632\u06cc \u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0647 \u0628\u0631\u0642 \u0646\u06cc\u0627\u0632 \u0627\u0633\u062a \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f .<\/p>\n<p>\u06af\u0632\u06cc\u0646\u0647 \u06cc \u0622\u062e\u0631 \u06a9\u0645 \u06a9\u0631\u062f\u0646 \u0645\u0635\u0631\u0641 \u0628\u0631\u0642 \u062f\u0631 \u062a\u0645\u0627\u0645\u06cc \u0645\u0646\u0627\u0632\u0644 \u0645\u06cc\u0628\u0627\u0634\u062f \u06a9\u0647 \u0628\u062a\u0648\u0627\u0646 \u0622\u0646 \u0631\u0627 \u062f\u0631 \u0633\u0637\u062d \u0634\u0647\u0631 \u06a9\u0646\u062a\u0631\u0644 \u0646\u0645\u0648\u062f .<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D9%82%D8%AF%D8%A7%D9%85%D8%A7%D8%AA%DB%8C_%DA%A9%D9%87_%D8%AF%D8%B1_%D8%B2%D9%85%D8%A7%D9%86_%D9%82%D8%B7%D8%B9_%D8%A8%D8%B1%D9%82_%D8%A8%D8%A7%DB%8C%D8%AF_%D8%A7%D8%B2_%D8%A2%D9%86_%D8%A7%D8%AC%D8%AA%D9%86%D8%A7%D8%A8_%DA%A9%D8%B1%D8%AF\"><\/span>\u0627\u0642\u062f\u0627\u0645\u0627\u062a\u06cc \u06a9\u0647 \u062f\u0631 \u0632\u0645\u0627\u0646 \u0642\u0637\u0639 \u0628\u0631\u0642 \u0628\u0627\u06cc\u062f \u0627\u0632 \u0622\u0646 \u0627\u062c\u062a\u0646\u0627\u0628 \u06a9\u0631\u062f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B4%D9%85%D8%B9\"><\/span>\u0634\u0645\u0639 :<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<\/li>\n<\/ul>\n<p>\u062e\u0648\u0634\u0628\u062e\u062a\u0627\u0646\u0647 \u0642\u0631\u0627\u0631 \u0646\u06cc\u0633\u062a \u0645\u0627 \u0628\u0647 \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc \u0642\u0631\u0646 19 \u0628\u0631\u06af\u0631\u062f\u06cc\u0645\u060c \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0631\u0642 \u0642\u0637\u0639 \u0645\u06cc\u0634\u0648\u062f\u060c \u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u062f \u0634\u0645\u0639 \u0631\u0648\u0634\u0646 \u06a9\u0646\u06cc\u062f \u060c \u0634\u0645\u0639 \u0647\u0627 \u0639\u0627\u0644\u06cc \u0647\u0633\u062a\u0646\u062f \u0648\u0644\u06cc \u062e\u06cc\u0644\u06cc \u0632\u0648\u062f \u062a\u0645\u0627\u0645 \u0645\u06cc\u0634\u0648\u0646\u062f \u0648 \u06af\u0627\u0647\u06cc \u0645\u0648\u062c\u0628 \u0622\u062a\u0634 \u0633\u0648\u0632\u06cc \u0645\u06cc\u0634\u0648\u0646\u062f \u0627\u0632 \u0637\u0631\u0641\u06cc \u0646\u0648\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0642\u0648\u06cc \u0647\u0645 \u0646\u062f\u0627\u0631\u0646\u062f \u067e\u0633 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0627\u0632 \u0631\u0648\u0634\u0646 \u06a9\u0631\u062f\u0646 \u0634\u0645\u0639 \u0627\u062c\u062a\u0646\u0627\u0628 \u06a9\u0646\u06cc\u062f \u0645\u0648\u0642\u0639 \u0642\u0637\u0639 \u0628\u0631\u0642 \u0646\u06cc\u0627\u0632\u06cc \u0646\u06cc\u0633\u062a \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u06cc\u062f\u060c \u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u06cc\u06a9 \u0641\u0627\u0646\u0648\u0633 \u0631\u0648\u0634\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0645\u0627\u06cc\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33826\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/281-min-1.jpg\" alt=\"\" width=\"1400\" height=\"600\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/281-min-1.jpg 1400w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/281-min-1-300x129.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/281-min-1-1024x439.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/281-min-1-768x329.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<ul>\n<li>\n<h3><span class=\"ez-toc-section\" id=\"%D9%87%D8%AF%D8%B1_%D8%AF%D8%A7%D8%AF%D9%86_%D8%A8%D8%A7%D8%AA%D8%B1%DB%8C_%D9%85%D9%88%D8%A8%D8%A7%DB%8C%D9%84\"><\/span>\u0647\u062f\u0631 \u062f\u0627\u062f\u0646 \u0628\u0627\u062a\u0631\u06cc \u0645\u0648\u0628\u0627\u06cc\u0644<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<\/li>\n<\/ul>\n<p>\u062f\u0631 \u0632\u0645\u0627\u0646 \u0642\u0642\u0637 \u0628\u0631\u0642 \u060c \u0648\u0642\u062a\u06cc \u0646\u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u062f \u062a\u0644\u0648\u0632\u06cc\u0648\u0646 \u0646\u06af\u0627\u0647 \u06a9\u0646\u06cc\u062f\u060c \u06cc\u0627 \u0646\u0648\u0631 \u06a9\u0627\u0641\u06cc \u0628\u0631\u0627\u06cc \u0645\u0637\u0627\u0644\u0639\u0647 \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f\u060c \u062a\u0646\u0647\u0627 \u0641\u06a9\u0631\u06cc \u06a9\u0647 \u0628\u0647 \u0633\u0631\u062a\u0627\u0646 \u062e\u0637\u0648\u0631 \u0645\u06cc\u06a9\u0646\u062f \u0628\u0627\u0632\u06cc \u0628\u0627 \u06af\u0648\u0634\u06cc \u0648 \u0622\u06cc \u067e\u062f \u0627\u0633\u062a \u0627\u0645\u0627 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0630\u062e\u06cc\u0631\u0647 \u0628\u0627\u062a\u0631\u06cc \u0622\u0646 \u0631\u0627 \u06a9\u0646\u0627\u0631 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f \u0648 \u0641\u0642\u0637 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631 \u0647\u0627\u06cc \u0645\u0647\u0645 \u0627\u0632 \u0622\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u0632\u06cc\u0631\u0627 \u0627\u06af\u0631 \u0628\u0627\u062a\u0631\u06cc \u0645\u0648\u0628\u0627\u06cc\u0644 \u062e\u0648\u062f \u0631\u0627 \u062a\u0645\u0627\u0645 \u06a9\u0646\u06cc\u062f\u060c \u062f\u06cc\u06af\u0631 \u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u062c\u0627\u06cc\u06cc \u0646\u062f\u0627\u0631\u062f \u0648 \u0648\u0642\u062a\u06cc \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u0628\u0631\u0627\u06cc \u0686\u0646\u062f \u0631\u0648\u0632 \u0637\u0648\u0644 \u0628\u06a9\u0634\u062f\u060c \u062f\u0631 \u0645\u0648\u0627\u0631\u062f \u0627\u0636\u0637\u0631\u0627\u0631\u06cc \u0628\u0647 \u06af\u0648\u0634\u06cc \u062e\u0648\u062f \u0646\u06cc\u0627\u0632 \u062e\u0648\u0627\u0647\u06cc\u062f \u062f\u0627\u0634\u062a&#8221; \u0627\u06af\u0631 \u0646\u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u062f \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0628\u0627\u0632\u06cc \u0646\u06a9\u0631\u062f\u0646 \u0628\u0627 \u06af\u0648\u0634\u06cc \u0645\u0642\u0627\u0648\u0645\u062a \u06a9\u0646\u06cc\u062f\u060c \u062d\u062f\u0627\u0642\u0644 \u0627\u0632 \u06cc\u06a9 \u067e\u0627\u0648\u0631 \u0628\u0627\u0646\u06a9 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f\u060c \u062a\u0627 \u062f\u0631 \u0645\u0648\u0627\u0642\u0639 \u0636\u0631\u0648\u0631\u06cc \u0627\u0632 \u0622\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<ul>\n<li>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B2_%D8%A8%D8%B1%D9%82_%D9%86%DA%A9%D8%B4%DB%8C%D8%AF%D9%86_%D8%B3%DB%8C%D9%85_%D9%87%D8%A7_%D9%88_%D8%B4%D8%A7%D8%B1%DA%98%D8%B1_%D9%87%D8%A7_%D8%A7%D8%B2_%D8%AF%D8%A7%D8%AE%D9%84_%D9%BE%D8%B1%DB%8C%D8%B2_%D8%A8%D8%B1%D9%82\"><\/span>\u0627\u0632 \u0628\u0631\u0642 \u0646\u06a9\u0634\u06cc\u062f\u0646 \u0633\u06cc\u0645 \u0647\u0627 \u0648 \u0634\u0627\u0631\u0698\u0631 \u0647\u0627 \u0627\u0632 \u062f\u0627\u062e\u0644 \u067e\u0631\u06cc\u0632 \u0628\u0631\u0642<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<\/li>\n<\/ul>\n<p>\u0628\u0647 \u06cc\u0627\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u06a9\u0647 \u062d\u062a\u0645\u0627\u064b \u0628\u0627\u06cc\u062f \u0642\u0628\u0644 \u0627\u0632 \u0647\u0631 \u0627\u062a\u0641\u0627\u0642\u06cc \u0627\u06cc\u0646 \u0633\u06cc\u0645 \u0647\u0627 \u0631\u0627 \u0627\u0632 \u0628\u0631\u0642 \u0628\u06a9\u0634\u06cc\u062f \u0632\u06cc\u0631\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0631\u0642 \u0628\u06cc\u0627\u06cc\u062f\u060c \u06cc\u06a9 \u062c\u0631\u0642\u0647 \u0627\u06cc\u062c\u0627\u062f \u0634\u0648\u062f \u0648 \u0645\u0634\u06a9\u0644 \u0628\u0632\u0631\u06af\u06cc \u0631\u0627 \u0628\u0647 \u0628\u0627\u0631 \u0628\u06cc\u0627\u0648\u0631\u062f \u0648 \u0628\u0647 \u062f\u0633\u062a\u06af\u0627\u0647 \u0634\u0645\u0627 \u0622\u0633\u06cc\u0628 \u0648\u0627\u0631\u062f \u06a9\u0646\u062f \u060c \u067e\u0633 \u0633\u0639\u06cc \u06a9\u0646\u06cc\u062f \u0622\u0646 \u0647\u0627 \u0631\u0627 \u0627\u0632 \u0628\u0631\u0642 \u0628\u06cc\u0631\u0648\u0646 \u0628\u06a9\u0634\u06cc\u062f \u0648 \u0645\u0631\u0627\u0642\u0628\u062a \u06a9\u0627\u0641\u06cc \u0631\u0627 \u0628\u0647 \u0627\u0646\u062c\u0627\u0645 \u0628\u0631\u0633\u0627\u0646\u06cc\u062f \u061b \u0627\u06af\u0631 \u0642\u0637\u0639 \u0628\u0631\u0642 \u0637\u0648\u0644\u0627\u0646\u06cc \u0634\u062f \u062d\u062a\u0645\u0627 \u0648\u0633\u0627\u06cc\u0644 \u0631\u0627 \u0627\u0632 \u0628\u0631\u0642 \u0628\u06a9\u0634\u06cc\u062f \u062a\u0627 \u0647\u0646\u06af\u0627\u0645 \u0648\u0635\u0644 \u0634\u062f\u0646 \u0628\u0631\u0642 \u0648\u0633\u0627\u06cc\u0644 \u0622\u0633\u06cc\u06cc\u0628 \u0646\u0628\u06cc\u0646\u0646\u062f \u061b \u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u062f \u0648\u0633\u0627\u06cc\u0644 \u0631\u0627 \u0627\u0632 \u0628\u0631\u0642 \u0628\u06a9\u0634\u06cc\u062f \u06cc\u0627 \u0627\u0632 \u0631\u0648\u0634 \u0647\u0627\u06cc \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u06cc\u0627 \u0627\u0632 \u06cc\u06a9 \u0645\u062d\u0627\u0641\u0638 \u062f\u0631 \u067e\u0646\u0644 \u0627\u0644\u06a9\u062a\u0631\u06cc\u06a9\u06cc \u062e\u0648\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f\u060c \u06cc\u0627 \u0648\u0633\u0627\u06cc\u0644 \u0627\u0644\u06a9\u062a\u0631\u06cc\u06a9\u06cc \u062d\u0633\u0627\u0633 \u0631\u0627 \u0628\u0647 \u06a9\u0627\u0628\u0644 \u0645\u062d\u0627\u0641\u0638\u062a \u0634\u062f\u0647 \u0645\u062a\u0635\u0644 \u06a9\u0646\u06cc\u062f.<\/p>\n<ul>\n<li>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AE%D8%A7%D9%85%D9%88%D8%B4_%DA%A9%D8%B1%D8%AF%D9%86_%DA%A9%D9%84_%D9%84%D8%A7%D9%85%D9%BE_%D9%87%D8%A7\"><\/span>\u062e\u0627\u0645\u0648\u0634 \u06a9\u0631\u062f\u0646 \u06a9\u0644 \u0644\u0627\u0645\u067e \u0647\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<\/li>\n<\/ul>\n<p>\u06cc\u0627\u062f\u062a\u0627\u0646 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0647\u0645\u0647 \u0644\u0627\u0645\u067e \u0647\u0627 \u0631\u0627 \u062e\u0627\u0645\u0648\u0634 \u0646\u06a9\u0646\u06cc\u062f. \u062d\u062a\u0645\u0627 \u0628\u0627\u06cc\u062f \u06cc\u06a9 \u0644\u0627\u0645\u067e \u062f\u0631 \u0642\u0633\u0645\u062a\u06cc \u0627\u0632 \u062e\u0627\u0646\u0647 \u0631\u0648\u0634\u0646 \u0628\u0627\u0634\u062f \u062a\u0627 \u0647\u0631 \u0648\u0642\u062a \u0628\u0631\u0642 \u0622\u0645\u062f\u060c \u0645\u062a\u0648\u062c\u0647 \u0634\u0648\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A8%D8%A7%D8%B2%D9%88_%D8%A8%D8%B3%D8%AA%D9%87_%DA%A9%D8%B1%D8%AF%D9%86_%D8%A8%DB%8C_%D8%AF%D9%84%DB%8C%D9%84_%D8%AF%D8%B1_%DB%8C%D8%AE%DA%86%D8%A7%D9%84\"><\/span>\u0628\u0627\u0632\u0648 \u0628\u0633\u062a\u0647 \u06a9\u0631\u062f\u0646 \u0628\u06cc \u062f\u0644\u06cc\u0644 \u062f\u0631 \u06cc\u062e\u0686\u0627\u0644<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0648\u0642\u062a\u06cc \u062f\u0631 \u06cc\u062e\u0686\u0627\u0644 \u06cc\u0627 \u0641\u0631\u06cc\u0632\u0631 \u0631\u0627 \u0628\u0627\u0632 \u0645\u06cc\u06a9\u0646\u06cc\u062f\u060c \u0647\u0648\u0627\u06cc \u062e\u0646\u06a9 \u0627\u0632 \u0622\u0646 \u062e\u0627\u0631\u062c \u0645\u06cc\u0634\u0648\u062f \u0648 \u062a\u0627 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0631\u0642 \u0648\u0635\u0644 \u0646\u0634\u0648\u062f \u060c\u0647\u0648\u0627\u06cc \u062f\u0631\u0648\u0646 \u06cc\u062e\u0686\u0627\u0644 \u062e\u0646\u06a9 \u0646\u0645\u06cc\u0634\u0648\u062f\u060c \u062f\u0631 \u0648\u0627\u0642\u0639 \u0647\u0648\u0627\u06cc \u0633\u0631\u062f \u062f\u0627\u062e\u0644 \u06cc\u062e\u0686\u0627\u0644 \u0631\u0627 \u0628\u0647 \u0647\u062f\u0631 \u0645\u06cc \u062f\u0647\u06cc\u062f \u0648 \u062a\u0627 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0631\u0642 \u0628\u0647 \u062f\u0633\u062a\u06af\u0627\u0647 \u0647\u0627 \u0645\u062a\u0635\u0644 \u0646\u0634\u0648\u062f \u0648 \u0645\u062f\u062a \u0632\u0645\u0627\u0646\u06cc \u0646\u06af\u0630\u0631\u062f\u060c \u06cc\u062e\u0686\u0627\u0644 \u0648 \u0641\u0631\u06cc\u0632\u0631 \u0646\u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u062e\u0646\u06a9\u06cc \u062e\u0648\u062f \u0631\u0627 \u062a\u0627\u0645\u06cc\u0646 \u06a9\u0646\u0646\u062f \u067e\u0633 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062f\u0631 \u06cc\u062e\u0686\u0627\u0644 \u0631\u0627 \u062a\u0627 \u062d\u062f \u0627\u0645\u06a9\u0627\u0646 \u0628\u0647 \u063a\u06cc\u0631 \u0627\u0632 \u0645\u0648\u0627\u0631\u062f \u0627\u0636\u0637\u0631\u0627\u0631\u06cc \u0628\u0627\u0632 \u0646\u06a9\u0646\u06cc\u062f \u062a\u0627 \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u062d\u062f\u0627\u0642\u0644 4 \u0633\u0627\u0639\u062a \u062f\u0631 \u06cc\u062e\u0686\u0627\u0644 \u0628\u0627\u0642\u06cc \u0628\u0645\u0627\u0646\u0646\u062f \u067e\u0633 \u0628\u0647 \u063a\u06cc\u0631 \u0627\u0632 \u0645\u0648\u0627\u0631\u062f \u0636\u0631\u0648\u0631\u06cc\u060c \u062f\u0631 \u06cc\u062e\u0686\u0627\u0644 \u0631\u0627 \u0628\u0627\u0632 \u0646\u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u062a\u0645\u0627\u0645 \u0627\u0646\u062c\u0645\u0627\u062f\u060c \u0646\u0632\u062f\u06cc\u06a9 \u0628\u0647 48 \u0633\u0627\u0639\u062a \u062f\u0631 \u0641\u0631\u06cc\u0632\u0631 \u0645\u06cc \u0645\u0627\u0646\u0646\u062f\u060c \u0627\u06af\u0631 \u06a9\u0627\u0645\u0644 \u0645\u0646\u062c\u0645\u062f \u0646\u0634\u062f\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u0627\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0628\u0647 24 \u0633\u0627\u0639\u062a \u06a9\u0627\u0647\u0634 \u0645\u06cc \u06cc\u0627\u0628\u062f \u0627\u06cc\u0646\u0637\u0648\u0631 \u0641\u06a9\u0631 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u0634\u0645\u0627 \u0645\u062b\u0644 \u0628\u0633\u062a\u0647 \u0647\u0627\u06cc \u06cc\u062e \u0647\u0633\u062a\u0646\u062f. \u06a9\u0644 \u0641\u0631\u06cc\u0632\u0631 \u0631\u0627 \u0639\u0627\u06cc\u0642 \u0628\u0646\u062f\u06cc \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0641\u0636\u0627\u06cc \u062e\u0627\u0644\u06cc \u062f\u0631 \u062f\u0633\u062a\u06af\u0627\u0647\u060c \u0628\u0631\u0627\u06cc \u062e\u0646\u06a9 \u06a9\u0631\u062f\u0646 \u0628\u0627\u0642\u06cc \u0646\u0645\u0627\u0646\u062f .<\/p>\n<ul>\n<li>\n<h3><span class=\"ez-toc-section\" id=\"%D9%82%D8%B1%D8%A7%D8%B1_%D8%AF%D8%A7%D8%AF%D9%86_%DA%98%D9%86%D8%B1%D8%A7%D8%AA%D9%88%D8%B1_%D8%AF%D8%B1_%D8%AF%D8%B1_%DA%AF%D8%A7%D8%B1%D8%A7%DA%98_%D9%88_%D9%85%DA%A9%D8%A7%D9%86_%DA%A9%D9%88%DA%86%DA%A9\"><\/span>\u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0646 \u0698\u0646\u0631\u0627\u062a\u0648\u0631 \u062f\u0631 \u062f\u0631 \u06af\u0627\u0631\u0627\u0698 \u0648 \u0645\u06a9\u0627\u0646 \u06a9\u0648\u0686\u06a9<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<\/li>\n<\/ul>\n<p>\u062e\u0648\u0634\u0628\u062e\u062a\u0627\u0646\u0647 \u0634\u0645\u0627 \u0645\u06cc \u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u0698\u0646\u0631\u0627\u062a\u0648\u0631 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u06a9\u0631\u0628\u0646 \u0645\u0648\u0646\u0648\u06a9\u0633\u06cc\u062f \u0633\u0645\u06cc \u0631\u0627 \u0628\u06cc\u0631\u0648\u0646 \u0628\u062f\u0647\u062f \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0627\u06cc\u062f \u0631\u0627\u0647\u06cc \u062f\u0631 \u0645\u0646\u0632\u0644 \u0628\u0631\u0627\u06cc \u0647\u0648\u0627\u06cc \u0622\u0632\u0627\u062f \u0628\u0627\u0632 \u0628\u0627\u0634\u062f \u0627\u0645\u0627 \u062d\u062a\u06cc \u0627\u06af\u0631 \u062f\u0631 \u06af\u0627\u0631\u0627\u0698 \u0631\u0627 \u0647\u0645 \u0628\u0627\u0632 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f\u060c \u0647\u0648\u0627 \u0628\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u06a9\u0627\u0641\u06cc \u0648\u0627\u0631\u062f \u0622\u0646 \u0646\u0645\u06cc \u0634\u0648\u062f. \u067e\u0633 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0627\u06cc\u0646 \u06a9\u0634\u0646\u062f\u0647 \u06cc \u062e\u0627\u0645\u0648\u0634 \u0631\u0627 \u0627\u0632 \u06af\u0627\u0631\u0627\u0698 \u062f\u0648\u0631 \u06a9\u0646\u06cc\u062f\u060c \u0632\u06cc\u0631\u0627 \u06af\u0627\u0632 \u0633\u0645\u06cc \u06a9\u0631\u0628\u0646 \u0645\u0648\u0646\u0648\u06a9\u0633\u06cc\u062f\u060c \u06cc\u06a9 \u06af\u0627\u0632 \u0628\u062f\u0648\u0646 \u0631\u0646\u06af \u0648 \u0628\u062f\u0648\u0646 \u0628\u0648 \u0627\u0633\u062a \u0648 \u06a9\u0645 \u06a9\u0645 \u0634\u0645\u0627 \u0631\u0627 \u0645\u0633\u0645\u0648\u0645 \u0645\u06cc \u06a9\u0646\u062f\u061b \u0628\u062f\u0648\u0646 \u0627\u06cc\u0646 \u06a9\u0647 \u062e\u0648\u062f\u062a\u0627\u0646 \u0622\u0646 \u0631\u0627 \u062d\u0633 \u06a9\u0646\u06cc\u062f \u067e\u0633 \u0647\u0645\u0627\u0646\u0637\u0648\u0631 \u06a9\u0647 \u0645\u06cc\u062f\u0627\u0646\u06cc\u062f \u00a0\u0698\u0646\u0631\u0627\u062a\u0648\u0631\u060c \u06a9\u0631\u0628\u0646 \u0645\u0646\u0648 \u0627\u06a9\u0633\u06cc\u062f \u0633\u0645\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u06a9\u0646\u062f\u060c \u067e\u0633 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0622\u0646 \u0631\u0627 \u062f\u0631 \u06cc\u06a9 \u0641\u0636\u0627\u06cc \u0628\u0627\u0632 \u0646\u06af\u0647 \u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f \u0686\u0631\u0627 \u06a9\u0647 \u06cc\u06a9 \u06a9\u0634\u0646\u062f\u0647 \u06cc \u0628\u06cc \u0635\u062f\u0627\u0633\u062a \u0648 \u06cc\u06a9 \u06af\u0627\u0632 \u0628\u06cc \u0631\u0646\u06af \u0648 \u0628\u0648 \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u06a9\u0646\u062f.<\/p>\n<p>\u0627\u0632 \u0622\u0646 \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u0634\u0645\u0627 \u0646\u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0698\u0646\u0631\u0627\u062a\u0648\u0631 \u0631\u0627 \u062f\u0627\u062e\u0644 \u06af\u0627\u0631\u0627\u0698 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f\u060c \u0628\u0627\u06cc\u062f \u06cc\u06a9 \u0642\u0633\u0645\u062a\u06cc \u0628\u0631\u0627\u06cc \u0627\u0645\u0646\u06cc\u062a \u0648 \u062e\u0634\u06a9 \u0646\u06af\u0647\u062f\u0627\u0634\u062a\u0646 \u0645\u062d\u06cc\u0637 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u061b \u0645\u062e\u0635\u0648\u0635\u0627\u064b \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0627\u062f \u0648 \u0628\u0631\u0641 \u0633\u0646\u06af\u06cc\u0646 \u062f\u0631 \u0631\u0627\u0647 \u0627\u0633\u062a \u060c \u0628\u0647\u062a\u0631\u06cc\u0646 \u062d\u0627\u0644\u062a \u0627\u06cc\u0646 \u0627\u0633\u062a \u06cc\u06a9 \u067e\u0646\u0627\u0647\u06af\u0627\u0647 \u0633\u0642\u0641\u06cc \u0686\u0648\u0628\u06cc \u0628\u0633\u0627\u0632\u06cc\u062f \u062a\u0627 \u062a\u0645\u0627\u0633 \u0645\u0633\u062a\u0642\u06cc\u0645 \u0628\u0627 \u0622\u0646 \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u0627\u0645\u0627 \u0645\u0631\u0627\u0642\u0628 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u067e\u0646\u0627\u0647\u06af\u0627\u0647 \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u06a9\u0648\u0686\u06a9 \u0646\u0628\u0627\u0634\u062f \u0632\u06cc\u0631\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0698\u0646\u0631\u0627\u062a\u0648\u0631 \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9 \u06a9\u0646\u0627\u0631\u0647 \u0647\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u0630\u0648\u0628 \u06a9\u0646\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33828\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/282-min-1.jpg\" alt=\"\" width=\"1400\" height=\"600\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/282-min-1.jpg 1400w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/282-min-1-300x129.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/282-min-1-1024x439.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/282-min-1-768x329.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<ul>\n<li>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B0%D8%AE%DB%8C%D8%B1%D9%87_%D9%86%DA%A9%D8%B1%D8%AF%D9%86_%D8%A2%D8%A8\"><\/span>\u0630\u062e\u06cc\u0631\u0647 \u0646\u06a9\u0631\u062f\u0646 \u0622\u0628<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<\/li>\n<\/ul>\n<p>\u0627\u0632 \u0622\u0646 \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0642\u0637\u0639 \u0628\u0631\u0642 \u0648 \u0622\u0628 \u0628\u0627 \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0645\u0631\u062a\u0628\u0637 \u0628\u0627\u0634\u062f\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0646\u0628\u0627\u06cc\u062f \u0641\u0631\u0627\u0645\u0648\u0634 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062d\u062a\u0645\u0627\u064b \u0622\u0628 \u0630\u062e\u06cc\u0631\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0632\u06cc\u0631\u0627 \u0634\u0645\u0627 \u0646\u0645\u06cc \u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u0642\u0631\u0627\u0631 \u0627\u0633\u062a \u0686\u0646\u062f \u0648\u0642\u062a \u0628\u0631\u0642 \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f. \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0647\u0631 \u0641\u0631\u062f \u062d\u062f\u0627\u0642\u0644 \u06cc\u0647 \u06af\u0627\u0644\u0646 \u0622\u0628 \u06a9\u0646\u0627\u0631 \u06af\u0630\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f .<\/p>\n<p>\u062f\u0631 \u0648\u06cc\u062f\u0626\u0648 \u06cc \u0632\u06cc\u0631 \u0639\u0644\u062a \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u0631\u0627 \u0645\u0634\u0627\u0647\u062f\u0647 \u06a9\u0646\u06cc\u062f .<\/p>\n<div class=\"h_iframe-aparat_embed_frame\"><iframe title=\"\u0639\u0644\u062a \u0642\u0637\u0639 \u0628\u0631\u0642\u061f\" src=\"https:\/\/www.aparat.com\/video\/video\/embed\/videohash\/WV0X5\/vt\/frame\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<p>\u0628\u0631\u0627\u06cc \u0645\u0637\u0627\u0644\u0639\u0647 \u06cc\u00a0 \u062f\u06cc\u06af\u0631 \u0645\u0642\u0627\u0644\u0627\u062a \u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647 \u0633\u0627\u06cc\u062a\u00a0<a href=\"https:\/\/decorshop.ir\/mag\/\">\u062f\u06a9\u0648\u0631\u0645\u06af<\/a>\u00a0\u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0632\u06cc\u0631 \u0645\u062c\u0645\u0648\u0639\u0647 \u0647\u0627\u06cc \u06a9\u0645\u067e\u0627\u0646\u06cc<a href=\"https:\/\/chenco.ir\/\" target=\"_blank\" rel=\"noopener\">\u00a0\u0686\u0634\u0645\u0647 \u0646\u0648\u0631<\/a>\u00a0\u0645\u06cc\u0628\u0627\u0634\u062f .<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0642\u0637\u0639 \u0628\u0631\u0642 \u062e\u0627\u0646\u06af\u06cc \u0642\u0637\u0639 \u0628\u0631\u0642 \u0622\u062b\u0627\u0631 \u0645\u062a\u0639\u062f\u062f \u0627\u062c\u062a\u0645\u0627\u0639\u06cc\u060c \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u0633\u06cc\u0627\u0633\u06cc \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0628\u0631\u0627\u06cc \u0622\u0646 ( \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0642\u0637\u0639 \u0628\u0631\u0642 ) \u0686\u0627\u0631\u0647 \u0627\u0646\u062f\u06cc\u0634\u06cc\u062f \u061b \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u062a\u0631\u06cc\u0646 \u0639\u0648\u0627\u0642\u0628 \u0627\u06cc\u0646 \u0642\u0637\u0639 \u0628\u0631\u0642 \u060c \u0622\u0633\u06cc\u0628 \u062f\u06cc\u062f\u0646 \u0628\u062e\u0634 \u062a\u0648\u0644\u06cc\u062f \u06a9\u0634\u0648\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0645\u062a\u0627\u0633\u0641\u0627\u0646\u0647 \u062f\u0631 \u0633\u0627\u0644\u06cc\u0627\u0646 \u06af\u0630\u0634\u062a\u0647 \u0647\u0645\u0648\u0627\u0631\u0647 \u0628\u062e\u0634 \u062a\u0648\u0644\u06cc\u062f \u0628\u0648\u062f\u0647 \u06a9\u0647 \u0642\u0631\u0628\u0627\u0646\u06cc \u0628\u062e\u0634 \u067e\u0631\u0645\u0635\u0631\u0641 \u0628\u0631\u0642 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":33830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,59],"tags":[214,224,218],"class_list":["post-33823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-34","category-59","tag-214","tag-224","tag-218"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/33823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=33823"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/33823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/33830"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=33823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=33823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=33823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}