{"id":33803,"date":"2021-07-07T14:57:25","date_gmt":"2021-07-07T10:27:25","guid":{"rendered":"https:\/\/decorshop.ir\/mag\/?p=33803"},"modified":"2023-04-27T11:57:46","modified_gmt":"2023-04-27T08:27:46","slug":"%d8%a2%d8%b3%db%8c%d8%a8-%d9%87%d8%a7%db%8c-%d9%82%d8%b7%d8%b9%db%8c-%d8%a8%d8%b1%d9%82-%d8%b1%d9%88%db%8c-%d9%84%d9%88%d8%a7%d8%b2%d9%85-%d9%85%d9%86%d8%b2%d9%84","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b3%db%8c%d8%a8-%d9%87%d8%a7%db%8c-%d9%82%d8%b7%d8%b9%db%8c-%d8%a8%d8%b1%d9%82-%d8%b1%d9%88%db%8c-%d9%84%d9%88%d8%a7%d8%b2%d9%85-%d9%85%d9%86%d8%b2%d9%84\/","title":{"rendered":"\u0622\u0633\u06cc\u0628 \u0647\u0627\u06cc \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u0631\u0648\u06cc \u0644\u0648\u0627\u0632\u0645 \u0645\u0646\u0632\u0644"},"content":{"rendered":"<p>\u0637\u06cc \u0631\u0648\u0632 \u0647\u0627\u06cc \u0627\u062e\u06cc\u0631 \u062f\u0631 \u0633\u0627\u0639\u0627\u062a \u0645\u062e\u062a\u0644\u0641 \u0634\u0627\u0647\u062f \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0634\u0647\u0631 \u0647\u0627 \u0628\u0648\u062f\u06cc\u0645. \u0627\u06cc\u0646 \u0627\u062a\u0641\u0627\u0642 \u0627\u06af\u0631 \u0686\u0647 \u0628\u0631 \u0631\u0648\u06cc \u0632\u0646\u062f\u06af\u06cc \u0631\u0648\u0632\u0645\u0631\u0647 \u0648 \u06a9\u0627\u0631 \u0647\u0627\u06cc \u0631\u0648\u0632\u0627\u0646\u0647 \u062a\u0627\u062b\u06cc\u0631 \u0645\u06cc \u06af\u0630\u0627\u0631\u062f \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627\u0639\u062b \u0628\u0631\u0648\u0632 \u062e\u0633\u0627\u0631\u062a \u0628\u0647 \u0644\u0648\u0627\u0632\u0645 \u0628\u0631\u0642\u06cc \u0634\u0648\u062f\u00a0 \u060c \u0628\u0627 \u067e\u06cc\u0634\u0631\u0641\u062a \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u0648 \u0635\u0646\u0639\u062a \u0633\u0627\u062e\u062a \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc \u0627\u0645\u0631\u0648\u0632\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0645\u062f\u0631\u0646 \u062a\u0631 \u0648 \u0642\u0627\u0628\u0644 \u0642\u06cc\u0627\u0633 \u0628\u0627 \u0632\u0646\u062f\u06af\u06cc \u062f\u0631 \u06af\u0630\u0634\u062a\u0647 \u0646\u06cc\u0633\u062a. \u0627\u06cc\u0646 \u062a\u063a\u06cc\u06cc\u0631 \u0648 \u062a\u062d\u0648\u0644 \u0628\u0627\u0639\u062b \u0634\u062f \u062a\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0644\u0648\u0627\u0632\u0645 \u062e\u0627\u0646\u06af\u06cc \u0628\u062f\u0648\u0646 \u0628\u0631\u0642 \u0648 \u0627\u0644\u06a9\u062a\u0631\u06cc\u0633\u06cc\u062a\u0647 \u0645\u06cc\u0633\u0631 \u0646\u0628\u0627\u0634\u062f \u0648 \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u062f\u0631 \u0633\u0637\u062d \u0634\u0647\u0631 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a\u06cc \u0631\u0627 \u0628\u0647 \u0648\u062c\u0648\u062f \u062e\u0648\u0627\u0647\u062f \u0622\u0648\u0631\u062f.<strong>\u00a0\u062a\u0627\u062b\u06cc\u0631 \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u0628\u0631 \u0644\u0648\u0627\u0632\u0645 \u062e\u0627\u0646\u06af\u06cc<\/strong>\u00a0\u0628\u0633\u06cc\u0627\u0631 \u0645\u0647\u0645 \u0627\u0633\u062a \u0648 \u0646\u0645\u06cc \u062a\u0648\u0627\u0646 \u0627\u0632 \u0622\u0646 \u0686\u0634\u0645 \u067e\u0648\u0634\u06cc \u06a9\u0631\u062f.<\/p>\n<p>\u0647\u0645\u0627\u0646\u0637\u0648\u0631 \u06a9\u0647 \u0645\u06cc\u062f\u0627\u0646\u06cc\u062f \u0628\u0633\u06cc\u0627\u0631\u06cc\u00a0 \u0627\u0632\u0644\u0648\u0627\u0632\u0645 \u0645\u0646\u0632\u0644\u00a0 \u00a0\u0628\u0647 \u0648\u0633\u06cc\u0644\u0647 \u0628\u0631\u0642 \u06a9\u0627\u0631 \u0645\u06cc \u06a9\u0646\u0646\u062f \u0648 \u062f\u0631 \u067e\u06cc \u0642\u0637\u0639 \u0648 \u0648\u0635\u0644 \u0634\u062f\u0646 \u0628\u0631\u0642 \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u06a9\u0631\u0631 \u0627\u062d\u062a\u0645\u0627\u0644 \u0622\u0633\u06cc\u0628 \u062f\u06cc\u062f\u0646 \u0622\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u0648 \u0627\u0632 \u0622\u0646\u062c\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u06cc\u0646 \u0622\u0633\u06cc\u0628 \u062c\u0628\u0631\u0627\u0646 \u0646\u0627\u067e\u0630\u06cc\u0631 \u0628\u0627\u0634\u062f \u0648 \u0634\u0645\u0627 \u0628\u0631\u0627\u06cc \u0647\u0645\u06cc\u0634\u0647 \u062f\u0633\u062a\u06af\u0627\u0647 \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u0628\u062f\u0647\u06cc\u062f \u0648 \u06cc\u0627 \u062d\u062a\u06cc \u062f\u0686\u0627\u0631 \u0647\u0632\u06cc\u0646\u0647 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u062a\u0639\u0645\u06cc\u0631 \u0648 \u06cc\u0627 \u062e\u0631\u06cc\u062f \u0645\u062c\u062f\u062f \u0627\u06cc\u0646 \u0644\u0648\u0627\u0632\u0645 \u0634\u0648\u06cc\u062f \u061b \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0642\u0635\u062f \u062f\u0627\u0631\u06cc\u0645 \u0646\u06a9\u0627\u062a\u06cc \u06a9\u0647 \u0628\u0627\u0639\u062b \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0635\u062f\u0645\u0647 \u062f\u06cc\u062f\u0646 \u0627\u06cc\u0646 \u0644\u0648\u0627\u0632\u0645 \u0645\u06cc\u0634\u0648\u0646\u062f \u0631\u0627 \u0645\u0639\u0631\u0641\u06cc \u06a9\u0646\u06cc\u0645 .<\/p>\n<p>\u0647\u0641\u062a\u0647 \u06af\u0630\u0634\u062a\u0647 \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u062f\u0631 \u0627\u06cc\u0646 \u0647\u0641\u062a\u0647 \u062c\u062f\u0648\u0644 \u0632\u0645\u0627\u0646\u0628\u0646\u062f\u06cc \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u062f\u0631 \u062a\u0647\u0631\u0627\u0646\u060c \u0627\u0635\u0641\u0647\u0627\u0646\u060c \u062a\u0628\u0631\u06cc\u0632\u060c \u0627\u0631\u0627\u06a9\u060c \u0645\u0634\u0647\u062f \u0648 \u0631\u0648\u0645\u06cc\u0647 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f. \u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u06cc\u0646\u00a0\u062c\u062f\u0648\u0644 \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u0627\u0644\u0628\u0631\u0632 \u0648 \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u062f\u0631 \u062f\u06cc\u06af\u0631 \u0634\u0647\u0631 \u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u06a9\u0634\u0648\u0631 \u0628\u0647 \u0635\u0648\u0631\u062a \u0627\u062d\u062a\u0645\u0627\u0644\u06cc \u0645\u0634\u062e\u0635 \u0634\u062f\u0647 \u0648 \u0645\u0631\u062f\u0645 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u062c\u062f\u0648\u0644 \u0632\u0645\u0627\u0646\u0628\u0646\u062f\u06cc \u0642\u0637\u0639 \u0628\u0631\u0642\u060c \u0628\u0631\u0646\u0627\u0645\u0647 \u0631\u06cc\u0632\u06cc \u0648 \u06a9\u0627\u0631 \u0647\u0627\u06cc \u0631\u0648\u0632\u0627\u0646\u0647 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u06af\u0648\u0646\u0647 \u0627\u06cc \u0647\u0645\u0627\u0647\u0646\u06af \u06a9\u0646\u0646\u062f \u062a\u0627 \u0628\u0627 \u0645\u0634\u06a9\u0644 \u0645\u0648\u0627\u062c\u0647 \u0646\u0634\u0648\u0646\u062f .<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b3%db%8c%d8%a8-%d9%87%d8%a7%db%8c-%d9%82%d8%b7%d8%b9%db%8c-%d8%a8%d8%b1%d9%82-%d8%b1%d9%88%db%8c-%d9%84%d9%88%d8%a7%d8%b2%d9%85-%d9%85%d9%86%d8%b2%d9%84\/#%D9%86%D9%85%D9%88%D9%86%D9%87_%D9%87%D8%A7%DB%8C%DB%8C_%D8%A7%D8%B2_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%87%D8%A7%DB%8C_%D9%82%D8%B7%D8%B9%DB%8C_%D8%A8%D8%B1%D9%82\" >\u0646\u0645\u0648\u0646\u0647 \u0647\u0627\u06cc\u06cc \u0627\u0632 \u0622\u0633\u06cc\u0628 \u0647\u0627\u06cc \u0642\u0637\u0639\u06cc \u0628\u0631\u0642<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b3%db%8c%d8%a8-%d9%87%d8%a7%db%8c-%d9%82%d8%b7%d8%b9%db%8c-%d8%a8%d8%b1%d9%82-%d8%b1%d9%88%db%8c-%d9%84%d9%88%d8%a7%d8%b2%d9%85-%d9%85%d9%86%d8%b2%d9%84\/#%D8%B1%D8%A7%D9%87_%DA%A9%D8%A7%D8%B1_%D9%87%D8%A7%DB%8C_%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%84%D9%88%D8%A7%D8%B2%D9%85_%D9%85%D9%86%D8%B2%D9%84_%D8%AF%D8%B1_%D8%A8%D8%B1%D8%A7%D8%A8%D8%B1_%D9%82%D8%B7%D8%B9%DB%8C_%D8%A8%D8%B1%D9%82\" >\u0631\u0627\u0647 \u06a9\u0627\u0631 \u0647\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0622\u0633\u06cc\u0628 \u0644\u0648\u0627\u0632\u0645 \u0645\u0646\u0632\u0644 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0642\u0637\u0639\u06cc \u0628\u0631\u0642<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b3%db%8c%d8%a8-%d9%87%d8%a7%db%8c-%d9%82%d8%b7%d8%b9%db%8c-%d8%a8%d8%b1%d9%82-%d8%b1%d9%88%db%8c-%d9%84%d9%88%d8%a7%d8%b2%d9%85-%d9%85%d9%86%d8%b2%d9%84\/#%D8%AF%D8%B3%D8%AA%DA%AF%D8%A7%D9%87_%D8%A7%D8%B3%D8%AA%D8%A7%D8%A8%D9%84%D8%A7%DB%8C%D8%B2%D8%B1\" >\u062f\u0633\u062a\u06af\u0627\u0647 \u0627\u0633\u062a\u0627\u0628\u0644\u0627\u06cc\u0632\u0631<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b3%db%8c%d8%a8-%d9%87%d8%a7%db%8c-%d9%82%d8%b7%d8%b9%db%8c-%d8%a8%d8%b1%d9%82-%d8%b1%d9%88%db%8c-%d9%84%d9%88%d8%a7%d8%b2%d9%85-%d9%85%d9%86%d8%b2%d9%84\/#%D8%AC%D8%B9%D8%A8%D9%87_%D9%81%DB%8C%D9%88%D8%B2\" >\u062c\u0639\u0628\u0647 \u0641\u06cc\u0648\u0632<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b3%db%8c%d8%a8-%d9%87%d8%a7%db%8c-%d9%82%d8%b7%d8%b9%db%8c-%d8%a8%d8%b1%d9%82-%d8%b1%d9%88%db%8c-%d9%84%d9%88%d8%a7%d8%b2%d9%85-%d9%85%d9%86%d8%b2%d9%84\/#%D8%AF%D8%B3%D8%AA%DA%AF%D8%A7%D9%87_UPS\" >\u062f\u0633\u062a\u06af\u0627\u0647 UPS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/decorshop.ir\/mag\/%d8%a2%d8%b3%db%8c%d8%a8-%d9%87%d8%a7%db%8c-%d9%82%d8%b7%d8%b9%db%8c-%d8%a8%d8%b1%d9%82-%d8%b1%d9%88%db%8c-%d9%84%d9%88%d8%a7%d8%b2%d9%85-%d9%85%d9%86%d8%b2%d9%84\/#%D8%AF%D8%B3%D8%AA%DA%AF%D8%A7%D9%87_GFCI\" >\u062f\u0633\u062a\u06af\u0627\u0647 GFCI<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D9%86%D9%85%D9%88%D9%86%D9%87_%D9%87%D8%A7%DB%8C%DB%8C_%D8%A7%D8%B2_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%87%D8%A7%DB%8C_%D9%82%D8%B7%D8%B9%DB%8C_%D8%A8%D8%B1%D9%82\"><\/span>\u0646\u0645\u0648\u0646\u0647 \u0647\u0627\u06cc\u06cc \u0627\u0632 \u0622\u0633\u06cc\u0628 \u0647\u0627\u06cc \u0642\u0637\u0639\u06cc \u0628\u0631\u0642<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0646\u0648\u0633\u0627\u0646\u0627\u062a \u0628\u0631\u0642 \u062f\u0631 \u0645\u0646\u0632\u0644 \u06af\u0627\u0647\u06cc \u0628\u0647 \u0635\u0648\u0631\u062a \u0622\u0646\u06cc \u0642\u0627\u0628\u0644 \u0645\u0634\u0627\u0647\u062f\u0647 \u0627\u0633\u062a \u0628\u0647 \u0637\u0648\u0631 \u0645\u062b\u0627\u0644 \u0633\u0648\u062e\u062a\u0646 \u0648\u0633\u0627\u06cc\u0644 \u0628\u0631\u0642\u06cc\u060c \u0622\u062a\u0634 \u06af\u0631\u0641\u062a\u0646 \u0644\u0648\u0627\u0632\u0645 \u062e\u0627\u0646\u06af\u06cc \u0648 \u06cc\u0627 \u0633\u0648 \u0633\u0648 \u0632\u062f\u0646 \u0644\u0627\u0645\u067e \u0647\u0627 \u0627\u0632 \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u06cc \u0646\u0648\u0633\u0627\u0646 \u0628\u0631\u0642 \u062f\u0631 \u0645\u0646\u0632\u0644 \u0627\u0633\u062a. \u0627\u0645\u0627 \u0628\u0631\u062e\u06cc \u0627\u0648\u0642\u0627\u062a \u0646\u0634\u0627\u0646\u0647 \u0647\u0627 \u0631\u0627 \u0646\u0645\u06cc \u062a\u0648\u0627\u0646 \u0645\u0634\u0627\u0647\u062f \u06a9\u0631\u062f \u0627\u0645\u0627 \u0628\u0647 \u0645\u0631\u0648\u0631 \u0632\u0645\u0627\u0646 \u0628\u0647 \u062f\u0633\u062a\u06af\u0627\u0647 \u0622\u0633\u06cc\u0628 \u0648\u0627\u0631\u062f \u0645\u06cc \u06a9\u0646\u062f \u0648\u0644\u06cc \u0628\u0627 \u0686\u0646\u062f \u0631\u0648\u0634 \u0628\u0647\u00a0\u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0646\u0648\u0633\u0627\u0646 \u0628\u0631\u0642\u00a0\u067e\u0631\u062f\u0627\u062e\u062a.<\/p>\n<p>\u0627\u0632 \u0622\u0633\u06cc\u0628 \u0647\u0627\u06cc \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u0645\u06cc\u062a\u0648\u0627\u0646 \u0628\u0647 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u062c\u0631\u06cc\u0627\u0646 \u0628\u0631\u0642 \u0628\u0647 \u0627\u0635\u0637\u0644\u0627\u062d \u0627\u0641\u062a \u067e\u06cc\u062f\u0627 \u0645\u06cc \u06a9\u0646\u062f \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f \u06a9\u0647 \u0644\u0648\u0627\u0632\u0645 \u0645\u0646\u0632\u0644 \u0647\u0645\u0627\u0646\u0646\u062f \u06cc\u062e\u0686\u0627\u0644 \u0648 \u06cc\u0627 \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646 \u0648 \u06cc\u0627 \u062d\u062a\u06cc \u0644\u0648\u0633\u062a\u0631\u0647\u0627 \u0646\u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0645\u0642\u062f\u0627\u0631 \u06a9\u0627\u0641\u06cc \u0628\u0631\u0642 \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u0631\u0627 \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u0646\u062f \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u062c\u0631\u06cc\u0627\u0646 \u062f\u0627\u062e\u0644 \u0633\u06cc\u0645 \u0647\u0627 \u062a\u0645\u0627\u06cc\u0644 \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0627\u0631\u062f \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0628\u0627\u0639\u062b \u0645\u06cc \u0634\u0648\u062f \u062a\u0627 \u0628\u0631\u062e\u06cc \u0627\u0632 \u0642\u0637\u0639\u0627\u062a \u062d\u06cc\u0627\u062a\u06cc \u062f\u0633\u062a\u06af\u0627\u0647 \u0622\u0633\u06cc\u0628 \u0628\u0628\u06cc\u0646\u0646\u062f\u0648 \u0627\u0632 \u0637\u0631\u0641\u06cc \u0642\u0637\u0639 \u0628\u0631\u0642 \u0648 \u06cc\u0627 \u0627\u0641\u062a \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u062c\u0631\u06cc\u0627\u0646 \u0645\u0642\u0627\u0648\u0645\u062a \u0633\u06cc\u0645 \u0647\u0627 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc \u062f\u0647\u062f \u0648 \u0627\u062d\u062a\u0645\u0627\u0644 \u0627\u062a\u0635\u0627\u0644 \u06a9\u0648\u062a\u0627\u0647 \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc \u062f\u0647\u062f \u061b\u00a0 \u0648\u0642\u062a\u06cc \u06a9\u0647 \u0622\u0645\u067e\u0631 \u06a9\u0645 \u0648 \u0634\u062f\u062a \u062c\u0631\u06cc\u0627\u0646 \u0632\u06cc\u0627\u062f \u0634\u0648\u062f \u062f\u0645\u0627\u06cc \u0642\u0637\u0639\u0627\u062a \u0644\u0648\u0627\u0632\u0645 \u062e\u0627\u0646\u06af\u06cc \u0628\u0627\u0644\u0627 \u0645\u06cc \u0631\u0648\u062f \u0648 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0630\u0648\u0628 \u0634\u0648\u0646\u062f.<\/p>\n<p>\u0627\u0644\u0628\u062a\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0644\u0648\u0627\u0632\u0645 \u0645\u0646\u0632\u0644 \u0647\u0627\u06cc \u0627\u0645\u0631\u0648\u0632\u06cc \u0628\u0647 \u06af\u0648\u0646\u0647 \u0627\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0646\u062f \u06a9\u0647 \u0642\u0627\u062f\u0631 \u0628\u0647 \u06a9\u0646\u062a\u0631\u0644 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0648 \u06a9\u0627\u0647\u0634 \u062c\u0631\u06cc\u0627\u0646 \u0628\u0631\u0642 \u0647\u0633\u062a\u0646\u062f \u061b\u00a0 \u0627\u0644\u0628\u062a\u0647 \u0644\u0627\u0632\u0645 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u0645\u06cc\u0632\u0627\u0646 \u062d\u0633\u0627\u0633\u06cc\u062a \u0644\u0648\u0627\u0632\u0645 \u0645\u0646\u0632\u0644\u00a0 \u0628\u0647 \u0646\u0648\u0633\u0627\u0646 \u0628\u0631\u0642 \u06cc\u06a9\u0633\u0627\u0646 \u0646\u06cc\u0633\u062a \u0648 \u062f\u0633\u062a\u06af\u0627\u0647 \u0647\u0627\u06cc \u06a9\u0646\u062a\u0631\u0644 \u06a9\u0646\u0646\u062f\u0647 \u0647\u0627\u06cc \u0627\u062e\u062a\u0635\u0627\u0635\u06cc \u0644\u0648\u0627\u0632\u0645 \u062e\u0627\u0646\u06af\u06cc \u062a\u0646\u0647\u0627\u06cc \u0645\u062d\u062f\u0648\u062f\u0647 \u0645\u0634\u062e\u0635\u06cc \u0627\u0632 \u0646\u0648\u0633\u0627\u0646\u0627\u062a \u0631\u0627 \u06a9\u0646\u062a\u0631\u0644 \u0645\u06cc \u0646\u0645\u0627\u06cc\u0646\u062f \u067e\u0633 \u0646\u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647 \u0622\u0646\u0647\u0627 \u0627\u06a9\u062a\u0641\u0627 \u06a9\u0631\u062f.<\/p>\n<p>\u0628\u0631\u062e\u06cc \u0627\u0632 \u0644\u0648\u0627\u0632\u0645 \u0645\u0646\u0632\u0644 \u0647\u0645\u0627\u0646\u0646\u062f\u0627\u062c\u0627\u0642 \u06af\u0627\u0632\u00a0 \u060c \u06a9\u0648\u0644\u0631 \u060c \u0645\u0627\u0634\u06cc\u0646 \u0638\u0631\u0641\u0634\u0648\u06cc\u06cc \u0648 \u0627\u0645\u062b\u0627\u0644 \u0627\u06cc\u0646 \u0644\u0648\u0627\u0632\u0645 \u0647\u0627 \u060c\u00a0 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u062e\u0627\u0645\u0648\u0634 \u0647\u0633\u062a\u0646\u062f \u0628\u0631\u0642 \u062f\u0631 \u0622\u0646\u0647\u0627 \u062c\u0631\u06cc\u0627\u0646 \u0646\u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647 \u0646\u0648\u0633\u0627\u0646 \u0628\u0631\u0642 \u0628\u0631 \u0631\u0648\u06cc \u0622\u0646\u0647\u0627 \u062a\u0627\u062b\u06cc\u0631\u06cc \u0646\u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a \u060c \u0627\u0645\u0627 \u0648\u0633\u06cc\u0644\u0647 \u0627\u06cc \u0647\u0645\u0627\u0646\u0646\u062f \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646 \u062d\u062a\u06cc \u0627\u06af\u0631 \u062e\u0627\u0645\u0648\u0634 \u0628\u0627\u0634\u062f \u0646\u06cc\u0632 \u0628\u0631\u0642 \u062f\u0627\u062e\u0644 \u0622\u0646 \u062f\u0631 \u062c\u0631\u06cc\u0627\u0646 \u0627\u0633\u062a \u0645\u06af\u0631 \u0622\u0646\u06a9\u0647 \u0628\u0647 \u0628\u0631\u0642 \u0648\u0635\u0644 \u0646\u0628\u0627\u0634\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B1%D8%A7%D9%87_%DA%A9%D8%A7%D8%B1_%D9%87%D8%A7%DB%8C_%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%84%D9%88%D8%A7%D8%B2%D9%85_%D9%85%D9%86%D8%B2%D9%84_%D8%AF%D8%B1_%D8%A8%D8%B1%D8%A7%D8%A8%D8%B1_%D9%82%D8%B7%D8%B9%DB%8C_%D8%A8%D8%B1%D9%82\"><\/span>\u0631\u0627\u0647 \u06a9\u0627\u0631 \u0647\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0622\u0633\u06cc\u0628 \u0644\u0648\u0627\u0632\u0645 \u0645\u0646\u0632\u0644 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0642\u0637\u0639\u06cc \u0628\u0631\u0642<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B3%D8%AA%DA%AF%D8%A7%D9%87_%D8%A7%D8%B3%D8%AA%D8%A7%D8%A8%D9%84%D8%A7%DB%8C%D8%B2%D8%B1\"><\/span>\u062f\u0633\u062a\u06af\u0627\u0647 \u0627\u0633\u062a\u0627\u0628\u0644\u0627\u06cc\u0632\u0631<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<\/li>\n<\/ul>\n<p>\u062a\u0647\u06cc\u0647 \u062f\u0633\u062a\u06af\u0627\u0647 \u0627\u0633\u062a\u0627\u0628\u0644\u0627\u06cc\u0632\u0631 \u06cc\u0627 \u0628\u0647 \u0627\u0635\u0637\u0644\u0627\u062d \u062a\u062b\u0628\u06cc\u062a \u06a9\u0646\u0646\u062f\u0647 \u0633\u0627\u062f\u0647 \u062a\u0631\u06cc\u0646 \u06a9\u0627\u0631 \u062f\u0631 \u062c\u0647\u062a \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0633\u0648\u062e\u062a\u0646 \u0648\u0633\u0627\u06cc\u0644 \u0628\u0631\u0642\u06cc \u0648 \u0646\u0648\u0633\u0627\u0646 \u0628\u0631\u0642 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u062f\u0633\u062a\u06af\u0627\u0647 \u0648\u0633\u0627\u06cc\u0644\u0647 \u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0647\u0631 \u0644\u062d\u0638\u0647 \u0648\u0644\u062a\u0627\u0698 \u0628\u0631\u0642 \u0648\u0631\u0648\u062f\u06cc \u0631\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u06af\u06cc\u0631\u06cc \u06a9\u0631\u062f\u0647 \u0648 \u062f\u0631 \u0635\u0648\u0631\u062a \u0645\u0634\u0627\u0647\u062f\u0647 \u0627\u0641\u062a \u0648 \u06cc\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062c\u0631\u06cc\u0627\u0646 \u0633\u0631\u06cc\u0639\u0627 \u0648\u0644\u062a\u0627\u0698 \u0648 \u062c\u0631\u06cc\u0627\u0646 \u0642\u0627\u0628\u0644 \u0642\u0628\u0648\u0644\u06cc \u0631\u0627 \u0628\u0647 \u062f\u0633\u062a\u06af\u0627\u0647 \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u0645\u0646\u062a\u0642\u0644 \u0645\u06cc \u06a9\u0646\u062f \u062a\u0627 \u0646\u0648\u0633\u0627\u0646 \u0628\u0631\u0642 \u062a\u0627\u062b\u06cc\u0631\u06cc \u0628\u0631 \u0644\u0648\u0627\u0632\u0645 \u062e\u0627\u0646\u06af\u06cc \u0634\u0645\u0627 \u0646\u06af\u0630\u0627\u0631\u062f \u060c \u0627\u0644\u0628\u062a\u0647\u00a0 \u0627\u0633\u062a\u0627\u0628\u0644\u0627\u06cc\u0632\u0631 \u06a9\u0647 \u0628\u0647 \u0646\u0627\u0645 \u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u0647\u0645\u0627\u0646\u0646\u062f \u062a\u0631\u0627\u0646\u0633 \u0627\u062a\u0648\u0645\u0627\u062a\u06cc\u06a9 \u0648 \u06cc\u0627 \u062a\u0631\u0627\u0646\u0633 \u0627\u0641\u0632\u0627\u06cc\u0646\u062f\u0647 \u0628\u0631\u0642 \u0645\u06cc \u0634\u0646\u0627\u0633\u0646\u062f \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u062d\u0627\u0641\u0638 \u0628\u0631\u0642 \u0644\u0648\u0627\u0632\u0645 \u062e\u0627\u0646\u06af\u06cc \u0628\u0647 \u0634\u0645\u0627\u0631 \u0645\u06cc \u0622\u06cc\u062f.<\/p>\n<p>\u062a\u0641\u0627\u0648\u062a \u0622\u0646 \u0628\u0627 \u0628\u0627\u0642\u06cc \u0645\u062d\u0627\u0641\u0638\u062a \u0647\u0627\u06cc \u0628\u0631\u0642 \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u062f\u0631 \u062f\u0642\u062a \u0628\u0627\u0644\u0627 \u062f\u0631 \u0627\u0646\u062f\u0627\u0632\u0647 \u06af\u06cc\u0631\u06cc \u0648\u0644\u062a\u0627\u0698 \u0627\u0633\u062a. \u062a\u0641\u0627\u0648\u062a \u0622\u0646 \u0628\u0627 \u0645\u062d\u0627\u0641\u0638 \u0647\u0627\u06cc \u0645\u0639\u0645\u0648\u0644\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0627\u0633\u062a\u0627\u0628\u0644\u0627\u06cc\u0632\u0631 \u0628\u0647 \u0645\u062d\u0636 \u0642\u0637\u0639 \u0648 \u06cc\u0627 \u0627\u0641\u062a \u062c\u0631\u06cc\u0627\u0646\u060c \u0648\u0644\u062a\u0627\u0698 \u0631\u0627 \u06a9\u0646\u062a\u0631\u0644 \u0645\u06cc \u0646\u0645\u0627\u06cc\u0646\u062f \u0648 \u062d\u062f\u0627\u0642\u0644 \u062c\u0631\u06cc\u0627\u0646 \u0645\u0645\u06a9\u0646 \u0631\u0627 \u0628\u0647 \u062f\u0633\u062a\u06af\u0627\u0647 \u0645\u06cc \u0631\u0633\u0627\u0646\u062f \u0648 \u0627\u0644\u0628\u062a\u0647 \u062f\u0631 \u0635\u0648\u0631\u062a \u0642\u0637\u0639 \u0634\u062f\u0646 \u0628\u0631\u0642 \u062c\u0631\u06cc\u0627\u0646 \u0631\u0627 \u0628\u0647 \u0622\u0631\u0627\u0645\u06cc \u06a9\u0627\u0647\u0634 \u0645\u06cc \u062f\u0647\u062f \u0648 \u0628\u0647 \u0637\u0648\u0631 \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u062f\u0633\u062a\u06af\u0627\u0647 \u0631\u0627 \u062e\u0627\u0645\u0648\u0634 \u0646\u0645\u06cc \u06a9\u0646\u062f \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0645\u062d\u0627\u0641\u0638 \u0628\u0631\u0642 \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646 \u060c \u0645\u062d\u0627\u0641\u0638 \u0648\u0644\u062a\u0627\u0698 \u06cc\u062e\u0686\u0627\u0644 \u0648 \u062f\u0633\u062a\u06af\u0627\u0647 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0646\u0648\u0633\u0627\u0646 \u0628\u0631\u0642 \u0647\u0633\u062a\u06cc\u062f \u0627\u0633\u062a\u0627\u0628\u0644\u0627\u06cc\u0632\u0631 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u062d\u0627\u0641\u0638 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u062f\u0631 \u0644\u0648\u0627\u0632\u0645 \u0645\u0646\u0632\u0644 \u0627\u0633\u062a.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33804\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/280-min.jpg\" alt=\"\" width=\"1400\" height=\"600\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/280-min.jpg 1400w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/280-min-300x129.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/280-min-1024x439.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/280-min-768x329.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<ul>\n<li>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AC%D8%B9%D8%A8%D9%87_%D9%81%DB%8C%D9%88%D8%B2\"><\/span>\u062c\u0639\u0628\u0647 \u0641\u06cc\u0648\u0632<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<\/li>\n<\/ul>\n<p>\u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0648\u0633\u0627\u06cc\u0644 \u0647\u0627\u06cc \u0646\u0648\u0633\u0627\u0646 \u06af\u06cc\u0631 \u0628\u0631\u0642 \u062e\u0627\u0646\u06af\u06cc \u062c\u0639\u0628\u0647 \u0641\u06cc\u0648\u0632 \u0627\u0633\u062a \u060c \u062c\u0639\u0628\u0647 \u0641\u06cc\u0648\u0632 \u0627\u0632 \u0646\u0648\u0633\u0627\u0646 \u0628\u0631\u0642 \u06a9\u0644 \u0633\u0627\u062e\u062a\u0645\u0627\u0646 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0645\u06cc \u06a9\u0646\u062f \u0648 \u0628\u0647 \u06a9\u0645\u06a9 \u0627\u06cc\u0646 \u062f\u0633\u062a\u06af\u0627\u0647 \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0644\u0648\u0627\u0632\u0645 \u062e\u0627\u0646\u06af\u06cc\u060c \u0627\u0632 \u062a\u0645\u0627\u0645\u06cc \u0648\u0633\u0627\u06cc\u0644 \u0628\u0631\u0642\u06cc \u0627\u0639\u0645 \u0627\u0632 \u0644\u0627\u0645\u067e \u0647\u0627\u060c \u0632\u0646\u06af \u062f\u0631\u0628 \u0648 \u062d\u062a\u06cc \u062f\u0631\u0628 \u0647\u0627\u06cc \u0631\u06cc\u0645\u0648\u062a \u062f\u0627\u0631 \u067e\u0627\u0631\u06a9\u06cc\u0646\u06af \u0645\u062d\u0627\u0641\u0638\u062a \u0645\u06cc \u0634\u0648\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33805\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/281-min.jpg\" alt=\"\" width=\"1400\" height=\"600\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/281-min.jpg 1400w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/281-min-300x129.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/281-min-1024x439.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/281-min-768x329.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<ul>\n<li>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B3%D8%AA%DA%AF%D8%A7%D9%87_UPS\"><\/span>\u062f\u0633\u062a\u06af\u0627\u0647 UPS<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<\/li>\n<\/ul>\n<p>\u0634\u0627\u06cc\u062f \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0647\u0645 \u067e\u06cc\u0634 \u0622\u0645\u062f\u0647 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0628\u0639\u062f \u0627\u0632 \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u0628\u0627 \u062e\u0648\u062f \u0628\u06af\u0648\u06cc\u06cc\u062f \u06a9\u0627\u0634 \u0641\u0631\u0635\u062a \u062f\u0627\u0634\u062a\u06cc\u062f \u062a\u0627 \u0648\u0633\u0627\u06cc\u0644 \u0628\u0631\u0642\u06cc \u0631\u0627 \u0627\u0632 \u067e\u0631\u06cc\u0632 \u062c\u062f\u0627 \u0645\u06cc \u06a9\u0631\u062f\u06cc\u062f \u062a\u0627 \u0622\u0633\u06cc\u0628 \u0646\u0628\u06cc\u0646\u0646\u062f \u060c\u00a0 \u0628\u0631\u0627\u06cc \u0631\u0641\u0639 \u0627\u06cc\u0646 \u0645\u0634\u06a9\u0644 \u06cc\u06a9 \u062f\u0633\u062a\u06af\u0627\u0647 \u0628\u0627 \u0639\u0646\u0648\u0627\u0646 UPS \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0639\u0631\u0636\u0647 \u0645\u06cc \u0634\u0648\u062f \u06a9\u0647 \u0628\u0639\u062f \u0627\u0632 \u0631\u0641\u062a\u0646 \u0628\u0631\u0642 \u0628\u0647 \u0628\u0647 \u06a9\u0645\u06a9 \u06cc\u06a9 \u0628\u0627\u062a\u0631\u06cc \u06a9\u0645\u06a9\u06cc \u0686\u0646\u062f\u06cc\u0646 \u062f\u0642\u06cc\u0642\u0647 \u062c\u0631\u06cc\u0627\u0646 \u0628\u0631\u0642 \u0631\u0627 \u0628\u0647 \u0648\u0633\u06cc\u0644\u0647 \u0628\u0627\u062a\u0631\u06cc \u062d\u0641\u0638 \u0645\u06cc \u06a9\u0646\u062f \u062a\u0627 \u0641\u0631\u0635\u062a \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0648\u0633\u0627\u06cc\u0644 \u0631\u0627 \u062e\u0627\u0645\u0648\u0634 \u0648 \u0627\u0632 \u0628\u0631\u0642 \u0628\u06a9\u0634\u06cc\u062f<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33807\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/282-min.jpg\" alt=\"\" width=\"1400\" height=\"600\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/282-min.jpg 1400w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/282-min-300x129.jpg 300w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/282-min-1024x439.jpg 1024w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2021\/07\/282-min-768x329.jpg 768w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<ul>\n<li>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B3%D8%AA%DA%AF%D8%A7%D9%87_GFCI\"><\/span>\u062f\u0633\u062a\u06af\u0627\u0647 GFCI<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<\/li>\n<\/ul>\n<p>ground fault circuit interrupter \u06cc\u0627 \u0628\u0647 \u0627\u062e\u062a\u0635\u0627\u0631 GFCI \u0648\u0633\u06cc\u0644\u0647 \u0627\u06cc\u0633\u062a \u06a9\u0647 \u062c\u0631\u06cc\u0627\u0646 \u0628\u0631\u0642 \u0631\u0627 \u062a\u062d\u062a \u0646\u0638\u0631 \u062f\u0627\u0631\u062f \u0648 \u0627\u06af\u0631 \u062c\u0631\u06cc\u0627\u0646 \u0628\u0631\u0642 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u062d\u062f \u0645\u062c\u0627\u0632 \u0628\u0627\u0634\u062f \u0628\u0631\u0642 \u0631\u0627 \u0642\u0637\u0639 \u0645\u06cc\u06a9\u0646\u062f \u062a\u0627 \u0627\u0632 \u0633\u0648\u062e\u062a\u0646 \u0644\u0648\u0627\u0632\u0645 \u0628\u0631\u0642\u06cc \u0634\u0645\u0627 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0646\u062f\u060c \u0628\u0631\u062e\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u062f\u0633\u062a\u06af\u0627\u0647 \u0647\u0627 \u062f\u0627\u0631\u0627\u06cc \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u062d\u0631\u0641\u0647 \u0627\u06cc \u060c \u062f\u06a9\u0645\u0647 \u0647\u0627\u06cc TEST- RESET \u0647\u0633\u062a\u0646\u062f \u0648 \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0634\u0648\u0631\u0647\u0627 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u062f\u0631 \u0627\u0645\u0648\u0631 \u0628\u0631\u0642\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u0634\u0648\u062f.<\/p>\n<p>\u0627\u0644\u0628\u062a\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u0647\u0627 \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0622\u0633\u06cc\u0628 \u062f\u06cc\u062f\u0646 \u0648\u0633\u0627\u06cc\u0644 \u0628\u0631\u0642\u06cc \u0645\u0646\u0632\u0644 \u062a\u0648\u0633\u0637 \u0646\u0648\u0633\u0627\u0646\u0627\u062a \u0648 \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0645\u0648\u0627\u0642\u0639\u06cc \u06a9\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0644\u0648\u0627\u0632\u0645 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0645\u06cc\u06a9\u0646\u06cc\u062f \u062f\u0633\u062a\u06af\u0627\u0647 \u0631\u0627 \u0627\u0632 \u067e\u0631\u06cc\u0632 \u0628\u0631\u0642 \u0628\u06a9\u0634\u06cc\u062f\u060c \u0686\u0648\u0646 \u06af\u0627\u0647\u0627 \u067e\u06cc\u0634 \u0645\u06cc\u0627\u06cc\u062f \u0648\u0642\u062a\u06cc \u062f\u0633\u062a\u06af\u0627\u0647 \u062e\u0627\u0645\u0648\u0634 \u0627\u0633\u062a \u0648\u0644\u06cc \u0628\u0647 \u067e\u0631\u06cc\u0632 \u0628\u0631\u0642 \u0645\u062a\u0635\u0644 \u0627\u0633\u062a \u0628\u0627\u0632 \u0647\u0645 \u0646\u0648\u0633\u0627\u0646\u0627\u062a \u0628\u0631\u0642 \u0628\u0627\u0639\u062b \u0622\u0633\u06cc\u0628 \u0632\u062f\u0646 \u0628\u0647 \u062f\u0633\u062a\u06af\u0627\u0647 \u0645\u06cc\u0634\u0648\u062f\u060c \u0648\u0644\u06cc \u0648\u0642\u062a\u06cc \u062f\u0633\u062a\u06af\u0627\u0647 \u0627\u0632 \u067e\u0631\u06cc\u0632 \u0628\u0631\u0642 \u062c\u062f\u0627 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f\u060c \u0647\u0631 \u06af\u0648\u0646\u0647 \u0646\u0648\u0633\u0627\u0646 \u0648\u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u0647\u06cc\u0686 \u06af\u0648\u0646\u0647 \u062a\u0627\u062b\u06cc\u0631\u06cc \u0628\u0631 \u0631\u0648\u06cc \u062f\u0633\u062a\u06af\u0627\u0647 \u0646\u062e\u0648\u0627\u0647\u062f \u06af\u0630\u0627\u0634\u062a .<\/p>\n<p>\u0627\u0645\u0631\u0648\u0632\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a\u00a0 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0645\u0634\u063a\u0644\u0647 \u06cc \u06a9\u0627\u0631\u06cc \u0627\u0645\u06a9\u0627\u0646 \u062e\u0631\u06cc\u062f \u062d\u0636\u0648\u0631\u06cc \u0648 \u06cc\u0627 \u062d\u062a\u06cc \u0645\u0634\u0627\u0647\u062f\u0647 \u06cc \u0645\u062f\u0644 \u0647\u0627 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0645\u0634\u06a9\u0644 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f \u061b\u00a0 \u06cc\u06a9\u06cc \u0627\u0632 \u0633\u0627\u06cc\u062a \u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631 \u06a9\u0647 \u0627\u0645\u06a9\u0627\u0646 \u062e\u0631\u06cc\u062f \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u060c <a href=\"https:\/\/decorshop.ir\/\">\u062f\u06a9\u0648\u0631\u0634\u0627\u067e<\/a>\u00a0\u0645\u06cc\u0628\u0627\u0634\u062f .<\/p>\n<p>\u0634\u0631\u06a9\u062a \u062f\u06a9\u0648\u0631 \u0634\u0627\u067e \u0632\u06cc\u0631 \u0645\u062c\u0645\u0648\u0639\u0647 \u06cc \u06a9\u0645\u067e\u0627\u0646\u06cc\u00a0<a href=\"https:\/\/chenco.ir\/\" target=\"_blank\" rel=\"noopener\">\u0686\u0634\u0645\u0647 \u0646\u0648\u0631<\/a> \u0627\u0633\u062a \u0628\u0627 \u0642\u062f\u0645\u062a\u06cc \u06f3\u06f0 \u0633\u0627\u0644\u0647 \u0645\u06cc\u0628\u0627\u0634\u062f \u061b \u0647\u0645\u0647 \u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u062f\u0627\u0631\u0627\u06cc \u06af\u0627\u0631\u0627\u0646\u062a\u06cc \u06f1\u06f2 \u0645\u0627\u0647\u0647 \u0645\u06cc\u0628\u0627\u0634\u0646\u062f \u0648 \u0627\u0632 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627\u06cc\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0647\u0633\u062a\u0646\u062f .<\/p>\n<p>\u0627\u0644\u0628\u062a\u0647 \u0627\u06cc\u0646<a href=\"https:\/\/chenco.ir\/\" target=\"_blank\" rel=\"noopener\">\u00a0\u0634\u0631\u06a9\u062a<\/a>\u00a0\u0628\u0631\u0627\u06cc \u0631\u0627\u062d\u062a\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0634\u0645\u0627 \u060c \u0627\u0645\u06a9\u0627\u0646 \u062e\u0631\u06cc\u062f \u0627\u0642\u0633\u0627\u0637\u06cc \u062d\u062a\u06cc \u0628\u062f\u0648\u0646 \u0636\u0627\u0645\u0646 \u0631\u0627 \u062f\u0631 \u0633\u0627\u06cc\u062a \u0641\u0631\u0627\u0647\u0645 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0637\u06cc \u0631\u0648\u0632 \u0647\u0627\u06cc \u0627\u062e\u06cc\u0631 \u062f\u0631 \u0633\u0627\u0639\u0627\u062a \u0645\u062e\u062a\u0644\u0641 \u0634\u0627\u0647\u062f \u0642\u0637\u0639\u06cc \u0628\u0631\u0642 \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0634\u0647\u0631 \u0647\u0627 \u0628\u0648\u062f\u06cc\u0645. \u0627\u06cc\u0646 \u0627\u062a\u0641\u0627\u0642 \u0627\u06af\u0631 \u0686\u0647 \u0628\u0631 \u0631\u0648\u06cc \u0632\u0646\u062f\u06af\u06cc \u0631\u0648\u0632\u0645\u0631\u0647 \u0648 \u06a9\u0627\u0631 \u0647\u0627\u06cc \u0631\u0648\u0632\u0627\u0646\u0647 \u062a\u0627\u062b\u06cc\u0631 \u0645\u06cc \u06af\u0630\u0627\u0631\u062f \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627\u0639\u062b \u0628\u0631\u0648\u0632 \u062e\u0633\u0627\u0631\u062a \u0628\u0647 \u0644\u0648\u0627\u0632\u0645 \u0628\u0631\u0642\u06cc \u0634\u0648\u062f\u00a0 \u060c \u0628\u0627 \u067e\u06cc\u0634\u0631\u0641\u062a \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u0648 \u0635\u0646\u0639\u062a \u0633\u0627\u062e\u062a \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc \u0627\u0645\u0631\u0648\u0632\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0645\u062f\u0631\u0646 \u062a\u0631 \u0648 \u0642\u0627\u0628\u0644 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":33808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,50,202,53,59],"tags":[214,215,216],"class_list":["post-33803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-34","category-50","category-202","category-53","category-59","tag-214","tag-215","tag-216"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/33803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=33803"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/33803\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/33808"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=33803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=33803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=33803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}