{"id":28945,"date":"2020-10-20T06:25:36","date_gmt":"2020-10-20T06:25:36","guid":{"rendered":"https:\/\/decorshop.ir\/?p=28945"},"modified":"2023-04-27T12:08:13","modified_gmt":"2023-04-27T08:38:13","slug":"10-%d9%85%d8%af%d9%84-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%da%a9%d8%b1%db%8c%d8%b3%d8%aa%d8%a7%d9%84%db%8c-%d8%ac%d8%af%db%8c%d8%af-%d9%88-%d9%85%d8%af%d8%b1%d9%86","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/10-%d9%85%d8%af%d9%84-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%da%a9%d8%b1%db%8c%d8%b3%d8%aa%d8%a7%d9%84%db%8c-%d8%ac%d8%af%db%8c%d8%af-%d9%88-%d9%85%d8%af%d8%b1%d9%86\/","title":{"rendered":"10 \u0645\u062f\u0644 \u0644\u0648\u0633\u062a\u0631 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u062c\u062f\u06cc\u062f \u0648 \u0645\u062f\u0631\u0646"},"content":{"rendered":"<h2>\u0644\u0648\u0633\u062a\u0631 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u062c\u062f\u06cc\u062f \u0648 \u0645\u062f\u0631\u0646<\/h2>\n<p><a href=\"http:\/\/chenco.ir\" target=\"_blank\" rel=\"noopener\">\u0644\u0648\u0633\u062a\u0631\u0647\u0627<\/a> \u062f\u0631 \u06af\u0630\u0634\u062a\u0647 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0648\u0633\u06cc\u0644\u0647 \u06cc \u062a\u062c\u0645\u0644\u06cc \u0648 \u06af\u0631\u0648\u0646 \u0642\u06cc\u0645\u062a \u0645\u062e\u0635\u062a\u0635 \u062e\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u0634\u0631\u0627\u0641 \u0648 \u062f\u0631\u0628\u0627\u0631\u06cc\u0627\u0646 \u0628\u0647 \u062d\u0633\u0628\u0627 \u0645\u06cc \u0622\u0645\u062f\u0647 \u0627\u0633\u062a \u0648\u0644\u06cc \u0628\u0647 \u0645\u0631\u0648\u0631 \u0632\u0645\u0627\u0646 \u0628\u0627\u0633\u0627\u062e\u062a\u0646 \u0644\u0648\u0633\u062a\u0631\u0647\u0627 \u062f\u0631 \u062c\u0646\u0633 \u0647\u0627 \u0648 \u0637\u0631\u062d \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u0632 \u062d\u0627\u0644\u062a \u0627\u0646\u062d\u0635\u0627\u0631\u06cc \u062e\u0627\u0631\u062c \u0634\u062f\u0647 \u0648 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0648\u0633\u06cc\u0644\u0647 \u06cc \u062a\u0632\u0626\u06cc\u0646\u06cc \u0631\u0627\u06cc\u062c \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0642\u0634\u0631 \u0639\u0627\u062f\u06cc \u0645\u0639\u0645\u0648\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a . \u062f\u0631\u0645\u06cc\u0627\u0646 \u0627\u0646\u0648\u0627\u0639 \u0644\u0648\u0633\u062a\u0631\u0647\u0627 \u062c\u0646\u0633 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u0622\u0646 \u0628\u0647 \u0639\u0644\u062a \u0645\u0642\u0631\u0648\u0646 \u0628\u0647 \u0635\u0631\u0641\u0647 \u0628\u0648\u062f\u0646 \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u0646\u0648\u0627\u0639 \u0628\u0631\u0646\u0632\u06cc \u0648 \u0646\u0642\u0631\u0647 \u0648 \u0637\u0644\u0627 \u0648&#8230; \u0622\u0646 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0645\u0631\u062f\u0645 \u0627\u0632 \u0645\u062d\u0628\u0648\u0628\u06cc\u062a \u0632\u06cc\u0627\u062f\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627 \u0631\u0627\u0633\u062a . \u0686\u0631\u0627 \u06a9\u0647 \u0646\u0647 \u062a\u0646\u0647\u0627 \u062f\u0627\u0631\u0627\u06cc \u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628\u06cc \u0627\u0633\u062a \u0628\u0644\u06a9\u0647 \u0628\u0647 \u0639\u0644\u062a \u062f\u0627\u0631\u0627 \u0628\u0648\u062f\u0646 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644 \u0647\u0627 \u0648 \u067e\u062e\u0634 \u06a9\u0631\u062f\u0646 \u0646\u0648\u0631 \u062c\u0644\u0648 \u0648 \u0634\u06a9\u0648\u0647 \u062e\u0627\u0635\u06cc \u0631\u0627 \u0628\u0647 \u0645\u062d\u06cc\u0637 \u0645\u06cc \u062f\u0647\u062f .<\/p>\n<p>\u0627\u0648\u0644\u06cc\u0646 \u0646\u06a9\u062a\u0647 \u0627\u06cc \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0628\u0647 \u0622\u0646 \u0628\u067e\u0631\u062f\u0627\u0632\u06cc\u0645 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0642\u0628\u0644 \u0627\u0632 \u0647\u0631\u0686\u06cc\u0632\u06cc \u0644\u0648\u0633\u062a\u0631 \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u0634\u0645\u0627 \u0628\u0627\u06cc\u062f \u062f\u0631 \u0627\u0628\u0639\u0627\u062f\u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0627\u0634\u062f \u06cc\u0639\u0646\u06cc \u0646\u0647 \u0628\u0627\u06cc\u062f \u062f\u0631 \u0627\u0628\u0639\u0627\u062f\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0648\u0642\u062a\u06cc \u0628\u0631 \u0631\u0648\u06cc \u0633\u0642\u0641 \u0646\u0635\u0628 \u0645\u06cc \u0634\u0648\u062f \u060c\u0628\u0632\u0631\u06af\u06cc \u06cc\u0627 \u06a9\u0648\u0686\u06cc\u06a9\u06cc \u0622\u0646 \u0628\u0647 \u0686\u0634\u0645 \u0628\u06cc\u0627\u06cc\u062f .<\/p>\n<p>\u0646\u06a9\u062a\u0647 \u06cc \u0628\u0639\u062f\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627\u06cc\u062f <a href=\"http:\/\/chenco.ir\" target=\"_blank\" rel=\"noopener\">\u0644\u0648\u0633\u062a\u0631<\/a> \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u0634\u0645\u0627 \u062f\u0631 \u0627\u0631\u062a\u0641\u0627\u0639 \u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0627\u0634\u062f \u06cc\u0639\u0646\u06cc \u0627\u06af\u0631 \u0633\u0642\u0641 \u0628\u0644\u0646\u062f \u06cc \u062f\u0627\u0631\u06cc\u062f \u0628\u0647 \u0633\u0631\u0627\u063a \u0644\u0648\u0633\u062a\u0631 \u0647\u0627\u06cc \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u0622\u0648\u06cc\u0632 \u062f\u0627\u0631 \u0648 \u0686\u0646\u062f \u0637\u0628\u0642\u0647 \u0628\u0631\u0648\u06cc\u062f \u0648 \u0627\u06af\u0631 \u0633\u0642\u0641\u062a\u0627\u0646\u00a0 \u06a9\u0648\u062a\u0627\u0647 \u0627\u0633\u062a \u0645\u062f\u0644 \u0647\u0627\u06cc \u0633\u0642\u0641\u06cc \u0644\u0648\u0633\u062a\u0631 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0645\u0646\u0627\u0633\u0628 \u062a\u0631 \u0627\u0633\u062a . \u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0647 \u0646\u0648\u0639 \u0645\u062a\u0631\u06cc\u0627\u0644 \u0628\u0647 \u06a9\u0627\u0631 \u0631\u0641\u062a\u0647 \u062f\u0631 \u062a\u0647\u06cc\u06cc\u0647 \u06cc \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644 \u0647\u0627 \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f .\u0686\u0631\u0627 \u06a9\u0647 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644 \u0647\u0627\u06cc \u06a9\u062f\u0631 \u0645\u0642\u062f\u0627\u0631 \u0646\u0648\u0631 \u062f\u0631\u06cc\u0627\u0641\u062a\u06cc \u0634\u0645\u0627 \u06a9\u0645 \u0645\u06cc\u06a9\u0646\u0646\u062f . \u0647\u0645\u0686\u0646\u06cc\u0646 \u062a\u0639\u062f\u0627\u062f \u0634\u0627\u062e\u0647 \u0647\u0627 \u0648 \u0646\u062d\u0648\u06cc \u0642\u0631\u0627\u0631\u06af\u06cc\u0631\u06cc \u0622\u0646\u0647\u0627 \u06a9\u0647 \u0628\u0647 \u0633\u0645\u062a \u0628\u0627\u0644\u0627 \u0628\u0627\u0634\u062f \u06cc\u0627 \u067e\u0627\u06cc\u06cc\u0646 \u062f\u0631 \u0645\u0642\u062f\u0627\u0631 \u0646\u0648\u0631 \u062f\u0631\u06cc\u0627\u0641\u062a\u06cc \u0627\u0647\u0645\u06cc\u062a \u062f\u0627\u0631\u0646\u062f .<\/p>\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0645\u06cc \u062e\u0648\u0627\u0647\u06cc\u0645 \u0628\u0627\u0647\u0645 \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u062f\u0647 \u0645\u062f\u0644 \u0627\u0632 <a href=\"https:\/\/decorshop.ir\/product-category\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%da%a9%d8%b1%db%8c%d8%b3%d8%aa%d8%a7%d9%84%db%8c\/\">\u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc<\/a> \u062c\u062f\u06cc\u062f \u0648 \u0645\u062f\u0631\u0646 \u0628\u067e\u0631\u062f\u0627\u0632\u06cc\u0645 \u0628\u0627 \u0645\u0627 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627\u0634\u06cc\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28947\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/1-11.jpg\" alt=\"\" width=\"225\" height=\"225\" \/><\/p>\n<p>\u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0627\u0632 \u06cc\u06a9 \u0635\u0641\u062d\u0647 \u06cc \u06af\u0631\u062f \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u0622\u0648\u06cc\u0632 \u0647\u0627\u06cc \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u062f\u0631\u0633\u062a \u0634\u062f\u0647 \u0627\u0633\u062a . \u0648 \u062f\u0631 \u062f\u0648 \u0631\u0646\u06af \u0632\u06cc\u062a\u0648\u0646\u06cc \u0648 \u06a9\u0631\u0648\u0645 \u0645\u0648\u062c\u0648\u062f \u0645\u06cc \u0628\u0627\u0634\u062f . \u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u0645\u0646\u0627\u0633\u0628 \u0641\u0636\u0627 \u0647\u0627\u06cc\u06cc \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u0627\u0633\u062a . \u0648 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0631\u0627\u06cc \u0641\u0636\u0644\u0627\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0633\u0642\u0641 \u0622\u0646\u062c\u0627 \u0627\u0631\u062a\u0641\u0627\u0639 \u06a9\u0645\u06cc \u062f\u0627\u0631\u062f . \u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u0628\u0647 \u0639\u0644\u062a \u062f\u0627\u0634\u062a\u0646 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644 \u0647\u0627 \u0642\u0627\u062f\u0631 \u0627\u0633\u062a \u0646\u0648\u0631 \u0631\u0627 \u0645\u0627\u0646\u0646\u062f \u0645\u0646\u0634\u0648\u0631 \u0645\u0646\u0639\u06a9\u0633 \u06a9\u0631\u062f\u0647 \u0648 \u062c\u0644\u0648\u0647 \u06cc \u0641\u0648\u0642 \u0627\u0644\u0639\u0627\u062f\u0647 \u0627\u06cc \u0628\u0647 \u0641\u0636\u0627 \u0634\u0645\u0627 \u0628\u062f\u0647\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28948\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/2-12.jpg\" alt=\"\" width=\"492\" height=\"297\" \/><\/p>\n<p>\u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u0627\u0632 \u0637\u0631\u062d <a href=\"https:\/\/decorshop.ir\/product-category\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%b3%d9%82%d9%81%db%8c\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%b3%d9%82%d9%81%db%8c-%d8%af%d8%a7%db%8c%da%a9%d8%a7%d8%b3%d8%aa\/\">\u062f\u0627\u06cc\u06a9\u0627\u0633\u062a<\/a> \u0645\u06cc \u0628\u0627\u0634\u062f . \u062f\u0631\u0648\u0627\u0642\u0639 \u0644\u0648\u0633\u062a\u0631 \u0647\u0627\u06cc \u062f\u0627\u06cc\u06a9\u0627\u0633\u062a \u060c\u0644\u0648\u0633\u062a\u0631 \u0647\u0627\u06cc \u0637\u0631\u062d \u0628\u0631\u0646\u0632\u06cc \u0645\u06cc \u0628\u0627\u0634\u0646\u062f \u06a9\u0647 \u0627\u0632 \u062c\u0646\u0633 \u0622\u0644\u0648\u0645\u06cc\u0646\u06cc\u0648\u0645 \u0622\u0628\u06a9\u0627\u0631\u06cc \u0634\u062f\u0647 \u0647\u0633\u062a\u0646\u062f \u0648 \u0648\u0632\u0646 \u0648 \u0642\u06cc\u0645\u062a\u06cc \u06a9\u0645 \u062a\u0631 \u0646\u0633\u0628\u062a \u0628\u0647 \u0645\u062f\u0644 \u0628\u0631\u0646\u0632\u06cc \u062e\u0648\u062f \u062f\u0627\u0631\u0646\u062f . \u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u062f\u0627\u0631\u0627\u06cc \u0637\u0648\u0644 \u0648 \u0639\u0631\u0636 65 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u0648 \u0627\u0631\u062a\u0641\u0627\u0639 85 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u0627\u0633\u062a . \u062f\u0627\u0631\u0627\u06cc\u00a0 10 \u0634\u0639\u0644\u0647 \u0645\u06cc \u0628\u0627\u0634\u062f \u0648 \u0628\u0647 \u062e\u0627\u0637\u0631 \u0627\u0631\u062a\u0641\u0627\u0639 \u0622\u0646 \u0645\u0646\u0627\u0633\u0628 \u0633\u0642\u0641 \u0647\u0627\u06cc \u0628\u0644\u0646\u062f \u0648 \u0641\u0636\u0627\u0647\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0645\u062a\u0631\u0627\u0698\u0628\u0632\u0631\u06af \u0627\u0633\u062a .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28949\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/3-12.jpg\" alt=\"\" width=\"660\" height=\"477\" \/><\/p>\n<p>\u0627\u06cc\u0646 <a href=\"https:\/\/decorshop.ir\/product-category\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%b3%d9%82%d9%81%db%8c\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%b3%d9%82%d9%81%db%8c-%da%a9%d8%b1%db%8c%d8%b3%d8%aa%d8%a7%d9%84%db%8c\/\">\u0644\u0648\u0633\u062a\u0631 \u0633\u0642\u0641\u06cc<\/a> \u0648\u00a0 6 \u0634\u0639\u0644\u0647 \u06cc \u0634\u0627\u062e\u0647 \u062f\u0627\u0631 \u0627\u0633\u062a \u0648 \u062f\u0627\u0631\u0627\u06cc \u0627\u0631\u062a\u0641\u0627\u0639 35 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u0648 \u0637\u0648\u0644 \u0648 \u0639\u0631\u0636 65 \u0633\u0627\u0646\u062a\u06cc \u0645\u062a\u0631 \u0627\u0633\u062a \u0648 \u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u0628\u0647 \u062e\u0627\u0637\u0631 \u0627\u06cc\u0646 \u0634\u0627\u062e\u0647 \u0647\u0627\u06cc \u0631\u0648 \u0628\u0647 \u067e\u0627\u06cc\u06cc\u0646 \u062f\u0627\u0631\u062f \u0646\u0648\u0631 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0631\u0627 \u0628\u0647 \u0641\u0636\u0627 \u0645\u06cc \u062f\u0647\u062f \u0648 \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062f\u0631 \u067e\u0630\u06cc\u0631\u0627\u06cc\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0648 \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u06cc \u0647\u0627 \u0627\u0633\u062a .\u062c\u0646\u0633 \u0622\u0646 \u0627\u0632 \u0628\u0631\u0646\u0632 \u0627\u0633\u062a \u0648 \u0627\u0632 \u062f\u0633\u062a\u0647 \u0633\u06cc \u0644\u0648\u0633\u062a\u0631 \u0647\u0627\u06cc \u06af\u0631\u0627\u0646 \u0642\u06cc\u0645\u062a \u0645\u06cc \u0628\u0627\u0634\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28950\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/4-8.jpg\" alt=\"\" width=\"225\" height=\"225\" \/><\/p>\n<p>\u0627\u06af\u0631 \u0633\u0627\u0644\u0646\u06cc \u0628\u0627 \u0633\u0642\u0641 \u0628\u0644\u0646\u062f \u0648 \u0645\u062a\u0631\u0627\u0698\u06cc \u0632\u06cc\u0627\u062f \u062f\u0627\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u0686\u0646\u062f \u0637\u0628\u0642\u0647\u06cc \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0627\u0633\u0628 \u0641\u0636\u0627 \u06cc \u0634\u0645\u0627 \u0645\u06cc \u0628\u0627\u0634\u0646\u062f. \u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631\u0647\u0627 \u0628\u0647 \u062e\u0627\u0637\u0631 \u0637\u0631\u0627\u062d\u06cc \u062e\u0627\u0635\u06cc \u06a9\u0647 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644 \u0647\u0627\u06cc \u0628\u0647 \u06a9\u0627\u0631 \u0631\u0641\u062a\u0647 \u062f\u0631 \u0622\u0646 \u062f\u0627\u0631\u062f \u0628\u0633\u06cc\u0627\u0631 \u0628\u0647 \u0634\u06a9\u0648\u0647 \u0648 \u062c\u0644\u0627\u0644 \u0641\u0636\u0627\u06cc \u0633\u0627\u0644\u0646 \u0634\u0645\u0627 \u0645\u06cc \u0627\u0641\u0632\u0627\u06cc\u062f \u0648 \u0627\u0646\u0639\u06a9\u0627\u0633 \u0646\u0648\u0631\u06cc \u062e\u06cc\u0631\u0647 \u06a9\u0646\u0646\u062f\u0647 \u0627\u06cc \u0631\u0627 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc \u06a9\u0646\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28951\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/5-11.jpg\" alt=\"\" width=\"225\" height=\"225\" \/><\/p>\n<p>\u0627\u06cc\u0646 \u0645\u062f\u0644 \u0644\u0648\u0633\u062a\u0631 \u0686\u0634\u0645\u0647 \u06cc \u0646\u0648\u0631 \u0628\u0647 \u0639\u0644\u062a \u062a\u0644\u0641\u06cc\u0642 \u0633\u0631\u0627\u0645\u06cc\u06a9 \u0648 \u0641\u0644\u0632 \u0628\u0631\u0646\u0632 \u0622\u0628\u06a9\u0627\u0631\u06cc \u0634\u062f\u0647 \u0648 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0648\u0631\u062f \u062a\u0648\u062c\u0647 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a . \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc \u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u0627\u0632 \u062d\u0628\u0627\u0628 \u06cc\u0627 \u0644\u0627\u0644\u0647 \u0628\u0631\u0627\u06cc \u0644\u0627\u0645\u067e \u0647\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0634\u062f\u0647 \u0647\u0645\u06cc\u0646 \u0627\u0645\u0631 \u0628\u0627\u0639\u062b \u0634\u062f\u0647 \u0627\u0633\u062a \u0627\u0632 \u0644\u0648\u0633\u062a\u0631 \u0646\u0648\u0631 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u062a\u0648\u0627\u0646 \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0631\u062f \u0648 \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0627\u06cc\u0646 \u062d\u0633 \u0631\u0627 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc \u06a9\u0646\u062f \u06a9\u0647 \u0627\u0646\u06af\u0627\u0631 \u06cc\u06a9 \u0634\u0645\u0639\u062f\u0627\u0646 \u0628\u0632\u0631\u06af \u0633\u0642\u0641\u06cc \u0645\u06cc \u0628\u0627\u0634\u062f \u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 . \u0627\u0632 \u0627\u06cc\u0646 \u0645\u062f\u0644 \u0645\u06cc \u062a\u0648\u0627\u0646 \u062f\u0631 \u0633\u0627\u0644\u0646 \u0647\u0627\u06cc\u06cc \u0628\u0627 \u062f\u06a9\u0648\u0631 \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u060c \u0648\u06cc\u06a9\u062a\u0648\u0631\u06cc\u0627\u06cc \u0648 \u0633\u0644\u0637\u0646\u062a\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28952\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/6-7.jpg\" alt=\"\" width=\"225\" height=\"225\" \/><\/p>\n<p>\u0627\u06af\u0631 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0645\u0642\u062f\u0627\u0631 \u0646\u0648\u0631 \u062f\u0631\u06cc\u0627\u0641\u062a\u06cc \u0627\u0647\u0645\u06cc\u062a \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0631\u062f \u0648 \u062f\u0631\u0645\u0642\u0627\u0628\u0644 \u0639\u0644\u0627\u0642\u0647 \u06cc \u0632\u06cc\u0627\u062f\u06cc \u0628\u0647 \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u0622\u0646\u062a\u06cc\u06a9 \u0648 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u062f\u0627\u0631\u06cc\u062f \u0645\u0627 \u0627\u06cc\u0646 \u0645\u062f\u0644 \u0644\u0648\u0633\u062a\u0631 \u0631\u0627 \u0628\u0647 \u0634\u0645\u0627 \u0645\u0639\u0631\u0641\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0628\u0647 \u0639\u0644\u062a \u0637\u0631\u0627\u062d\u06cc \u0644\u0627\u0644\u0647 \u0647\u0627 \u0628\u0647 \u0633\u0645\u062a \u067e\u0627\u06cc\u06cc\u0646 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0627\u0633\u0628 \u0641\u0636\u0627\u06cc \u0634\u0645\u0627 \u0645\u06cc \u0628\u0627\u0634\u062f \u0648 \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0627\u0633\u0628 \u0641\u0636\u0627\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0633\u0642\u0641 \u06a9\u0648\u062a\u0627\u0647\u06cc \u062f\u0627\u0631\u0646\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28953\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/7-5.jpg\" alt=\"\" width=\"225\" height=\"225\" \/><\/p>\n<p>\u0627\u06cc\u0646 \u062a\u0627\u06cc\u067e \u0627\u0632 \u0644\u0648\u0633\u062a\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0627\u0633\u0628 \u0641\u0636\u0627\u0647\u0627\u06cc \u0631\u0627\u0647\u0631\u0648 \u0647\u0627\u06cc \u0628\u0644\u0646\u062f \u0648 \u0628\u0627\u0644\u0627\u06cc \u0645\u06cc\u0632 \u0646\u0627\u0647\u0627\u0631 \u062e\u0648\u0631\u06cc \u0647\u0627\u06cc \u0634\u06a9\u06cc\u0644 \u0648 \u0633\u0644\u0637\u0646\u062a\u06cc \u0645\u06cc \u0628\u0627\u0634\u062f . \u0628\u0647 \u0639\u0644\u062a \u0637\u0631\u0627\u062d\u06cc \u0645\u0633\u062a\u0637\u06cc\u0644\u06cc \u0634\u06a9\u0644\u06cc \u06a9\u0647 \u062f\u0627\u0631\u062f \u0628\u0633\u06cc\u0627\u0631 \u0628\u0631\u0627\u06cc \u0641\u0636\u0627\u06cc \u0628\u0627\u0644\u0627\u06cc \u0645\u06cc\u0632 \u063a\u0630\u0627 \u062e\u0648\u0631\u06cc \u0645\u0646\u0627\u0633\u0628 \u0645\u06cc \u0628\u0627\u0634\u062f . \u0647\u0645\u0686\u0646\u06cc\u06cc\u0646 \u0627\u0632 \u0622\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0631\u0627\u06cc \u0645\u062d\u06cc\u0637 \u0647\u0627\u06cc \u0628\u0632\u0631\u06af\u06cc \u06a9\u0647 \u062a\u0646\u0647\u0627 \u06cc\u06a9 \u062c\u0627\u06cc\u06af\u0627\u0647 \u0628\u0631\u0627\u06cc \u0644\u0648\u0633\u062a\u0631 \u062f\u0627\u0631\u0646\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f \u0686\u0648\u0646 \u0637\u0631\u0627\u062d\u06cc \u0645\u0633\u062a\u0637\u06cc\u0644 \u0634\u06a9\u0644 \u0622\u0646 \u0628\u0627\u0639\u062b \u0645\u06cc \u0634\u0648\u062f \u06a9\u0647 \u0641\u0636\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0631\u0627 \u0631\u0648\u0634\u0646 \u06a9\u0646\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28954\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/8-2.jpg\" alt=\"\" width=\"225\" height=\"225\" \/><\/p>\n<p>\u0634\u0627\u06cc\u062f \u062a\u0635\u0648\u0631 \u0627\u06a9\u062b\u0631\u0627\u0641\u0631\u0627\u062f \u0627\u06cc\u0646 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0627\u0632 \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u0641\u0642\u0637 \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0647\u0627\u06cc \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647\u06a9\u0631\u062f \u0648\u0644\u06cc \u0627\u06cc\u0646 \u0637\u0648\u0631 \u0646\u06cc\u0633\u062a . \u0634\u0645\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u0644\u0648\u0633\u062a\u0631 \u0641\u0648\u0642 \u062f\u0631 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0648 \u0641\u0636\u0627\u0647\u06cc\u06cc \u06a9\u0647 \u0633\u0642\u0641 \u0647\u0627\u06cc \u06a9\u0648\u062a\u0627\u0647\u06cc \u062f\u0627\u0631\u0646\u062f \u0646\u06cc\u0632 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28955\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/9-2.jpg\" alt=\"\" width=\"225\" height=\"225\" \/><\/p>\n<p>\u0627\u06af\u0631 \u0641\u0636\u0627\u06cc \u0634\u0645\u0627 \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0648\u0686\u06a9 \u0627\u0633\u062a \u0648\u0644\u06cc \u0639\u0644\u0627\u0642\u0647 \u0634\u062f\u06cc\u062f\u06cc \u0628\u0647 \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u062f\u0627\u0631\u06cc\u062f \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0627\u06cc\u0646 \u0645\u062f\u0644 \u0644\u0648\u0633\u062a\u0631\u0647\u0627 \u0628\u0631\u0627\u06cc \u0641\u0636\u0627\u06cc \u062e\u0648\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f . \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0632 \u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0631\u0627\u06cc \u0628\u0627\u0644\u0627\u06cc \u067e\u06cc\u0634\u062e\u0648\u0627\u0646 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0648 \u0631\u0627\u0647\u0631\u0648 \u0647\u0627 \u0646\u06cc\u0632 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28956\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/0.jpg\" alt=\"\" width=\"225\" height=\"225\" \/><\/p>\n<p>\u0627\u06af\u0631 \u06cc\u06a9 \u0644\u0648\u0633\u062a\u0631 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u067e\u0631\u0632\u0631\u0642 \u0648 \u0628\u0631\u0642 \u0648 \u062e\u06cc\u0631\u0647 \u06a9\u0646\u0646\u062f\u0647 \u0645\u06cc \u062e\u0648\u0627\u0647\u06cc\u062f \u062d\u062a\u0645\u0627 \u0627\u06cc\u0646 \u0645\u062f\u0644 \u0631\u0627 \u0645\u062f \u0646\u0638\u0631 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0686\u0631\u0627 \u06a9\u0647 \u0628\u0647 \u0639\u0644\u062a \u062a\u0639\u062f\u062f \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644 \u0647\u0627\u06cc \u0628\u0647 \u06a9\u0627\u0631 \u0631\u0641\u062a\u0647 \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc \u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u0641\u0636\u0627 \u0628\u0647 \u0637\u0648\u0631 \u0686\u0634\u0645 \u06af\u06cc\u0631 \u0648 \u062e\u06cc\u0631\u0647 \u06a9\u0646\u0646\u062f\u0647 \u0632\u06cc\u0628\u0627 \u0645\u06cc \u06a9\u0646\u062f .<\/p>\n<p>\u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u0645 \u0645\u0637\u0627\u0644\u0628 \u06af\u0641\u062a\u0647 \u0634\u062f\u0647 \u0645\u0641\u06cc\u062f \u0628\u0648\u062f\u0647 \u0628\u0627\u0634\u062f. \u0634\u0645\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0633\u0648\u0627\u0644\u0627\u062a \u0627\u062d\u062a\u0645\u0627\u0644\u06cc \u062e\u0648\u062f \u0631\u0627 \u0645\u0634\u0627\u0648\u0631\u0627\u0646 \u0645\u0627 \u06a9\u0647 \u0628\u0647 \u0635\u0648\u0631\u0627\u062a \u0634\u0628\u0627\u0646\u0647 \u0631\u0648\u0632\u06cc \u0622\u0645\u0627\u062f\u0647 \u062e\u062f\u0645\u062a \u0631\u0633\u0627\u0646\u06cc \u0628\u0647 \u0634\u0645\u0627 \u0639\u0632\u06cc\u0632\u0627\u0646 \u0645\u06cc \u0628\u0627\u0634\u0646\u062f \u060c \u0628\u067e\u0631\u0633\u06cc\u062f . \u0645\u062f\u0644 \u0647\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0646\u0645\u0648\u0646\u0647 \u0647\u0627\u06cc \u06a9\u0627\u0631\u0647\u0627 \u0631\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646 \u062f\u0631 \u0633\u0627\u06cc\u062a <a href=\"http:\/\/decorshop.ir\">\u062f\u06a9\u0648\u0631\u0634\u0627\u067e<\/a> \u0645\u0634\u0627\u0647\u062f\u0647 \u06a9\u0631\u062f\u0647 \u0648 \u062f\u0631 \u0635\u0648\u0631\u062a \u067e\u0633\u0646\u062f \u0628\u0627 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062e\u0627\u0637\u0631 \u0628\u0647 \u062e\u0631\u06cc\u062f\u0646 \u0622\u0646 \u0627\u0642\u062f\u0627\u0645 \u0646\u0645\u0627\u06cc\u06cc\u062f .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0644\u0648\u0633\u062a\u0631 \u06a9\u0631\u06cc\u0633\u062a\u0627\u0644\u06cc \u062c\u062f\u06cc\u062f \u0648 \u0645\u062f\u0631\u0646 \u0644\u0648\u0633\u062a\u0631\u0647\u0627 \u062f\u0631 \u06af\u0630\u0634\u062a\u0647 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0648\u0633\u06cc\u0644\u0647 \u06cc \u062a\u062c\u0645\u0644\u06cc \u0648 \u06af\u0631\u0648\u0646 \u0642\u06cc\u0645\u062a \u0645\u062e\u0635\u062a\u0635 \u062e\u0627\u0646\u0647 \u0647\u0627\u06cc \u0627\u0634\u0631\u0627\u0641 \u0648 \u062f\u0631\u0628\u0627\u0631\u06cc\u0627\u0646 \u0628\u0647 \u062d\u0633\u0628\u0627 \u0645\u06cc \u0622\u0645\u062f\u0647 \u0627\u0633\u062a \u0648\u0644\u06cc \u0628\u0647 \u0645\u0631\u0648\u0631 \u0632\u0645\u0627\u0646 \u0628\u0627\u0633\u0627\u062e\u062a\u0646 \u0644\u0648\u0633\u062a\u0631\u0647\u0627 \u062f\u0631 \u062c\u0646\u0633 \u0647\u0627 \u0648 \u0637\u0631\u062d \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u0632 \u062d\u0627\u0644\u062a \u0627\u0646\u062d\u0635\u0627\u0631\u06cc \u062e\u0627\u0631\u062c \u0634\u062f\u0647 \u0648 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0648\u0633\u06cc\u0644\u0647 \u06cc \u062a\u0632\u0626\u06cc\u0646\u06cc \u0631\u0627\u06cc\u062c \u062f\u0631 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":32744,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-28945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-34"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/28945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=28945"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/28945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/32744"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=28945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=28945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=28945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}