{"id":28938,"date":"2023-05-14T15:53:57","date_gmt":"2023-05-14T12:23:57","guid":{"rendered":"https:\/\/decorshop.ir\/?p=28938"},"modified":"2023-05-15T15:53:54","modified_gmt":"2023-05-15T12:23:54","slug":"%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/","title":{"rendered":"\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u0645\u0634\u0627\u0647\u062f\u0647 \u0645\u062f\u0644 \u0647\u0627"},"content":{"rendered":"<p>\u0628\u0627 \u062e\u0648\u0627\u0646\u062f\u0646 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u06a9\u0647 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 <strong>\u0631\u0627\u0647\u0646\u0645\u0627\u06cc <a href=\"\/product-category\/\u0644\u0648\u0633\u062a\u0631\u0647\u0627-\u0628\u0631-\u0627\u0633\u0627\u0633-\u06a9\u0627\u0631\u0628\u0631\u062f\/\u0644\u0648\u0633\u062a\u0631-\u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\/\">\u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/a><\/strong> \u0627\u0633\u062a\u060c \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u0648 \u0645\u0646\u0627\u0633\u0628 \u062a\u0631\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u062e\u0648\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f. \u067e\u0633 \u062a\u0627 \u0627\u0646\u062a\u0647\u0627\u06cc \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 <a href=\"\/mag\/\"><strong>\u062f\u06a9\u0648\u0631\u0645\u06af<\/strong> <\/a>\u0647\u0645\u0631\u0627\u0647 \u0645\u0627 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0628\u0627 \u0646\u06a9\u0627\u062a \u0645\u0647\u0645 \u062f\u0631 \u0645\u0648\u0631\u062f \u062e\u0631\u06cc\u062f <a href=\"\/product-category\/\u0644\u0648\u0633\u062a\u0631\/\">\u0644\u0648\u0633\u062a\u0631<\/a> \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0622\u0634\u0646\u0627 \u0634\u0648\u06cc\u062f.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/#%D9%86%DA%A9%D8%A7%D8%AA_%D9%85%D9%87%D9%85_%D8%AF%D8%B1_%D9%85%D9%88%D8%B1%D8%AF_%D8%AE%D8%B1%DB%8C%D8%AF_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87\" >\u0646\u06a9\u0627\u062a \u0645\u0647\u0645 \u062f\u0631 \u0645\u0648\u0631\u062f \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/#%D8%A7%D9%87%D9%85%DB%8C%D8%AA_%D9%87%D9%85%D8%A7%D9%87%D9%86%DA%AF_%D8%A8%D9%88%D8%AF%D9%86_%D8%B4%DA%A9%D9%84_%D9%87%D9%86%D8%AF%D8%B3%DB%8C_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%A8%D8%A7_%D9%88%D8%B3%D8%A7%DB%8C%D9%84_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87\" >\u0627\u0647\u0645\u06cc\u062a \u0647\u0645\u0627\u0647\u0646\u06af \u0628\u0648\u062f\u0646 \u0634\u06a9\u0644 \u0647\u0646\u062f\u0633\u06cc \u0644\u0648\u0633\u062a\u0631 \u0628\u0627 \u0648\u0633\u0627\u06cc\u0644 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/#%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D9%86%D9%88%D8%B1_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87\" >\u0628\u0647\u062a\u0631\u06cc\u0646 \u0646\u0648\u0631 \u0628\u0631\u0627\u06cc \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/#%D8%AE%D8%B1%DB%8C%D8%AF_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87\" >\u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/#%D9%86%DA%A9%D8%AA%D9%87_%D8%A7%D9%88%D9%84\" >\u0646\u06a9\u062a\u0647 \u0627\u0648\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/#%D9%86%DA%A9%D8%AA%D9%87_%D8%AF%D9%88%D9%85\" >\u0646\u06a9\u062a\u0647 \u062f\u0648\u0645<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/#%D9%86%DA%A9%D8%AA%D9%87_%DB%8C_%D8%B3%D9%88%D9%85\" >\u0646\u06a9\u062a\u0647 \u06cc \u0633\u0648\u0645<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/#%D9%86%DA%A9%D8%AA%D9%87_%DB%8C_%DA%86%D9%87%D8%A7%D8%B1%D9%85\" >\u0646\u06a9\u062a\u0647 \u06cc \u0686\u0647\u0627\u0631\u0645<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/#%D9%84%D9%88%D8%B3%D8%AA%D8%B1%D9%87%D8%A7%DB%8C_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D9%81%D8%B6%D8%A7%DB%8C_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87\" >\u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0641\u0636\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 :<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/#%D8%AC%D9%85%D8%B9_%D8%A8%D9%86%D8%AF%DB%8C\" >\u062c\u0645\u0639 \u0628\u0646\u062f\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/#%D8%B3%D9%88%D8%A7%D9%84%D8%A7%D8%AA_%D9%85%D8%AA%D8%AF%D8%A7%D9%88%D9%84_%D8%AF%D8%B1_%D9%85%D9%88%D8%B1%D8%AF_%D8%AE%D8%B1%DB%8C%D8%AF_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87\" >\u0633\u0648\u0627\u0644\u0627\u062a \u0645\u062a\u062f\u0627\u0648\u0644 \u062f\u0631 \u0645\u0648\u0631\u062f \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/#%D8%A8%D8%B1%D8%A7%DB%8C_%D8%B1%D9%88%D8%B4%D9%86%D8%A7%DB%8C%DB%8C_%D8%A8%D8%A7%D9%84%D8%A7%DB%8C_%D8%A7%D9%BE%D9%86_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87%D8%8C_%DA%86%D9%87_%D9%84%D9%88%D8%B3%D8%AA%D8%B1%DB%8C_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D8%A7%D8%B3%D8%AA%D8%9F\" >\u0628\u0631\u0627\u06cc \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627\u0644\u0627\u06cc \u0627\u067e\u0646 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\u060c \u0686\u0647 \u0644\u0648\u0633\u062a\u0631\u06cc \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/decorshop.ir\/mag\/%d8%b1%d8%a7%d9%87%d9%86%d9%85%d8%a7%db%8c-%d8%ae%d8%b1%db%8c%d8%af-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87-%d8%a8%d9%87-%d9%87%d9%85%d8%b1%d8%a7%d9%87-%d9%85\/#%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D8%B1%D9%86%DA%AF_%D9%84%D8%A7%D9%85%D9%BE_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87_%DA%86%D9%87_%D8%B1%D9%86%DA%AF%DB%8C_%D8%A7%D8%B3%D8%AA%D8%9F\" >\u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0646\u06af \u0644\u0627\u0645\u067e \u0628\u0631\u0627\u06cc \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0686\u0647 \u0631\u0646\u06af\u06cc \u0627\u0633\u062a\u061f<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D9%86%DA%A9%D8%A7%D8%AA_%D9%85%D9%87%D9%85_%D8%AF%D8%B1_%D9%85%D9%88%D8%B1%D8%AF_%D8%AE%D8%B1%DB%8C%D8%AF_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87\"><\/span>\u0646\u06a9\u0627\u062a \u0645\u0647\u0645 \u062f\u0631 \u0645\u0648\u0631\u062f \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u0646\u062a\u062e\u0627\u0628 \u06cc\u06a9 \u0644\u0648\u0633\u062a\u0631 \u0645\u0646\u0627\u0633\u0628 \u0648 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0628\u0631\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\u060c \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u0638\u0627\u0647\u0631 \u062c\u0630\u0627\u0628\u06cc \u0628\u0647 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0645\u06cc \u0628\u062e\u0634\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u06a9\u0647 \u062f\u0631 \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0627 <strong>\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/strong> \u0627\u0633\u062a\u060c \u0628\u0647 \u0646\u06a9\u0627\u062a \u0645\u0647\u0645 \u062f\u0631 \u0645\u0648\u0631\u062f \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0628\u0631\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u0634\u0627\u0631\u0647 \u0645\u06cc \u06a9\u0646\u06cc\u0645.<\/p>\n<figure id=\"attachment_39436\" aria-describedby=\"caption-attachment-39436\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-39436\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2020\/10\/\u0644\u0648\u0633\u062a\u0631-\u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647-1.jpg\" alt=\"\u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\" width=\"700\" height=\"540\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2020\/10\/\u0644\u0648\u0633\u062a\u0631-\u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647-1.jpg 700w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2020\/10\/\u0644\u0648\u0633\u062a\u0631-\u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647-1-300x231.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-39436\" class=\"wp-caption-text\"><a href=\"\/product-category\/\u0644\u0648\u0633\u062a\u0631\/\u0644\u0648\u0633\u062a\u0631-\u0645\u062f\u0631\u0646\/\">\u0644\u0648\u0633\u062a\u0631 \u0645\u062f\u0631\u0646<\/a> \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/figcaption><\/figure>\n<ul>\n<li><strong>\u062a\u0648\u062c\u0647 \u0628\u0647 \u0633\u0628\u06a9 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/strong>: \u0642\u0628\u0644 \u0627\u0632 \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0628\u0627\u06cc\u062f \u0633\u0628\u06a9 \u06a9\u0644\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0631\u0627 \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f. \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0644\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0647\u0627 \u062f\u0627\u0631\u0627\u06cc \u0633\u0628\u06a9 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0645\u0627\u0646\u0646\u062f \u0645\u062f\u0631\u0646 \u0648 \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u0647\u0633\u062a\u0646\u062f. \u0628\u0631\u0627\u06cc \u0634\u0646\u0627\u062e\u062a \u0633\u0628\u06a9 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\u060c \u0628\u0647 \u0645\u062f\u0644 \u06a9\u0627\u0628\u06cc\u0646\u062a \u0647\u0627 \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u06af\u0631 \u06a9\u0627\u0628\u06cc\u0646\u062a \u0647\u0627 \u0628\u062f\u0648\u0646 \u0637\u0631\u062d \u0628\u0627 \u0631\u0646\u06af \u0647\u0627\u06cc \u0633\u0627\u062f\u0647 \u0648 \u0631\u0648\u0634\u0646 \u0628\u0627\u0634\u0646\u062f\u060c \u0633\u0628\u06a9 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0634\u0645\u0627 \u0645\u062f\u0631\u0646 \u0627\u0633\u062a. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 <strong>\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/strong>\u060c \u0644\u0648\u0633\u062a\u0631 \u0645\u062f\u0631\u0646 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0633\u0628\u06a9 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u0633\u062a.<\/li>\n<li><strong>\u062a\u0648\u062c\u0647 \u0628\u0647 \u062c\u0646\u0633 \u0645\u06cc\u0632 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647:<\/strong> \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0645\u06cc\u0632 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0634\u0645\u0627 \u0686\u0648\u0628\u06cc \u0627\u0633\u062a\u060c \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u0686\u0648\u0628\u06cc \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0647\u0633\u062a\u0646\u062f. \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u0634\u0627\u062e\u0647 \u0627\u06cc \u0686\u0648\u0628\u06cc \u06cc\u0627 \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u0622\u0648\u06cc\u0632 \u062a\u06a9 \u0634\u0639\u0644\u0647 \u06cc\u0627 \u0686\u0646\u062f \u0634\u0639\u0644\u0647 \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631\u0647\u0627 \u0628\u0631\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0647\u0633\u062a\u0646\u062f.<\/li>\n<li><strong>\u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u0631\u062a\u0641\u0627\u0639 \u0633\u0642\u0641 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647:<\/strong> \u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0645\u0648\u0627\u0631\u062f\u06cc \u06a9\u0647 \u062f\u0631 <strong>\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 <\/strong>\u0628\u0647 \u0622\u0646 \u0627\u0634\u0627\u0631\u0647 \u0645\u06cc \u0634\u0648\u062f\u060c \u062a\u0646\u0627\u0633\u0628 \u062f\u0627\u0634\u062a\u0646 \u0627\u0631\u062a\u0641\u0627\u063a \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0648 \u0627\u0631\u062a\u0641\u0627\u0639 \u0644\u0648\u0633\u062a\u0631 \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0647\u0627\u06cc\u06cc \u0628\u0627 \u0633\u0642\u0641 \u0647\u0627\u06cc \u0628\u0644\u0646\u062f\u060c \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u0622\u0648\u06cc\u0632 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D9%87%D9%85%DB%8C%D8%AA_%D9%87%D9%85%D8%A7%D9%87%D9%86%DA%AF_%D8%A8%D9%88%D8%AF%D9%86_%D8%B4%DA%A9%D9%84_%D9%87%D9%86%D8%AF%D8%B3%DB%8C_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%A8%D8%A7_%D9%88%D8%B3%D8%A7%DB%8C%D9%84_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87\"><\/span>\u0627\u0647\u0645\u06cc\u062a \u0647\u0645\u0627\u0647\u0646\u06af \u0628\u0648\u062f\u0646 \u0634\u06a9\u0644 \u0647\u0646\u062f\u0633\u06cc \u0644\u0648\u0633\u062a\u0631 \u0628\u0627 \u0648\u0633\u0627\u06cc\u0644 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0647\u0627 \u0645\u0633\u062a\u0637\u06cc\u0644 \u0634\u06a9\u0644 \u0647\u0633\u062a\u0646\u062f \u0648 \u0628\u0647 \u0627\u06cc\u0646 \u062a\u0631\u062a\u06cc\u0628 \u0645\u06cc\u0632 \u0646\u0647\u0627\u0631 \u062e\u0648\u0631\u06cc \u0647\u0645 \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0645\u062f\u0644 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u06cc \u0634\u0648\u062f. \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0634\u06a9\u0644 \u0647\u0646\u062f\u0633\u06cc \u0645\u0633\u062a\u0637\u06cc\u0644\u060c \u0647\u0645\u0627\u0647\u0646\u06af\u06cc \u062e\u0648\u0628\u06cc \u0628\u0627 \u0627\u06cc\u0646 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0647\u0627 \u062f\u0627\u0631\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 <strong>\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u0686\u0632\u062e\u0627\u0646\u0647<\/strong>\u060c \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u06cc\u0632 \u0646\u0647\u0627\u0631 \u062e\u0648\u0631\u06cc \u0622\u0646\u0647\u0627 \u06af\u0631\u062f \u0627\u0633\u062a\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u06af\u0631\u062f \u0646\u0635\u0628 \u06a9\u0646\u0646\u062f. \u062f\u0631 \u062d\u0642\u06cc\u0642\u062a \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u062a\u06a9 \u0634\u0639\u0644\u0647 \u06cc\u0627 \u0633\u0647 \u0634\u0639\u0644\u0647 \u06af\u0631\u062f\u060c \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u0633\u062a.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D9%86%D9%88%D8%B1_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87\"><\/span>\u0628\u0647\u062a\u0631\u06cc\u0646 \u0646\u0648\u0631 \u0628\u0631\u0627\u06cc \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0644\u0648\u0633\u062a\u0631\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0627\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u06cc \u06a9\u0646\u06cc\u062f\u060c \u0646\u0628\u0627\u06cc\u062f \u0646\u0648\u0631 \u0631\u0627 \u0628\u0647 \u0637\u0648\u0631 \u0645\u0633\u062a\u0642\u06cc\u0645 \u067e\u062e\u0634 \u06a9\u0646\u062f. \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u063a\u06cc\u0631 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u060c \u0646\u0648\u0631 \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u0633\u062a\u0642\u06cc\u0645 \u067e\u062e\u0634 \u0645\u06cc \u06a9\u0646\u0646\u062f \u0648 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0646\u0648\u0631 \u0632\u06cc\u0627\u062f \u0648 \u0645\u0633\u062a\u0642\u06cc\u0645 \u0686\u0634\u0645 \u0634\u0645\u0627 \u0631\u0627 \u0627\u0630\u06cc\u062a \u06a9\u0646\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u06a9\u0647 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0647\u0627 \u062f\u0631 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0627 \u0633\u0627\u0644\u0646 \u0647\u0627\u06cc \u067e\u0630\u06cc\u0631\u0627\u06cc\u06cc\u060c \u0641\u0636\u0627\u06cc \u06a9\u0645\u062a\u0631\u06cc \u062f\u0627\u0631\u0646\u062f\u060c \u0628\u0627\u06cc\u062f \u0627\u0632 \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u062f\u0631 \u0627\u06cc\u0646 \u0641\u0636\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f. \u0637\u0628\u0642 <strong>\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/strong>\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0644\u0648\u0633\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u06a9\u0647 \u0646\u0648\u0631 \u0631\u0627 \u063a\u06cc\u0631 \u0645\u0633\u062a\u0642\u06cc\u0645 \u067e\u062e\u0634 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-39437\" src=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2020\/10\/\u0644\u0648\u0633\u062a\u0631-\u0622\u0634\u067e\u0632\u062e\u0627\u0646\u06471.jpg\" alt=\"\u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\" width=\"700\" height=\"540\" srcset=\"https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2020\/10\/\u0644\u0648\u0633\u062a\u0631-\u0622\u0634\u067e\u0632\u062e\u0627\u0646\u06471.jpg 700w, https:\/\/decorshop.ir\/mag\/wp-content\/uploads\/2020\/10\/\u0644\u0648\u0633\u062a\u0631-\u0622\u0634\u067e\u0632\u062e\u0627\u0646\u06471-300x231.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AE%D8%B1%DB%8C%D8%AF_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87\"><\/span>\u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u0646\u062a\u062e\u0627\u0628 \u0644\u0648\u0633\u062a\u0631 \u0628\u0631\u0627\u06cc \u0641\u0636\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u062f\u0631\u062e\u0627\u0646\u0647 \u0647\u0627\u06cc \u0645\u0627 \u0627\u06cc\u0631\u0627\u0646\u06cc \u0647\u0627 \u06a9\u0647 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0642\u0644\u0628 \u0647\u0631 \u062e\u0627\u0646\u0647 \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc \u0634\u0648\u062f \u06a9\u0645\u06cc \u0645\u0634\u06a9\u0644 \u0648 \u0632\u0645\u0627\u0646 \u0628\u0631 \u0627\u0633\u062a . \u0627\u0632\u0622\u0646 \u062c\u0627 \u06a9\u0647 \u062f\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u067e\u062e\u062a \u0648 \u067e\u0632\u0647\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc \u0634\u0648\u062f \u0628\u0627\u06cc\u062f \u062f\u0627\u0631\u0627\u06cc \u0645\u0646\u0628\u0639 \u0646\u0648\u0631 \u06a9\u0627\u0641\u06cc \u0628\u0627\u0634\u062f \u0648 \u0627\u0632 \u0647\u0645\u0647 \u0645\u0647\u0645 \u062a\u0631 \u0627\u06cc\u0646 \u0645\u0646\u0628\u0639 \u0646\u0648\u0631 \u0628\u0627\u06cc\u062f \u062c\u0648\u0631\u06cc \u0637\u0631\u0627\u062d\u06cc \u0648 \u0633\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f \u06a9\u0647 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u062a\u062d\u0645\u0644 \u062d\u0631\u0627\u0631\u062a \u0648 \u06af\u0631\u0645\u0627\u06cc \u0622\u0646 \u0641\u0636\u0627 \u0631\u0627 \u0628\u0647 \u0639\u0644\u062a \u067e\u062e\u062a \u0648 \u067e\u0632 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f . \u0628\u0631\u0627\u06cc \u0628\u062a\u0648\u0627\u0646 \u06cc\u06a9 \u0627\u0646\u062a\u062e\u0627\u0628 \u062f\u0631\u0633\u062a \u0648 \u0627\u0635\u0648\u0644\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u0645 \u0628\u0627\u06cc\u062f \u0628\u0647 \u0686\u0646\u062f \u0646\u06a9\u062a\u0647 \u06cc \u0627\u0633\u0627\u0633\u06cc \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u0645 .<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%86%DA%A9%D8%AA%D9%87_%D8%A7%D9%88%D9%84\"><\/span>\u0646\u06a9\u062a\u0647 \u0627\u0648\u0644<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0646\u062d\u0648\u0647 \u06cc \u0637\u0631\u0627\u062d\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0645\u06cc \u0628\u0627\u0634\u062f\u060c \u0645\u0639\u0645\u0648\u0644\u0627 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0647\u0627 \u0628\u0647 \u062f\u0648 \u0645\u062f\u0644 \u0637\u0631\u0627\u062d\u06cc \u0645\u06cc \u0634\u0648\u0646\u062f \u06cc\u0627 \u062f\u0627\u0631\u0627\u06cc \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0627 \u0637\u0631\u0627\u062d\u06cc \u0648 \u0633\u0628\u06a9 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0633\u0627\u0644\u0646 \u0647\u0633\u062a\u0646\u062f \u0648 \u06cc\u0627 \u062f\u0627\u0631\u0627\u06cc \u0637\u0631\u0627\u062d\u06cc \u0645\u062c\u0632\u0627 \u0645\u06cc \u0628\u0627\u0634\u0646\u062f . \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644 \u0645\u062b\u0644\u0627 \u06a9\u0627\u0628\u06cc\u0646\u062a \u0647\u0627 \u0648 \u0631\u0646\u06af \u0647\u0627\u06cc \u0628\u0647 \u06a9\u0627\u0631 \u0631\u0641\u062a\u0647 \u062f\u0631 \u0622\u0646 \u0647\u0645 \u0631\u0646\u06af \u0628\u0627 \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0633\u0627\u0644\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a \u0628\u0627\u06cc\u062f \u0628\u0631\u0627\u06cc \u0622\u0646 \u06cc\u06a9 \u0644\u0648\u0633\u062a\u0631\u0645\u0627\u0646\u0646\u062f \u060c\u0644\u0648\u0633\u062a\u0631 \u0633\u0627\u0644\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0634\u0648\u062f \u0648 \u06cc\u0627 \u062f\u0627\u0631\u0627\u06cc \u0637\u0631\u0627\u062d\u06cc \u0648 \u0631\u0646\u06af \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0633\u062a .<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%86%DA%A9%D8%AA%D9%87_%D8%AF%D9%88%D9%85\"><\/span>\u0646\u06a9\u062a\u0647 \u062f\u0648\u0645<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062c\u0646\u0633 \u0648 \u0631\u0646\u06af \u0645\u062a\u0631\u06cc\u0627\u0644 \u0628\u0647 \u06a9\u0627\u0631 \u0631\u0641\u062a\u0647 \u062f\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u0633\u062a \u060c \u0627\u06af\u0631 \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u0632 \u06a9\u0627\u0628\u06cc\u0646\u062a \u0647\u0627\u06cc \u0627\u0645 \u062f\u06cc \u0627\u0641 \u0648 \u0686\u0648\u0628 \u0648 \u0645\u06cc\u0632 \u0646\u0627\u0647\u0627\u0631 \u062e\u0648\u0631\u06cc \u0686\u0648\u0628\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a \u0642\u0637\u0639\u0627 \u0644\u0648\u0633\u062a\u0631 \u0645\u0646\u0627\u0633\u0628 \u0622\u0646 \u0641\u0636\u0627 \u06cc\u06a9 \u0644\u0648\u0633\u062a\u0631 \u0686\u0648\u0628\u06cc \u0645\u06cc \u0628\u0627\u0634\u062f . \u0627\u06af\u0631 \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u0632 \u0645\u062a\u0631\u06cc\u0627\u0644 \u0641\u0644\u0632\u06cc \u0645\u0627\u0646\u0646\u062f \u06a9\u0627\u0628\u06cc\u0646\u062a \u0647\u0627\u06cc \u0641\u0644\u0632\u06cc \u0648&#8230; \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a \u0645\u0627 \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0631 \u067e\u0627\u06cc\u0647 \u0645\u0648\u0627\u062f \u0641\u0644\u0632\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0646\u062f \u0631\u0627 \u0628\u0647 \u0634\u0645\u0627 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc \u062f\u0647\u06cc\u0645 .<\/p>\n<p>\u0627\u06af\u0631 \u0637\u0631\u0627\u062d\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u06cc \u0634\u0645\u0627 \u0645\u062f\u0631\u0646 \u0627\u0633\u062a \u0648 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0627\u0632 \u0686\u0646\u062f \u0645\u062a\u0631\u06cc\u0627\u0644 \u0645\u062e\u062a\u0644\u0641 \u0627\u0633\u062a \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0628\u0647 \u0633\u0631\u0627\u063a \u0644\u0648\u0633\u062a\u0631\u0647\u0627 \u0648 \u0622\u0648\u06cc\u0632 \u0647\u0627\u06cc \u0633\u0627\u062f\u0647 \u0648 \u0645\u062f\u0631\u0646 \u0628\u0631\u0648\u06cc\u062f \u06a9\u0647 \u062f\u0631 \u0686\u0646\u062f \u0633\u0627\u0644 \u0627\u062e\u06cc\u0631 \u0631\u0634\u062f \u0632\u06cc\u0627\u062f\u06cc \u0646\u06cc\u0632 \u0627\u06cc\u0646 \u062a\u0627\u06cc\u067e \u0644\u0648\u0633\u062a\u0631\u0647\u0627 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a .<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%86%DA%A9%D8%AA%D9%87_%DB%8C_%D8%B3%D9%88%D9%85\"><\/span>\u0646\u06a9\u062a\u0647 \u06cc \u0633\u0648\u0645<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0627\u06af\u0631 \u062f\u0631 <a href=\"https:\/\/decorshop.ir\/product-category\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1%d9%87%d8%a7-%d8%a8%d8%b1-%d8%a7%d8%b3%d8%a7%d8%b3-%da%a9%d8%a7%d8%b1%d8%a8%d8%b1%d8%af\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87\/\">\u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/a> \u062e\u0648\u062f \u0645\u06cc\u0632 \u0646\u0627\u0647\u0627\u0631 \u062e\u0648\u0631\u06cc \u0631\u0627 \u0642\u0631\u0627\u0631 \u0645\u06cc \u062f\u0647\u06cc\u062f \u0628\u0627\u06cc\u062f \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0634\u06a9\u0644 \u0645\u06cc\u0632 \u0646\u0627\u0647\u0627\u0631\u062e\u0648\u0631\u06cc \u0628\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0648 \u062e\u0631\u06cc\u062f\u0646 \u0645\u06cc\u0632 \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u06cc\u062f \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644 \u0627\u06af\u0631 \u0645\u06cc\u0632 \u0646\u0627\u0647\u0627\u0631\u062e\u0648\u0631\u06cc \u0634\u0645\u0627 \u0645\u0633\u062a\u0637\u06cc\u0644 \u0634\u06a9\u0644 \u0627\u0633\u062a \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u062f\u0644 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0622\u0648\u06cc\u0632 \u0647\u0627\u06cc \u0645\u0633\u062a\u0637\u06cc\u0644\u06cc \u0634\u06a9\u0644 \u0648 \u0627\u06af\u0631 \u0645\u06cc\u0632 \u0634\u0645\u0627 \u062f\u0627\u06cc\u0631\u0647 \u0627\u06cc \u0634\u06a9\u0644 \u0627\u0633\u062a \u0645\u062f\u0644 \u0647\u0627\u06cc \u062a\u06a9 \u0634\u0639\u0644\u0647 \u0648 \u06cc\u0627 \u0633\u0647 \u0634\u0639\u0644\u0647 \u062f\u0627\u06cc\u0631\u0647 \u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0627\u0633\u0628 \u0645\u06cc \u0628\u0627\u0634\u062f .<\/p>\n<p>\u0627\u06af\u0631 \u0645\u06cc\u0632 \u0646\u0627\u0647\u0627\u0631\u062e\u0648\u0631\u06cc \u0648 \u0637\u0631\u0627\u062d\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0634\u0645\u0627 \u0645\u0631\u0628\u0639\u06cc \u0634\u06a9\u0644 \u0627\u0633\u062a \u0622\u0648\u06cc\u0632 \u0647\u0627\u06cc \u0631\u06cc\u0633\u0647 \u0627\u06cc \u0648 \u0686\u0647\u0627\u0631 \u0636\u0644\u0639\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0627\u0633\u0628 \u0647\u0633\u062a\u0646\u062f .<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%86%DA%A9%D8%AA%D9%87_%DB%8C_%DA%86%D9%87%D8%A7%D8%B1%D9%85\"><\/span>\u0646\u06a9\u062a\u0647 \u06cc \u0686\u0647\u0627\u0631\u0645<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u06a9\u0647 \u0628\u0627\u06cc\u062f \u0628\u0647 \u0622\u0646 \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u0645 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0645\u0639\u0645\u0648\u0644\u0627 \u0628\u0627\u0644\u0627\u06cc \u0627\u067e\u0646 \u0648 \u06cc\u0627 \u062c\u0632\u06cc\u0631\u0647 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u0632 \u0646\u0648\u0631 \u0647\u0627\u06cc \u0647\u0627\u0644\u0648\u0698\u0646 \u0628\u0631\u0627\u06cc \u06a9\u0645\u06a9 \u0628\u0647 \u0645\u0646\u0628\u0639 \u0646\u0648\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f . \u0634\u0645\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0633\u062a\u0647 \u0628\u0647 \u0637\u0631\u0627\u062d\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u062e\u0648\u062f \u0627\u0632 \u0622\u0648\u06cc\u0632 \u0647\u0627\u06cc \u062a\u06a9 \u0634\u0639\u0644\u0647 \u0648 \u06cc\u0627 \u0644\u0627\u0645\u067e \u0647\u0627\u06cc \u0627\u062f\u06cc\u0633\u0648\u0646\u06cc \u0648.. \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0631\u0627\u0633\u0627\u0633 \u062a\u062d\u0642\u06cc\u0642 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0646\u062c\u0627\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a \u0628\u0631\u062e\u06cc \u0627\u0632 \u0646\u0648\u0631\u0647\u0627 \u062f\u0631 \u062a\u062d\u0631\u06cc\u06a9 \u0627\u0634\u062a\u0647\u0627 \u0648 \u0628\u0627\u0632 \u0634\u062f\u0646 \u0622\u0646 \u0627\u062b\u0631 \u0628\u0633\u0632\u0627\u06cc\u06cc \u062f\u0627\u0631\u0646\u062f \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062f\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0631\u0646\u06af \u0646\u0648\u0631 \u062f\u0631\u06cc\u0627\u0641\u062a\u06cc \u0646\u06cc\u0632 \u062f\u0642\u062a \u06a9\u0646\u06cc\u062f \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644 \u0646\u0648\u0631\u0647\u0627\u06cc \u0642\u0631\u0645\u0632 \u0648 \u0632\u0631\u062f \u0648 \u0646\u0627\u0631\u0646\u062c\u06cc \u0628\u0633\u06cc\u0627\u0631 \u062a\u062d\u0631\u06cc\u06a9 \u06a9\u0646\u0646\u062f\u0647 \u06cc \u0627\u0634\u062a\u0647\u0627 \u0645\u06cc \u0628\u0627\u0634\u062f \u0648 \u062f\u0631\u0645\u0642\u0627\u0628\u0644 \u0627\u06cc\u0646 \u0631\u0646\u06af \u0647\u0627 \u0646\u0648\u0631 \u062e\u0627\u06a9\u0633\u062a\u0631\u06cc \u0627\u0634\u062a\u0647\u0627 \u0631\u0627 \u0628\u0647 \u0642\u062f\u0631 \u0686\u0634\u0645 \u06af\u06cc\u0631\u06cc \u06a9\u0645 \u0645\u06cc \u06a9\u0646\u062f .<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%84%D9%88%D8%B3%D8%AA%D8%B1%D9%87%D8%A7%DB%8C_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D9%81%D8%B6%D8%A7%DB%8C_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87\"><\/span><a href=\"https:\/\/decorshop.ir\/product-category\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1%d9%87%d8%a7-%d8%a8%d8%b1-%d8%a7%d8%b3%d8%a7%d8%b3-%da%a9%d8%a7%d8%b1%d8%a8%d8%b1%d8%af\/%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%a2%d8%b4%d9%be%d8%b2%d8%ae%d8%a7%d9%86%d9%87\/\">\u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0641\u0636\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/a> :<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0647\u0645\u0627\u0646 \u0637\u0648\u0631 \u06a9\u0647 \u06af\u0641\u062a\u06cc\u0645 \u0628\u0633\u062a\u0647 \u0628\u0647 \u0637\u0631\u0627\u062d\u06cc \u0648 \u0633\u0628\u06a9 \u0628\u0647 \u06a9\u0627\u0631 \u0631\u0641\u062a\u0647 \u062f\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0634\u0645\u0627 \u0628\u0627\u06cc\u062f \u0628\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0648 \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0628\u0631\u0627\u06cc \u0622\u0646 \u0641\u0636\u0627 \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u06cc\u062f. \u0648\u0644\u06cc \u062f\u0631 \u0644 \u0628\u0639\u0636\u06cc \u0627\u0632 \u062a\u0627\u06cc\u067e \u0647\u0627 \u0627\u0632 \u0644\u0648\u0633\u062a\u0631\u0647\u0627 \u0631\u0627 \u0628\u0647 \u0646\u062f\u0631\u062a \u062f\u0631 \u0641\u0636\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644 \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u060c \u0634\u0627\u062e\u0647 \u0627\u06cc \u0648 \u0686\u0646\u062f \u0637\u0628\u0642\u0647 \u0627\u0635\u0644\u0627 \u0628\u0647 \u0639\u0644\u062a \u0637\u0631\u0627\u062d\u06cc \u062e\u0627\u0635\u06cc \u06a9\u0647 \u062f\u0627\u0631\u0646\u062f \u0645\u0646\u0627\u0633\u0628 \u0641\u0636\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0646\u0645\u06cc \u0628\u0627\u0634\u0646\u062f \u0645\u06af\u0631 \u0627\u06cc\u0646\u06a9\u0647 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u06cc \u0628\u0627 \u0637\u0631\u0627\u062d\u06cc \u062e\u0627\u0635 \u0648 \u0645\u062c\u0644\u0644 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f . \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0644\u0648\u0633\u062a\u0631 \u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0648 \u0633\u0627\u062f\u0647 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0641\u0636\u0627 \u0647\u0627 \u0645\u0646\u0627\u0633\u0628 \u0645\u06cc \u0628\u0627\u0634\u0646\u062f . \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0686\u0646\u062f \u0645\u062f\u0644 \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0628\u0627 \u0648 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0645\u06cc \u067e\u0631\u062f\u0627\u0632\u06cc\u0645 \u0628\u0627 \u0645\u0627 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627\u0634\u06cc\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28936\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/7-4.jpg\" alt=\"\" width=\"600\" height=\"600\" \/><\/p>\n<p>\u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u0628\u0647 \u0639\u0644\u062a \u0637\u0631\u0627\u062d\u06cc \u062e\u0627\u0635\u06cc \u06a9\u0647 \u062f\u0627\u0631\u062f \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0627\u0633\u0628 \u0641\u0636\u0627\u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0645\u06cc \u0628\u0627\u0634\u062f \u0648 \u0627\u0632 \u0622\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647 \u0622\u0633\u0627\u0646\u06cc \u062f\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0647\u0627\u06cc\u06cc \u0628\u0627 \u0647\u0631 \u0637\u0631\u062d \u0648 \u0633\u0628\u06a9\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f . \u0645\u0639\u0645\u0648\u0644\u0627 \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0631\u0627 \u062f\u0631 \u0631\u0646\u06af\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u06cc \u06a9\u0646\u0646\u062f \u06a9\u0647 \u062f\u0631 \u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u06a9\u0627\u0628\u06cc\u0646\u062a \u0647\u0627\u06cc \u0622\u0646 \u0641\u0636\u0627 \u0628\u0627\u0634\u062f \u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u0628\u0647 \u0639\u0644\u062a \u0631\u0646\u06af \u062e\u0646\u062b\u06cc\u06cc \u06a9\u0647 \u062f\u0627\u0631\u062f \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0628\u0627 \u0647\u0631 \u0633\u0628\u06a9 \u0648 \u0631\u0646\u06af\u06cc \u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u0637\u0627\u0628\u0642 \u062f\u0627\u0631\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28939\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/2-11.jpg\" alt=\"\" width=\"600\" height=\"600\" \/><\/p>\n<p>\u0627\u06af\u0631 \u062f\u0631 \u0641\u0636\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u06cc \u062e\u0648\u062f \u06cc\u06a9 \u0645\u06cc\u0632 \u06af\u0631\u062f \u0646\u0627\u0647\u0627\u0631 \u062e\u0648\u0631\u06cc \u062f\u0627\u0631\u06cc\u062f \u0648 \u06cc\u0627 \u0646\u0647 \u0686\u06cc\u062f\u0645\u0627\u0646 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0634\u0645\u0627 \u06af\u0631\u062f \u0627\u0633\u062a \u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0627\u0633\u0628 \u0641\u0636\u0627\u06cc \u0634\u0645\u0627 \u0645\u06cc \u0628\u0627\u0634\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28941\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/3-11.jpg\" alt=\"\" width=\"300\" height=\"300\" \/><\/p>\n<p>\u0627\u06af\u0631 \u06cc\u06a9 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0628\u0627 \u0637\u0631\u0627\u062d\u06cc \u0686\u0648\u0628\u06cc \u062f\u0627\u0631\u06cc\u062f \u0648\u0644\u06cc \u0647\u0645 \u0632\u0645\u0627\u0646 \u0628\u0647 \u0644\u0648\u0633\u062a\u0631 \u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0639\u0644\u0627\u0642\u0647 \u062f\u0627\u0631\u06cc\u062f . \u0645\u0627 \u0627\u06cc\u0646 \u0645\u062f\u0644 \u0627\u0632 \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc \u0686\u0634\u0645\u0647 \u0646\u0648\u0631 \u0631\u0627 \u0628\u0647 \u0634\u0645\u0627 \u0645\u0639\u0631\u0641\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u0645 . \u0627\u0632 \u0627\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u0647\u0645\u0686\u0646\u06cc\u0646\u06cc \u0645\u06cc \u062a\u0648\u0627\u0646 \u062f\u0631 \u0628\u0627\u0644\u0627\u06cc \u0645\u06cc\u0632 \u0646\u0627\u0647\u0627\u0631 \u062e\u0648\u0631\u06cc \u0645\u0633\u062a\u0637\u06cc\u0644\u06cc \u0634\u06a9\u0644 \u0646\u06cc\u0632 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28942\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2020\/10\/4-7.jpg\" alt=\"\" width=\"225\" height=\"225\" \/><\/p>\n<p>\u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0622\u0648\u06cc\u0632 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0628\u0627\u0644\u0627\u06cc \u067e\u06cc\u0634\u062e\u0648\u0627\u0646 \u0648 \u06cc\u0627 \u062c\u0632\u06cc\u0631\u0647 \u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u06cc \u062e\u0648\u062f \u0647\u0633\u062a\u06cc\u062f \u0648 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0645\u0647\u0645 \u0627\u0633\u062a \u06a9\u0647 \u0627\u06cc\u0646 \u0622\u0648\u06cc\u0632 \u0647\u0627 \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0647\u0627\u06cc \u062e\u0627\u0635\u06cc \u0646\u06cc\u0632 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u0645\u0627 \u0627\u06cc\u0646 \u0645\u062f\u0644 \u0631\u0627 \u0628\u0647 \u0634\u0645\u0627 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc \u062f\u0647\u06cc\u0645 .<\/p>\n<p>\u0634\u0645\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0645\u062f\u0644 \u0647\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u062a\u0627\u06cc\u067e \u0644\u0648\u0633\u062a\u0631\u0647\u0627 \u0631\u0627 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062a\u0648\u0636\u06cc\u062d\u0627\u062a \u0644\u0627\u0632\u0645\u0647 \u062f\u0631 \u0648\u0628 \u0633\u0627\u06cc\u062a <a href=\"http:\/\/decorshop.ir\">\u062f\u06a9\u0648\u0631\u0634\u0627\u067e<\/a> \u0645\u0634\u0627\u0647\u062f\u0647 \u06a9\u0631\u062f\u0647 \u0648 \u062f\u0631 \u0635\u0648\u0631\u062a \u067e\u0634\u0646\u062f \u0628\u0647 \u062e\u0631\u06cc\u062f \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0622\u0646 \u0627\u0642\u062f\u0627\u0645 \u0646\u0645\u0627\u06cc\u06cc\u062f . \u0647\u0645\u06a9\u0627\u0631\u0627\u0646 \u0645\u0627 \u062f\u0631 \u0637\u0648\u0644 \u0634\u0628\u0627\u0646\u0647 \u0631\u0648\u0632 \u0622\u0645\u0627\u062f\u0647 \u067e\u0627\u0633\u062e \u06af\u0648\u06cc\u06cc \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a \u0627\u062d\u062a\u0645\u0627\u0644\u06cc \u0634\u0645\u0627 \u0647\u0633\u062a\u0646\u062f. \u062a\u0645\u0627\u0645 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0648\u0628 \u0633\u0627\u06cc\u062a \u0645\u0627 \u0628\u0627 <a href=\"http:\/\/chenco.ir\" target=\"_blank\" rel=\"noopener\">\u0627\u0631\u0633\u0627\u0644 \u0627\u0631\u06cc\u06af\u0627\u0646<\/a> \u0648 \u0628\u0627 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u06cc\u0641\u06cc\u062a \u062f\u0631 \u0627\u0631\u0633\u0627\u0644 \u0648 \u0628\u0633\u062a\u0647 \u0628\u0646\u062f\u06cc \u0628\u0647 \u062f\u0633\u062a \u0634\u0645\u0627 \u0639\u0632\u06cc\u0632\u0627\u0646 \u0627\u0631\u0633\u0627\u0644 \u0645\u06cc \u0634\u0648\u062f . \u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u0645 \u0645\u0637\u0627\u0644\u0628 \u06af\u0641\u062a\u0647 \u0634\u062f\u0647 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0645\u0641\u06cc\u062f \u0628\u0648\u062f\u0647 \u0628\u0627\u0634\u062f \u0628\u0627 \u0645\u0627 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627\u0634\u06cc\u062f .<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AC%D9%85%D8%B9_%D8%A8%D9%86%D8%AF%DB%8C\"><\/span>\u062c\u0645\u0639 \u0628\u0646\u062f\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062a\u0648\u062c\u0647 \u0628\u0647 \u0631\u0646\u06af \u06a9\u0627\u0628\u06cc\u0646\u062a \u0647\u0627\u060c \u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0645\u0648\u0627\u0631\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 <strong>\u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<\/strong> \u0628\u0647 \u0622\u0646 \u062a\u0648\u062c\u0647 \u0645\u06cc \u0634\u0648\u062f. \u062f\u0631 \u062d\u0642\u06cc\u0642\u062a \u0647\u0645\u0627\u0647\u0646\u06af \u0628\u0648\u062f\u0646 \u0644\u0648\u0633\u062a\u0631 \u0628\u0627 \u06a9\u0627\u0628\u06cc\u0646\u062a \u0647\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\u060c \u0627\u0647\u0645\u06cc\u062a \u0632\u06cc\u0627\u062f\u06cc \u062f\u0631 \u0637\u0631\u0627\u062d\u06cc \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u062f\u0627\u062e\u0644\u06cc \u062f\u0627\u0631\u062f. \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u06a9\u0627\u0628\u06cc\u0646\u062a \u0647\u0627\u06cc \u0631\u0648\u0634\u0646 \u06cc\u0627 \u0637\u0648\u0633\u06cc \u062f\u0627\u0631\u0646\u062f\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0627\u0632 \u0644\u0648\u0633\u062a\u0631\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0628\u062f\u0646\u0647 \u0631\u0648\u0634\u0646 \u06cc\u0627 \u0646\u0642\u0631\u0647 \u0627\u06cc \u062f\u0631 \u0622\u0646\u0647\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u0648\u062f.<\/p>\n<p>\u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u06cc\u0645 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0645\u0641\u06cc\u062f \u0628\u0648\u062f\u0647 \u0628\u0627\u0634\u062f. \u0645\u0627 \u0631\u0627 \u0627\u0632 \u0646\u0638\u0631\u0627\u062a \u0648 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u0627\u062a \u062e\u0648\u062f \u0628\u06cc \u0628\u0647\u0631\u0647 \u0646\u06af\u0630\u0627\u0631\u06cc\u062f \u0648 \u0627\u06af\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0631\u0627 \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u06cc\u062f \u0628\u0631\u0627\u06cc\u0645\u0627\u0646 \u06a9\u0627\u0645\u0646\u062a \u0628\u06af\u0630\u0627\u0631\u06cc\u062f. \u0645\u0637\u0627\u0644\u0628 \u0645\u0641\u06cc\u062f \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0631\u0627 \u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u062f \u062f\u0631 <a href=\"\/mag\/\"><strong>\u062f\u06a9\u0648\u0631\u0645\u06af<\/strong> <\/a>\u0648 <a href=\"https:\/\/chenco.ir\/blog\/\" rel=\"sponsored noopener\" data-schema-attribute=\"\" target=\"_blank\"><strong>\u0648\u0628\u0644\u0627\u06af \u0686\u0634\u0645\u0647 \u0646\u0648\u0631<\/strong> <\/a>\u0645\u0637\u0627\u0644\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<blockquote><p><em>\u062e\u0648\u0627\u0646\u062f\u0646 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0631\u0627 \u0646\u06cc\u0632 \u0628\u0647 \u0634\u0645\u0627 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u06a9\u0646\u06cc\u0645:<\/em><\/p><\/blockquote>\n<p><a href=\"\/mag\/\u0637\u0631\u0627\u062d\u06cc-\u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646-\u0633\u0628\u06a9-\u0641\u0631\u0627\u0646\u0633\u0648\u06cc-\u0628\u0627-\u0645\u0639\u0631\u0641\u06cc-\u06f7\/\"><strong>\u0637\u0631\u0627\u062d\u06cc \u062f\u06a9\u0648\u0631\u0627\u0633\u06cc\u0648\u0646 \u0633\u0628\u06a9 \u0641\u0631\u0627\u0646\u0633\u0648\u06cc \u0628\u0627 \u0645\u0639\u0631\u0641\u06cc \u06f7 \u0637\u0631\u0627\u062d \u0645\u0634\u0647\u0648\u0631<\/strong><\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B3%D9%88%D8%A7%D9%84%D8%A7%D8%AA_%D9%85%D8%AA%D8%AF%D8%A7%D9%88%D9%84_%D8%AF%D8%B1_%D9%85%D9%88%D8%B1%D8%AF_%D8%AE%D8%B1%DB%8C%D8%AF_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87\"><\/span>\u0633\u0648\u0627\u0644\u0627\u062a \u0645\u062a\u062f\u0627\u0648\u0644 \u062f\u0631 \u0645\u0648\u0631\u062f \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647<span class=\"ez-toc-section-end\"><\/span><\/h2>\n        <section class=\"sc_fs_faq sc_card \">\n            <div>\n\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"%D8%A8%D8%B1%D8%A7%DB%8C_%D8%B1%D9%88%D8%B4%D9%86%D8%A7%DB%8C%DB%8C_%D8%A8%D8%A7%D9%84%D8%A7%DB%8C_%D8%A7%D9%BE%D9%86_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87%D8%8C_%DA%86%D9%87_%D9%84%D9%88%D8%B3%D8%AA%D8%B1%DB%8C_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D8%A7%D8%B3%D8%AA%D8%9F\"><\/span>\u0628\u0631\u0627\u06cc \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627\u0644\u0627\u06cc \u0627\u067e\u0646 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\u060c \u0686\u0647 \u0644\u0648\u0633\u062a\u0631\u06cc \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a\u061f<span class=\"ez-toc-section-end\"><\/span><\/h3>                <div>\n\t\t\t\t\t                    <p>\n\t\t\t\t\t\t\u0628\u0631\u0627\u06cc \u062f\u0627\u0634\u062a\u0646 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u06cc \u0628\u0627 \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u062c\u0630\u0627\u0628\u060c \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0637\u0648\u0644 \u0627\u067e\u0646\u060c \u0627\u0632 \u0622\u0648\u06cc\u0632\u0647\u0627\u06cc \u062a\u06a9 \u0634\u0639\u0644\u0647 \u06cc\u0627 \u0686\u0646\u062f \u0634\u0639\u0644\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.                     <\/p>\n                <\/div>\n            <\/div>\n        <\/section>\n\t\t        <section class=\"sc_fs_faq sc_card \">\n            <div>\n\t\t\t\t<h3><span class=\"ez-toc-section\" id=\"%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D8%B1%D9%86%DA%AF_%D9%84%D8%A7%D9%85%D9%BE_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%84%D9%88%D8%B3%D8%AA%D8%B1_%D8%A2%D8%B4%D9%BE%D8%B2%D8%AE%D8%A7%D9%86%D9%87_%DA%86%D9%87_%D8%B1%D9%86%DA%AF%DB%8C_%D8%A7%D8%B3%D8%AA%D8%9F\"><\/span>\u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0646\u06af \u0644\u0627\u0645\u067e \u0628\u0631\u0627\u06cc \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0686\u0647 \u0631\u0646\u06af\u06cc \u0627\u0633\u062a\u061f<span class=\"ez-toc-section-end\"><\/span><\/h3>                <div>\n\t\t\t\t\t                    <p>\n\t\t\t\t\t\t\u0628\u0631 \u0637\u0628\u0642 \u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\u060c \u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0646\u06af \u0628\u0631\u0627\u06cc \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0631\u0646\u06af \u0632\u0631\u062f \u0648 \u0633\u0641\u06cc\u062f \u0627\u0633\u062a.                     <\/p>\n                <\/div>\n            <\/div>\n        <\/section>\n\t\t\n<script type=\"application\/ld+json\">\n    {\n\t\t\"@context\": \"https:\/\/schema.org\",\n\t\t\"@type\": \"FAQPage\",\n\t\t\"mainEntity\": [\n\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\u0628\u0631\u0627\u06cc \u0631\u0648\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627\u0644\u0627\u06cc \u0627\u067e\u0646 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\u060c \u0686\u0647 \u0644\u0648\u0633\u062a\u0631\u06cc \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a\u061f\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"\u0628\u0631\u0627\u06cc \u062f\u0627\u0634\u062a\u0646 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u06cc \u0628\u0627 \u0646\u0648\u0631\u067e\u0631\u062f\u0627\u0632\u06cc \u062c\u0630\u0627\u0628\u060c \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0637\u0648\u0644 \u0627\u067e\u0646\u060c \u0627\u0632 \u0622\u0648\u06cc\u0632\u0647\u0627\u06cc \u062a\u06a9 \u0634\u0639\u0644\u0647 \u06cc\u0627 \u0686\u0646\u062f \u0634\u0639\u0644\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t,\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0646\u06af \u0644\u0627\u0645\u067e \u0628\u0631\u0627\u06cc \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0686\u0647 \u0631\u0646\u06af\u06cc \u0627\u0633\u062a\u061f\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"\u0628\u0631 \u0637\u0628\u0642 \u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\u060c \u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0646\u06af \u0628\u0631\u0627\u06cc \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0631\u0646\u06af \u0632\u0631\u062f \u0648 \u0633\u0641\u06cc\u062f \u0627\u0633\u062a.\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t\t    ]\n}\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"<p>\u0628\u0627 \u062e\u0648\u0627\u0646\u062f\u0646 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u06a9\u0647 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0631\u0627\u0647\u0646\u0645\u0627\u06cc \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u0633\u062a\u060c \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u0648 \u0645\u0646\u0627\u0633\u0628 \u062a\u0631\u06cc\u0646 \u0644\u0648\u0633\u062a\u0631 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u062e\u0648\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f. \u067e\u0633 \u062a\u0627 \u0627\u0646\u062a\u0647\u0627\u06cc \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u062f\u06a9\u0648\u0631\u0645\u06af \u0647\u0645\u0631\u0627\u0647 \u0645\u0627 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0628\u0627 \u0646\u06a9\u0627\u062a \u0645\u0647\u0645 \u062f\u0631 \u0645\u0648\u0631\u062f \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0622\u0634\u0646\u0627 \u0634\u0648\u06cc\u062f. \u0646\u06a9\u0627\u062a \u0645\u0647\u0645 \u062f\u0631 \u0645\u0648\u0631\u062f \u062e\u0631\u06cc\u062f \u0644\u0648\u0633\u062a\u0631 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u06cc\u06a9 \u0644\u0648\u0633\u062a\u0631 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":32748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[202,203,34],"tags":[],"class_list":["post-28938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-202","category-203","category-34"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/28938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=28938"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/28938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/32748"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=28938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=28938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=28938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}