{"id":14166,"date":"2019-09-24T13:02:26","date_gmt":"2019-09-24T13:02:26","guid":{"rendered":"https:\/\/decorshop.ir\/?p=14166"},"modified":"2023-04-27T12:09:54","modified_gmt":"2023-04-27T08:39:54","slug":"choosing-the-perfect-wallpaper","status":"publish","type":"post","link":"https:\/\/decorshop.ir\/mag\/choosing-the-perfect-wallpaper\/","title":{"rendered":"6 \u0646\u06a9\u062a\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc &#8211; \u0627\u06cc\u0646 \u06cc\u06a9\u06cc \u0628\u0647 \u062a\u0646 \u062e\u0627\u0646\u0647 \u0634\u0645\u0627 \u0645\u06cc\u200c\u0646\u0634\u06cc\u0646\u062f!"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/decorshop.ir\/mag\/choosing-the-perfect-wallpaper\/#%D9%86%DA%A9%D8%A7%D8%AA%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%A9%D8%A7%D8%BA%D8%B0_%D8%AF%DB%8C%D9%88%D8%A7%D8%B1%DB%8C\" >\u0646\u06a9\u0627\u062a\u06cc \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/decorshop.ir\/mag\/choosing-the-perfect-wallpaper\/#%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%A9%D8%A7%D8%BA%D8%B0_%D8%AF%DB%8C%D9%88%D8%A7%D8%B1%DB%8C_%DA%86%D9%87_%D8%B7%D8%B1%D8%AD_%D9%88_%D9%86%D9%82%D8%B4%DB%8C_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D8%AE%D8%A7%D9%86%D9%87_%D9%85%D8%A7%D8%B3%D8%AA%D8%9F\" >\u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc | \u0686\u0647 \u0637\u0631\u062d \u0648 \u0646\u0642\u0634\u06cc \u0645\u0646\u0627\u0633\u0628 \u062e\u0627\u0646\u0647 \u0645\u0627\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/decorshop.ir\/mag\/choosing-the-perfect-wallpaper\/#%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%A9%D8%A7%D8%BA%D8%B0_%D8%AF%DB%8C%D9%88%D8%A7%D8%B1%DB%8C_%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D8%AC%D9%86%D8%B3_%DA%A9%D8%A7%D8%BA%D8%B0_%D8%AF%DB%8C%D9%88%D8%A7%D8%B1%DB%8C_%D8%B1%D8%A7_%D9%85%DB%8C%E2%80%8C%D8%B4%D9%86%D8%A7%D8%B3%DB%8C%D8%AF%D8%9F\" >\u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc | \u0628\u0647\u062a\u0631\u06cc\u0646 \u062c\u0646\u0633 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0631\u0627 \u0645\u06cc\u200c\u0634\u0646\u0627\u0633\u06cc\u062f\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/decorshop.ir\/mag\/choosing-the-perfect-wallpaper\/#%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%A9%D8%A7%D8%BA%D8%B0_%D8%AF%DB%8C%D9%88%D8%A7%D8%B1%DB%8C_%D8%AE%D8%A7%D9%86%D9%87_%D9%85%D9%86_%DA%86%D9%86%D8%AF_%D9%85%D8%AA%D8%B1_%DA%A9%D8%A7%D8%BA%D8%B0_%D8%AF%DB%8C%D9%88%D8%A7%D8%B1%DB%8C_%D9%84%D8%A7%D8%B2%D9%85_%D8%AF%D8%A7%D8%B1%D8%AF%D8%9F\" >\u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc | \u062e\u0627\u0646\u0647 \u0645\u0646 \u0686\u0646\u062f \u0645\u062a\u0631 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0644\u0627\u0632\u0645 \u062f\u0627\u0631\u062f\u061f<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D9%86%DA%A9%D8%A7%D8%AA%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%A9%D8%A7%D8%BA%D8%B0_%D8%AF%DB%8C%D9%88%D8%A7%D8%B1%DB%8C\"><\/span>\u0646\u06a9\u0627\u062a\u06cc \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062f\u06cc\u06af\u0631 \u0631\u0648\u0632\u06af\u0627\u0631 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u06a9\u0650\u0631\u0650\u0645 \u0631\u0646\u06af \u0648 \u0627\u0633\u062a\u062e\u0648\u0627\u0646\u06cc \u062e\u0627\u0646\u0647 \u0645\u0627\u062f\u0631\u0628\u0632\u0631\u06af\u200c\u0647\u0627\u06cc\u0645\u0627\u0646 \u0628\u0647 \u0633\u0631 \u0622\u0645\u062f\u0647 \u0627\u0633\u062a \u0648 \u0628\u0627\u06cc\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u062c\u062f\u06cc\u062f\u06cc \u0631\u0627 \u062f\u0631 \u0628\u0631\u0646\u0627\u0645\u0647 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u0645. \u0632\u0645\u0627\u0646 \u0622\u0646 \u0631\u0633\u06cc\u062f\u0647 \u062a\u0627 \u0634\u0627\u0646\u0633 \u062c\u062f\u06cc\u062f\u06cc \u0628\u0647 \u06a9\u0627\u063a\u062f \u062f\u06cc\u0648\u0627\u0631\u06cc \u0628\u062f\u0647\u06cc\u0645. \u0634\u0627\u06cc\u062f \u062f\u0631 \u0631\u0642\u0627\u0628\u062a \u0628\u0627 \u0631\u0646\u06af \u06a9\u0631\u062f\u0646 \u062f\u06cc\u0648\u0627\u0631 \u067e\u06cc\u0631\u0648\u0632 \u0634\u0648\u062f! \u0627\u0645\u0631\u0648\u0632 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u0645 \u0628\u062e\u0648\u0627\u0646\u06cc\u0645 \u06a9\u0647 \u0686\u06af\u0648\u0646\u0647 \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631\u06cc\u0646 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u0645\u061f<\/p>\n<p>\u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0628\u0631\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0627 \u0627\u062d\u0633\u0627\u0633 \u0646\u0648\u0633\u062a\u0627\u0644\u0698\u06cc\u06a9\u06cc \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0631\u062f. \u0648 \u0628\u0631\u0627\u06cc \u0628\u0631\u062e\u06cc \u06cc\u0627\u062f\u0622\u0648\u0631 \u0631\u0648\u0632\u0647\u0627\u06cc \u062a\u0644\u062e \u06a9\u0646\u062f\u0646 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0627\u0632 \u0631\u0648\u06cc \u062f\u06cc\u0648\u0627\u0631. \u062a\u0627 \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0647\u0645\u06cc\u0634\u0647 \u062f\u0648\u0631\u0634 \u0631\u0627 \u062e\u0637 \u0642\u0631\u0645\u0632 \u0645\u06cc\u200c\u06a9\u0634\u0646\u062f. \u0634\u0627\u06cc\u062f \u0647\u0645 \u062a\u0635\u0648\u0631 \u0628\u0631\u062e\u06cc \u0627\u0632 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc\u060c \u0637\u0631\u062d\u200c\u0647\u0627\u06cc \u06af\u0644 \u062f\u0631\u0634\u062a \u0648 \u0628\u0631\u062c\u0633\u062a\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0633\u0644\u06cc\u0642\u0647 \u0627\u06cc\u0631\u0627\u0646\u06cc \u0646\u0645\u06cc\u200c\u067e\u0633\u0646\u062f\u062f. \u0627\u0645\u0627 \u0645\u062f\u062a \u0632\u0645\u0627\u0646\u06cc\u200c\u0633\u062a \u06a9\u0647 \u062f\u0648\u0628\u0627\u0631\u0647 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u062c\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0627\u0632 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0628\u0627 \u0637\u0631\u062d \u0648 \u0646\u0642\u0634\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0647\u0631 \u0646\u06af\u0627\u0647\u06cc \u0631\u0627 \u0628\u0647 \u0633\u0645\u062a \u062e\u0648\u062f \u0645\u06cc\u200c\u06a9\u0634\u0627\u0646\u062f.<\/p>\n<h2 style=\"font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-family: IRANSans-fa;\"><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%A9%D8%A7%D8%BA%D8%B0_%D8%AF%DB%8C%D9%88%D8%A7%D8%B1%DB%8C_%DA%86%D9%87_%D8%B7%D8%B1%D8%AD_%D9%88_%D9%86%D9%82%D8%B4%DB%8C_%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D8%AE%D8%A7%D9%86%D9%87_%D9%85%D8%A7%D8%B3%D8%AA%D8%9F\"><\/span>\u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc | \u0686\u0647 \u0637\u0631\u062d \u0648 \u0646\u0642\u0634\u06cc \u0645\u0646\u0627\u0633\u0628 \u062e\u0627\u0646\u0647 \u0645\u0627\u0633\u062a\u061f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2019\/09\/2-64.jpg\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" srcset=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2019\/09\/2-64.jpg 636w, https:\/\/decorshop.ir\/wp-content\/uploads\/2019\/09\/2-64-300x169.jpg 300w, https:\/\/decorshop.ir\/wp-content\/uploads\/2019\/09\/2-64-600x338.jpg 600w\" alt=\"\u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc\" width=\"636\" height=\"358\" \/><br \/>\n<a role=\"button\" href=\"#https:\/\/decorshop.ir\/product-category\/%d9%85%d8%a8%d9%84\/%d9%85%d8%a8%d9%84%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c\/\"><br \/>\n\u062e\u0631\u06cc\u062f \u0627\u0646\u0648\u0627\u0639 \u0645\u0628\u0644 \u062e\u0627\u0646\u06af\u06cc\u060c \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u0648 \u0627\u0633\u067e\u0631\u062a \u0627\u0632 \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u062f\u06a9\u0648\u0631\u0634\u0627\u067e<br \/>\n<\/a><\/p>\n<p>\u0634\u0627\u06cc\u062f \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0628\u0627 \u0637\u0631\u062d \u062f\u0631\u0634\u062a \u06cc\u0627 \u0633\u0647\u200c\u0628\u0639\u062f\u06cc \u0645\u0647\u0645\u0627\u0646 \u0634\u0645\u0627 \u0631\u0627 \u0645\u06cc\u062e\u06a9\u0648\u0628 \u06a9\u0646\u062f \u0627\u0645\u0627 \u062e\u06cc\u0644\u06cc \u0632\u0648\u062f \u0627\u0632 \u0645\u062f \u0645\u06cc\u200c\u0627\u0641\u062a\u062f. \u0622\u0646\u062c\u0627\u0633\u062a \u06a9\u0647 \u067e\u0634\u06cc\u0645\u0627\u0646\u06cc \u0633\u0648\u062f\u06cc \u0646\u062f\u0627\u0631\u062f!<\/p>\n<p>\u0646\u0642\u0634\u200c\u0647\u0627\u06cc \u0638\u0631\u06cc\u0641\u06cc \u06a9\u0647 \u0637\u0631\u062d \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u0627\u062c\u0633\u0627\u0645 \u0627\u0631\u06af\u0627\u0646\u06cc\u06a9 \u0627\u0644\u0647\u0627\u0645 \u06af\u0631\u0641\u062a\u0647\u200c\u0627\u0646\u062f\u060c \u0645\u0627\u0646\u062f\u06af\u0627\u0631\u062a\u0631\u0646\u062f. \u062d\u062a\u06cc \u0628\u0627 \u0648\u0633\u0627\u06cc\u0644 \u062f\u06cc\u06af\u0631 \u062e\u0627\u0646\u0647 \u0647\u0645\u060c \u0628\u0647\u062a\u0631 \u0633\u062a \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u062f\u0631 \u0647\u0646\u06af\u0627\u0645 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0628\u0627 \u0637\u0631\u062d \u0631\u06cc\u0632 \u062e\u0648\u0628 \u0641\u06a9\u0631 \u06a9\u0646\u06cc\u062f. \u0686\u0631\u0627 \u06a9\u0647 \u0646\u0635\u0628 \u062f\u0642\u06cc\u0642 \u0648 \u062a\u0631\u0627\u0632 \u06a9\u0631\u062f\u0646 \u0644\u0627\u06cc\u0647\u200c\u0647\u0627 \u06a9\u0646\u0627\u0631 \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0633\u062e\u062a \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/p>\n<p>\u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631\u06cc\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0631\u0627\u06cc \u067e\u0648\u0634\u0627\u0646\u062f\u0646 \u0646\u0648\u0627\u0642\u0635 \u0633\u0637\u062d \u062f\u06cc\u0648\u0627\u0631\u060c \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u062f\u0627\u0631\u0627\u06cc \u0628\u0627\u0641\u062a \u0628\u0627 \u0646\u0642\u0634\u200c\u0647\u0627\u06cc \u067e\u0631\u062a\u06a9\u0631\u0627\u0631 \u0627\u0633\u062a. \u0622\u0646\u200c\u0647\u0627 \u062f\u0631 \u06af\u0648\u0634\u0647 \u062f\u0646\u062c \u062e\u0627\u0646\u0647 \u0634\u0645\u0627 \u0648 \u06cc\u0627 \u0627\u062a\u0627\u0642\u200c\u062e\u0648\u0627\u0628 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p>\n<p>\u0646\u0642\u0634\u200c\u0647\u0627\u06cc \u06cc\u06a9\u200c\u062f\u0633\u062a\u060c \u0645\u0644\u0627\u06cc\u0645 \u0648 \u0645\u0633\u0637\u062d \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0628\u0647 \u06a9\u0627\u0631 \u0642\u0633\u0645\u062a\u200c\u0647\u0627\u06cc \u0631\u0633\u0645\u06cc \u062e\u0627\u0646\u0647 \u0634\u0645\u0627 \u0645\u062b\u0644 \u0648\u0631\u0648\u062f\u06cc \u0648 \u0633\u0627\u0644\u0646 \u063a\u0630\u0627\u062e\u0648\u0631\u06cc \u0645\u06cc\u200c\u0622\u06cc\u0646\u062f\u060c \u0627\u06af\u0631 \u0628\u0647 \u0637\u0631\u062d\u200c\u0647\u0627\u06cc \u06cc\u06a9\u200c\u062f\u0633\u062a \u0648 \u0645\u0633\u0637\u062d \u0639\u0644\u0627\u0642\u0647 \u062f\u0627\u0631\u06cc\u062f \u0627\u0645\u0627 \u062f\u06cc\u0648\u0627\u0631\u062a\u0627\u0646 \u067e\u0633\u062a\u06cc \u0628\u0644\u0646\u062f\u06cc \u062f\u0627\u0631\u062f\u060c \u0646\u06af\u0631\u0627\u0646 \u0646\u0628\u0627\u0634\u06cc\u062f. \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0622\u0633\u062a\u0631 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc\u060c \u062a\u0627 \u062d\u062f \u0627\u0645\u06a9\u0627\u0646 \u0633\u0637\u062d \u062f\u06cc\u0648\u0627\u0631\u062a\u0627\u0646 \u0635\u0627\u0641 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0642\u0633\u0645\u062a \u0646\u06a9\u0627\u062a\u06cc \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0637\u0631\u062d \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0622\u0648\u0631\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f:<\/p>\n<ul>\n<li>\u0646\u0642\u0634 \u0631\u0627\u0647\u200c\u0631\u0627\u0647 \u0627\u0641\u0642\u06cc\u060c <a href=\"https:\/\/decorshop.ir\/mag\/%d8%af%da%a9%d9%88%d8%b1%d8%a7%d8%b3%db%8c%d9%88%d9%86-%d9%85%d9%86%d8%b2%d9%84-%da%a9%d9%88%da%86%da%a9\/\">\u0627\u062a\u0627\u0642<\/a> \u0634\u0645\u0627 \u0631\u0627 \u0628\u0632\u0631\u06af\u200c\u062a\u0631 \u062c\u0644\u0648\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f \u0648\u0644\u06cc \u0633\u0642\u0641 \u0631\u0627 \u06a9\u0648\u062a\u0627\u0647\u200c\u062a\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/li>\n<li>\u0646\u0642\u0634 \u0631\u0627\u0647\u200c\u0631\u0627\u0647 \u0639\u0645\u0648\u062f\u06cc\u060c \u0641\u0636\u0627\u06cc \u0627\u062a\u0627\u0642 \u0631\u0627 \u0628\u0632\u0631\u06af\u062a\u0631 \u06a9\u0631\u062f\u0647 \u0648 \u0633\u0642\u0641 \u0631\u0627 \u0628\u0644\u0646\u062f\u062a\u0631 \u0645\u06cc\u200c\u200c\u06a9\u0646\u062f.<\/li>\n<li>\u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0628\u0627 \u0632\u0645\u06cc\u0646\u0647 \u0631\u0648\u0634\u0646\u060c \u0627\u062a\u0627\u0642 \u0634\u0645\u0627 \u0631\u0627 \u0628\u0632\u0631\u06af\u200c\u062a\u0631 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0628\u0631\u0639\u06a9\u0633 \u0632\u0645\u06cc\u0646\u0647 \u062a\u06cc\u0631\u0647\u060c \u0627\u062a\u0627\u0642 \u0631\u0627 \u06a9\u0648\u0686\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/li>\n<li>\u0646\u0642\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0634\u062a \u0627\u062a\u0627\u0642 \u0631\u0627 \u06a9\u0648\u0686\u06a9 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f. \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0627\u06cc\u0646 \u0646\u0642\u0634\u200c\u0647\u0627 \u062a\u0646\u0647\u0627 \u062f\u0631 \u06cc\u06a9 \u062f\u06cc\u0648\u0627\u0631 \u0627\u062a\u0627\u0642\u06cc \u0628\u0632\u0631\u06af \u0628\u0647 \u06a9\u0627\u0631 \u0628\u0631\u062f\u0647 \u0634\u0648\u0646\u062f.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%A9%D8%A7%D8%BA%D8%B0_%D8%AF%DB%8C%D9%88%D8%A7%D8%B1%DB%8C_%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D8%AC%D9%86%D8%B3_%DA%A9%D8%A7%D8%BA%D8%B0_%D8%AF%DB%8C%D9%88%D8%A7%D8%B1%DB%8C_%D8%B1%D8%A7_%D9%85%DB%8C%E2%80%8C%D8%B4%D9%86%D8%A7%D8%B3%DB%8C%D8%AF%D8%9F\"><\/span><strong>\u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc | \u0628\u0647\u062a\u0631\u06cc\u0646 \u062c\u0646\u0633 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0631\u0627 \u0645\u06cc\u200c\u0634\u0646\u0627\u0633\u06cc\u062f\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2019\/09\/3-52.jpg\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" srcset=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2019\/09\/3-52.jpg 636w, https:\/\/decorshop.ir\/wp-content\/uploads\/2019\/09\/3-52-300x169.jpg 300w, https:\/\/decorshop.ir\/wp-content\/uploads\/2019\/09\/3-52-600x338.jpg 600w\" alt=\"\u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0645\u0646\u0627\u0633\u0628 \u0627\u062a\u0627\u0642 \u062e\u0648\u0627\u0628\" width=\"636\" height=\"358\" \/><\/p>\n<p>\u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0648\u06cc\u0646\u06cc\u0644 \u067e\u0631\u06a9\u0627\u0631\u0628\u0631\u062f\u062a\u0631\u06cc\u0646 \u0645\u062f\u0644 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0645\u062f\u0644 \u0628\u0647 \u0622\u0633\u0627\u0646\u06cc \u0646\u0635\u0628 \u0648 \u062a\u0645\u06cc\u0632 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0646\u0635\u0628 \u0622\u0633\u0627\u0646 \u0648\u06cc\u0646\u06cc\u0644 \u0645\u0648\u062c\u0628 \u0634\u062f\u0647 \u062a\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0627\u0648\u0644 \u06a9\u0633\u0627\u0646\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u062e\u0648\u062f\u0634\u0627\u0646 \u0642\u0635\u062f \u0646\u0635\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0631\u0627 \u062f\u0627\u0631\u0646\u062f.<\/p>\n<p>\u0628\u06cc\u0634\u062a\u0631 \u062f\u0648 \u0645\u062f\u0644 \u0627\u0632 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0648\u06cc\u0646\u06cc\u0644 \u062f\u0631 \u062e\u0627\u0646\u0647\u200e\u200c\u0647\u0627 \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u0634\u0648\u062f. \u06cc\u06a9 \u0646\u0648\u0639 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0628\u0627 \u0631\u0648\u06a9\u0634 \u0648\u06cc\u0646\u06cc\u0644 \u06a9\u0647 \u0628\u0627 \u0627\u0633\u0641\u0646\u062c \u0648 \u0622\u0628\u200c\u0635\u0627\u0628\u0648\u0646 \u062a\u0645\u06cc\u0632 \u0645\u06cc\u200c\u0634\u0648\u062f. \u062f\u0631 \u0648\u0627\u0642\u0639 \u0632\u0645\u06cc\u0646\u0647 \u06a9\u0627\u0631\u060c \u06cc\u06a9 \u0635\u0641\u062d\u0647 \u06a9\u0627\u063a\u0630\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0639\u062f \u0627\u0632 \u0646\u0635\u0628 \u0628\u0627 \u0648\u06cc\u0646\u06cc\u0644 \u0645\u0627\u06cc\u0639 \u067e\u0648\u0634\u0627\u0646\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0646\u0648\u0639 \u062f\u06cc\u06af\u0631 \u06a9\u0627\u063a\u062f \u062f\u06cc\u0648\u0627\u0631\u06cc \u0648\u06cc\u0646\u06cc\u0644 \u062c\u0627\u0645\u062f \u0627\u0633\u062a \u06a9\u0647 \u06a9\u0627\u0645\u0644\u0627 \u0636\u062f\u0622\u0628 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0645\u062f\u0644 \u0645\u0646\u0627\u0633\u0628 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0648 \u062d\u0645\u0627\u0645 \u0627\u0633\u062a. \u06cc\u0627\u062f \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0631 \u0642\u062f\u06cc\u0645 \u0627\u0632 \u0633\u0642\u0641 \u062a\u0627 \u06a9\u0641 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0631\u0627 \u0634\u0644\u0646\u06af! \u0645\u06cc\u200c\u06af\u0631\u0641\u062a\u0646\u062f \u0628\u0647 \u062e\u06cc\u0631. \u062d\u062a\u0645\u0627 \u0627\u0632 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0648\u06cc\u0646\u06cc\u0644 \u0631\u0627\u0636\u06cc \u0645\u06cc\u200c\u0628\u0648\u062f\u0646\u062f. \u0641\u0642\u0637 \u0628\u0647 \u06cc\u0627\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u06a9\u0646\u062f\u0646 \u0627\u06cc\u0646 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0627\u0632 \u062f\u06cc\u0648\u0627\u0631 \u062f\u0634\u0648\u0627\u0631\u062a\u0631 \u0627\u0633\u062a.<\/p>\n<p>\u0645\u062f\u0644\u200c\u0647\u0627\u06cc \u062e\u0627\u0635 \u062f\u06cc\u06af\u0631\u06cc \u0647\u0645 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u062f\u0631 \u0635\u0648\u0631\u062a \u06a9\u0627\u0631\u0628\u0631\u06cc \u062f\u0631\u0633\u062a\u060c \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0628\u0627 \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc\u200c\u0631\u0633\u0646\u062f. \u0627\u0645\u0627 \u0642\u06cc\u0645\u062a \u0622\u0646\u200c\u0647\u0627 \u0627\u0632 \u0648\u06cc\u0646\u06cc\u0644 \u06af\u0631\u0627\u0646\u200c\u062a\u0631 \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644 \u0645\u062f\u0644 \u0641\u0644\u0648\u06a9(Flock) \u060c \u06cc\u06a9 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0645\u062e\u0645\u0644\u06cc \u0648 \u0634\u06cc\u06a9 \u0627\u0633\u062a. \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0641\u0648\u06cc\u0644(foil) \u060c \u0628\u0627 \u06cc\u06a9 \u0644\u0627\u06cc\u0647 \u0646\u0627\u0632\u06a9 \u0628\u0631\u0627\u0642 \u0648 \u0645\u062a\u0627\u0644\u06cc\u06a9 \u067e\u0648\u0634\u06cc\u062f\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%A9%D8%A7%D8%BA%D8%B0_%D8%AF%DB%8C%D9%88%D8%A7%D8%B1%DB%8C_%D8%AE%D8%A7%D9%86%D9%87_%D9%85%D9%86_%DA%86%D9%86%D8%AF_%D9%85%D8%AA%D8%B1_%DA%A9%D8%A7%D8%BA%D8%B0_%D8%AF%DB%8C%D9%88%D8%A7%D8%B1%DB%8C_%D9%84%D8%A7%D8%B2%D9%85_%D8%AF%D8%A7%D8%B1%D8%AF%D8%9F\"><\/span><strong><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwj8urmPi6nwAhWEY8AKHQaSCwcQFjABegQIAxAD&amp;url=https%3A%2F%2Fwww.bhg.com%2Fdecorating%2Fhome-accessories%2Fwall-art%2Fselect-the-perfect-wallpaper%2F%23%3A~%3Atext%3DConsider%2520how%2520the%2520room%2520is%2Cthe%2520decorative%2520impact%2520of%2520borders.&amp;usg=AOvVaw3197F4AT9iGThXM6WSviEb\" target=\"_blank\" rel=\"noopener\">\u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc<\/a> | \u062e\u0627\u0646\u0647 \u0645\u0646 \u0686\u0646\u062f \u0645\u062a\u0631 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0644\u0627\u0632\u0645 \u062f\u0627\u0631\u062f\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2019\/09\/4-37.jpg\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" srcset=\"https:\/\/decorshop.ir\/wp-content\/uploads\/2019\/09\/4-37.jpg 636w, https:\/\/decorshop.ir\/wp-content\/uploads\/2019\/09\/4-37-300x169.jpg 300w, https:\/\/decorshop.ir\/wp-content\/uploads\/2019\/09\/4-37-600x338.jpg 600w\" alt=\"\u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0628\u0631\u0627\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647\" width=\"636\" height=\"358\" \/><\/p>\n<p>\u062f\u0634\u0648\u0627\u0631\u062a\u0631\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u062e\u0631\u06cc\u062f \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u0637\u0631\u062d \u062f\u0644\u062e\u0648\u0627\u0647 \u0628\u0648\u062f \u06a9\u0647 \u067e\u0634\u062a \u0633\u0631 \u06af\u0630\u0627\u0634\u062a\u06cc\u0645. \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u06af\u06cc\u0631\u06cc \u0645\u062a\u0631\u0627\u0698 \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0622\u0633\u0627\u0646\u200c\u062a\u0631 \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f\u06cc \u0628\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u0627\u0632 \u062f\u0633\u062a\u0648\u0631 \u0632\u06cc\u0631 \u067e\u06cc\u0631\u0648\u06cc \u06a9\u0646\u06cc\u062f. \u06a9\u0627\u063a\u0630 \u0642\u0644\u0645 \u0648 \u0645\u062a\u0631 \u0641\u0631\u0627\u0645\u0648\u0634 \u0646\u0634\u0648\u062f.<\/p>\n<ol>\n<li>\u0627\u0631\u062a\u0641\u0627\u0639 \u062f\u06cc\u0648\u0627\u0631 \u0631\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u0628\u06af\u06cc\u0631\u06cc\u062f. \u0622\u0646 \u0631\u0627 \u062f\u0631 \u0639\u0631\u0636 \u0647\u0631 \u062f\u06cc\u0648\u0627\u0631 \u0636\u0631\u0628 \u06a9\u0646\u06cc\u062f. \u06cc\u0639\u0646\u06cc \u0627\u06cc\u0646 \u0645\u062d\u0627\u0633\u0628\u0647 \u0631\u0627 (\u0627\u0631\u062a\u0641\u0627\u0639 \u062f\u06cc\u0648\u0627\u0631 x \u0639\u0631\u0636 \u062f\u06cc\u0648\u0627\u0631) \u0628\u0631\u0627\u06cc \u062a\u06a9\u200c\u062a\u06a9 \u062f\u06cc\u0648\u0627\u0631\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0642\u0631\u0627\u0631 \u0627\u0633\u062a \u06a9\u0627\u063a\u0630 \u0634\u0648\u062f\u060c \u0645\u062d\u0627\u0633\u0628\u0647 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0633\u067e\u0633 \u0645\u0633\u0627\u062d\u062a\u200c\u0647\u0627\u06cc \u062d\u0633\u0627\u0628\u200c\u0634\u062f\u0647 \u0631\u0627 \u0628\u0627 \u0647\u0645 \u062c\u0645\u0639 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0645\u0633\u0627\u062d\u062a \u0647\u0645\u0647 \u062f\u0631 \u0648 \u067e\u0646\u062c\u0631\u0647\u200c\u0647\u0627 \u0631\u0627 \u0627\u0632 \u0645\u0642\u062f\u0627\u0631 \u0628\u0627\u0644\u0627 \u06a9\u0645 \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0628\u0631\u0686\u0633\u0628 \u0631\u0648\u06cc \u0631\u0648\u0644 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0631\u0627 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f. \u0686\u0647 \u0645\u0633\u0627\u062d\u062a\u06cc \u0631\u0627 \u067e\u0648\u0634\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f\u061f \u0645\u0637\u0645\u0626\u0646 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0645\u0633\u0627\u062d\u062a \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u0634\u062f\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0646\u06cc\u0627\u0632\u062a\u0627\u0646 \u0628\u0627\u0634\u062f.<\/li>\n<li>\u06cc\u06a9 \u0631\u0648\u0644 \u0627\u0636\u0627\u0641\u0647 \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f \u062a\u0627 \u062e\u06cc\u0627\u0644\u062a\u0627\u0646 \u0631\u0627\u062d\u062a \u0628\u0627\u0634\u062f. \u0628\u0627\u0644\u0627\u062e\u0631\u0647 \u0627\u0634\u062a\u0628\u0627\u0647 \u0631\u062e \u0645\u06cc\u200c\u062f\u0647\u062f. \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0639\u062f\u0627 \u0647\u0631 \u0686\u0647 \u0628\u06af\u0631\u062f\u06cc\u062f \u067e\u06cc\u062f\u0627 \u0646\u06a9\u0646\u06cc\u062f. \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0641\u0631\u0648\u0634\u0646\u062f\u0647 \u0628\u062e\u0648\u0627\u0647\u06cc\u062f \u06a9\u0647 \u062f\u0631 \u0635\u0648\u0631\u062a \u0628\u0627\u0632 \u0646\u06a9\u0631\u062f\u0646 \u0644\u0648\u0644\u060c \u067e\u0633 \u0628\u06af\u06cc\u0631\u062f.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>\u0646\u06a9\u0627\u062a\u06cc \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u062f\u06cc\u06af\u0631 \u0631\u0648\u0632\u06af\u0627\u0631 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u06a9\u0650\u0631\u0650\u0645 \u0631\u0646\u06af \u0648 \u0627\u0633\u062a\u062e\u0648\u0627\u0646\u06cc \u062e\u0627\u0646\u0647 \u0645\u0627\u062f\u0631\u0628\u0632\u0631\u06af\u200c\u0647\u0627\u06cc\u0645\u0627\u0646 \u0628\u0647 \u0633\u0631 \u0622\u0645\u062f\u0647 \u0627\u0633\u062a \u0648 \u0628\u0627\u06cc\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u062c\u062f\u06cc\u062f\u06cc \u0631\u0627 \u062f\u0631 \u0628\u0631\u0646\u0627\u0645\u0647 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u0645. \u0632\u0645\u0627\u0646 \u0622\u0646 \u0631\u0633\u06cc\u062f\u0647 \u062a\u0627 \u0634\u0627\u0646\u0633 \u062c\u062f\u06cc\u062f\u06cc \u0628\u0647 \u06a9\u0627\u063a\u062f \u062f\u06cc\u0648\u0627\u0631\u06cc \u0628\u062f\u0647\u06cc\u0645. \u0634\u0627\u06cc\u062f \u062f\u0631 \u0631\u0642\u0627\u0628\u062a \u0628\u0627 \u0631\u0646\u06af \u06a9\u0631\u062f\u0646 \u062f\u06cc\u0648\u0627\u0631 \u067e\u06cc\u0631\u0648\u0632 \u0634\u0648\u062f! \u0627\u0645\u0631\u0648\u0632 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u0645 \u0628\u062e\u0648\u0627\u0646\u06cc\u0645 \u06a9\u0647 \u0686\u06af\u0648\u0646\u0647 \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631\u06cc\u0646 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":32878,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,50,59,34],"tags":[45,46,61],"class_list":["post-14166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-56","category-50","category-59","category-34","tag-45","tag-46","tag-61"],"_links":{"self":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/14166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/comments?post=14166"}],"version-history":[{"count":0,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/posts\/14166\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media\/32878"}],"wp:attachment":[{"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/media?parent=14166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/categories?post=14166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decorshop.ir\/mag\/wp-json\/wp\/v2\/tags?post=14166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}